{"id":76537,"date":"2016-04-23T16:57:16","date_gmt":"2016-04-23T16:57:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/23\/la-haine-du-diable-et-le-mepris-de-la-hauteur\/"},"modified":"2016-04-23T16:57:16","modified_gmt":"2016-04-23T16:57:16","slug":"la-haine-du-diable-et-le-mepris-de-la-hauteur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/23\/la-haine-du-diable-et-le-mepris-de-la-hauteur\/","title":{"rendered":"La haine du Diable et le m\u00e9pris de la hauteur"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La haine du Diable et le m\u00e9pris de la hauteur<\/h2>\n<\/p>\n<p><p>23 avril 2016 &ndash; D&rsquo;une certaine fa\u00e7on, mais plut\u00f4t buissonni\u00e8re et marqu\u00e9e par l&rsquo;humeur et la psychologie intuitive, voici un encha&icirc;nement sur \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/humeur-de-crise-10\">l&rsquo;humeur de crise-10<\/a>\u00a0\u00bb d&rsquo;hier, concernant l&rsquo;\u00e9pouvantable climat r\u00e9gnant entre les USA, en tant que tels c&rsquo;est-\u00e0-dire dans le chef de leurs \u00e9lites-Syst\u00e8me absolument plong\u00e9es dans une pathologie de l&rsquo;hyst\u00e9rie, et la Russie qui semble proche de ne plus supporter ses \u00ab\u00a0partenaires\u00a0\u00bb. Il s&rsquo;agit d&rsquo;une sorte de dialogue sans se conna&icirc;tre, par l&rsquo;interm\u00e9diaire fort aimable du syst\u00e8me de la communication. Le site <em><a href=\"http:\/\/russia-insider.com\/en\/politics\/madeleine-albright-russia-bangladesh-missiles\/ri14022\">Russia Insider<\/a><\/em> a eu l&rsquo;id\u00e9e, certainement sugg\u00e9r\u00e9e par l&rsquo;un des dialogueurs (devinez lequel ?), de mettre en opposition un extrait d&rsquo;une interview de Madeleine <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Madeleine_Albright\">Albright<\/a> au site autrichien <em>DiePress.com<\/em> et un commentaire de l&rsquo;inimitable aventurier-\u00e9crivain-activiste russe &Eacute;douard Limonov (voir son histoire extraordinaire dans l&rsquo;excellent<em> <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Limonov_(roman)\">Limonov<\/a><\/em>, du fils d&rsquo;H\u00e9l\u00e8ne Carr\u00e8re d&rsquo;Encausse).<\/p>\n<\/p>\n<p><p>(Pour Albright, je veux dire le visage d&rsquo;Albright, qui a son importance dans le dialogue, choisir plut\u00f4t celui que pr\u00e9sente <em>Russia Insider<\/em>, assez cors\u00e9 et telle que la dame est devenue aujourd&rsquo;hui, d\u00e9couvrant le vrai visage de la mission qui lui avait \u00e9t\u00e9 assign\u00e9e et qu&rsquo;elle a remplie, plut\u00f4t que celui, un peu trop flatteur conform\u00e9ment aux consignes, du <em>Wikip\u00e9dia<\/em>.)<\/p>\n<\/p>\n<p><p>Voici le dialogue qui <strong>est en fait un anti-dialogue<\/strong>&#8230;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; &#8230;<em>M\u00eame la Russie s&rsquo;est jug\u00e9e trahie par ce qui est arriv\u00e9 en Libye<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>J&rsquo;en ai plus qu&rsquo;assez de tous ces gens qui ne cessent de trouver des excuses \u00e0 la Russie. La Russie ne cesse de provoquer et ensuite de se sentir offens\u00e9e. Ce pays a travers\u00e9 une crise d&rsquo;identit\u00e9. Je n&rsquo;oublierai jamais, dans les ann\u00e9es 1990, cet homme que j&rsquo;avais rencontr\u00e9 pr\u00e8s de Moscou et qui m&rsquo;avait dit : \u00ab\u00a0Je suis si honteux. Nous \u00e9tions une superpuissance et maintenant nous sommes un Bangladesh avec des missiles\u00a0\u00bb. Poutine s&rsquo;est servi de cette situation, affirmant qu&rsquo;il avait \u00ab\u00a0reconstruit la Russie une fois de plus pour lui faire retrouver sa gloire\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Vous avez ressenti cela lorsque vous l&rsquo;avez rencontr\u00e9 en 2000 ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>C&rsquo;est un homme intelligent mais c&rsquo;est un homme v\u00e9ritablement diabolique. Un officier du KGB qui veut exercer le pouvoir et qui pense que tout le monde s&rsquo;est alli\u00e9 pour conspirer contre la Russie. Ce n&rsquo;est pas la v\u00e9rit\u00e9. Poutine joue bien avec de mauvaises cartes, dans tous les cas pour l&rsquo;instant. Je crois que son but est de saper et de briser l&rsquo;UE. Il veut que l&rsquo;OTAN disparaisse de sa sph\u00e8re d&rsquo;influence. <\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Cela signifie-t-il que les craintes de Poutine des pays baltes sont justifi\u00e9es ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>Oui, \u00e0 cause des m\u00e9thodes de guerre asym\u00e9trique utilis\u00e9es par les Russes<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Poutine a au moins atteint son but de restaurer la Russie une fois de plus<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>En envahissant et en annexant un autre pays pour la premi\u00e8re fois depuis 1945 : la Crim\u00e9e en Ukraine<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Et il affirme que c&rsquo;est un fait irr\u00e9versible<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>Oui, et cela ne devrait pas \u00eatre tol\u00e9r\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Comment appr\u00e9ciez-vous la pr\u00e9sence russe en Syrie ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; <em>Poutine est intervenu en Syrie pour distraire notre attention de l&rsquo;Ukraine et pour affirmer sa pr\u00e9sence au Moyen-Orient. Il voulait seulement d\u00e9montrer la puissance de la Russie. Mais laissez-moi insister sur ce fait : les USA n&rsquo;ont aucun probl\u00e8me avec la Russie pour autant qu&rsquo;elle n&rsquo;intervient pas et n&rsquo;occupe pas d&rsquo;autres pays<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>DiePress<\/em><\/strong> : &laquo; <em>Au d\u00e9but, Poutine a m\u00eame connu un succ\u00e8s \u00e9conomique.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Albright<\/em><\/strong> : &laquo; &#8230;<em>En s&rsquo;appuyant sur le prix du p\u00e9trole et ce n&rsquo;est plus possible aujourd&rsquo;hui. Poutine a r\u00e9veill\u00e9 la nationalisme pour faire oublier aux Russes que la Russie est en fait un Bangladesh avec des missiles.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Digression plut\u00f4t que r\u00e9ponse d&rsquo;&Eacute;douard Limonov<\/em><\/strong> : &laquo; <em>Il s&rsquo;agit en fait d&rsquo;une tentative grossi\u00e8re d&rsquo;insulter notre pays. Nous devons r\u00e9pliquer d&rsquo;une fa\u00e7on similaire plut\u00f4t que de lui faire le cadeau de lui opposer des arguments rationnels<\/em>. <em>Albright est une vieille femme d&rsquo;une laideur repoussante, avec un nez crochu qui lui vaudrait le r\u00f4le de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Baba_Yaga\">Baba Yaga<\/a> sans n\u00e9cessit\u00e9 de l&rsquo;auditionner. Et on pourrait la filmer sans m\u00eame devoir la maquiller parce qu&rsquo;elle est naturellement d&rsquo;une laideur suffisamment repoussante. En bref, un arch\u00e9type de la laideur<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le Bangladesh est un pays chaud, d&rsquo;une grande beaut\u00e9, habit\u00e9 par des gens \u00e0 le peau sombre, aimables et pacifiques. C&rsquo;est l\u00e0 o&ugrave; le Gange sacr\u00e9 et le Brahmapoutre se rencontrent, pour former ce spectacle naturel unique du Delta du Gange. Sa civilisation remonte \u00e0 plusieurs milliers d&rsquo;ann\u00e9es, alors que l&rsquo;histoire des USA est courte et tr\u00e8s vulgaire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Russie est un pays froid, ancien, avec des origines myst\u00e9rieuses. La Russie atteignit soudain le pinacle de la puissance sans l&rsquo;avoir cherch\u00e9 en 1945. En 1991, l&rsquo;URSS se suicida mais l&rsquo;arbre de vie de la Russie n&rsquo;\u00e9tait pas mort et il redevenu si fort qu&rsquo;il inqui\u00e8te d\u00e9sormais les USA et la vieille Europe. Ils tremblent de peur, pour dire le vrai. Les Russes sont des gens simples, incroyablement braves et un peu na\u00effs, comme toutes les grandes nations ont coutume d&rsquo;\u00eatre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous vous enterrerons et nous viendrons pleurer \u00e0 vos fun\u00e9railles parce que nous sommes \u00e9galement un peuple sentimental<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>&#8230;Il faut absolument suivre le conseil de Limonov et <strong>ne faire en aucune fa\u00e7on \u00e0 ces gens la gr\u00e2ce de prendre leur discours au pied de la lettre en montrant justement ce en quoi ce discours n&rsquo;a rien \u00e0 mettre au pied de la lettre inexistante, c&rsquo;est-\u00e0-dire cet \u00e0-peu-pr\u00e8s-tout o&ugrave; se m\u00e9langent infamie, mensonges, d\u00e9terminisme-narrativiste, aveuglement, inculture, indiff\u00e9rence pour la v\u00e9rit\u00e9, hyst\u00e9rie de la foi d\u00e9voy\u00e9e<\/strong>. C&rsquo;est l&rsquo;interpr\u00e9tation de Limonov qui a du poids l\u00e0-dedans, parce que ses arguments usent compl\u00e8tement du contrepied en n&rsquo;en \u00e9tant pas <em>stricto sensu<\/em>, et ainsi refusant cat\u00e9goriquement le dialogue, se cantonnant dans l&rsquo;affirmation de la caricature-mal\u00e9fique pour caract\u00e9riser l&rsquo;adversaire, et dans l&rsquo;appr\u00e9ciation civilisationnelle pour ridiculiser mortellement leur dialectique par le m\u00e9pris complet du cadre qui les a fait ce qu&rsquo;ils sont. (Je parle de \u00ab\u00a0l&rsquo;adversaire\u00a0\u00bb et de \u00ab\u00a0leur dialectique\u00a0\u00bb pour, \u00e0 dessein, <strong>compl\u00e8tement d\u00e9shumaniser Albright, qui n&rsquo;est dans ce cas qu&rsquo;elle a bien voulu et qu&rsquo;elle a elle-m\u00eame entretenu qu&rsquo;une zombie-Syst\u00e8me hideuse dans une horde de zombies-Syst\u00e8me diversement hideux et \u00e2nonnant la m\u00eame rengaine qui leur est dict\u00e9e par le Diable, &ndash; ou bien le Syst\u00e8me si vous voulez, pour rester dans nos r\u00e9f\u00e9rences<\/strong>.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le visage de Albright, non pas d\u00e9lit de faci\u00e8s mais aveu et signe de reconnaissance de faci\u00e8s : la photo que nous montre RI nous dit qu&rsquo;Albright pourrait \u00eatre <a href=\"http:\/\/www.dedefensa.org\/article\/message-de-lange-dechu-1\">un Soros<\/a> d\u00e9guis\u00e9 en vieille sorci\u00e8re mitonnant m\u00e9caniquement la derni\u00e8re recette du Diable, tandis que certaines photos de Soros nous font soup\u00e7onner que Soros pourrait \u00eatre Albright d\u00e9guis\u00e9e en vieil impr\u00e9cateur au service du Diable. Effectivement, les deux photos, et celle d&rsquo;Albright dans ce cas, ont une parent\u00e9 \u00e9vidente avec le Diable et la hideur dont parle Limonov est celle du Diable&#8230; C&rsquo;est bien ce qu&rsquo;il nous signifie Limonov, qui appuie sur la hideur de cette femme et cite <em>Baba Yaga<\/em>. Bien entendu, je ne connaissais rien de <em>Baba Yaga<\/em>, mais en lisant mon <em>Wikip\u00e9dia<\/em>, avec <em>Baba<\/em> pour vieille femme, et <em>Yaga<\/em> aux infinies significations dans diverses langues de l&rsquo;Est, mais toujours dans le m\u00eame sens qui pourrait trouver sa pleine puissance et sa logique irrationnelle pour mon compte, d&rsquo;\u00eatre celui d&rsquo;une \u00ab\u00a0sorci\u00e8re\u00a0\u00bb : <strong>Albright en \u00ab\u00a0vieille sorci\u00e8re hideuse\u00a0\u00bb.<\/strong><\/p>\n<\/p>\n<p><p>(Je fais un petit apart\u00e9 dans le domaine du rationnel pour pr\u00e9ciser qu&rsquo;Albright a un CV impressionnant sinon \u00e9blouissant, tant du point de vue de l&rsquo;\u00e9ducation et des \u00e9tudes, autant que de celui de la carri\u00e8re professionnelle, et que cela ne signifie rien pourtant, et qu&rsquo;il s&rsquo;agit pourtant, par ou\u00ef-dire de confiance dirais-je, d&rsquo;une personne d&rsquo;une exceptionnelle m\u00e9diocrit\u00e9 et d&rsquo;une exceptionnelle vulgarit\u00e9, illustrant parfaitement la d\u00e9cadence compl\u00e8te du personnel-Syst\u00e8me en zombie-Syst\u00e8me et inspir\u00e9e \u00e0 cet \u00e9gard par le Diable qui a ais\u00e9ment raison de ces psychologies affaiblies telles que nous les fabrique l&rsquo;am\u00e9ricanisme, et encore plus l&rsquo;am\u00e9ricanisation pour les \u00ab\u00a0Am\u00e9ricains\u00a0\u00bb d&rsquo;adoption, surtout ceux de l&rsquo;Est, les plus redoutables \u00e0 cause de la Chute qu&rsquo;occasionne cette transmutation. Je me rappelle la stup\u00e9faction de mon interlocutrice lorsqu&rsquo;il y eut la nouvelle de la nomination d&rsquo;Albright comme ambassadrice US \u00e0 l&rsquo;ONU, en f\u00e9vrier 1993. C&rsquo;\u00e9tait \u00e0 Bruxelles, mon interlocutrice, diplomate fran\u00e7aise d&rsquo;une famille de grande noblesse g\u00e9orgienne, du temps o&ugrave; la France avait une diplomatie, venait de la d\u00e9l\u00e9gation fran\u00e7aise \u00e0 l&rsquo;ONU pour la d\u00e9l\u00e9gation fran\u00e7aise \u00e0 l&rsquo;UEO, \u00e0 Bruxelles. Elle avait c\u00f4toy\u00e9 Albright \u00e0 New York et se rappelait d&rsquo;une personne d&rsquo;une incroyable m\u00e9diocrit\u00e9, mais habile dans la flatterie et dans le positionnement \u00e0 l&rsquo;int\u00e9rieur des r\u00e9seaux du pouvoir. De sa carri\u00e8re diplomatique dans l&rsquo;esprit que je dis, on peut garder \u00e0 l&rsquo;esprit quelques performances du genre bien connu, toutes tir\u00e9es du <em>Wikip\u00e9dia<\/em> d&rsquo;\u00e0-c\u00f4t\u00e9 : &laquo; <em>En <a href=\"https:\/\/fr.wikipedia.org\/wiki\/1996\">1996<\/a>, lors d&rsquo;une interview accord\u00e9e \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lesley_Stahl\">Lesley Stahl<\/a> dans le magazine de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/CBS_News\">CBS<\/a> intitul\u00e9 Sixty Minutes, elle d\u00e9clare \u00e0 propos des sanctions contre l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Irak\">Irak<\/a> et de la mort suppos\u00e9e d&rsquo;un demi-million d&rsquo;enfants : \u00ab\u00a0Je pense que c&rsquo;est un choix tr\u00e8s dur, mais le prix&#8230; nous pensons que \u00e7a vaut le prix.\u00a0\u00bb (\u00ab\u00a0I think this is a very hard choice, but the price&#8230; we think the price is worth it.\u00a0\u00bb). Elle d\u00e9clarera par la suite avoir regrett\u00e9 cette r\u00e9ponse mais maintiendra tout son soutien aux principes des sanctions commerciales internationales<\/em>. [&#8230;] <em>Le 27 septembre 1996, les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Talibans\">Talibans<\/a> prennent Kaboul, la secr\u00e9taire d&rsquo;&Eacute;tat Madeleine Albright d\u00e9clare alors que \u00ab\u00a0c&rsquo;est un pas positif\u00a0\u00bb. Fort de son soutien politique, les fondamentalistes s&#8217;emparent d\u00e8s lors du pouvoir \u00e0 Kaboul<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Ainsi Limonov, en r\u00e9ponse au discours-zombie, remet en quelques phrases bien pos\u00e9es les choses bien en place. <strong>Il nous dit simplement : mais regardez-l\u00e0 donc, c&rsquo;est le Diable que vous avez en face de vous, ne voyez-vous donc pas ?<\/strong> L&rsquo;\u00e9vidence nous frappe ; vous comprenez, ce n&rsquo;est absolument pas une diabolisation selon la recettes des temps postmodernes, diabolisation en fer-blanc avec articles en soldes, c&rsquo;est l&rsquo;\u00e9vidence de l&rsquo;existence du fait diabolique qui conduit cette \u00e9poque, ce Syst\u00e8me, et fait de ces cr\u00e9atures trop faibles pour lui r\u00e9sister des messag\u00e8res du Diable&#8230; Car je continue \u00e0 n&rsquo;\u00eatre pas un de ces impitoyables procureurs du peuple mettant en cause l&rsquo;\u00eatre de l&rsquo;accus\u00e9 : pour moi, tous ces \u00eatres souffrent de faiblesse bien plus qu&rsquo;ils ne portent la culpabilit\u00e9 du Mal qu&rsquo;ils auraient en eux. Ils ne r\u00e9sistent pas \u00e0 la proximit\u00e9 du Diable, ce sont tous des Faust-postmodernes, par faiblesse et conformisme, et puis pour r\u00e9pondre \u00e0 la logique du march\u00e9. Ils r\u00e9pondent comme un seul \u00eatre transgenre \u00e0 l&rsquo;appel du vieux Plotin aveugle mais si clairvoyant au-del\u00e0 des si\u00e8cles :<\/p>\n<\/p>\n<p><p>&laquo; <em>Car on pourrait d\u00e8s lors arriver \u00e0 une notion du mal comme ce qui est non-mesure par rapport \u00e0 la mesure, sans limite par rapport \u00e0 la limite, absence de forme par rapport \u00e0 ce qui produit la forme et d\u00e9ficience permanente par rapport \u00e0 ce qui est suffisant en soi, toujours ind\u00e9termin\u00e9, stable en aucun fa\u00e7on, affect\u00e9 de toutes mani\u00e8res, insatiable, indigence totale. Et ces choses ne sont pas des accidents qui lui adviennent, mais elles constituent son essence en quelque sorte, et quelle que soit la partie de lui que tu pourrais voir, il est toutes ces choses. Mais les autres, ceux qui participeraient de lui et s&rsquo;y assimileraient, deviennent mauvais, <strong>n&rsquo;\u00e9tant pas mauvais en soi<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Pour le reste, qui est la partie constructive de son commentaire, sa v\u00e9ritable riposte si vous voulez, \u00e9galement contrepied de la part de Limonov. L&rsquo;URSS d\u00e9sint\u00e9gr\u00e9e, la Russie pi\u00e9tin\u00e9e devenue \u00ab\u00a0Bangladesh avec des missiles\u00a0\u00bb ? Mais savez-vous ce qu&rsquo;est le Bangladesh, \u00e0 la civilisation mill\u00e9naire, qui se baigne au Gange sacr\u00e9 et nous offre la somptueuse beaut\u00e9 de l&rsquo;ouverture sur le Delta du Gange, cette hydrographie de Dieu ? La seule chose que vous retenez, vous autres <em>Yankees<\/em> d&rsquo;origine ou d&rsquo;adoption, c&rsquo;est la couleur de leur peau et leur pauvret\u00e9 selon vos canons, je veux dire vos r\u00e9f\u00e9rences. <strong>Pour vous, de l&rsquo;expression \u00ab\u00a0un Bangladesh avec des missiles\u00a0\u00bb, il n&rsquo;y a que les missiles \u00e0 sauver, c&rsquo;est-\u00e0-dire \u00e0 r\u00e9cup\u00e9rer pour les fourguer \u00e0 l&rsquo;un ou l&rsquo;autre groupe djihadiste&#8230;<\/strong><\/p>\n<\/p>\n<p><p>Le mat\u00e9rialisme pur de ces fous-de-Dieu de l&rsquo;exceptionnalisme hollywoodien que sont les <em>Yankees<\/em> les fait vivre cul-par-dessus-t\u00eate, hauteur vers le bas, m\u00e9prisant l&rsquo;ancien et la civilisation mill\u00e9naire, se r\u00e9v\u00e9lant absolument vulgaires dans l&rsquo;essence, arrivant \u00e0 cr\u00e9er cette monstruosit\u00e9 d&rsquo;une essence-vulgaire, d&rsquo;une essence-zombie&#8230; Le terme \u00ab\u00a0vulgaire\u00a0\u00bb pour d\u00e9signer les USA qui se sont constitu\u00e9s en porte-voix des multiples Commandements du Diable, peut-\u00eatre bien autant de Commandements que de lignes de code du JSF, ce terme ne peut \u00eatre mieux choisi, il \u00e9mane d&rsquo;une \u00e2me po\u00e9tique, d&rsquo;un esprit noble et d&rsquo;un caract\u00e8re ferme comme le marbre des vieux temples des Anciens.<\/p>\n<\/p>\n<blockquote>\n<p><p>Voil\u00e0 la r\u00e9ponse de Limonov, le vieil aventurier devenu sage. Je trouve qu&rsquo;il n&rsquo;en est pas de meilleure. Je lui trouve aussi une force symbolique qui nous instruit, bien mieux que mille \u00e9tudes savantes, du caract\u00e8re paroxystique auquel aujourd&rsquo;hui atteint la folie du Syst\u00e8me, et par cons\u00e9quent l&rsquo;affrontement entre les USA, bloc-BAO en bandouill\u00e8re, et la Russie. Pourquoi donner une telle importance \u00e0 ce montage un peu fac\u00e9tieux, provocateur et d&rsquo;apparence qu&rsquo;on jugerait futile, entre Albright et Limonov ? Parce que je le ressens intuitivement de cette fa\u00e7on, surtout de la part d&rsquo;un Limonov qui n&rsquo;est en g\u00e9n\u00e9ral pas si bien vu de la ligne russe-officielle dont les r\u00e9seaux pro-russes les mieux achaland\u00e9s sont n\u00e9cessairement assez proches, qui n&rsquo;est certainement pas un poutinien inconditionnel. Mais, dans ce cas, il se passe que je devine qu&rsquo;il parle pour la Russie, porte-parole symbolique, parlant de la Russie en des termes qui devraient glacer d&rsquo;effroi le Diable et toutes ses entreprises. <strong>Je trouve que Limonov parle comme si la Russie disait \u00e0 ceux qui veulent sa mort, \u00e0 ceux qui demandent simplement \u00e0 la Russie de \u00ab\u00a0n&rsquo;avoir jamais exist\u00e9\u00a0\u00bb, que cette fois l&rsquo;on en est au point o&ugrave; l&rsquo;affrontement voulu par le Diable va \u00eatre accept\u00e9, qu&rsquo;il aura lieu, et qu&rsquo;il rejoindra les grands chapitres de l&rsquo;histoire du monde.<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Soudain, le Diable tressaille sur des bases qu&rsquo;il juge brusquement bien fragiles : et s&rsquo;il avait un peu trop pr\u00e9sum\u00e9 de ses forces ? <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La haine du Diable et le m\u00e9pris de la hauteur 23 avril 2016 &ndash; D&rsquo;une certaine fa\u00e7on, mais plut\u00f4t buissonni\u00e8re et marqu\u00e9e par l&rsquo;humeur et la psychologie intuitive, voici un encha&icirc;nement sur \u00ab\u00a0l&rsquo;humeur de crise-10\u00a0\u00bb d&rsquo;hier, concernant l&rsquo;\u00e9pouvantable climat r\u00e9gnant entre les USA, en tant que tels c&rsquo;est-\u00e0-dire dans le chef de leurs \u00e9lites-Syst\u00e8me absolument&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6316,1007,17463,5932,17462,17464,9444,15651,7061,10032,916,11448,2730,4163,17465],"class_list":["post-76537","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-affrontement","tag-albright","tag-bangladesh","tag-diable","tag-diepress","tag-gange","tag-insider","tag-limonov","tag-paroxysme","tag-plotin","tag-poutine","tag-russia","tag-russie","tag-soros","tag-vulgaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76537"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76537\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}