{"id":76541,"date":"2016-04-25T17:05:52","date_gmt":"2016-04-25T17:05:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/25\/de-tchernobyl-1986-a-tchernobyl-2016\/"},"modified":"2016-04-25T17:05:52","modified_gmt":"2016-04-25T17:05:52","slug":"de-tchernobyl-1986-a-tchernobyl-2016","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/25\/de-tchernobyl-1986-a-tchernobyl-2016\/","title":{"rendered":"De Tchernobyl-1986 \u00e0 Tchernobyl-2016"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">De Tchernobyl-1986 \u00e0 Tchernobyl-2016<\/h2>\n<\/p>\n<p><p>25 avril 2016 (1986) &ndash; Je voudrais donner ici quelques indications, dans mon souvenir et aussi avec l&rsquo;aide d&rsquo;une consultation rapide des num\u00e9ros de <em>dedefensa &#038; eurostrat\u00e9gie<\/em> (<em>dd&#038;e<\/em>, Lettre d&rsquo;Analyse\/papier) de l&rsquo;\u00e9poque, des conditions que nous conn&ucirc;mes, dans le monde de ce que nous ne nommions pas encore \u00ab\u00a0la communication\u00a0\u00bb, selon la connaissance progressive que nous e&ucirc;mes de la catastrophe de Tchernobyl. Bien que nous ayons \u00e9t\u00e9 inform\u00e9s quelques jours plus tard que la premi\u00e8re explosion datait du 25 avril (aujourd&rsquo;hui, on donne la date du 26), rien ne fut port\u00e9 \u00e0 notre connaissance commune et diverse avant le 28, d&rsquo;abord par une annonce en Su\u00e8de d&rsquo;une certaine augmentation du taux de radioactivit\u00e9 dans l&rsquo;atmosph\u00e8re avec hypoth\u00e8se que \u00ab\u00a0quelque chose s&rsquo;\u00e9tait pass\u00e9 en URSS\u00a0\u00bb, ensuite quelques heures plus tard le m\u00eame jour, par une nouvelle de l&rsquo;agence Tass annon\u00e7ant l&rsquo;accident avec tr\u00e8s peu de d\u00e9tails.<\/p>\n<\/p>\n<p><p>Ainsi la catastrophe de Tchernobyl prit peu \u00e0 peu de la consistance dans l&rsquo;espace d&rsquo;une semaine sinon d&rsquo;une d\u00e9cade, au contraire des catastrophes qui sont aujourd&rsquo;hui connues dans l&rsquo;heure sinon dans la minute. Elle eut d&rsquo;abord une connotation essentiellement politique, bien plus qu&rsquo;environnementale. Les premi\u00e8res questions soulev\u00e9es concernaient l&rsquo;\u00e9tat du r\u00e9gime en URSS vis-\u00e0-vis de l&rsquo;information, alors que Gorbatchev se trouvait engag\u00e9 dans une terrible bataille, d&rsquo;abord pour la <em>glasnost<\/em> (\u00ab\u00a0transparence\u00a0\u00bb, ou \u00ab\u00a0publicit\u00e9 des nouvelles\u00a0\u00bb) qui supposait la libre circulation de l&rsquo;information. Ces deux-trois jours de d\u00e9lais entre l&rsquo;accident et la premi\u00e8re annonce furent d&rsquo;abord per\u00e7us comme le signe de l&rsquo;\u00e9chec de sa tentative jusqu&rsquo;alors, sinon, pour les esprits les plus bienveillants, comme le signe que son projet de <em>glasnost<\/em> n&rsquo;\u00e9tait que de la propagande qui ne changeait rien au r\u00e9gime. <strong>Pourtant, il apparut rapidement que ce d\u00e9lai ne faisait que refl\u00e9ter en r\u00e9alit\u00e9 l&rsquo;\u00e9tat complet de d\u00e9sorganisation et de d\u00e9sordre qui r\u00e9gnait alors en URSS, et il semble bien que les nouvelles de Tchernobyl mirent un certain temps \u00e0 arriver au Kremlin, et que la d\u00e9p\u00eache de Tass du 28 ne faisait que t\u00e9moigner de cette lenteur.<\/strong> Ensuite mais aussit\u00f4t, les Russes, alors-Sovi\u00e9tiques, ne furent pas avares de d\u00e9clarations en URSS mais aussi dans les pays occidentaux de la part des ambassades et jusqu&rsquo;\u00e0 des interviews \u00e0 des organes de presse \u00e9trangers. (Vitali Chourkine, ambassadeur \u00e0 Washington, r\u00e9pondant \u00e0 une commission de l&rsquo;administration Reagan le 30 avril ; le diplomate A.I. Chegaeev faisant des \u00ab\u00a0confidences\u00a0\u00bb \u00e0 un ing\u00e9nieur ouest-allemand reproduites dans la presse le 2 mai ; Eltsine, alors secr\u00e9taire du PC de Moscou, parlant \u00e0 la TV ouest-allemande ARD le 2 mai ; Youry Kvitsinki, ambassadeur en RFA, r\u00e9pondant \u00e0 une interview de <em>Bild Zeitung<\/em> le 3 mai, etc&#8230;) Les r\u00e9ponses \u00e9taient tr\u00e8s souvent diff\u00e9rentes, m\u00eame contradictoires, t\u00e9moignant l\u00e0 aussi de l&rsquo;\u00e9tat de d\u00e9sordre du pays et les intervenants sovi\u00e9tiques ne cherchant pas \u00e0 le dissimuler.<\/p>\n<\/p>\n<p><p>Ce d\u00e9sordre n&rsquo;\u00e9tait pas du \u00e0 Gorbatchev, il ne faisait que t\u00e9moigner de l&rsquo;\u00e9tat de d\u00e9cr\u00e9pitude du r\u00e9gime tel qu&rsquo;il s&rsquo;\u00e9tait d\u00e9velopp\u00e9 pendant des d\u00e9cennies, tel que l&rsquo;avait trouv\u00e9 Gorbatchev, et il en t\u00e9moignait justement parce que la doctrine de Gorbatchev, bon an mal an, commen\u00e7ait \u00e0 se d\u00e9velopper, et que l&rsquo;information commen\u00e7ait \u00e0 rendre compte des r\u00e9alit\u00e9s (\u00e9videmment catastrophiques) de l&rsquo;\u00e9tat de l&rsquo;URSS. Bien que Gorbatchev ait qualifi\u00e9 la catastrophe de Tchernobyl comme l&rsquo;une des \u00ab\u00a0moments les plus graves et les plus tendus de sa pr\u00e9sidence\u00a0\u00bb, <strong>la fa\u00e7on dont la chose fut relay\u00e9e par la communication montra en v\u00e9rit\u00e9 que la <em>glasnost<\/em> \u00e9tait en marche, et le d\u00e9sordre qui \u00e9tait ainsi montr\u00e9 constitua finalement un des arguments pour cette dynamique<\/strong>.<\/p>\n<\/p>\n<p><p>Ce d\u00e9sordre avait une dimension strat\u00e9gique sinon apocalyptique qui fut assez vite r\u00e9alis\u00e9e. Il montrait l&rsquo;\u00e9tat d&rsquo;impr\u00e9paration incroyable des forces d&rsquo;intervention sovi\u00e9tiques agissant en cas de catastrophe nucl\u00e9aire comme en cas d&rsquo;attaque nucl\u00e9aire (le militaire et le civil intimement m\u00eal\u00e9s). Ce qui avait \u00e9t\u00e9 per\u00e7u \u00e0 l&rsquo;Ouest et pr\u00e9sent\u00e9 \u00e0 l&rsquo;Est comme un des avantages fondamentaux des capacit\u00e9s strat\u00e9giques sovi\u00e9tiques, &ndash; une puissante d\u00e9fense civile en cas d&rsquo;attaque nucl\u00e9aire, &ndash; se d\u00e9couvrait comme un mythe sans aucune r\u00e9alit\u00e9 \u00e0 l&rsquo;occasion d&rsquo;une catastrophe nucl\u00e9aire. <strong>A cet \u00e9gard, Tchernobyl joua un r\u00f4le fondamental, sinon d\u00e9cisif apr\u00e8s les diverses alertes \u00e0 cet \u00e9gard, dans la perception commune (\u00e0 l&rsquo;Est et \u00e0 l&rsquo;Ouest, chez Gorbatchev comme chez Reagan) du risque terrible d&rsquo;absence de contr\u00f4le du fait nucl\u00e9aire, donc de la fragilit\u00e9 extr\u00eame de l'\u00a0\u00bb\u00e9quilibre de la terreur\u00a0\u00bb<\/strong>. Cela fit beaucoup pour conduire les deux hommes \u00e0 une acc\u00e9l\u00e9ration suppl\u00e9mentaire d&rsquo;une tendance politique d\u00e9j\u00e0 en cours, d&rsquo;armistice et d&rsquo;arrangement nucl\u00e9aires, avec le sommet de Reykjavik d&rsquo;octobre 1986 et l&rsquo;accord sur l&rsquo;\u00e9limination totale des armes nucl\u00e9aires de th\u00e9\u00e2tre \u00e0 longue port\u00e9e (accord INF de d\u00e9cembre 1987). Accessoirement, mais non sans importance, cette interpr\u00e9tation donna un avantage important sinon d\u00e9cisif \u00e0 Gorbatchev <a href=\"http:\/\/www.dedefensa.org\/article\/la-syrie-ou-lenterrement-dun-complexe-cmi\">dans sa lutte<\/a> contre le monstrueux complexe militaro-industriel qui \u00e9crasait l&rsquo;URSS et dont il sut finalement se d\u00e9barrasser (Poutine devrait lui en \u00eatre gr\u00e9 aujourd&rsquo;hui, lui qui a pu ainsi reconstruire l&rsquo;industrie d&rsquo;armement sur des bases plus saines.)<\/p>\n<\/p>\n<p><p>Tchernobyl est surtout rest\u00e9 dans les m\u00e9moires comme un tournant de la lutte environnementale contre le nucl\u00e9aire, du d\u00e9veloppement des mouvements \u00e9cologistes, etc., alors que cet aspect des r\u00e9actions ne vint que secondairement et prit l&rsquo;importance consid\u00e9rable qu&rsquo;on lui a connue depuis \u00e0 cause de la dimension strat\u00e9gique et politique, et \u00e0 cause des remous internes en URSS \u00e0 propos des r\u00e9formes Gorbatchev. Bien qu&rsquo;il y ait eu diverses alertes de contamination nucl\u00e9aire par les conditions atmosph\u00e9riques (l&rsquo;orientation des vents notamment) qui montr\u00e8rent d&rsquo;ailleurs autant de d\u00e9sordre \u00e0 l&rsquo;Ouest qu&rsquo;\u00e0 l&rsquo;Est, mon sentiment constant \u00e0 cette \u00e9poque \u00e9tait bien que cet aspect \u00e9tait per\u00e7u d&rsquo;une fa\u00e7on secondaire et d&rsquo;une fa\u00e7on tr\u00e8s chaotique. Ce n&rsquo;est qu&rsquo;assez lentement que l&rsquo;ampleur apocalyptique des effets de la catastrophe sur l&rsquo;environnement fut r\u00e9alis\u00e9e pleinement, tandis qu&rsquo;apparaissaient les difficult\u00e9s \u00e9normes pour contenir les suites de la catastrophes, pour contr\u00f4ler les incendies, les malfonctionnements des r\u00e9acteurs, etc., avec des interventions humaines des sp\u00e9cialistes de la d\u00e9fense civile ou de l&rsquo;arm\u00e9e, dont certaines \u00e9taient d&rsquo;un r\u00e9el h\u00e9ro\u00efsme dans les conditions terribles de contamination.<\/p>\n<\/p>\n<blockquote>\n<p><p>Quoi qu&rsquo;il en soit, cette diversit\u00e9 des aspects de la catastrophe, sa dimension strat\u00e9gique et politique, sa dimension technologique, sa dimension sociale sinon structurelle, port\u00e8rent sans doute le coup le plus terrible \u00e0 l&rsquo;URSS agonisante telle qu&rsquo;elle apparaissait d&rsquo;une fa\u00e7on ouverte depuis l&rsquo;arriv\u00e9e de Gorbatchev. De cette fa\u00e7on, la catastrophe \u00e9tait bien celle de la fin d&rsquo;un monde et, par ses dimensions multiples, les m\u00e9langes de genres jusqu&rsquo;alors per\u00e7us comme s\u00e9par\u00e9s, notamment entre le civil et le militaire, \u00e9galement comme le d\u00e9but d&rsquo;une nouvelle \u00e8re. Je me rappelle que nous sent&icirc;mes le poids exceptionnel de cet \u00e9v\u00e9nement sans en saisir toutes les nuances, \u00e0 l&rsquo;\u00e9poque o&ugrave; nous le v\u00e9c&ucirc;mes, et qu&rsquo;il fut finalement et d&rsquo;une fa\u00e7on tout \u00e0 fait remarquable, moins per\u00e7u d\u00e8s l&rsquo;origine comme une p\u00e9rip\u00e9tie de plus de l&rsquo;affrontement Est-Ouest que comme une trag\u00e9die effectivement complexe qui appelait \u00e0 des changements fondamentaux, et qui annon\u00e7ait m\u00eame des changements fondamentaux qui allaient tous nous affecter, \u00e0 l&rsquo;Est comme \u00e0 l&rsquo;Ouest. <strong>Cela aussi, bien que cela ait une connotation absolument tragique, constituait une victoire psychologique de Gorbatchev, qui avait \u00e9t\u00e9 le premier dirigeant sovi\u00e9tique (et peut-\u00eatre le premier dirigeant politique tout court de l&rsquo;\u00e9poque) \u00e0 penser le monde et les risques strat\u00e9giques et technologiques hors des grands antagonismes politiques, mais plut\u00f4t comme d&rsquo;\u00e9normes risques catastrophiques nous mena\u00e7ant tous.<\/strong><\/p>\n<\/p>\n<p><p>&#8230; Voil\u00e0 pour le pass\u00e9 mais le pr\u00e9sent \u00e0 ses exigences, dont certaines ne sont pas banales. Certes, ce ne sont pas ces seules consid\u00e9rations qui m&rsquo;ont conduit \u00e0 ce texte du <em>Journal dde.crisis<\/em>, puisque s&rsquo;y ajoute une autre nouvelle, vieille de quelques heures, qui m&rsquo;est apparue, \u00e0 la lumi\u00e8re de ce que nous avons appris \u00e0 croire et \u00e0 savoir de Tchernobyl et de ses cons\u00e9quences, comme un \u00e9trange contrepied des \u00e9v\u00e8nements ; et c&rsquo;est plus \u00e0 elle qu&rsquo;au tamis de mes souvenirs que l&rsquo;on doit ce texte, car c&rsquo;est finalement bien \u00e0 elle que je veux en venir. Je me rapporte \u00e0 telle nouvelle, retransmise notamment par les Russes, <strong>sur l&rsquo;\u00e9tat de la flore et de la faune dans le territoire d\u00e9cr\u00e9t\u00e9 zone interdite de Tchernobyl depuis trente ans, sans pr\u00e9sence humaine ; car ce qui devrait \u00eatre une sorte de \u00ab\u00a0zone maudite\u00a0\u00bb est en fait devenue rien de moins qu&rsquo;une \u00ab\u00a0r\u00e9serve naturelle\u00a0\u00bb qui s&rsquo;est cr\u00e9\u00e9e d&rsquo;elle-m\u00eame&#8230;<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je donne rapidement le texte RT-fran\u00e7ais du 24 avril 2016, <a href=\"https:\/\/francais.rt.com\/international\/19581-tchernobyl-30-ans-reserve-naturelle\">trente ans plus tard<\/a>, qui est surtout l\u00e0 comme l\u00e9gende de vid\u00e9os montrant une nature sauvage et assez belle, sinon tr\u00e8s belle, avec une profusion remarquable d&rsquo;animaux&#8230; &laquo; <em>A la grande surprise de tous, apr\u00e8s la catastrophe nucl\u00e9aire qui a eu lieu il y a 30 ans, les animaux n&rsquo;ont pas quitt\u00e9 la zone radioactive. Les grands mammif\u00e8res y sont d\u00e9sormais beaucoup plus nombreux qu&rsquo;avant la catastrophe nucl\u00e9aire<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le 26 avril 1986, l&rsquo;incendie et l&rsquo;explosion de la centrale de Tchernobyl ont conduit \u00e0 l&rsquo;accident nucl\u00e9aire le plus grave de l&rsquo;histoire du nucl\u00e9aire civil. De grandes concentrations de particules radioactives se sont retrouv\u00e9es dans l&rsquo;air for\u00e7ant les autorit\u00e9s \u00e0 demander aux habitants de la r\u00e9gion de quitter d\u00e9finitivement les lieux. Des milliers de personnes ont \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 plus de 4 300 kilom\u00e8tres. En revanche, les animaux, eux, sont rest\u00e9s. Trente ans apr\u00e8s la catastrophe, une \u00e9quipe de chercheurs g\u00e9orgiens a conclu que la faune sauvage prosp\u00e9rait dans le p\u00e9rim\u00e8tre d&rsquo;exclusion entourant la centrale. Contre toute attente, <strong>le site ressemble plus \u00e0 une r\u00e9serve naturelle qu&rsquo;\u00e0 une zone sinistr\u00e9e<\/strong><\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les chercheurs ont laiss\u00e9 94 app\u00e2ts olfactifs et 30 cam\u00e9ras contr\u00f4l\u00e9es \u00e0 distance dans les villages abandonn\u00e9s. Pendant cinq mois, au moins 14 esp\u00e8ces ont \u00e9t\u00e9 film\u00e9s et plus de 173 d\u00e9couvertes. Il s&rsquo;est av\u00e9r\u00e9 que les animaux que l&rsquo;on rencontre le plus souvent sont des bisons eurasiatiques, des \u00e9cureuils roux, des \u00e9lans, des sangliers et des loups gris. Si de l&rsquo;ext\u00e9rieur, tous ces animaux ont l&rsquo;air parfaitement sains, ils n&rsquo;ont pas encore \u00e9t\u00e9 v\u00e9ritablement examin\u00e9s par des scientifiques.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>J&rsquo;imagine que ces constats, vid\u00e9os, etc., peuvent donner lieu, et donneront lieu si ce n&rsquo;est d\u00e9j\u00e0 fait, \u00e0 diverses r\u00e9flexions, controverses, sur la sant\u00e9 des b\u00eates, sur la r\u00e9elle nocivit\u00e9 du nucl\u00e9aire, sur la moralit\u00e9 des choses et la relativit\u00e9 des appr\u00e9ciations, avec le travail des \u00ab\u00a0scientifiques\u00a0\u00bb pour savoir si ces animaux sont \u00ab\u00a0sains\u00a0\u00bb (et peut-\u00eatre sauront-ils nous expliquer, en passant, ce que c&rsquo;est qu&rsquo;\u00eatre \u00ab\u00a0sain\u00a0\u00bb, aujourd&rsquo;hui). <strong>Je pr\u00e9f\u00e8re me tenir \u00e0 distance de toute cette connaissance raisonneuse et imp\u00e9rative, de ces moralit\u00e9s diverses en forme de <em>diktat<\/em>, pour ne consid\u00e9rer que le symbole<\/strong>. Je suis un ami des b\u00eates, au sens de la force du sentiment et du penchant du caract\u00e8re plus que d&rsquo;une appartenance \u00e0 une association, parce que je distingue dans leur manufacture un rangement qui met en avant une s\u00e9paration de ce qui est du domaine du Bien de ce qui est vuln\u00e9rable aux atteintes du Mal, bien propre \u00e0 d\u00e9gager ce que, dans un \u00eatre, on peut sortir de meilleur en fonction des sp\u00e9cificit\u00e9s dont la nature divine du monde l&rsquo;a dot\u00e9.<\/p>\n<\/p>\n<p><p>J&rsquo;aime \u00e0 citer Schellings, le m\u00e9taphysicien allemand, parce que, apr\u00e8s un temps, de relecture en relecture, j&rsquo;ai finalement r\u00e9ussi \u00e0 embrasser la profondeur du propos : &laquo; <em>Et, de m\u00eame qu&rsquo;il y a un enthousiasme (Enthusiasmus) pour le bien, il y a aussi une exaltation de l&rsquo;esprit (Begeisterung) pour le mal. Chez l&rsquo;animal, comme chez tout \u00eatre naturel, ce principe obscur, assur\u00e9ment, est aussi \u00e0 l&rsquo;&oelig;uvre, mais il n&rsquo;est pas parvenu comme chez l&rsquo;homme \u00e0 la lumi\u00e8re, il n&rsquo;est pas <strong>esprit <\/strong>et entendement, mais passion (Sucht) et app\u00e9tition aveugle, bref aucune chute, aucune s\u00e9paration des principes ne sont possibles l\u00e0 o&ugrave; il n&rsquo;y a encore aucune unit\u00e9 absolue ou personnelle<\/em> [&#8230;] <em>L&rsquo;animal ne peut jamais sortir de l&rsquo;unit\u00e9, tandis que l&rsquo;homme peut rompre quand il lui pla&icirc;t (willk\u00fcrch) le lien des forces. C&rsquo;est pourquoi Fr. Baader dit avec raison qu&rsquo;il serait \u00e0 souhaiter que la perversit\u00e9 ne puisse aller chez l&rsquo;homme que jusqu&rsquo;\u00e0 l&rsquo;animalit\u00e9 (\u00e0 devenir animal<strong>), mais que malheureusement l&rsquo;homme ne saurait \u00eatre qu&rsquo;en-de\u00e7a ou au-del\u00e0 de l&rsquo;animal<\/strong>. <\/em>&raquo; &#8230; Et puis l\u00e0-dessus, je me rappelle ce que j&rsquo;\u00e9crivis \u00e0 propos de ma chienne <em>Margot<\/em>, lorsqu&rsquo;elle mourut apr\u00e8s plusieurs mois d&rsquo;h\u00e9ro\u00efque agonie, <a href=\"http:\/\/www.dedefensa.org\/article\/a-margot-pour-quelle-repose-en-paix\">en mai 2011<\/a>, parce que ces mots font partie de ceux \u00e0 propos desquels j&rsquo;\u00e9prouve l&rsquo;un des plus grands bonheurs \u00e0 les avoir \u00e9crits, <strong>parce qu&rsquo;ils sont pour moi un honneur que je rendis \u00e0 un \u00eatre qui le m\u00e9ritait pleinement et enti\u00e8rement <\/strong>:<\/p>\n<\/p>\n<p><p>&laquo; <em>\u00ab\u00a0Elle \u00e9tait venue poser sa t\u00eate, c&rsquo;est-\u00e0-dire sa puissante m\u00e2choire qui aurait broy\u00e9 un bras, sur mes genoux, dans un mouvement d&rsquo;une douceur infinie. Elle \u00e9tait rest\u00e9e, peut-\u00eatre deux ou trois minutes, dans cette attitude \u00e9trange, avec son regard, qui semblait si apais\u00e9, qui cherchait et trouvait le mien. Je la caressai. Elle me disait adieu.\u00a0\u00bb<\/em> [&#8230;] <em>Pensant aux sentiments que j&rsquo;\u00e9prouvais pour elle, o&ugrave;, bien entendu, amour et tendresse ont leur place sans fin, j&rsquo;ajouterai que j&rsquo;avais aussi de l&rsquo;estime, voire du respect, notamment pour ce que je nommerais son h\u00e9ro\u00efsme, o&ugrave; l&rsquo;on trouvait \u00e9galement du sto\u00efcisme. Cet \u00eatre portait, dans son allure, dans son geste, dans l&rsquo;\u00e9quilibre de son mouvement et dans la r\u00e9solution de son attitude, dans la patience d\u00e9sinvolte qu&rsquo;elle montrait, la noblesse de son caract\u00e8re. Curieusement mais r\u00e9solument, je sens que je n&rsquo;ai pas \u00e0 m&rsquo;expliquer de ces sentiments pour un animal, de la consid\u00e9ration que je lui porte, de la certitude intuitive de me trouver devant l&rsquo;innocence originelle. S&rsquo;il faut une explication, ce sont les hommes qui devront me la donner ; notamment pourquoi, consid\u00e9rant ce qu&rsquo;ils sont devenus et ce qu&rsquo;ils ont fait d&rsquo;eux-m\u00eames, pourquoi il faudrait que je les consid\u00e9rasse n\u00e9cessairement comme d&rsquo;essence sup\u00e9rieure \u00e0 Margot<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi ne s&rsquo;\u00e9tonnera-t-on pas si je consid\u00e8re que ce ne peut \u00eatre que belle justice symbolique et divine que <strong>les lieux maudits pour les hommes de Tchernobyl, et maudits par leurs actes, soient devenus une terre d&rsquo;\u00e9lection pour les animaux, que leur pr\u00e9sence en accordance avec la r\u00e9silience de la nature ait vaincu ce que l&rsquo;intelligence humaine a produit de plus prodigieux et de plus prodigieusement mauvais, passant de \u00ab\u00a0l&rsquo;enthousiasme pour le bien\u00a0\u00bb \u00e0 l'\u00a0\u00bbexaltation pour le mal\u00a0\u00bb<\/strong>. Laissez-moi m\u00e9diter un instant \u00e0 propos de ce symbole de ces animaux en leur royaume de Tchernobyl, en avan\u00e7ant cette observation \u00e9videmment symbolique <strong>que leur innocence originelle est parvenue \u00e0 r\u00e9duire l&rsquo;&oelig;uvre d&rsquo;entropisation de la Mati\u00e8re lorsqu&rsquo;elle est manipul\u00e9e par les hommes, pour ce que les hommes en ont fait.<\/strong> Je ne juge ni ne condamne en cet instant, bien loin de me trouver dans un pr\u00e9toire, mais j&rsquo;observe le symbole, c&rsquo;est-\u00e0-dire ce que je veux consid\u00e9rer comme symbole, pour mieux m\u00e9diter \u00e0 ce propos.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ne me parlez pas de cruaut\u00e9 et de loi de la jungle, vous autres avec vos lois internationales, morales et vertueuses, qui ne servent aujourd&rsquo;hui qu&rsquo;\u00e0 justifier \u00e0 vos propres yeux le chaos, le malheur des \u00eatres, la souffrance des \u00e2mes et la destruction du monde. Les animaux savent comment survivre et ils n&rsquo;ont pas peur de la mort, ni des actes qui y conduisent parce qu&rsquo;ils en savent d&rsquo;instinct l&rsquo;in\u00e9luctabilit\u00e9 et qu&rsquo;il leur a \u00e9t\u00e9 donn\u00e9 la gr\u00e2ce de ne pas laisser &laquo; <em>ce principe obscur <\/em>[parvenir] <em>comme chez l&rsquo;homme \u00e0 la lumi\u00e8re <\/em>[parce que, chez eux,]<em> il n&rsquo;est pas <strong>esprit <\/strong>et entendement<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Laissez-moi contempler ce symbole des animaux en leur royaume, \u00e0 Tchernobyl-2016, trente ans apr\u00e8s Tchernobyl-1986.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De Tchernobyl-1986 \u00e0 Tchernobyl-2016 25 avril 2016 (1986) &ndash; Je voudrais donner ici quelques indications, dans mon souvenir et aussi avec l&rsquo;aide d&rsquo;une consultation rapide des num\u00e9ros de dedefensa &#038; eurostrat\u00e9gie (dd&#038;e, Lettre d&rsquo;Analyse\/papier) de l&rsquo;\u00e9poque, des conditions que nous conn&ucirc;mes, dans le monde de ce que nous ne nommions pas encore \u00ab\u00a0la communication\u00a0\u00bb, selon&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6045,7554,3483,11145,13374,3004,4207,17469,963],"class_list":["post-76541","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-catastrophe","tag-glasnost","tag-gorbatchev","tag-margot","tag-naturelle","tag-nucleaire","tag-reserve","tag-schellings","tag-urss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76541"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76541\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}