{"id":76566,"date":"2016-05-12T05:45:08","date_gmt":"2016-05-12T05:45:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/12\/les-incontinences-de-francois-h-le-rappeur-de-lelysee\/"},"modified":"2016-05-12T05:45:08","modified_gmt":"2016-05-12T05:45:08","slug":"les-incontinences-de-francois-h-le-rappeur-de-lelysee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/12\/les-incontinences-de-francois-h-le-rappeur-de-lelysee\/","title":{"rendered":"Les incontinences de Fran\u00e7ois H., le rappeur de l&rsquo;\u00c9lys\u00e9e"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les incontinences de Fran\u00e7ois H., le rappeur de l&rsquo;&Eacute;lys\u00e9e<\/h2>\n<\/p>\n<p><p>12 mai 2016 &ndash; En un sens, ce type, Fran\u00e7ois H., est plus \u00ab\u00a0performant\u00a0\u00bb en fait de d\u00e9construction qu&rsquo;un Robespierre ou qu&rsquo;un L\u00e9nine. Il a l&rsquo;air bonasse du notaire de province rougissant et un peu moite qui va au boxon tirer son coup en douce, mais c&rsquo;est d\u00e9sormais un habitu\u00e9. Dans tout ce qu&rsquo;il fait, Fran\u00e7ois H. parvient \u00e0 une quasi-perfection dans l&rsquo;acte mal\u00e9fique, et surtout dans l&rsquo;auto-dissimulation de cet agir-l\u00e0 qu&rsquo;il r\u00e9alise comme on tire la chasse, en catimini et en col-cravate. Bref, c&rsquo;est pas mon genre&#8230;<\/p>\n<\/p>\n<p><p>Tout cela pour dire qu&rsquo;il a r\u00e9ussi \u00e0 me faire signer une p\u00e9tition, pour la premi\u00e8re fois de ma vie. (Je suis le citoyen d\u00e9mocratique mod\u00e8le tel que je le r\u00eave : j&rsquo;ai vot\u00e9 une fois dans ma vie, j&rsquo;ai sign\u00e9 une p\u00e9tition une fois dans ma vie, et cela \u00e0 l&rsquo;un et l&rsquo;autre bout de ma vie.) D\u00e9j\u00e0, avant-hier, <a href=\"https:\/\/francais.rt.com\/france\/20342-autorites-choisissent-rappeur-pour-commemorer-verdun-scandale\">en lisant ceci<\/a> sur RT-fran\u00e7ais, j&rsquo;\u00e9tais un peu mal \u00e0 l&rsquo;aise, &ndash; vous savez, comme lorsqu&rsquo;on va s&rsquo;indigner de quelque chose et que l&rsquo;on ne va pas plus loin, &ndash; \u00ab\u00a0\u00e0 quoi bon ?\u00a0\u00bb, se dit-on, \u00e9puis\u00e9 de tant d&rsquo;indignations diverses, et puis appel\u00e9 \u00e0 une t\u00e2che urgente que vous pr\u00e9pariez d\u00e9j\u00e0&#8230; Tout de m\u00eame me disais-je encore, choisir un rappeur pour c\u00e9l\u00e9brer Verdun, tout de m\u00eame &#8230; Et puis, autre chose \u00e0 faire&#8230;<\/p>\n<\/p>\n<p><p>(RT : &laquo; <em>Afin de comm\u00e9morer le centenaire de la plus meurtri\u00e8re des batailles de la Premi\u00e8re Guerre mondiale, le gouvernement a d\u00e9cid\u00e9 d&rsquo;organiser un concert de rap le 29 mai<\/em>. [&#8230;] <em>L&rsquo;Elys\u00e9e souhaitait un rendez-vous populaire qui fasse la part belle \u00e0 la jeunesse. Il a donc organis\u00e9 un concert gratuit pour comm\u00e9morer les cent ans de la terrible bataille de Verdun. Jusque-l\u00e0, rien de bien clivant. Sauf que la t\u00eate d&rsquo;affiche n&rsquo;est pas pour plaire \u00e0 tout le monde. C&rsquo;est Black M, rappeur issu du groupe Sexion d&rsquo;Assaut, qui a \u00e9t\u00e9 choisi. Accompagn\u00e9 de Lefa et Abou Debeing, il chantera le 29 mai au Parc de Londres, \u00e0 Verdun<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Hier matin, je re\u00e7ois un message annon\u00e7ant une p\u00e9tition et m&rsquo;invitant \u00e0 la signer, et alors l\u00e0, c&rsquo;est vrai, la chose explose silencieusement dans mon esprit, se r\u00e9alise, s&rsquo;impose compl\u00e8tement et je n&rsquo;y tiens plus ! Je signe aussit\u00f4t, et, pour faire suivre \u00e0 qui le voudra, envoies la p\u00e9tition ici ou l\u00e0 ; ce moment-l\u00e0, \u00e0 cet instant, \u00e9tait absolument opportun. Soudain, tout s&rsquo;est assembl\u00e9 dans mon esprit, et ce qu&rsquo;est Verdun pour moi, et les voir l\u00e0, qui ont trouv\u00e9 cette trouvaille de \u00ab\u00a0communicant\u00a0\u00bb trouveur-de-trouvaille, absolument atroce, signe affreux d&rsquo;un caract\u00e8re compl\u00e8tement dissous, &ndash; m\u00eame pas dissolu, non dissous, &ndash; d&rsquo;une colonne vert\u00e9brale aussi ferme qu&rsquo;un \u00e9clair au chocolat, d&rsquo;un c&oelig;ur sec comme un coup de trique, d&rsquo;une \u00e2me aussi inspir\u00e9e qu&rsquo;une endive, d&rsquo;une \u00e9rection extr\u00eamement molle jusqu&rsquo;\u00e0 pouvoir figurer comme \u00ab\u00a0cr\u00e9ation contemporaine\u00a0\u00bb dans un atelier d&rsquo;exposition d\u00e9mocratique de l&rsquo;Art Contemporain (AC).<\/p>\n<\/p>\n<p><p>(Imaginez que Monsieur Bernard Arnault, Pr\u00e9sident-directeur g\u00e9n\u00e9ral de LVMH, Pr\u00e9sident de la <a href=\"https:\/\/www.lvmh.fr\/actualites-documents\/actualites\/daniel-buren-colore-fondation-louis-vuitton\/\">Fondation Louis Vuitton<\/a> et grand m\u00e9c\u00e8ne devant l&rsquo;\u00e9ternel de l&rsquo;A.C., et enfin \u00e9l\u00e9gant cornac et pygmalion de sa Fondation, nous dise, entre flute \u00e0 champagne, cravate en soie et Merc\u00e9d\u00e8s coup\u00e9e \u00e0 sa taille : &laquo; <em>Fran\u00e7ois H. a con\u00e7u un projet grandiose, pertinent et enchanteur, fruit d&rsquo;un dialogue v\u00e9ritable avec sa propre \u00ab\u00a0bite \u00e0 \u00e9rection extr\u00eamement molle\u00a0\u00bb. Son &oelig;uvre r\u00e9pond magnifiquement \u00e0 l&rsquo;architecture dans la continuit\u00e9 d&rsquo;un travail, initi\u00e9 d\u00e8s les ann\u00e9es 1970, o&ugrave; se croisent couleurs, transparence et lumi\u00e8re<\/em>. &raquo; Si vous voulez, le travail de l&rsquo;artiste dit-\u00ab\u00a0bite \u00e0 \u00e9rection extr\u00eamement molle\u00a0\u00bb comme \u00e9quivalent A.C.-postmoderne de la cath\u00e9drale gothique, &ndash; voil\u00e0, c&rsquo;est cela, bite-molle <em>versus<\/em> cath\u00e9drale gothique&#8230; Le march\u00e9 tranchera, on sait bien dans quel sens.)<\/p>\n<\/p>\n<p><p>Je persifle, certes, et me conduis en garnement mais c&rsquo;est pour mieux dissimuler l&rsquo;indignation silencieuse qui me prend et me soul\u00e8ve. Savent-ils ce que c&rsquo;est que Verdun, ces types dans leur 4&#215;4 aux vitres teint\u00e9es et leurs Peugeot grand luxe ? Ont-ils consacr\u00e9 un instant de leur pr\u00e9cieux temps-compt\u00e9 \u00e0 tenter de saisir la nostalgie tragique du souvenir de l&rsquo;immense et terrible bataille ? Savent-ils encore \u00ab\u00a0tenter de saisir\u00a0\u00bb ? Peuvent-ils encore entr&rsquo;apercevoir l&rsquo;immensit\u00e9 tragique de cet \u00e9v\u00e9nement, cette horreur m\u00e9lang\u00e9e au sublime exactement, toutes ces choses que leurs petits phrases \u00e9triqu\u00e9es comme leurs petits costumes et m\u00e9caniques comme leurs psalmodies labellis\u00e9es-\u00ab\u00a0droit-de-l&rsquo;homme\u00a0\u00bb, ne peuvent jamais esp\u00e9rer effleurer seulement ? Devant eux, devant leur impuissance \u00e0 embrasser le tragique du monde, mon indignation elle-m\u00eame devient s\u00e9r\u00e9nit\u00e9, comme stup\u00e9faite et presque apais\u00e9e par l&rsquo;immensit\u00e9 du vide que des \u00eatres aussi affreusement non-signifiants et de constitutions certes fragiles peuvent arriver \u00e0 produire, ou \u00e0 pondre, comme les poules des &oelig;ufs, comme l&rsquo;on pond exactement l&rsquo;immensit\u00e9 du vide.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, je suis d&rsquo;une foi bien approximative sinon mauvaise, moi avec mon obsession vertueuse de Verdun ; je le reconnais, de parti-pris, sans complaisance, sans am\u00e9nit\u00e9 pour les pleureuses du type \u00ab\u00a0quelle-absurdit\u00e9-la guerre\u00a0\u00bb, \u00ab\u00a0plus-jamais-\u00e7a\u00a0\u00bb ; non qu&rsquo;elles disent, les pleureuses, des choses non fond\u00e9es, mais simplement parce qu&rsquo;elles parlent de choses qui les d\u00e9passent et qui leur laissent du temps pour \u00ab\u00a0aller jouer avec cette poussi\u00e8re\u00a0\u00bb. (<a href=\"http:\/\/www.babelio.com\/livres\/Montherlant-Va-jouer-avec-cette-poussiere\/49329\"><em>Va jouer avec cette poussi\u00e8re<\/em><\/a>, conseillait Henry de Montherlant.) Non, il n&rsquo;est pas utile d&rsquo;essayer de dire une fois de plus ce que Verdun <a href=\"http:\/\/www.dedefensa.org\/article\/2016-notre-verdun-et-ma-nostalgie-infinie-1\">repr\u00e9sente pour moi<\/a>, cet instant apocalyptique o&ugrave; s&rsquo;exprima absolument le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb et o&ugrave; tant de jeunes hommes surent lui r\u00e9sister, au prix de la vie pr\u00e9cieuse de tant de milliers de jeunes hommes&#8230; Oui Sire, c&rsquo;\u00e9tait aussi le temps <a href=\"http:\/\/www.dedefensa.org\/article\/chronique-du-19-courant-jai-rendez-vous-avec\">o&ugrave; Alan Seeger \u00e9crivait<\/a>, avec comme le d\u00e9fi du sacrifice dans sa plume tragique : &laquo; &#8230;<em>Mais j&rsquo;ai rendez-vous avec la Mort <\/em>\/ <em>A minuit, dans quelque ville en flammes,<\/em> \/ <em>Quand le printemps s&rsquo;en va vers le nord<\/em> \/ <em>Et, fid\u00e8le \u00e0 la parole donn\u00e9e,<\/em> \/ <em>Je ne manquerai pas ce rendez-vous<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Ainsi Fran\u00e7ois H. rappera-t-il, le 29 mai, au bras de <em>Black M<\/em>, achevant ainsi la d\u00e9construction reconstructive des civilisations qui se sont fortement entrechoqu\u00e9es ces derniers temps. En 1984, dans le froid glacial d&rsquo;une soir\u00e9e de novembre de la bataille comm\u00e9mor\u00e9e sur le champ d&rsquo;elle-m\u00eame, devant les croix de l&rsquo;immense cimeti\u00e8re et de son ossuaire, Fran\u00e7ois Mitterrand avait pris la main d&rsquo;Helmut Kohl pour consacrer dans cet instant la solitude m\u00e9taphysique d&rsquo;un silence tragique ; trente ans plus tard, Fran\u00e7ois H. prend le bras de <em>Black M<\/em>, et l&rsquo;on rappera Folleville ! Je n&rsquo;\u00e9tais pas tr\u00e8s fanatique de l&rsquo;esprit qui pr\u00e9sidait \u00e0 cette rencontre Mitterrand-Kohl, qui enterrait un peu trop vite les morts sans avoir exactement identifi\u00e9 la cause de leur malheur, &ndash; le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb et nullement \u00ab\u00a0le choc des nations\u00a0\u00bb, &ndash; mais enfin la dignit\u00e9 et le sens du tragique n&rsquo;\u00e9taient pas absents de ce rendez-vous digne d&rsquo;Alan Seeger. Ainsi peut-on mieux mesurer le rude chemin parcouru \u00e0 marche forc\u00e9e, et l&rsquo;on aurait tort de trop s&rsquo;en exclamer, ou de trop hurler d&rsquo;indignation. Je suis s&ucirc;r que certains trouveront l&rsquo;id\u00e9e charmante, et puis, hein, \u00e9lectoralement fort bien ajust\u00e9e.<\/p>\n<\/p>\n<p><p>&#8230;C&rsquo;est-\u00e0-dire qu&rsquo;il faut laisser dire, laisser faire et laisser aller, car la sottise des <a href=\"http:\/\/www.dedefensa.org\/article\/le-zombie-et-la-porte-ouverte-toc-toc-toc\">zombies-Syst\u00e8me<\/a> est encore plus grande que celle de leur seul ma&icirc;tre \u00e0 tous, dont vous savez bien, &ndash; je r\u00e9p\u00e8te souvent cette citation de Gu\u00e9non, &ndash; qu&rsquo;il ne peut jamais se dispenser de faire une sottise&#8230; (&laquo; <em>On dit m\u00eame que le diable, quand il veut, est fort bon th\u00e9ologien ; il est vrai, pourtant, qu&rsquo;il ne peut s&#8217;emp\u00eacher de laisser \u00e9chapper toujours quelque sottise, qui est comme sa signature.<\/em>.. &raquo;) Ainsi, par leur sottise assez remarquable pour qu&rsquo;on la mesure abyssale, par leur absence compl\u00e8te de conviction et d&rsquo;intuition, par leur inf\u00e9condit\u00e9, par leur s\u00e9cheresse de vieille fille-notaire de province d\u00e9guis\u00e9e en jeune mac de l&rsquo;esprit postmoderne, ainsi organisent-ils encore plus rapidement que sa gravit\u00e9 ne le promet l&rsquo;effondrement de la chose informe qu&rsquo;ils ont fini par nous arranger. Ils sont \u00e0 peine grotesques, parce que difficile \u00e0 distinguer, parce qu&rsquo;on voit au travers d&rsquo;eux, parce que la transparence qu&rsquo;ils vous promettent dans leur politique est d\u00e9j\u00e0 l\u00e0, effa\u00e7ant leur substance informe et r\u00e9duisant \u00e0 rien leur essence. Ils sont invisibles \u00e0 force de transparente inexistence&#8230; \u00ab\u00a0Fermez le ban !\u00a0\u00bb disait le sous-officier caricatur\u00e9 ais\u00e9ment bas-de-plafond ; \u00ab\u00a0Tirez la chasse !\u00a0\u00bb dit le gardien du mus\u00e9e de la postmodernit\u00e9 o&ugrave; l&rsquo;exposition du rien r\u00e9duit la visite \u00e0 pas grand&rsquo;chose, et le dernier n&rsquo;oubliera pas de fermer la porte derri\u00e8re lui sur ce mus\u00e9e disparu en poussi\u00e8re lorsque l&rsquo;entropisation aura achev\u00e9 son &oelig;uvre.<\/p>\n<\/p>\n<p><p>&#8230; Ainsi est-il arriv\u00e9, ce moment o&ugrave; moi qui n&rsquo;ai gu\u00e8re l&rsquo;habitude de l&rsquo;activisme militant, je vous dis, lecteurs, pour ceux-l\u00e0 qui partageraient mon indignation devenue s\u00e9r\u00e9nit\u00e9 : si vous en avez le go&ucirc;t, faites comme moi, <a href=\"http:\/\/www.net-petitions.com\/contre-la-venue-du-rappeur-black-m-a-verdun\/\">signez la p\u00e9tition<\/a>. Advienne que pourra et qu&rsquo;elles continuent \u00e0 reposer en paix, <em><a href=\"http:\/\/www.dedefensa.org\/article\/de-la-grande-guerre\">Les &Acirc;mes de Verdun<\/a><\/em>, tandis que le rappeur danse avec cette poussi\u00e8re.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>J&rsquo;ajoute ici quelques citations venues d&rsquo;un site ou l&rsquo;autre, pour rendre compte du climat d&rsquo;enthousiasme qui salue l&rsquo;initiative parisienne-verdunoise du 29 mai.<\/p>\n<\/p>\n<p><p>&bull; De <em><a href=\"http:\/\/www.lefigaro.fr\/vox\/histoire\/2016\/05\/11\/31005-20160511ARTFIG00316-commemorations-de-verdun-que-fete-t-on-monsieur-le-president.php\">Koztoujours, le 11 mai <\/a><\/em>: &laquo; <em>Ainsi le <a href=\"https:\/\/www.francebleu.fr\/infos\/societe\/le-rappeur-black-m-tete-d-affiche-du-concert-pour-le-centenaire-de-la-bataille-de-verdun-1462864057\">rappeur Black M sera t\u00eate d&rsquo;affiche<\/a> du concert de comm\u00e9moration de la bataille de Verdun le 29 mai prochain &ndash; la seule date officielle &ndash; comme l&rsquo;a d\u00e9voil\u00e9 le Secr\u00e9taire d&rsquo;Etat aux anciens combattants hier. Pourquoi un concert ? Pourquoi une f\u00eate ? Pourquoi Black M ? Pourquoi t\u00eate d&rsquo;affiche ? Un concert, cela peut s&rsquo;envisager. Certes. Il peut y en avoir de magnifiques et m\u00eame improvis\u00e9s. Personne n&rsquo;a oubli\u00e9 Rostropovitch au pied du Mur de Berlin. Vous me direz que Rostropovitch, c&rsquo;est \u00e9litiste et que, depuis que l&rsquo;on a abandonn\u00e9 l&rsquo;id\u00e9e d&rsquo;\u00e9lever les hommes, d&rsquo;\u00e9lever les \u00e2mes, par l&rsquo;art et par la beaut\u00e9, cela ne se fait plus. Permettez-moi de penser tout de m\u00eame qu&rsquo;entre Rostropovitch et Black M, il y avait de la marge. Il y a des concerts dignes, il y a des concerts festifs : tout l&rsquo;enjeu est de savoir discerner les circonstances appropri\u00e9es. Ce discernement \u00e9l\u00e9mentaire vous manque-t-il, \u00e0 vous, \u00e0 vos conseillers, \u00e0 votre ministre ?! <\/em>&raquo;<\/p>\n<\/p>\n<p><p>(Note personnelle pour une autre comparaison illustrant le go&ucirc;t exquis du temps courant : du concert de l&rsquo;Orchestre Symphonique du Th\u00e9\u00e2tre Marinski de Saint-Petersbourg <a href=\"http:\/\/www.francemusique.fr\/actu-musicale\/syrie-valery-gergiev-dirige-un-concert-dans-l-amphitheatre-de-palmyre-130529\">\u00e0 Palmyre le 6 mai<\/a>, pour saluer les victimes de la barbarie-en-cours, le ministre britannique de la d\u00e9fense de Sa tr\u00e8s Gracieuse Majest\u00e9 a dit que c&rsquo;\u00e9tait une &laquo; <em>tentative de mauvais go&ucirc;t de d\u00e9tourner l&rsquo;attention des souffrances continues de millions de Syriens<\/em> &raquo;. Bach, Prokofiev et Tchedrine \u00e0 Palmyre, c&rsquo;est le mauvais go&ucirc;t ; <em>Black M<\/em> \u00e0 Verdun, c&rsquo;est la classe. Imparable, Votre Honneur.)<\/p>\n<\/p>\n<p><p>&bull; De Maxime Tandonnet, dans <a href=\"http:\/\/www.lefigaro.fr\/vox\/politique\/2016\/05\/11\/31001-20160511ARTFIG00111-concert-de-rap-aux-ceremonies-de-verdun-la-france-humiliee.php\"><em>FigaroVox<\/em>, le 11 mai<\/a> : &laquo; <em>Le chanteur a cru bon de se justifier: \u00ab\u00a0C&rsquo;est la sc\u00e8ne et c&rsquo;est quelque chose que j&rsquo;aime \u00e9norm\u00e9ment <\/em>[&hellip;]<em> Je les invite \u00e0 venir me voir, qu&rsquo;ils aiment ou pas ma musique, on va s&rsquo;amuser\u00a0\u00bb. Mais, justement, la pens\u00e9e de Verdun, la comm\u00e9moration de cet atroce martyre des jeunesses et des peuples europ\u00e9ens, ne se pr\u00eatent pas \u00e0 la sc\u00e8ne ni \u00e0 l&rsquo;amusement. Imagine-t-on un concert de rap pour cl\u00f4turer d&rsquo;autres c\u00e9r\u00e9monies solennelles, comme la panth\u00e9onisation de Jean Moulin ou de Pierre Brossolette, la c\u00e9l\u00e9bration du 11 novembre ou du 8 mai, la journ\u00e9e de la D\u00e9portation ou la comm\u00e9moration de l&rsquo;abolition de l&rsquo;esclavage?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Non, alors, pourquoi Verdun? Ce nom est aujourd&rsquo;hui un symbole complexe du patriotisme absolu, jusqu&rsquo;au sacrifice ultime du bonheur et de la vie, du courage et de la volont\u00e9 inflexibles &#8211; &laquo;ils ne passeront pas&raquo; &#8211; de l&rsquo;honneur, de l&rsquo;unit\u00e9 des Fran\u00e7ais, de l&rsquo;absurdit\u00e9 sanglante de la haine et enfin, de la r\u00e9conciliation entre deux peuples. D\u00e9sacraliser ainsi Verdun est une mani\u00e8re d&rsquo;achever ces grands principes que les \u00e9lites dirigeantes fran\u00e7aises jugent d\u00e9sormais d\u00e9pass\u00e9s et incompatibles avec l&rsquo;id\u00e9ologie dominante, fond\u00e9e sur le culte du libre arbitre individuel, du narcissisme et de l&rsquo;argent roi<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les incontinences de Fran\u00e7ois H., le rappeur de l&rsquo;&Eacute;lys\u00e9e 12 mai 2016 &ndash; En un sens, ce type, Fran\u00e7ois H., est plus \u00ab\u00a0performant\u00a0\u00bb en fait de d\u00e9construction qu&rsquo;un Robespierre ou qu&rsquo;un L\u00e9nine. Il a l&rsquo;air bonasse du notaire de province rougissant et un peu moite qui va au boxon tirer son coup en douce, mais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13314,3126,4467,2653,3203,3170,17496,2786,6717,12850,17495,3309,17498,6161,17497],"class_list":["post-76566","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-ac","tag-black","tag-figaro","tag-francois","tag-hollande","tag-kohl","tag-koztoujours","tag-m","tag-mitterrand","tag-palmyre","tag-pinnault","tag-postmodernite","tag-tandonnet","tag-verdun","tag-vox"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76566"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76566\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}