{"id":76573,"date":"2016-05-17T11:21:32","date_gmt":"2016-05-17T11:21:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/17\/pepe-et-dilma\/"},"modified":"2016-05-17T11:21:32","modified_gmt":"2016-05-17T11:21:32","slug":"pepe-et-dilma","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/17\/pepe-et-dilma\/","title":{"rendered":"P\u00e9p\u00e9 et Dilma"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">P\u00e9p\u00e9 et Dilma<\/h2>\n<\/p>\n<p><p>Nous profitions d&rsquo;un commentaire mis \u00e0 notre texte sur le Br\u00e9sil du <a href=\"http:\/\/www.dedefensa.org\/article\/de-dilma-suspendue-aux-jo-boitillant\">13 mai 2016<\/a> pour introduire un document tr\u00e8s int\u00e9ressant qui est une interview de P\u00e9p\u00e9 Escobar, en fran\u00e7ais (que P\u00e9p\u00e9 parle remarquablement), datant du <a href=\"http:\/\/lesakerfrancophone.fr\/destitution-de-la-presidente-bresilienne-dilma-rousseff-entretien-avec-pepe-escobar\">12 mai<\/a> sur <em>Le Sakerfrancophone<\/em>. L&rsquo;int\u00e9r\u00eat est que la remarque faite par notre lecteur s&rsquo;appuie sur un texte d&rsquo;Escobar portant sur la situation au Br\u00e9sil, tandis que l&rsquo;interview porte \u00e9galement sur ce sujet.<\/p>\n<\/p>\n<p><p>Quant \u00e0 la remarque du lecteur <em>Dont Acte<\/em>, en date du 16 mai sur le <em><a href=\"http:\/\/www.dedefensa.org\/article\/de-dilma-suspendue-aux-jo-boitillant\">Forum<\/a> <\/em>du m\u00eame texte r\u00e9f\u00e9renc\u00e9, sous le titre &laquo; <em>Trop rapide ?<\/em> &raquo;, nous en rappelons l&rsquo;\u00e9nonc\u00e9 : &laquo; <em>Pour \u00ab\u00a0l&rsquo;interpr\u00e9tation, assez courante, selon laquelle Rousseff est victime d&rsquo;un &lsquo;coup&rsquo; o&ugrave; les activismes habituels US &#038; associ\u00e9s, type-&lsquo;r\u00e9volution de couleur&rsquo;, ont \u00e9videmment leur part &raquo;, je vous trouve un peu rapide. Voyez <a href=\"https:\/\/www.rt.com\/op-edge\/342821-brazil-dilma-rousseff-impeachment\/\">cette interpr\u00e9tation<\/a> v\u00e9rifi\u00e9e et valid\u00e9e par le journaliste br\u00e9silien Pepe Escobar, souvent cit\u00e9 et appr\u00e9ci\u00e9 sur votre site. La reprise en main de l&rsquo;Am\u00e9rique Latine par les USA n&rsquo;est pas un vain mot<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Un peu rapide aussi, lorsque vous consid\u00e9rez la neutralisation du BRICS qu&rsquo;est le Br\u00e9sil avec ce qui semble \u00eatre une certaine d\u00e9sinvolte. Est-ce bien l\u00e0 votre pens\u00e9e ? &Agrave; vous lire, on comprend que les USA s&rsquo;autod\u00e9truisent tr\u00e8s bien tout seul et les forces antisyst\u00e8me des BRICS, pas toujours francs du collier, en deviendraient superflues<\/em>&hellip;<\/p>\n<\/p>\n<p><p>&raquo; <em>Ne jetez-vous pas le b\u00e9b\u00e9 avec l&rsquo;eau du bain ? Combien de parties d&rsquo;\u00e9checs ont-elles \u00e9t\u00e9 perdues faute de pi\u00e8ces dans les derniers mouvements ? Aucun alli\u00e9 n&rsquo;est superflu, il faut faire fl\u00e8che de tout bois et les apports des BRICS sont pr\u00e9cieux aujourd&rsquo;hui comme hier dans ce combat<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;interview d&rsquo;Escobar est tr\u00e8s vivante, tr\u00e8s enlev\u00e9e, et explore, sur plus de 36 minutes, tous les aspects de la crise br\u00e9silienne. L&rsquo;int\u00e9r\u00eat de l&rsquo;interview est que P\u00e9p\u00e9 peu s&rsquo;\u00e9tendre longuement, &ndash; il a le temps et aucune des contraintes s&rsquo;attachant \u00e0 un texte de diffusion internationale, vers un public bien connu, &ndash; sur la situation int\u00e9rieure du Br\u00e9sil, o&ugrave; il se trouvait au moment des \u00e9v\u00e8nements tr\u00e8s r\u00e9cents qu&rsquo;on sait, ce qui est une chance puisqu&rsquo;on sait que ce Br\u00e9silien globe-trotter est tr\u00e8s rarement dans son pays. Dans tous les cas, il \u00e9tait \u00e0 Paris apr\u00e8s avoir quitt\u00e9 le Br\u00e9sil la semaine derni\u00e8re et fut aussit\u00f4t mobilis\u00e9 pour cette interview qui est pr\u00e9sent\u00e9e de la fa\u00e7on suivante, le <a href=\"http:\/\/lesakerfrancophone.fr\/destitution-de-la-presidente-bresilienne-dilma-rousseff-entretien-avec-pepe-escobar\">12 mai<\/a> par <em>Le Sakerfrancophone<\/em> :<\/p>\n<\/p>\n<p><p>&laquo; <em>La pr\u00e9sidente br\u00e9silienne <strong>Dilma Rousseff<\/strong> vient d&rsquo;\u00eatre officiellement \u00e9cart\u00e9e du pouvoir pr\u00e9sidentiel au Br\u00e9sil. L&rsquo;annonce fait suite au vote mercredi des s\u00e9nateurs en faveur de l&rsquo;ouverture du proc\u00e8s en destitution de la dirigeante, qui est automatiquement remplac\u00e9e pour une p\u00e9riode de 180 jours maximum par celui qui \u00e9tait alors vice-pr\u00e9sident de la R\u00e9publique, <strong>Michel Temer<\/strong>. Ce que beaucoup d\u00e9noncent comme un &laquo; coup d&rsquo;&Eacute;tat institutionnel &raquo; met fin \u00e0 13 ans de pouvoir de la gauche au Br\u00e9sil. Vendredi dernier, le Cercle des Volontaires recevait le journaliste et analyste g\u00e9opolitique br\u00e9silien <strong>Pepe Escobar<\/strong> afin qu&rsquo;il nous livre son analyse sur des \u00e9v\u00e9nements pas forc\u00e9ment faciles \u00e0 appr\u00e9hender vus de France<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Nous allons vous donner ci-dessous notre interpr\u00e9tation de cette interview, c&rsquo;es-\u00e0-dire la fa\u00e7on dont nous l&rsquo;avons per\u00e7ue, avec notamment tout ce qu&rsquo;indiquent le langage parl\u00e9, le ton, les mimiques, etc., particuli\u00e8rement d&rsquo;un personnage aussi expansif et chaleureux que P\u00e9p\u00e9 Escobar.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;intervention des USA et la situation des BRICS. Certes, il y a la NSA, l&rsquo;ambassade US, bien d&rsquo;autre chose, et une op\u00e9ration de \u00ab\u00a0guerre hybride\u00a0\u00bb contre Dilma, d&rsquo;un type nouveau, extr\u00eamement complexe, additionnant les habituels outils de corruption, l&rsquo;aspect politique et parlementaire, l&rsquo;aspect judiciaire, l&rsquo;aspect bureaucratique, etc. Au total, une op\u00e9ration que P\u00e9p\u00e9 lui-m\u00eame s&rsquo;accorde \u00e0 juger extr\u00eamement complexe et \u00ab\u00a0sophistiqu\u00e9e\u00a0\u00bb (on le voit avec ses explications) et dont l&rsquo;effet attendu est plut\u00f4t sur \u00ab\u00a0le long terme\u00a0\u00bb. Nous ne l&rsquo;avons pas trouv\u00e9 extr\u00eamement convaincu lui-m\u00eame de l&rsquo;efficacit\u00e9 et de la forme de cette intervention, sans douter certes de mise en route mais en s&rsquo;interrogeant un peu sur sa r\u00e9alisation. Quant aux BRICS, bien entendu, la r\u00e9affirmation est compl\u00e8te de la volont\u00e9 US de d\u00e9truire les BRICS, per\u00e7us comme un ennemi mortel, &ndash; mais il s&rsquo;agit l\u00e0 d&rsquo;un fait bien connu depuis qu&rsquo;existe les BRIC-devenus-BRICS, \u00ab\u00a0ennemi mortel\u00a0\u00bb des USA parmi tant d'\u00a0\u00bbennemis mortels\u00a0\u00bb de cette grande et exemplaire d\u00e9mocratie amie de tout le monde&#8230;<\/p>\n<\/p>\n<p><p>&bull; Tout ce qu&rsquo;il peut y avoir d&rsquo;impressionnant pour un esprit ouvert \u00e0 cette sorte d&rsquo;explication (subversion US, attaque des BRICS) est extr\u00eamement compens\u00e9 par divers aspects de la situation politique int\u00e9rieure du Br\u00e9sil, actuellement entr\u00e9 dans une phase de 180 jours o&ugrave; Dilma Rousseff est \u00ab\u00a0jug\u00e9e\u00a0\u00bb pour d\u00e9terminer si sa destitution doit \u00eatre r\u00e9alis\u00e9e. <strong>L\u00e0-dessus, P\u00e9p\u00e9 s&rsquo;exclame qu&rsquo;au Br\u00e9sil, il est impossible de savoir ce qui se passera demain, \u00ab\u00a0alors, imaginez dans 180 jours !\u00a0\u00bb<\/strong>&#8230; (M\u00eame r\u00e9serve par cons\u00e9quent, en plus long encore, pour l&rsquo;op\u00e9ration de d\u00e9stabilisation \u00ab\u00a0\u00e0 long terme\u00a0\u00bb mentionn\u00e9e plus haut. Cette op\u00e9ration est d&rsquo;ailleurs confront\u00e9e \u00e0 diverses interf\u00e9rences, dont une \u00ab\u00a0op\u00e9ration Mains Propres\u00a0\u00bb, ou \u00ab\u00a0op\u00e9ration Karcher\u00a0\u00bb selon P\u00e9p\u00e9, partie de l&rsquo;initiative improbable d&rsquo;un \u00ab\u00a0petit juge de province\u00a0\u00bb, pourtant mentionn\u00e9 comme un correspondant US mais \u00e9tant intervenu dans ce cas selon sa seule initiative et pour un effet de complication tr\u00e8s inattendu.)<\/p>\n<\/p>\n<p><p>&bull; P\u00e9p\u00e9 juge le nouveau pouvoir temporaire, &ndash; Temer \u00e9tant \u00e9videmment plus ou moins \u00e0 la solde des USA, et partisan de mesures ultralib\u00e9rales, &ndash; extr\u00eamement impopulaire, avec 1% d&rsquo;avis favorables pour Temer, frisant les 2% les dimanches et jours f\u00e9ri\u00e9s. <strong>P\u00e9p\u00e9 ne croit pas que Temer pourra gouverner jusqu&rsquo;au terme de ces 180 jours<\/strong>, notamment en raison d&rsquo;une opposition populaires qu&rsquo;il pr\u00e9voit extr\u00eamement forte maintenant que la pr\u00e9sidence n&rsquo;est plus aux mains du parti le plus repr\u00e9sentatif du peuple (le parti de Lula et de Rousseff). Seule la r\u00e9ussite imm\u00e9diatement perceptible de l&rsquo;une ou l&rsquo;autre r\u00e9forme, &ndash; par exemple, moins de ch\u00f4mage, &ndash; pourrait lui permettre de survivre. (En attendant, divers conflits et proc\u00e9dures se poursuivent, mettant en cause des personnalit\u00e9s du \u00ab\u00a0complot anti-Dilma\u00a0\u00bb, dont on sait qu&rsquo;ils sont, dans ce pays extr\u00eamement corrompu, les plus archi-corrompus, certains avec de graves enqu\u00eates et inculpations \u00e0 leur encontre.)<\/p>\n<\/p>\n<blockquote>\n<p><p>&bull; Un point qui nous para&icirc;t tr\u00e8s important est le jugement que P\u00e9p\u00e9 porte sur Dilma Rousseff. A l&rsquo;entendre, Dilma est une tr\u00e8s mauvaise \u00e9conomiste qui croit conna&icirc;tre l&rsquo;\u00e9conomie et qui n&rsquo;\u00e9coute gu\u00e8re les conseils. Elle a pris des d\u00e9cisions catastrophiques qui l&rsquo;ont m\u00eame forc\u00e9e, pour \u00e9viter un effondrement, \u00e0 prendre des mesures ultra-lib\u00e9rales d&rsquo;aust\u00e9rit\u00e9 qui ont en retour consid\u00e9rablement \u00e9rod\u00e9 sa popularit\u00e9. P\u00e9p\u00e9 juge donc son action politique comme tr\u00e8s critiquable, allant jusqu&rsquo;\u00e0 dire que l&rsquo;une des rares erreurs de Lula, &ndash; qu&rsquo;il tient manifestement en tr\u00e8s haute estime, &ndash; fut de la choisir pour sa succession. <strong>On ne peut donc \u00e9viter le jugement que l&rsquo;action de Dilma est une des causes essentielles de l&rsquo;\u00e9volution de la situation br\u00e9silienne qui a permis aux activistes US et pro-US d&rsquo;intervenir<\/strong>, &ndash; et l&rsquo;on en serait m\u00eame \u00e0 se demander comment ils ne sont pas intervenus plus t\u00f4t et plus efficacement, et par quelle habilet\u00e9 de maladresse ils parviennent \u00e0 offrir une situation br\u00e9silienne dont la perspective n&rsquo;est pas si mauvaise&#8230; (Mais la r\u00e9ponse se trouve bien entendu dans le fait que les troupes qu&rsquo;ils subventionnent, parlementaires, grandes fortunes, m\u00e9dias, etc., portent tout de m\u00eame le poids consid\u00e9rable de la corruption qui les entretient.)<\/p>\n<\/p>\n<p><p>&bull; En effet dirions-nous pour encha&icirc;ner sur cette observation de cette \u00ab\u00a0perspective&#8230; pas si mauvaise\u00a0\u00bb, c&rsquo;est l\u00e0 un des autres avis int\u00e9ressants de notre interview\u00e9 : P\u00e9p\u00e9 croit \u00e0 un retour de Lula, et m\u00eame dans les meilleures conditions possibles. Il estime que le tournant a \u00e9t\u00e9 le moment o&ugrave; une intervention de militaires sur l&rsquo;a\u00e9roport de Sao Paulo a emp\u00each\u00e9 une arrestation arbitraire de Lula qui aurait compromis son avenir politique. (Les indications que donne le journaliste sont assez vagues et rapidement mentionn\u00e9es mais il semble bien qu&rsquo;il y ait l\u00e0 un \u00e9l\u00e9ment important o&ugrave; il est fait, pour la premi\u00e8re fois \u00e0 notre connaissance, \u00e9tat de l&rsquo;interf\u00e9rence des militaires dans la situation politique.) Au contraire, P\u00e9p\u00e9 estime que Lula <strong>est en tr\u00e8s bonne position pour conserver et renforcer sa popularit\u00e9 d&rsquo;ici 2018, pour nettoyer un peu la direction de son parti \u00e9galement touch\u00e9 par la corruption, et \u00eatre r\u00e9\u00e9lu pr\u00e9sident cette m\u00eame ann\u00e9e (2018)<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Ces observations prises sur le vif et s&rsquo;\u00e9tendant longuement sur la situation int\u00e9rieure du pays nous paraissent importantes, parce qu&rsquo;elles mettent l&rsquo;accent sur un fait qui devrait tout de m\u00eame \u00eatre pris en compte : lorsqu&rsquo;une attaque de subversion US a lieu, elle n&rsquo;est pas la cause de tous les d\u00e9boires du pays qui la subit, et notamment selon le paradoxe absurde de la responsabilit\u00e9 des conditions qui ont permis qu&rsquo;elle soit lanc\u00e9e, &ndash; qu&rsquo;elle ne peut avoir install\u00e9eselle-m\u00eame  puisqu&rsquo;elle n&rsquo;\u00e9tait pas encore lanc\u00e9e&#8230; Pour bien nous faire comprendre, nous dirions que si Chavez \u00e9tait toujours vivant, et donc au pouvoir, il nous semble que la situation au Venezuela sera tr\u00e8s notablement diff\u00e9rente de ce qu&rsquo;elle aujourd&rsquo;hui, &ndash; o&ugrave;, pourtant, les subversifs pro-US avec leurs gros sabots et leurs gros moyens n&rsquo;ont m\u00eame pas r\u00e9ussi \u00e0 renverser Maduro, qui tend plut\u00f4t \u00e0 \u00eatre remplac\u00e9 par le chaos.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Chaos\u00a0\u00bb, le mot est dit&#8230; C&rsquo;est en effet \u00e0 lui que nous songeons pour d\u00e9finir la situation br\u00e9silienne, comme la situation de tr\u00e8s-tr\u00e8s-grand nombre de pays, comme la situation mondiale et celle des relations internationales. (Ce pourquoi aussi, dans cette situation de chaos \u00e0 tous les niveaux, nous parlons de \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-chaos-nouveau\">chaos-<strong>nouveau<\/strong><\/a>\u00ab\u00a0.) C&rsquo;est dans ce contexte que nous jugeons que les BRICS en tant que tels n&rsquo;ont plus du tout l&rsquo;importance qu&rsquo;ils avaient il y a trois ans encore, non parce qu&rsquo;ils ont perdu leur poids, leur r\u00e9alit\u00e9, <strong>mais simplement parce que la politique ne se d\u00e9finit plus en termes d&rsquo;affrontement de blocs, d&rsquo;id\u00e9ologies, etc.<\/strong> La partie d&rsquo;\u00e9checs dont parle notre lecteur peut encore et tout juste, tout juste et de moins en moins, se concevoir au niveau tactique (Poutine en Syrie, entre septembre 2015 et le d\u00e9but de cette ann\u00e9e), mais plus du tout au niveau strat\u00e9gique o&ugrave; des forces sup\u00e9rieures sont en action. L&rsquo;avantage de Poutine au Moyen-Orient est en train de se r\u00e9duire notablement \u00e0 cause d&rsquo;une \u00e9volution beaucoup moins favorable sur le terrain, parce que la Russie, selon les termes d&rsquo;<a href=\"https:\/\/elijahjm.wordpress.com\/2016\/05\/11\/russia-equivocates-in-syria-iran-is-confused-and-al-qaeda-takes-the-initiative\/\">Elijah J. Magnier<\/a>, n&rsquo;intervient pas pour la raison qu&rsquo;elle \u00ab\u00a0est en train de s&#8217;emp\u00eatrer politiquement dans la boue de la politique am\u00e9ricaine et de se perdre dans l&rsquo;imbroglio de la diplomatie\u00a0\u00bb (&laquo;&#8230;<em>is sinking politically in the mud of American diplomacy and is engaged in the tunnel of diplomacy<\/em> &raquo;).<\/p>\n<\/p>\n<blockquote>\n<p><p>&#8230; Et s&rsquo;il y a \u00ab\u00a0boue\u00a0\u00bb dans la politique US, et si l&rsquo;activit\u00e9 US entra&icirc;ne les autres dans des imbroglios, ce n&rsquo;est absolument pas par man&oelig;uvre strat\u00e9gique mais bien plut\u00f4t selon l&rsquo;\u00e9vidence du chaos des \u00e9lections et de l&rsquo;absence de pouvoir r\u00e9gnant aujourd&rsquo;hui aux USA, tout cela permettant des initiatives d\u00e9sordonn\u00e9es et dans tous les sens. <strong>De ce point de vue, ce que l&rsquo;on peut attendre, et sp\u00e9cifiquement pour les USA qui occupe le centre du Syst\u00e8me et du chaos, c&rsquo;est bien plus un coup de poker qu&rsquo;une man&oelig;uvre savante comme les \u00e9checs ont le secret<\/strong> : ou Clinton est \u00e9lue, et c&rsquo;est alors un tournant franc et massif vers la confrontation pouvant conduire \u00e0 des conflits de haut niveau et non plus des accrochages de subversion et de communication, ou bien c&rsquo;est Trump et alors l&rsquo;un ou l&rsquo;autre renversement est possible, &ndash; avec, dans les deux cas, <strong>le joker de troubles int\u00e9rieurs aux USA, le chaos accouchant alors du chaos, selon la marche m\u00eame de la nature du monde.<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 17 mai 2016 \u00e0 11H19<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>P\u00e9p\u00e9 et Dilma Nous profitions d&rsquo;un commentaire mis \u00e0 notre texte sur le Br\u00e9sil du 13 mai 2016 pour introduire un document tr\u00e8s int\u00e9ressant qui est une interview de P\u00e9p\u00e9 Escobar, en fran\u00e7ais (que P\u00e9p\u00e9 parle remarquablement), datant du 12 mai sur Le Sakerfrancophone. L&rsquo;int\u00e9r\u00eat est que la remarque faite par notre lecteur s&rsquo;appuie sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10643,3677,11035,12774,12128,2631,17506,17252,17507,4900,3676,13823,2879,9775,2730,3867,2639],"class_list":["post-76573","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-acte","tag-bresil","tag-brics","tag-chaos-nouveau","tag-couleur","tag-de","tag-dilma","tag-dont","tag-elijah","tag-escobar","tag-lula","tag-pepe","tag-revolution","tag-rousseff","tag-russie","tag-syrie","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76573"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76573\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}