{"id":76581,"date":"2016-05-22T15:24:57","date_gmt":"2016-05-22T15:24:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/22\/de-leffet-de-la-dissolution-de-loutil-militaire-us-1\/"},"modified":"2016-05-22T15:24:57","modified_gmt":"2016-05-22T15:24:57","slug":"de-leffet-de-la-dissolution-de-loutil-militaire-us-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/22\/de-leffet-de-la-dissolution-de-loutil-militaire-us-1\/","title":{"rendered":"De l&rsquo;effet de la dissolution de l&rsquo;outil militaire US"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">De l&rsquo;effet de la dissolution de l&rsquo;outil militaire US<\/h2>\n<\/p>\n<p><p>Il nous est arriv\u00e9 \u00e9pisodiquement de citer David P. Goldman, qui fut longtemps connu sous le seul pseudonyme de \u00ab\u00a0<em>Spengler<\/em>\u00ab\u00a0, dans ses chroniques r\u00e9guli\u00e8res de <em>ATimes.com<\/em>, extr\u00eamement suivies dans les milieux d&rsquo;affaires sensibles \u00e0 l&rsquo;influence anglo-saxonne des grandes places financi\u00e8res asiatiques telle que Hong-Kong La derni\u00e8re fois que nous l&rsquo;avions fait, c&rsquo;\u00e9tait le <a href=\"http:\/\/www.dedefensa.org\/article\/de-lanarchie-a-la-secession\">22 juin 2015<\/a>, et il s&rsquo;agissait, dans le cadre d&rsquo;un <em>F&#038;C <\/em>consacr\u00e9 aux d\u00e9sordres publics aux USA (&laquo; <em>De l&rsquo;anarchie \u00e0 la s\u00e9cession<\/em> &raquo;), d&rsquo;un texte typiquement \u00ab\u00a0spengl\u00e9rien\u00a0\u00bb, marqu\u00e9 par une forte tendance sociale-darwinisme appuy\u00e9e sur un supr\u00e9macisme de type \u00e9videmment anglo-saxon&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; &bull; <em>L\u00e0-dessus, des th\u00e8ses radicales viennent se greffer, dont la plus radicale est celle du \u00ab\u00a0genosuicide\u00a0\u00bb (ou \u00e9thnosuicide ?) de la communaut\u00e9 africaine-am\u00e9ricaine, qui n&rsquo;est finalement qu&rsquo;une forme du social-darwinisme qui a domin\u00e9 la pens\u00e9e des capitalistes extr\u00e9mistes depuis la Guerre de S\u00e9cession. Ici, c&rsquo;est David P. Goldman, alias Spengler, commentateur social-darwinien patent\u00e9, partisan du supr\u00e9macisme anglo-saxon, qui la pr\u00e9sente sur ATimes.com, le <\/em><a href=\"http:\/\/atimes.com\/2015\/06\/genosuicide-and-its-causes\/\"><em>15 juin 2015<\/em><\/a>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En un sens, <em>Spengler<\/em>-Goldman est un bon thermom\u00e8tre, une mesure de l&rsquo;influence de la tendance la plus \u00ab\u00a0dure\u00a0\u00bb du <em>business<\/em> globalis\u00e9e dont les centres sont Wall Street et la <em>City<\/em> de Londres, et les relais dans les diverses places financi\u00e8res du monde ; son aire de r\u00e9flexion couvre essentiellement l&rsquo;Asie, mais ses consid\u00e9rations embrassent le monde globalis\u00e9e et les diverses puissances qui s&rsquo;y affirment, ou qui y p\u00e9riclitent. <em>Spengler<\/em>-Goldman ne s&#8217;embarrasse pas de sentiments, il fait m\u00eame profession de raisonner avec le cynisme le plus r\u00e9aliste, en sacrifiant \u00e0 la conception social-darwinienne qui habille cette d\u00e9marche. Quant aux USA, <em>Spengler<\/em>-Goldman a donc, et tr\u00e8s naturellement, toujours \u00e9t\u00e9 plut\u00f4t partisan, m\u00eame si avec parfois des critiques sur la mani\u00e8re, de la politique militariste d&rsquo;expansion h\u00e9g\u00e9monique, et de la puissance militaire des USA qui assure la solidit\u00e9 des conceptions qu&rsquo;il d\u00e9fend. C&rsquo;est pourquoi ce texte que nous signalons aujourd&rsquo;hui nous para&icirc;t tr\u00e8s int\u00e9ressant. Son originalit\u00e9 est qu&rsquo;il montre bien que l&rsquo;affaiblissement dramatique, sinon l&rsquo;effondrement par dissolution en termes de n\u00e9cessit\u00e9 strat\u00e9gique de la puissance militaire US, <strong>est un fait qui commence \u00e0 p\u00e9n\u00e9trer m\u00eame dans ces milieux o&ugrave; la notion de puissance strat\u00e9gique h\u00e9g\u00e9monique inh\u00e9rente aux USA est une constante qui semblait absolument indestructible<\/strong>, sauf accident gravissime comme aurait pu l&rsquo;\u00eatre une attaque par surprise.<\/p>\n<\/p>\n<p><p>Dans ce texte <a href=\"http:\/\/atimes.com\/2016\/05\/americas-instructive-humiliation-in-the-south-china-sea\/\">du 20 mai<\/a> (<em>ATimes.com<\/em>), <em>Spengler<\/em>-Goldman parle de l'\u00a0\u00bbhumiliation instructive de l&rsquo;Am\u00e9rique en Mer de Chine du Sud\u00a0\u00bb, o&ugrave; le comportement US (de l&rsquo;US Navy) acte la crainte des forces navales US d&rsquo;\u00e9voluer dans des zones o&ugrave; elles se trouveraient \u00e0 port\u00e9e des nouveaux syst\u00e8mes terre-mer de d\u00e9fense c\u00f4ti\u00e8re de la Chine, notamment les missiles DF-21 sp\u00e9cialement con\u00e7us pour attaquer les porte-avions US. <em>Spengler<\/em>-Goldman rappelle l&rsquo;influence que la Chine a acquise dans la r\u00e9gion \u00e0 cause de la perception de la baisse de la puissance US aussi bien cons\u00e9cutive \u00e0 l&rsquo;affirmation chinoise qu&rsquo;au d\u00e9clin inh\u00e9rent de l&rsquo;appareil militaire US. Il cite la r\u00e9flexion du nouveau pr\u00e9sident philippin, un <em>Super<\/em>-Trump (sorte de groupe rock postmoderne) si l&rsquo;on en croit les diverses anecdotes \u00e0 son propos et ses d\u00e9clarations exotiques ; mais quant \u00e0 la Chine et les USA, Rodrigo Duterte est plus fermement et s\u00e9rieusement r\u00e9aliste, avec les pieds sur terre, selon cette d\u00e9claration qu&rsquo;il fit l&rsquo;ann\u00e9e derni\u00e8re :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Les Am\u00e9ricains ne mourront jamais pour notre d\u00e9fense. Si l&rsquo;Am\u00e9rique s&rsquo;y int\u00e9ressait vraiment, elle aurait envoy\u00e9 ses porte-avions et ses fr\u00e9gates d\u00e8s le moment o&ugrave; la Chine commen\u00e7a \u00e0 r\u00e9clamer des portions de territoires contest\u00e9es, mais cela ne fut pas le cas&#8230; L&rsquo;Am\u00e9rique a peur de partir en guerre. Nous ferions beaucoup mieux de devenir des amis de la Chine<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>(Ce qu&rsquo;oublie, ou ne sait pas encore le nouveau pr\u00e9sident Rodrigo Duterte, c&rsquo;est que m\u00eame s&rsquo;ils le voulaient, &ndash; et sans doute le voudraient-ils, &ndash; <strong>les USA ne peuvent certainement pas affecter un porte-avions \u00e0 la d\u00e9fense des Philippines parce qu&rsquo;ils ne dispose pas de l&rsquo;objet en question<\/strong>. Les quelques rares sp\u00e9cimens restant sont affect\u00e9s \u00e0 des zones strat\u00e9giques plus importantes, dans le sens quantitatif et qualitatif, que les seules Philippines.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L\u00e0-dessus, <em>Spengler<\/em>-Goldman d\u00e9veloppe une analyse du statut des forces militaires US d&rsquo;un point de vue technique qu&rsquo;il n&rsquo;a gu\u00e8re l&rsquo;habitude d&rsquo;aborder, parce qu&rsquo;un esprit comme le sien tenait justement jusqu&rsquo;alors pour acquise la toute-puissance des USA, et qu&rsquo;il \u00e9tait donc inutile qu&rsquo;il tremp\u00e2t sa plume dans le cambouis des d\u00e9comptes technologiques de la puissance. Cette fois, il va jusqu&rsquo;\u00e0 citer parall\u00e8lement un expert US et un expert russe pour faire le pan\u00e9gyrique du syst\u00e8me sol-air S-500 russe, qui est promis \u00e0 mettre en p\u00e9ril, outre les t\u00eates de missiles strat\u00e9giques intercontinentaux, la g\u00e9n\u00e9ration des avions tout-<em>stealth<\/em> de l&rsquo;USAF (B-2, F-22 F-35). D&rsquo;ailleurs, il n&rsquo;est peut \u00eatre pas n\u00e9cessaire de recourir au S-500 pour en \u00eatre quitte, &ndash; pour le F-35 sans aucun doute, en bonne partie pour le F-22, et m\u00eame pour le B-2 que l&rsquo;USAF ne peut se r\u00e9soudre \u00e0 envoyer en mission sans un certain nombre d&rsquo;avions de protection si bien qu&rsquo;on sait parfaitement quand et o&ugrave; le B-2 \u00ab\u00a0invisible\u00a0\u00bb est en mission (les Fran\u00e7ais avaient pu d\u00e9couvrir cette \u00e9trange tactique durant la guerre du Kosovo),&#8230; Ce que <em>Spengler<\/em>-Goldman reconna&icirc;t plus loin, en rappelant les innombrables d\u00e9boires du F-35 (JSF) : il effleure du coup l&rsquo;aspect particuli\u00e8rement dramatique de la dissolution de la puissance militaire US que l&rsquo;on voit plus loin.<\/p>\n<\/p>\n<p><p>Bien entendu, et m\u00eame s&rsquo;il cite \u00e9galement des syst\u00e8mes russes (signe que, pour lui, l&rsquo;alliance strat\u00e9gique Chine-Russie du point de vue du militaire est un fait acquis), <em>Spengler<\/em>-Goldman parle essentiellement de la Chine, qui prend ainsi, dans son estimation, une stature aussi impressionnante que <a href=\"http:\/\/www.dedefensa.org\/article\/linvasion-de-lukraine-est-un-fait-historique-point-final\">celle des Russes<\/a> vus par un Gour\u00e9 ou par un Karber. Cela fait beaucoup. Sa conclusion rejoint d&rsquo;ailleurs l&rsquo;\u00e9tat d&rsquo;esprit qu&rsquo;on lui suppose en d\u00e9couvrant son texte, si inhabituellement technique, et si inhabituellement tr\u00e8s-pessimiste \u00e0 propos de la puissance militaire US :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Voil\u00e0 les faits terre-\u00e0-terre (mais aussi dans les airs et sur mer). Il n&rsquo;est pas surprenant que les alli\u00e9s de l&rsquo;Am\u00e9rique en Asie veuillent s&rsquo;entendre avec la Chine. Il faudra rien de moins qu&rsquo;un effort \u00e0-la-Reagan pour restaurer l&rsquo;avantage technologique de l&rsquo;Am\u00e9rique et changer cette situation<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette observation va bien dans le sens qui nous importe. L&rsquo;effort de r\u00e9armement produit par Reagan entre 1981 et 1985 (gu\u00e8re au-del\u00e0) fut certainement la seule occurrence depuis 1945-1948 et jusqu&rsquo;\u00e0 aujourd&rsquo;hui o&ugrave; le monde strat\u00e9gico-financier s&rsquo;int\u00e9ressa \u00e0 l&rsquo;aspect quincaillerie de la puissance am\u00e9ricaniste, le reste de l&rsquo;\u00e9poque depuis 1945 s&rsquo;appuyant sur la certitude de la domination incontest\u00e9e des USA. Il s&rsquo;agit donc d&rsquo;une prise de conscience constituant un fait important de communication, <strong>la perception du monde financier de la nouvelle impuissance militaire US par rapport \u00e0 la t\u00e2che qui lui est impartie dans le cadre de la globalisation d&rsquo;une supr\u00e9matie strat\u00e9gique sans aucune d\u00e9faillance<\/strong>. C&rsquo;est bien ce fait qui nous importe car il doit rapidement conduire \u00e0 des modifications d&rsquo;attitudes, de politiques financi\u00e8res, etc., dans un monde globalis\u00e9 (celui de la finance) o&ugrave; la loyaut\u00e9 nationale, la fid\u00e9lit\u00e9 \u00e0 un parti n&rsquo;ont strictement aucune place.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus et pour faire bonne mesure, on s&rsquo;attardera \u00e9galement sur le constat de <em>Spengler<\/em>-Goldman : la n\u00e9cessit\u00e9 d&rsquo;un \u00ab\u00a0effort \u00e0-la-Reagan\u00a0\u00bb (\u00ab\u00a0<em>a Reaganesque effort<\/em>\u00ab\u00a0). Si un effort de r\u00e9armement \u00e9tait concevable \u00e0 cette \u00e9poque, et bien que celui qu&rsquo;effectua Reagan ne soit pas sans erreurs ni faiblesses (c&rsquo;est sous sa pr\u00e9sidence que commen\u00e7a \u00e0 \u00eatre mis en application le concept qui allait aboutir au <a href=\"http:\/\/www.dedefensa.org\/article\/notes-autour-de-lair-dominance-en-perdition\">choix catastrophique<\/a> du \u00ab\u00a0tout-<em>stealth<\/em>\u00a0\u00bb pour l&rsquo;USAF), il se heurte aujourd&rsquo;hui \u00e0 des blocages et \u00e0 des ph\u00e9nom\u00e8nes d&rsquo;inversion non seulement catastrophiques, mais tout simplement confinant \u00e0 la paralysie autodestructrice. On a d\u00e9j\u00e0 vu, \u00e0 diverses reprises, combien le labyrinthe de gaspillage et de comptabilit\u00e9 corrompue du Pentagone, sa bureaucratie pl\u00e9thorique que Rumsfeld d\u00e9non\u00e7ait d\u00e9j\u00e0 (en 2001, et le 10 septembre !) comme un <a href=\"http:\/\/www.dedefensa.org\/article\/le-courage-de-rumsfeld-et-un-discours-historique\">danger plus grave<\/a> que l&rsquo;URSS durant la Guerre froide, les impasses technologiques qui apparaissent de plus en plus nombreuses, constituent une impossibilit\u00e9 terrifiante pour r\u00e9aliser le renforcement-r\u00e9armement de la puissance US. Une hyperpuissance dont le budget de la d\u00e9fense atteint officiellement $600 milliards, et officieusement jusqu&rsquo;\u00e0 $1.200 milliards, soit dans tous les cas bien plus que les budgets de la d\u00e9fense r\u00e9unis de la Russie et de la Chine, qui se d\u00e9couvre proche d&rsquo;un \u00e9tat d&rsquo;inf\u00e9riorit\u00e9 vis-\u00e0-vis de chacune de ces puissances, <strong>une telle hyperpuissance se r\u00e9v\u00e8le \u00e0 elle-m\u00eame affect\u00e9e d&rsquo;une pathologie ontologique dans son incapacit\u00e9 de  r\u00e9aliser la puissance \u00e0 laquelle ces divers moyens l&rsquo;engagent imp\u00e9rativement \u00e0 pr\u00e9tendre<\/strong>.<\/p>\n<\/p>\n<p><p>Le Pentagone a d\u00e9sormais d\u00e9pass\u00e9 le stade de la productivit\u00e9, m\u00eame poussive ; &icirc;l en est au stade o&ugrave; des augmentations budg\u00e9taires ajouteront encore plus de chaos, de gaspillages, de corruptions \u00e0 la situation existante, bien plus qu&rsquo;elles ne r\u00e9soudront le probl\u00e8me que d\u00e9couvre <em>Spengler<\/em>-Goldman. Le Pentagone en est au stade o&ugrave; <strong>la seule solution pour r\u00e9soudre ses propres probl\u00e8mes est celui de sa propre destruction, ou \u00ab\u00a0autodestruction contr\u00f4l\u00e9e\u00a0\u00bb si l&rsquo;on veut une r\u00e9f\u00e9rence sympathique \u00e0 l&rsquo;\u00e9quation surpuissance-autodestruction <\/strong>; c&rsquo;est-\u00e0-dire, comme le pr\u00f4naient notamment d\u00e8s 2008 Winslow Wheeler et d&rsquo;autres r\u00e9formistes dont l&rsquo;option de <a href=\"http:\/\/www.dedefensa.org\/article\/loption-de-la-pause-strategique\">\u00ab\u00a0la pause strat\u00e9gique\u00a0\u00bb<\/a> en \u00e9tait l&rsquo;esquisse, la d\u00e9structuration de l&rsquo;ensemble en diverses entit\u00e9s s\u00e9par\u00e9es de fa\u00e7on \u00e0 voir si quelque chose peut \u00eatre fait au niveau des abats apr\u00e8s avoir d\u00e9coup\u00e9 le monstre en morceaux.<strong> C&rsquo;est bien entendu une d\u00e9cision inenvisageable et impensable \u00e0 moins d&rsquo;un v\u00e9ritable coup d&rsquo;&Eacute;tat int\u00e9rieur<\/strong>, pendant que la situation n&rsquo;a fait qu&#8217;empirer depuis 2008 jusqu&rsquo;aux constats catastrophiques d&rsquo;aujourd&rsquo;hui. Il reste \u00e0 <em>Spengler<\/em>-Goldman \u00e0 d\u00e9couvrir cet aspect de la situation.<\/p>\n<\/p>\n<p><p>En attendant, c&rsquo;est certainement dans le domaine int\u00e9rieur, au niveau du gouvernement US, des \u00e9lites, des groupes de pression, de l&rsquo;&Eacute;tat profond\u00a0\u00bb, etc., &ndash; nommez-les comme vous voulez, &ndash; <strong>que la r\u00e9alisation de cette situation pourrait produire des effets d\u00e9vastateurs<\/strong>. Si notre hypoth\u00e8se au niveau de la communication avec ce texte est bonne et que des observations comme celles de <em>Spengler<\/em>-Goldman se r\u00e9pandent dans les milieux financiers fortement li\u00e9s \u00e0 l&rsquo;h\u00e9g\u00e9monie militaire strat\u00e9gique des USA, la disparition de cette h\u00e9g\u00e9monie militaire strat\u00e9gique devient un facteur de plus dans le \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-chaos-nouveau\">chaos-nouveau<\/a>\u00a0\u00bb qui s&rsquo;est abattu sur les USA, en plus du monde ext\u00e9rieur, depuis le d\u00e9but de la campagne \u00e9lectorale.<\/p>\n<\/p>\n<p><p>(Ci-dessous le texte de <em>Spengler<\/em>-Goldman sur <em>ATimes.com<\/em> le <a href=\"http:\/\/atimes.com\/2016\/05\/americas-instructive-humiliation-in-the-south-china-sea\/\">20 mai 2016<\/a>.)<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>__________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">America&rsquo;s instructive humiliation in the South China Sea<\/h2>\n<\/p>\n<p><p>\u00ab\u00a0Let us admit it fairly, as a business people should: We have had no end of a lesson: it will do us no end of good,\u00a0\u00bb wrote Rudyard Kipling in 1902 after the Boers humiliated the British Army in the first round of the Boer War. America should express the same gratitude towards China, which has humiliated America in the South China Sea. By exposing American weakness without firing a shot, Beijing has taught Washington a lesson which the next administration should take to heart.<\/p>\n<\/p>\n<p><p>Last year I asked a ranking Pentagon planner what America would do about China&rsquo;s ship-killer missiles, which reportedly can sink an aircraft carrier a couple of hundred miles from its coast. If China wants to deny the American navy access to the South China Sea, the official replied, we can do the same: persuade Japan to manufacture surface-to-ship missiles and station them in the Philippines.<\/p>\n<\/p>\n<p><p>It didn&rsquo;t occur to Washington that the Philippines might not want to take on China. The country&rsquo;s president-elect Rodrigo Duterte explained last year (as <a href=\"http:\/\/www.wsj.com\/articles\/the-new-political-risk-in-the-south-china-sea-1463505005\">David Feith<\/a> reported in the Wall Street Journal), \u00ab\u00a0America would never die for us. If America cared, it would have sent its aircraft carriers and missile frigates the moment China started reclaiming land in contested territory, but no such thing happened &hellip; America is afraid to go to war. We&rsquo;re better off making friends with China.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>It isn&rsquo;t only the Philippines who see the obvious. China <a href=\"http:\/\/economictimes.indiatimes.com\/news\/defence\/south-china-sea-dispute-china-claims-support-of-40-countries\/articleshow\/52363836.cms\">claims the support<\/a> of 40 countries for its position that territorial claims to the South China Sea should be resolved by direct negotiations between individual countries, rather than before a United Nations tribunal constituted under the UN Convention on Law of the Seas, as Washington wants. A joint statement by the foreign ministers of China, Russia and India after a meeting in Moscow last month supported China&rsquo;s position.<\/p>\n<\/p>\n<p><p>The 7th Fleet was the eight-hundred-pound gorilla in the South China Sea after World War II, relying on a weapons system now more than nine decades old, namely the aircraft carrier. That was before China fielded its DF-21 \u00ab\u00a0carrier killer\u00a0\u00bb surface-to-ship missile. The latest iteration of the missile, designated DF-26, reportedly has a <a href=\"http:\/\/nationalinterest.org\/blog\/the-buzz\/chinas-df-26-anti-ship-ballistic-missile-what-does-the-16260\">range of 2,500 miles<\/a>. New technologies, including lasers and rail guns, might defeat the new Chinese missiles, but a great deal of investment would be required to make them practical, as a January report from the <a href=\"http:\/\/www.japantimes.co.jp\/news\/2016\/01\/24\/asia-pacific\/chinas-risk-tolerance-exceeds-expectations-amid-faltering-u-s-rebalance-asia-study-says\/#.Vz87SpErKM8\">Center for Strategic and International Studies <\/a>argued.<\/p>\n<\/p>\n<p><p>The new generation of diesel-electric submarines first launched by Germany in the early 1980s, moreover, is quiet enough to evade sonar. Diesel electric subs \u00ab\u00a0sank\u00a0\u00bb American carriers in NATO exercises. Even without its surface-to-ship missiles, which can swamp existing defenses of US vessels, <a href=\"http:\/\/nationalinterest.org\/blog\/the-buzz\/could-sink-the-us-navy-lethal-stealth-submarines-15034\">China&rsquo;s stealth submarines<\/a> can sink American carriers, and anything else that floats.<\/p>\n<\/p>\n<p><p>Perhaps a greater concern is the next generation of Russian air defense, the new S-500 anti-aircraft and anti-missile systems might make the American F-35 stealth fighter obsolete before it becomes operational. Writing in The National Interest, Dave Majumdar warns that the new Russian systems are \u00ab\u00a0so capable that many US defense officials worry that even stealth warplanes like the F-22, F-35 and the B-2 might have problems overcoming them.\u00a0\u00bb Pentagon officials think that the present generation of Russian anti-aircraft missiles embodied in the S-400 can overcome the jamming capabilities of existing F-16&rsquo;s. Once Russia put a few S-400 systems on the back of trucks in Syria, it owned the skies over the Levant. The Pentagon doesn&rsquo;t want to find out how good it is.<\/p>\n<\/p>\n<p><p>Russian commentator<a href=\"http:\/\/russia-insider.com\/en\/s-500-will-push-f-22-and-f-35-retirement\/ri14401\"> Andrei Akulov<\/a> details the alleged superiority of the S-500, due for deployment next year:<\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0The S-500 is expected to be much more capable than the current <\/em><a href=\"http:\/\/www.strategic-culture.org\/news\/2016\/04\/20\/russia-s400-air-defense-system-superior-weapon-crucial-deterrence.html\"><em>S-400 Triumph<\/em><\/a><em>.<\/em><\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0For instance, its response time is only 3-4 seconds (for comparison, the response time of S-400 is nine to ten seconds).<\/em><\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0The S-500 <\/em><a href=\"http:\/\/rbth.com\/defence\/2016\/04\/07\/enemies-will-not-be-able-to-listen-in-on-russias-new-s-500-system_582867\"><em>is able to detect<\/em><\/a><em> and simultaneously attack (as well as make speeds of up to 4.3 miles per second) up to ten ballistic missile warheads out at 600 km flying at speeds of twenty-three thousand feet per second.<\/em><\/p>\n<\/p>\n<p><p><em>\u00ab\u00a0Prometey <\/em><a href=\"https:\/\/en.wikipedia.org\/wiki\/S-500_%28missile_system%29\"><em>can engage<\/em><\/a><em> targets at altitudes of about 125 miles, including incoming ballistic missiles in space at ranges as great as 400 miles.<\/em><\/p>\n<\/p>\n<p><p>Akulov concludes, \u00ab\u00a0It&rsquo;s not often that a relatively inexpensive air defense weapon is able to make a trillion dollar fighter program obsolete. That&rsquo;s exactly what the S-500 missile system will do to US brand new F-35 stealth fighter.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>China and Russia have narrowed the technology gap with the United States, and in some instances have probably leapfrogged America&rsquo;s military. In the past, the United States responded to such circumstances (for example the Russian Sputnik launch of 1957) by pouring resources into defense R&#038;D at national laboratories, universities and private industries. Instead, Washington today is spending the lion&rsquo;s share of a dwindling defense budget on systems that may not work at all.<\/p>\n<\/p>\n<p><p>At an estimated lifetime cost of $1.5 trillion, the F-35 is the costliest weapons system in American history. Even before a myriad of technical problems delayed its deployment, Pentagon planners warned that the flawed aircraft would degrade US defenses by consuming most of the Pentagon&rsquo;s research and development budget. A still-classified report signed by several four-star generals was handed to President George W. Bush midway-through his second term warning of this baleful outcome. Bush ignored it. Former Air Force official <a href=\"http:\/\/www.washingtontimes.com\/news\/2015\/jul\/9\/jed-babbin-the-deadly-f-35-strike-fighter\/?page=all\">Jed Babbin<\/a> detailed the aircraft&rsquo;s flaws in the Washington Times last year, concluding, \u00ab\u00a0The F-35 program is an example of how weapons shouldn&rsquo;t be bought. It needs to be stopped in its tracks.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Those are the facts on the ground (as well as the air and sea). It&rsquo;s not surprising that America&rsquo;s allies in Asia want an accommodation with China. Nothing short of a Reaganesque effort to restore America&rsquo;s technological edge will change this.<\/p>\n<\/p>\n<p><h4><em>Spengler<\/em> (David P. Goldman)<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De l&rsquo;effet de la dissolution de l&rsquo;outil militaire US Il nous est arriv\u00e9 \u00e9pisodiquement de citer David P. Goldman, qui fut longtemps connu sous le seul pseudonyme de \u00ab\u00a0Spengler\u00ab\u00a0, dans ses chroniques r\u00e9guli\u00e8res de ATimes.com, extr\u00eamement suivies dans les milieux d&rsquo;affaires sensibles \u00e0 l&rsquo;influence anglo-saxonne des grandes places financi\u00e8res asiatiques telle que Hong-Kong La derni\u00e8re&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[5994,2623,3977,17518,17515,17517,8477,3194,17516,569,16552,4351],"class_list":["post-76581","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-asie","tag-bureaucratie","tag-chine","tag-df-21","tag-dissolution-philippines","tag-duterte","tag-goldman","tag-pentagone","tag-rodrigo","tag-rumsfeld","tag-s-500","tag-spengler"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76581"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76581\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}