{"id":76595,"date":"2016-05-30T09:34:25","date_gmt":"2016-05-30T09:34:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/30\/ainsi-suffirait-il-de-lire-tocqueville\/"},"modified":"2016-05-30T09:34:25","modified_gmt":"2016-05-30T09:34:25","slug":"ainsi-suffirait-il-de-lire-tocqueville","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/05\/30\/ainsi-suffirait-il-de-lire-tocqueville\/","title":{"rendered":"Ainsi suffirait-il de lire Tocqueville&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Ainsi suffirait-il de lire Tocqueville&#8230;<\/h2>\n<\/p>\n<p><p>30 mai 2016 &ndash; Lisant <em>Malaise dans la d\u00e9mocratie <\/em>de Jean-Pierre Le Goff (<a href=\"http:\/\/www.dedefensa.org\/article\/humeur-de-crise-11\">d\u00e9j\u00e0 signal\u00e9<\/a>), je v\u00e9rifie aussit\u00f4t que <strong>ma vieille et profonde affection pour Tocqueville est si justifi\u00e9e<\/strong>. Contrairement \u00e0 ce qu&rsquo;en disent, unanimement et au pas cadenc\u00e9, les intellectuels am\u00e9ricanistes-Syst\u00e8me (avec les suivistes franchouillards) qui lui vouent un culte-zombie comme l&rsquo;apologiste de la <em>D\u00e9mocratie am\u00e9ricaine<\/em> et justifient en son nom toutes les saloperies qui ont suivi, je tiens Tocqueville comme un  antiam\u00e9ricaniste \u00e0 peine dissimul\u00e9 par un demi-sourire de connivence et comme au fond un antimoderne. La plupart du temps, quand il est cit\u00e9 sur ce site, comme <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lempire-de-la-communication\">encore tr\u00e8s r\u00e9cemment<\/a>, on ne manque pas de rappeler cette observation du tr\u00e8s-finaud Sainte-Beuve, faite \u00e0 l&rsquo;occasion de la mort de cet aristocrate faussement-lib\u00e9ral (je veux dire, sans le moindre rapport avec \u00ab\u00a0notre\u00a0\u00bb lib\u00e9ralisme) : &laquo; <em>Tocqueville m&rsquo;a tout l&rsquo;air de s&rsquo;attacher \u00e0 la d\u00e9mocratie comme Pascal \u00e0 la Croix : en enrageant. C&rsquo;est bien pour le talent, qui n&rsquo;est qu&rsquo;une belle lutte ; mais pour la v\u00e9rit\u00e9 et la pl\u00e9nitude de conviction cela donne \u00e0 penser<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>(Curieusement, je ne tiens pas ce jugement \u00e9ventuellement ambigu comme dommageable pour Tocqueville. S&rsquo;il s&rsquo;attache \u00ab\u00a0\u00e0 la d\u00e9mocratie\u00a0\u00bb, Tocqueville, c&rsquo;est parce qu&rsquo;il la voit comme un fait et une tendance irr\u00e9sistibles, comme une catastrophe irr\u00e9versible. [Il suffit de lire ce qu&rsquo;il dit des grands \u00e9lans \u00ab\u00a0d\u00e9mocratiques\u00a0\u00bb de 1848 dans ses <em>Souvenirs<\/em>.] C&rsquo;est \u00e0 ce point que se tient la conviction dont parle Sainte-Beuve. Certes, on peut alors dire qu&rsquo;il enrage, Tocqueville, et l&rsquo;on comprend sa rage, comme l&rsquo;on comprend celle de Pascal, oblig\u00e9 de passer par la religion catholique pour parler de Dieu quand l&rsquo;on mesure ce qu&rsquo;est devenu cette religion qui aujourd&rsquo;hui nous fait l&rsquo;apologie de l&rsquo;Art Contemporain et nous invite, conform\u00e9ment aux consignes du Syst\u00e8me, \u00e0 ouvrir toutes grandes nos fronti\u00e8res pour que triomphe le capitalisme globalis\u00e9.) <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Eh bien, gr\u00e2ce en soit rendue \u00e0 Le Goff, l&rsquo;un de ces nombreux piliers de la gauche fran\u00e7aise \u00ab\u00a0s\u00e9rieuse et structur\u00e9e\u00a0\u00bb qui est en train de virer vite fait leur cuti, nous revenons un instant \u00e0 Tocqueville pour une citation assez longue qui se suffit \u00e0 elle-m\u00eame pour enterrer la postmodernit\u00e9 dans un caveau plein de paillettes \u00e9teintes et de fluo \u00e0 l&rsquo;\u00e9clat fan\u00e9e comme une &oelig;uvre de l&rsquo;Art Contemporain r\u00e9duite \u00e0 son rien par le pass\u00e9 lib\u00e9rateur. Le Goff a \u00e9t\u00e9 assez mal accueilli dans le dernier carr\u00e9-Syst\u00e8me qui continue son <em>turf<\/em>, fid\u00e8le \u00e0 sa r\u00e9mun\u00e9ration mensuelle. Un exemple, dans <em><a href=\"http:\/\/www.liberation.fr\/debats\/2016\/02\/10\/les-francais-ces-zombies-bisounours_1432417\">Lib\u00e9 du 10 f\u00e9vrier 2016<\/a><\/em> (un peu de retard, moi, dans la lecture de <em>Lib\u00e9<\/em>), une critique qui  se voudrait bien cinglante contre Le Goff ; vigueur salonarde, jugement comme-il-faut, Joffrin, car c&rsquo;est de lui qu&rsquo;il s&rsquo;agit, entretient sa ternitude comme Waterloo sa mornitude ; donc,  <em>fatwa<\/em> contre Le Goff, le tra&icirc;tre, l&rsquo;antipostmoderne&#8230; Joffrin reconna&icirc;t d&rsquo;ailleurs dans la prose de Le Goff, &laquo; <em>l&rsquo;\u00e9ternel lamento des antimodernes si bien d\u00e9crits par Antoine Compagnon <\/em>&raquo;. Comme il se doit, Joffrin n&rsquo;a pas lu Compagnon, comme il n&rsquo;a pas lu Tocqueville, parce qu&rsquo;il se trouve qu&rsquo;on d\u00e9couvre dans <em>Les Antimodernes<\/em> bien plus de sympathie que de m\u00e9pris furieux pour les susnomm\u00e9s, Joseph de Maistre en t\u00eate. Foutriquet de Joffrin avec sa prose de notaire qui compte ses sous ! Qualifier par extension indirecte mais logique la prose sublime et temp\u00eatueuse de Joseph de Maistre, prince des antimodernes, d'\u00a0\u00bb\u00e9ternel lamento\u00a0\u00bb, faut oser ! Mais comme on sait, \u00ab\u00a0les cons \u00e7a ose tout, c&rsquo;est m\u00eame \u00e0 \u00e7a&#8230;\u00a0\u00bb, etc. Bref, va faire joujou avec ta poussi\u00e8re, Joffrin-<em>Lib\u00e9<\/em>.<\/p>\n<\/p>\n<p><p>Bref et re-bref, il y a dans Le Goff, page 25, dans le chapitre o&ugrave; il commence sa charge contre l&rsquo;individualisme postmoderne issu de Mai-68, de l&rsquo;am\u00e9ricanisme et du d\u00e9cha&icirc;nement de la Mati\u00e8re, une tr\u00e8s longue citation de Tocqueville, dont l&rsquo;auteur (Le Goff) nous dit qu&rsquo; &laquo; [i]<em>l faut prendre le temps de le citer<\/em> &raquo;, comme s&rsquo;il disait : savourez cela comme on go&ucirc;te un vin de haute lign\u00e9e pour s&rsquo;en impr\u00e9gnez la bouche, et l&rsquo;\u00e2me ; lisez-le doucement et relisez-le, impr\u00e9gnez-vous de sa prose si \u00e9l\u00e9gante pour en mesurer l&rsquo;extr\u00eame profondeur, &ndash; car, voyez-vous, tout est dit, en 1835 comme si c&rsquo;\u00e9tait \u00e9crit pour 2016. Nous citons donc la citation, elle en vaut tellement bien la peine qui devient ainsi un v\u00e9ritable plaisir des dieux&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>&laquo; <em>L&rsquo;individualisme est un sentiment r\u00e9fl\u00e9chi et paisible qui dispose chaque citoyen \u00e0 s&rsquo;isoler de la masse de ses semblables et \u00e0 se retirer \u00e0 l&rsquo;\u00e9cart avec ses familles et ses amis ; de telle sorte que, apr\u00e8s s&rsquo;\u00eatre ainsi cr\u00e9\u00e9 une petite soci\u00e9t\u00e9 \u00e0 son image, il abandonne volontiers la grande soci\u00e9t\u00e9 \u00e0 elle-m\u00eame. <\/em>[&#8230;] <em>Non seulement la d\u00e9mocratie fait oublier \u00e0 chaque homme ses a\u00efeux, mais elle lui cache ses descendants et le s\u00e9pare de ses contemporains ; elle le ram\u00e8ne sans cesse vers lui et menace de le renfermer enfin tout entier dans la solitude de son propre c&oelig;ur. <\/em>[&#8230;] <em>Chacun d&rsquo;eux, ainsi mis \u00e0 l&rsquo;\u00e9cart, est comme \u00e9tranger \u00e0 la destin\u00e9e de tous les autres ; ses enfants et ses amis particuliers forment pour lui toute l&rsquo;esp\u00e8ce humaine ; quant au demeurant de ses concitoyens, il est \u00e0 c\u00f4t\u00e9 d&rsquo;eux mais il ne les voit pas ; il les touche et ne les sent point ; il n&rsquo;existe qu&rsquo;en lui-m\u00eame et pour lui seul, et, s&rsquo;il lui reste encore une famille, on peut dire au moins qu&rsquo;il n&rsquo;a plus de patrie. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>\u00ab\u00a0Au moins\u00a0\u00bb, avec celui-l\u00e0 (et avec Le Goff finalement), <strong>vous ressentez \u00e0 nouveau cette fiert\u00e9 transcendante et absolument collective<\/strong>, bien autant dans son pass\u00e9 que nulle part ailleurs, d&rsquo;\u00eatre Fran\u00e7ais.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainsi suffirait-il de lire Tocqueville&#8230; 30 mai 2016 &ndash; Lisant Malaise dans la d\u00e9mocratie de Jean-Pierre Le Goff (d\u00e9j\u00e0 signal\u00e9), je v\u00e9rifie aussit\u00f4t que ma vieille et profonde affection pour Tocqueville est si justifi\u00e9e. Contrairement \u00e0 ce qu&rsquo;en disent, unanimement et au pas cadenc\u00e9, les intellectuels am\u00e9ricanistes-Syst\u00e8me (avec les suivistes franchouillards) qui lui vouent un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2947,8784,2825,17490,3879,17540,2711,17539,8082],"class_list":["post-76595","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-amerique","tag-antimodernes","tag-democratie","tag-goff","tag-individualisme","tag-joffrin","tag-le","tag-libe","tag-sainte-beuve"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76595"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76595\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}