{"id":76632,"date":"2016-06-19T17:01:17","date_gmt":"2016-06-19T17:01:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/06\/19\/mon-18-juin\/"},"modified":"2016-06-19T17:01:17","modified_gmt":"2016-06-19T17:01:17","slug":"mon-18-juin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/06\/19\/mon-18-juin\/","title":{"rendered":"Mon 18-juin"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mon 18-juin<\/h2>\n<\/p>\n<p><p>19 juin 2016 &ndash; Hier, dans la seizi\u00e8me <em><a href=\"http:\/\/www.dedefensa.org\/article\/humeur-de-crise-16\">Humeur de crise<\/a><\/em>, je rappelais un passage du discours de Malraux de d\u00e9cembre 1964 en pr\u00e9cisant qu&rsquo;il \u00e9tait extrait d&rsquo;un film :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Voyant ce passage du discours de Malraux qui s&rsquo;\u00e9coute autant avec les yeux de l&rsquo;\u00e2me tragique et po\u00e9tique, dans un film documentaire splendide, tr\u00e8s r\u00e9cemment diffus\u00e9 et dont je reparlerai tr\u00e8s vit<\/em>e&#8230; &raquo;. C&rsquo;\u00e9tait une fa\u00e7on de saluer le 18 juin, et saluer \u00ab\u00a0mon 18-juin\u00a0\u00bb un jour plus tard, le 19, a \u00e9galement un sens.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je m&rsquo;explique et qu&rsquo;importe s&rsquo;il ne s&rsquo;agit que d&rsquo;un rapport chronologique, mais cela est peut-\u00eatre \u00e9galement un signe&#8230; Il y a une certaine logique pour <em>dedefensa.org<\/em>, et donc pour moi, de faire \u00ab\u00a0mon 18 juin\u00a0\u00bb le 19 juin, ou \u00ab\u00a019 courant&#8230;\u00a0\u00bb qui est devenu un des th\u00e8mes du site. C&rsquo;est exactement ce qu&rsquo;il \u00e9tait \u00e9crit dans un article du 19 octobre 2011 o&ugrave; le site lan\u00e7ait sa formule de donation mensuelle selon un code qui nous est propre, et qui \u00e9tait succinctement r\u00e9sum\u00e9 de la sorte :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pour l&rsquo;imm\u00e9diat, que faire sinon renouveler l&rsquo;op\u00e9ration d&rsquo;il y a un mois, qui devient ainsi presque structurellement notre \u00ab\u00a0appel du 19 courant\u00a0\u00bb. Apr\u00e8s tout et en d\u00e9sespoir de cause, et tant qu&rsquo;elle tiendra, arrivera-t-on peut-\u00eatre \u00e0 cette formule r\u00e9p\u00e9titive. Il y a l&rsquo;appel du 18 juin, peut-\u00eatre y aura-t-il \u00ab\u00a0l&rsquo;appel du 19 courant\u00a0\u00bb&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le film donc&#8230; <em>Au premier rendez-vous de la r\u00e9sistance<\/em> a \u00e9t\u00e9 pr\u00e9sent\u00e9 le <a href=\"http:\/\/www.histoire.fr\/actualit%C3%A9s\/au-premier-rendez-vous-de-la-resistance\">8 juin<\/a> sur la cha&icirc;ne <em>Histoire<\/em>, pr\u00e9c\u00e9d\u00e9 d&rsquo;une \u00e9mission <em>Historiquement Show<\/em> <a href=\"http:\/\/www.histoire.fr\/actualit%C3%A9s\/historiquement-show-241-sp%C3%A9ciale-premiers-r%C3%A9sistants-%E2%80%93-arletty\">le 3 juin<\/a> consacr\u00e9e \u00e0 la p\u00e9riode 1940-1945 (r\u00e9sistance et collaboration), et notamment \u00e0 ce film de Luc Detoo pr\u00e9sent\u00e9 par l&rsquo;historien Francis Hughenin. Le film est une \u00e9trange et glaciale d\u00e9monstration <em>a contrario<\/em> de la sorte d&rsquo;univers o&ugrave; nous vivons, enferm\u00e9s dans des conventions et des convenances, l&rsquo;esprit anim\u00e9 d&rsquo;une superbe libert\u00e9 pour s&rsquo;\u00e9lancer dans les champs sans fin des lieux communs et des clich\u00e9s, chevauchant l&rsquo;ivresse du conformisme qui se proclame v\u00e9rit\u00e9 de soi. Le film ne d\u00e9montre pas, il montre simplement que la r\u00e9sistance, \u00e0 ses extr\u00eames d\u00e9buts, lorsque parlait la patriotisme le plus pur, lorsque s&rsquo;exprimait la foi la plus intense, venait de la partie politique de la nation fran\u00e7aise qu&rsquo;on n&rsquo;a cess\u00e9 depuis de rel\u00e9guer sur les bancs de l&rsquo;infamie, celui de la collaboration, de la trahison, de l'\u00a0\u00bbintelligence avec l&rsquo;ennemi\u00a0\u00bb. Nous vivons sur l&rsquo;image d&rsquo;Epinal absolument invers\u00e9, et l&rsquo;on se demande bien ce qui a chang\u00e9 depuis.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La gauche r\u00e9sistante, la droite collabo, il faut vraiment mettre tout \u00e7a \u00e0 la poubelle et revoir toute la p\u00e9riode<\/em> &raquo;, dit St\u00e9phane Courtois en commentaire du film documentaire de Detoo.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Parmi les quatre premiers envoy\u00e9s de De Gaulle en France pour organiser les premiers r\u00e9seaux de la r\u00e9sistance, il y avait deux Cagoulards, un maurassien et un royaliste ; les premiers chefs et h\u00e9ros de la France Libre, R\u00e9my, Maurice Duclos, Pierre Fourcault, Honor\u00e9 d&rsquo;Estienne d&rsquo;Orves (les quatre envoy\u00e9s), Daniel Cordier qui croyait qu&rsquo;il retrouverait Maurras \u00e0 Londres le 17 juin 1940, Loustanau Lacau et Marie-Madeleine Fourcade, Renouvin, Henry Frenay fondateur du premier grand r\u00e9seau (<em>Combat<\/em>), ils \u00e9taient tous royalistes, conservateurs et catholiques, maurassiens ; de Gaulle lui-m\u00eame \u00e9tait de cette \u00e9cole, et, avec lui, le plus grand chef militaire de la France Libre, le royaliste Philippe de Hautecloque, dit Leclerc&#8230; Et ainsi de suite, et autant pour la \u00ab\u00a0th\u00e9orie des deux France\u00a0\u00bb, l&rsquo;une vertueuse et de gauche, l&rsquo;autre ha\u00efssable et de droite. Les maurassiens furent les plus constants adversaires de l&rsquo;Allemagne durant l&rsquo;entre-deux-guerres, ne cessant de d\u00e9noncer le r\u00e9armement, les perspectives de volont\u00e9 de puissance de Hitler&#8230;<\/p>\n<\/p>\n<p><p>Les historiens qui peuvent parler \u00e0 l&rsquo;occasion de ce film, ceux \u00e0 qui il est rarement donn\u00e9 la parole dans &laquo; <em>notre bonne r\u00e9publique de 2016<\/em> &raquo; (Courtois), ceux-l\u00e0 notent l&rsquo;extraordinaire confusion de la p\u00e9riode o&ugrave; les partis, au lieu de se regrouper entre droite et gauche, se voyaient divis\u00e9s chacun entre pacifistes et bellicistes, avec une position \u00e0 mesure vis-\u00e0-vis de l&rsquo;ennemi. Simplement, les royalistes, les maurassiens et les conservateurs qui choisirent la r\u00e9sistance furent notablement plus rapides que les communistes, dont on sait qu&rsquo;ils attendirent le sifflet de l&rsquo;arbitre de Moscou, le 21 juin 1941, pour s&rsquo;engager dans cette voie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Une partie de la droite et de l&rsquo;extr\u00eame-droite percevait dans l&rsquo;Allemagne et le nazisme un danger fondamental pour la France, et ils furent les premiers r\u00e9sistants. <\/em>&raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela est expliqu\u00e9 par Simon Epstein, de l&rsquo;universit\u00e9 h\u00e9bra\u00efque de J\u00e9rusalem, auteur en 2001 des<em> Dreyfusards sous l&rsquo;occupation<\/em>, o&ugrave; il montre le nombre impressionnant des partisans de Dreyfus en 1898 encore actifs en 1940 devenus p\u00e9tainistes et collaborateurs pendant la Deuxi\u00e8me Guerre mondiale (on n&rsquo;appr\u00e9cia gu\u00e8re le bouquin, sur les rives de Saint-Germain-des-Pr\u00e9s). Quant aux socialistes et aux radicaux aux premiers temps de la r\u00e9sistance, ils tenaient congr\u00e8s avant de s&rsquo;engager.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>N&rsquo;oubliez pas que sur les 17 ministres socialistes du gouvernement du Front Populaire, les deux-tiers furent exclus de la SFIO en 1944 pour p\u00e9tainisme ou collaborationnisme<\/em> &raquo; [Epstein].)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien, je ne vais pas rappeler tout cela, ou l&rsquo;apprendre pour ceux qui l&rsquo;ignoraient, pour renverser la \u00ab\u00a0th\u00e9orie des deux France\u00a0\u00bb en sens inverse et verser ainsi dans le m\u00eame pi\u00e8ge \u00e0 l&rsquo;envers. Peu me chaut, sinon pour d\u00e9noncer avec une vigueur consid\u00e9rable le proc\u00e9d\u00e9, les arguties des th\u00e9oriciens et des th\u00e9sards avec leurs rangements et leurs causes pour lesquels ils fabriquent le pass\u00e9 en fonction des n\u00e9cessit\u00e9s pr\u00e9sentes et des privil\u00e8ges \u00e0 conserver. Ce que je vois, moi, c&rsquo;est ce que vaut ce qu&rsquo;ils nomment aujourd&rsquo;hui \u00ab\u00a0le devoir de m\u00e9moire\u00a0\u00bb, dont on sait qu&rsquo;il se fait toujours selon \u00ab\u00a0les consignes du Parti\u00a0\u00bb, pour employer l&rsquo;expression sans caract\u00e9riser le Parti en question, sinon de le d\u00e9signer comme le Parti du conformisme et de la bienpensance \u00e0 la fois tendance et bien en cour, qui permet de faire la promotion des \u00ab\u00a0valeurs\u00a0\u00bb du jour, et avec lui son fr\u00e8re jumeau le parti de la repentance qui permet de liquider les principes que la tradition nous avait conserv\u00e9s pour nous les transmettre&#8230;<\/p>\n<\/p>\n<p><p>L&rsquo;on dirait aussi bien, finalement et puisque c&rsquo;est toujours du m\u00eame qu&rsquo;on parle depuis deux si\u00e8cles, qu&rsquo;il s&rsquo;agit du Parti-Syst\u00e8me. Tout ce que nous apprend ce magnifique film documentaire qui rend justice \u00e0 ceux qui furent ignor\u00e9s, sinon train\u00e9s dans la boue des torrents de d\u00e9nonciation de leurs \u00e9coles de pens\u00e9e, c&rsquo;est que le \u00ab\u00a0devoir de m\u00e9moire\u00a0\u00bb est une belle expression du pr\u00e9sent-en-cours de chaque \u00e9poque pour d\u00e9signer le pi\u00e8ge o&ugrave; nous enferme, depuis au moins deux si\u00e8cles, notre histoire-tout-court (pour faire diff\u00e9rence avec l&rsquo;Histoire selon la m\u00e9tahistoire) sortie de nos \u00e9tablissements universitaires et des partis et groupes associ\u00e9s des \u00e9lites-Syst\u00e8me, et de la pens\u00e9 conforme qui y r\u00e8gne sans partage ni \u00e9lection d\u00e9mocratique, comme de droit-divin.<\/p>\n<\/p>\n<p><p>L&rsquo;on sort de la vision de ce film l&rsquo;esprit songeur, en s&rsquo;\u00e9tonnant une fois de plus combien l&rsquo;organisation humaine telle que nous la connaissons dans nos pi\u00e8tres contr\u00e9es tient au feu une telle passion pour la domination de l&rsquo;esprit-partisan du jour sur la v\u00e9rit\u00e9-de-situation qui permet de garder un lien indestructible avec le pass\u00e9. L&rsquo;on sort de ce film moins s&ucirc;r que jamais de ce que notre civilisation ne cesse de se dire d&rsquo;elle-m\u00eame et sur elle-m\u00eame, avec son auto-glorification et sa vaniteuse vertu dissimulant \u00e0 peine l&rsquo;<em>hybris<\/em> qu&rsquo;on y sent comme on sent la charogne des charniers. L&rsquo;on sort de ce film avec dans la bouche l&rsquo;amertume de ce d\u00e9go&ucirc;t pour les classements que les publicistes professionnels ne cessent de tenter de nous imposer. L&rsquo;on sort de ce film assur\u00e9 que le combat que l&rsquo;on doit aujourd&rsquo;hui mener n&rsquo;a nul besoin de leurs \u00e9tiquettes, de leurs slogans, sans d&rsquo;ailleurs les clouer au pilori ; simplement, pas besoin de ces pi\u00e8ges-l\u00e0&#8230; Et l&rsquo;on sort de ce film, finalement assur\u00e9 que lorsqu&rsquo;une \u00e9poque catastrophique atteint son point de paroxysme et que l&rsquo;ennemi ultime, l&rsquo;Ennemi-Diabolique est \u00e0 visage d\u00e9couvert, et que vous l&rsquo;avez identifi\u00e9 jusqu&rsquo;au fond des yeux, alors une certaine s\u00e9r\u00e9nit\u00e9 finit par s&rsquo;installer en vous parce que le moment est celui de la s&ucirc;ret\u00e9 de soi.  <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mon 18-juin 19 juin 2016 &ndash; Hier, dans la seizi\u00e8me Humeur de crise, je rappelais un passage du discours de Malraux de d\u00e9cembre 1964 en pr\u00e9cisant qu&rsquo;il \u00e9tait extrait d&rsquo;un film : &laquo; Voyant ce passage du discours de Malraux qui s&rsquo;\u00e9coute autant avec les yeux de l&rsquo;\u00e2me tragique et po\u00e9tique, dans un film documentaire&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[16812,2756,17578,2753,17501,17581,2631,14458,17580,2747,2685,17488,7627,17577,2615,15412,2755,8020,17579],"class_list":["post-76632","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-16812","tag-action","tag-cagoule","tag-collaboration","tag-courtois","tag-dorves","tag-de","tag-epstein","tag-estienne","tag-francaise","tag-gaulle","tag-historiquement","tag-juin","tag-maurras","tag-premier","tag-rendez-vous","tag-resistance","tag-show","tag-stephane"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76632"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76632\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}