{"id":76656,"date":"2016-07-05T17:05:38","date_gmt":"2016-07-05T17:05:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/05\/dostoievski-et-la-degenerescence-du-monde-par-le-reseau\/"},"modified":"2016-07-05T17:05:38","modified_gmt":"2016-07-05T17:05:38","slug":"dostoievski-et-la-degenerescence-du-monde-par-le-reseau","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/05\/dostoievski-et-la-degenerescence-du-monde-par-le-reseau\/","title":{"rendered":"Dosto\u00efevski et la d\u00e9g\u00e9n\u00e9rescence du monde par le r\u00e9seau"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Dosto\u00efevski et la d\u00e9g\u00e9n\u00e9rescence du monde par le r\u00e9seau<\/h2>\n<\/p>\n<p><p>Car il est pouss\u00e9 dans le filet par ses propres pieds ; et il marche sur les mailles du filet&#8230;<\/p>\n<\/p>\n<p><p>Job, 8, 18<\/p>\n<\/p>\n<p><p>J&rsquo;ai souvenance d&rsquo;un brillant texte de notre cher Guy Sorman (qui redonna jadis ses lettres de prosa\u00efsme au Figaro magazine) dans le journal de la &laquo; droite &raquo; espagnole ABC (BHL est charg\u00e9 lui de distraire et surtout d&rsquo;instruire les maigres sections d&rsquo;assaut du mondialisme dans El Pais). Et Guy Sorman, essayiste pourtant renomm\u00e9 pour ses piles d&rsquo;invendus, et entre deux \u00e9loges des r\u00e9fugi\u00e9s consid\u00e9r\u00e9s comme des forces vives du capital selon les Marx Brothers et Merkel, pr\u00e9sentait ainsi son argumentaire : &laquo; m\u00eame la Russie finira un jour par \u00eatre d\u00e9mocratique et progressiste et globalement dans le global &raquo;. Sans oublier la Chine, l&rsquo;Iran, la Turquie et tous les autres bons copains de ses mod\u00e8les Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>La Russie n&rsquo;est donc pas progressiste, branch\u00e9e et dans le coup, et ce surtout depuis que &ndash; selon Marc Ferro &ndash; elle a d\u00e9\u00e7u les aspirations prol\u00e9tariennes d&rsquo;une gauche que l&rsquo;on croyait port\u00e9e plut\u00f4t \u00e0 servir la soupe \u00e0 la vieille bourgeoisie am\u00e9ricanis\u00e9e.<\/p>\n<\/p>\n<p><p>Sur la Russie et le progr\u00e8s j&rsquo;ai heureusement mieux que Sorman ou BHL : Dosto\u00efevski. Je l&rsquo;ai aussi sur le th\u00e8me des &laquo; r\u00e9seaux &raquo;, sociaux ou num\u00e9riques, qui aujourd&rsquo;hui captent, d\u00e9tournent et recyclent toutes les \u00e9nergies et intellects de la plan\u00e8te terre devenue nervalienne. On cite bri\u00e8vement cette vision du mage dans Aur\u00e9lia :<\/p>\n<\/p>\n<p><p>&laquo; Cette pens\u00e9e me conduisit \u00e0 celle qu&rsquo;il y avait <strong>une vaste conspiration de tous les \u00eatres<\/strong> anim\u00e9s pour r\u00e9tablir le monde dans son harmonie premi\u00e8re, et que les communications avaient lieu par le magn\u00e9tisme des astres, qu&rsquo;<strong>une cha&icirc;ne non interrompue liait autour de la terre les intelligences d\u00e9vou\u00e9es \u00e0 cette communication g\u00e9n\u00e9rale,<\/strong> et les chants, les danses, les regards, aimant\u00e9s de proche en proche, traduisaient la m\u00eame aspiration. La lune \u00e9tait pour moi le refuge des \u00e2mes fraternelles qui, d\u00e9livr\u00e9es de leurs corps mortels, travaillaient plus librement \u00e0 <strong>la r\u00e9g\u00e9n\u00e9ration de l&rsquo;univers<\/strong>. (1) &raquo;<\/p>\n<\/p>\n<p><p>Dosto\u00efevski a abord\u00e9 le th\u00e8me de la confrontation de la Russie et du progr\u00e8s, de la Russie et de l&rsquo;Occident dans plusieurs de ses plus grands livres, en particulier dans l&rsquo;<em>Idiot <\/em>et dans <em>Les Poss\u00e9d\u00e9s<\/em>, qui eux font allusion \u00e0 une <strong>origine am\u00e9ricaine de la prochaine r\u00e9volution<\/strong>.<\/p>\n<\/p>\n<p><p>Dans le r\u00e9cit satirique <em>Crocodile<\/em> (2), il le fait d&rsquo;une mani\u00e8re parodique, s&rsquo;en prenant aux pr\u00e9jug\u00e9s modernistes du dernier homme \u00e0 venir (et surtout \u00e0 durer). Il y a l&rsquo;\u00e9pisode humanitaire &ndash; ne pas maltraiter un pauvre animal, f&ucirc;t-ce un croco &ndash;, l&rsquo;\u00e9pisode p\u00e9dagogique &ndash; de l&rsquo;importance de la question \u00e9conomique ! &ndash; et pour finir l&rsquo;\u00e9pisode gastronomique qui r\u00e9sout la question &ndash; en d\u00e9vorant le crocodile.<\/p>\n<\/p>\n<p><p>Depuis deux si\u00e8cles nous nous gorgeons de ce progr\u00e8s technique et \u00e9conomique, et il semble que l&rsquo;imb\u00e9cillit\u00e9 satisfaite qui l&rsquo;accompagne n&rsquo;a jamais \u00e9t\u00e9 plus remise en question qu&rsquo;\u00e0 l&rsquo;\u00e9poque de Flaubert ou de Dosto\u00efevski. Mais \u00e0 la m\u00eame \u00e9poque un Walt Whitman c\u00e9l\u00e8bre les ach\u00e8vements de ce qu&rsquo;il est convenu de nommer \u00e0 la t\u00e9l\u00e9 la modernit\u00e9&#8230;<\/p>\n<\/p>\n<p><p>Dans <em>Passage to India<\/em> ou <em>Song of the Exposition<\/em> (\u00e0 comparer avec le cadre m\u00e9di\u00e9val et traditionnel des Tableaux, le chef d&rsquo;oeuvre pianistique de Moussorgski), le trop c\u00e9l\u00e9br\u00e9 Walt Whitman chante et c\u00e9l\u00e8bre sur tous les tons le canal de Suez, ce passage qui va r\u00e9unir l&rsquo;orient et l&rsquo;occident, notions fort disparues auxquelles on fait mine de croire encore : car &laquo;dans un monde unifi\u00e9 on ne peut s&rsquo;exiler &raquo; (Debord). Avec une accumulation dont il a le secret, le &laquo; poh\u00e8te &raquo; am\u00e9ricain fait l&rsquo;\u00e9tat des lieux, et il nous \u00e9tourdit avec son clinquant verbalisme, chaque mot faisant office de paradigme roturier de la modernit\u00e9 aboyante:<\/p>\n<\/p>\n<p><p><em>With latest connections, works, the inter-transportation of the world,<\/em><\/p>\n<\/p>\n<p><p><em>Steam-power, the great express lines, gas, petroleum,<\/em><\/p>\n<\/p>\n<p><p><em>These triumphs of our time, the Atlantic&rsquo;s delicate cable,<\/em><\/p>\n<\/p>\n<p><p><em>The Pacific railroad, the Suez canal, the Mont Cenis and Gothard and<\/em><\/p>\n<\/p>\n<p><p><em>Hoosac tunnels, the Brooklyn bridge,<\/em><\/p>\n<\/p>\n<p><p><em>This earth all spann&rsquo;d with iron rails, with lines of steamships threading in every sea,<\/em><\/p>\n<\/p>\n<p><p><em>Our own rondure, the current globe I bring.<\/em><\/p>\n<\/p>\n<p><p>Barde &laquo; tendance &raquo; avant l&rsquo;heure, Ma\u00efakovski un rien couillon, &laquo; animal verbal &raquo; (Daudet) plus que po\u00e8te, Whitman est en extase devant ce qui p\u00e9tarade. Il admire nos exploits \u00e0 Suez (dont bien s&ucirc;r Dosto\u00efevski se moque avec son crocodile du Nil), et il c\u00e9l\u00e8bre le chemin de fer unificateur, celui des Anglais aux Indes ou des Am\u00e9ricains :<\/p>\n<\/p>\n<p><p><em>I see the tracks of the railroads of the earth,<\/em><\/p>\n<\/p>\n<p><p><em>I see them in Great Britain, I see them in Europe,<\/em><\/p>\n<\/p>\n<p><p><em>I see them in Asia and in Africa.<\/em><\/p>\n<\/p>\n<p><p><em>I see the electric telegraphs of the earth,<\/em><\/p>\n<\/p>\n<p><p><em>I see the filaments of the news of the wars, deaths, losses, gains, passions,<\/em><\/p>\n<\/p>\n<p><p><em>Of my race.<\/em><\/p>\n<\/p>\n<p><p>Or pr\u00e9cis\u00e9ment sur ces chemins de fer qui ont vid\u00e9 les campagnes et ruin\u00e9 le contribuable fran\u00e7ais (la moiti\u00e9 des lignes servant \u00e0 faire \u00e9lire un d\u00e9put\u00e9), ou ont justifi\u00e9 une bonne moiti\u00e9 des crises boursi\u00e8res de l&rsquo;\u00e9poque (comme les actions techno d&rsquo;aujourd&rsquo;hui), Dosto\u00efevski a quelque chose de peu aimable \u00e0 dire, et qu&rsquo;il va dire dans <em>l&rsquo;Idiot<\/em>. C&rsquo;est un autre <em>idiot m\u00e9taphorique<\/em> (un simple d&rsquo;esprit qui voit l&rsquo;Esprit) que le Prince, l&rsquo;ivrogne Lebedev qui s&rsquo;exprime sur les chemins de fer et leur r\u00e9seau qui selon lui s&rsquo;en prend aux formes de vie.<\/p>\n<\/p>\n<p><p><em>Montrez-moi donc quelque chose qui approche de cette force dans notre si\u00e8cle de vices et de chemins de fer&hellip;<\/em><\/p>\n<\/p>\n<p><p><strong>Lebedev voit dans tout r\u00e9seau moderne un affaiblissement \u00e0 la fois spirituel et physique de l&rsquo;homme<\/strong>, li\u00e9 au progr\u00e8s de la matrice du confort mat\u00e9riel. L&rsquo;homme va \u00eatre coup\u00e9 de ses sources de vie et de son tellurisme. C&rsquo;est aussi la le\u00e7on d&rsquo;Andersen (<em>La Vierge des glaces<\/em>), de Novalis ou de Vigny (&laquo; avant vous j&rsquo;\u00e9tais belle et j&rsquo;allais parfum\u00e9e &raquo;&hellip;). Mais Tocqueville nous a aussi pr\u00e9venus sur les risques que faisaient peser l&rsquo;\u00e9galit\u00e9 et le r\u00e9seau fort sur les hommes dits modernes. Dans le tome II de sa somme, il d\u00e9crit, dans un texte mal compris, cet <strong>affaiblissement des<em> forces de vie <\/em>li\u00e9es au d\u00e9veloppement \u00e9tatique<\/strong> :<\/p>\n<\/p>\n<p><p><em>&laquo; C&rsquo;est ainsi que tous les jours il rend moins utile et plus rare l&#8217;emploi du libre arbitre ; qu&rsquo;il renferme l&rsquo;action de la volont\u00e9 dans un plus petit espace, et d\u00e9robe peu \u00e0 peu \u00e0 chaque citoyen jusqu&rsquo;\u00e0 l&rsquo;usage de lui-m\u00eame. L&rsquo;\u00e9galit\u00e9 a pr\u00e9par\u00e9 les hommes \u00e0 toutes ces choses : elle les a dispos\u00e9s \u00e0 les souffrir et souvent m\u00eame \u00e0 les regarder comme un bienfait&hellip; il ne tyrannise point, il g\u00eane, il comprime, il \u00e9nerve, il \u00e9teint, il h\u00e9b\u00e8te, et il r\u00e9duit enfin chaque nation a n&rsquo;\u00eatre plus qu&rsquo;un troupeau d&rsquo;animaux timides et industrieux, dont le gouvernement est le berger (3). <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Retournons \u00e0 <em>l&rsquo;Idiot<\/em>. <strong>Lebedev voit le premier, cent-vingt ans avant Tchernobyl, un lien entre l&rsquo;\u00e9toile absinthe de l&rsquo;Apocalypse (Tchernobyl d\u00e9signe comme on sait l&rsquo;absinthe en russe) et l&rsquo;extension du r\u00e9seau en Europe :<\/strong><\/p>\n<\/p>\n<p><p><em>&laquo; Le coll\u00e9gien lui affirma que l&rsquo;&quot;&Eacute;toile Absinthe&quot; qui, dans l&rsquo;Apocalypse, tombe sur terre \u00e0 la source des eaux, pr\u00e9figurait, selon l&rsquo;interpr\u00e9tation de son p\u00e8re, le r\u00e9seau des chemins de fer \u00e9tendu aujourd&rsquo;hui sur l&rsquo;Europe. &raquo;<\/em><\/p>\n<\/p>\n<p><p>Lebedev d\u00e9gage comme le prince Muichkine une aura d&rsquo;imperfection, d&rsquo;inad\u00e9quation \u00e0 la mondanit\u00e9. C&rsquo;est souvent le cas chez Dosto\u00efevski : le porteur de la v\u00e9rit\u00e9 doit \u00eatre ridiculis\u00e9 ou caricatur\u00e9 &ndash; pour ne pas \u00eatre pris au s\u00e9rieux par <strong>la compagnie qui doit continuer de se tordre,<\/strong> comme dit Allais<strong>.<\/strong><\/p>\n<\/p>\n<p><p>Lebedev va d\u00e9signer une autre cible, qui nous rapproche de la petite soci\u00e9t\u00e9 actuelle: l&rsquo;id\u00e9ologie du bonheur mat\u00e9riel universel ; le dernier homme dont parle Francis Fukuyama apr\u00e8s bien d&rsquo;autres.<\/p>\n<\/p>\n<p><p><em>Vous n&rsquo;avez pas d&rsquo;autre fondement moral que la satisfaction de l&rsquo;\u00e9go\u00efsme individuel et des besoins mat\u00e9riels. La paix universelle, le bonheur collectif r\u00e9sultant du besoin !<\/em><\/p>\n<\/p>\n<p><p>Lebedev n&rsquo;est bien s&ucirc;r pas un sot : il n&rsquo;incrimine pas la machine en tant que telle. Il incrimine plut\u00f4t la notion de r\u00e9seau. Par ailleurs il a pleinement conscience que son expression des forces de vie est incompr\u00e9hensible \u00e0 un esprit moderne :<\/p>\n<\/p>\n<p><p><em>&laquo; Par eux-m\u00eames les chemins de fer ne peuvent corrompre les sources de vie. Ce qui est maudit, c&rsquo;est l&rsquo;ensemble ; c&rsquo;est, dans ses tendances, tout l&rsquo;esprit scientifique et pratique de nos derniers si\u00e8cles. Oui, il se peut que tout cela soit bel et bien maudit ! &raquo;<\/em><\/p>\n<\/p>\n<p><p>Sur le ton de l&rsquo;impr\u00e9cation, emport\u00e9 par cette inspiration religieuse, Lebedev adresse un d\u00e9fi au monde mat\u00e9rialiste et satisfait, monde sans gouvernail et sans cap m\u00eame :<\/p>\n<\/p>\n<p><p><em>&laquo; Je vous lance maintenant un d\u00e9fi \u00e0 vous tous, ath\u00e9es que vous \u00eates : comment sauverez-vous le monde ? Quelle route normale lui avez-vous ouverte vers le salut, vous autres, savants, industriels, d\u00e9fenseurs de l&rsquo;association, du salariat et de tout le reste ? Par quoi sauverez-vous le monde ? Par le cr\u00e9dit ? Qu&rsquo;est-ce que le cr\u00e9dit ? &Agrave; quoi vous m\u00e8nera-t-il? &raquo;<\/em><\/p>\n<\/p>\n<p><p>Ainsi Dosto\u00efevski n&rsquo;encenserait pas ce monde et son cr\u00e9dit ?<\/p>\n<\/p>\n<p><p>A ce propos le psalmiste dit :<\/p>\n<\/p>\n<p><p>&laquo; Que l&rsquo;usurier jette le filet sur tout ce qui est \u00e0 lui&#8230; (4) &raquo;<\/p>\n<\/p>\n<p><p><strong>Cent ans avant l&rsquo;effet de serre et le r\u00e9chauffement climatique du cerveau qui va avec<\/strong>, Lebedev voit l&rsquo;av\u00e8nement de l&rsquo;homoncule affaibli par sa si riche information et la &laquo; thermocratie &raquo; (5). Il constate <strong>l&rsquo;absence de la force<\/strong> dans notre soci\u00e9t\u00e9 :<\/p>\n<\/p>\n<p><p><em>&laquo; Et osez dire apr\u00e8s cela que les sources de vie n&rsquo;ont pas \u00e9t\u00e9 affaiblies, troubl\u00e9es, sous cette \u00ab\u00a0\u00e9toile\u00a0\u00bb, sous ce r\u00e9seau dans lequel les hommes se sont emp\u00eatr\u00e9s. Et ne croyez pas m&rsquo;en imposer par votre prosp\u00e9rit\u00e9, par vos richesses, par la raret\u00e9 des disettes et par la rapidit\u00e9 des moyens de communication !  <\/em><strong>Les richesses sont plus abondantes, mais les forces d\u00e9clinent ; il n&rsquo;y a plus de pens\u00e9e qui cr\u00e9e un lien entre les hommes ; tout s&rsquo;est ramolli, tout a cuit et tous sont cuits !<\/strong><em> Oui, tous, tous, tous nous sommes cuits !&hellip; Mais suffit ! (6) <\/em>&raquo;<\/p>\n<\/p>\n<p><h4>Nicolas Bonnal<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d;font-size:1.25em;\">Notes<\/h2>\n<\/p>\n<p><p>(1) Nerval, Aur\u00e9lia, 2\u00e8me partie, VI.<\/p>\n<\/p>\n<p><p>(2) Lisez mon \u00e9tude sur france-courtoise.info\/pdf\/BonnalDostoievskiCrocodile.pdf. Voyez aussi Internet, nouvelle voie initiatique (les Belles Lettres, 2000)&#8230;<\/p>\n<\/p>\n<p><p>(3) De la D\u00e9mocratie II, IV, ch.6<\/p>\n<\/p>\n<p><p>(4) Psaumes, 109, 11<\/p>\n<\/p>\n<p><p>(5) Gilles Ch\u00e2telet, Vivre et penser comme des porcs (2000).<\/p>\n<\/p>\n<p><p>(6) L&rsquo;Idiot, III, chapitre  IV<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dosto\u00efevski et la d\u00e9g\u00e9n\u00e9rescence du monde par le r\u00e9seau Car il est pouss\u00e9 dans le filet par ses propres pieds ; et il marche sur les mailles du filet&#8230; Job, 8, 18 J&rsquo;ai souvenance d&rsquo;un brillant texte de notre cher Guy Sorman (qui redonna jadis ses lettres de prosa\u00efsme au Figaro magazine) dans le journal&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2640,12699,2631,5358,17614,2913,12732,7899,3122],"class_list":["post-76656","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bonnal","tag-chemin","tag-de","tag-fer","tag-lidiot","tag-les","tag-possedes","tag-reseau","tag-whitman"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76656"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76656\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}