{"id":76665,"date":"2016-07-12T12:03:46","date_gmt":"2016-07-12T12:03:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/12\/the-lady-is-a-trump\/"},"modified":"2016-07-12T12:03:46","modified_gmt":"2016-07-12T12:03:46","slug":"the-lady-is-a-trump","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/12\/the-lady-is-a-trump\/","title":{"rendered":"<em>The Lady Is A Trump<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>The Lady Is A Trump<\/em><\/h2>\n<\/p>\n<p><p>12 juillet 2016 &ndash; Il suffit de changer une lettre et le <em>standard<\/em> \u00e0 la signification ambigu\u00eb de 1937 (voyez <em><a href=\"https:\/\/www.youtube.com\/watch?v=ZPAmDULCVrU\">The Lady Is A Tramp<\/a><\/em> interpr\u00e9t\u00e9 par Lady Gaga et le vieux Tony Bennett, Lady Gaga grande chanteuse presque <em>jazzy<\/em>), ce <em>standard<\/em> devient une fable ironique sur un destin qui h\u00e9sit\u00e9 entre le tragique, le monstrueux, l&rsquo;ironie grin\u00e7ante et le d\u00e9risoire. \u00ab\u00a0<em>Tramp\u00a0\u00bb<\/em> signifie \u00ab\u00a0vagabond\u00a0\u00bb et d\u00e9crit dans la chanson une \u00ab\u00a0Dame\u00a0\u00bb fantasque  peu pr\u00e9occup\u00e9e des conventions et qui n&rsquo;a que m\u00e9pris pour les richesses affich\u00e9es (version bienveillante), qui s&rsquo;av\u00e8re \u00eatre aussi bien une \u00ab\u00a0vagabonde\u00a0\u00bb, une \u00ab\u00a0clocharde\u00a0\u00bb comme il y en avait tant \u00e0 cette \u00e9poque de d\u00e9sastre \u00e9conomique ; ainsi l&rsquo;ambigu\u00eft\u00e9 est-elle de faire d&rsquo;une <em>Lady<\/em> une vagabonde, et d&rsquo;une vagabonde une <em>Lady<\/em>&#8230; Avec une seule lettre chang\u00e9e, \u00ab\u00a0<em>Trump<\/em>\u00a0\u00bb signifie \u00ab\u00a0atout\u00a0\u00bb ou \u00ab\u00a0carte ma&icirc;tresse\u00a0\u00bb, et c&rsquo;est aussi le nom que vous savez, et le titre devient tout \u00e0 fait diff\u00e9rent, d&rsquo;une actualit\u00e9 br&ucirc;lante puisque l&rsquo;\u00e9lection se joue entre une <em>Lady<\/em> et un Trump, mais d&rsquo;une signification \u00e9galement tr\u00e8s ambig\u00fce. Le destin ne cesse de ricaner.<\/p>\n<\/p>\n<p><p>Hillary (<em>The Lady<\/em>), en deux petites semaines, pas plus, a invers\u00e9 le sens des choses de la communication. Depuis lors, en effet, c&rsquo;est elle qui tient la vedette de la une des m\u00e9dias de la communication, o&ugrave; elle a remplac\u00e9 l&rsquo;innommable Donald Trump, ainsi rattrapant le capital de c\u00e9l\u00e9brit\u00e9 m\u00e9diatique qui avait \u00e9t\u00e9 jusqu&rsquo;alors la rente de situation de <em>The Donald<\/em>. On peut alors dire effectivement que <em>The Lady Is A Trump<\/em>, mais d&rsquo;une fa\u00e7on bien contradictoire qui m\u00e9rite sans le moindre doute une explication pr\u00e9cise. <strong>L&rsquo;\u00e9nergie de la communication a chang\u00e9 de camp, mais en m\u00eame temps le destin lui-m\u00eame, tout cela faisant de ce champ de la communication qui avait \u00e9t\u00e9 une route sem\u00e9e de p\u00e9tales de rose pour la notori\u00e9t\u00e9 populiste du Trump, un redoutable champ de mines pour <em>The Lady<\/em><\/strong>. Je crois qu&rsquo;on devrait appr\u00e9cier ce ph\u00e9nom\u00e8ne comme un double renversement extraordinaire, o&ugrave; Clinton reprend l&rsquo;avantage de la notori\u00e9t\u00e9 et de la communication, mais pour exposer en pleine lumi\u00e8re, chose affreuse, le c\u00f4t\u00e9 sombre du personnage. (<em>The Lady Is A McBeth.<\/em>)<\/p>\n<\/p>\n<p><p>L&rsquo;ironie complexe et \u00e0 plusieurs faces du destin est que se sont encha&icirc;n\u00e9s <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-tsunami-uss-titanic\">dans une s\u00e9quence rapide<\/a> deux \u00e9v\u00e8nements qui ont \u00e9t\u00e9 autant de crises, dont Hillary a \u00e9t\u00e9 l&rsquo;incontestable vedette, renvoyant Trump \u00e0 une sobri\u00e9t\u00e9 et un effacement auxquels il ne nous avait nullement accoutum\u00e9s. Mais quelle vedette catastrophique !  L&rsquo;encha&icirc;nement s&rsquo;est fait entre le paroxysme de la crise de l&rsquo;<em>emailgate<\/em> et la crise de la fusillade de Dallas qui fait crier \u00e0 la \u00ab\u00a0guerre raciale\u00a0\u00bb, avec l&rsquo;expansion g\u00e9n\u00e9rale du mouvement <em>BlackLiveMatters<\/em> (BLM), dont <em>The Lady<\/em> est une fervente partisane et une avocate bruyante et affich\u00e9e.<\/p>\n<\/p>\n<p><p>Dans le premier cas, tout a commenc\u00e9 par la meilleure nouvelle du monde, de la non-inculpation de <em>The Lady<\/em>, suivie aussit\u00f4t et j&rsquo;imagine d&rsquo;une fa\u00e7on tr\u00e8s inattendue pour elle et sa suffisance courante d&rsquo;une tr\u00e8s rapide et catastrophique d\u00e9gradation de la situation, culminant pour l&rsquo;\u00e9pisode concern\u00e9 par l&rsquo;audition du directeur du FBI par le Congr\u00e8s, le 7 juillet. Le r\u00e9sultat net est impressionnant dans le sens \u00e9galement catastrophique : d&rsquo;abord une possible sinon probable deuxi\u00e8me enqu\u00eate du FBI <a href=\"http:\/\/www.mcclatchydc.com\/news\/politics-government\/election\/article88965897.html\">demand\u00e9e par le Congr\u00e8s<\/a> dans le but d&rsquo;\u00e9ventuellement inculper Clinton de mensonge sous serment lors d&rsquo;une audition (en 2015), ce qui rel\u00e8verait de \u00ab\u00a0l&rsquo;outrage au Congr\u00e8s\u00a0\u00bb ; <strong>ensuite et surtout des <a href=\"http:\/\/www.washingtonexaminer.com\/new-washington-post-poll-spells-bad-news-for-clinton\/article\/2596106\">sondages catastrophiques<\/a> <\/strong>portant, non seulement sur la d\u00e9sapprobation de sa non-inculpation, mais plus encore qui d\u00e9veloppe et d\u00e9taille dans tous les sens possibles un doute majoritaire sur la capacit\u00e9 de Clinton d&rsquo;assurer des fonctions pr\u00e9sidentielles en raison de son attitude vis-\u00e0-vis des documents <em>classified<\/em> et des l\u00e9g\u00e8ret\u00e9s qu&rsquo;elle prend avec ces mati\u00e8res, donc une immense ombre projet\u00e9e sur sa \u00ab\u00a0comp\u00e9tence\u00a0\u00bb alors que la confiance dans son honn\u00eatet\u00e9 est parall\u00e8lement toujours au plus bas du plus en plus bas. Le jugement de Comey sur une Clinton \u00ab\u00a0assez peu sophistiqu\u00e9e\u00a0\u00bb a \u00e9t\u00e9 d\u00e9vastateur et renverse totalement l&rsquo;argumentation jusqu&rsquo;alors d\u00e9velopp\u00e9e. Horreur et consternation ! <strong>Ce n&rsquo;est plus Trump qui est \u00ab\u00a0incomp\u00e9tent\u00a0\u00bb et peu qualifi\u00e9 pour la fonction pr\u00e9sidentielle, mais <em>The Lady<\/em> elle-m\u00eame<\/strong>.<\/p>\n<\/p>\n<p><p>La deuxi\u00e8me aventure n&rsquo;est pas plus heureuse. L&rsquo;attitude extr\u00e9miste prise par Clinton sur la culpabilit\u00e9 collective et d&rsquo;une certaine fa\u00e7on absolue, sans appel et sans retour des Blancs vis-\u00e0-vis des Noirs aux USA n&rsquo;a pas eu un \u00e9cho extr\u00eamement satisfaisant pour elle tant l&rsquo;outrance et l&rsquo;exag\u00e9ration l&rsquo;ont fait percevoir comme \u00e0 la fois irresponsable et marginalis\u00e9e par elle-m\u00eame. Encore ne sait-on pas o&ugrave; tout cela va nous mener, car si le mouvement avec notamment le groupe BLM prend de l&rsquo;ampleur, il risque de la d\u00e9passer et de l&#8217;emporter, exactement comme les diverses manipulations des islamiste-djihadistes jusqu&rsquo;\u00e0 <em>Daesh<\/em> &#038; Cie, si largement dues aux USA dans leur manufacture et leur entretien, ont tr\u00e8s largement \u00e9chapp\u00e9 au contr\u00f4le de leurs producteurs. Du coup et le plus logiquement du monde, on a tendance \u00e0 mettre ces divers troubles, y compris nombre des menaces qui se profilent \u00e0 l&rsquo;horizon, \u00e0 son d\u00e9bit et<strong> cela fait d&rsquo;elle une candidate du d\u00e9sordre et, d&rsquo;une autre fa\u00e7on mais toujours dans le m\u00eame sens, d&rsquo;irrespect de la loi<\/strong> ; alors, certes, <em>The Lady Is a Tramp<\/em>, dans le sens le plus d\u00e9favorable du terme pour la perception d&rsquo;un \u00e9lectorat de plus en plus sensible \u00e0 ces th\u00e8mes.<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Pendant ce temps et profitant de l&rsquo;aubaine, Trump peut inscrire <a href=\"https:\/\/twitter.com\/realDonaldTrump\">sur son tweet<\/a> en grande lettres rouges majestueuses \u00ab\u00a0<em>I am the Law &#038; Order Candidate<\/em>\u00ab\u00a0<\/strong>&#8230; Lui, le candidat \u00ab\u00a0de la loi et de l&rsquo;ordre\u00a0\u00bb, lui qu&rsquo;on a accus\u00e9 d&rsquo;amener le d\u00e9sordre, de bouleverser toutes les r\u00e8gles (lois non-\u00e9crites) de cette d\u00e9mocratie-Syst\u00e8me, lui qu&rsquo;on a d\u00e9sign\u00e9 comme l&rsquo;antiSyst\u00e8me venu mettre tout sens-dessus-dessous, &ndash; <strong>et il n&rsquo;a m\u00eame pas besoin de se faire Syst\u00e8me pour repousser toutes ces accusations et au contraire s&rsquo;afficher du camp de la loi et de l&rsquo;ordre, mais au contraire il lui suffit de rester antiSyst\u00e8me&#8230;<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>On dit, &ndash; que ne dit-on pas, certes, &ndash; qu&rsquo;en plus de ses nombreuses vertus, <em>The Lady<\/em> a celle de faire grande consommation de m\u00e9dicaments ayant de f\u00e2cheux effets sur ses nerfs. Pour cette fois, sa compl\u00e8te culpabilit\u00e9 n&rsquo;est pas \u00e9tablie, puisque ce traitement concernerait les s\u00e9quelles d&rsquo;un accident de sant\u00e9 qu&rsquo;elle a eu lorsqu&rsquo;elle \u00e9tait secr\u00e9taire d&rsquo;&Eacute;tat (elle avait \u00e9t\u00e9 oblig\u00e9e de porter des lunettes pendant un certain temps, \u00e0 la suite de cet accident affectant le syst\u00e8me nerveux et la r\u00e9gion c\u00e9r\u00e9brale). L\u00e0 encore, le destin la poursuit d&rsquo;un acharnement qu&rsquo;il justifie par la fa\u00e7on dont elle a pr\u00e9tendue se jouer de lui tout au long de sa carri\u00e8re ; l&rsquo;on dira alors que toutes ces malversations et ces fatalit\u00e9s s&rsquo;additionnent pour nous restituer la figure d&rsquo;un personnage irr\u00e9m\u00e9diablement compromis, d\u00e9sormais pris dans l&rsquo;\u00e9tau et le filet de ses briganderies et de ses faiblesses, et qui, \u00e0 chaque occasion, aggrave son cas. <strong><em>The Lady <\/em>devient ainsi, en paraissant de plus en plus \u00eatre une <em>Tramp<\/em>, le Trump caricatural qu&rsquo;elle d\u00e9non\u00e7ait, c&rsquo;est-\u00e0-dire une <em>Trump <\/em>sans aucun des avantages dont le candidat r\u00e9publicain a su profiter.<\/strong><\/p>\n<\/p>\n<p><p>Je trouve l\u00e0-dessus qu&rsquo;il y a un enseignement important, ou plut\u00f4t un double enseignement qui est d&rsquo;une r\u00e9elle importance. On en a d\u00e9j\u00e0 vu des occurrences pr\u00e9c\u00e9demment, mais ce cas est fameux par sa nettet\u00e9 et son tranchant, et d&rsquo;autant plus important qu&rsquo;il caract\u00e9rise l&rsquo;\u00e9v\u00e9nement de loin le plus important parmi ceux qui sont programm\u00e9s pour cette deuxi\u00e8me partie de la riche ann\u00e9e 2016. D&rsquo;une part, il n&rsquo;y a dans l&rsquo;encha&icirc;nement des deux crises (<em>emailgate<\/em> et \u00ab\u00a0guerre raciale) aucun effet de supplantation mais un m\u00e9canisme d&rsquo;addition entra&icirc;nant une multiplication des effets. La fusillade de Dallas, le soir de l&rsquo;audition de Comey au Congr\u00e8s n&rsquo;a pas enterr\u00e9 l&rsquo;effet du premier \u00e9v\u00e9nement chronologique, <strong>il l&rsquo;a poursuivi sous une autre forme somme toute, \u00e0 cause de la prise de position de Clinton, <em>the Lady <\/em>se jetant ainsi dans la gueule du loup<\/strong>&#8230; (N&rsquo;a-t-elle donc pas de conseillers pour l&rsquo;avertir de tels effets f\u00e2cheux, et notamment que si l&rsquo;on soutient en sous-main  de tels mouvements de s\u00e9dition, m\u00eame vertueux et se pr\u00e9tendant <em>soft<\/em>, il s&rsquo;agit officiellement d&rsquo;en d\u00e9noncer au moins les effets de d\u00e9sordre ? Je crains que les conseillers de <em>The Lady<\/em> soit tous, surtout ceux du genre f\u00e9minin, du genre <em>Tramp<\/em> qui se prend pour Trump, c&rsquo;est-\u00e0-dire du registre hyst\u00e9rique de<a href=\"http:\/\/www.dedefensa.org\/article\/deluge-biblique-et-affectivisme-postmoderne\"> l&rsquo;affectivisme<\/a>.) Pour r\u00e9sumer ce point et mettre en \u00e9vidence tout son int\u00e9r\u00eat, une crise ne chasse pas l&rsquo;autre, au contraire elle la poursuit, la compl\u00e8te, la renforce, et la m\u00eame personne, &ndash; <em>The Lady<\/em>, &ndash; se trouve charg\u00e9e de responsabilit\u00e9s aggrav\u00e9es et amplifi\u00e9es dans les divers sens qu&rsquo;activent ces crises : c&rsquo;est le premier enseignement.<\/p>\n<\/p>\n<p><p>Le second est <strong>l&rsquo;inversion parfaite des r\u00f4les qui confirme la crise profonde du Syst\u00e8me, qui ne sait plus produire sa surpuissance que pour fabriquer de l&rsquo;autodestruction<\/strong>. C&rsquo;est la repr\u00e9sentante du Syst\u00e8me qui se trouve au milieu des agitations, \u00e0 la fois de la corruption et de d\u00e9sordre, alors que le Syst\u00e8me pr\u00e9tend afficher les vertus contraires, combattre la corruption avec un succ\u00e8s \u00e9clatant et contenir le d\u00e9sordre pour mieux nous m\u00e9nager ses lendemains-\u00e0-lui qui chantent. Le plus remarquable est bien qu&rsquo;elle reste repr\u00e9sentante du Syst\u00e8me pendant qu&rsquo;elle accumule les catastrophes, chargeant le Syst\u00e8me de cette m\u00eame infamie, qu&rsquo;on n&rsquo;ose pas trop lui retirer cette \u00ab\u00a0qualit\u00e9\u00a0\u00bb, et d&rsquo;ailleurs qu&rsquo;il n&rsquo;y a pas d&rsquo;alternative, de \u00ab\u00a0plan B\u00a0\u00bb comme ils disent&#8230; Pendant ce temps, le repr\u00e9sentant auto-institu\u00e9 de l&rsquo;antiSyst\u00e8me n&rsquo;a qu&rsquo;\u00e0 laisser faire pour \u00eatre par\u00e9 des vertus en question, par simple effet antagoniste, <strong>et donner ainsi \u00e0 l&rsquo;antiSyst\u00e8me des lettres de noblesse qui lui permette d&rsquo;affirmer \u00e0 la fois sa n\u00e9cessit\u00e9 et sa l\u00e9gitimit\u00e9<\/strong>. Effectivement, Donald J. Trump s&rsquo;affirme plus que jamais du camp de l&rsquo;antiSyst\u00e8me et cela lui est de moins en moins reproch\u00e9.<\/p>\n<\/p>\n<p><p>Finalement et tous comptes faits &#8230; <em>That&rsquo;s why, that&rsquo;s why the Lady is <strong>NOT<\/strong> a Trump.<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Lady Is A Trump 12 juillet 2016 &ndash; Il suffit de changer une lettre et le standard \u00e0 la signification ambigu\u00eb de 1937 (voyez The Lady Is A Tramp interpr\u00e9t\u00e9 par Lady Gaga et le vieux Tony Bennett, Lady Gaga grande chanteuse presque jazzy), ce standard devient une fable ironique sur un destin qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[831,4646,17431,934,7258,17320,3278,9286,15600,6618,3050,17626,2639],"class_list":["post-76665","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-a","tag-antisysteme","tag-blm","tag-clinton","tag-donald","tag-emailgate","tag-hillary","tag-is","tag-lady","tag-legitimation","tag-the","tag-tramp","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76665"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76665\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}