{"id":76697,"date":"2016-07-31T17:16:44","date_gmt":"2016-07-31T17:16:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/31\/incirlik-en-vedette-americaine-encerclee-otage-chantage\/"},"modified":"2016-07-31T17:16:44","modified_gmt":"2016-07-31T17:16:44","slug":"incirlik-en-vedette-americaine-encerclee-otage-chantage","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/07\/31\/incirlik-en-vedette-americaine-encerclee-otage-chantage\/","title":{"rendered":"Incirlik en vedette am\u00e9ricaine\u00a0: encercl\u00e9e, otage, chantage&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Incirlik en vedette am\u00e9ricaine : encercl\u00e9e, otage, chantage&#8230;<\/h2>\n<\/p>\n<p><p>D\u00e9cid\u00e9ment, la base US, OTAN &#038; Cie, en territoire turc, d&rsquo;Incirlik est \u00e0 la fois l&rsquo;enjeu et la barom\u00e8tre des \u00e9v\u00e9nements de Turquie et de tout ce qui les entoure. Depuis hier et ce matin, la base est \u00e0 nouveau coup\u00e9e du reste de la Turquie, encercl\u00e9e, et elle redevient \u00e0 nouveau l&rsquo;objet de menaces et d&rsquo;anath\u00e8mes. Divers th\u00e8mes sont agit\u00e9s, autour de le singuli\u00e8re situation selon laquelle Incirlik serait une sorte d'\u00a0\u00bbotage\u00a0\u00bb que la direction turque, Erdogan en t\u00eate, reprendrait r\u00e9guli\u00e8rement sous sa surveillance agressive. Les deux th\u00e8mes principaux pr\u00e9sent\u00e9s pour de tels mouvements sont 1) Incirlink comme moyen de pression sur les USA pour obtenir l&rsquo;extradition de G\u00fclen, l&rsquo;ennemi \u00e0 la fois d\u00e9sign\u00e9 et jur\u00e9 d&rsquo;Erdogan ; et 2) Incirlink encercl\u00e9e pour pr\u00e9venir une deuxi\u00e8me tentative de putsch qui est un des grands sujets de conversation m\u00e9diatiques et dans les presse alternative\/antiSyst\u00e8me en g\u00e9n\u00e9ral, depuis hier \u00e9galement.<\/p>\n<\/p>\n<p><p>On va reprendre ici ce qu&rsquo;en dit <em>ZeroHegde.com<\/em>, en se cantonnant \u00e0 la partie concernant Incirlink. En effet, <em>ZeroHedge.com<\/em> reprend toute l&rsquo;affaire du putsch avort\u00e9, y ajoutant l&rsquo;affaire des d\u00e9clarations <a href=\"http:\/\/www.dedefensa.org\/article\/centcom-ils-ont-gaulemes-sonovobitches\">Vogel-Clapper \u00e0 Aspen<\/a>. L&rsquo;ensemble <em>ZeroHedge.com<\/em> est \u00e9galement int\u00e9ressant \u00e0 lire parce que ce site, qui est une des grandes bases de lecture dans la presse alternative et antiSyst\u00e8me, avait pris une position absolument hostile \u00e0 Erdogan, estimant que le putsch \u00e9tait un coup mont\u00e9 (<em>falseflag<\/em> pour les intimes) par Erdogan, pour lui permettre de passer du rang d&rsquo;&Eacute;mir \u00e0 celui d&rsquo;&Eacute;mir-dictateur avec tous les pouvoirs. On peut observer qu&rsquo;en fonction des derni\u00e8res nouvelles o&ugrave; il devient extr\u00eamement difficile de ne pas distinguer diverses traces et coups de patte de la communaut\u00e9 de s\u00e9curit\u00e9 nationale US et de ses diverse r\u00e9seaux d&rsquo;influence, <em>ZeroHedge.com<\/em> nuance implicitement sa position. (Texte <a href=\"http:\/\/www.zerohedge.com\/news\/2016-07-30\/turkey-surrounds-blocks-access-natos-incirlik-airbase-amid-speculation-second-coup\">du 31 juillet<\/a>.)<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>Which brings us to today, and the news that NATO&rsquo;s critical Incirlik Air Base was hours ago completely blocked off by Turkey, with all inputs and outputs to the Adana base having been closed according to Turkey&rsquo;s Hurriyet among rumors of yet <a href=\"http:\/\/www.hurriyet.com.tr\/incirlik-ussune-giris-cikislar-yasaklandi-40176636\">another coup<\/a>. As the Turkish Minister for European Affairs, Omar Celik, tweeted moments ago, this is just a routine \u00ab\u00a0safety inspection\u00a0\u00bb, although it has not stopped local papers from speculating that a a second Gulen-inspired coup attempt may be underway. Hurriyet has raised concern that the closing may be tied to an attempt by the Erdogan regime to prevent a second coup attempt.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> Some 7,000 armed police with heavy vehicles have surrounded and blocked the Incirlik air base in Adana used by NATO forces, already restricted in the aftermath of a failed coup. Unconfirmed reports say troops were sent to deal with a new coup attempt. Hurriyet reported earlier that Adana police had been tipped off about a new coup attempt, and forces were immediately alerted. The entrance to the base was closed off.  Security forces armed with rifles and armored TOMA vehicles used by Turkish riot police could be seen at the site in photos taken by witnesses. Indeed, the massive presence of armed police supported by heavy vehicles calls into question the Turkish government&rsquo;s official line that the lock down at the Incirlik base is merely a \u00ab\u00a0safety inspection.\u00a0\u00bb?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Local media has focused on the base after the failed coup in Turkey occurred the night of July 15. Although the main scenes of the events were Istanbul and Ankara, Incirlik was shut down  for a time by local authorities shortly after the putsch, and several Turkish soldiers from the base were deemed by Turkish officials to be involved in the overthrow attempt. The lockdown at Incirlik follows a massive wave of protests on Thursday when pro-Erdogan nationalists took to the streets yelling \u00ab\u00a0death to the US\u00a0\u00bb and called for the immediate closure of the Incirlik base. Security personnel dispersed the protesters before they were able to make it to the base. And while there has been no official statement from US armed forces stationed at Incirlik at this time, the situation continues to develop in front of the air bBase as more heavy trucks have been dispatched to surround and block access to the critical military facility.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>It is unclear if Erdogan is naive enough to think that he can out-bluff and out-bully the US and keep Incirlik hostage until he gets Gulen repatriated by Obama on a silver platter, a hostage \u00ab\u00a0tit for tat\u00a0\u00bb we first described two weeks ago. If so, one wonders, if he is doing so alone, or with the moral support of others, perhaps such recently prominent enemies of Erdogan as Vladimir Putin. Recall that just over a month ago [29]Erdogan publicly apologized to Putin for downing the Russian Su-24 fighter jet in November, and called Putin \u00ab\u00a0a friend.\u00a0\u00bb Finally, at least as of this moment, it appears that theairspace around Incirlik is closed<\/em>.<\/p>\n<\/p>\n<p><p>A quel jeu joue-t-on avec Incirlink ?<strong> <a href=\"https:\/\/en.wikipedia.org\/wiki\/Incirlik_Air_Base\">Cette base<\/a> occupe \u00e9videmment une position strat\u00e9gique exceptionnelle<\/strong> ; toute proche de la Syrie, mais aussi du Liban et d&rsquo;Isra\u00ebl, \u00e0 bonne port\u00e9e de l&rsquo;Iran et de l&rsquo;Afghanistan, et \u00e0 port\u00e9e acceptable de la Russie et des routes suivies par les avions russes, elle abrite aussi bien des forces de combat (US\/OTAN) que des forces d&rsquo;appui strat\u00e9gique, logistique (ravitailleurs en vol) et de reconnaissance\/renseignement. Les USA en ont fait leur plaque strat\u00e9gique tournante de la r\u00e9gion et l&rsquo;une des principales bases de CENTCOM autant que la connexion directe entre l&rsquo;OTAN et les r\u00e9gions du Moyen-Orient et du sous-continent indien. D&rsquo;autre part, Incirlink est fameuse pour abriter un contingent d&rsquo;armes nucl\u00e9aires US (bombes B-61, entre 36 et une centaine selon les \u00e9valuations). <strong>Incirlink fait partie des plus grandes bases strat\u00e9giques US dans l&rsquo;\u00e9norme r\u00e9seau de bases du Pentagone<\/strong>, dans la cat\u00e9gorie des bases de Ramstein, Okinawa, Guam, etc.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il semble bien qu&rsquo;Erdogan, d&rsquo;ailleurs avec les conseils appuy\u00e9s des Russes supposerions-nous sans audace excessive, ait bien mesur\u00e9 de quel poids strat\u00e9gique \u00e9norme Incirlink p\u00e8se dans la besace de l&rsquo;occupation strat\u00e9gique et des r\u00e9seaux US, et quel r\u00f4le peu ordinaire ce point strat\u00e9gique peut jouer dans un jeu d&rsquo;affrontement et d&rsquo;antagonisme de communication avec les USA et avec l&rsquo;OTAN. Il est assez probable que les cris d&rsquo;alarme et autres avertissements venus <a href=\"http:\/\/www.dedefensa.org\/article\/centcom-ils-ont-gaulemes-sonovobitches\">de Aspen, Colorado<\/a>, ces trois derniers jours, aient encore fortement accru cette perception d&rsquo;Erdogan. <strong>Plusieurs chefs US n&rsquo;ont pas cach\u00e9 qu&rsquo;ils \u00e9taient tr\u00e8s inquiets de la situation en Turquie, de la situation de leur influence en Turquie, et par cons\u00e9quent du sort d&rsquo;Incirlink, montrant par l\u00e0 une position de faiblesse qui doit enchanter Erdogan<\/strong>. La pol\u00e9mique touche bien entendu, mais tout de m\u00eame avec une rapidit\u00e9 qui en dit long, la rivalit\u00e9 interarmes : l&rsquo;US Navy lance ses relais selon la logique que la situation d&rsquo;Incirlik montre l&rsquo;avantage des porte-avions navigant en eaux internationales sur les bases terrestres qui ne sont jamais \u00e0 l&rsquo;abri d&rsquo;un pouvoir local soudain devenu incontr\u00f4lable (voir les d\u00e9clarations du vice-amiral d&rsquo;escadre retir\u00e9 de l&rsquo;US Navy, Peter Daly, <a href=\"http:\/\/sputniknews.com\/military\/20160728\/1043696591\/incirlik-justify-usa-carrier-spending.html\">le 28 juillet<\/a>, \u00e0 <em>Sputnik.News<\/em>).<\/p>\n<\/p>\n<p><p>Il semble bien qu&rsquo;on voit se dessiner <strong>une situation nouvelle du point de vue des affrontements postmodernes de communication<\/strong>, par rapport \u00e0 un point strat\u00e9gique de cette importance devenant un enjeu de pression et de contrainte dans une situation de grande tension. (Par exemple, si l&rsquo;on admet qu&rsquo;il existe la possibilit\u00e9 d&rsquo;un second coup de force, ou si Erdogan croit qu&rsquo;il peut y en avoir la possibilit\u00e9, les man&oelig;uvres autour d&rsquo;Incirlik [successivement ou simultan\u00e9ment fermeture des fournitures d&rsquo;\u00e9lectricit\u00e9 et d&rsquo;autres fournitures de base, enqu\u00eate \u00e0 l&rsquo;int\u00e9rieur de la base et arrestation d&rsquo;officiers turcs stationn\u00e9s sur la partie turque de la base, encerclement et interdiction d&rsquo;acc\u00e8s, etc.] deviennent une tactique, voire un moyen de chantage du type \u00ab\u00a0s&rsquo;il y a r\u00e9ellement amorce d&rsquo;un nouveau coup de force, j&rsquo;interviens sur la base\u00a0\u00bb, ou entre les tractations avec le sort de G\u00fclen.) Ainsi l&rsquo;atout strat\u00e9gique consid\u00e9rable que constitue pour les USA une base de cette importance <strong>devient brutalement un handicap qui compromet gravement les capacit\u00e9s de leur diplomatie, aussi bien ouverte que secr\u00e8te, en m\u00eame temps qu&rsquo;un r\u00e9v\u00e9lateur embarrassant des activit\u00e9s US, ouvertes ou secr\u00e8tes<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Encore n&rsquo;a-t-on pas parl\u00e9 de l&rsquo;aspect otanien, qui joue un r\u00f4le tr\u00e8s important. Depuis le 15 juillet, dans tous les cas en mati\u00e8re de communication, l&rsquo;OTAN est paralys\u00e9e dans cette situation o&ugrave; deux de ses principaux membres sont en situation d&rsquo;affrontement si direct. Ses relations publiques sont dans le plus grand embarras et ne donnent plus gu\u00e8re d&rsquo;indications, dans une occurrence qui peut s&rsquo;av\u00e9rer comme catastrophique \u00e0 un moment o&ugrave; la coh\u00e9sion de l&rsquo;Alliance est extr\u00eamement fragile \u00e0 cause des pressions antirusses forcen\u00e9es de certains membres, et du freinage de plus en plus net contre cette tendance de la part d&rsquo;autres membres. Justement, la crise d&rsquo;Incirlik (Turquie-USA) se fait sur le fond d&rsquo;un rapprochement de la Turquie et de la Russie, \u00e0 un moment o&ugrave; la politique g\u00e9n\u00e9rale US est dans une phase de compl\u00e8te incertitude, sinon de paralysie et d&rsquo;impuissance, avec la fin du mandat Obama et les pr\u00e9sidentielles en cours, dont le r\u00e9sultat sera extr\u00eamement important pour l&rsquo;orientation de la politique ext\u00e9rieure des USA. Dans ces conditions, on peut envisager les remarques de ceux qui n&rsquo;excluent pas qu&rsquo;une aggravation continue de la crise conduise <strong>\u00e0 un retrait de la Turquie de l&rsquo;OTAN, et par cons\u00e9quent \u00e0 la plus grave crise de l&rsquo;OTAN de toute son histoire, &ndash; bien plus grave que la crise fran\u00e7aise de 1964-1966<\/strong> (retrait de la France du commandement int\u00e9gr\u00e9), parce qu&rsquo;\u00e0 le reprise compl\u00e8te de sa souverainet\u00e9 par la Turquie (cas similaire \u00e0 la France), s&rsquo;ajouterait un renversement d&rsquo;alliance (avec la Russie), absent du cas fran\u00e7ais.<\/p>\n<\/p>\n<p><p>Le cas-Incirlik nous ouvre de nouvelles et amusantes perspectives : <strong>comment un formidable avantage strat\u00e9gique peut devenir un embarras et m\u00eame un lien strat\u00e9gique dont le d\u00e9nouement peut conduire \u00e0 une catastrophe mena\u00e7ant tout un \u00e9difice<\/strong>. Mais l&rsquo;on comprend la cause centrale de cette situation, qui se trouve dans l&rsquo;effondrement de la puissance US, et la cause technique de cette situation, qui est l&rsquo;importance consid\u00e9rable prise par la communication. On ne se trouve pas loin d&rsquo;un cas de rupture entre les USA et la Turquie, et d&rsquo;une menace de dislocation de l&rsquo;OTAN, tout cela d&rsquo;une fa\u00e7on \u00e9ventuellement tr\u00e8s rapide, selon un processus dont l&rsquo;aggravation a \u00e9t\u00e9 d&rsquo;abord le fait de processus de communication, que les acteurs les aient voulus ou pas.<\/p>\n<\/p>\n<p><p>Mis en ligne le 31 juillet 2016 \u00e0 17H16<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incirlik en vedette am\u00e9ricaine : encercl\u00e9e, otage, chantage&#8230; D\u00e9cid\u00e9ment, la base US, OTAN &#038; Cie, en territoire turc, d&rsquo;Incirlik est \u00e0 la fois l&rsquo;enjeu et la barom\u00e8tre des \u00e9v\u00e9nements de Turquie et de tout ce qui les entoure. Depuis hier et ce matin, la base est \u00e0 nouveau coup\u00e9e du reste de la Turquie, encercl\u00e9e,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5518,7059,3015,3737,584,2730,3068,2613],"class_list":["post-76697","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-base","tag-centcom","tag-communication","tag-erdogan","tag-otan","tag-russie","tag-strategique","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76697"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76697\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}