{"id":76701,"date":"2016-08-02T10:26:53","date_gmt":"2016-08-02T10:26:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/02\/la-nsa-est-elle-antisysteme\/"},"modified":"2016-08-02T10:26:53","modified_gmt":"2016-08-02T10:26:53","slug":"la-nsa-est-elle-antisysteme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/02\/la-nsa-est-elle-antisysteme\/","title":{"rendered":"La NSA est-elle antiSyst\u00e8me\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La NSA est-elle antiSyst\u00e8me ?<\/h2>\n<\/p>\n<p><p>On n&rsquo;arr\u00eate pas un train type-TGV lanc\u00e9 \u00e0 grande vitesse. La <em>narrative<\/em> lanc\u00e9e par les d\u00e9mocrates concernant les fuites <em>WikiLeaks<\/em> sur <a href=\"http:\/\/www.dedefensa.org\/article\/sous-le-regard-et-la-poigne-impitoyables-de-lantisysteme\">les <em>e-mails<\/em> de la DNC<\/a> (<em>Democratic National Committee<\/em>) qui avaient aussit\u00f4t provoqu\u00e9 la d\u00e9mission de la pr\u00e9sidente du DNC, Debbie Wasserman-Schlutz, cette <em>narrative<\/em> est fix\u00e9e et ne bougera plus. La presse-Syst\u00e8me a r\u00e9agi comme si elle n&rsquo;\u00e9tait qu&rsquo;une, montrant ainsi la puissance extraordinaire de l&rsquo;influence du Syst\u00e8me, agissant nullement par consigne ni machination complexe mais par une formidable pression psychologique dont l&rsquo;origine de conception et de manufacture d\u00e9passe manifestement toute entreprise humaine. Cela correspond effectivement \u00e0 l&rsquo;appr\u00e9ciation que le Syst\u00e8me est une \u00e9gr\u00e9gore, et l&rsquo;une de ses lignes d&rsquo;action de communication, notamment pour faire \u00e9lire sa candidate contre l&rsquo;antiSyst\u00e8me Trump, est l&rsquo;implication fautive et comploteuse de la Russie par tous les moyens ; cette conception entre \u00e9videmment dans la ligne russophobe qui structure la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-la-politique-systeme\">politique-Syst\u00e8me<\/a> o&ugrave; elle se trouve actuellement, poussant dans sa logique jusqu&rsquo;\u00e0 l&rsquo;affrontement avec la Russie si un obstacle antiSyst\u00e8me ne fait pas sortir le TGV de ses rails.<\/p>\n<\/p>\n<p><p>La <em>narrative<\/em> est donc grav\u00e9e dans le marbre d\u00e9sormais : c&rsquo;est la Russie qui a fourni sa cargaison d&rsquo;e-mails \u00e0 <em>WikiLeaks<\/em>, Trump est devenu une sorte de <em><a href=\"http:\/\/www.dedefensa.org\/article\/le-manchurian-president-ou-la-dissolution\">Manchurian Candidate<\/a><\/em> des Russes, et le <em>carpet bombing<\/em> de la communication-Syst\u00e8me est donc dirig\u00e9 contre le faux-messager (technique du \u00ab\u00a0<em>shot the messenger<\/em>\u00a0\u00bb devenue \u00ab\u00a0<em>shot the fake-messenger<\/em>\u00ab\u00a0). Le contenu du message, qui est l&rsquo;archi-corruption du DNC et le complot \u00e0 ciel ouvert contre Sanders n&rsquo;int\u00e9resse plus personne ; d&rsquo;ailleurs, la victime la premi\u00e8re, puisque \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/ode-attristee-a-bernie-tsipras\">Bernie Tsipras<\/a>\u00a0\u00bb est rentr\u00e9 vite fait et fort glorieusement dans les rangs et engage ses troupes \u00e0 voter pour Clinton, \u00ab\u00a0la candidate du progr\u00e8s, de l&rsquo;honn\u00eatet\u00e9 et de la d\u00e9mocratie r\u00e9unis\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Affaire class\u00e9e, et passons \u00e0 la suivante&#8230; Celle-ci, bien qu&rsquo;ayant tous les rapports du monde avec la pr\u00e9c\u00e9dente, <strong>n&rsquo;a aucune chance de susciter le moindre int\u00e9r\u00eats de la presse-Syst\u00e8me, mais c&rsquo;est moins sa publicit\u00e9 que sa v\u00e9racit\u00e9, et ce qu&rsquo;elle pourrait raisonnablement laisser pr\u00e9voir par cons\u00e9quent, qui nous int\u00e9ressent<\/strong>. Il s&rsquo;agit des r\u00e9v\u00e9lations d&rsquo;un \u00ab\u00a0lanceur d&rsquo;alerte\u00a0\u00bb chevronn\u00e9, un officier de la NSA durant trente ans, qui a quitt\u00e9 l&rsquo;agence en 2001, et qui s&rsquo;est r\u00e9v\u00e9l\u00e9 \u00e0 l&rsquo;occasion de la crise Snowden comme une source annexe et discr\u00e8te, comme le meilleur commentateur de cette affaire et des activit\u00e9s de la NSA. Il s&rsquo;agit de William Binney, qui a \u00e9t\u00e9 interview\u00e9 par une radio de New York, lors d&rsquo;une \u00e9mission tr\u00e8s appr\u00e9ci\u00e9e (\u00ab\u00a0<em>Aaron Klein Investigative Radio<\/em>\u00ab\u00a0) et a affirm\u00e9 que les fuites qui ont aliment\u00e9 <em>WikiLeaks<\/em> dans l&rsquo;affaire de la DNC venaient de la NSA et nullement des Russes. L&rsquo;affaire a \u00e9t\u00e9 reprise par <em><a href=\"http:\/\/www.breitbart.com\/jerusalem\/2016\/07\/31\/exclusive-nsa-architect-agency-clintons-deleted-emails\/\">Breitbart.com<\/a><\/em> et par <em><a href=\"http:\/\/www.zerohedge.com\/news\/2016-07-31\/whistleblowers-stunning-claim-nsa-has-all-hillarys-deleted-emails-it-may-be-leak\">ZeroHedge.com<\/a><\/em> les 31 juillet et 1<sup>er<\/sup> ao&ucirc;t, mais d&rsquo;abord par <em>Breitbart.com<\/em>, et sous la plume d&rsquo;Aaron Klein lui-m\u00eame, \u00e0 partir de J\u00e9rusalem d&rsquo;o&ugrave; il op\u00e8re \u00e9galement comme correspondant de ce m\u00eame <em>Breitbart.com<\/em>.<\/p>\n<\/p>\n<p><p>(Ce dernier point, &ndash; Aaron Klein, qui a sorti l&rsquo;affaire Binney, travaillant notamment \u00e0 J\u00e9rusalem, qu&rsquo;on peut supposer proche des Isra\u00e9liens d&rsquo;autant qu&rsquo;il est \u00e9videmment juif, &ndash; est extr\u00eamement int\u00e9ressant parce qu&rsquo;il semble confirmer que, dans les \u00e9lections US, Isra\u00ebl joue un r\u00f4le tr\u00e8s sp\u00e9cifique et remarquable par divers relais indirects possibles mais bien d\u00e9coupl\u00e9s des sources officielles pour ne pas \u00eatre mis en cause officiellement. Ce r\u00f4le semble bien \u00eatre, pour des raisons restant \u00e0 d\u00e9terminer mais \u00e0 propos desquelles on peut conjecturer, de contrer les <em>narrative<\/em> du camp d\u00e9mocrate et de la candidate Clinton, singuli\u00e8rement antirusses. En plus de cette intervention Aaron Klein\/Binney\/<em>Breitbart.com<\/em> qui va dans ce sens, on doit rappeler que <em>DEBKAFiles<\/em>, proche des services de s\u00e9curit\u00e9 nationale isra\u00e9liens, a publi\u00e9 le 26 juillet [voir <a href=\"http:\/\/www.dedefensa.org\/article\/debkafiles-defend-les-russes-contre-clinton\">le 27 juillet<\/a> sur ce site] une nouvelle affirmant que les Russes ne sont pour rien dans l&rsquo;affaire <em>WikiLeaks<\/em>\/DNC. L&rsquo;intervention de Klein, avec Binney comme source beaucoup plus marquante, renforce l&rsquo;interpr\u00e9tation d&rsquo;une tendance isra\u00e9lienne, <strong>qui serait \u00e9ventuellement plus encore de soutenir les Russes que Trump, mais ceci aboutissant tout de m\u00eame \u00e0 cela par les logiques convergentes des engagements<\/strong>. L&rsquo;orientation correspondrait bien \u00e0 l&rsquo;hypoth\u00e8se d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-notre-sympathy-for-the-devil\">nouvelle orientation<\/a> g\u00e9n\u00e9rale isra\u00e9lienne.) <\/p>\n<\/p>\n<p><p>Nous citons Alex Christoforou, le <a href=\"http:\/\/theduran.com\/nsa-whistleblower-says-dnc-hack-not-done-russia-u-s-intelligence\/\">1<sup>er<\/sup> ao&ucirc;t<\/a> 2016 sur le site <em>TheDuran.com<\/em> (site antiSyst\u00e8me bien structur\u00e9 et aliment\u00e9, de la fili\u00e8re <em>Russia Insider<\/em>, qui est bas\u00e9 \u00e0 Chypre). Le texte reprend toute l&rsquo;affaire, avec une synth\u00e8se courte restituant les principaux \u00e9l\u00e9ments d&rsquo;une affaire qui est plus complexe que la seule affirmation de Binney sur le cas <em>WikiLeaks<\/em>\/DNC. (Depuis l&rsquo;affaire Snowden, Binney est consid\u00e9r\u00e9 comme une source extr\u00eamement fiable alors qu&rsquo;il avait lui-m\u00eame d\u00e9crit d\u00e8s 2012 l&rsquo;\u00e9tat d&rsquo;avancement de la structure totalitaire de la NSA : &laquo; <em><a href=\"http:\/\/www.zerohedge.com\/news\/2016-07-31\/whistleblowers-stunning-claim-nsa-has-all-hillarys-deleted-emails-it-may-be-leak\">Zerohedge has some background on Binney<\/a>, who is about as rock solid a security analyst as you could get<\/em>. [&#8230;] <em>Not surprisingly, Binney received little attention in 2012 &ndash; his suggestions at the time were seen as preposterous and ridiculously conspiratorial. Only after the fact <\/em>[Snowden]<em>, did it become obvious that he was right. More importantly, in the aftermath of the Snowden revelations, <strong>what Binney has to say has become gospel<\/strong><\/em><strong>. &raquo;)<\/strong><\/p>\n<\/p>\n<p><p>Voici donc r\u00e9sum\u00e9e cette affaire avec l&rsquo;entr\u00e9e en sc\u00e8ne de Binney :<\/p>\n<\/p>\n<p><p>&laquo; <em>On <a href=\"http:\/\/www.breitbart.com\/jerusalem\/2016\/07\/31\/exclusive-nsa-architect-agency-clintons-deleted-emails\/\">Aaron Klein&rsquo;s Sunday radio program<\/a>, \u00ab\u00a0Aaron Klein Investigative Radio\u00a0\u00bb (broadcast on New York&rsquo;s AM 970 The Answer and Philadelphia&rsquo;s NewsTalk 990 AM), US government whistleblower William Binney threw his hat into the DNC hack ring by stating that the Democratic National Committee&rsquo;s server was not hacked by Russia but<strong> by a disgruntled U.S. intelligence worker. <\/strong>The motivation of the hacker&hellip;concern over Hillary Clinton&rsquo;s disregard of national security secrets when she used a personal email and consistently lied about it. Binney was just getting started with revelations we are sure no main stream media news site will dare to cover. The \u00ab\u00a0Putin did it\u00a0\u00bb fairytale is just to easy for the sheep to follow.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Binney also proclaimed that the NSA has all of Clinton&rsquo;s deleted emails, and the FBI could gain access to them if they so wished.  <strong>No need for Trump to ask the Russians for those emails, he can just call on the FBI or NSA to hand them over.<\/strong><\/em> &raquo;<\/p>\n<\/p>\n<p><p>Binney estime que la NSA (et le FBI par ailleurs) dispose de toute la correspondance, \u00e0 la fois d&rsquo;Hillary Clinton et du DNC (le parti d\u00e9mocrate). Ce n&rsquo;est certainement pas une surprise mais c&rsquo;est une indication pr\u00e9cieuse au regard de la conviction que Binney affiche que l&rsquo;affaire <em>WikiLeaks<\/em>\/DNC est venue de la NSA et de personne d&rsquo;autre, et notamment, certainement pas les Russes. Toutes ces pr\u00e9cisions sont int\u00e9ressantes \u00e0 une autre lumi\u00e8re, que r\u00e9sume la question : qui, \u00e0 la NSA, a fuit\u00e9 ? est-ce un nouveau \u00ab\u00a0lanceur d&rsquo;alerte\u00a0\u00bb ou est-ce une op\u00e9ration plus ou moins indirectement \u00ab\u00a0autoris\u00e9e\u00a0\u00bb par la NSA elle-m\u00eame ? En effet, l&rsquo;on doit \u00e0 cet \u00e9gard se reporter \u00e0 un article de <em>The Observer<\/em>, <a href=\"http:\/\/observer.com\/2016\/03\/hillary-has-an-nsa-problem\/\">de mars 2016<\/a>, titr\u00e9 : &laquo; <em>Hillary has an NSA problem<\/em>. &raquo; Probl\u00e8me assez simple, au demeurant, et effroyablement grave du point de vue de l&rsquo;agence dont on conna&icirc;t l&rsquo;obsession pour le secret et tout ce qui va avec : les pratiques de Clinton ont mis en grave danger l&rsquo;enti\u00e8ret\u00e9 de a proc\u00e9dure dite-<em>Gamma<\/em>, qui est le programme de protection des mat\u00e9riels ultra-ultra-ultra-secrets de la NSA&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Binney surmised that the hack of the DNC could have been coordinated by someone inside the U.S. intelligence community angry over Clinton&rsquo;s compromise of national security data with her email use<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>And the other point is that Hillary, according to an <a href=\"http:\/\/observer.com\/2016\/03\/hillary-has-an-nsa-problem\/\">article<\/a> published by the Observer in March of this year, has a problem with NSA because she compromised Gamma material.  Now that is the most sensitive material at NSA. And so there were a number of NSA officials complaining to the press or to the people who wrote the article that she did that. She lifted the material that was in her emails directly out of Gamma reporting. That is a direct compromise of the most sensitive material at the NSA. So she&rsquo;s got a real problem there. So there are many people who have problems with what she has done in the past. So I don&rsquo;t necessarily look at the Russians as the only one(s) who got into those emails<\/em>.<\/p>\n<\/p>\n<p><p><strong>&raquo; <em>The Observer defined the GAMMA classification:<\/em><\/strong><em> \u00ab\u00a0GAMMA compartment, which is an NSA handling caveat that is applied to extraordinarily sensitive information (for instance, decrypted conversations between top foreign leadership, as this was)\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi est-on conduit \u00e0 comprendre la gravit\u00e9 du probl\u00e8me : qui est donc ce \u00ab\u00a0<em>someone inside the U.S. intelligence community angry over Clinton&rsquo;s compromise of national security data with her email use<\/em>\u00a0\u00bb ? On est l\u00e0 dans l&rsquo;anti-Snowden (et dans l&rsquo;anti-Binney en un sens) et la pi\u00e8ce qui se joue serait plut\u00f4t \u00ab\u00a0les hy\u00e8nes se d\u00e9vorent entre elles\u00a0\u00bb, &ndash; nous voulons dire \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me. La but de la d\u00e9marche de ceux qui ont l\u00e2ch\u00e9 la cargaison <em>WikiLeaks<\/em>\/DNC n&rsquo;est pas du tout, mais alors pas du tout de torpiller la NSA et de la clouer au pilori, &ndash; comme un Snowden ou comme un Binney \u00e9ventuellement, &ndash; <strong>mais bien au contraire de d\u00e9fendre la NSA contre des hy\u00e8nes irresponsables-hyst\u00e9riques type-Clinton, qui disposent du mat\u00e9riel ultra-secret dont elles se jugent redevables comme de leur premier tube de rouge \u00e0 l\u00e8vres<\/strong>. Cela conduit donc \u00e0 s&rsquo;interroger et de conjecturer sur le fait de savoir si l&rsquo;op\u00e9ration est le fait d&rsquo;un \u00ab\u00a0loup solitaire\u00a0\u00bb \u00e0 l&rsquo;int\u00e9rieur de la NSA, ou bien de la NSA elle-m\u00eame montant une classique op\u00e9ration de \u00ab\u00a0fuites\u00a0\u00bb destin\u00e9es \u00e0 attaquer une personnalit\u00e9 terriblement g\u00eanante pour elle&#8230; Poser la question dans le sens hypoth\u00e9tique qu&rsquo;on a choisi, ce n&rsquo;est pas loin d&rsquo;y r\u00e9pondre.<\/p>\n<\/p>\n<p><p>La NSA se fiche du tiers comme du quart de l&rsquo;op\u00e9ration-<em>narrative<\/em> mont\u00e9e par Clinton\/DNC contre les Russes \u00e0 propos de l&rsquo;attaque de WikiLeaks ; ce n&rsquo;est pas son probl\u00e8me et elle n&rsquo;a aucune estime particuli\u00e8re, ni pour Poutine, ni pour le respect d&rsquo;une v\u00e9rit\u00e9-de-situation si c&rsquo;est le cas. Par contre, il semble bien qu&rsquo;elle ne se fiche pas du tout du comportement de Clinton lorsqu&rsquo;elle \u00e9tait secr\u00e9taire d&rsquo;&Eacute;tat et m\u00eame depuis, et <strong>qu&rsquo;elle serait par cons\u00e9quent conduite \u00e0 tout craindre d&rsquo;une pr\u00e9sidence Clinton o&ugrave; la pr\u00e9sidente toute-puissante, pleine de l&rsquo;ivresse et de la fi\u00e8vre de sa toute-puissance, serait encore plus amen\u00e9e \u00e0 disposer des secrets de la NSA de la m\u00eame fa\u00e7on, sinon pire, que ce qu&rsquo;elle en fit<\/strong>. Connaissant la personnalit\u00e9 de Clinton et son degr\u00e9 d&rsquo;\u00e9nervement psychologique confinant \u00e0 la pathologie, son extraordinaire sentiment d&rsquo;impunit\u00e9 et de droit divin pour tous les privil\u00e8ges possible, sa certitude quasi-ontologique de ne d\u00e9pendre en rien des lois de son pays, et notamment des lois qui r\u00e9gulent la bonne marche de l&rsquo;oligarchie au pouvoir, cette crainte n&rsquo;est pas infond\u00e9e comme il n&rsquo;est pas infond\u00e9 de conjecturer que la NSA l&rsquo;\u00e9prouve dans les transes de son obsession pour le secret.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela nous conduit \u00e0 une conclusion, toujours dans le m\u00eame domaine hypoth\u00e9tique (NSA effectivement impliqu\u00e9e en tant que telle) selon la ligne de r\u00e9flexion que nous avons adopt\u00e9e, sous forme de trois questions chronologiques, aussi int\u00e9ressantes l&rsquo;une que l&rsquo;autre :<\/p>\n<\/p>\n<p><p>1). Va-t-il y avoir d&rsquo;autres fuites contre Clinton\/DNC pendant la campagne \u00e9lectorale ? La NSA, ou ce (celui\/celle) qui la repr\u00e9sente, entend-elle jouer un r\u00f4le actif pour tenter d&#8217;emp\u00eacher l&rsquo;\u00e9lection de Clinton ?<\/p>\n<\/p>\n<p><p>2). Si Clinton est \u00e9lue, trouvera-t-elle face \u00e0 elle un adversaire r\u00e9solue, capable des pires man&oelig;uvres, dans la NSA elle-m\u00eame, plus que jamais angoiss\u00e9e \u00e0 l&rsquo;id\u00e9e de la fa\u00e7on dont la nouvelle pr\u00e9sidente traiterait les informations ultra-secr\u00e8tes engageant la m\u00eame NSA, dont elle disposerait \u00e9videmment ? Ce ne serait pas une mince affaire, tant un monstre bureaucratique comme la NSA dispose effectivement de moyens consid\u00e9rables, au niveau de la communication, contre la fonction de la pr\u00e9sidence toute enti\u00e8re expos\u00e9e \u00e0 de telles attaques. <\/p>\n<\/p>\n<p><p>3). Si la r\u00e9ponse \u00e0 la deuxi\u00e8me question est positive, un tel conflit, avec manoeuvres vicieuses et fuites \u00e0 l&rsquo;appui, ne pourrait-il conduire \u00e0 une situation qui mettrait en danger la nouvelle pr\u00e9sidente, d\u00e9j\u00e0 dans une position affaiblie \u00e0 la lumi\u00e8re de l&rsquo;enqu\u00eate <em>emailgate <\/em>du FBI d\u00e9j\u00e0 r\u00e9alis\u00e9e, notamment au risque d&rsquo;une proc\u00e9dure de destitution lanc\u00e9e par un Congr\u00e8s o&ugrave; les r\u00e9publicains vivraient \u00e9videmment au rythme d&rsquo;une haine corse contre elle ? (L\u00e0 aussi, on doit rappeler un autre pr\u00e9c\u00e9dent, qui est <a href=\"http:\/\/www.dedefensa.org\/article\/le-president-et-quelques-generaux\">celui du Watergate<\/a>, issu d&rsquo;un montage bureaucratique de l&rsquo;\u00e9l\u00e9ment militaire [la pr\u00e9sidence du <em>Joint Chiefs of Staff<\/em>] du complexe militaro-industriel et portant effectivement sur le comportement d&rsquo;un pr\u00e9sident par rapport \u00e0 des informations secr\u00e8tes.)    <\/p>\n<\/p>\n<p><p>Comme l&rsquo;on voit, la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lantisysteme\">fonction antiSyst\u00e8me<\/a> reste un artefact baladeur capable de se fixer dans des occurrences bien inattendue, puisqu&rsquo;effectivement dans ce cas ce serait la NSA qui aurait l&rsquo;honneur de cette charge, Hillary tenant indiscutablement la position du Syst\u00e8me. C&rsquo;est tout le charme de ces monstres postmodernes o&ugrave; pullulent les \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/su-24-etat-parallele\">&Eacute;tats parall\u00e8les<\/a>\u00a0\u00bb et manifestement concurrents, et extr\u00eamement sensibles \u00e0 la protection de leurs pr\u00e9rogatives.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NSA est-elle antiSyst\u00e8me ? On n&rsquo;arr\u00eate pas un train type-TGV lanc\u00e9 \u00e0 grande vitesse. La narrative lanc\u00e9e par les d\u00e9mocrates concernant les fuites WikiLeaks sur les e-mails de la DNC (Democratic National Committee) qui avaient aussit\u00f4t provoqu\u00e9 la d\u00e9mission de la pr\u00e9sidente du DNC, Debbie Wasserman-Schlutz, cette narrative est fix\u00e9e et ne bougera plus.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13398,12416,934,12595,5931,17661,5145,2607,12224,2639,2626,9887,3865],"class_list":["post-76701","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-aaron","tag-binney","tag-clinton","tag-e-mails","tag-fuites","tag-gamma","tag-klein","tag-russophobie","tag-snowden","tag-trump","tag-watergate","tag-wikileaks","tag-william"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76701"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76701\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}