{"id":76711,"date":"2016-08-07T14:10:00","date_gmt":"2016-08-07T14:10:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/07\/poids-et-fou-rire-du-mensonge\/"},"modified":"2016-08-07T14:10:00","modified_gmt":"2016-08-07T14:10:00","slug":"poids-et-fou-rire-du-mensonge","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/07\/poids-et-fou-rire-du-mensonge\/","title":{"rendered":"Poids et fou-rire du mensonge"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Poids et fou-rire du mensonge<\/h2>\n<\/p>\n<p><p>7 ao&ucirc;t 2016 &ndash; C&rsquo;est un tout petit instant qu&rsquo;on doit d\u00e9signer, si l&rsquo;on va au fond des choses avec ironie et gravit\u00e9 \u00e0 la fois, &ndash; deux choses qui vont si bien ensemble, &ndash; comme un instant formidable d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> essentielle de notre temps. Cela se passe le 4 ao&ucirc;t, \u00e0 l&rsquo;ouverture du briefing quotidien du d\u00e9partement d&rsquo;&Eacute;tat, \u00e0 Washington D.C. La chose a \u00e9t\u00e9 largement diffus\u00e9e, surtout par vid\u00e9o, mais aussi avec des textes accompagnant cette vid\u00e9o. Je vas m&rsquo;attarder \u00e0 la documentation de ce court instant parce que je crois que, dans cet instant, on trouve l&rsquo;essence m\u00eame de notre \u00e9poque, &ndash; \u00e0 la fois extraordinairement \u00e9cras\u00e9e par le poids du mensonge que l&rsquo;on d\u00e9signe de fa\u00e7ons diff\u00e9rentes sur notre site, parce qu&rsquo;il prend des formes diff\u00e9rentes, &ndash; <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-virtualisme-narrative\">virtualisme, narrative<\/a>, <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> notamment, &ndash; \u00e0 la fois disposant de moyens exceptionnels de mise en \u00e9vidence \u00e9clatante (pour ceux qui ont les yeux normalement ouverts) de ce mensonge et de son poids. (Bien entendu, c&rsquo;est la syst\u00e8me de la communication et <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-technologisme-versus-communication-1\">son c\u00f4t\u00e9-<em>Janus<\/em><\/a> qui permet cet \u00e9tonnant contraste de possibilit\u00e9s.)<\/p>\n<\/p>\n<p><p>Donc l&rsquo;officier du service public qui est charg\u00e9 de ce briefing, Mark Toner, arrive devant son pupitre et dit quelques mots pour introduire son briefing. Il est d&rsquo;humeur guillerette, Toner, et ne cesse de rire dans ces premi\u00e8res secondes, &ndash; on apprendra que c&rsquo;est son dernier briefing avant son d\u00e9part en vacances, <strong>et alors tout cela et le reste se comprennent parce que si humain (\u00ab\u00a0humain, trop humain\u00a0\u00bb, doit penser son chef de service \u00e0 cet instant, non ?)<\/strong>. Puis apr\u00e8s quelques \u00e9changes joyeux et ironiques, il songe \u00e0 en venir au principal et Toner dit, se rappelant qu&rsquo;il y a quelques stagiaires en plus des journalistes accr\u00e9dit\u00e9s habituels :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Je pense que nous avons quelques stagiaires au fond de la salle. Bienvenu. Je suis heureux de vous accueillir pour cet exercice de transparence de la d\u00e9mocratie<\/em>&#8230; &raquo; ;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>et l\u00e0, il n&rsquo;en peut plus, Toner, et part d&rsquo;un \u00e9clat de rire absolument tonitruant, un fou-rire qu&rsquo;il ne peut r\u00e9fr\u00e9ner ni contenir, suivi par tous les journalistes, &ndash; car effectivement, d\u00e9signer la communication gouvernementale \u00e0 la presse d'\u00a0\u00bbexercice de transparence en d\u00e9mocratie\u00a0\u00bb est vraiment le sommet du mensonge comme d\u00e9finition de la pratique syst\u00e9matique du mensonge, &ndash; et tout cela <strong>d&rsquo;un tel naturel que nul ne devrait s&rsquo;y tromper me semble-t-il si l&rsquo;on assez d&rsquo;honn\u00eatet\u00e9 et d&rsquo;attention aux \u00eatres, cet \u00e9clat de rire n&rsquo;a rien de cynique, ni de m\u00e9prisant, mais enveloppe bien une situation que tous, les journalistes, le public, lui-m\u00eame, doivent servir et subir \u00e0 la fois&#8230;<\/strong><\/p>\n<\/p>\n<p><p>On voit la vid\u00e9o de cette intervention <a href=\"https:\/\/www.youtube.com\/watch?v=Jmiflg3FJK0\">le 5 ao&ucirc;t<\/a> sur <em>Youtube<\/em>, avec ce commentaire :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Mark Toner, the deputy spokesman for the US State Department, literally burst out laughing at the idea of transparency and democracy during an official press briefing on Thursday, August 4th<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Plusieurs sites de grands r\u00e9seaux l&rsquo;ont repris, avec texte et vid\u00e9o, par exemple Fox.<em>News<\/em> <a href=\"http:\/\/www.foxnews.com\/politics\/2016\/08\/04\/spokesman-erupts-in-laughter-after-claiming-state-dept-is-transparent.html\">le 4 ao&ucirc;t<\/a> et surtout le Washington <em>Examine<\/em>r <a href=\"http:\/\/www.washingtonexaminer.com\/spokesman-erupts-in-laughter-after-claiming-state-dept.-is-transparent\/article\/2598633\">le 4 ao&ucirc;t<\/a> \u00e9galement, avec la vid\u00e9o bien s&ucirc;r, mais un texte beaucoup plus long sur la fa\u00e7on dont le State Department traite la communication. J&rsquo;en donne ici deux extraits, le second rappelant certaines autres occasions o&ugrave; le d\u00e9partement a \u00e9t\u00e9 pris en flagrant d\u00e9lit de bidouillages des information, &ndash; et je souligne en gras certains passages qui m&rsquo;int\u00e9ressent :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>A top State Department spokesman on Thursday boasted that his department is open and transparent, but could hardly finish the sentence before erupting in laughter. \u00ab\u00a0Welcome to the State Department,\u00a0\u00bb spokesman Mark Toner said. \u00ab\u00a0I think we have some interns in the back. Welcome. Good to see you in this exercise in transparency and democracy.\u00a0\u00bb Toner then burst out laughing at his own comments as reporters in the room laughed with him. \u00ab\u00a0Sorry, I didn&rsquo;t mean to break out laughing there,\u00a0\u00bb he said. The incident prompted Associated Press reporter Matthew Lee to say, \u00ab\u00a0I thought it was an exercise in spin and obfuscation.\u00a0\u00bb<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>The State Department has come under fire for years for failing to be as transparent as it claims. For example, <strong>it took several months for it to finally release<\/strong> the emails it had from former Secretary Hillary Clinton, which it only did pursuant to a court order. Then, State learned that thousands of additional emails that Clinton erased had been captured by the FBI. State has said it would release those as well, but has not given a timeline.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>This year, after it was discovered that one of its press briefing videos was altered, State Department spokespeople said immediately that it was just a \u00ab\u00a0glitch.\u00a0\u00bb Three weeks later, State <a href=\"http:\/\/www.washingtonexaminer.com\/state-dept.-admits-intentionally-altering-video-of-iran-press-conference\/article\/2592732\">finally admitted<\/a> the video was altered intentionally, <strong>but it then said it had no further ideas on how to investigate how this happened<\/strong>. Only after Secretary of State John Kerry demanded a more thorough investigation did officials agree to look again, but <strong>eight weeks later, no progress has been made<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On me pardonnera d&rsquo;insister sur ce cas, mais je le trouve, dans son instantan\u00e9it\u00e9 et dans sa spontan\u00e9it\u00e9, dans son poids symbolique, et paradoxalement <strong>dans son extr\u00eame transparence d\u00e9mocratique de la d\u00e9monstration d&rsquo;absence totale de \u00ab\u00a0transparence dans la d\u00e9mocratie\u00a0\u00bb<\/strong>, si compl\u00e8tement significatif et d\u00e9monstratif, par rapport \u00e0 ce que je voudrais en dire plus loin, et pour me permettre effectivement d&rsquo;en dire plus, plus loin. J&rsquo;ajoute donc <a href=\"http:\/\/www.state.gov\/r\/pa\/prs\/dpb\/2016\/08\/260841.htm\">la transcription \u00e9crite<\/a> que le d\u00e9partement d&rsquo;&Eacute;tat a donn\u00e9 de cette \u00e9tonnant instant de v\u00e9rit\u00e9-de-situation, &ndash; et le lecteur press\u00e9 ou impatient peut passer directement au commentaire plus loin, il ne ratera pas une information essentielle, mais il n&rsquo;aura pas le compl\u00e9ment final de ce \u00ab\u00a0dossier\u00a0\u00bb qui est que la transcription \u00e9crite du d\u00e9partement d&rsquo;&Eacute;tat n&rsquo;a dans ce cas rien cach\u00e9 de cet \u00e9tonnant instant \u00ab\u00a0d&rsquo;une extr\u00eame transparence d\u00e9mocratique de la d\u00e9monstration d&rsquo;absence totale de &lsquo;transparence dans la d\u00e9mocratie'\u00a0\u00bb, avec l&rsquo;indication des rires (\u00ab\u00a0<em>laugher<\/em>\u00ab\u00a0), &ndash; sauf qu&rsquo;ils auraient pu mettre \u00e0 l&rsquo;instant crucial de l&rsquo;\u00e9clat de rire\/fou-rire de Toner inextinguible, plut\u00f4t \u00ab\u00a0<em>insane-laughter<\/em>\u00a0\u00bb &#8230; (Et l&rsquo;on retrouve aussi <a href=\"http:\/\/www.dedefensa.org\/article\/la-narrative-systeme-cest-bien-plus-quorwell\">l&rsquo;inamovible Matt Lee<\/a>, de AP, toujours prompt au sarcasme ; c&rsquo;est lui qui remarque sur la fin \u00ab\u00a0je croyais que c&rsquo;\u00e9tait un  exercice en manipulation et en dissimulation\u00a0\u00bb.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>Hi guys. Happy Thursday<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Question<\/em><\/strong> : &laquo; <em>Thank you<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>And what makes it even more special is it&rsquo;s a Thursday in August, which means tomorrow &ndash; everybody want to join with me?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Question<\/em><\/strong> : &laquo; <em>No briefing<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>True to our tradition, there will be &ndash; thank you, Matt &ndash; no briefing<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Question<\/em><\/strong> : &laquo; <em>There will be one<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>What was that, Said? <\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Question<\/em><\/strong> : &laquo; <em>There will be a briefing. An old one<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>An old briefing<\/em>. (<em>Laughter<\/em>.) <em>Anyway, welcome to the State Department. I think we have some interns in the back. Welcome. Good to see you in this exercise in transparency in democracy<\/em>. (<em>Laughter<\/em>.) &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Question [Matt Lee]<\/em><\/strong> : &laquo; <em>Is that what it is?<\/em> (<em>Laughter<\/em>.) <em>I thought it was a<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>Sorry, I didn&rsquo;t mean to break out in laughter<\/em>. (<em>Laughter.<\/em>) &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Question [Matt Lee]<\/em><\/strong> : &laquo; <em>I thought it was an exercise in spin and obfuscation<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mr. Toner<\/em><\/strong> : &laquo; <em>All right. Can you tell this is my last briefing before vacation? Anyway.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Okay, let&rsquo;s start<\/em>&#8230;  &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On me pardonnera la longueur de cette introduction, mais vraiment, l&rsquo;incident me para&icirc;t tellement significatif&#8230; Le porte-parole, Toner, est excit\u00e9, il part le lendemain en vacances, en plus il est, comme c&rsquo;est toujours le cas dans ces services de bureaucratie de la communication, surcharg\u00e9 de travail et par cons\u00e9quent \u00e9puis\u00e9 nerveusement puisque charg\u00e9 d&rsquo;une mission tr\u00e8s d\u00e9licate : <strong>manipuler les nouvelles et dissimuler les choses trop sensibles, devant notamment des vieux briscards type-Matt Lee, qui doivent \u00eatre en plus des copains<\/strong> \u00e0 qui, autour d&rsquo;un caf\u00e9 ou d&rsquo;un <em>bourbon<\/em>, on ne dissimule rien de certaines pratiques qui font partie du <em>job<\/em>.<\/p>\n<\/p>\n<p><p>Ce qu&rsquo;il m&rsquo;importe de dire, c&rsquo;est ma conviction qu&rsquo;en cet instant si rapide, et qui semblerait si futile, on a, symboliquement et op\u00e9rationnellement, un condens\u00e9 d&rsquo;une puissance extr\u00eame du drame que nous vivons aujourd&rsquo;hui, dans cette \u00e9poque sans \u00e9quivalent et exceptionnelle <strong>: l&rsquo;omnipr\u00e9sence du mensonge qu&rsquo;il faut \u00e0 la fois alimenter, servir, et diffuser comme si c&rsquo;\u00e9tait le vrai, alors que, dans de telles occurrences o&ugrave; la chose est si flagrante, tout le monde sait qu&rsquo;il s&rsquo;agit de l&rsquo;univers du mensonge total et totalitaire<\/strong>. Je ne partage pas du tout, certains commentaires qui ont \u00e9t\u00e9 fait, notamment de la vid\u00e9o <em>Youtube<\/em>, selon lesquels ce rire, &ndash; qui est d&rsquo;ailleurs un fou-rire incontr\u00f4l\u00e9, &ndash; du porte-parole est pour se moquer avec arrogance et m\u00e9pris de ceux qui croient \u00e0 cette fable de \u00ab\u00a0la transparence d\u00e9mocratique\u00a0\u00bb, et cela avec les complicit\u00e9s des journalistes, pour l&rsquo;essentiel venus de la presse-Syst\u00e8me ; pour moi, non, pas du tout, <strong>au contraire tous ces gens traversent un moment de lucidit\u00e9 sur ce qu&rsquo;ils font, retrouvant un instant l&rsquo;esprit critique qui importe<\/strong>&#8230; Je leur fais absolument cr\u00e9dit de cela, parce que je le ressens absolument, et il n&rsquo;est question ici que d&rsquo;une tr\u00e8s forte conviction de mon chef devant le spectacle, les mimiques, les mines qu&rsquo;on peut voir. Personne ne peut nous d\u00e9partager, mais je remarquerai que s&rsquo;il s&rsquo;agit de duplicit\u00e9 et de cynisme qui impliquent une certaine r\u00e9flexion et du machiav\u00e9lisme, c&rsquo;est un bien grand risque et un risque bien sot de d\u00e9voiler ainsi que tout n&rsquo;est que mensonge&#8230;<\/p>\n<\/p>\n<p><p>(A propos de cette remarque \u00ab\u00a0dans de telles occurrences o&ugrave; la chose est si flagrante, tout le monde sait qu&rsquo;il s&rsquo;agit de l&rsquo;univers du mensonge total et totalitaire\u00a0\u00bb, je n&rsquo;en dirais pas autant et m\u00eame au contraire des pens\u00e9es, jugements et conceptions plus larges, des concepts g\u00e9n\u00e9raux, des analyses plus fouill\u00e9es du c\u00f4t\u00e9 des USA\/bloc-BAO, c&rsquo;est-\u00e0-dire du Syst\u00e8me, o&ugrave; le plus souvent l&rsquo;on croit que ce que l&rsquo;on dit rencontre la v\u00e9rit\u00e9, oubliant que la mat\u00e9riel basique de tout ces exercices est le mensonge int\u00e9gral et brut de fonderie, comme on le voit dans ce briefing. <strong>C&rsquo;est qu&rsquo;alors, dans ces occasions plus g\u00e9n\u00e9rales, l&rsquo;intelligence de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-humaine-1\">la raison-subvertie<\/a> reprend le dessus et impose la conviction rationalis\u00e9e<\/strong> ; cette attitude touche surtout les experts, hommes politiques et autres de cette trempe, y compris dans la presse-Syst\u00e8me les commentateurs qui ne vont pas chercher les \u00ab\u00a0faits\u00a0\u00bb, tandis que les sp\u00e9cialistes de la communication sont ceux qui sont les plus susceptibles d&rsquo;\u00eatre confront\u00e9s au mensonge puisqu&rsquo;ils manient le mat\u00e9riel, c&rsquo;est-\u00e0-dire le mensonge brut.)<\/p>\n<\/p>\n<p><p>Ce que nous montre donc l&rsquo;\u00e9pisode, outre l&rsquo;omnipr\u00e9sence du mensonge qui forme \u00ab\u00a0le mat\u00e9riel de base\u00a0\u00bb, c&rsquo;est qu&rsquo;\u00e0 cet instant les jugements identifient justement cela. Mais on n&rsquo;y peut rien pensent-ils \u00e9videmment, puisque le mensonge est omnipr\u00e9sent et qu&rsquo;aucun \u00eatre ne peut changer cette situation. (On peut en rire, comme ils font, se jugeant alors eux-m\u00eames avec une certaine d\u00e9rision et, au fond, une pi\u00e8tre opinion d&rsquo;eux-m\u00eames. Certains se r\u00e9voltent et passent dans la dissidence, mais l&rsquo;on voit que cela ne change rien et que le mensonge totalitaire continue \u00e0 r\u00e9gner.)<\/p>\n<\/p>\n<p><p>Ici surgit \u00e0 nouveau la question : qui ordonne ce mensonge totalitaire ? et ma r\u00e9ponse reste, imperturbable : <strong>personne d&rsquo;humain, mais bien une volont\u00e9 g\u00e9n\u00e9rale du Syst\u00e8me contre laquelle on ne peut rien de fa\u00e7on op\u00e9rationnelle et directe<\/strong>. (Pour cette raison d&rsquo;illustrer ce que je crois \u00eatre une v\u00e9rit\u00e9-de-situation, on voit des remarques, soulign\u00e9s en gras dans le texte cit\u00e9, de l&rsquo;impuissance humaine \u00e0 redresser certaines distorsions mensong\u00e8res trop voyantes, dont on ignore m\u00eame d&rsquo;o&ugrave; elles viennent [&laquo; <em>State <a href=\"http:\/\/www.washingtonexaminer.com\/state-dept.-admits-intentionally-altering-video-of-iran-press-conference\/article\/2592732\">finally admitted<\/a> the video was altered intentionally, <strong>but it then said it had no further ideas on how to investigate how this happened &raquo;<\/strong><\/em>].)&#8230; Puis s&rsquo;encha&icirc;ne alors, au-del\u00e0, l&rsquo;autre question, encore plus fondamentale : qu&rsquo;est-ce donc que ce Syst\u00e8me ? Plus que jamais, je r\u00e9fute la r\u00e9ponse m\u00e9caniste qui est la formation d\u00e9terministe de cette machinerie, qui n&rsquo;est pour moi que la description du processus, du moyen de la formation, de l&rsquo;\u00e9tablissement de cette dictature, de la manufacture de la pression permanente du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Pour moi, il y a une source fondamentale qui est la r\u00e9ponse du \u00ab\u00a0pourquoi ?\u00a0\u00bb, la cause fondamentale de l&rsquo;existence de ce Syst\u00e8me, agissant comme il le fait, dans le sens de la d\u00e9structuration-dissolution et imposant le mensonge total-totalitaire comme moyen. J&rsquo;ai identifi\u00e9 d\u00e9j\u00e0 cette source <strong>comme \u00e9tant \u00ab\u00a0le Mal\u00a0\u00bb, sans moyen d&rsquo;aller plus loin dans la certitude (pseudo-certitude) de l&rsquo;explication rationnelle, car l\u00e0 interviennent les questions fondamentales de conviction et de \u00ab\u00a0foi\u00a0\u00bb (autant de la part de ceux qui favorisent cette conception que de la part de ceux qui la r\u00e9futent)<\/strong>, et l&rsquo;argument rationnel n&rsquo;est plus suffisant pour permettre un d\u00e9bat, &ndash; surtout lorsqu&rsquo;on croit, comme moi, que la raison est en g\u00e9n\u00e9ral, pour ceux qui y croient sans le redressement n\u00e9cessaire que sugg\u00e8rent l&rsquo;esprit critique et l&rsquo;exp\u00e9rience, rien de moins que la raison-subvertie qui est prisonni\u00e8re du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus, l&rsquo;incident d\u00e9crit ici conduit \u00e0 un autre propos, pas moins int\u00e9ressant, qui est le poids du mensonge, et qui sugg\u00e8re puissamment les limites de l&#8217;empire du Syst\u00e8me sur ceux qui sont <a href=\"http:\/\/www.dedefensa.org\/article\/jecris-ton-ombre-zombie-1\">zombies<\/a>-serviteurs directs ; car, \u00e0 certains moment, et le plus souvent involontairement et inconsciemment, le zombie l&rsquo;est un peu moins et tend \u00e0 se r\u00e9volter contre sa condition de serviteur, imposant une charge de tension terrible et affreusement contradictoire \u00e0 sa psychologie&#8230; Je veux dire que le mensonge, lorsqu&rsquo;il est aussi flagrant, aussi impudent, et lorsqu&rsquo;il est  r\u00e9p\u00e9t\u00e9 \u00e0 l&rsquo;infini sans souci de la dignit\u00e9 de l&rsquo;esprit et des exigences du caract\u00e8re, finit par peser d&rsquo;un poids insupportable. M\u00eame si l&rsquo;on identifie pas la cause de ce poids, sa charge ne cesse de peser ; et, de m\u00eame que la cause de cette charge n&rsquo;est pas clairement identifi\u00e9e (plut\u00f4t inconsciemment soup\u00e7onn\u00e9e), de m\u00eame les r\u00e9actions qu&rsquo;on distingue parfois, et m\u00eame de plus en plus souvent \u00e0 mesure que monte la tension, provoque des instants de r\u00e9volte qui n&#8217;emploie pas les cvhemins habituels de la r\u00e9volte, qui s&rsquo;expriment de diff\u00e9rentes fa\u00e7ons, et notamment par de soudain emportement d&rsquo;ironie et d&rsquo;humour devant ce qui para&icirc;t \u00e0 la fois insupportable et ridicule dans son m\u00e9pris impudent des choses vraies, aboutissant au fou-rire soudain de Toner, <strong>que tout le monde comprend parfaitement, au quart de tour, nul ne doutant chez ces journalistes que tout le monde participe \u00e0 un simulacre grossier de d\u00e9mocratie, &ndash; donc formidable instant de v\u00e9rit\u00e9-de-situation<\/strong>.<\/p>\n<\/p>\n<p><p>C&rsquo;est pour moi une chose av\u00e9r\u00e9e et qui joue un r\u00f4le consid\u00e9rable, &ndash; impossible \u00e0 vraiment identifier, ni \u00e0 mesurer certes, &ndash; dans la d\u00e9gradation acc\u00e9l\u00e9r\u00e9 du Syst\u00e8me, et l&rsquo;installation du chaos de la communication. (Voir les pr\u00e9sidentielles USA-2016, et notamment le parcours de Clinton.) Le poids du mensonge permanent, charge inconsciente mais terrible \u00e0 supporter, mine les psychologies, \u00e9rode les volont\u00e9s et les caract\u00e8res, fragilise infiniment les certitudes, et contribue immens\u00e9ment \u00e0 la d\u00e9construction-dissolution du Syst\u00e8me en cours. <strong>Le poids du mensonge dans sa signification quasiment \u00e9thique (et inconsciemment \u00e9thique pour la plupart d&rsquo;entre nous et d&rsquo;entre eux) est quelque chose qui rend psychologiquement malade, sinon conduit certains vers la folie<\/strong>. La mat\u00e9riel humain n&rsquo;est pas fiable \u00e0 cet \u00e9gard, malgr\u00e9 ses imperfections sans fin, ses l\u00e2chet\u00e9s, ses faiblesses, et cela finira par mettre le Syst\u00e8me dans une position d\u00e9licate, lui qui p\u00e8sede tout son poids et exige toujours plus. S&rsquo;il veut sauver sa peau cliquetante et cuirass\u00e9e, le Syst\u00e8me a int\u00e9r\u00eat \u00e0 installer vite fait les robots brillantissimes que lui proposent les z\u00e9lotes du dieu-Progr\u00e8s qui dirigent Google, Apple &#038; Cie, avant qu&rsquo;eux-m\u00eames (les z\u00e9lotes) ne s&rsquo;effondrent, psychologies \u00e9puis\u00e9es \u00e0 leur tour, et ne prennent de longues vacances dans des \u00e9tablissements psychiatriques tr\u00e8s chics et o&ugrave; l&rsquo;on fr\u00e9quente du beau monde, avec entonnoirs dernier cri sur la t\u00eate.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poids et fou-rire du mensonge 7 ao&ucirc;t 2016 &ndash; C&rsquo;est un tout petit instant qu&rsquo;on doit d\u00e9signer, si l&rsquo;on va au fond des choses avec ironie et gravit\u00e9 \u00e0 la fois, &ndash; deux choses qui vont si bien ensemble, &ndash; comme un instant formidable d&rsquo;une v\u00e9rit\u00e9-de-situation essentielle de notre temps. Cela se passe le 4&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3889,3888,9831,17673,7540,4086,10232,2702,3099,17674,12034,12511],"class_list":["post-76711","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-detat","tag-departement","tag-epuisee","tag-fou-rire","tag-lee","tag-mark","tag-matt","tag-mensonge","tag-psychologie","tag-toner","tag-totalitaire","tag-verite-de-situation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76711"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76711\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}