{"id":76722,"date":"2016-08-15T06:01:47","date_gmt":"2016-08-15T06:01:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/15\/1920-chesterton-et-le-feminisme-guerrier\/"},"modified":"2016-08-15T06:01:47","modified_gmt":"2016-08-15T06:01:47","slug":"1920-chesterton-et-le-feminisme-guerrier","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/08\/15\/1920-chesterton-et-le-feminisme-guerrier\/","title":{"rendered":"1920 : Chesterton et le f\u00e9minisme guerrier"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">1920 : Chesterton et le f\u00e9minisme guerrier<\/h2>\n<\/p>\n<p><p>En 1920 Chesterton visite l&rsquo;Am\u00e9rique et y voit poindre nos d\u00e9sastres : le cr\u00e9puscule des libert\u00e9s, le contr\u00f4le de notre sant\u00e9, la dictature humanitaire et f\u00e9ministe, la tartuferie paritairement correcte, le contr\u00f4le technoscientifique. On ne craint pas encore l&rsquo;antis\u00e9mite ou l&rsquo;int\u00e9griste, on craint alors le communiste (pourtant install\u00e9 \u00e0 Moscou par l&rsquo;argent des banques US) ou le buveur d&rsquo;alcool. Et on le contr\u00f4le, parce que dans le paradis des libert\u00e9s dont se moquent alors d&rsquo;autres g\u00e9nies comme Kafka (Amerika) ou C\u00e9line (le Voyage), on ne l\u00e9sine jamais sur les moyens.<\/p>\n<\/p>\n<p><p>Avant nos fouilles humiliantes dans les a\u00e9roports, Chesterton d\u00e9crit le passage aux douanes de la nouvelle inquisition. Et je laisse tel quel son bel anglais limpide :<\/p>\n<\/p>\n<p><p><strong><em>It would be easy enough to suggest that in this America has introduced a quite abnormal spirit of inquisition; an interference with liberty unknown among all the ancient despotisms and aristocracies.<\/em><\/strong><\/p>\n<\/p>\n<p><p>Chesterton pr\u00e9f\u00e8re d&rsquo;ailleurs la douane &ndash; et la police &#8211; jordanienne \u00e0 la douane am\u00e9ricaine. A la m\u00eame \u00e9poque il \u00e9crit son Auberge volante sur l&rsquo;islamisation de l&rsquo;Angleterre.<\/p>\n<\/p>\n<p><p>Vient la grande phrase digne du g\u00e9nie de la formule de l&rsquo;auteur du nomm\u00e9 jeudi : les libert\u00e9s que nous perdons sont les libert\u00e9s personnelles. L&rsquo;homme n&rsquo;est plus libre de son corps ou de sa sant\u00e9 avec l&rsquo;arriv\u00e9e de la prohibition ; il n&rsquo;est plus ma&icirc;tre de sa vie quotidienne.<\/p>\n<\/p>\n<p><p><strong><em>But to-day personal liberties are the first liberties we lose. It is not a question of drawing the line in the right place, but of beginning at the wrong end. What are the rights of man, if they do not include the normal right to regulate his own health, in relation to the normal risks of diet and daily life?<\/em><\/strong><\/p>\n<\/p>\n<p><p>Chesterton annonce le contr\u00f4le de nos libert\u00e9s par des entreprises priv\u00e9es.<\/p>\n<\/p>\n<p><p>Les lib\u00e9raux comme Hayek ou Friedman ne voulaient pas nous dire que rien n&#8217;emp\u00eache une entreprise de se mettre au service du servage : il suffit de la payer pour cela. On privatise le fascisme comme la taule ou l&rsquo;\u00e9lectricit\u00e9, c&rsquo;est aussi simple que cela.<\/p>\n<\/p>\n<p><p>Ce totalitarisme de tous les instants annonce bien s&ucirc;r l&rsquo;Etat mondial. Il s&rsquo;appuie aussi sur la technique du Panopticon. Chesterton voit venir notre destruction aux bons soins des machines :<\/p>\n<\/p>\n<p><p><strong><em>He tells us that our national dignities and differences must be melted into the huge mould of a World State, or else (and I think these are almost his own words) we shall be destroyed by the instruments and machinery we have ourselves made.<\/em><\/strong><\/p>\n<\/p>\n<p><p>L&rsquo;Etat mondial et son ordre nouveau, Chesterton les voit bien s&ucirc;r \u00e9merger en Am\u00e9rique avec sa fabrication du citoyen unique :<\/p>\n<\/p>\n<p><p><strong><em>Now it is not too much to say that Mr. Wells finds his model in America. The World State is to be the United States of the World&#8230; The pattern of the World State is to be found in the New World.<\/em><\/strong><\/p>\n<\/p>\n<p><p>Le mot pattern est toujours difficile \u00e0 traduire : on lit le dessein, le dessin, le mod\u00e8le ; il vient pourtant de notre bon vieux mot patron. Le patron &ndash; restons fran\u00e7ais &#8211; de l&rsquo;ordre mondial se produit via l&rsquo;am\u00e9ricanisation de la plan\u00e8te et par la t\u00e9l\u00e9vision, les m\u00e9dias et l&rsquo;homog\u00e9n\u00e9isation de toute la consommation. Les vieilles nations seront d\u00e9truites et une seule nation toute neuve na&icirc;tra partout, sans d\u00e9termination dirait le ministre Peillon.<\/p>\n<\/p>\n<p><p><strong><em>The idea of making a new nation literally out of any old nation that comes along. In a word, what is unique is not America but what is called Americanization<\/em><\/strong><strong>.<\/strong><\/p>\n<\/p>\n<p><p>Le nouvel ordre homog\u00e8ne n&rsquo;a pas trop besoin de violences militaires (encore que l&rsquo;imp\u00e9rialisme messianique et humanitaire d\u00e9nonc\u00e9 une g\u00e9n\u00e9ration avant par le savant John  Hobson soit toujours en guerre), parce qu&rsquo;il est d&rsquo;inspiration f\u00e9minine et f\u00e9ministe. Avant que Madonna ou Hillary Clinton ne se m\u00ealent d&rsquo;humanitaire, Chesterton pressent que le totalitarisme des temps nouveaux sera bas\u00e9 sur de bons sentiments, le politiquement correct de nos chers vieux m\u00e9dias. Philippe Muray a repris la formule (garderie) : l&rsquo;ordre global est une banale nursery o&ugrave; on nous casse les pieds et tape sur les doigts !<\/p>\n<\/p>\n<p><p><strong><em>And as there can be no laws or liberties in a nursery, the extension of feminism means that there shall be no more laws or liberties in a state than there are in a nursery. The woman does not really regard men as citizens but as children. She may, if she is a humanitarian, love all mankind; but she does not respect it. Still less does she respect its votes.<\/em><\/strong><\/p>\n<\/p>\n<p><p>Il a bien raison ; la d\u00e9mocratie f\u00e9ministe ne respectera pas nos votes. Voyez le Brexit.<\/p>\n<\/p>\n<p><p>On parle de l&rsquo;ignoble th\u00e9orie du genre \u00e0 cause de laquelle des parents martyrs vont en prison en Allemagne et ailleurs. C&rsquo;est la sauce scientifique, de cette science aux ordres d&rsquo;essence  postmoderne qui ne cesse de nous mentir et de nous d\u00e9truire, qui est ici insupportable. Chesterton encore, cinquante ans avant la th\u00e9orie du genre :<\/p>\n<\/p>\n<p><p><strong><em>Now a man must be very blind nowadays not to see that there is a danger of a sort of amateur science or pseudo-science being made the excuse for every trick of tyranny and interference<\/em><\/strong><strong>.<\/strong><\/p>\n<\/p>\n<p><h4>Nicolas Bonnal<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1920 : Chesterton et le f\u00e9minisme guerrier En 1920 Chesterton visite l&rsquo;Am\u00e9rique et y voit poindre nos d\u00e9sastres : le cr\u00e9puscule des libert\u00e9s, le contr\u00f4le de notre sant\u00e9, la dictature humanitaire et f\u00e9ministe, la tartuferie paritairement correcte, le contr\u00f4le technoscientifique. On ne craint pas encore l&rsquo;antis\u00e9mite ou l&rsquo;int\u00e9griste, on craint alors le communiste (pourtant install\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[13956,934,3278],"class_list":["post-76722","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-chesterton","tag-clinton","tag-hillary"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76722"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76722\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}