{"id":76756,"date":"2016-09-01T10:03:35","date_gmt":"2016-09-01T10:03:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/01\/pourquoi-khaos-plutot-que-chaos\/"},"modified":"2016-09-01T10:03:35","modified_gmt":"2016-09-01T10:03:35","slug":"pourquoi-khaos-plutot-que-chaos","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/01\/pourquoi-khaos-plutot-que-chaos\/","title":{"rendered":"Pourquoi <em>Khaos<\/em> plut\u00f4t que \u201cchaos\u201d\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pourquoi <em>Khaos<\/em> plut\u00f4t que \u00ab\u00a0chaos\u00a0\u00bb ?<\/h2>\n<\/p>\n<p><p>1er septembre 2016 &ndash; Ecrivant ou lisant, je ne sais, le titre de ce texte <a href=\"http:\/\/www.dedefensa.org\/article\/le-jerusalem-post-contre-soros-khaos\">du 31 ao&ucirc;t<\/a> \u00e0 propos d&rsquo;un article incendiaire du Jerusalem <em>Post <\/em>contre notre fascinant comp\u00e8re Georges Soros, si souvent pr\u00e9sent dans ce <em>Journal-dde.crisis<\/em>, il m&rsquo;est apparu \u00e0 l&rsquo;occasion d&rsquo;un petit temps de la r\u00e9flexion qu&rsquo;il ne serait pas inutile de chercher \u00e0 expliquer jusqu&rsquo;aux causes les plus dissimul\u00e9es l&#8217;emploi du <em>Khaos<\/em> grec plut\u00f4t que le \u00ab\u00a0chaos\u00a0\u00bb fran\u00e7ais comme cela serait venu normalement sous la plume. Au d\u00e9part, bien s&ucirc;r, puisque l&#8217;emploi \u00e9tait \u00e9videmment voulu, il y a la recherche innocente d&rsquo;un effet, un jeu de prononciation, &ndash; que cette prononciation soit juste ou pas, qu&rsquo;importe. Je dis \u00ab\u00a0sorosse\u00a0\u00bb plus que \u00ab\u00a0soro\u00a0\u00bb certes, et avec, quand j&#8217;emploie ce mot, l&rsquo;habitude de dire \u00ab\u00a0khaosse\u00a0\u00bb et non \u00ab\u00a0khao\u00a0\u00bb (et \u00ab\u00a0kao\u00a0\u00bb plut\u00f4t que \u00ab\u00a0kaosse\u00a0\u00bb bien entendu, pour le cas fran\u00e7ais) ; bien, tout cela c&rsquo;est du jeu de l&rsquo;effet mais bient\u00f4t se pose la question du sens, parce qu&rsquo;il y a si souvent un sens cach\u00e9 dans les mots et dans l&#8217;emploi des mots que vous faites, \u00e0 votre insu, \u00e9clair\u00e9 par l&rsquo;intuition, et le d\u00e9couvrir est souvent source d&rsquo;illumination ; l<strong>e mot parle de lui-m\u00eame par lui-m\u00eame, et pour se faire entendre, avant que vous le fassiez parler ; ainsi avez-vous l&rsquo;occasion, que dis-je le devoir de faire votre miel de l&rsquo;esprit en l&rsquo;\u00e9coutant attentivement<\/strong>.<\/p>\n<\/p>\n<p><p>Je sais approximativement, sans bravoure ni trop m&rsquo;y risquer que <em>Khaos<\/em> d\u00e9signe, chez les Grecs, l&rsquo;esp\u00e8ce de n\u00e9ant \u00e0 l&rsquo;origine du monde, ou bien le Rien \u00e0 l&rsquo;origine du Tout, ou bien l&rsquo;Unique, ou le Principe Unique selon la Tradition primordiale, ou bien ou bien&#8230; (Ou bien encore, selon mon entendement, \u00ab\u00a0la non-essence d&rsquo;au-del\u00e0 de l&rsquo;essence\u00a0\u00bb que d\u00e9crit <a href=\"http:\/\/www.dedefensa.org\/article\/chronique-du-19-courant-le-grand-age\">Pseudo-Denys l&rsquo;A\u00e9ropagite<\/a> : &laquo; [&#8230;C&rsquo;]<em>est l\u00e0 qu&rsquo;il fait taire tout savoir positif, qu&rsquo;il \u00e9chappe enti\u00e8rement \u00e0 toute saisie et \u00e0 toute vision, car il appartient tout entier \u00e0 Celui qui est au-del\u00e0 de tout, car il ne s&rsquo;appartient plus lui-m\u00eame ni n&rsquo;appartient \u00e0 rien d&rsquo;\u00e9tranger, uni par le meilleur de lui-m\u00eame \u00e0 Celui qui \u00e9chappe \u00e0 toute inconnaissance, ayant renonc\u00e9 \u00e0 tout savoir positif, et gr\u00e2ce \u00e0 cette inconnaissance m\u00eame connaissant par del\u00e0 toute intelligence<\/em>.&raquo;)<\/p>\n<\/p>\n<p><p>Ainsi de <em>Khaos<\/em> et selon une approche plus retenue mais n\u00e9anmoins avec quelque lumi\u00e8re certaine, selon Jean-Fran\u00e7ois Gautier dans <em>Le sens de l&rsquo;Histoire<\/em>, (Ellipse, 2013) : &laquo; <em>Comment interpr\u00e9ter cette figure dans les langues modernes ? Le terme fran\u00e7ais &lsquo;chaos&rsquo; ne convient pas : il d\u00e9signe un d\u00e9sordre, sans plus. D&rsquo;\u00e9minents professeurs traduisent &lsquo;Khaos&rsquo; par Espace ou par Faille. Aucune de ces propositions n&rsquo;est vraiment satisfaisante. Chacune sugg\u00e8re une grandeur, ou une potentialit\u00e9 de m\u00e9trique &ndash; f&ucirc;t-elle envisag\u00e9e de mani\u00e8re n\u00e9gative, ou privative. Or m\u00eame l&rsquo;Ab&icirc;me et la B\u00e9ance ont des bords. Et la situation est telle, \u00e0 ce moment initial du po\u00e8me d&rsquo;H\u00e9siode, que ce qui est habituellement d\u00e9sign\u00e9 comme de l&rsquo;espace n&rsquo;existe pas encore. Le terme &lsquo;Khaos&rsquo; \u00e9voque autant, dans ses sources mythologiques, un vide physique que le fait psychologique de \u00ab\u00a0rester bouche b\u00e9e\u00a0\u00bb. Aussi bien peut-on se rapprocher de l&rsquo;antique en changeant radicalement de registre et en traduisant &lsquo;provista Khaos genet&rsquo; par \u00ab\u00a0<strong>D&rsquo;abord, ce fut Ind\u00e9chiffrable<\/strong>&#8230;\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Comme l&rsquo;on voit, il s&rsquo;agit du terrain des hypoth\u00e8ses les plus hautes de ce que peut concevoir l&rsquo;esprit du symbolique et de la m\u00e9taphysique lorsqu&rsquo;il explore la Mystique pure, et aussi de la perspective la plus large jusqu&rsquo;\u00e0 n&rsquo;avoir plus de bornes qui se puisse concevoir dans le champ explor\u00e9, et l&rsquo;hypoth\u00e8se que justement l&rsquo;esprit ne peut concevoir. M\u00eame si je diverge un peu sur le sens que monsieur Gautier donne au mot \u00ab\u00a0chaos\u00a0\u00bb, <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-chaos-nouveau\">le diff\u00e9renciant<\/a> du mot \u00ab\u00a0d\u00e9sordre\u00a0\u00bb comme on l&rsquo;a vu, je con\u00e7ois \u00e9videmment que le mot <em>Khaos <\/em>est d&rsquo;une ampleur infinie, effectivement ind\u00e9chiffrable pour l&rsquo;esprit comme elle est inconcevable et incompr\u00e9hensible par lui. Notre souffle repris, admettons qu&rsquo;on puisse envisager, avec toutes les r\u00e9serves qui s&rsquo;imposent, ce terme infiniment imp\u00e9n\u00e9trable de <em>Khaos <\/em>pour l&rsquo;improbable Soros, lui qui est \u00e9galement humain, trop humain&#8230; Ainsi utilisant ce terme \u00e9nigmatique, et passant de la fonction op\u00e9rationnelle compl\u00e8tement incompr\u00e9hensible de Soros comme la d\u00e9crit bien le Jerusalem <em>Post<\/em>, <strong>le personnage-Soros devient-il compl\u00e8tement objet symbolique du propos, c&rsquo;est-\u00e0-dire objet symbolique d&rsquo;une \u00e9poque catastrophique que nous ne parvenons en aucune fa\u00e7on \u00e0 comprendre selon nos instruments rationnels, que notre esprit s&rsquo;il en reste \u00e0 lui-m\u00eame n&rsquo;a plus la capacit\u00e9 d&#8217;embrasser, sans parler certes d&rsquo;esp\u00e9rer la comprendre<\/strong>.<\/p>\n<\/p>\n<p><p>M\u00eame l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/le-diable-est-nu\">hypoth\u00e8se \u00ab\u00a0le Diable\u00a0\u00bb<\/a> ne suffit plus, sinon \u00e0 la consid\u00e9rer effectivement dans le champ symbolique que nous avons envisag\u00e9 : Soros comme symbole et non comme personnage. Cela implique que ses agitations de milliardaire retors, ses \u00ab\u00a0plans\u00a0\u00bb divers de sp\u00e9culateur devenu philanthrope-comploteur, ses ambitions de m\u00e9galomane (ainsi le JP le d\u00e9finit-il), n&rsquo;ont strictement aucun effet ni aucune importance sur l&rsquo;essentiel des choses. <strong>Il n&rsquo;est l\u00e0 que comme agitateur-symbole d&rsquo;un courant qui le d\u00e9passe, comme \u00ab\u00a0idiot utile\u00a0\u00bb, certes supr\u00eame mais extr\u00eamement sot, d&rsquo;un bouleversement catastrophique..<\/strong>.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Idiot utile\u00a0\u00bb, effectivement, l&rsquo;expression m&rsquo;est venue comme tr\u00e8s bienvenue parce qu&rsquo;il est lui-m\u00eame, Soros, accus\u00e9 de manipuler des personnages et des institutions chr\u00e9tiennes et catholiques, d&rsquo;en faire des \u00ab\u00a0idiots utiles\u00a0\u00bb de ses \u00ab\u00a0ambitions\u00a0\u00bb d\u00e9crites rapidement et \u00e9videmment comme subversion totale et \u00e9minemment diabolique du discours religieux. Il y a l\u00e0-dessus un article de <em>Breitbart.News<\/em> du <a href=\"http:\/\/www.breitbart.com\/big-government\/2016\/08\/31\/report-george-soros-exploits-catholic-useful-idiots\/\">31 ao&ucirc;t 2016<\/a>, relayant un article furieux, dans le Washington <em>Times<\/em>, du P\u00e8re Robert Sirico, fondateur de l&rsquo;<em>Action Institute<\/em> (catholique, bien entendu) dans l&rsquo;&Eacute;tat du Michigan.  A partir de nouvelles contenues dans les <em>e-mails<\/em> Soros-OSF et les accusations qui les accompagnent dont la presse-Syst\u00e8me US n&rsquo;a surtout pas dit mot, on peut penser que l&rsquo;ensemble ne d\u00e9plaira pas ni n&rsquo;\u00e9tonnera bien entendu ceux qui portent un regard plus que suspicieux sur l&rsquo;&Eacute;glise du temps courant et sur le pape Fran\u00e7ois d&rsquo;aujourd&rsquo;hui, avec accusation d&rsquo;\u00eatre un antipape \u00e0 la clef. <strong>Cela ferait de Soros-Fran\u00e7ois un dr\u00f4le d&rsquo;attelages d'\u00a0\u00bbidiots utiles\u00a0\u00bb r\u00e9ciproques, disons du Diable, mais bien au-del\u00e0 dirais-je moi, \u00ab\u00a0idiots utiles\u00a0\u00bb r\u00e9ciproques d&rsquo;une forme symbolique d&rsquo;un <em>Khaos<\/em> o&ugrave; se d\u00e9-constitue et se reconstitue d&rsquo;un m\u00eame mouvement notre \u00e9poque<\/strong> pour nous signifier que les \u00e9v\u00e9nements en cours conduisent \u00e0 une sorte de renouvellement de tout et du Tout, cette chute g\u00e9n\u00e9rale et pr\u00e9cipit\u00e9e, comme ces animaux qui viennent se suicider en se jetant dans le vide selon un instinct imm\u00e9morial, notre-chute dans le Rien pour que les choses se re-mettent en place, pour imposer et signifier un nouveau Tout ; <strong>Chute et Cycle ainsi boucl\u00e9s<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Symbolisme tout cela, certes, et le diabolique-Soros comme symbole-en-chef, un peu comme on dirait chef-de-gare si l&rsquo;on voit ce que je veux signifier&#8230; C&rsquo;est-\u00e0-dire qu&rsquo;il y a chez lui, chez ce personnage qui me fascine par sa justesse symbolique dans ses actes et ce qu&rsquo;il en pr\u00e9tend implicitement, parfait dans cette \u00e9poque pr\u00e9cis\u00e9ment avec ses innombrables bassesses qui s&rsquo;enfoncent plus bas que bas, <strong>il y a chez Soros des aspects \u00e0 la fois effrayants et lucif\u00e9riens car son action d\u00e9structurante et dissolvante n&rsquo;est pas une image ; et aussi, pas moins pr\u00e9sents, des aspects \u00e0 la fois d\u00e9risoires et illusoires aux yeux de l&rsquo;enjeu cosmique dont je parle<\/strong>, dont on est oblig\u00e9 de parler si l&rsquo;on veut tenir un discours qui tiennent compte de ce qu&rsquo;on ressent de l&rsquo;importance formidable du Moment de l'\u00a0\u00bbhistoire du Tout\u00a0\u00bb revenu au Rien avant une nouvelle \u00e9closion&#8230; Il y a un abysse effectivement entre ce Soros-terrestre qui pr\u00e9tend \u00e0 bien plus haut que lui, le Diable op\u00e9rationnel disons, avec toutes ses initiatives, tout son fric frelat\u00e9 r\u00e9parti en pr\u00e9bendes selon un plan de comptable, sorte de d\u00e9miurge-inverti, ses tentacules dans tous les sens, sa posture d&rsquo;araign\u00e9e tissant sa toile \u00ab\u00a0o&ugrave; tr\u00f4ne Hillary-emprisonn\u00e9e\u00a0\u00bb (Hillary \u00e9tant le bon coup du moment, si j&rsquo;ose dire) ; et puis les r\u00e9sultats de toutes ses intrigues, foireux, catastrophiques par rapports aux \u00ab\u00a0valeurs\u00a0\u00bb qu&rsquo;il affiche, par exemple lorsqu&rsquo;il nous pond une Ukraine mille-fois plus type-Ianoukovitch que du temps de Ianoukovitch, une \u00ab\u00a0Kiev-la-folle\u00a0\u00bb de basses fosses qui devient absolument d\u00e9risoire, qui part en guerre tous les trois jours en accouchant d&rsquo;un avorton sans queue ni t\u00eate, ni chenilles cliquetantes, qui barbote dans l&rsquo;impuissance et le d\u00e9risoire de sacorruption de souk, qui emmerde infiniment tous ses bailleurs de fonds et ses fournisseurs en \u00ab\u00a0valeurs\u00a0\u00bb avec ses caprices d&rsquo;idiot cong\u00e9nital-attard\u00e9, etc.<\/p>\n<\/p>\n<p><p>&#8230;Par contre oui, par le chaos par lui ainsi avanc\u00e9, multipli\u00e9, dans le sens o&ugrave; il importe que ce chaos acc\u00e9l\u00e8re et acc\u00e9l\u00e8re encore l&rsquo;effondrement du Syst\u00e8me avec ses spasmes d\u00e9structurants et dissolvants qui se retournent contre lui, le Syst\u00e8me, en un gracieux mouvement d&rsquo;autodestruction, puisqu&rsquo;il n&rsquo;y a plus que lui, le Syst\u00e8me, qui soit structur\u00e9, alors oui, Soros le symbole-en-chef devenu chef-de-gare cela a du sens&#8230; <strong>L&rsquo;insens\u00e9 fait sens si j&rsquo;ose dire en une formule bien de notre temps et bien de chez nous<\/strong>, et le Diable, enfin venu \u00e0 son terme, n&rsquo;est plus que \u00ab\u00a0sottise\u00a0\u00bb de lui-m\u00eame, lui qui ne peut s&#8217;emp\u00eacher de &laquo; <em>de laisser \u00e9chapper toujours quelque<\/em> [<a href=\"http:\/\/www.dedefensa.org\/article\/notre-armageddon\">bouffonne et colossale<\/a>] <em>sottise qui est comme sa signature <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>&#8230; Apr\u00e8s tout, je sais bien pourquoi il me fascine : pour qu&rsquo;un personne d&rsquo;une telle m\u00e9diocrit\u00e9 puisse prendre une telle importance d&rsquo;apparence jusqu&rsquo;\u00e0 sembler symbolique, au point qu&rsquo;on songerait sans sombrer dans le ridicule de parler du Diable et de <em>Khaos<\/em> \u00e0 son propos, il faut que l&rsquo;\u00e9poque des Temps Pr\u00e9sent soit anim\u00e9 des soubresauts les plus immenses et les plus pressants et alors elle prend le premier-venu ramass\u00e9 dans les corbeilles des Bourses les plis douteuses pour nous le faire savoir. <strong>C&rsquo;est fait<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi Khaos plut\u00f4t que \u00ab\u00a0chaos\u00a0\u00bb ? 1er septembre 2016 &ndash; Ecrivant ou lisant, je ne sais, le titre de ce texte du 31 ao&ucirc;t \u00e0 propos d&rsquo;un article incendiaire du Jerusalem Post contre notre fascinant comp\u00e8re Georges Soros, si souvent pr\u00e9sent dans ce Journal-dde.crisis, il m&rsquo;est apparu \u00e0 l&rsquo;occasion d&rsquo;un petit temps de la r\u00e9flexion&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[17734,2631,12487,17736,17735,17733,12101,4163],"class_list":["post-76756","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-au-dela","tag-de","tag-hesiode","tag-indechiffrable","tag-lessence","tag-non-essence","tag-pseudo-denys","tag-soros"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76756"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76756\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}