{"id":76772,"date":"2016-09-13T08:19:37","date_gmt":"2016-09-13T08:19:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/13\/hillary-sa-pneumonie-et-notre-destin\/"},"modified":"2016-09-13T08:19:37","modified_gmt":"2016-09-13T08:19:37","slug":"hillary-sa-pneumonie-et-notre-destin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/13\/hillary-sa-pneumonie-et-notre-destin\/","title":{"rendered":"Hillary, sa pneumonie et notre destin"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Hillary, sa pneumonie et notre destin<\/h2>\n<\/p>\n<p><p>9\/11, &laquo; <em>A Day That Will Live in Infamy<\/em> &raquo;&#8230; La phrase de Roosevelt concernant l&rsquo;attaque de Pearl Harbor a d\u00e9j\u00e0 \u00e9t\u00e9 mise \u00e0 toutes les sauces, alors pourquoi pas \u00e0 celle du malaise d&rsquo;Hillary Clinton lors de la c\u00e9l\u00e9bration fun\u00e8bre de l&rsquo;attaque 9\/11, quinze ans plus tard ; et plus encore, certains verraient dans toutes ces circonstances rassembl\u00e9es, avec bien des arguments sans doute, la substance \u00e9crasante d&rsquo;un symbole qui n&rsquo;a gu\u00e8re d&rsquo;\u00e9quivalent pour sa puissance, d&rsquo;une puissance telle que personne n&rsquo;aurait os\u00e9 l&rsquo;envisager&#8230; Qu&rsquo;une partie de la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> d&rsquo;une hypoth\u00e8se d\u00e9nonc\u00e9e hyst\u00e9riquement par le Syst\u00e8me comme une obsession complotiste de toute la racaille antiSyst\u00e8me se fasse jour lors de la c\u00e9l\u00e9bration fun\u00e8bre et sacr\u00e9e de l&rsquo;\u00e9v\u00e9nement fondateur de la postmodernit\u00e9, comment s&rsquo;interdire d&rsquo;y voir un de ces symboles formidables que les Anciens auraient appr\u00e9ci\u00e9 avec terreur, angoisse et respect comme un signe imp\u00e9ratif du Ciel ? Encore faudrait-il l&rsquo;interpr\u00e9ter ; eux, ils avaient leurs grand&rsquo;pr\u00eatres avec leur sagesse imm\u00e9moriale, nous nous avons nos zombies-Syst\u00e8me avec l&rsquo;arrogance stup\u00e9fiante de leur vide habit\u00e9 par leur rien&#8230; Mesurez la diff\u00e9rence et soyez fiers de la modernit\u00e9 et de son fameux Progr\u00e8s.<\/p>\n<\/p>\n<blockquote>\n<p><p> Dans tous les cas, <strong>on ne peut plus \u00e9carter la \u00ab\u00a0possibilit\u00e9 de l&rsquo;extension du domaine de la crise\u00a0\u00bb, pour employer un langage houellebecquien, et le port de sc\u00e9narios dans ce sens dans le bagage intellectuel de tout \u00ab\u00a0honn\u00eate homme\u00a0\u00bb (esp\u00e8ce rare, <em>circa<\/em>-XVII\u00e8me si\u00e8cle) est d\u00e9sormais autoris\u00e9<\/strong>. Le sc\u00e9nario le plus \u00e9vident  dans le domaine de l&rsquo;hypoth\u00e8se est que l&rsquo;incident \u00e9norm\u00e9ment symbolique de l'\u00a0\u00bb\u00e9pisode m\u00e9dical\u00a0\u00bb de la candidate Hillary Clinton ne soit pas circonscrit aussi vite et aussi bien qu&rsquo;il doit \u00eatre, et que, rapidement, il apparaisse qu&rsquo;Hillary ne fait plus le poids, qu&rsquo;elle ne tient plus la distance, qu&rsquo;elle ne peut plus faire bonne figure sinon figure agressive comme elle a jusqu&rsquo;ici tent\u00e9 de faire. Ce n&rsquo;est pas danser autour d&rsquo;une malade comme on danserait autour d&rsquo;un cadavre que d&rsquo;\u00e9crire cela, mais relever <strong>une r\u00e9alit\u00e9 d\u00e9sormais possible d&rsquo;une partie politique extraordinaire, surr\u00e9aliste, impr\u00e9vue et impr\u00e9visible, et plac\u00e9 au c&oelig;ur m\u00eame du centre affreusement bouillonnant de la Grande Crise d&rsquo;effondrement du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans ce sc\u00e9nario, d&rsquo;ailleurs, ce serait les caciques vermoulues de corruption de la direction du parti d\u00e9mocrate (le DNC), les meilleurs repr\u00e9sentants du Syst\u00e8me dans la bagarre, qui y viendraient, et, une fois la chose d\u00e9cid\u00e9e, sans faire de cadeau \u00e0 Hillary. C&rsquo;est alors qu&rsquo;on verrait la circonstance la plus inattendue pour nos esprits pleins de cette raison qui a du mal \u00e0 accepter les effets de la tornade m\u00e9tahistorique qui nous emporte : la \u00ab\u00a0fille pr\u00e9f\u00e9r\u00e9e\u00a0\u00bb du Syst\u00e8me, avec tous ses arguments soci\u00e9taux, pro-<em>black<\/em>, pro-f\u00e9ministe, pro-guerre et ainsi de suite, tentant de repousser les pressions pour se retirer, &ndash; car elle sait se battre, la gueuse, &ndash; et r\u00e9sistant aux instances du parti ; et ainsi, ce miracle \u00e9tonnant de nos \u00ab\u00a0chaises musicales Syst\u00e8me-antiSyst\u00e8me\u00a0\u00bb, d&rsquo;<strong>une Hillary devenant brusquement antiSyst\u00e8me par sa r\u00e9sistance aux pressions pour se d\u00e9barrasser d&rsquo;elle<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>(Tout cela sous le regard impavide d&rsquo;un Trump ? Car si cela se faisait, nous conseillerions \u00e0 Trump de ne pas s&rsquo;immiscer dans le d\u00e9bat, &ndash; dans cette premi\u00e8re phase interne au parti d\u00e9mocrate dans tous les cas, &ndash;  et de continuer sa mission de d\u00e9molition de tout ce qui a pr\u00e9c\u00e9d\u00e9 en mettant en accusation l&rsquo;<em>establishment<\/em> et celle qui le repr\u00e9sente n\u00e9cessairement. Il montrerait ainsi que sa principale qualit\u00e9, celle que nous serions tent\u00e9s de deviner chez lui comme pouvant \u00eatre le secret cach\u00e9 de sa capacit\u00e9 \u00e0 rassembler un tr\u00e8s gros soutien sur son nom, qui serait la clef d&rsquo;une \u00e9ventuelle victoire, est bien son impavidit\u00e9, sa placidit\u00e9 devant les \u00e9v\u00e9nements ; cette sorte de vertu pachydermique, &ndash; hommage au plus grand, au plus puissant et au plus noble des animaux de la cr\u00e9ation, &ndash; qui semble comme une r\u00e9f\u00e9rence de calme dans cette temp\u00eate extraordinaire.)<\/p>\n<\/p>\n<p><p>Mais tout cela n&rsquo;est que supputations&#8230; Elles sont autoris\u00e9es, aujourd&rsquo;hui, pendant que le <em>Post<\/em>, <em>Le Monde<\/em>, <em>The Guardian<\/em> &#038; toute la compagnie des saltimbanques de la vertu ont le nez embaum\u00e9 ailleurs du fait in\u00e9vitables qu&rsquo;ils sont occup\u00e9s \u00e0 une de leurs besognes saisonni\u00e8res, occup\u00e9s \u00e0 vidanger leurs chiottes cette fois bouch\u00e9s par le plein d&rsquo;anath\u00e8mes lanc\u00e9es par eux contre ceux qui montent des \u00ab\u00a0complots\u00a0\u00bb imaginaires sur la sant\u00e9 de leur ch\u00e8re candidate. Voici donc la supputation ou le sc\u00e9nario <a href=\"https:\/\/jonrappoport.wordpress.com\/2016\/09\/12\/hillary-dropping-out-of-the-race-no-longer-a-fantasy\/\">envisag\u00e9 par Jon Rappoport<\/a> sur son <em>blog<\/em> et repris sur son site <em><a href=\"http:\/\/www.nomorefakenews.com\">NoMoreFakeNews.com<\/a><\/em>, et \u00e9galement sur <em><a href=\"http:\/\/www.infowars.com\/hillary-dropping-out-of-the-race-no-longer-a-fantasy\/\">Infowars.com<\/a><\/em>. <strong>Rappoport nous offre la version ambitieuse de l&rsquo;hypoth\u00e8se<\/strong>, celle qui n&rsquo;implique pas le remplacement de Clinton effectu\u00e9 dans les temps comme une rustine pos\u00e9e sur un pneu crev\u00e9, mais bien un report des \u00e9lections pour permettre au pauvre parti d\u00e9mocrate si \u00e9prouv\u00e9 de refaire ses forces ; alors, il s&rsquo;agirait d&rsquo;envisager que le Congr\u00e8s, dans un vote sur mesure et dans sa grande sagesse, adresse une supplique \u00e0 Sa Majest\u00e9 BHO pour qu&rsquo;il veuille bien consentir \u00e0 demeurer quelques temps de plus, quelques mois si l&rsquo;on veut, peut-\u00eatre plus qui sait, dans tous les cas le temps de faire quelques solides parcours de golf de plus pour nous rassurer tous et consolider <a href=\"http:\/\/www.dedefensa.org\/article\/le-meilleur-president-us-de-lhistoire-du-golf\">son titre envi\u00e9<\/a> ; et Rappoport de nous confier qu&rsquo;Obama finirait, avec une r\u00e9ticence qui l&rsquo;honore, d&rsquo;accepter cette charge suppl\u00e9mentaire, avec une abn\u00e9gation qui l&rsquo;honore \u00e9galement&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Apr\u00e8s que les dirigeants du Congr\u00e8s lui aient demand\u00e9 de rester en fonction plusieurs mois de plus, il accepta avec r\u00e9ticence, disant : \u00ab\u00a0Bon, je dois bien avoir soixante ou soixante-dix instruction pr\u00e9sidentielle<\/em> [<em>executive order<\/em>] <em>mises en forme et pr\u00eates \u00e0 \u00eatre diffus\u00e9es, aussi peut-\u00eatre bien que je pourrais continuer \u00e0 conduire la pays encore un peu plus proche du futur que nous envisageons pour lui. Nous sommes tous dans la m\u00eame gal\u00e8re.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Rappoport nous dit : d\u00e9sormais, cette hypoth\u00e8se n&rsquo;est plus \u00ab\u00a0<em>fantasy<\/em>\u00ab\u00a0, et nous sommes d&rsquo;accord avec lui. Elle reste pourtant extr\u00eamement minoritaire dans le domaine de la possibilit\u00e9 des choses pour la carte et le territoire houellebecquiens de la crise. En effet, Rappoport ne s&rsquo;attarde pas aux cons\u00e9quences possibles\/probables et n\u00e9cessairement impr\u00e9visibles d&rsquo;un tel sc\u00e9nario dans l&rsquo;atmosph\u00e8re psychologique surchauff\u00e9e des USA-2016&#8230; &Eacute;videmment, si cette occurrence se dessinait jusqu&rsquo;\u00e0 la r\u00e9alisation, jusqu&rsquo;\u00e0 la mise en place de l&rsquo;op\u00e9ration, <em>The Donald<\/em>, tout en conservant sa placidit\u00e9, <strong>devrait montrer que le caract\u00e8re pachydermique qui le caract\u00e9rise contient aussi un registre fameux de col\u00e8re<\/strong>, &ndash; qui n&rsquo;a vu, dans le r\u00e9el ou sur document, la fureur d&rsquo;un \u00e9l\u00e9phant, notamment exprim\u00e9e par les mouvements de sa trompe ? Bref, nous pouvons esp\u00e9rer qu&rsquo;il serait cette fois surprenant que les foules US, qui se sont d\u00e9cha&icirc;n\u00e9es comme on les a vues, dans des sens diff\u00e9rents et selon des modes qui divergent, acceptent une telle issue avec, justement, la placidit\u00e9 du pachyderme qui n&rsquo;est pas leur qualit\u00e9 particuli\u00e8re du Moment pr\u00e9sent.<\/p>\n<\/p>\n<p><p>Qu&rsquo;importe finalement, tout cela n&rsquo;est encore que construction de l&rsquo;esprit, m\u00eame si des esprits mal intentionn\u00e9s ont laiss\u00e9 filtrer que les instances du DNC pr\u00e9paraient une r\u00e9union d&rsquo;urgence pour examiner la situation et envisager toutes les possibilit\u00e9s, &ndash; apr\u00e8s tout, c&rsquo;est le moins que ce DNC puisse faire pour faire son boulot. Cette \u00e9lection pr\u00e9sidentielle USA-2016 est vraiment tr\u00e8s surprenante dans sa capacit\u00e9 \u00e0 tenir ce qui semblerait une promesse qu&rsquo;elle se serait faite de nous surprendre constamment par des \u00e9v\u00e9nements impr\u00e9visibles, m\u00eame s&rsquo;ils auraient pu et m\u00eame du \u00eatre pr\u00e9vus par les esprits notamment antiSyst\u00e8me les plus prompts \u00e0 \u00e9chafauder des hypoth\u00e8ses o&ugrave; le Syst\u00e8me se trouverait dans l&#8217;embarras&#8230; Car et pour en revenir \u00e0 notre d\u00e9but, si l&rsquo;on avait parl\u00e9 de la sant\u00e9 d&rsquo;Hillary personne n&rsquo;avait avanc\u00e9 l&rsquo;hyopoth\u00e8se que <strong>ce probl\u00e8me de sant\u00e9 p&ucirc;t appara&icirc;tre aux yeux du monde \u00e9bahis le jour m\u00eame de la c\u00e9r\u00e9monie la plus sacr\u00e9e de l&rsquo;\u00e8re de la modernit\u00e9 ?<\/strong> On vous le dit, 9\/11, doublement &laquo; <em>A Day That Will Live in Infamy<\/em> &raquo;.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Hillary dropping out of the race no longer a fantasy<\/h2>\n<\/p>\n<p><p>Hillary buckled and fainted at the 9\/11 memorial. The video available <a href=\"http:\/\/www.infowars.com\/hillary-dropping-out-of-the-race-no-longer-a-fantasy\/\">here at InfoWars<\/a>, tells the story.<\/p>\n<\/p>\n<p><p>I&rsquo;ve written about her health problems before, including the blood-thinning Coumadin she&rsquo;s taking. And the blood clots. And the advisory against flying, because new life-threatening blood clots can occur.<\/p>\n<\/p>\n<p><p>I wrote&mdash;and I still say&mdash;Democrat power players would go along with electing her even if she was dragged into the Oval Office dead on arrival. They don&rsquo;t care.<\/p>\n<\/p>\n<p><p>After Hillary&rsquo;s fainting spell at the 9\/11 memorial, the Washington Post, that organ of unquestioned truth, grants that it&rsquo;s now acceptable to ask polite questions about her health. Well done, boys. You&rsquo;re really going out on a limb. Thanks so much.<\/p>\n<\/p>\n<p><p>I think it&rsquo;s time for major media to take an overt stand about Hillary: \u00ab\u00a0She may be very sick, dangerously so, but it&rsquo;s still a crime to emphasize that because it&rsquo;s sexist, and besides, untoward publicity could allow Trump to slip into the White House, and besides, our news organization has donated to the Clinton Foundation, and besides, she&rsquo;s Hillary and we all know and love her and we don&rsquo;t want to think about something bad happening to her because then we would cry.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>I would accept that statement.<\/p>\n<\/p>\n<p><p>&mdash;Hillary&rsquo;s public coughing fits. The physical instability. The fainting. The handler, Todd Madison, walking out on stage, putting his hand on her, telling her to keep talking, as if she&rsquo;s forgotten what&rsquo;s going on. You have to conclude her doctors have tried everything they can to keep her upright and functioning, and if this is best they can do, she&rsquo;s in bad shape.<\/p>\n<\/p>\n<p><p>Hillary dropping out of the race for the Oval Office is no longer a fantasy. It could happen. If it does, the media will swing into gear and try to demand a delay in the election.<\/p>\n<\/p>\n<p><p>There is no basis for such a demand, because both major Parties can pick their candidate on their own terms. The Democrats, for example, as we&rsquo;ve seen, can rig the vote and secretly back Hillary from the beginning and cook up propaganda to defeat Bernie Sanders. They can choose a slew of so-called super-delegates who owe nothing to the voters and, instead, support whoever they want to (Hillary). So if she drops out, the Democrat leaders can simply decide, again, without consulting voters, who the substitute is. Kaine? Biden? Sanders? Elizabeth Warren? Michelle Obama? Rachel Maddow? Karl Marx?<\/p>\n<\/p>\n<p><p>No doubt, some progressive pundit will suggest Obama should stay in office for a while, because he has the experience, he&rsquo;s Presidential, he&rsquo;s done such a magnificent job in his two terms, his mission is unfinished (he must get the TPP treaty ratified), we need him to continue the dialogue on race in the post-racial society, he knows how to bypass Congress with a blizzard of executive orders, he can figure out a way to admit millions more illegal immigrants to these shores, he backs Black Lives Matter, and he knows how to talk about fake employment numbers and pretend they&rsquo;re real.<\/p>\n<\/p>\n<p><p>The Democrats and their supporters will go on a victim binge: woe is us, Hillary our leader has fallen, we&rsquo;re crippled (differently abled), we need time to regroup, we can&rsquo;t be expected to make a snap judgment, who cares about constitutional rules governing elections, this is really serious, we have to decide what&rsquo;s best for The People&mdash;and we have to find a way to pay off Bernie Sanders so he stays in hiding and keeps his big mouth shut.<\/p>\n<\/p>\n<p><p>I, for one, would like to see Trump vs. Bernie. Socialist vs. Capitalist. They could do three debates on Globalism and its horrendous effects on America, at which point the public would realize they both claim to perceive the gargantuan threat, albeit from different angles.<\/p>\n<\/p>\n<p><p>Hillary was the unabashed queen bee of Globalism.<\/p>\n<\/p>\n<p><p>At any rate, you can bet that, as we speak, media giants are taking private briefings on how the election season would proceed if she drops out. They&rsquo;re preparing their talking points and tall stories and outright lies. All somehow culminating in a Democrat Party victory this November, come hell or high water.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0After Congressional leaders begged President Obama to stay on for several months, he reluctantly agreed, saying: &lsquo;Well, I do have sixty or seventy executive orders drawn up and ready to go, so perhaps I could bring the country a little closer to the future we envision. We&rsquo;re all in this together.'\u00a0\u00bb<\/p>\n<\/p>\n<p><h4>Jon Rappoport<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hillary, sa pneumonie et notre destin 9\/11, &laquo; A Day That Will Live in Infamy &raquo;&#8230; La phrase de Roosevelt concernant l&rsquo;attaque de Pearl Harbor a d\u00e9j\u00e0 \u00e9t\u00e9 mise \u00e0 toutes les sauces, alors pourquoi pas \u00e0 celle du malaise d&rsquo;Hillary Clinton lors de la c\u00e9l\u00e9bration fun\u00e8bre de l&rsquo;attaque 9\/11, quinze ans plus tard ;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[354,370,934,5575,3009,3278,17748,4014,5295,8569,2639,12538],"class_list":["post-76772","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-354","tag-370","tag-clinton","tag-day","tag-democrates","tag-hillary","tag-infamy","tag-of","tag-rapport","tag-sante","tag-trump","tag-usa-2016"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76772"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76772\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}