{"id":76798,"date":"2016-09-23T17:03:13","date_gmt":"2016-09-23T17:03:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/23\/washington-nihilisme-turbo\/"},"modified":"2016-09-23T17:03:13","modified_gmt":"2016-09-23T17:03:13","slug":"washington-nihilisme-turbo","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/09\/23\/washington-nihilisme-turbo\/","title":{"rendered":"Washington, nihilisme-<em>turbo<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Washington, nihilisme-<em>turbo<\/em><\/h2>\n<\/p>\n<p><p>23 septembre 2016 &ndash; Nous aurions voulu commencer ce \u00ab\u00a0<em>F&#038;C<\/em>\u00a0\u00bb par un texte exposant avec une logique implacable, fortement document\u00e9e dans ce sens, que la seule issue \u00e0 la crise actuelle, \u00e0 la Grande Crise pour notre compte, est la destruction des USA, &ndash; la destruction du Syst\u00e8me, pour notre compte l\u00e0 encore. Il s&rsquo;agit du texte que nous pr\u00e9sentons en rubrique <em>Ouverture libre<\/em> ce <a href=\"http:\/\/www.dedefensa.org\/article\/delenda-est-systema-america\">23 septembre 2016<\/a>, sous le titre &laquo; <em>Delenda Est Systema (America)<\/em> &raquo;. Nous l&rsquo;avons jug\u00e9 trop long pour le faire figurer dans ce \u00ab\u00a0F&#038;C\u00a0\u00bb, et par cons\u00e9quent nous recommandons de l&rsquo;avoir \u00e0 l&rsquo;esprit apr\u00e8s l&rsquo;avoir parcouru sinon lu pr\u00e9cis\u00e9ment pour ce qu&rsquo;il dit, pour mieux comprendre le d\u00e9veloppement que nous faisons ici.<\/p>\n<\/p>\n<p><p>L&rsquo;auteur, un citoyen am\u00e9ricain du nom de P.T. Carlo publi\u00e9 sur le site russe <em>Katehon.com<\/em> argumente avec minutie et selon un jugement qui prend en compte les principaux d\u00e9veloppements du point de vue civilisationnel ; ainsi n&rsquo;accorde-t-il pas plus d&rsquo;importance, par exemple, \u00e0 l&rsquo;action US en Syrie qu&rsquo;\u00e0 diverses autres domaines d&rsquo;activisme, et certainement pas plus et sans doute plut\u00f4t moins qu&rsquo;\u00e0 l&rsquo;activisme au niveau des mati\u00e8res soci\u00e9tales (\u00ab\u00a0id\u00e9ologie LGBTQ\u00a0\u00bb, notamment). Cette approche est absolument justifi\u00e9e lorsqu&rsquo;on consid\u00e8re l&rsquo;ampleur des mouvements lanc\u00e9s par le Syst\u00e8me dans ces domaines, et les effets d\u00e9structurants et dissolvants qui sont caus\u00e9s sur l&rsquo;architecture des soci\u00e9t\u00e9s. La conclusion de ce d\u00e9veloppement pr\u00e9cis, argument\u00e9, m\u00e9thodique est absolument radical, extr\u00e9miste au-del\u00e0 de tout, et pourtant compl\u00e8tement logique et rationnel : \u00ab\u00a0L&rsquo;Am\u00e9rique doit \u00eatre d\u00e9truite\u00a0\u00bb (<em>Delenda Est America<\/em>). Comme nous le notons dans notre rapide introduction \u00e0 ce texte :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ce texte se terminant part l&rsquo;exorde \u00ab\u00a0L&rsquo;Am\u00e9rique doit \u00eatre d\u00e9truite\u00a0\u00bb \u00e0 la mani\u00e8re du Delenda Est Cartago du vieux Caton, est absolument radical et extr\u00eame ; <strong>pour autant il n&rsquo;est en rien excessif, ni exalt\u00e9, il est m\u00eame tout \u00e0 fait raisonnable et mesur\u00e9 car son radicalisme extr\u00eame est la seule r\u00e9ponse rationnelle \u00e0 apporter \u00e0 l&rsquo;actuelle pouss\u00e9e dissolvante du Syst\u00e8me (de l&rsquo;Am\u00e9rique)<\/strong><\/em>. &raquo;  <\/p>\n<\/p>\n<p><p>C&rsquo;est donc avec cette id\u00e9e \u00e0 l&rsquo;esprit que nous pouvons entrer dans le vif de notre sujet, qui concerne essentiellement la dynamique suivie par les USA en Syrie ; nous parlons de \u00ab\u00a0dynamique\u00a0\u00bb plut\u00f4t que de \u00ab\u00a0politique\u00a0\u00bb parce qu&rsquo;il s&rsquo;agit d&rsquo;un courant d&rsquo;entra&icirc;nement qui surpasse les USA, et nous employons le mot \u00ab\u00a0suivi\u00a0\u00bb parce que les USA, en l&rsquo;occurrence, ne font effectivement que suivre sans rien concevoir ; en d&rsquo;autres mots, les USA sont tout entiers emport\u00e9e par le Syst\u00e8me, sa surpuissance, sa volont\u00e9 de nihilisme par la d\u00e9structuration et la dissolution.<\/p>\n<\/p>\n<p><p>A ce point, nous pr\u00e9sentons un texte de RT <a href=\"https:\/\/www.rt.com\/usa\/360317-carter-dunford-syria-russia-senate\/\">du 22 septembre<\/a> qui fait rapport de l&rsquo;audition devant la Commission des Forces Arm\u00e9es du S\u00e9nat, &ndash; commission pr\u00e9sid\u00e9e par McCain, avec Lindsay Graham dans ses rangs, et cela dit tout, &ndash; de la direction du Pentagone, le secr\u00e9taire \u00e0 la d\u00e9fense Ashley Carter et le pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9ta-major (JCS), le G\u00e9n\u00e9ral du Corps des Marines Dunford. L&rsquo;extr\u00e9misme aveugle, la pratique du mensonge, l&rsquo;irresponsabilit\u00e9, l&rsquo;esp\u00e8ce de bellicisme hallucin\u00e9 font de ces deux hommes la paire la plus catastrophique qu&rsquo;on ait vue \u00e0 la t\u00eate du Pentagone depuis la cr\u00e9ation de ce d\u00e9partement en 1947, &ndash; qualifi\u00e9e de cette sorte dans notre \u00ab\u00a0chapeau\u00a0\u00bb : &laquo; [le couple] <em>le plus inconsistant, le plus humainement d\u00e9grad\u00e9, <strong>le plus compl\u00e8tement inf\u00e9od\u00e9 au Syst\u00e8me qu&rsquo;on ait vu \u00e0 cette position<\/strong><\/em>. &raquo; Les deux hommes ont \u00e9t\u00e9 sp\u00e9cialement s\u00e9lectionn\u00e9s, chacun \u00e0 leur tour, pour remplacer l&rsquo;\u00e9quipe Hagel-Dempsey, faite de deux autres chefs qui avaient l&rsquo;habitude d\u00e9testable de penser par eux-m\u00eames et d&rsquo;avoir des positions s\u00e9rieuses. (Jusqu&rsquo;alors, effectivement, le Pentagone avait jou\u00e9 un r\u00f4le de frein dans la grande saga des guerres am\u00e9ricanistes depuis 9\/11, notamment en 2006-2008 pour emp\u00eacher une attaque de l&rsquo;Iran, avec le r\u00f4le des amiraux Fallon et Mullen notamment.)<\/p>\n<\/p>\n<p><p><strong>S\u00e9lectionn\u00e9s pour ob\u00e9ir sans broncher \u00e0 Obama, Carter-Dunford ob\u00e9issent sans broncher au Syst\u00e8me<\/strong>, quitte \u00e0 commettre des actes d&rsquo;insubordination parmi les plus flagrants de l&rsquo;histoire militaire US, comme on a vu ces derni\u00e8res semaines. (L&rsquo;insubordination est dans ce cas un acte de pure couardise puisqu&rsquo;il s&rsquo;agit en fait d&rsquo;ob\u00e9ir au Syst\u00e8me tandis que Kerry-Obama ont sembl\u00e9 un moment s&rsquo;en \u00e9carter, avant de vite revenir dans le rang, bien entendu.) Les choses sont parfaitement en place, avec chacun \u00e0 sa place, d\u00e9veloppant un concert gigantesque d&rsquo;irresponsabilit\u00e9s partag\u00e9es et crois\u00e9es, se renfor\u00e7ant les unes les autres, &ndash; pour un seul but obsessionnel, \u00ab\u00a0<em>Assad has to go<\/em>\u00ab\u00a0&#8230; (Nous avons nous-m\u00eames soulign\u00e9 de l&#8217;emploi de caract\u00e8res gras certains mots et passages qui nous semblent dignes d&rsquo;int\u00e9r\u00eat, dont certains seront utilis\u00e9s plus loin pour notre commentaire.)<\/p>\n<\/p>\n<p><p>&laquo; <em>Speaking to the US Senate, <strong>the Pentagon&rsquo;s leaders blamed Russia for the Aleppo aid convoy attack, but admitted they \u00ab\u00a0had no facts.\u00a0\u00bb Only US coalition planes should be allowed over Syria, they said, though that would require war against both Syria and Russia<\/strong>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Defense Secretary Ash Carter and General Joseph Dunford, Chairman of the Joint Chiefs of Staff, faced the Senate Armed Services Committee on Thursday to report on the ongoing military operations and \u00ab\u00a0national security challenges\u00a0\u00bb faced by the US. <\/em>[&#8230;] <em>The lawmakers were far less interested in the war against Islamic State (IS, formerly ISIS\/ISIL) than about the future of the Syrian government, Iran&rsquo;s \u00ab\u00a0malign influence,\u00a0\u00bb and \u00ab\u00a0aggression\u00a0\u00bb by China and Russia &ndash; all ranked far ahead of terrorism on Carter and Dunford&rsquo;s list of security challenges.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The Pentagon had \u00ab\u00a0no intention\u00a0\u00bb of sharing intelligence with Russia when it came to Syria, Dunford told the lawmakers unequivocally. Secretary Carter explained that the joint implementation councils envisioned by the ceasefire proposal negotiated in Geneva wouldn&rsquo;t share intelligence, just coordinate efforts &ndash; but that they were a moot point anyway, since the ceasefire was effectively dead.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Both the lawmakers and the Pentagon chiefs blamed that development on Russia, focusing on the alleged airstrike against the humanitarian convoy in east Aleppo while the US-led airstrike against the Syrian Army fighting IS in Deir ez-Zor went unmentioned. \u00ab\u00a0<strong>I don&rsquo;t have the facts<\/strong>,\u00a0\u00bb Dunford said, when asked about the convoy attack by Sen. Richard Blumenthal (D-Connecticut). \u00ab\u00a0It was either the Russians or the regime,\u00a0\u00bb he added. \u00ab\u00a0There is no doubt in my mind that the Russians are responsible,\u00a0\u00bb whether directly or because they backed the government in Damascus, Dunford said, describing the attack as \u00ab\u00a0an unacceptable atrocity.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Carter explained Dunford&rsquo;s logic in a response to Sen. Lindsey Graham (R-South Carolina), saying that \u00ab\u00a0the Russians are responsible for this strike whether they conducted it or not, because they took responsibility for the conduct of the Syrians by associating themselves with the Syrian regime.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The latest proposal by Secretary of State John Kerry involves grounding only Syrian and Russian airplanes, Carter told Sen. Jeanne Shaheen (D-New Hampshire). \u00ab\u00a0There can be no question of grounding US aircraft\u00a0\u00bb over Syria, he said, adding that US jets conduct their strikes \u00ab\u00a0<strong>with exceptional precision&hellip; that no other country can match<\/strong>.\u00a0\u00bbSen. Roger Wicker (R-Mississippi) asked about what it would take for the US to impose a no-fly zone over Syria, using the phrase \u00ab\u00a0control the airspace.\u00a0\u00bb \u00ab\u00a0Right now&hellip; for us to control all of the airspace in Syria <strong>would require us to go to war against Syria and Russia<\/strong>,\u00a0\u00bb Dunford replied, drawing a rebuke from committee chairman John McCain (R-Arizona), who argued a no-fly zone was possible without war.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Asked about the video of US-backed Syrian rebels insulting US Special Forces in Al-Rai and running them out of the northern Syrian town, Carter and Dunford shrugged it off. A \u00ab\u00a0<strong>very small minority<\/strong> took verbal action\u00a0\u00bb against US troops, said Dunford, who admitted <strong>he did not watch the video<\/strong> but had discussed it with US commanders. He said the incident was \u00ab\u00a0irrelevant\u00a0\u00bb because the US-backed forces and Turkey were making \u00ab\u00a0great progress\u00a0\u00bb along Syria&rsquo;s northern border.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>In their exchange with Graham, Carter and Dunford confirmed there is a plan to arm the Kurdish militia in Syria, over Turkish objections, as a way of advancing on the IS stronghold of Raqqa. Once Raqqa is taken, however, an Arab force would be required to hold it. \u00ab\u00a0We have a plan,\u00a0\u00bb Dunford said, but described it as \u00ab\u00a0not resourced.\u00a0\u00bbDunford agreed with Graham&rsquo;s assertion that the US had two objectives &ndash; to destroy IS and to \u00ab\u00a0remove Assad,\u00a0\u00bb referring to the Syrian president &ndash; but admitted the Kurds were not interested in the latter. \u00ab\u00a0If the main fighting force inside of Syria is not signed up to take Assad out, where does that force come from?\u00a0\u00bb Graham asked. <strong>Neither Dunford nor Carter had an answer to that<\/strong>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Both the Pentagon heads and the lawmakers agreed throughout the hearing that caps on military spending mandated by sequestration were harmful and needed to be repealed. Lack of funding posed a significant threat to readiness and maintenance, Carter and Dunford argued, before pointing out that the US military <strong>was still the strongest, most powerful and most competent in the world<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il y a dans ce compte-rendu un spectacle \u00e9difiant du simulacre qu&rsquo;impose le Syst\u00e8me. Tous les acteurs de la sc\u00e8ne sont sinc\u00e8res, y compris \u00e0 propos des mensonges, directs ou par omission, qu&rsquo;ils \u00e9changent et qui font partie convenue du th\u00e9\u00e2tre de leur complicit\u00e9. Ainsi ne dit-on pas un mot de l&rsquo;attaque de Deir ez-Zor, ce qui permet au secr\u00e9taire \u00e0 la d\u00e9fense Carter de nous assurer une fois de plus &laquo; <em>que les avions de combat US conduisent leurs attaques avec une extr\u00eame pr\u00e9cision&#8230;  qu&rsquo;aucune autre nation ne peut \u00e9galer<\/em> &raquo;, alors que Deir ez-Zor avait \u00e9t\u00e9 pr\u00e9sent\u00e9e comme une erreur de frappe de l&rsquo;USAF, &ndash; \u00e0 moins qu&rsquo;il s&rsquo;agisse d&rsquo;une \u00ab\u00a0erreur de haute pr\u00e9cision\u00a0\u00bb, qu'\u00a0\u00bbaucune autre nation ne peut \u00e9galer\u00a0\u00bb, &ndash; et puis non, apr\u00e8s tout, puisqu&rsquo;il a suffi, comme on vous l&rsquo;a dit, de ne pas parler de Deir ez-Zor, avec l&rsquo;aide empress\u00e9e et diligente de l&rsquo;in\u00e9galable duo McCain-Graham.<\/p>\n<\/p>\n<p><p>Malgr\u00e9 l&rsquo;extraordinaire complicit\u00e9 de toute cette bande, on ne parvient tout de m\u00eame pas \u00e0 dissimuler les impasses, comme lorsque Graham demande imprudemment avec quelle force l&rsquo;on parviendra enfin \u00e0 \u00eatre quitte d&rsquo;Assad-Hitler puisque les Kurdes, que les USA continuent \u00e0 armer fr\u00e9n\u00e9tiquement, sont pr\u00eats \u00e0 d\u00e9truire <em>Daesh<\/em> mais \u00ab\u00a0ne sont pas int\u00e9ress\u00e9s \u00e0 faire tomber Assad\u00a0\u00bb. Les comp\u00e8res de la \u00ab\u00a0machine militaire qui reste toujours la plus puissante et la plus comp\u00e9tente du monde\u00a0\u00bb, <strong>r\u00e9pondent platement qu&rsquo;\u00e0 vrai dire ils n&rsquo;ont pas de r\u00e9ponse \u00e0 cette question. Mimique ahurie de Carter tandis que le G\u00e9n\u00e9ral des Marines Dunford regarde les mouches voler.<\/strong> Il n&rsquo;y en eut pas un seul pour ajouter et pour clore ce d\u00e9bat aga\u00e7ant, qu&rsquo;apr\u00e8s tout, \u00ab\u00a0tout cela est de la faute des Russes\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Ce qui flottait dans cette salle pompeuse, aux lambris somptueux qui c\u00e9l\u00e8brent la vertu in\u00e9galable du S\u00e9nat des &Eacute;tats-Unis, c&rsquo;est une extraordinaire chape de plomb mena\u00e7ant d&rsquo;\u00e9craser tous ces moustiques jouant leur sc\u00e8ne pr\u00e9f\u00e9r\u00e9e : l&rsquo;\u00e9crasante chape de plomb du nihilisme, qui est la marque absolue de la dynamique qui emporte les &Eacute;tats-Unis dans le d\u00e9lire de l&rsquo;impuissance de leur puissance, ou de l&rsquo;hyperimpuissance de leur hyperpuissance. <strong>La tension ne cesse de monter en Syrie, certes, pour la ni\u00e8me fois d&rsquo;ailleurs, mais pour mieux nous exposer l&rsquo;extraordinaire vacuit\u00e9 des actes conduits par la \u00ab\u00a0nation exceptionnelle\u00a0\u00bb<\/strong>. Plus que jamais, il s&rsquo;agit d&rsquo;un tourbillon crisique dont nul ne sait le sens ni la raison d&rsquo;\u00eatre, et il nous para&icirc;t tr\u00e8s audacieux pour l&rsquo;instant d&rsquo;avancer que les \u00e9v\u00e9nements actuels pourraient avoir quoi que ce soit de d\u00e9cisif.<\/p>\n<\/p>\n<p><p>Dans ces conditions, peut-on parler de la possibilit\u00e9 d&rsquo;une Guerre Mondiale par le biais d&rsquo;un affrontement entre Russes et forces am\u00e9ricanistes, comme <a href=\"http:\/\/www.dedefensa.org\/article\/douguine-deir-ez-zor-et-la-troisieme-guerre-mondiale\">Douguine<\/a> en pr\u00e9sentait la possibilit\u00e9 ? L\u00e0 encore, on a vu la remarquable irresponsabilit\u00e9 se transformer en prudence froussarde dans le chef des dirigeants du Pentagone qui ne cessent pourtant de vanter la puissance de leurs forces et leur ma&icirc;trise de la situation en Syrie. R\u00e9pondant \u00e0 une question d&rsquo;un autre s\u00e9nateur imprudent (le r\u00e9publicain Wicker) sur l&rsquo;hypoth\u00e8se d&rsquo;une <em>no-fly zone<\/em>, Dunford assura en r\u00e9trop\u00e9dalant aussit\u00f4t que &laquo; <em>pour l&rsquo;instant, si nous voulons contr\u00f4ler tout l&rsquo;espace a\u00e9rien il nous faudra partir en guerre contre la Syrie et la Russie<\/em> &raquo;. (McCain n&rsquo;\u00e9tait pas d&rsquo;accord et le fit savoir, comme il est de coutume avec lui.) Il est manifeste que cette r\u00e9ponse contient implicitement une r\u00e9serve fondamentale, qui revient toujours entre les lignes dans ce genre d&rsquo;audition : \u00ab\u00a0il nous faudra partir en guerre contre la Russie et nous ne sommes pas pr\u00eats \u00e0 le faire&#8230;\u00a0\u00bb<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Puisque le Guerre Mondiale a d\u00e9j\u00e0 commenc\u00e9<\/h3>\n<\/p>\n<p><p>&#8230;Car enfin, posons encore une fois la question,  risque-t-on, oui ou non, la Troisi\u00e8me Guerre Mondiale ? Peut-\u00eatre monsieur Tarak Ahmad, Syrien, membre de l&rsquo;opposition l\u00e9gale \u00e0 Assad mais partisan du maintien du r\u00e9gime et de la souverainet\u00e9 syrienne, et qui donc se bat au c\u00f4t\u00e9 des forces r\u00e9guli\u00e8res syrienne avec ses huit mille hommes regroup\u00e9s en milices, peut-\u00eatre Ahmad d\u00e9tient-il la r\u00e9ponse. On en a le sentiment lorsqu&rsquo;il confie le <a href=\"https:\/\/sputniknews.com\/politics\/20160922\/1045602725\/wwiii-in-syria.html\">22 septembre 2016<\/a> \u00e0 <em>Sputnik.News<\/em>, en commentaire des derniers \u00e9v\u00e9nements en Syrie : <strong>\u00ab\u00a0Mais allons ! La Troisi\u00e8me Guerre mondiale a d\u00e9j\u00e0 commenc\u00e9&#8230;\u00a0\u00bb<\/strong><\/p>\n<\/p>\n<p><p>&laquo; <em>Syrian Social Nationalist Party representative Tarek Ahmad says that the war in Syria has reached a dead end, with the intervention of foreign powers turning the situation into a chaotic mess. Moreover, the politician says that Syria is just one front in a Third World War being waged by Washington and its allies<\/em>. [&#8230;] <em>\u00ab\u00a0The US&rsquo;s goal is not limited to Syria,\u00a0\u00bb the politician emphasized. \u00ab\u00a0The Syrian front is not the goal in and of itself. We need to look at this issue objectively, and to admit that a Third World War is taking place in Syria, one which is led by the US and its allies &ndash; even if these allies are simultaneously victims as well.\u00a0\u00bb \u00ab\u00a0America&rsquo;s main objective,\u00a0\u00bb according to Ahmad, &quot;is to bring any world power that threatens them under control. Consequently, <\/em>[Washington] <em>is waging a war with these powers; and these powers include China and Russia.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Effectivement, voil\u00e0 une fa\u00e7on d\u00e9cisive de r\u00e9pondre, en \u00e9vitant les r\u00e9f\u00e9rences aux sch\u00e9mas du pass\u00e9, si absolues et \u00ab\u00a0<em>unthinkable<\/em>\u00a0\u00bb puisqu&rsquo;ils conduisent en g\u00e9n\u00e9ral au conflit nucl\u00e9aire lorsqu&rsquo;on \u00e9voque l&rsquo;hypoth\u00e8se de la Guerre Mondiale. Il est par cons\u00e9quent essentiel de s&rsquo;entendre sur les mots :<strong> si l&rsquo;on veut baptiser la Grande Crise d&rsquo;effondrement du Syst\u00e8me \u00ab\u00a0Troisi\u00e8me Guerre mondiale\u00a0\u00bb, alors effectivement nous y sommes en plein, alors effectivement cette \u00ab\u00a0guerre\u00a0\u00bb-l\u00e0 est commenc\u00e9e et Tarak Ahmad a raison<\/strong>. Elle est alors n\u00e9cessairement multiforme et extraordinairement contrast\u00e9e, elle concerne un nombre tr\u00e8s grand de sujets, dont certains d&rsquo;entre eux ne sont pas d&rsquo;usage dans un tel classement ; pour tout dire, notre \u00ab\u00a0Guerre Mondiale\u00a0\u00bb en cours ne ressemble \u00e0 aucune des grandes guerres qui l&rsquo;a pr\u00e9c\u00e9d\u00e9e, et l\u00e0-dedans la Syrie &laquo; <em>est juste un front dans la Troisi\u00e8me Guerre Mondiale conduite par Washington et ses alli\u00e9s<\/em>&#8230; &raquo; <strong>L&rsquo;id\u00e9e de \u00ab\u00a0front\u00a0\u00bb, &ndash; un \u00ab\u00a0front parmi d&rsquo;autres, &ndash; est \u00e9videmment extr\u00eamement int\u00e9ressante pour la compr\u00e9hension de cette situation<\/strong>, tandis qu&rsquo;il reste \u00e0 d\u00e9battre avec un esprit critique pour savoir si cette \u00ab\u00a0Troisi\u00e8me Mondiale\u00a0\u00bb-l\u00e0 est vraiment livr\u00e9e \u00ab\u00a0par Washington et ses alli\u00e9s\u00a0\u00bb ; car l&rsquo;on conna&icirc;t \u00e0 suffisance les divisions existante entre \u00ab\u00a0alli\u00e9s\u00a0\u00bb et m\u00eame \u00e0 Washington, comme le montre la campane pr\u00e9sidentielle en cours, et si le conflit en cours prenait un tour plus affirm\u00e9 et plus brutal \u00e0 une occasion ou l&rsquo;autre il pourrait y avoir des surprises.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette id\u00e9e de la Syrie comme \u00ab\u00a0un front parmi d&rsquo;autres\u00a0\u00bb permet effectivement d&rsquo;incorporer d&rsquo;autres batailles en cours, comme la bataille soci\u00e9tale qui rel\u00e8ve du point fondamental de la d\u00e9structuration de la soci\u00e9t\u00e9 beaucoup plus que des obsessions psychanalytiques des uns et des autres. <strong>Nous retrouvons absolument notre sch\u00e9ma crisique<\/strong>, qu&rsquo;il s&rsquo;agisse de <a href=\"http:\/\/www.dedefensa.org\/article\/le-tourbillon-crisique-regne\">tourbillon crisique<\/a> ou de toute autre forme parmi celles qu&rsquo;on a d\u00e9j\u00e0 souvent explor\u00e9es (<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-facteur-crisique\">infrastructure crisique<\/a>, <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-la-chaine-crisique-ddecrisis\">cha&icirc;ne crisique<\/a>, etc.), tout cela regroup\u00e9 dans la crise haute, c&rsquo;est-\u00e0-dire la Grande Crise du Syst\u00e8me. Bien \u00e9videmment, les USA (Washington) jouent un r\u00f4le central, avec le bloc-BAO en bandouill\u00e8re, \u00e9tant le c&oelig;ur m\u00eame du Syst\u00e8me et s&rsquo;\u00e9tant retrouv\u00e9s, en quelques ann\u00e9es sous la pr\u00e9sidence d&rsquo;Obama, la force la plus avanc\u00e9e sur la voie du nihilisme. <strong>La transformation de Clinton en une candidate du nihilisme, comme elle ne cesse de plus en plus de s&rsquo;affirmer, est un autre point remarquable qui enrichit le concept selon lequel nous somme bien au c&oelig;ur de notre \u00ab\u00a0Guerre Mondiale\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>On observe alors, avec ces divers exemples et r\u00e9f\u00e9rences, que nous nous rapprochons de l&rsquo;autre centre bouillonnant de la Grande Crise, avec la Syrie : les \u00e9lections pr\u00e9sidentielles aux USA. Ainsi sommes-nous conduits \u00e0 envisager une grande question strat\u00e9gique, concernant cette Troisi\u00e8me Guerre Mondiale en cours, qui est la question de la r\u00e9union des deux principaux fronts :<strong> une connexion se fera-t-elle entre les deux fronts, entre le \u00ab\u00a0front syrien\u00a0\u00bb et le \u00ab\u00a0front USA-2016\u00a0\u00bb ?<\/strong> En d&rsquo;autres mots, la situation syrienne, avec le r\u00f4le pr\u00e9cipit\u00e9 et nihiliste qu&rsquo;y jouent les USA, deviendra-t-elle un sujet de pol\u00e9mique et de controverse entre Trump et Clinton ?<\/p>\n<\/p>\n<p><p>On n&rsquo;a pas \u00e9t\u00e9 sans remarquer, &ndash; du moins devrait-on, selon nous, &ndash; une intervention extr\u00eamement r\u00e9cente du G\u00e9n\u00e9ral Michael Flynn, dont nous avons d\u00e9j\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article\/flynn-en-mode-turbo\">beaucoup parl\u00e9<\/a> sur ce site et qui tient une place importante de conseiller de s\u00e9curit\u00e9 nationale aupr\u00e8s de Donald Trump. Dans une intervention publique dans le cours de la campagne (voir <em>Infowars.com<\/em>, <a href=\"http:\/\/www.infowars.com\/general-warns-hillary-is-psychotic\/\">le 22 septembre<\/a>), Flynn a affirm\u00e9 que <strong>Clinton \u00e9tait \u00ab\u00a0dans l&rsquo;incapacit\u00e9 d&rsquo;\u00eatre pr\u00e9sidente\u00a0\u00bb \u00e0 cause de ses \u00ab\u00a0troubles psychotiques\u00a0\u00bb<\/strong>. L&rsquo;homme qui affirme cela a \u00e9t\u00e9 en contacts professionnels avec Clinton pendant largement plus d&rsquo;une ann\u00e9e, d&rsquo;abord en 2011 comme l&rsquo;un des adjoints au DNI (<em>Director, National Intelligence<\/em>), puis comme directeur de la DIA du Pentagone (<em>Defense Intelligence Agency<\/em>) \u00e0 partir d&rsquo;avril 2012. Flynn eut notamment \u00e0 intervenir en ce qui concerne la Syrie et l&rsquo;attitude de la Maison-Blanche, notamment la \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/lhyperimpuissance-us-en-mode-turbo\">narrative<\/a><\/em> <a href=\"http:\/\/www.dedefensa.org\/article\/de-hersh-a-flynn-une-revolte-des-generaux\">imp\u00e9n\u00e9trable<\/a>\u00a0\u00bb qu&rsquo;elle opposa \u00e0 toutes ses tentatives de faire parvenir au pr\u00e9sident et \u00e0 ses conseillers les analyses de la DIA annon\u00e7ant la cr\u00e9ation de <em>Daesh<\/em> du fait de la \u00ab\u00a0politique\u00a0\u00bb suivie par les USA, est d\u00e9sormais un \u00e9pisode fameux ; il est \u00e9vident que Clinton eut, vis-\u00e0-vis d la DIA et de Flynn, la m\u00eame attitude.<\/p>\n<\/p>\n<p><p>L&rsquo;article du <em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Michael_T._Flynn\">Wikip\u00e9dia<\/a><\/em> consacr\u00e9 \u00e0 Flynn est \u00e0 recommander comme un monument de d\u00e9sinformation, de m\u00e9sinformation, sinon d&rsquo;excr\u00e9ments-information. Cet effort particulier de diffamation o&ugrave; Flynn est quasiment d\u00e9sign\u00e9, au travers de citations choisies, comme un agent russe, mesure la crainte du Syst\u00e8me de voir cet officier, avec son exp\u00e9rience concernant Clinton et la Syrie, entrer dans l&rsquo;ar\u00e8ne politique, dans tous les cas indirectement, en servant de guide et d&rsquo;informateur pour Trump sur des sujets o&ugrave; il est particuli\u00e8rement bien inform\u00e9. Avec les \u00e9v\u00e9nements syriens prenant le tour qu&rsquo;on leur voit, il n&rsquo;est pas du tout impossible, effectivement, que la question vienne au premier plan, &ndash; par exemple, d\u00e8s le d\u00e9bat t\u00e9l\u00e9vis\u00e9 Clinton contre Trump de lundi prochain. <strong>Les deux \u00ab\u00a0fronts\u00a0\u00bb pourraient alors \u00eatre r\u00e9unis par le fait m\u00eame de la communication, et un d\u00e9bat sur la \u00ab\u00a0politique\u00a0\u00bb US en Syrie pourrait s&rsquo;ouvrir \u00e0 l&rsquo;\u00e9cho public aux USA m\u00eame, dans un pays d\u00e9j\u00e0 survolt\u00e9 et parcouru par des tensions consid\u00e9rables. <\/strong>Ainsi parviendrait-on \u00e0 donner \u00e0 la \u00ab\u00a0Guerre Mondiale d\u00e9j\u00e0 en cours\u00a0\u00bb un sens absolument universel, rapprochant tous les sujets qui la composent et permettant une description encore plus pr\u00e9cise de notre Grande Crise g\u00e9n\u00e9rale hors de tous les sch\u00e9mas convenus que certains continuent \u00e0 solliciter pour tenter de comprendre notre \u00e9poque absolument tellurique.  <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, nihilisme-turbo 23 septembre 2016 &ndash; Nous aurions voulu commencer ce \u00ab\u00a0F&#038;C\u00a0\u00bb par un texte exposant avec une logique implacable, fortement document\u00e9e dans ce sens, que la seule issue \u00e0 la crise actuelle, \u00e0 la Grande Crise pour notre compte, est la destruction des USA, &ndash; la destruction du Syst\u00e8me, pour notre compte l\u00e0 encore.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[934,3032,2926,2645,3851,3867,5630,2639,12538],"class_list":["post-76798","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-clinton","tag-dia","tag-flynn","tag-guerre","tag-mondiale","tag-syrie","tag-troisieme","tag-trump","tag-usa-2016"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76798"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76798\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}