{"id":76852,"date":"2016-10-21T18:42:33","date_gmt":"2016-10-21T18:42:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/10\/21\/cry-for-yourself-america\/"},"modified":"2016-10-21T18:42:33","modified_gmt":"2016-10-21T18:42:33","slug":"cry-for-yourself-america","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/10\/21\/cry-for-yourself-america\/","title":{"rendered":"<em>Cry For Yourself, America<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Cry For Yourself, America<\/em><\/h2>\n<\/p>\n<p><p>21 octobre 2016 &ndash; &laquo; Vous \u00eates pratiquement en train de pleurer ! Vous \u00eates pratiquement en train de pleurer ! &raquo; (&laquo; <em>You&rsquo;re practically crying. You&rsquo;re practically crying<\/em> &raquo;), &ndash; s&rsquo;exclame, exc\u00e9d\u00e9, William Scarborough s&rsquo;adressant \u00e0 William Kristol en train de geindre&#8230; Kristol se d\u00e9cha&icirc;ne, mais plut\u00f4t passivement, comme on se laisse emporter,  parce que clame-t-il toute la presse et la TV US, ce qu&rsquo;on nomme la presse-Syst\u00e8me bien entendu, et notamment la station hyper-bobo, tr\u00e8s-progressiste type-Clinton MSNBC o&ugrave; on le re\u00e7oit, a d\u00e9roul\u00e9 un tapis rouge sous les pieds avantageux de Donald Trump, qu&rsquo;elle l&rsquo;a donc favoris\u00e9 outrageusement, &ndash; extraordinaire et \u00e9trange jugement d&rsquo;un Kristol transport\u00e9 d&rsquo;une sainte-fureur&#8230; <a href=\"http:\/\/www.breitbart.com\/video\/2016\/10\/20\/watch-kristol-scarborough-have-heated-exchange-over-morning-joe-trump-coverage\/\">Regardez toute la sc\u00e8ne<\/a> datant de mercredi soir, avec les intervenant, Kristol donc, gourou des <em>neocons<\/em> avec son <em>Weekly Standard<\/em>, Scarborough, le pr\u00e9sentateur-vedette de MSNBC, et avec lui Mika Brzezinski, &ndash; exactement, la fille de son p\u00e8re, &ndash; quasi-<em>alter-ego<\/em> de Scarborough \u00e0 MSNBC.<\/p>\n<\/p>\n<p><p>Les deux, Scarborough et Mika, ont \u00e0 \u00ab\u00a0g\u00e9rer\u00a0\u00bb comme l&rsquo;on dit, une quasi-<em>nervous breakdown<\/em> du susdit-Kristol, absolument, paroxystiquement d\u00e9cha&icirc;n\u00e9 devant la promotion que la presse-Syst\u00e8me a faite du <em>The-Donald<\/em>. C&rsquo;est bien cela l&rsquo;affaire, vous avez bien lu, la presse-Syst\u00e8me acquise \u00e0 119% \u00e0 Hillary, accus\u00e9e de faire tant de gr\u00e2ce et salamalecs \u00e0 <em>The-Donald<\/em>. (Dans les faits bruts, on comprend l&rsquo;attaque,  selon la logique-fric expos\u00e9e dans ce m\u00eame <em>Journal-dde.crisis<\/em>, <a href=\"http:\/\/www.dedefensa.org\/article\/le-4eme-pouvoir-de-lex-4eme-pouvoir\">le 6 mai dernier<\/a> ; mais qui ne peut comprendre que cela n&rsquo;implique en rien une pr\u00e9f\u00e9rence, et que tout ce temps consacr\u00e9 \u00e0 Trump parce que c&rsquo;est un \u00e9v\u00e9nement public et \u00ab\u00a0vendeur\u00a0\u00bb est ponctu\u00e9 de diffamations, de montages et d&rsquo;insultes ?) L&rsquo;\u00e9change vaut d&rsquo;\u00eatre vu, et m\u00eame d&rsquo;\u00eatre retranscrit au moins en partie, simplement pour avoir une id\u00e9e de son intensit\u00e9, de la force du paroxysme de l&rsquo;hyst\u00e9rie psychologique, o&ugrave; d&rsquo;ailleurs les deux journalistes se trouvent \u00e0 certains moments aussi emport\u00e9s que leur invit\u00e9. J&rsquo;en donne la transcription, simplement pour l&rsquo;atmosph\u00e8re, la tension de la chose, et aussi pour l&rsquo;illustration de cette tension qu&rsquo;offre le contenu de l&rsquo;affrontement o&ugrave; l&rsquo;on s&rsquo;insulte pratiquement (\u00ab\u00a0Vous mentez. S&rsquo;il vous pla&icirc;t, ne venez pas \u00e0 mon \u00e9mission pour mentir [&laquo; <em>You lied. Please don&rsquo;t come on my air and lie<\/em>. &raquo;]) ; ayez aussi et surtout \u00e0 l&rsquo;esprit qu&rsquo;il s&rsquo;agit de gens du m\u00eame camp (pro-Clinton) et que tout leur dit, statistiquement et par leur conviction m\u00eame, que leur h\u00e9ro\u00efne l&#8217;emportera&#8230;<\/p>\n<\/p>\n<p><p>(Si vous trouvez cela trop long, passez la transcription pour la suite du commentaire. Je renouvelle pourtant l&rsquo;explication que cette transcription a sa place ici parce que, par sa densit\u00e9, sa rapidit\u00e9, elle constitue une tr\u00e8s bonne illustration du commentaire qui suit, et donc effectivement elle est chronologiquement \u00e0 sa place.)<\/p>\n<\/p>\n<p><p>***<\/p>\n<\/p>\n<p><p>(N.B : \u00ab\u00a0<em>fluke<\/em>\u00a0\u00bb signifie \u00ab\u00a0hasard\u00a0\u00bb, difficilement traduisible en fran\u00e7ais dans le cas pr\u00e9sent. Kristoll veut donc dire que Trump est arriv\u00e9 l\u00e0 o&ugrave; il est par hasard, sans que rien de politique ne soit fait dans ce sens ; Trump c&rsquo;est une chose, si l&rsquo;on veut aller au terme de la pens\u00e9e, un \u00ab\u00a0objet non identifi\u00e9\u00a0\u00bb, et c&rsquo;est \u00e0 cela que MSNBC, poursuit Kristoll en pleurant semble-t-il, a accord\u00e9 tant d&rsquo;importance en terme de temps d&rsquo;antenne&#8230;)<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I think something happened that would make some people leave Donald Trump. I don&rsquo;t like&#8230; yes, on style points, style was a little better in the first 30 minutes and he had a couple clever insults but that&rsquo;s not the point. The headline out of this debate is obviously the failure to say ahead of time that you will accept the results of the democratic election in America. Pretty unprecedented. Doesn&rsquo;t mean that there&rsquo;s going to be violence in the streets, certainly not in others now say who cares what Donald Trump says. He&rsquo;s going to be a failed fluke presidential candidate and he should be ignored on election night and Republicans need so say that<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>Failed fluke?<\/em><\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>Yes. he won the nomination in a flukey way<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>Your people nominated him. That&rsquo;s not a fluke<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I hope it was a fluke<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>He beat 16 people. The Republican party nominated him<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>Some Republicans refuse to support him and he&rsquo;s going to lose the general election<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>It&rsquo;s not a fluke<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I think it was a fluke in some ways<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>A fluke is something no one expected<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>Ok fine the Republican party&#8230; does that make you feel better about it?<\/em><\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>Yes<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>You feel great because the Republican party nominated a guy who is really a bad guy as president and you think it&rsquo;s funny and amusing<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>No, I actually think Republicans need to come clean on themselves<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>What does come clean on themselves mean?<\/em><\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>Just be honest about what&rsquo;s right and wrong<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>What&rsquo;s wrong is Donald Trump. This show&#8230; this show was very tough&#8230; this show was really tough on Trump in late 2015 and early 2016<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>We were<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>Are you going to pretend that<\/em>&#8230;<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: We were.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>If that&rsquo;s your way&#8230;<\/em><\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>He wouldn&rsquo;t answer a question. Do you mean when he peppered him&#8230;<\/em><\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>A lot of people &ndash; a lot of people accommodated Donald Trump at different times. I&rsquo;m not going to get into it<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>You just did. You lied. Please don&rsquo;t come on my air and lie. You said in late &rsquo;15 early December&#8230; I can&rsquo;t even believe you are doing this, I don&rsquo;t know why you are so bitter<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I&rsquo;m not bitter. I&rsquo;m trying to say that Republicans&#8230;<\/em><\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>You&rsquo;re practically crying. You&rsquo;re practically crying.<\/em><\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I am upset about this election<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>Early December&#8230; in early December 2015 we compared it to Germany 1933 what he was doing<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>Really? You treated him that way when he called in, is that right?<\/em><\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>We treated him tough<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>You asked the most tough questions<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>We did.<\/em><\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>We don&rsquo;t need to get into this<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>It&rsquo;s too late. You&rsquo;re bitter &mdash; you come on here practically crying, we have it on tape, you&rsquo;re screaming at Mika<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I&rsquo;m fine<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>Why is Paul Ryan, why are Mitch McConnell&#8230;<\/em><\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>That&rsquo;s what I was going to say<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>Don&rsquo;t attack us<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>I&rsquo;m not attacking you<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>Why is Paul Ryan still endorsing? Why does Mitch McConnell still endorse him? By the way, while you are attacking me personally I said from the beginning I would never vote for him.I said I was voting for Jeb Bush and I said I was voting for John Kasich. Then we said after the Muslim ban that this is what Germany looked like in 1933. So i don&rsquo;t know.<\/em><\/p>\n<\/p>\n<p><p><strong><em>Brzezinski<\/em><\/strong> : <em>Sorry if we were easy on him<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Scarborough <\/em><\/strong>: <em>If comparing him to Hitler in 1933 is going easy on him&#8230; that was three months before anybody voted, then we were easy on him<\/em>.<\/p>\n<\/p>\n<p><p><strong><em>Kristol<\/em><\/strong> : <em>If you behaved in a great way more power to you<\/em>.<\/p>\n<\/p>\n<p><p>***<\/p>\n<\/p>\n<p><p>&#8230; Ce n&rsquo;est pas du fond de cet \u00e9change dont je veux parler, bien entendu, mais du paroxysme hyst\u00e9rique de la psychologie qu&rsquo;on y distingue. Kristol est \u00e9videmment tout l&rsquo;objet de mon attention \u00e0 cet \u00e9gard, mais qu&rsquo;on r\u00e9alise bien qu&rsquo;il n&rsquo;est pas le seul dans cet \u00e9tat lorsque vous songez, par exemple, \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article\/la-folle-de-lonu\">une Power \u00e0 l&rsquo;ONU<\/a>. Il faut \u00e9galement avoir \u00e0 l&rsquo;esprit que Kristol dispose d&rsquo;une influence qui ne se d\u00e9ment pas malgr\u00e9 15-20 ann\u00e9es tr\u00e8s visible et r\u00e9f\u00e9renc\u00e9e o&ugrave; cet homme n&rsquo;a cess\u00e9 de se tromper, de recommander des initiatives absurdes, de faire des analyses qui sont autant de <em>narrative<\/em> dans le virtualisme, de vivre et de p\u00e9rorer dans le monde parall\u00e8le deWashington D.C., etc. ; notez bien que je ne dis pas une seconde qu&rsquo;il a \u00e9t\u00e9 un menteur ou qu&rsquo;il a \u00e9t\u00e9 insinc\u00e8re, car je le crois de la meilleure foi du monde, et \u00e0 aucun moment n&rsquo;exprimant pas ce qu&rsquo;il croit, qu&rsquo;il juge raisonnable et rationnel, etc. Cet homme est un exemple un peu plus voyant parmi des milliers d&rsquo;autres qui sont tous des zombies-Syst\u00e8me, d&rsquo;un comportement qui n&rsquo;est en aucune fa\u00e7on, ni \u00e9labor\u00e9, ni machiav\u00e9lique, ni bien entendu de type \u00ab\u00a0complotiste\u00a0\u00bb dans le sens premier du terme.<\/p>\n<\/p>\n<p><p>(Un \u00ab\u00a0complot\u00a0\u00bb est, au sens premier et imp\u00e9ratif, une &laquo; <em>entreprise en pr\u00e9paration form\u00e9e secr\u00e8tement entre deux ou plusieurs personnes<\/em> <em>contre l&rsquo;int\u00e9r\u00eat d&rsquo;un \u00e9tat, d&rsquo;un groupe de personnes ou une personne<\/em>. &raquo; Il n&rsquo;y a jamais eu cela chez les <em>neocons<\/em> dans le cas de Kristol, et chez les autres, tous les autres, bien qu&rsquo;on leur ait beaucoup pr\u00eat\u00e9 \u00e0 cet \u00e9gard ; il n&rsquo;y a pas \u00ab\u00a0complot\u00a0\u00bb dans un lieu de pouvoir, &ndash; Washington D.C., &ndash; o&ugrave; tout le monde pense la m\u00eame chose en diff\u00e9rant seulement sur la m\u00e9thode ou la chronologie, l&rsquo;exprime \u00e0 ciel ouvert, essaie de faire avancer sa conception op\u00e9rationnelle sans s&rsquo;en dissimuler une seconde. D&rsquo;ailleurs, les trois qui s&rsquo;algaradent de la sorte, Kristol, Scarborough et Brzezinski, sont tous trois d&rsquo;accord sur le fond, notamment sur ce qu&rsquo;il faut penser de Trump pour le cas.)<\/p>\n<\/p>\n<p><p>Ce que vous voyez dans ce segment extr\u00eamement significatif et symbolique, et pour cela je m&rsquo;y arr\u00eate, c&rsquo;est un d\u00e9bat hyst\u00e9rique autant par la tension psychologique que par la formidable <em>narrative<\/em> pr\u00e9tendant cr\u00e9er une r\u00e9alit\u00e9 fantasmagorique, pure <em>Fantasy<\/em>, o&ugrave; il se d\u00e9veloppe (Trump-Hitler, 1933-2016) ; d\u00e9bat hyst\u00e9rique entre trois psychologies \u00e9galement \u00e9puis\u00e9es par leur pathologie commune, &ndash; en effet, les deux qui n&rsquo;ont pas l&rsquo;air de l&rsquo;\u00eatre sont \u00e9galement touch\u00e9es, &ndash; avec l&rsquo;une des trois, la plus \u00e9puis\u00e9e donc la plus vuln\u00e9rable, qui attire toute l&rsquo;attention en s&rsquo;effondrant en une crise de nerfs \u00e0 peine contenue et qui ferait presque para&icirc;tre les deux autres raisonnables. Il n&rsquo;y a aucune pens\u00e9e l\u00e0-dedans, aucun argument, rien que des tensions psychologiques diff\u00e9remment exprim\u00e9es, autour d&rsquo;un m\u00eame sujet qui est une m\u00eame consigne : a-t-on ou n&rsquo;a-t-on pas trop pr\u00eat\u00e9 d&rsquo;attention \u00e0 la chose (Trump-<em>fluke<\/em>) ? A-t-on ou n&rsquo;a-t-on pas accompli ce qui est quasiment, pour chacun des trois, le devoir civique de traiter Trump comme il doit l&rsquo;\u00eatre, c&rsquo;est-\u00e0-dire en l&rsquo;excommuniant absolument et sans retour, en le faisant Trump-Hitler ?<\/p>\n<\/p>\n<p><p>(<strong>Je parle absolument du \u00ab\u00a0devoir civique\u00a0\u00bb, et intentionnellement de \u00ab\u00a0devoir civique\u00a0\u00bb pour appuyer sur leur franchise et leur sens quasi-terroris\u00e9 du devoir, par rapport \u00e0 ce que je nomme le Syst\u00e8me, qui enveloppe absolument toutes ces pens\u00e9es et p\u00e8se de tout son poids sur ces psychologies<\/strong>. Sur ce point, qui fait l&rsquo;essentiel du propos, je veux apporter une pr\u00e9cision de circonstances qui, hier soir, m&rsquo;a d\u00e9cid\u00e9 \u00e0 \u00e9crire ce texte dans le sens o&ugrave; je l&rsquo;\u00e9cris. J&rsquo;ai revu, enregistr\u00e9 de <em>Arte<\/em> du 19 au soir, le <em>Danton<\/em> de Andrzej Wajda, et <strong>nullement, en aucune fa\u00e7on avec <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Danton_(film,_1983)\">l&rsquo;&oelig;il de 1983<\/a><\/strong> (*) qui en fait notamment, \u00e0 c\u00f4t\u00e9 d&rsquo;une &oelig;uvre que je ressens comme d&rsquo;une v\u00e9rit\u00e9 historique \u00e9blouissante et d&rsquo;au-del\u00e0 de l&rsquo;historien courant et \u00ab\u00a0s\u00e9rieux\u00a0\u00bb, une parabole pour illustrer la situation d&rsquo;alors en Pologne apr\u00e8s le \u00ab\u00a0coup\u00a0\u00bb de Jaruzelski contre <em>Solidarnosc<\/em>. Dira-t-on \u00ab\u00a0dr\u00f4le de rapprochement-comparaison\u00a0\u00bb ? Ce que j&rsquo;ai vu essentiellement dans ce film magnifique, ce sont les agitations des divers acteurs-figurants de la R\u00e9volution, leurs querelles de morts-vivants, d\u00e9j\u00e0 zombies-Syst\u00e8me \u00e0 peine avant l&rsquo;heure, leurs marches diverses mais in\u00e9luctables vers la mort, mais comme marionnettes toutes semblables, \u00e9cras\u00e9es par le poids de cette entit\u00e9 qu&rsquo;est la R\u00e9volution, pr\u00e9figuration du Syst\u00e8me ou d\u00e9j\u00e0 le Syst\u00e8me lui-m\u00eame dans ses premiers \u00e9lans. (**) [Quelle justesse du mot de Maistre, et quelle belle illustration dans ce film : &laquo; <em>Les sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement. <\/em>&raquo;]  Certes, rien \u00e0 voir dans les circonstances, les mots, les lieux, les comportements, les id\u00e9ologies, les caract\u00e8res, les personnalit\u00e9s, etc., avec la sc\u00e8ne dont je parle ici <strong>sinon, et c&rsquo;est pour moi l&rsquo;essentiel, cette proximit\u00e9 de la masse et de la force \u00e9crasante qui les emprisonne tous<\/strong>, &ndash; car nos trois lascars de MSNBC, m\u00eame si de \u00ab\u00a0nuances\u00a0\u00bb diff\u00e9rentes, etc., sont du m\u00eame et seul parti, certains disent le \u00ab\u00a0parti de la guerre\u00a0\u00bb, c&rsquo;est-\u00e0-dire le parti du Syst\u00e8me. Dans <em>Danton<\/em>, la Terreur est celle du sang de la guillotine de la R\u00e9volution et des pressions qu&rsquo;elle exerce sur les psychologies avant de trancher les t\u00eates, sur le plateau de MSNBC la Terreur est celle de la communication-Syst\u00e8me et des pressions qu&rsquo;elle exerce sur les psychologies sans trancher les t\u00eates. Je parle ainsi de l&rsquo;effet similaire sur les psychologies.)<\/p>\n<\/p>\n<p><p>Certes, si vous regardez ce d\u00e9bat sans \u00eatre inform\u00e9, non pas du fond du d\u00e9bat mais de la r\u00e9f\u00e9rence universelle dans ce lieu de Washington D.C. qui l&rsquo;enveloppe et le conditionne absolument, vous pouvez le trouver effectivement tr\u00e8s \u00e9chauff\u00e9, tr\u00e8s enfi\u00e9vr\u00e9 et un peu \u00e0 la limite du contr\u00f4le de soi (pour Kristol), mais nullement marqu\u00e9 du sceau d&rsquo;une sorte de folie ; or, c&rsquo;est bien le cas, c&rsquo;est absolument le cas selon ma profonde conviction, qu&rsquo;il y a le sceau d&rsquo;une sorte de folie, au sens pathologique, dans ce d\u00e9bat, avec la r\u00e9f\u00e9rence universelle qui y pr\u00e9side. (C&rsquo;est moins visible que dans le <em>Danton<\/em>, certes, mais le signe de cette folie \u00e9merge par instant, lorsque par exemple Trump est mis sur le m\u00eame pied qu&rsquo;Hitler-1933, ce qui est un signe de l&rsquo;agression catastrophique que subissent les pens\u00e9es impliqu\u00e9es du fait de la pathologie de leurs psychologies \u00e9puis\u00e9es.)<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est cela qui importe, puisque par ailleurs vous n&rsquo;y trouvez selon moi nul cynisme, aucune construction mensong\u00e8re, aucune man&oelig;uvre malveillante de l&rsquo;esprit ; en effet, l\u00e0 encore parle ma profonde conviction, forg\u00e9e par 15-20 ann\u00e9es (gardons cette r\u00e9f\u00e9rence temporelle) d&rsquo;appr\u00e9ciation et de perception de leur comportement de plus en plus visible et \u00e9vident, en \u00e9volution tr\u00e8s rapide durant cette s\u00e9quence de temps \u00e0 mesure de l&rsquo;\u00e9puisement de leurs psychologies, jusqu&rsquo;au paroxysme d&rsquo;aujourd&rsquo;hui. La seule interrogation qui reste ouverte dans ma conviction c&rsquo;est, chaque fois que je rencontre un de ces moments qui montre un paroxysme encore augment\u00e9e, toujours plus fort, plus d\u00e9cha&icirc;n\u00e9, <strong>de chercher \u00e0 deviner, \u00e0 distinguer si l&rsquo;on se trouve enfin au Moment pur, celui du paroxysme final qui va rencontrer et se transmuter, peut-\u00eatre en participant \u00e0 sa manufacture parce qu&rsquo;il en est l&rsquo;enfant, dans le Moment de cet \u00ab\u00a0\u00e9v\u00e9nement cosmique\u00a0\u00bb que nous attendons. (&laquo; <em><a href=\"http:\/\/www.dedefensa.org\/article\/humeur-de-crise-25\">Nous attendons un \u00e9v\u00e9nement cosmique<\/a><\/em>. &raquo;)<\/strong><\/p>\n<\/p>\n<p><p>Il me faut insister et r\u00e9p\u00e9ter que, malgr\u00e9 l&rsquo;apparence et l&rsquo;\u00e9vidence \u00e0 la fois de la s\u00e9quence, il ne s&rsquo;agit pas du seul Kristol. Dans mon propos, je le r\u00e9p\u00e8te apr\u00e8s l&rsquo;avoir dit accessoirement, les trois se trouvent <strong>sous la m\u00eame influence qui les d\u00e9passe et les soumet \u00e0 la fois<\/strong>, m\u00eame s&rsquo;ils paraissent avoir des comportements si diff\u00e9rents, Kristol qui perd tout contr\u00f4le de soi et les deux autres r\u00e9agissant en g\u00e9n\u00e9ral d&rsquo;une fa\u00e7on rationnelle avec une vivacit\u00e9 qu&rsquo;explique justement le comportement de Kristol. <strong>Ma conviction est certes qu&rsquo;ils sont tous trois sous la pression de cette m\u00eame influence, comme sont tous ces gens dont nous parlons lorsque nous parlons de ce lieu maudit o&ugrave; tr\u00f4ne le Syst\u00e8me qu&rsquo;est Washington D.C.<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>(Certains \u00e9chappent \u00e0 la mal\u00e9diction, sans nul doute, comme c&rsquo;est le cas lorsqu&rsquo;une bataille se livre, parce que c&rsquo;est bien le cas dans notre \u00e9poque toute enti\u00e8re livr\u00e9e \u00e0 sa mal\u00e9diction ; certains, &ndash; ma coutume est de les d\u00e9signer antiSyst\u00e8me, &ndash; luttent \u00e0 divers degr\u00e9s de capacit\u00e9 et de lucidit\u00e9, donc avec efficacit\u00e9, contre la pression qu&rsquo;exerce sur leurs psychologies cette mal\u00e9diction. C&rsquo;est tout ce qui fait que ce temps est celui de la Trag\u00e9die Absolue, \u00e0 c\u00f4t\u00e9 d&rsquo;\u00eatre, par la ruse terrible du Diable, \u00e9galement le temps de la \u00ab\u00a0trag\u00e9die-bouffe\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Mon intuition est que nous ne sommes plus tr\u00e8s loin de ce \u00ab\u00a0Moment pur\u00a0\u00bb dont je parle plus haut, sans que je sache s&rsquo;il s&rsquo;agit vraiment d&rsquo;une intuition ou bien d&rsquo;une esp\u00e9rance trop vite per\u00e7ue comme une intuition. <strong>Je ne peux en dire plus \u00e0 cet \u00e9gard<\/strong>, parce que l&rsquo;intuition est aussi une \u00e9nigme, une \u00e9preuve initiatique \u00e0 chaque fois recommenc\u00e9e, \u00e0 laquelle l&rsquo;esprit doit se soumettre.<\/p>\n<\/p>\n<p><p>Peut-\u00eatre, sans doute et m\u00eame certainement, certains jugeront-ils que c&rsquo;est faire fort grand cas d&rsquo;un cas finalement assez anodin et relevant plut\u00f4t de l&rsquo;anecdotique plaisant. Selon mon jugement, en juger ainsi c&rsquo;est s&rsquo;en tenir \u00e0 l&rsquo;\u00e9cume de l&rsquo;apparence comme l&rsquo;on parle de l'\u00a0\u00bb\u00e9cume du jour\u00a0\u00bb. Au contraire, cette sc\u00e8ne, &ndash; il y en a beaucoup du genre dans le syst\u00e8me de la communication de la presse-Syst\u00e8me aux USA par les temps qui courent \u00e0 une telle vitesse, &ndash; cette sc\u00e8ne est <strong>un signe de l&rsquo;extraordinaire surpuissance du Syst\u00e8me qui p\u00e8se sur toutes ces agitations, des soubresauts monstrueux de cette surpuissance soumise \u00e0 son \u00e9preuve ultime, sa propre \u00e9preuve qu&rsquo;elle s&rsquo;impose \u00e0 elle-m\u00eame<\/strong>. Je ne peux plus me d\u00e9partir de cette conviction formidable que nous affrontons l&rsquo;\u00e9preuve ultime, et qu&rsquo;elle nous est impos\u00e9e par la fureur et l&#8217;embrasement de forces qui nous d\u00e9passent, dont le Syst\u00e8me lui-m\u00eame mais comme une force parmi d&rsquo;autres et contre d&rsquo;autres. Cette fureur et cet embrasement qui exacerbent nos psychologies alimentent irr\u00e9sistiblement nos d\u00e9sordre et notre chaos, et nous guettons avec fi\u00e8vre et angoisse, et avec la n\u00e9cessit\u00e9 qui interdit de ne rien faire d&rsquo;autre que de l&rsquo;attendre et de l&rsquo;esp\u00e9rer malgr\u00e9 la souffrances qu&rsquo;il nous promet parce que sans cela nous sombrerons dans le n\u00e9antissement, &ndash; nous guettons la survenue de ce \u00ab\u00a0Moment pur\u00a0\u00bb comme annonciateur de \u00ab\u00a0l&rsquo;\u00e9v\u00e9nement cosmique\u00a0\u00bb&#8230; <strong>Ce \u00ab\u00a0Moment pur\u00a0\u00bb o&ugrave; le Temps n&rsquo;a plus qu&rsquo;une seule fonction, celle de s&rsquo;arr\u00eater \u00e0 cet \u00ab\u00a0\u00e9v\u00e9nement cosmique\u00a0\u00bb dont il a permis la survenue.<\/strong><\/p>\n<\/p>\n<p><p>Notes<\/p>\n<\/p>\n<p><p>(*) Une chose m&rsquo;a fait \u00e9clater d&rsquo;un bon rire r\u00e9publicain dans la fiche <em>Wikip\u00e9dia<\/em> consacr\u00e9e au film, en imaginant la t\u00eate de Lang, chemise rose d\u00e9cha&icirc;n\u00e9e, sortant furieusement de la salle de projection du film comme peut le faire le conformisme lorsqu&rsquo;il se heurte \u00e0 la production d&rsquo;un esprit libre : &laquo; <em>Le film a \u00e9t\u00e9 command\u00e9 \u00e0 l&rsquo;origine par la R\u00e9publique Fran\u00e7aise, lors de la pr\u00e9sidence socialiste de Fran\u00e7ois Mitterrand, soucieuse de c\u00e9l\u00e9brer la R\u00e9volution Fran\u00e7aise. Le Pr\u00e9sident et ses ministres ne s&rsquo;attendaient pas \u00e0 ce que Wajda consid\u00e8re cette phase de la R\u00e9volution Fran\u00e7aise, la Terreur, comme fonci\u00e8rement abjecte et sinistre. Lors de la projection priv\u00e9e faite avant la sortie du film, Jack Lang, alors ministre de la Culture, et d&rsquo;autres ministres sont sortis de la salle de projection avant la fin de la s\u00e9ance, furieux que l&rsquo;on caricature ainsi une facette essentielle de l&rsquo;histoire<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>(**) In\u00e9vitable avec PhG : le \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0, certes&#8230; La R\u00e9volution en est un des composants formateurs et le Syst\u00e8me en est la r\u00e9alisation op\u00e9rationnelle. Cette rencontre n&rsquo;est pas d&rsquo;une simple co\u00efncidence. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cry For Yourself, America 21 octobre 2016 &ndash; &laquo; Vous \u00eates pratiquement en train de pleurer ! Vous \u00eates pratiquement en train de pleurer ! &raquo; (&laquo; You&rsquo;re practically crying. You&rsquo;re practically crying &raquo;), &ndash; s&rsquo;exclame, exc\u00e9d\u00e9, William Scarborough s&rsquo;adressant \u00e0 William Kristol en train de geindre&#8230; Kristol se d\u00e9cha&icirc;ne, mais plut\u00f4t passivement, comme on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[1006,12703,16761,9831,12755,3653,17842,5627,6794,3216,3099,11189,7137,2639],"class_list":["post-76852","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-brzezinski","tag-cosmique","tag-danton","tag-epuisee","tag-evenement","tag-kristol","tag-mika","tag-moment","tag-msnbc","tag-neocon","tag-psychologie","tag-pur","tag-scarborough","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76852"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76852\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}