{"id":76869,"date":"2016-10-30T11:24:29","date_gmt":"2016-10-30T11:24:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/10\/30\/la-generale-orwell-et-le-miracle-du-fbi\/"},"modified":"2016-10-30T11:24:29","modified_gmt":"2016-10-30T11:24:29","slug":"la-generale-orwell-et-le-miracle-du-fbi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/10\/30\/la-generale-orwell-et-le-miracle-du-fbi\/","title":{"rendered":"La g\u00e9n\u00e9rale Orwell et le miracle du FBI"},"content":{"rendered":"<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La g\u00e9n\u00e9rale Orwell et le miracle du FBI<\/h2>\n<\/p>\n<p><p>You ask for miracles, Theo&#8230;I give you the FBI. (Pi\u00e8ge de cristal)<\/p>\n<\/p>\n<p><p>On se souvient tous du regrett\u00e9 acteur Alan Rickman, qui incarne un terroriste allemand d\u00e9jant\u00e9 dans Pi\u00e8ge de cristal (&laquo; mon tailleur est celui d&rsquo;Arafat &raquo;). Avec une groupe de terroristes bien blonds (\u00f4 fabuleux danseur russe Aleksandr Godounov), il prend le contr\u00f4le d&rsquo;une tour multinationale appartement \u00e0 un gentil japonais am\u00e9ricanis\u00e9 (on est en 1987, quand le Nikkei bat ses records). Et comme nos terroristes \u00e9chevel\u00e9s connaissent quelques probl\u00e8mes, le FBI arrive et les sauve par sa maladresse et son incomp\u00e9tence. Peu apr\u00e8s, le r\u00e9sistible Bruce Willis arrive et extermine tout le monde. A la m\u00eame \u00e9poque John McTiernan, qui a connu la prison depuis (en a-t-il trop dit ? Regardez ce qui est arriv\u00e9 au fr\u00e8re de Ridley Scott &ndash; Enemy of the State &#8211; ou au pourfendeur du Deep State Alan J. Pakula), r\u00e9alise A la poursuite d&rsquo;octobre rouge. Sean Connery en commandant de sous-marin lituanien en rupture de ban sovi\u00e9tique veut passer \u00e0 l&rsquo;ouest pour boire du Coke et s&rsquo;acheter une Cadillac. Il vole le sous-marin le plus \u00e9volu\u00e9 d&rsquo;alors (d\u00e9j\u00e0, cher Philippe Grasset, les yankees reconnaissant la supr\u00e9matie technologique russe!!!) et casse le cou \u00e0 son commissaire politique pour franchir le Rubicon (le rubis quoi ? Demande Huma Abedin).<\/p>\n<\/p>\n<p><p>Comment s&rsquo;appelle le commissaire politique dans le sous-marin octobre rouge ? Je vous le donne en mille. Il s&rsquo;appelle Poutine.<\/p>\n<\/p>\n<p><p>Car on sait des choses \u00e0 Hollywood. L&rsquo;\u00e9crivain Tom Clancy travaille main dans la main avec la CIA et le pentagone, et c&rsquo;est lui qui a relanc\u00e9 cette CIA \u00e9clabouss\u00e9e par les eaux troubles du Watergate et les meilleurs Steven Seagal.<\/p>\n<\/p>\n<p><p>Pourquoi dans le cas qui nous occupe le FBI a d\u00e9cid\u00e9 de couler la campagne de la g\u00e9n\u00e9rale Orwell ? Elle est le Bien pourtant la g\u00e9n\u00e9rale Orwell. Elle est la fin du monde assur\u00e9e, cette Regina Infernarum. Elle est la guerre mondiale, la guerre nucl\u00e9aire, la guerre m\u00e9diatique, la guerre aux hommes et aux homophobes, la sorci\u00e8re d&rsquo;Eastwick \u00e9chapp\u00e9e de l&rsquo;asile. Alors ? Une r\u00e9volte des conservateurs de l&rsquo;&Eacute;tat profond ? Une secr\u00e8te vengeance ? Un machisme exacerb\u00e9 (vite, qu&rsquo;elle soit \u00e9lue, et qu&rsquo;elle foute tout ce qui reste de hauts fonctionnaires au ch\u00f4mage pour les remplacer par des islamistes mod\u00e9r\u00e9es saoudiennes) ? Qui veut du mal  \u00e0 la d\u00e9esse Hillary ? The Donald se rend-il compte que la partie la plus cach\u00e9e du Deep State (expliquez \u00e0 Bruno Lemaire que \u00e7a d\u00e9signe &laquo; le tas profond &raquo; sur les rives du Potomac) va envoyer des agents grim\u00e9s en barbus pour  l&rsquo;\u00e9liminer ?<\/p>\n<\/p>\n<p><p>Qui a dit que la vie moderne \u00e9tait un mauvais film ? Gilles Deleuze je crois. Sa fille est cin\u00e9aste. Quant \u00e0 Bruce Willis, il a vir\u00e9 aussi sa cuti, passant de ce r\u00e9pugnant Pi\u00e8ge de cristal \u00e0 Red, film d&rsquo;espionnage parodique et russophile qui nous a enchant\u00e9s Philippe Grasset et moi.<\/p>\n<\/p>\n<p><p>Encore un miracle, FBI ! Encore un miracle, Wikileaks ! Et qu&rsquo;on nous d\u00e9barrasse de la g\u00e9n\u00e9rale Orwell et des s\u00e9vices secrets.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La g\u00e9n\u00e9rale Orwell et le miracle du FBI You ask for miracles, Theo&#8230;I give you the FBI. (Pi\u00e8ge de cristal) On se souvient tous du regrett\u00e9 acteur Alan Rickman, qui incarne un terroriste allemand d\u00e9jant\u00e9 dans Pi\u00e8ge de cristal (&laquo; mon tailleur est celui d&rsquo;Arafat &raquo;). Avec une groupe de terroristes bien blonds (\u00f4 fabuleux&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[3690,17874,2838,916,12538,17873],"class_list":["post-76869","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bruce","tag-clancy","tag-fbi","tag-poutine","tag-usa-2016","tag-willis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76869"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76869\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}