{"id":76954,"date":"2016-12-05T10:46:56","date_gmt":"2016-12-05T10:46:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/12\/05\/considerations-sur-quelques-principes-desagregateurs\/"},"modified":"2016-12-05T10:46:56","modified_gmt":"2016-12-05T10:46:56","slug":"considerations-sur-quelques-principes-desagregateurs","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/12\/05\/considerations-sur-quelques-principes-desagregateurs\/","title":{"rendered":"Consid\u00e9rations sur quelques principes d\u00e9sagr\u00e9gateurs"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Consid\u00e9rations sur quelques principes d\u00e9sagr\u00e9gateurs<\/h2>\n<\/p>\n<p><p>Deux ph\u00e9nom\u00e8nes au moins ont concouru efficacement \u00e0 l&rsquo;effondrement de l&rsquo;URSS et \u00e0 la restitution des pays de l&rsquo;Est de l&rsquo;Europe aux d\u00e9lices du capitalisme sauvage.<\/p>\n<\/p>\n<p><p>Ils se sont combin\u00e9s pour d\u00e9velopper des effets synergiques et ne sont pas totalement ind\u00e9pendants l&rsquo;un de l&rsquo;autre.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Transmettre une foi vibrante<\/h3>\n<\/p>\n<p><p>Le premier est l&rsquo;intransmissibilit\u00e9 de l&rsquo;\u00e9lan r\u00e9volutionnaire.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9nergie mentale qu&rsquo;il mobilise chez les acteurs du bouleversement social, bravant la mort et faisant fi de leur int\u00e9r\u00eat  priv\u00e9 imm\u00e9diat, est tout \u00e0 fait consid\u00e9rable.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r des circonstances objectives exceptionnelles et une lente maturation des esprits vers cette issue radicale aux probl\u00e8mes sociaux sont pr\u00e9sentes pour le d\u00e9clenchement de la r\u00e9volte.  Puis vient le long moment du maintien de la tension psychique qui fera aboutir les \u00e9meutes et les fera aboutir au changement.<\/p>\n<\/p>\n<p><p>Et une autre dose d&rsquo;investissement est encore n\u00e9cessaire pour le faire durer.<\/p>\n<\/p>\n<p><p>Outre les facteurs exog\u00e8nes comme une vacance manifeste du pouvoir devenu \u00e9vidente aux yeux de tous sauf pour l&rsquo;aristocratie d\u00e9cadente, et la guerre mondialis\u00e9e de 1914, des hommes apparaissent \u00e0 ces moments qui incarnent l&rsquo;id\u00e9al r\u00e9volutionnaire, le portent jusqu&rsquo;\u00e0 sa r\u00e9alisation.<\/p>\n<\/p>\n<p><p>Au fur et \u00e0 mesure que s&rsquo;\u00e9loigne dans le temps le moment de l&rsquo;incandescence, ti\u00e9dissent les ardeurs radicales et d\u00e9butent les accommodements.<\/p>\n<\/p>\n<p><p>La g\u00e9n\u00e9ration suivante \u00e0 laquelle est enseign\u00e9e  par des comm\u00e9morations et des livres l&rsquo;\u00e9pop\u00e9e h\u00e9ro\u00efque est d\u00e9j\u00e0 dans un plasma post-r\u00e9volutionnaire. Elle n&rsquo;a pas v\u00e9cu les instants h\u00e9ro\u00efques galvanisants et ne les comprend plus.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Dialectique de la corruption<\/h3>\n<\/p>\n<p><p>Le deuxi\u00e8me est \u00e0 rep\u00e9rer dans le hiatus entre l&rsquo;\u00e9lite dirigeante th\u00e9oriquement garante de l&rsquo;orthodoxie r\u00e9volutionnaire et son comportement r\u00e9el.<\/p>\n<\/p>\n<p><p>D&rsquo;apr\u00e8s B. Drweski, sp\u00e9cialiste de l&rsquo;Europe Centrale et de l&rsquo;Est \u00e0 l&rsquo;Inalco, assez t\u00f4t, une lutte des classes est apparue au sein du Parti Communiste de l&rsquo;URSS.<\/p>\n<\/p>\n<p><p>Les effectifs du PCUS sont pass\u00e9s rapidement de quelques centaines ou milliers \u00e0 plusieurs millions. Cette n\u00e9cessaire hypertrophie qui a jou\u00e9 un r\u00f4le de promotion sociale pour les d\u00e9favoris\u00e9s a eu des effets pervers. Le changement de taille a dragu\u00e9 dans ses filets des opportunistes, les futurs oligarques. Petit \u00e0 petit, des hommes d&rsquo;appareil ont \u00e9t\u00e9 contamin\u00e9s par la quincaillerie consum\u00e9riste occidentale.<\/p>\n<\/p>\n<p><p>Drweski rapporte que d\u00e8s les ann\u00e9es soixante dix, des \u00e9tudiants communistes \u00e9taient envoy\u00e9s \u00e0 Chicago pour y apprendre les th\u00e9ories de Friedman.<\/p>\n<\/p>\n<p><p>Le peuple vivait  la dissolution de l&rsquo;\u00e9thique communiste et la dissonance cognitive  entre les principes d\u00e9clar\u00e9s et la r\u00e9alit\u00e9 de la corruption m\u00e2tin\u00e9e avec une fascination pour un mode de vie \u00e9loign\u00e9 de l&rsquo;\u00e9galitarisme aust\u00e8re et un peu gris. La p\u00e9n\u00e9tration des images t\u00e9l\u00e9visuelles en particulier les feuilletons  lui faisait croire que le Paradis sur terre existe et qu&rsquo;il est en Occident.<\/p>\n<\/p>\n<p><p>Le vingti\u00e8me congr\u00e8s a sonn\u00e9 l&rsquo;heure de l&rsquo;amplification de l&#8217;embourgeoisement d&rsquo;une caste constitu\u00e9e progressivement qui ne croyait plus en ce qu&rsquo;elle pr\u00f4nait mais qui portait toujours l&rsquo;\u00e9tiquette de communiste. Elle a conduit le syst\u00e8me \u00e0 sa casse.<\/p>\n<\/p>\n<p><p>La destruction du  socialisme r\u00e9el avec tous ses inconv\u00e9nients mais ses avantages  r\u00e9els pour le peuple \u00e9duqu\u00e9, nourri, soign\u00e9 et occup\u00e9 \u00e0 un travail s&rsquo;est sold\u00e9e par le transfert massif des biens de production collectifs vers la minorit\u00e9 bureaucratique convertie depuis longtemps et pr\u00eate \u00e0 r\u00e9aliser instantan\u00e9ment la contre-r\u00e9volution.<\/p>\n<\/p>\n<p><p>L&rsquo;inefficacit\u00e9 \u00e9conomique de la R\u00e9publique des Soviets n&rsquo;est pas en cause.<\/p>\n<\/p>\n<p><p>En tr\u00e8s peu d&rsquo;ann\u00e9es, l&rsquo;URSS  rendue exsangue pour avoir terrass\u00e9 quasiment seule le monstre nazi,  s&rsquo;est relev\u00e9e de la perte de 27 millions de ses habitants, les plus valeureux, les plus communistes r\u00e9alisant un trou g\u00e9n\u00e9rationnel qui n&rsquo;a pas \u00e9t\u00e9 sans effets dans la g\u00e9n\u00e9alogie de la Contre-R\u00e9volution et de l&rsquo;an\u00e9antissement total de ses infrastructures.<\/p>\n<\/p>\n<p><p>Bien avant les Us(a), Les Sovi\u00e9tiques ont \u00e9t\u00e9 capables d&rsquo;envoyer des hommes dans l&rsquo;espace.<\/p>\n<\/p>\n<p><p>La course aux armements non plus.<\/p>\n<\/p>\n<p><p>La d\u00e9faite du bloc qui privil\u00e9giait la justice sociale \u00e0 une pr\u00e9tendue libert\u00e9 est plut\u00f4t de l&rsquo;ordre immat\u00e9riel de la croyance, par perte de la foi.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Notre m\u00e9cr\u00e9ance et leur Libert\u00e9<\/h3>\n<\/p>\n<p><p>Nous avons maintenant en Occident cette m\u00eame m\u00e9cr\u00e9ance qui s&rsquo;installe.<\/p>\n<\/p>\n<p><p>Les instruments de pouvoir qui subjuguent le peuple ont perdu de leur tranchant.<\/p>\n<\/p>\n<p><p>Des techniques de l&rsquo;information, tr\u00e8s affin\u00e9es, r\u00e9alisent une  diffusion d&rsquo;une propagande absorb\u00e9e passivement et sans contrainte par des spectateurs qui offrent leur cerveau \u00e0 cette impr\u00e9gnation.<\/p>\n<\/p>\n<p><p>Le montage des JT en forme de feuilletons haletants permet une alternance entre s\u00e9quences sanglantes propices \u00e0 g\u00e9n\u00e9rer la peur et du divertissement  people arrivant pour soulager la peur, rassurer et r\u00e9compenser.<\/p>\n<\/p>\n<p><p>Ainsi, les d\u00e9mocraties occidentales ont manufactur\u00e9 l&rsquo;opinion et la soumission  des peuples \u00e0 un ordre qui les capture  dans un besoin insatiable de consommation inutile et aberrante et les asservit par le cr\u00e9dit.<\/p>\n<\/p>\n<p><p>De pr\u00e9tendus ing\u00e9nieurs sociaux modifient leurs modalit\u00e9s perceptives et orientent leurs \u00e9motions.<\/p>\n<\/p>\n<p><p>L&rsquo;un des ressorts le plus usit\u00e9 dans ces psy-ops est la Peur.<\/p>\n<\/p>\n<p><p>La Peur primitive et archa\u00efque.<\/p>\n<\/p>\n<p><p>La Peur qui emprunte le circuit court par l&rsquo;amygdale sans passer par le cortex \u00e9volu\u00e9.<\/p>\n<\/p>\n<p><p>La r\u00e9p\u00e9tition des messages du danger rouge puis maintenant vert a cr\u00e9\u00e9 des autoroutes vers l&rsquo;aversion du Communiste puis du Musulman.<\/p>\n<\/p>\n<p><p>Pendant la guerre dite froide ( le Vietnam, le Cambodge et l&rsquo;Angola n&rsquo;ont pas \u00e9t\u00e9 particuli\u00e8rement gel\u00e9s) une majorit\u00e9 pouvait adh\u00e9rer \u00e0 la th\u00e8se d&rsquo;une lArm\u00e9e Rouge \u00e0 Paris en quelques heures. Les m\u00e9nages s&rsquo;\u00e9quipaient en r\u00e9frig\u00e9rateurs et d&rsquo;automobiles.<\/p>\n<\/p>\n<p><p>Les classes laborieuses b\u00e9n\u00e9ficiaient de la protection sociale garantie justement par l&rsquo;existence des acquis communistes \u00e0 l&rsquo;Est.<\/p>\n<\/p>\n<p><p>D\u00e9sormais, le contrefort communiste dissous, plus aucune r\u00e8gle ne vient entraver la propension pr\u00e9datrice du capitalisme.<\/p>\n<\/p>\n<p><p>En m\u00eame temps que le cauchemar de la paup\u00e9risation de la majorit\u00e9 se densifie, l&rsquo;acc\u00e8s \u00e0 des informations alternatives s&rsquo;intensifie.<\/p>\n<\/p>\n<p><p>Les deux premi\u00e8res multinationales en terme de capitalisation boursi\u00e8re, Apple et Google, participent \u00e0 une r\u00e9organisation de la distribution de l&rsquo;information.<\/p>\n<\/p>\n<p><p>La preuve est donn\u00e9e  par Trump  de cette attitude r\u00e9fractaire \u00e0 l&rsquo;\u00e9gard des injonctions des media mainstream.<\/p>\n<\/p>\n<p><p>Le Wapo s&rsquo;institue en Secr\u00e9tariat d\u00e9l\u00e9gu\u00e9 au Minist\u00e8re de la V\u00e9rit\u00e9  en est encore une autre.<\/p>\n<\/p>\n<p><p>Les deux cents sites alternatifs cit\u00e9s par le Washington Post r\u00e9alisent du mieux qu&rsquo;ils le peuvent leur travail de r\u00e9information<\/p>\n<\/p>\n<p><p>La preuve aussi <a href=\"https:\/\/www.rt.com\/usa\/369119-veterans-constitution-dapl-protest\/\">par l&rsquo;appui<\/a> des 3500 Anciens Combattants au refus des peuples indig\u00e8nes de se faire spolier leur terre et leur eau \u00e0 Standing Rock.<\/p>\n<\/p>\n<p><p>La France sous-imp\u00e9riale peut massacrer autant que n\u00e9cessaire pour elle dans ses ex-colonies.<\/p>\n<\/p>\n<p><p>Personne ne trouve rien \u00e0 y redire.<\/p>\n<\/p>\n<p><p>Mais quand le Pr\u00e9sident de la France d\u00e9core un chef d&rsquo;Etat notoirement autocratique et r\u00e9trograde, il appara&icirc;t un degr\u00e9 de dissonance inacceptable pour le cerveau humain.<\/p>\n<\/p>\n<p><p>De plus, il est devient impossible de soutenir diplomatiquement et logistiquement des rebelles djihadistes auxquels les princes r\u00e9cipiendaire de la L\u00e9gion d&rsquo;Honneur accordent le financement et pr\u00e9tendre lutter contre le terrorisme islamiste.<\/p>\n<\/p>\n<p><p>Le surgeon occidental du r\u00e9gime de Tel  Aviv ne peut clamer qu&rsquo;il est l&rsquo;unique d\u00e9mocratie qui vaille dans la r\u00e9gion et emprisonner des enfants de 12 ans pour des ann\u00e9es en raison d&rsquo;un simple jet de pierre sur un tank. Il arrache des larmes de sang et de rage \u00e0 des millions qui ne croient que ce qu&rsquo;ils voient et vivent.<\/p>\n<\/p>\n<p><p>Les Britanniques, \u00e9claireurs en la mati\u00e8re puisque les a&icirc;n\u00e9s des Fran\u00e7ais en imp\u00e9rialisme d\u00e9cadent et thatcherisme d\u00e9vastateur, n&rsquo;ont pas renonc\u00e9 \u00e0 poursuivre Blair pour ses &laquo; mensonges &raquo; plus que pour ses crimes.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les trompettes sonnent le tocsin<\/h3>\n<\/p>\n<p><p>Les murs du mensonge entretenu depuis plusieurs d\u00e9cennies sont plus que l\u00e9zard\u00e9s.<\/p>\n<\/p>\n<p><p>Ils risquent de s&rsquo;effondrer \u00e0 tout moment.<\/p>\n<\/p>\n<p><p>La religion du consum\u00e9risme est en train de perdre ses adeptes, une petite conscience \u00e9cologique se m\u00eale \u00e0 un certain degr\u00e9 de nationalisme pour privil\u00e9gier la production in situ.<\/p>\n<\/p>\n<p><p>Il ne manque plus que le catalyseur qui va pr\u00e9cipiter toute cette m\u00e9tastabilit\u00e9 vers un autre \u00e9tat.<\/p>\n<\/p>\n<p><h4>Badia Benjelloun<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consid\u00e9rations sur quelques principes d\u00e9sagr\u00e9gateurs Deux ph\u00e9nom\u00e8nes au moins ont concouru efficacement \u00e0 l&rsquo;effondrement de l&rsquo;URSS et \u00e0 la restitution des pays de l&rsquo;Est de l&rsquo;Europe aux d\u00e9lices du capitalisme sauvage. Ils se sont combin\u00e9s pour d\u00e9velopper des effets synergiques et ne sont pas totalement ind\u00e9pendants l&rsquo;un de l&rsquo;autre. Transmettre une foi vibrante Le premier&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,2803,3014,2639,12538],"class_list":["post-76954","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-effondrement","tag-systeme","tag-trump","tag-usa-2016"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76954"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76954\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}