{"id":76984,"date":"2016-12-20T12:52:36","date_gmt":"2016-12-20T12:52:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/12\/20\/moscou-2016-ambassade-de-la-republique-de-californie\/"},"modified":"2016-12-20T12:52:36","modified_gmt":"2016-12-20T12:52:36","slug":"moscou-2016-ambassade-de-la-republique-de-californie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/12\/20\/moscou-2016-ambassade-de-la-republique-de-californie\/","title":{"rendered":"Moscou-2016, ambassade de la R\u00e9publique de Californie&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Moscou-2016, ambassade de la R\u00e9publique de Californie&#8230;<\/h2>\n<\/p>\n<p><p>Ce n&rsquo;est pas un faux, c&rsquo;est au contraire un authentique, absolument confirm\u00e9 : <strong>la R\u00e9publique de Californie a ouvert son \u00ab\u00a0ambassade\u00a0\u00bb \u00e0 Moscou le 18 d\u00e9cembre 2016<\/strong>. Le mouvement <em>Yes California<\/em>, qui travaille \u00e0 renforcer le soutien pour faire voter son projet de r\u00e9f\u00e9rendum en 2018, et son r\u00e9f\u00e9rendum <em>Calexit<\/em> (s\u00e9cession de la Californie) lui-m\u00eame en 2019, a bien ouvert une \u00ab\u00a0ambassade\u00a0\u00bb pour instruire les Russes des caract\u00e8res politiques, culturels et soci\u00e9taux de la Californie, e<strong>t justifier ainsi son ind\u00e9pendance en 2019<\/strong>.<\/p>\n<\/p>\n<p><p>Le chef du mouvement <em>Yes California<\/em>, Louis Martinelli, a donc pr\u00e9sent\u00e9 cette initiative bien <a href=\"http:\/\/www.dedefensa.org\/article\/californie-elegant-modele-de-secession\">dans le go&ucirc;t du jour<\/a>, ce dimanche 18 d\u00e9cembre \u00e0 Moscou, selon ce qu&rsquo;en rapporte notamment <a href=\"https:\/\/www.rt.com\/usa\/370698-calexit-california-embassy-moscow\/\">RT ce 19 d\u00e9cembre<\/a> : &laquo; <em>The movement, Yes California, is hoping for a \u00ab\u00a0Calexit\u00a0\u00bb break from the US. Speaking at a press conference on Sunday, Louis Marinelli, leader of the movement, said the embassy will not deal with diplomatic issues, but will act as more of a cultural center that will educate Russians about California&rsquo;s history, boost trade ties and promote tourism. \u00ab\u00a0We&rsquo;re not requesting military assistance from Russia,\u00a0\u00bb Marinelli explained. \u00ab\u00a0We&rsquo;re certainly going to request recognition of our independence and recognition of our<\/em> [2019] <em>independence referendum result, as we&rsquo;re going to request that the entire international community recognizes the results.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>(Curiosit\u00e9 \u00e0 savourer : on voit sur la vid\u00e9o de la conf\u00e9rence de presse la salle o&ugrave; la nouvelle \u00ab\u00a0ambassade\u00a0\u00bb de la R\u00e9publique de Californie accueillait la presse moscovite avec ses murs encombr\u00e9s de portraits de Guevara, de Assad, de Chavez, etc. A savourer en fonction de ce qui pr\u00e9c\u00e8de et en fonction de ce qui suit&#8230;)<\/p>\n<\/p>\n<p><p>En m\u00eame, temps le site exotique <em>WhtDoesItMeans<\/em> s&rsquo;appuie sur l&rsquo;\u00e9v\u00e9nement <a href=\"http:\/\/www.whatdoesitmean.com\/index2190.htm\">pour annoncer<\/a> qu&rsquo;<strong>Hillary Clinton pourrait bien (r)entrer dans la course et devenir gouverneur de la Californie en 2018, cet &Eacute;tat o&ugrave; elle a \u00e9cras\u00e9 Donald Trump et fait <a href=\"http:\/\/www.dedefensa.org\/article\/californie-elegant-modele-de-secession\">toute la diff\u00e9rence<\/a> qui lui permet d&rsquo;avoir l&rsquo;avantage en voix populaires aux USA<\/strong>. Le sc\u00e9nario se poursuit avec l&rsquo;ind\u00e9pendance de la Californie, la premi\u00e8re pr\u00e9sidente de la Californie (Hillary), envisageant l&rsquo;achat d&rsquo;armements russes pour permettre \u00e0 la Californie de d\u00e9fendre ses fronti\u00e8res contre son grand voisins, les USA-sans-la-Californie du pr\u00e9sident Donald Trump&#8230; <em>Si non \u00e8 vero&#8230;<\/em><\/p>\n<\/p>\n<p><p>(On prendra garde \u00e0 ceci que le site <em>WhatDoesItMeans<\/em>, dont nous avons <a href=\"http:\/\/www.dedefensa.org\/article\/a-la-recherche-du-complot-perdu-et-enfin-decouvert\">d\u00e9j\u00e0 parl\u00e9<\/a> \u00e0 plusieurs reprises, <strong>est en train d&rsquo;acqu\u00e9rir un certain cr\u00e9dit qui ne peut vraiment \u00e9tonner dans une \u00e9poque si originale<\/strong>. On le voit notamment \u00e0 la lecture d&rsquo;un article de Larry Johnson sur <em>NoQuarter<\/em> <a href=\"http:\/\/www.noquarterusa.net\/blog\/79482\/barack-obama-didnt-know-didnt-know\/\">du 17 d\u00e9cembre<\/a>, o&ugrave; <em>WhatDoestItMeans<\/em> est abondamment cit\u00e9 comme une source par divers commentateurs de la campagne USA-2016 d\u00e8s mai dernier. Larry Johnson est un homme s\u00e9rieux puisque, ancien officier de la CIA, il fait partie de l&rsquo;association fameuse des officiers du renseignement US \u00ab\u00a0dissidents\u00a0\u00bb <a href=\"http:\/\/www.dedefensa.org\/article\/allegations-of-hacking-election-are-baseless\">VIPS<\/a>.)<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Rien dans tout cela ne manque ni d&rsquo;humour ni d&rsquo;ironie, ni d&rsquo;inversion \u00e9l\u00e9gante ni de subversion \u00e9tonnante<\/strong>, &ndash; de la s\u00e9cession de la Californie au retour d&rsquo;Hillary, du soutien de la R\u00e9publique de Clifornie implicitement demand\u00e9 \u00e0 Moscou, de la future pr\u00e9sidente de la R\u00e9publique de Californie demandant des armes au pr\u00e9sident Poutine pour se prot\u00e9ger du pr\u00e9sident Trump, pendant que les pr\u00e9sidents Trump et Poutine feraient excellent m\u00e9nage sur les ruines du Syst\u00e8me&#8230; Peut-\u00eatre est-ce cela la formule de l&rsquo;effondrement du Syst\u00e8me : <strong>le jour o&ugrave;, dans un immense \u00e9clat de rire, le c\u00f4t\u00e9 bouffe l&#8217;emporta d\u00e9finitivement dans l&rsquo;irr\u00e9sistible <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> du monde<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 20 d\u00e9cembre 2016 \u00e0 12H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moscou-2016, ambassade de la R\u00e9publique de Californie&#8230; Ce n&rsquo;est pas un faux, c&rsquo;est au contraire un authentique, absolument confirm\u00e9 : la R\u00e9publique de Californie a ouvert son \u00ab\u00a0ambassade\u00a0\u00bb \u00e0 Moscou le 18 d\u00e9cembre 2016. Le mouvement Yes California, qui travaille \u00e0 renforcer le soutien pour faire voter son projet de r\u00e9f\u00e9rendum en 2018, et son&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[12603,2942,934,7258,12005,3278,10625,916,2949,11956,2639,12538,7934],"class_list":["post-76984","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-california","tag-californie","tag-clinton","tag-donald","tag-faal","tag-hillary","tag-martinelli","tag-poutine","tag-secession","tag-sorcha","tag-trump","tag-usa-2016","tag-yes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76984"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76984\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}