{"id":77009,"date":"2017-01-03T07:11:29","date_gmt":"2017-01-03T07:11:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/01\/03\/la-sagesse-de-seneque-en-2016-de-notre-ere\/"},"modified":"2017-01-03T07:11:29","modified_gmt":"2017-01-03T07:11:29","slug":"la-sagesse-de-seneque-en-2016-de-notre-ere","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/01\/03\/la-sagesse-de-seneque-en-2016-de-notre-ere\/","title":{"rendered":"La sagesse de S\u00e9n\u00e8que en 2016 de notre \u00e8re"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La sagesse de S\u00e9n\u00e8que en 2016 de notre \u00e8re<\/h2>\n<\/p>\n<p><p><em>Pour Perceval (le 78)<\/em><\/p>\n<\/p>\n<p><p>Pr\u00e9cepteur de N\u00e9ron, S\u00e9n\u00e8que fut bien plac\u00e9 pour savoir que les bons conseils n&rsquo;ont pas de bons suiveurs. Pourtant, \u00e0 vingt si\u00e8cles de l\u00e0, et dans les temps postmodernes, d\u00e9sabus\u00e9s et d\u00e9sertiques o&ugrave; nous vivons, nous ne pouvons que nous \u00e9merveiller de la justesse de ses analyses, de ses observations, parfois de ses conseils, comme si S\u00e9n\u00e8que, \u00e0 l&rsquo;instar d&rsquo;un Montesquieu, d&rsquo;un Arioste ou d&rsquo;un la Bo\u00e9tie faisait partie de ces penseurs qui cogitent dans ce que Debord appelait le pr\u00e9sent \u00e9ternel. En lisant S\u00e9n\u00e8que, on croit lire le journal d&rsquo;un grand contemporain.<\/p>\n<\/p>\n<p><p>Je lui laisse la parole :<\/p>\n<\/p>\n<p><p>Sur les temps obs\u00e9d\u00e9s par l&rsquo;argent et par l&rsquo;insatisfaction : &quot;les riches sont plus malheureux que les mendiants; car les mendiants ont peu de besoins, tandis que les riches en ont beaucoup&quot;.<\/p>\n<\/p>\n<p><p>Sur l&rsquo;obsession des comiques et de la d\u00e9rision, si sensible depuis les ann\u00e9es Coluche et Mitterrand : &quot;certains ma&icirc;tres ach\u00e8tent de jeunes esclaves effront\u00e9s et aiguisent leur impudence, afin de leur faire prof\u00e9rer bien \u00e0 propos des paroles injurieuses que nous n&rsquo;appelons pas insultes, mais bons mots.&quot;<\/p>\n<\/p>\n<p><p>Sur la d\u00e9pression, fameux mal de vivre mis \u00e0 la mode par les romantiques, S\u00e9n\u00e8que \u00e9crit ces lignes lumineuses :&quot;De l\u00e0 cet ennui, ce m\u00e9contentement de soi, ce va-et-vient d&rsquo;une \u00e2me qui ne se fixe nulle part, cette r\u00e9signation triste et maussade \u00e0 l&rsquo;inaction&#8230;, cette oisivet\u00e9 m\u00e9contente.&quot;<\/p>\n<\/p>\n<p><p>Avec cette cerise sur le g\u00e2teau, qui s&rsquo;applique si bien \u00e0 la mentalit\u00e9 fran\u00e7aise : &quot;On d\u00e9sire voir tout le monde \u00e9chouer parce que l&rsquo;on n&rsquo;a pas pu r\u00e9ussir&quot; (omnes destrui cupiunt, quia se non potuere prouehere, dit sublimement le texte latin).<\/p>\n<\/p>\n<p><p>Je me souviens de cette ligne de Flaubert qui parle de Fr\u00e9d\u00e9ric Moreau qui sort se promener dans les boulevards et les magasins &quot;pour se d\u00e9barrasser de lui-m\u00eame&quot;. S\u00e9n\u00e8que \u00e9crit : &quot;Toute occasion de sortir de soi, de s&rsquo;\u00e9chapper \u00e0 soi-m\u00eame lui est agr\u00e9able, surtout aux esprits les plus m\u00e9diocres qui adorent se laisser d\u00e9vorer par leurs occupations&quot;. Son contemporain, le po\u00e8te Lucr\u00e8ce, \u00e9crit : &quot;Ainsi chacun ne cesse de se fuir lui-m\u00eame\u00a0\u00bb (Hoc se quisque modo semper fugit).<\/p>\n<\/p>\n<p><p>Sur le tourisme de masse et les croisi\u00e8res, S\u00e9n\u00e8que remarque :&quot;On entreprend des voyages sans but; on parcourt les rivages; un jour sur mer, le lendemain, partout on manifeste la m\u00eame instabilit\u00e9, le m\u00eame d\u00e9go&ucirc;t du pr\u00e9sent.&quot;<\/p>\n<\/p>\n<p><p>Extraordinaire aussi, cette allusion au d\u00e9lire immobilier qui a d\u00e9truit le monde et son \u00e9pargne : &quot;Nous entreprendrons alors de construire des maisons, d&rsquo;en d\u00e9molir d&rsquo;autres, de reculer les rives de la mer, d&rsquo;amener l&rsquo;eau malgr\u00e9 les difficult\u00e9s du terrain&hellip;&quot;<\/p>\n<\/p>\n<p><p>Une soci\u00e9t\u00e9 comme la n\u00f4tre ou celle de S\u00e9n\u00e8que (je pense heureusement qu&rsquo;il y en eut d&rsquo;autres) ne manque pas d&rsquo;esquinter les gens, de les r\u00e9duire \u00e0 l&rsquo;\u00e9tat de l\u00e9gumes. J&rsquo;avais cit\u00e9 il y a dix ans la phrase de Soljenitsyne sur ses contemporains occidentaux &quot;qui ne savent pas s&rsquo;ils sont vivants&quot;. S\u00e9n\u00e8que le sait d\u00e9j\u00e0, \u00e0 son \u00e9poque de pain et de jeux, de cirque et de sang : &quot;Curius Dentatus disait qu&rsquo;il aimerait mieux \u00eatre mort que vivre mort&quot; (Curius Dentatus aiebat malle esse se mortuum quam uiuere).<\/p>\n<\/p>\n<p><p>L&rsquo;obsession du &quot;people&quot;, amplifi\u00e9e par l&rsquo;apparition d&rsquo;Internet, dont tous les portails se pr\u00e9occupent jusqu&rsquo;\u00e0 la naus\u00e9e, est aussi d\u00e9crite par le penseur sto\u00efcien : &quot;De la curiosit\u00e9 provient un vice affreux : celui d&rsquo;\u00e9couter tout ce qui se raconte, de s&rsquo;enqu\u00e9rir indiscr\u00e8tement des petites nouvelles (auscultatio et publicorum secretorumque inquisitio), tant intimes que publiques, et d&rsquo;\u00eatre toujours plein d&rsquo;histoires.&quot;<\/p>\n<\/p>\n<p><p>Je terminerais sur l&rsquo;insupportable obsession humanitaire de nos temps m\u00e9diatiques et mis\u00e9rables, dont Chesterton disait qu&rsquo;ils \u00e9taient la marque d&rsquo;id\u00e9es chr\u00e9tiennes devenues folles : &quot;C&rsquo;est une torture sans fin que de se laisser tourmenter des maux d&rsquo;autrui\u00a0\u00bb (nam alienis malis torqueri aeterna miseria est).<\/p>\n<\/p>\n<p><p>La sagesse dit enfin sous la plume de S\u00e9n\u00e8que <em>: Si te ad studia reuocaueris, omne uitae fastidium effugeris<\/em>&hellip; que je ne traduirai pas.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sagesse de S\u00e9n\u00e8que en 2016 de notre \u00e8re Pour Perceval (le 78) Pr\u00e9cepteur de N\u00e9ron, S\u00e9n\u00e8que fut bien plac\u00e9 pour savoir que les bons conseils n&rsquo;ont pas de bons suiveurs. Pourtant, \u00e0 vingt si\u00e8cles de l\u00e0, et dans les temps postmodernes, d\u00e9sabus\u00e9s et d\u00e9sertiques o&ugrave; nous vivons, nous ne pouvons que nous \u00e9merveiller de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,3083,3309,12646,12613,12645],"class_list":["post-77009","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-depression","tag-postmodernite","tag-rome-postmodernite","tag-seneque","tag-similitude"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77009"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77009\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}