{"id":77011,"date":"2017-01-03T17:27:40","date_gmt":"2017-01-03T17:27:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/01\/03\/vous-avez-aime-2016-vous-adorerez-2017\/"},"modified":"2017-01-03T17:27:40","modified_gmt":"2017-01-03T17:27:40","slug":"vous-avez-aime-2016-vous-adorerez-2017","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/01\/03\/vous-avez-aime-2016-vous-adorerez-2017\/","title":{"rendered":"Vous avez aim\u00e9 2016\u00a0? Vous adorerez 2017&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Vous avez aim\u00e9 2016 ? Vous adorerez 2017&#8230;<\/h2>\n<\/p>\n<p><p>&#8230; Il ne s&rsquo;agit pas des bons v&oelig;ux de Julien Assange, le symbole et le porte-parole de <em>WikiLeaks<\/em>, retranch\u00e9 dans sa forteresse forc\u00e9e de l&rsquo;ambassade d&rsquo;Equateur \u00e0 Londres. Interview\u00e9 par <em>FoxNews<\/em>, Assange d\u00e9mentait pour la ni\u00e8me fois que les livraisons qui ont para&icirc;t-il fait d\u00e9railler le libre exercice de la d\u00e9mocratie en Am\u00e9rique durant USA-2016 n&rsquo;\u00e9taient pas d&rsquo;origine russe. &laquo; <em>S&ucirc;r \u00e0 1000%, je suis<\/em> &raquo;, a dit Assange.<\/p>\n<\/p>\n<blockquote>\n<p><p>Pendant ce temps, un tweet du susdit <em>WikiLeaks <\/em>se faisait le porteur des bons v&oelig;ux implicites de l&rsquo;interview\u00e9 en tweetant simplement sur les projets de l&rsquo;organisation au nom de laquelle il parlait&#8230; Il s&rsquo;agit de quelque chose comme : &laquo; <strong><em>Si vous pensez que 2016 a \u00e9t\u00e9 un grand cru WikiLeaks, 2017 vous mettra sur le cul.<\/em><\/strong> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Divers sites rendent compte des deux \u00e9v\u00e9nements (Assange et le tweet), dont <em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-01-03\/wikileaks-hints-huge-upcoming-revelations-2017-will-blow-you-away\">ZeroHedge.com<\/a><\/em> et RT ; <a href=\"https:\/\/www.rt.com\/news\/372550-wikileaks-2017-showdown-leaks\/\">ci-apr\u00e8s<\/a>, le r\u00e9seau russe dans un texte court, avec vid\u00e9os, sur le tweet de l&rsquo;organisation fameuse : &laquo; <em>WikiLeaks has promised 2017 will be an even bigger year for leaks than 2016, which saw the whistleblowing site publish thousands of documents exposing US political secrets, covert trade deals and private communications from global leaders. \u00ab\u00a0If you thought 2016 was a big WikiLeaks year, 2017 will blow you away,\u00a0\u00bb WikiLeaks tweeted on Monday, giving no hints as to what may be in store.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>It proved a very busy 2016 for the whistleblowing site, as it delivered a massive trove of documents over the 12-month period. This included more than 50,000 emails from Hillary Clinton&rsquo;s campaign chair JohnPodesta and more than 27,000 emails from the Democratic National Committee, which confirmed the DNC worked against Democratic presidential candidate Bernie Sanders, favoring Clinton. More US State Department cables were released, as well as documents which gave an insight into the US arming of Yemen. Text from the Transatlantic Trade and Investment Partnership (TTIP) and Trade in Services Agreement (TiSA) was also revealed<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Dans le m\u00eame tweet, <em>WikiLeaks <\/em>offre un lien \u00e0 ses lecteurs pour des donations, &laquo; <em>pour aider le site \u00e0 pr\u00e9parer cette confrontation <\/em>&raquo; (avec le Syst\u00e8me), dont on jugerait bien qu&rsquo;elle pourrait avoir un air de finalit\u00e9 des choses. Bonne nouvelle donc, et excellents v&oelig;ux : <strong><em>WikiLeaks<\/em> s&rsquo;appr\u00eate \u00e0 une ann\u00e9e d&rsquo;affrontement avec 2016 comme r\u00e9f\u00e9rence, c&rsquo;est-\u00e0-dire l&rsquo;ann\u00e9e o&ugrave; cette entit\u00e9 \u00e0 r\u00e9ussi \u00e0 \u00e9branler le monstre, &ndash; le syst\u00e8me de l&rsquo;am\u00e9ricanisme, le Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p><em>WikiLeaks <\/em>est devenu une entit\u00e9 <strong>suffisamment incompr\u00e9hensible et ind\u00e9maillable<\/strong>. Ses livraisons peuvent donc alimenter la suite de la grande Crise, par le biais de la confusion des sources et de la myriade des interpr\u00e9tations de ces m\u00eames livraisons, par les r\u00e9actions du <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> avec son enfant naturel surnomm\u00e9 <em>Fake-News<\/em>, par l&rsquo;alimentation de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/larmageddon-de-lantirussisme\">antirussisme<\/a>, par l&rsquo;enfermement de Trump dans un r\u00e9seau d&rsquo;accusations abracadabrantesques l&#8217;emp\u00eachant d&rsquo;\u00e9tablir un arrangement pour gouverner, etc. <em>WikiLeaks<\/em> sera au rendez-vous <strong>pour hyper-acc\u00e9l\u00e9rer le d\u00e9sordre dans l&rsquo;Empire du d\u00e9sordre<\/strong>, jusqu&rsquo;\u00e0 ce que la surpuissance de cette dynamique produise assez d&rsquo;autodestruction pour combler notre attente. On adorera&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 3 janvier 2017 \u00e0 17H33<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez aim\u00e9 2016 ? Vous adorerez 2017&#8230; &#8230; Il ne s&rsquo;agit pas des bons v&oelig;ux de Julien Assange, le symbole et le porte-parole de WikiLeaks, retranch\u00e9 dans sa forteresse forc\u00e9e de l&rsquo;ambassade d&rsquo;Equateur \u00e0 Londres. Interview\u00e9 par FoxNews, Assange d\u00e9mentait pour la ni\u00e8me fois que les livraisons qui ont para&icirc;t-il fait d\u00e9railler le libre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[7972,12611,9886,4426,3356,12629,2639,12538,9887],"class_list":["post-77011","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-annee","tag-antirussisme","tag-assange","tag-bonne","tag-desordre","tag-fake-news","tag-trump","tag-usa-2016","tag-wikileaks"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77011"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77011\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}