{"id":77058,"date":"2017-07-11T10:57:49","date_gmt":"2017-07-11T10:57:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/11\/israel-vs-soros-qui-est-le-deconstructeur\/"},"modified":"2017-07-11T10:57:49","modified_gmt":"2017-07-11T10:57:49","slug":"israel-vs-soros-qui-est-le-deconstructeur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/11\/israel-vs-soros-qui-est-le-deconstructeur\/","title":{"rendered":"Isra\u00ebl vs Soros\u00a0: qui est le d\u00e9constructeur\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Isra\u00ebl vs Soros : qui est le d\u00e9constructeur ?<\/h2>\n<\/p>\n<p><p>Il y a <strong>\u00e0 nouveau<\/strong> un tr\u00e8s s\u00e9rieux accrochage entre Isra\u00ebl et Soros, cette fois de la mani\u00e8re la plus officielle puisqu&rsquo;il s&rsquo;agit d&rsquo;une communication du minist\u00e8re isra\u00e9lien des affaires \u00e9trang\u00e8res rectifiant un communiqu\u00e9 de l&rsquo;ambassadeur d&rsquo;Isra\u00ebl en Hongrie. Ce dernier (l&rsquo;ambassadeur) avait condamn\u00e9 une campagne officielle du gouvernement hongrois contre Soros justifi\u00e9e par l&rsquo;action du milliardaire-activiste qui soutient la politique de migration en UE, que refuse la Hongrie.<\/p>\n<\/p>\n<p><p>Des affiches dans ce sens ont \u00e9t\u00e9 placard\u00e9es sur la voie publique, sous le titre \u00ab\u00a0Ne laissons pas le dernier mot \u00e0 Soros\u00a0\u00bb. L\u00e0-dessus, des graffitis ont souvent \u00e9t\u00e9 appos\u00e9s sur ces affiches, de caract\u00e8re antis\u00e9mite (notamment \u00ab\u00a0Juif puant\u00a0\u00bb). C&rsquo;est alors qu&rsquo;intervient l&rsquo;ambassadeur isra\u00e9lien \u00e0 Budapest selon les formules consacr\u00e9es, notamment selon l&rsquo;affirmation que ces inscriptions rappellent des \u00e9v\u00e9nements \u00ab\u00a0de triste m\u00e9moire\u00a0\u00bb et alimentent \u00ab\u00a0des sentiments de haine et de peur\u00a0\u00bb. (La Hongrie a eu une place importante dans l&rsquo;holocauste des juifs, avec plus de 500.000 juifs hongrois d\u00e9port\u00e9s dans les camps.) Enfin, dernier \u00e9pisode, l&rsquo;intervention du minist\u00e8re isra\u00e9lien des affaires \u00e9trang\u00e8res qui redresse sans \u00e9quivoque et d&rsquo;une fa\u00e7on archi-officielle (porte-parole Emmanuel Nahshon)  l&rsquo;intervention de l&rsquo;ambassadeur : <strong>cette intervention de l&rsquo;ambassadeur &laquo; <em>n&rsquo;est en aucune fa\u00e7on un acte visant \u00e0 d\u00e9l\u00e9gitimer la critique<\/em> [du gouvernement hongrois] <em>contre George Soros<\/em><\/strong><em>, qui ne cesse de miner le gouvernement d\u00e9mocratiquement \u00e9lu d&rsquo;Isra\u00ebl<\/em> [&#8230;] <em>Les  organisations financ\u00e9es par Soros diffament l&rsquo;&Eacute;tat juif et cherche \u00e0 lui d\u00e9nier le droit de se d\u00e9fendre<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-07-10\/bizarre-confrontation-israel-calls-george-soros-threat-democratic-governments\">ZeroHedge.com<\/a><\/em>, qui rapporte la nouvelle, poursuit en d\u00e9veloppant une analyse de l&rsquo;attitude du gouvernement isra\u00e9lien autant que ses rapports avec la Hongrie, qui est le pestif\u00e9r\u00e9 favori de l&rsquo;UE, au sein de l&rsquo;UE.<\/p>\n<\/p>\n<p><p>&laquo; <em>Israel&rsquo;s U-turn is confusing because it is normally quick to denounce anti-Semitism or threats to Jewish communities anywhere in the world. While it made that point in the statement, it chose to focus on the threat it believes Soros poses to Israeli democracy. The foreign ministry&rsquo;s unusual decision to issue a statement clarifying comments by one of its ambassadors comes days before Netanyahu, who also serves as Israel&rsquo;s foreign minister, is scheduled to visit Orban.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em><a href=\"http:\/\/www.reuters.com\/article\/us-israel-hungary-soros-idUSKBN19V1J4\">According to Reuters<\/a>, among the organizations Soros funds is Human Rights Watch, which is frequently critical of Israel&rsquo;s occupation of the West Bank and its policies toward the Palestinians. And, like Hungary, Israel has passed legislation that seeks to limit the influence of non-governmental organizations that receive a large portion of their funding from abroad. In this case from Soros and his Open Society initiative.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Just as strange as Israel&rsquo;s attack on Soros, is Netanyahu&rsquo;s surprisingly close relationship to Hungary&rsquo;s prime minister. As Reuters writes, Israel and Hungary were briefly at odds last month after Orban praised Hungary&rsquo;s World War Two leader Miklos Horthy, calling him an \u00ab\u00a0exceptional statesman\u00a0\u00bb. <\/em><em>Horthy &ndash; an ally of Adolf Hitler who approved anti-Jewish legislation in the 1920s and 1930s &ndash; cooperated with the Germans in deporting Hungarian Jews during the Holocaust. While Israel initially expressed alarm over Orban&rsquo;s remarks, it then quickly accepted the Hungarian government&rsquo;s explanation that Orban had zero tolerance for anti-Semitism and was not suggesting everything Horthy did was positive. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The strong ties between Netanyahu and Orban have raised eyebrows all the way at the European Union, where Orban is regarded as an \u00ab\u00a0illiberal maverick\u00a0\u00bb and populist whose party has curtailed press freedom and stymied EU efforts to tackle the migrant crisis. <\/em><em>Ultimately, however, the explanation for Israel&rsquo;s seemingly bizarre behavior may be simple: money and influence. Hungary has <a href=\"http:\/\/www.reuters.com\/article\/us-europe-migrants-israel-fences-idUSKCN0R31GE20150903\">held discussions with Israel <\/a>about purchasing high tech security fences to keep migrants out, estimated by some to cost in the hundreds of millions of dollars, while Israel has sought better ties with countries that it hopes will take its side in any EU discussions where Israel is criticized. <\/em>&raquo; <\/p>\n<\/p>\n<p><p>On observera d&rsquo;abord que ce n&rsquo;est certainement pas la premi\u00e8re fois qu&rsquo;un rel\u00e8ve un antagonisme entre Soros et Isra\u00ebl, malgr\u00e9 que Soros soit juif et que le fait ait souvent aliment\u00e9 les th\u00e9ories antis\u00e9mites diverses. Le <a href=\"https:\/\/www.bloomberg.com\/view\/articles\/2016-08-16\/how-george-soros-threatens-to-make-israel-a-pariah\">16 ao&ucirc;t 2016<\/a>, <em>Bloomberg.News <\/em>notait qu&rsquo;un antagonisme tr\u00e8s vif opposait Soros et le lobby juif \u00e0 Washington D.C., essentiellement sur des bases apparemment id\u00e9ologiques (Soros se voulant \u00ab\u00a0de gauche\u00a0\u00bb et le lobby \u00e9tat en g\u00e9n\u00e9ral per\u00e7u comme \u00ab\u00a0de droite\u00a0\u00bb, des \u00e9tiquettes grotesques en la circonstance, dans l&rsquo;un et l&rsquo;autre cas, &ndash; une fois de plus discr\u00e9ditant les notions de \u00ab\u00a0gauche\u00a0\u00bb et de \u00ab\u00a0droite\u00a0\u00bb). Quelques jours plus tard, le <a href=\"\/%5D%20http:\/www.jpost.com\/Opinion\/Our-World-Soross-campaign-of-global-chaos-464770\">22 ao&ucirc;t 2016<\/a>, le Jerusalem Post attaquait Soros, cette fois <strong>selon l&rsquo;argument que toutes ses activit\u00e9s tendaient \u00e0 \u00ab\u00a0semer le chaos\u00a0\u00bb dans le monde, et surtout \u00e0 l&rsquo;int\u00e9rieur de la \u00ab\u00a0civilisation\u00a0\u00bb du bloc-BAO<\/strong>. L&rsquo;article se terminait par ce paragraphe :<\/p>\n<\/p>\n<p><p>&laquo; <em>The peoples of the West need to recognize the common foundations of all Soros&rsquo;s actions. They need to realize as well that the only response to these premeditated campaigns of subversion is for the people of the West to stand up for their national rights and their individual right to security. They must stand with the national institutions that guarantee that security, in accordance with the rule of the law, and uphold and defend their national values and traditions<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Par contre, c&rsquo;est certainement <strong>la toute premi\u00e8re fois d&rsquo;une fa\u00e7on aussi officielle sinon solennelle que le gouvernement isra\u00e9lien met en cause Soros<\/strong>, s&rsquo;inscrivant ainsi comme l&rsquo;un des tr\u00e8s rares gouvernements (avec la Hongrie, justement) \u00e0 officiellement avoir mis en cause les activit\u00e9s subversives <strong>et de d\u00e9construction<\/strong> du milliardaire-activiste. Bien entendu, le fait frappant est que Soros est juif et qu&rsquo;il appara&icirc;t dans ses biographies officielles et en g\u00e9n\u00e9ral dans le chef de la presseSyst\u00e8me et de ses \u00ab\u00a0journalistes\u00a0\u00bb comme une victime de l&rsquo;\u00e9v\u00e9nement de l&rsquo;Holocauste. A cet \u00e9gard, on ne s&rsquo;attarde pas trop, dans ces biographies, sur les conditions exactes de cette situation moralement si lou\u00e9e dans la pens\u00e9e-Syst\u00e8me ; c&rsquo;est dommage parce qu&rsquo;elles sont extr\u00eamement ambigu\u00ebs, sinon perverses et compl\u00e8tement inverties. A cet \u00e9gard, nous \u00e9crivions le <a href=\"http:\/\/www.dedefensa.org\/article\/soros-et-ses-coyotes\">27 janvier 2017<\/a>, utilisant des \u00e9l\u00e9ments d&rsquo;un autre texte repris dans le m\u00eame article (\u00ab\u00a0<em>George Soros Declares War on President Trump<\/em>\u00ab\u00a0, article de \u00ab\u00a0Harper\u00a0\u00bb, sur le site <em>Sic Semper Tyrannis<\/em> [SST], le site du colonel Lang, qui restitue le <em>verbatim<\/em> de l&rsquo;\u00e9mission de t\u00e9l\u00e9vision cit\u00e9e, de d\u00e9cembre 1998 sur CBS.<em>News<\/em>).<\/p>\n<\/p>\n<p><p>&laquo; <em>Pour renforcer le texte de Sedov en s&rsquo;attachant \u00e0 la personnalit\u00e9 de Soros, nous reprenons \u00e9galement un texte qui donne diverses pr\u00e9cisions int\u00e9ressantes sur lui en m\u00eame temps qu&rsquo;il aliment la m\u00eame hypoth\u00e8se (\u00ab\u00a0George Soros Declares War on President Trump\u00a0\u00bb). Tout ce mat\u00e9riel est en g\u00e9n\u00e9ral plus ou moins connu, mais il est bon de pouvoir en disposer \u00e0 nouveau, surtout avec des d\u00e9tails int\u00e9ressants et parfois in\u00e9dits. <strong>On y trouve par exemple le d\u00e9tail de l&rsquo;interview de Soros qui s&rsquo;av\u00e8re \u00eatre de d\u00e9cembre 1998, dans l&rsquo;\u00e9mission 60 Minutes de la CBS, qui a depuis \u00e9t\u00e9 le plus souvent possible escamot\u00e9e<\/strong>. Soros y d\u00e9taille son activit\u00e9 en Hongrie en 1944, alors qu&rsquo;il \u00e9tait adolescent, et qu&rsquo;il se mit au service des forces fascistes et des occupants allemands du pays, pour participer \u00e0 la r\u00e9cup\u00e9ration des biens Juifs hongrois d\u00e9port\u00e9s par les Allemands vers les camps d&rsquo;extermination. Juif lui-m\u00eame, et ne manquant jamais de brandir l&rsquo;anath\u00e8me de l&rsquo;Holocauste, Soros commente son r\u00f4le <strong>avec une extr\u00eame d\u00e9sinvolture, du type \u00ab\u00a0il fallait bien que quelqu&rsquo;un fasse ce travail, alors pourquoi pas moi plut\u00f4t qu&rsquo;un autre\u00a0\u00bb<\/strong>&#8230; Ce personnage \u00e9trangement proche de ce qu&rsquo;on imagine \u00eatre un caract\u00e8re diabolique sinon <a href=\"http:\/\/www.dedefensa.org\/article\/message-de-lange-dechu-1\">le Diable<\/a> himself, a cette remarque qu&rsquo;il juge \u00ab\u00a0amusante\u00a0\u00bb, de comparer le r\u00f4le de r\u00e9cup\u00e9rateur des biens juifs (dont certains durent sans doute lui permettre de lancer sa fortune) \u00e0 celui de trader-sp\u00e9culateur : \u00ab\u00a0Mais je n&rsquo;avais en aucune fa\u00e7on l&rsquo;id\u00e9e que je n&rsquo;aurais pas d&ucirc; \u00eatre l\u00e0, parce qu&rsquo;en fait &#8230; d&rsquo;un point de vue assez amusant, c&rsquo;est comme sur les march\u00e9s sp\u00e9culatifs &#8230; l&rsquo;id\u00e9e que si je n&rsquo;avais pas \u00e9t\u00e9 l\u00e0, bien s&ucirc;r je n&rsquo;aurais pas fait ces choses mais quelqu&rsquo;un d&rsquo;autre les aurait&#8230; enfin, de toutes les fa\u00e7ons, elles auraient \u00e9t\u00e9 faites&#8230;\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>On voit que le personnage de Soros, &ndash; que nous aurions purement et simplement <strong>tendance \u00e0 consid\u00e9rer comme <a href=\"http:\/\/www.dedefensa.org\/article\/message-de-lange-dechu-1\">diabolique<\/a><\/strong>, &ndash; d\u00e9passe largement les querelles habituelles et en g\u00e9n\u00e9ral complotistes qui entourent des personnalit\u00e9s juives de cet acabit, et permet de mieux appr\u00e9hender l&rsquo;antagonisme \u00e0 premi\u00e8re vue surprenant entre Isra\u00ebl et lui. Nous pensons qu&rsquo;il faut comprendre cet antagonisme <strong>du point de vue du \u00ab\u00a0d\u00e9constructeur\u00a0\u00bb (ou \u00ab\u00a0d\u00e9construction-dissolution-entropisation\u00a0\u00bb)<\/strong>. Pour nous, Soros n&rsquo;est pas un personnage classique des habituelles rengaines de l&rsquo;antis\u00e9mitisme et du complot qui va avec, mais bien un personnage-clef de la tendance postmoderne de la d\u00e9construction, ou bien pour nous de la dynamique d\u00e9structuration-dissolution-entropisation ; c&rsquo;est-\u00e0-dire <strong>un personnage-clef de la tendance de la destruction du monde par l&rsquo;attaque de tout ce qui est principiel<\/strong> ; ce pourquoi, bien entendu, il nous appara&icirc;t \u00e9galement comme <strong>purement et simplement diabolique<\/strong>, dans le sens le plus large de ce mot, y compris de type-m\u00e9taphysique ou plut\u00f4t anti-m\u00e9taphysique, et bien entendu du type-th\u00e9ologique si l&rsquo;on veut se r\u00e9f\u00e9rer au ph\u00e9nom\u00e8ne religieux<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans ce cas, Isra\u00ebl se pr\u00e9sente comme une structure reposant sur des principes, et cette structure qui en appelle \u00e0 la l\u00e9gitimit\u00e9 et \u00e0 la souverainet\u00e9 consid\u00e8re Soros comme un pur ennemi, un destructeur de soi-m\u00eame. Bien s&ucirc;r, on peut observer ironiquement qu&rsquo;Isra\u00ebl joue bien souvent un r\u00f4le d\u00e9structurant lui-m\u00eame, mais il s&rsquo;agit l\u00e0 des avatars qui font se d\u00e9placer les acteurs du r\u00f4le de soutien du Syst\u00e8me au r\u00f4le de l&rsquo;antiSyst\u00e8me selon la position occup\u00e9e et la bataille qui est conduite. <strong>Dans le cas qui nous occupe, Isra\u00ebl s&rsquo;oppose \u00e0 Soros-le-d\u00e9constructeur qu&rsquo;il identifie justement comme un ennemi jur\u00e9 de tout ce qui est structurel, principiel et l\u00e9gitimant<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi sommes-nous tr\u00e8s peu partisans de l&rsquo;explication que sugg\u00e8re <em>ZeroHedge.com<\/em> (\u00ab\u00a0influence et argent\u00a0\u00bb) pour pr\u00e9senter les tr\u00e8s bonnes relations d&rsquo;Isra\u00ebl avec une Hongrie quasiment fasciste que la vulgate-Syst\u00e8me de type-UE percevrait plut\u00f4t comme une ennemie d&rsquo;un Isra\u00ebl pr\u00e9sent\u00e9 dans ce cas comme un reliquat vertueux de l&rsquo;Holocauste. (A moins que l&rsquo;on s&rsquo;attache \u00e0 l&rsquo;objet m\u00eame de cette raison, puisque l&rsquo;\u00e9vocation de \u00ab\u00a0l&rsquo;influence [et de] l&rsquo;argent\u00a0\u00bb concerne un contrat important pour que la Hongrie obtienne l&rsquo;aide d&rsquo;Isra\u00ebl pour l&rsquo;\u00e9dification d&rsquo;un mur permettant de contrecarrer l&rsquo;entr\u00e9e d&rsquo;immigrants ill\u00e9gaux en Hongrie.) Il devrait \u00eatre de notori\u00e9t\u00e9 publique que l&rsquo;une des contradictions d&rsquo;Isra\u00ebl, en face de son r\u00f4le d\u00e9constructeur du Moyen-Orient, c&rsquo;est son avenir en tant que soci\u00e9t\u00e9 homog\u00e8ne et structur\u00e9e face aux diverses pressions extr\u00e9mistes et fondamentalistes (aussi bien ceux des juifs les plus orthodoxes que ceux des islamistes). Cette position <strong>rapproche ce pays de certains autres qui luttent \u00e9galement d&rsquo;une fa\u00e7on ouverte contre les pressions per\u00e7ues comme d\u00e9structurantes et d\u00e9constructrices que lui impose le Syst\u00e8me<\/strong>, ce qui est le cas de la Hongrie sur cette question de l&rsquo;immigration que voudrait lui imposer Bruxelles. Dans ce cas, on arrive donc \u00e0 une situation o&ugrave; <strong>l&rsquo;UE et Soros sont des alli\u00e9s objectifs dans la t\u00e2che de la d\u00e9construction, tandis que la Hongrie de Orban et l&rsquo;Isra\u00ebl de Netanyahou sont des alli\u00e9s contre cette pouss\u00e9e<\/strong>. C&rsquo;est un sujet dont parleront certainement Orban et Netanyahou durant la tr\u00e8s prochaine visite du Premier ministre isra\u00e9liens en Hongrie.<\/p>\n<\/p>\n<p><p>Mis en ligne le 11 juillet 2017 \u00e0 10H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isra\u00ebl vs Soros : qui est le d\u00e9constructeur ? Il y a \u00e0 nouveau un tr\u00e8s s\u00e9rieux accrochage entre Isra\u00ebl et Soros, cette fois de la mani\u00e8re la plus officielle puisqu&rsquo;il s&rsquo;agit d&rsquo;une communication du minist\u00e8re isra\u00e9lien des affaires \u00e9trang\u00e8res rectifiant un communiqu\u00e9 de l&rsquo;ambassadeur d&rsquo;Isra\u00ebl en Hongrie. Ce dernier (l&rsquo;ambassadeur) avait condamn\u00e9 une campagne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3334,4646,7482,4880,5530,12725,2722],"class_list":["post-77058","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisemitisme","tag-antisysteme","tag-deconstruction","tag-holocauste","tag-hongrie","tag-migration","tag-orban"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77058"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77058\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}