{"id":77102,"date":"2017-02-18T10:12:25","date_gmt":"2017-02-18T10:12:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/18\/pourquoi-le-systeme-veut-faire-passer-marine\/"},"modified":"2017-02-18T10:12:25","modified_gmt":"2017-02-18T10:12:25","slug":"pourquoi-le-systeme-veut-faire-passer-marine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/18\/pourquoi-le-systeme-veut-faire-passer-marine\/","title":{"rendered":"Pourquoi le syst\u00e8me veut faire passer Marine"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pourquoi le syst\u00e8me veut faire passer Marine<\/h2>\n<\/p>\n<p><p>La rapidit\u00e9 de la soumission de Trump au syst\u00e8me a \u00e9t\u00e9 admirable, comme la soumission de Syriza en Gr\u00e8ce, ou la rapidit\u00e9 de l&rsquo;annulation du Brexit ! Comme dirait C\u00e9line, la r\u00e9sistance populiste ne demande qu&rsquo;\u00e0 <em>foutre le camp<\/em> &#8211; ou \u00e0 cliquer rageusement sur sa souris&hellip;<\/p>\n<\/p>\n<p><p>Voyons le cas de Marine \u00e9lue.<\/p>\n<\/p>\n<p><p>La France aurait des taux d&rsquo;int\u00e9r\u00eat pour rembourser sa dette qui monteraient le soir-m\u00eame \u00e0 10%. La France aurait une r\u00e9volution orange dans la rue. La France aurait une r\u00e9bellion de la fonction publique. La France aurait une fuite de capitaux. La France aurait des bourgeois d\u00e9sesp\u00e9r\u00e9s par l&rsquo;effondrement du prix des appartements parisiens et des ch\u00e2teaux ancestraux. La France se ferait ferrer par l&rsquo;Otan encore plus vite que la Serbie. La France se prendrait les attentats les plus rapides de sa carri\u00e8re&hellip; <strong>Pour toutes ces raisons, le syst\u00e8me veut Marine.<\/strong><\/p>\n<\/p>\n<p><p>Il y a un m\u00e9contentement unique. Il ne cesse pas encore et il peut \u00eatre stopp\u00e9. Par qui ? Par l&rsquo;\u00e9lection du candidat r\u00e9siduel le plus <em>m\u00e9chant<\/em> pour l&rsquo;oligarchie mondiale : le candidat FN, qui est l\u00e0 depuis trente ans. Le caract\u00e8re pseudo-r\u00e9volutionnaire (la Bastille) de la France ici sera utilis\u00e9 \u00e0 plein. Soumettons les Fran\u00e7ais et le reste suivra vite.<\/p>\n<\/p>\n<p><p><strong>Donc je dis : le syst\u00e8me a int\u00e9r\u00eat \u00e0 faire \u00e9lire Marine Le Pen.<\/strong> Le <em>bataclan<\/em> si elle est \u00e9lue serait tel qu&rsquo;elle se soumettrait encore plus vite que son mod\u00e8le Trump. Le syst\u00e8me pourrait alors imposer plus vite son agenda terroriste et totalitaire : guerre contre la rebelle Russie, invasion du sud, abolition du cash, contr\u00f4le biom\u00e9trique, interdiction de l&rsquo;or, censure du r\u00e9seau, etc.<\/p>\n<\/p>\n<p><p>Le chaos de l&rsquo;\u00e9lection FN serait tel que le tsunami (qui est comme on sait une m\u00e9thode de contr\u00f4le froid, comme l&rsquo;attentat, l&rsquo;effet de serre, le r\u00e9fugi\u00e9) serait imparable. Donc le syst\u00e8me va faire \u00e9lire Marine qui a d\u00e9j\u00e0 donn\u00e9 des garanties en virant son p\u00e8re. <strong>Tel est son int\u00e9r\u00eat : crever l&rsquo;abc\u00e8s populiste une fois pour toutes.<\/strong><\/p>\n<\/p>\n<p><p>Dans mon livre sur Trump, publi\u00e9 avant son \u00e9lection, j&rsquo;annon\u00e7ais d\u00e9j\u00e0 la couleur (p.171) :<\/p>\n<\/p>\n<p><p>&laquo; Relisant les pages informatives que nous avons rassembl\u00e9es sur Donald Trump, nous traversons une crise morale. Tout nous semble boursoufl\u00e9, truqu\u00e9, presque minable. Ses affaires, sa fortune m\u00eame semble gonfl\u00e9e. Ses propos sont nuls ou scandaleux, ou ne m\u00e9ritent m\u00eame pas d&rsquo;\u00eatre relev\u00e9s.<\/p>\n<\/p>\n<p><p><strong>Quelques propositions int\u00e9ressantes et courageuses sont vite contredites. Sa politique est inapplicable<\/strong> et c&rsquo;est tant mieux comme \u00e7a. Il suscite en outre tellement d&rsquo;hostilit\u00e9 \u00e0 l&rsquo;\u00e9tranger et dans les milieux importants (t\u00e9l\u00e9vision, n\u00e9goces) qu&rsquo;il risque d&rsquo;\u00eatre ruin\u00e9 avant m\u00eame l&rsquo;\u00e9lection. &raquo;<\/p>\n<\/p>\n<p><p>Et la suite \u00e9tait simple \u00e0 pr\u00e9voir au chapitre XVII :<\/p>\n<\/p>\n<p><p>&laquo; &hellip;<strong> il semble que l&rsquo;affaire Trump va servir d&rsquo;op\u00e9ration psychologique au niveau mondial. Le syst\u00e8me a peur des foules, et il a besoin de faire un exemple &ndash; en montrant le mauvais&hellip;<\/strong> l&rsquo;accusation de racisme, de nazisme, de fascisme, de machisme par les m\u00e9dias, les exc\u00e8s ou soi-disant exc\u00e8s de Trump porteront leurs fruits et <strong>tout le petit monde du petit blanc frustr\u00e9 rentrera dans sa niche comme en France<\/strong>. Il sera &laquo; agit\u00e9 &raquo; une nouvelle fois avant de &laquo; s&rsquo;asservir &raquo; pour rien, et c&rsquo;est tant mieux ! &raquo;<\/p>\n<\/p>\n<p><p>Je donnais une bonne r\u00e9f\u00e9rence cin\u00e9ma datant des troubldes ann\u00e9es Nixon-Ford (plus troubl\u00e9es qu&rsquo;en 2017, car il y avait un reste de marxisme et le militant \u00e9tait encore dispos\u00e9 \u00e0 se sacrifier pour les imposer &ndash;aujourd&rsquo;hui il clique) :<\/p>\n<\/p>\n<p><p>&laquo; Dans le Film <em>Network<\/em> de 1976, le pr\u00e9sentateur t\u00e9l\u00e9 Howard Beale invite le t\u00e9l\u00e9spectateur \u00e0 se rebeller et \u00e0 gueuler par sa fen\u00eatre &ndash; ce qu&rsquo;il s&#8217;empresse de faire. Ensuite pour plaire \u00e0 son patron, qui parle de marks, de dollars, de roubles, de shekels, de march\u00e9, de capital, de chiffres, de syst\u00e8me holistique, de nature (le capital adore \u00e7a), d&rsquo;investissements, de fin des peuples, de pognon, de &laquo; <em>mouvement autonome du non-vivant<\/em>&raquo;, il pr\u00eache un \u00e9vangile de la r\u00e9signation &ndash; et se fait enfin tuer pour baisse de taux d&rsquo;\u00e9coute ! Le film marquait la transition de la r\u00e9bellion \u00e0 la soumission. &raquo;<\/p>\n<\/p>\n<p><p>Et je continuai :<\/p>\n<\/p>\n<p><p>&laquo; Il se peut que Trump serve aussi d&rsquo;exorcisme \u00e0 la fin pour calmer le ressentiment g\u00e9n\u00e9ral en Am\u00e9rique et organiser plus calmement la faillite du pays qui a d\u00e9j\u00e0 commenc\u00e9, m\u00eame si elle est d\u00e9crite rarement. La fascisation et la militarisation des Etats-Unis d\u00e9crite par Paul Craig Roberts servira \u00e0 pr\u00e9venir ou \u00e9craser massivement toute r\u00e9bellion, d&rsquo;o&ugrave; qu&rsquo;elle vienne. Il semble bien que l&rsquo;on en prenne aussi le chemin en France. &raquo;<\/p>\n<\/p>\n<p><p><strong>Oui, faire monter le p\u00e9ril FN et m\u00eame faire \u00e9lire Marine est la meilleure chose qui puisse arriver au syst\u00e8me.<\/strong> La bourse et l&rsquo;immobilier \u00e9croul\u00e9s pour un temps assez bref serviront les malins. L&rsquo;optimisme des antisyst\u00e8mes, on sait o&ugrave; cela m\u00e8ne (Cuba ? Caracas ?)&hellip;<\/p>\n<\/p>\n<p><p>Je rappelais que cette tactique est d\u00e9crite par Aristote dans sa remarquable <em>Politique<\/em> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans la d\u00e9mocratie, les r\u00e9volutions naissent avant tout de la turbulence des d\u00e9magogues. Pour ce qui concerne les particuliers, ils contraignent par leurs d\u00e9nonciations perp\u00e9tuelles les riches eux-m\u00eames \u00e0 se r\u00e9unir pour conspirer ; car la communaut\u00e9 de crainte rapproche les gens les plus ennemis.<\/em><\/p>\n<\/p>\n<p><p>Et le plus grand philosophe de l&rsquo;Antiquit\u00e9 de ponctuer froidement, comme s&rsquo;il avait pr\u00e9vu la fin du mauvais film :<\/p>\n<\/p>\n<p><p>&laquo; <em>Par leurs injustices, les d\u00e9magogues et leurs comp\u00e8res avaient contraint les citoyens puissants \u00e0 quitter la ville ; mais les exil\u00e9s se r\u00e9unirent, et, revenant contre le peuple, ils lui arrach\u00e8rent tout son pouvoir. <\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong>Cette tactique (une simple op\u00e9ration psy) n&rsquo;a pas chang\u00e9 depuis trois mille ans. <\/strong>Le peuple en a parfois marre des \u00e9lites. Les \u00e9lites laissent un populiste arriver au pouvoir, puis elles le liquident &#8211; sauf quand elles le secondent, comme dans le cas trop connu du caporal boh\u00e9mien.<\/p>\n<\/p>\n<p><p>Sourions, nous sommes bien gard\u00e9s !<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Bibliographie<\/h3>\n<\/p>\n<p><p>Aristote &ndash; Politique, livre VIII, th\u00e9orie g\u00e9n\u00e9rale des r\u00e9volutions (traduit par Barth\u00e9l\u00e9my Sant-Hilaire, 1874 (sur Remacle.org)<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; Donald Trump, candidat du chaos, Editions Dualpha, chapitres XVI et XVII<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi le syst\u00e8me veut faire passer Marine La rapidit\u00e9 de la soumission de Trump au syst\u00e8me a \u00e9t\u00e9 admirable, comme la soumission de Syriza en Gr\u00e8ce, ou la rapidit\u00e9 de l&rsquo;annulation du Brexit ! Comme dirait C\u00e9line, la r\u00e9sistance populiste ne demande qu&rsquo;\u00e0 foutre le camp &#8211; ou \u00e0 cliquer rageusement sur sa souris&hellip; Voyons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[12787,4926,11963,3572,12786,2639],"class_list":["post-77102","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-aristote","tag-complot","tag-elites-systeme","tag-marine","tag-populistes","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77102"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77102\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}