{"id":77110,"date":"2017-02-22T14:54:12","date_gmt":"2017-02-22T14:54:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/22\/rene-guenon-et-la-conspiration-mondialiste-en-1920\/"},"modified":"2017-02-22T14:54:12","modified_gmt":"2017-02-22T14:54:12","slug":"rene-guenon-et-la-conspiration-mondialiste-en-1920","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/22\/rene-guenon-et-la-conspiration-mondialiste-en-1920\/","title":{"rendered":"Ren\u00e9 Gu\u00e9non et la conspiration mondialiste en 1920"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Ren\u00e9 Gu\u00e9non et la conspiration mondialiste en 1920<\/h2>\n<\/p>\n<p><p>On rappelle la phrase \u00e9ternelle de Chateaubriand, extraite de la conclusion de ses M\u00e9moires:<\/p>\n<\/p>\n<p><p>&laquo; La folie du moment est d&rsquo;arriver \u00e0 l&rsquo;unit\u00e9 des peuples et de ne faire qu&rsquo;un seul homme de l&rsquo;esp\u00e8ce enti\u00e8re&hellip; &raquo;<\/p>\n<\/p>\n<p><p>On pourrait croire que Ren\u00e9 Gu\u00e9non s&rsquo;adresse \u00e0 un a\u00e9ropage d&rsquo;apprentis-initi\u00e9s en rupture de ban avec le monde moderne et en recherche d&rsquo;une s&ucirc;re spiritualit\u00e9. Rien de plus erron\u00e9. Il a publi\u00e9 nombre de livres et de textes pratiques, inform\u00e9s contre le monde moderne et ses conspirations, ou contre le monde moderne et son abrutissement (sa d\u00e9nonciation du courtisan moli\u00e9resque \u00e0 perruque, ignorant du moyen \u00e2ge, montre que ce monde moderne est apparu d&rsquo;un coup, vers et apr\u00e8s la Renaissance). Les noms ont \u00e0 peine chang\u00e9, les m\u00e9thodes et les objectifs restent les m\u00eames : conspiration, universalisme, gouvernement global, exotisme andro\u00efde, humanitarisme cool, r\u00e9gime alimentaire !<\/p>\n<\/p>\n<p><p>Parmi ces livres, celui sur le th\u00e9osophisme. Il annonce la belle conspiration mondiale, multiraciale et occultiste sous l&rsquo;\u00e9gide anglo-saxonne et en particulier britannique. Ce livre devait attaquer la secte sur le plan spirituel, mais Gu\u00e9non ne r\u00e9siste pas dans les derniers chapitres de son livre \u00e0 d\u00e9voiler ce qui se trame derri\u00e8re la coulisse, comme disait notre bon Disraeli.<\/p>\n<\/p>\n<p><p>Et cela donne par exemple ces lignes sur l&rsquo;orientation humaniste ou m\u00eame v\u00e9g\u00e9tarienne de la secte :<\/p>\n<\/p>\n<p><p>&hellip; <em>il est facile de se rendre compte que le but d\u00e9clar\u00e9 de presque toutes ces associations, en mettant \u00e0 part celles qui ont un caract\u00e8re tr\u00e8s sp\u00e9cial et ouvertement th\u00e9osophiste, se rattache \u00e0 peu pr\u00e8s exclusivement \u00e0 un certain nombre d&rsquo;id\u00e9es directrices \u00e0 base sentimentale : humanitarisme, pacifisme, antialcoolisme, v\u00e9g\u00e9tarisme, qui sont particuli\u00e8rement ch\u00e8res \u00e0 la mentalit\u00e9 essentiellement moraliste&raquo; du Protestantisme anglo-saxon. Certains mouvements actuels, certaines campagnes antialcooliques par exemple, ont des dessous fort curieux \u00e0 \u00e9tudier&hellip;<\/em><\/p>\n<\/p>\n<p><p>Sur cette base humanitaire on d\u00e9clare tout le temps la guerre, y compris \u00e0 son syst\u00e8me digestif.<\/p>\n<\/p>\n<p><p>Gu\u00e9non remarque sur le v\u00e9g\u00e9tarisme (cf. les interdits hitl\u00e9riens \u00e0 cet \u00e9gard) :<\/p>\n<\/p>\n<p><p><em>&hellip; nous sommes les fr\u00e8res des animaux, disent-ils, et on ne doit pas d\u00e9vorer ses fr\u00e8res, m\u00eame s&rsquo;ils sont moins &laquo; \u00e9volu\u00e9s &raquo; que nous ; on pourrait leur r\u00e9pondre que, de la fa\u00e7on dont ils comprennent l&rsquo;\u00e9volution, nous sommes aussi les fr\u00e8res des v\u00e9g\u00e9taux, voire m\u00eame des min\u00e9raux, de sorte que leur raisonnement, rigoureusement poursuivi et appliqu\u00e9, nous condamnerait \u00e0 mourir de faim purement et simplement.<\/em><\/p>\n<\/p>\n<p><p>Dans le chapitre-cl\u00e9, le XXIX, Gu\u00e9non indique que la secte est \u00e0 dominante anglaise et surtout imp\u00e9rialiste :<\/p>\n<\/p>\n<p><p><em>&hellip;si la Soci\u00e9t\u00e9 prise dans son ensemble est en effet internationale, sa direction n&rsquo;en est pas moins devenue purement anglaise ; aussi, quelles qu&rsquo;aient pu \u00eatre parfois les apparences, nous avons la conviction, nous pourrions m\u00eame dire la certitude, que le th\u00e9osophisme, envisag\u00e9 sous ce rapport, est surtout un instrument au service de l&rsquo;imp\u00e9rialisme britannique.<\/em><\/p>\n<\/p>\n<p><p>La secte pensait garder le contr\u00f4le de l&rsquo;Inde, qui n&rsquo;a jamais su se lib\u00e9rer de l&#8217;emprise occidentale. Consid\u00e9rez cette abolition du <em>cash<\/em>, qui sent le <em>sectif\u00e9r\u00e9<\/em>.<\/p>\n<\/p>\n<p><p>&laquo; Beaucoup de vieux Indiens et plusieurs livres sur la r\u00e9volte de l&rsquo;Inde parlent de la mani\u00e8re incompr\u00e9hensible dont les nouvelles d&rsquo;\u00e9v\u00e9nements ayant lieu \u00e0 distance p\u00e9n\u00e9traient quelquefois dans les bazars des natifs avant qu&rsquo;elles arrivassent aux Europ\u00e9ens, dans les m\u00eames endroits, malgr\u00e9 l&#8217;emploi des moyens de communications les plus rapides dont ils pouvaient disposer. L&rsquo;explication qui m&rsquo;a \u00e9t\u00e9 donn\u00e9e de ce fait est que les Fr\u00e8res (c&rsquo;est-\u00e0-dire les &laquo; Mahatmas &raquo;), qui \u00e0 cette \u00e9poque d\u00e9siraient conserver le pouvoir britannique parce qu&rsquo;ils le regardaient comme pr\u00e9f\u00e9rable pour l&rsquo;Inde \u00e0 tout autre syst\u00e8me de gouvernement venant des natifs. &raquo;<\/p>\n<\/p>\n<p><p>Un bon gouvernement mondial pour tout le monde &#8211; \u00e0 dominante humanitaire. Pour GK Chesterton comme pour Jack London il en va de m\u00eame \u00e0 la m\u00eame \u00e9poque. Tiens, un peu de Jack London pour la piqure de rappel. Il parle d\u00e9j\u00e0 de nos \u00e9lites dans le Talon de fer :<\/p>\n<\/p>\n<p><p><em>Ils se croyaient les sauveurs du genre humain, et se consid\u00e9raient comme des travailleurs h\u00e9ro\u00efques se sacrifiant pour son plus grand bien. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Jack London rajoute :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ils \u00e9taient convaincus que leur classe \u00e9tait l&rsquo;unique soutien de la civilisation&hellip; Sans eux, l&rsquo;anarchie r\u00e9gnerait et l&rsquo;humanit\u00e9 retomberait dans la nuit primordiale d&rsquo;o&ugrave; elle eut tant de peine \u00e0 \u00e9merger. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Et l&rsquo;\u00e9lite finit alors par ha\u00efr le peuple :<\/p>\n<\/p>\n<p><p>&laquo; <em>Telle \u00e9tait la b\u00eate (le peuple) qu&rsquo;il fallait fouler aux pieds, et son \u00e9crasement constituait le supr\u00eame devoir de l&rsquo;aristocrate &raquo;.<\/em><\/p>\n<\/p>\n<p><p>Retour \u00e0 Ren\u00e9 Gu\u00e9non qui va pr\u00e9ciser une autre fois les objectifs mondiaux de la bonne vieille secte imp\u00e9riale (tout empire est par essence multiracial ; et plus une r\u00e9publique est multiraciale plus elle devient imp\u00e9riale &ndash; ou l&rsquo;inverse) :<\/p>\n<\/p>\n<p><p>&laquo; <em>Voici le texte de ce serment, dont le d\u00e9but ne laisse place \u00e0 aucune \u00e9quivoque : &laquo; Estimant que l&rsquo;int\u00e9r\u00eat primordial de l&rsquo;Inde est de <strong>se d\u00e9velopper librement sous le pavillon britannique, de s&rsquo;affranchir de toute coutume<\/strong> qui puisse nuire \u00e0 l&rsquo;union de tous les habitants, et de rendre \u00e0 l&rsquo;Hindouisme un peu de <strong>flexibilit\u00e9 sociale<\/strong> et de fraternisme v\u00e9cu, je promets (&hellip;) :  5&deg; <strong>de ne tenir aucun compte, dans la vie sociale et politique, des diff\u00e9rences de couleur et de race ; de faire ce que je pourrai pour favoriser l&rsquo;entr\u00e9e libre des races de couleur dans tous les pays, sur le m\u00eame pied que les \u00e9migrants blancs ; 6&deg; de combattre activement tout ostracisme social<\/strong> en ce qui concerne les veuves qui se remarient ; 7&deg; d&rsquo;encourager l&rsquo;union des travailleurs dans tous les domaines de progr\u00e8s spirituel, \u00e9ducatif, social et politique, sous la direction du Congr\u00e8s National Hindou &raquo;. <\/em><\/p>\n<\/p>\n<p><p>Annulation des nations et cr\u00e9ation d&rsquo;un r\u00e9seau de fr\u00e8res ! Gu\u00e9non pr\u00e9cise :<\/p>\n<\/p>\n<p><p><em>&laquo; Ce pr\u00e9tendu &laquo; Congr\u00e8s National Hindou &raquo;, il est bon de le dire, fut cr\u00e9\u00e9 par l&rsquo;administration Anglaise avec la coop\u00e9ration des th\u00e9osophistes&hellip; &raquo;<\/em><\/p>\n<\/p>\n<p><p>Et il rappelle que l&rsquo;on a fait mine d&rsquo;arr\u00eater alors l&rsquo;agent (pardon, la grande initi\u00e9e) Annie Besant :<\/p>\n<\/p>\n<p><p>&laquo; On a bien essay\u00e9, en 1916, pour la r\u00e9habiliter aux yeux des Hindous et donner \u00e0 ceux-ci quelque confiance en elle, d&rsquo;un <strong>simulacre d&rsquo;internement<\/strong> dans sa propre villa de Gulistan, ce qui ne l&#8217;emp\u00eacha d&rsquo;ailleurs nullement d&rsquo;y tenir des r\u00e9unions ; mais cette ruse assez grossi\u00e8re ne put tromper personne, et il n&rsquo;y a qu&rsquo;en Europe que quelques-uns ont cru que cette mesure avait \u00e9t\u00e9 motiv\u00e9e par un changement r\u00e9el dans l&rsquo;attitude politique de Besant. &raquo;<\/p>\n<\/p>\n<p><p>Et Gu\u00e9non termine par les buts messianiques de l&rsquo;\u00e9poque.<\/p>\n<\/p>\n<p><p>&laquo; &hellip;l&rsquo;Angleterre est appel\u00e9e \u00e0 dicter ses lois au monde entier (le r\u00f4le essentiel du Manou est, en effet, le r\u00f4le de l\u00e9gislateur). <strong>Ce sera bien la r\u00e9alisation des &laquo; Etats-Unis du Monde <\/strong>&raquo;, mais sous l&rsquo;\u00e9gide de la &laquo; nation dirigeante et \u00e0 son profit exclusif ; ainsi, l&rsquo;internationalisme des chefs du th\u00e9osophisme, c&rsquo;est bien, tout simplement, l&rsquo;imp\u00e9rialisme britannique port\u00e9 \u00e0 son degr\u00e9 le plus extr\u00eame&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Un autre qui avait bien d\u00e9crit la m\u00e9thode imp\u00e9riale est cet auteur :<\/p>\n<\/p>\n<p><p><strong><em>Sous peine de mor<\/em><\/strong><em>t, elle force toutes les nations \u00e0 adopter le mode bourgeois de production; <strong>elle les force \u00e0 introduire chez elles ce qu&rsquo;elle appelle civilisation, c&rsquo;est-\u00e0-dire \u00e0 devenir bourgeoises.<\/strong> En un mot, elle se fa\u00e7onne un monde \u00e0 son image.<\/em><\/p>\n<\/p>\n<p><p><strong>Sous peine de mort<\/strong> : Marx a tout dit. Quand vous calculerez le nombre de civilisations que les anglo-saxons &#8211; ou les occidentaux- ont d\u00e9truites dans le monde entier&hellip;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Bibliographie<\/h3>\n<\/p>\n<p><p>Chateaubriand &ndash; M\u00e9moires d&rsquo;Outre-tombe (conclusion)<\/p>\n<\/p>\n<p><p>Chesterton &ndash; Un nomm\u00e9 jeudi &ndash; H\u00e9r\u00e9tiques &ndash; le retour de Don Quichotte<\/p>\n<\/p>\n<p><p>Mgr Henri Delassus &ndash; La conjuration antichr\u00e9tienne<\/p>\n<\/p>\n<p><p>Ren\u00e9 Gu\u00e9non &ndash; Le th\u00e9osophisme, histoire d&rsquo;une pseudo-religion &ndash; Le r\u00e8gne de la quantit\u00e9 &ndash; L&rsquo;erreur spirite &ndash; La Crise du monde moderne<\/p>\n<\/p>\n<p><p>Jack London &ndash; Le Talon de fer<\/p>\n<\/p>\n<p><p>Marx &#8211; Manifeste du parti communiste<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; Litt\u00e9rature et conspiration : les grand auteurs \u00e0 l&rsquo;\u00e2ge des complots (Dualpha) &ndash; Chroniques sur la Fin de l&rsquo;Histoire (Amazon-Kindle)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ren\u00e9 Gu\u00e9non et la conspiration mondialiste en 1920 On rappelle la phrase \u00e9ternelle de Chateaubriand, extraite de la conclusion de ses M\u00e9moires: &laquo; La folie du moment est d&rsquo;arriver \u00e0 l&rsquo;unit\u00e9 des peuples et de ne faire qu&rsquo;un seul homme de l&rsquo;esp\u00e8ce enti\u00e8re&hellip; &raquo; On pourrait croire que Ren\u00e9 Gu\u00e9non s&rsquo;adresse \u00e0 un a\u00e9ropage d&rsquo;apprentis-initi\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2875,2631,2632,9772,2622,12812,12811],"class_list":["post-77110","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-chateaubriand","tag-de","tag-globalisation","tag-guenon","tag-la","tag-quantite","tag-regne"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77110"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77110\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}