{"id":77116,"date":"2017-02-27T13:21:37","date_gmt":"2017-02-27T13:21:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/27\/linsoutenable-decomposition-de-lame-du-monde\/"},"modified":"2017-02-27T13:21:37","modified_gmt":"2017-02-27T13:21:37","slug":"linsoutenable-decomposition-de-lame-du-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/02\/27\/linsoutenable-decomposition-de-lame-du-monde\/","title":{"rendered":"L&rsquo;insoutenable d\u00e9composition de l&rsquo;\u00e2me du monde"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">L&rsquo;insoutenable d\u00e9composition de l&rsquo;\u00e2me du monde<\/h2>\n<\/p>\n<p><p>27 f\u00e9vrier 2017 &ndash; Nous d\u00e9veloppons notre r\u00e9flexion \u00e0 partir d&rsquo;un article du 25 f\u00e9vrier de Erico Mathias Tavares de l&rsquo;agence de marketing Sinclair &#038; Co (article disponible sur <a href=\"https:\/\/www.linkedin.com\/pulse\/two-state-solution-west-erico-matias-tavares\"><em>LikedIn<\/em><\/a> et sur <a href=\"http:\/\/www.zerohedge.com\/news\/2017-02-25\/two-state-solution-west\"><em>ZeroHedge.com<\/em><\/a>), avec le titre &laquo; <em>A Two-State Solution&#8230; For the West?<\/em> &raquo;. Il s&rsquo;agit d&rsquo;une appr\u00e9ciation argument\u00e9e et chiffr\u00e9e sur <strong>l&rsquo;extraordinaire division antagoniste et extr\u00e9miste qui s&rsquo;est install\u00e9e aux USA avec Trump<\/strong>, qui marque \u00e9galement, d&rsquo;une mani\u00e8re diff\u00e9rente et peut-\u00eatre moins spectaculaire <strong>mais tout aussi insoutenable<\/strong>, les pays de l&rsquo;UE. Tavares embrasse donc avec juste raison la situation \u00ab\u00a0de l&rsquo;Ouest\u00a0\u00bb, ce que nous nommons dans notre jargon \u00ab\u00a0bloc-BAO\u00a0\u00bb, c&rsquo;est-\u00e0-dire le c&oelig;ur et la substance m\u00eame de notre \u00ab\u00a0civilisation-devenue-contre-civilisation\u00a0\u00bb dont les caract\u00e8res de puissance et les \u00ab\u00a0valeurs\u00a0\u00bb constituent le paradigme dominant de l&rsquo;\u00e9poque, d\u00e9velopp\u00e9 dans un esprit de terrorisation et d&rsquo;une fa\u00e7on totalitaire. Cette \u00ab\u00a0division antagoniste\u00a0\u00bb \u00e0 l&rsquo;int\u00e9rieur du bloc-BAO et, d&rsquo;une fa\u00e7on spectaculaire, aux USA m\u00eame, est \u00e9videmment le signe principal marquant la Grande Crise de cette contre-civilisation (<em>ditto<\/em>, la Grande Crise d&rsquo;effondrement du Syst\u00e8me).<\/p>\n<\/p>\n<p><p>Rien dans l&rsquo;article de Tavares n&rsquo;\u00e9voque les questions g\u00e9opolitiques, financi\u00e8res, etc., bref tout ce qui fait d&rsquo;habitude les fondements des relations internationales <strong>lorsqu&rsquo;elles se d\u00e9veloppent dans un cadre accept\u00e9 par tous, et aussi les causes habituelles des situations crisiques. <\/strong>(M\u00eame si ces relations sont conflictuelles sinon violemment conflictuelles, m\u00eame si ce cadre est instable, changeant de forme, etc., <strong>il s&rsquo;agit toujours de relations internationales \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un cadre commun<\/strong> : m\u00eame Hitler, appr\u00e9ci\u00e9 comme criminel sans pr\u00e9c\u00e9dent ni \u00e9quivalent, comme monstrueux, comme malade, comme fou, etc., m\u00eame lui \u00e9voluait dans ce cadre commun et la preuve en fut donn\u00e9e par le fait que les chefs nazis furent jug\u00e9s par un tribunal occidental \u00e0 Nuremberg, signifiant ainsi qu&rsquo;il y avait bien un cadre commun.)<\/p>\n<\/p>\n<p><p>A partir de la r\u00e9f\u00e9rence \u00e0 ce conflit qui nous d\u00e9chire aujourd&rsquo;hui parce qu&rsquo;il d\u00e9chire l&rsquo;\u00e2me de notre civilisation, qui se d\u00e9finit \u00e0 notre sens par l&rsquo;id\u00e9e d&rsquo;un affrontement entre les principes et les valeurs <a href=\"http:\/\/www.dedefensa.org\/article\/la-question-principes-contre-valeurs\">que nous avons d\u00e9j\u00e0 d\u00e9fini<\/a>, qui porte sur l&rsquo;\u00e9tat des psychologies et sur l&rsquo;orientation des \u00e2mes ; \u00e0 partir du constat de ce conflit donc, Tavares \u00e9crit sans aucune \u00e9quivoque, d&rsquo;une fa\u00e7on qui nous satisfait tout \u00e0 fait, avec notamment ce paragraphe de sa conclusion : &laquo; <em>N&rsquo;ayons aucune illusion \u00e0 cet \u00e9gard : c&rsquo;est une division tr\u00e8s profonde et il extr\u00eamement improbable que nous puissions jamais retrouver un degr\u00e9 d&rsquo;unit\u00e9 politique et de conception dans les soci\u00e9t\u00e9s occidentales comme ce que nous avons connu dans le pass\u00e9. <strong>Nous sommes \u00e0 un tournant fondamental de l&rsquo;Histoire<\/strong><\/em>. <\/p>\n<\/p>\n<p><p>Tavares s&rsquo;attache principalement \u00e0 la situation actuelle aux USA, qui est r\u00e9sum\u00e9e rigoureusement par un m\u00e9dian de six sondages sur l&rsquo;appr\u00e9ciation du travail du pr\u00e9sident Trump apr\u00e8s autour d&rsquo;un mois d&rsquo;exercice (cette fois, les chiffres sont si tranchants, si accord\u00e9s \u00e0 ce qu&rsquo;on ressent d&rsquo;intuition autant que de conviction de cette situation qu&rsquo;on peut les prendre <strong>comme une image rigoureuse autant que comme un symbole<\/strong>) : 41,5% de toutes les personnes interrog\u00e9es sont satisfaites de Trump, dont 39,5% parmi les ind\u00e9pendants (sans parti) ; pour les deux grands partis, <strong>85,2% des r\u00e9publicains et 7,8% des d\u00e9mocrates <\/strong>sont satisfaits de Trump et le soutiennent. (C&rsquo;est une rupture compl\u00e8te avec la tradition de rassemblement de tous derri\u00e8re un pr\u00e9sident \u00e9lu apr\u00e8s l&rsquo;affrontement de la campagne : au d\u00e9but, disons dans les 100 premiers jours de \u00ab\u00a0l&rsquo;\u00e9tat de gr\u00e2ce\u00a0\u00bb, une majorit\u00e9 dans chaque parti se rassemble derri\u00e8re le pr\u00e9sident pour signifier l&rsquo;unit\u00e9 du pays.) La rigueur des chiffres concerne la position de Trump ; <strong>le symbole concerne l&rsquo;extraordinaire division, compl\u00e8tement sans pr\u00e9c\u00e9dent\/sans \u00e9quivalent (SPSE), des &Eacute;tats-Unis d&rsquo;Am\u00e9rique<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>Notice the huge disparity between Republicans and Democrats. It could not be any more striking than this &ndash; and just a few weeks after Trump&rsquo;s inauguration. This reflects of what is going on across much of the US, down to family and friends. It is clearly not confined to just \u00ab\u00a0millennial snowflakes\u00a0\u00bb, although these tend to be the loudest. Try walking in that very progressive US neighborhood wearing a &lsquo;Make America Great Again&rsquo; cap and see how that cold war can turn <\/em><em>&lrm;<\/em><em>hot very quickly.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The two sides no longer seem to agree on what a country is: if it should have borders, who has the rights and obligations in their societies and what it should stand for. Those are pretty basic &ndash; and fundamental &ndash; differences that look more and more irreconcilable by the day. Heck, there isn&rsquo;t even an agreement on who is a woman and who is a man<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>A partir de ce constat qui implique une crise profonde (&laquo; &#8230;<em>une division tr\u00e8s profonde et il extr\u00eamement improbable que nous puissions jamais retrouver un degr\u00e9 d&rsquo;unit\u00e9 politique et de conception dans les soci\u00e9t\u00e9s occidentales comme ce que nous avons connu dans le pass\u00e9<\/em> &raquo;), Tavares d\u00e9veloppe certaines options th\u00e9oriques pour envisager les modifications structurelles permettant d&rsquo;esp\u00e9rer sortir de cette crise, dans le sens d\u00e9j\u00e0 vu r\u00e9cemment (voir <a href=\"http:\/\/www.dedefensa.org\/article\/reflexion-sur-leclatement-des-usa\">Lind<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article\/marine-et-la-californie-meme-combat\">Buchanan<\/a>) d&rsquo;un red\u00e9coupage par le moyen d&rsquo;une sorte de s\u00e9cessionnisme ou de s\u00e9paratisme, qui pourrait se faire selon la formule de \u00ab\u00a0deux &Eacute;tats\u00a0\u00bb cohabitant sous un m\u00eame chapeau f\u00e9d\u00e9raliste (ou conf\u00e9d\u00e9ral plut\u00f4t). L&rsquo;auteur ne va pas sans aussit\u00f4t remarquer que le m\u00eame probl\u00e8me se pose en Europe, quoiqu&rsquo;\u00e0 partir de donn\u00e9es consid\u00e9rablement diff\u00e9rentes, le centre-Bruxelles UE diff\u00e9rant consid\u00e9rablement, dans tous les domaines concevables, du centre-Washington D.C.  Quoi qu&rsquo;il soit, laissons se poursuivre la logique qui aboutit \u00e0 une sorte de formule \u00ab\u00a0\u00e0-la-belge\u00a0\u00bb que nous connaissons bien, au moins par proximit\u00e9 et observation \u00ab\u00a0de l&rsquo;ext\u00e9rieur\u00a0\u00bb (dans l&rsquo;esprit de la chose) selon notre fa\u00e7on de voir :<\/p>\n<\/p>\n<p><p>&laquo; <em>So what can be done about this?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Well, since everyone seems so keen in implementing a two-state <\/em><em>&lrm;<\/em><em>solution in the Israel-Palestine conflict, why not do the same across the West? With one key difference: these two \u00ab\u00a0states\u00a0\u00bb would remain formally linked through a very limited federal\/national government. Mainland Chinese public officials even have a name for it: one country, two systems<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Similarly, the same concept could be implemented across the European Union. If Germans, Swedes, French and the Dutch want their countries or municipalities to go full multicultural, good for them. What they shouldn&rsquo;t do is impose their vision of the world through the supranational mechanisms of the European Union on the Poles, Hungarians, Finns and many others who do vigorously want to retain their culture and identities.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>And that&rsquo;s what we have in every election cycle, with one party seeking to push its values onto the rest of society, which is increasingly divided and at odds with each other. So the pushback from either side is predictable. New \u00ab\u00a0populist\u00a0\u00bb movements across Europe already threaten the very existence of that federal government (except that in Europe&rsquo;s case it is anything but limited), and they will not go away any time soon.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>This two-state system might be a seemingly fair way to achieve the best of both worlds, allowing both ideologies to coexist within a common governmental framework. <strong>A large scale version of Belgium if you like. But the reality is not so simple (just look at Belgium!)<\/strong><\/em> &raquo;<\/p>\n<\/p>\n<p><p>Apr\u00e8s cette mise en garde, &ndash; &laquo; <em>Une version \u00e9largie de la Belgique, si vous voulez. Mais la r\u00e9alit\u00e9 n&rsquo;est si simple (voyez la Belgique, justement !)<\/em> &raquo;, &ndash; suivent diff\u00e9rents arguments <strong>contre cette formule, ou rendant tr\u00e8s difficile l&rsquo;application de la dite-formule<\/strong>. Il s&rsquo;agit d&rsquo;arguments r\u00e9alistes mais rendus absolument th\u00e9oriques par la seule dimension chronologique : ils sont envisag\u00e9s \u00e0 partir du moment pr\u00e9sent alors que chaque prolongement envisag\u00e9, qui se place dans une logique de succession plut\u00f4t que dans dynamique de simultan\u00e9it\u00e9, engendrerait une multitude d&rsquo;effets et de nouveaux probl\u00e8mes qui transformeraient compl\u00e8tement les \u00e9v\u00e9nements \u00e0 venir tels qu&rsquo;on les pr\u00e9voyait&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>First, Western nations for the most have accumulated debts at the supra-regional level so large that apportioning them <\/em><em>&lrm;<\/em><em>between the two \u00ab\u00a0states\u00a0\u00bb is likely to be extremely contentious<\/em>. [&#8230;] <em>Second, transitioning into a multicultural society can be very problematic, as evidenced by the debate on Sweden&rsquo;s immigration policies that has now gone viral, at least until a consensual set of rules and behaviors can be forged<\/em>. [&#8230;] <em>Third, Western alliances would likely have to be redrawn along this split in Western aspirations. Donald Trump has more in common with Hungary&rsquo;s Prime Minister Viktor Orb&aacute;n than Sadiq Khan, the Mayor of London<\/em>&#8230; [&#8230;] <em>Indeed, Trump proposes core nationalistic values not too dissimilar from his Russian counterpart Vladimir Putin (a key reason why the globalist media and intelligence are so keen to demonstrate a formal connection between the two). On the other hand, German Chancellor Angela Merkel &ndash; a hardcore globalist &ndash; could not be farther apart from either one<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Fourth, how can each \u00ab\u00a0state\u00a0\u00bb coordinate on international commercial policies with the other one, as many companies have extensive operations across the two? This cold war is now spreading to the corporate sector, with some employees feeling alienated and consumers on each side threatening boycotts and sanctions. It has come to that. And finally, a divided West is a weak West<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Sans aller \u00e0 une analyse critique plus profonde des cas \u00e9voqu\u00e9s qui n&rsquo;est pas ici notre propos, on s&rsquo;arr\u00eatera \u00e0 la mention de la Belgique, ou d&rsquo;un hypoth\u00e9tique \u00ab\u00a0mod\u00e8le belge\u00a0\u00bb dans le raisonnement de Tavares, avec tout de m\u00eame l&rsquo;avertissement, &ndash; &laquo; <em>A large scale version of Belgium if you like.<strong> But the reality is not so simple (just look at Belgium!)<\/strong><\/em> &raquo; &ndash; pour observer combien cette hypoth\u00e8se ou cette suggestion est extr\u00eamement fragile (et, nous semble-t-il, plut\u00f4t offerte en d\u00e9sespoir de cause). Nous ne parlons pas seulement des difficult\u00e9s int\u00e9rieures, innombrables et souvent picrocholines cela va de soi, de la survie permanente du \u00ab\u00a0mod\u00e8le belge\u00a0\u00bb, <strong>mais plut\u00f4t des contraintes ext\u00e9rieures qui ont emp\u00each\u00e9, sinon interdit son \u00e9clatement<\/strong>. La Belgique est enserr\u00e9e dans un carcan de pressions centrip\u00e8tes, for\u00e7ant au maintien de son unit\u00e9, et renfor\u00e7ant de ce fait le symbole unitariste de la royaut\u00e9 constitutionnelle : le cadre europ\u00e9en, install\u00e9 \u00e0 Bruxelles, et le cadre euroatlantique de l&rsquo;OTAN, \u00e9galement install\u00e9 en Belgique ; l&rsquo;hostilit\u00e9 des grandes puissances europ\u00e9ennes entourant la Belgique, en g\u00e9n\u00e9ral oppos\u00e9es \u00e0 toute id\u00e9e de rattachement des parties belges qui leur sont proches, ou proches des autres (par exemple, l&rsquo;hostilit\u00e9 de la diplomatie fran\u00e7aise au rattachement de la Wallonie \u00e0 la France), par cons\u00e9quent hostiles \u00e0 l&rsquo;\u00e9clatement de la Belgique. La Belgique pr\u00e9sente un cas de n\u00e9o-f\u00e9d\u00e9ralisme proche du conf\u00e9d\u00e9ralisme qui ne peut \u00eatre appr\u00e9ci\u00e9 sur ses vertus propres et peut par cons\u00e9quent difficilement \u00eatre appr\u00e9ci\u00e9 comme un \u00ab\u00a0mod\u00e8le\u00a0\u00bb transposable.<\/p>\n<\/p>\n<blockquote>\n<p><p>Cela n&rsquo;est dit que pour montrer <em>a contrario<\/em> les difficult\u00e9s que pr\u00e9sente les solutions de pseudo-s\u00e9paratisme ou de s\u00e9cessionnisme qui sont actuellement d\u00e9battues aux USA comme solution du \u00ab\u00a0moindre mal\u00a0\u00bb, \u00e9vitant les affrontements, \u00e0 partir du moment o&ugrave; n&rsquo;existent pas les contraintes ext\u00e9rieures qui forcent la Belgique \u00e0 \u00eatre un pseudo-\u00ab\u00a0mod\u00e8le\u00a0\u00bb. Au contraire, <strong>il nous semble que cette sorte de proposition demande trop de pr\u00e9-conditions raisonnables, essentiellement et paradoxalement une bonne entente pr\u00e9alable des parties recherchant un statut de s\u00e9paration qui constitue le contraire de l&rsquo;actuelle situation aux USA o&ugrave; l&rsquo;hostilit\u00e9 est \u00e0 son comble<\/strong>. La seule r\u00e9f\u00e9rence r\u00e9ussie de la p\u00e9riode est celle de la s\u00e9paration de la Tch\u00e9quie et de la Slovaquie, qui s&rsquo;est r\u00e9alis\u00e9e dans un ordre parfait au d\u00e9but des ann\u00e9es1990 parce que toutes les conditions raisonnables \u00e9taient r\u00e9unies, &ndash; et encore, pour aboutir \u00e0 une s\u00e9paration totale tant le lien du f\u00e9d\u00e9ralisme semblait \u00eatre devenu inutile. Le cas de la Tch\u00e9co-Slovaquie est plut\u00f4t l'\u00a0\u00bbexception qui confirme la r\u00e8gle\u00a0\u00bb, c&rsquo;est-\u00e0-dire une \u00ab\u00a0exception\u00a0\u00bb qui met victorieusement \u00e0 l&rsquo;\u00e9preuve une r\u00e8gle th\u00e9orique qui existe certes, mais qui s&rsquo;av\u00e8re par ailleurs, notamment dans les cas envisag\u00e9s, parfaitement inapplicable.<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le Diable salue l&rsquo;Internationale de la D\u00e9structuration<\/h3>\n<\/p>\n<p><p>&#8230; D&rsquo;une certaine fa\u00e7on, on pourrait penser que la r\u00e9flexion de fond de ce <em>F&#038;C<\/em> s&rsquo;encha&icirc;ne parfaitement et gracieusement sur les <em>Notes d&rsquo;analyse <\/em>d&rsquo;hier, <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-linaction-et-le-silence\">26 f\u00e9vrier 2017<\/a>. En effet, on voit <strong>l&rsquo;importance extraordinaire qu&rsquo;ont acquis des probl\u00e8mes int\u00e9rieurs<\/strong> qui semblaient au d\u00e9part maintenus dans le cadre des m&oelig;urs en (r)\u00e9volution et <strong>du bouleversement des us &#038; coutumes dont la fonction, li\u00e9e \u00e0 la tradition, est pourtant de n&rsquo;\u00eatre pas boulevers\u00e9e<\/strong>. La candidature et l&rsquo;\u00e9lection de Trump, qui se sont jou\u00e9es et d\u00e9velopp\u00e9es pour beaucoup sur ce terrain, en ont fait jaillir l&rsquo;exacerbation et la violence hors de leur latence furieuse, imposant les questions soci\u00e9tales d\u00e9j\u00e0 bouillonnantes <strong>au rang de premier domaine d&rsquo;affrontement civique et, par extension, premier domaine d&rsquo;affrontement de la politique<\/strong>. La chose a pris une telle extension qu&rsquo;effectivement, comme on l&rsquo;a vu hier, les probl\u00e8mes qui ont toujours sembl\u00e9 dominants sinon \u00e9crasants de politique ext\u00e9rieure et de s\u00e9curit\u00e9 nationale li\u00e9s \u00e0 l&rsquo;id\u00e9ologie et \u00e0 la g\u00e9opolitique semblent insensiblement mais absolument passer au second plan ; un peu comme si la politique ext\u00e9rieure et de s\u00e9curit\u00e9 nationale semblait \u00e9voluer vers une sorte de \u00ab\u00a0trou noir\u00a0\u00bb d&rsquo;un d\u00e9sordre absolu o&ugrave; ceux qui tirent leur \u00e9pingle du jeu sont ceux qui conservent le plus leur sang-froid et qui \u00e9chappent, sur le plan int\u00e9rieur, \u00e0 cette \u00ab\u00a0guerre civile soci\u00e9tale\u00a0\u00bb, &ndash; essentiellement la Russie, certes.<\/p>\n<\/p>\n<p><p>Ce que nous vivons \u00e0 cet \u00e9gard est une sorte de \u00ab\u00a0r\u00e9volution invertie\u00a0\u00bb. D&rsquo;habitude, la r\u00e9volution est d&rsquo;abord un \u00e9clatement sauvage de la violence, jusqu&rsquo;\u00e0 l&rsquo;anarchie, \u00e0 la terreur, \u00e0 la tyrannie, avec ensuite, une fois cette violence apais\u00e9e, une (r)\u00e9volution sensibles des meurs, et la disparition des us &#038; coutumes pour leur remplacement par de nouvelles formes pr\u00e9tendant d&rsquo;une fa\u00e7on absurde \u00e0 une posture traditionnelles&#8230; Il s&rsquo;agit des effets soci\u00e9taux qui naissent et se d\u00e9veloppent \u00e0 partir des premiers imp\u00e9ratifs sociaux impos\u00e9s par la violence de la r\u00e9volution. L&rsquo;inversion est aujourd&rsquo;hui compl\u00e8te : on d\u00e9couvre le surgissement de nouveaux comportements soci\u00e9taux, et la tentative de suppression des us &#038; coutumes par quelque chose d&rsquo;enti\u00e8rement nouveau, sans qu&rsquo;il y ait eu la r\u00e9volution n\u00e9cessaire pour les engendrer et les imposer. <strong>Tout se passe comme si nous avions les effets de la r\u00e9volution sans la r\u00e9volution, ou bien encore les effets de la r\u00e9volution avant la r\u00e9volution<\/strong>&#8230; Dans ce dernier cas, chacun ayant pu mesurer les effets de cette r\u00e9volution non encore faite, il est tr\u00e8s possible, il est <strong>infiniment possible que la r\u00e9volution dont on attend qu&rsquo;elle confirme ses effets qui l&rsquo;ont pr\u00e9c\u00e9d\u00e9e, se transforme en une contre-r\u00e9volution violente, contre les effets de la r\u00e9volution-qui-n&rsquo;a-pas-encore-eu-lieu.<\/strong>..<\/p>\n<\/p>\n<p><p>Le caract\u00e8re compl\u00e8tement inhabituel et inverti de cette situation est largement confirm\u00e9 par les r\u00e9actions de plus en plus violentes aux cons\u00e9quences soci\u00e9tales qu&rsquo;une partie veut imposer au nom de cette r\u00e9volution-qui-n&rsquo;a-pas-encore-eu-lieu. Cela \u00e9tant constat\u00e9 et pour faire franchir un palier \u00e0 la r\u00e9flexion et retrouver notre champ habituel, l&rsquo;on sait bien \u00e0 quoi est due cette situation si particuli\u00e8re ; elle s&rsquo;est r\u00e9alis\u00e9e sous l&#8217;empire de la domination d&rsquo;un Syst\u00e8me d\u00e9structurant, qui est en lui-m\u00eame une r\u00e9volution totalement nihiliste puisqu&rsquo;absolument et aveugl\u00e9ment d\u00e9structurant, et qui a impos\u00e9, <strong>notamment gr\u00e2ce \u00e0 une manipulation diabolique du syst\u00e8me de la communication<\/strong>, ses effets notamment soci\u00e9taux.<\/p>\n<\/p>\n<p><p>La violence de cette pouss\u00e9e est telle que les pseudo-\u00ab\u00a0effets de la r\u00e9volution\u00a0\u00bb pr\u00e9tendent \u00e9galer en fait d&rsquo;anarchie, de terreur et de tyrannie, ce que serait une r\u00e9volution elle-m\u00eame. Par cons\u00e9quent, ces questions soci\u00e9tales qui semblaient devoir \u00eatre cantonn\u00e9es dans le d\u00e9bat social et civique normal sont devenues des formes oppressives d&rsquo;une id\u00e9ologie nihiliste qui repr\u00e9sente parfaitement la tyrannie du Syst\u00e8me, &ndash; leur masque est tomb\u00e9, \u00e0 cet \u00e9gard. Il est donc impossible de consid\u00e9rer les deux parties, &ndash;partisans et adversaires des effets soci\u00e9taux de la pseudo-\u00ab\u00a0r\u00e9volution-qui-n&rsquo;a-pas-encore eu-lieu\u00a0\u00bb, c&rsquo;est-\u00e0-dire des pressions du Syst\u00e8me en v\u00e9rit\u00e9, &ndash; comme \u00e9tant une alternative politique et humaine courante de la sempiternelle \u00ab\u00a0querelles des anciens et des modernes\u00a0\u00bb ; cela est impossible, essentiellement gr\u00e2ce \u00e0 la repr\u00e9sentation qui est faite \u00e0 une vitesse extraordinaire de la modernit\u00e9 <strong>d&rsquo;\u00eatre une caricature et un simulacre, conduit par une hypertrophie du paroxysme de la psychologie et de la banalisation de l&rsquo;hyst\u00e9rie<\/strong>&#8230; Puisqu&rsquo;enfin, il est devenu \u00e9vident que la modernit\u00e9, parall\u00e8lement \u00e0 la fuite en avant de la r\u00e9volution soci\u00e9tale, <strong>a elle aussi laiss\u00e9 tomber son faux-nez pour appara&icirc;tre selon ce qu&rsquo;on soup\u00e7onnait depuis longtemps qu&rsquo;elle est : un vrai masque pour dissimuler le Syst\u00e8me<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>On comprend alors l&rsquo;importance que prennent les questions soci\u00e9tales jusqu&rsquo;\u00e0 usurper la place des questions de politique ext\u00e9rieures. Au reste, il y a de la logique dans cette pirouette, qui nous fait ne pas abandonner compl\u00e8tement le domaine. Les questions soci\u00e9tales se d\u00e9veloppent <strong>selon des normes qui en font apr\u00e8s tout une ligne centrale de politique ext\u00e9rieure <\/strong>; elles constituent un lien fondamental et tr\u00e8s puissant d&rsquo;une politique id\u00e9ologique et d&rsquo;une agitation r\u00e9volutionnaire activement aliment\u00e9es par les principaux pays du bloc-BAO, <strong>comme le ferait une Internationale de la D\u00e9structuration<\/strong> ; mieux encore, cela est r\u00e9alis\u00e9 avec la complicit\u00e9 active des directions et des \u00e9lites de ces pays, &ndash; directions-Syst\u00e8mes et \u00e9lites-Syst\u00e8me bien entendu&#8230; Ces derniers temps, cette belle m\u00e9canique a rencontr\u00e9 <strong>son fameux grain de sable<\/strong>, avec l&rsquo;introduction d&rsquo;un \u00e9l\u00e9ment impr\u00e9vu dans le moteur central de l&rsquo;ensemble ; le grain de sable, l&rsquo;\u00e9l\u00e9ment impr\u00e9vu pourtant venu du Syst\u00e8me, c&rsquo;est-\u00e0-dire Trump, <strong>transformant effectivement la douce et irr\u00e9sistible mar\u00e9e galopantes des questions soci\u00e9tales en un f\u00e9roce ouragan d&rsquo;affrontement entre des forces oppos\u00e9es<\/strong>, chacun \u00e9tant soudain et enfin \u00e0 d\u00e9couvert et les questions soci\u00e9tales faisant surgir partout leurs oppositions antiSyst\u00e8me.<\/p>\n<\/p>\n<blockquote>\n<p><p>Par cons\u00e9quent, outre d&rsquo;observer les effets de violents soubresauts caus\u00e9s par ces questions soci\u00e9tales parvenues \u00e0 la provocation d&rsquo;un antagonisme d&rsquo;une sorte de violence r\u00e9volutionnaire<strong>, il est aussi question de choisir son camp de toute urgence<\/strong>, puisqu&rsquo;il s&rsquo;av\u00e8re \u00e9vident que le Syst\u00e8me est de la partie ; <strong>et ce camp ne peut \u00eatre que du c\u00f4t\u00e9 de tout ce qui s&rsquo;oppose au Syst\u00e8me<\/strong>&#8230; Dans ce cas, les questions soci\u00e9tales ne peuvent plus \u00eatre appr\u00e9ci\u00e9es pour elles-m\u00eames, mais d&rsquo;abord pour des instruments au service du Syst\u00e8me, et leur dialectique de modernisation et de lib\u00e9ration n&rsquo;ont plus que la valeur d&rsquo;un pi\u00e8tre simulacre : <strong>elles ne sont que des outils de la d\u00e9structuration aveugle, de la course \u00e0 la n\u00e9antisation, du nihilisme m\u00e9canique du Syst\u00e8me<\/strong>. C&rsquo;est dire enfin, et en un mot, combien l&rsquo;on doit peu esp\u00e9rer de ces formules raisonnables de s\u00e9paratisme, de s\u00e9cessionnisme, etc., dans une sorte de concorde \u00ab\u00a0\u00e0 l&rsquo;amiable\u00a0\u00bb car la partie soci\u00e9tales, en gros les globalistes et les progressiste-soci\u00e9taux, dont nombre tiennent la fonction toujours pris\u00e9e d'\u00a0\u00bbidiots utiles\u00a0\u00bb, n&rsquo;est pas du genre qui accepte des compromis de s\u00e9paration \u00ab\u00a0\u00e0 l&rsquo;amiable\u00a0\u00bb, de cohabitation s\u00e9par\u00e9e dans le respect r\u00e9ciproque. <strong>Ce qu&rsquo;ils veulent, c&rsquo;est l&rsquo;an\u00e9antissement de leurs adversaires, selon les consignes du Syst\u00e8me<\/strong>, &ndash; si l&rsquo;on veut, dans ce cas, les \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/french-touch-nous-sommes-tous-les-deplorables\">Deplorable<\/a><\/em>\u00a0\u00bb dans le rangement dialectique hautement intellectuel d&rsquo;Hillary Clinton. <strong>Il importe de le comprendre et de le savoir<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Reste la sempiternelle interrogation du \u00ab\u00a0pourquoi ?\u00a0\u00bb ultime, de la Cause Premi\u00e8re et de la Fin Derni\u00e8re de ce courant d\u00e9structuration-dissolution-entropisation par\u00e9 des riches atours de l&rsquo;humanisme, sinon du posthumanisme. Le cas int\u00e9ressant que nous montre la situation actuelle est que ce mouvement, victime de lui-m\u00eame selon le principe d&rsquo;autodestruction, montre d\u00e9sormais \u00e0 ciel ouvert son extr\u00eame avidit\u00e9 de passer \u00e0 la phase de la dissolution et du nivellement globalis\u00e9, avec l&rsquo;\u00eatre r\u00e9duit \u00e0 un d\u00e9bris de l&rsquo;entropisation, <strong>pour rien d&rsquo;autre que l&rsquo;accomplissement de cette entropisation, Cause Premi\u00e8re et Fin Derni\u00e8re enfin r\u00e9unies<\/strong>&#8230; Pour cette explication finale, nous ne pouvons faire que convoquer une fois de plus, et avec un entrain renouvel\u00e9 comme lorsque vous vous jugez en droit de crier \u00ab\u00a0<em>Eureka !<\/em>\u00a0\u00bb dans votre bain, la figure centrale du Diable, comme nous l&rsquo;avons d\u00e9j\u00e0 fait le <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-la-probabilite-evidente-du-diable\">7 janvier 2017<\/a> ; parce que, en toute simplicit\u00e9, <strong>lui seul, le Diable, peut inspirer une telle furie destructrice (d\u00e9structurante) sans \u00eatre but que de faire ce qu&rsquo;elle fait<\/strong>. Cela s&rsquo;explique notamment avec cet extrait du texte r\u00e9f\u00e9renc\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo; <em>Tout cela, certes et on l&rsquo;a compris \u00e9videmment, pour nous mener \u00e0 la conclusion que nous nous trouvons devant <\/em><strong><em>la terrible simplicit\u00e9 du Mal qui implique n\u00e9cessairement l&rsquo;existence du Diable<\/em><\/strong><em>. (Cette simplicit\u00e9 affreuse du Mal qui rend si complexe la recherche de son antidote et explique qu&rsquo;on puisse rencontrer, en plein d\u00e9sarroi, ce que tel auteur nommait &lsquo;l&rsquo;ambigu\u00eft\u00e9 du Bien&rsquo;.) Nous nous trouvons devant \u00ab\u00a0la terrible simplicit\u00e9 du Mal\u00a0\u00bb, c&rsquo;est-\u00e0-dire de son \u00e9vidente brutalit\u00e9, tout cela si puissant jusqu&rsquo;\u00e0 cette surpuissance que nous \u00e9voquons constamment \u00e0 propos du Syst\u00e8me,  q<strong>u&rsquo;il nous faut convoquer le Diable et tout ce que cela suppose de fa\u00e7on de voir, de percevoir et de penser, pour continuer \u00e0 supporter la terrible charge de tenter de comprendre ce qui est en train de se passer, pour d\u00e9terminer la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a><\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>On verra alors que l&rsquo;acte de faire intervenir dans le contexte m\u00e9tahistorique qui importe de tels acteurs \u00e0 part \u00f4 combien enti\u00e8re et tels qu&rsquo;ils sont, &ndash; le Mal, le Diable, etc., &ndash; les faire intervenir dans le m\u00e9canisme de la pens\u00e9e et du jugement <strong>suscite un formidable rajeunissement de l&rsquo;esprit, un raffermissement extraordinaire du caract\u00e8re et une mesure puissante et tonitruante de la valeur de ce qu&rsquo;est la libert\u00e9 de l&rsquo;esprit<\/strong> ; c&rsquo;est-\u00e0-dire la transformation de la libert\u00e9, de la situation contrainte et abaiss\u00e9e de \u00ab\u00a0valeur\u00a0\u00bb li\u00e9e \u00e0 une id\u00e9ologie dont l&rsquo;accomplissement est la liquidation de la libert\u00e9 de l&rsquo;esprit, <strong>en un principe intangible qui est \u00e0 la base de la puissance ontologique de l&rsquo;esprit<\/strong>. En pensant de la sorte, nous mettons le Diable en \u00e9chec, &ndash; un peu comme dans une partie d&rsquo;\u00e9checs, &ndash; un peu comme le cur\u00e9 qui montre la croix au vampire, mais \u00e0 notre fa\u00e7on, <strong>sans n\u00e9cessit\u00e9 d&rsquo;une baignade dans le b\u00e9nitier<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;insoutenable d\u00e9composition de l&rsquo;\u00e2me du monde 27 f\u00e9vrier 2017 &ndash; Nous d\u00e9veloppons notre r\u00e9flexion \u00e0 partir d&rsquo;un article du 25 f\u00e9vrier de Erico Mathias Tavares de l&rsquo;agence de marketing Sinclair &#038; Co (article disponible sur LikedIn et sur ZeroHedge.com), avec le titre &laquo; A Two-State Solution&#8230; For the West? &raquo;. Il s&rsquo;agit d&rsquo;une appr\u00e9ciation argument\u00e9e&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3303,5932,10119,12823,2879,12816,6222,12824,12825,2639],"class_list":["post-77116","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-belgique","tag-diable","tag-dissolution","tag-questions","tag-revolution","tag-secessionniste","tag-separatisme","tag-societales","tag-tavares","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77116"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77116\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}