{"id":77126,"date":"2017-03-04T12:38:36","date_gmt":"2017-03-04T12:38:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/03\/04\/chambre-dechos-du-tourbillon-invertie\/"},"modified":"2017-03-04T12:38:36","modified_gmt":"2017-03-04T12:38:36","slug":"chambre-dechos-du-tourbillon-invertie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/03\/04\/chambre-dechos-du-tourbillon-invertie\/","title":{"rendered":"Chambre d&rsquo;\u00e9chos du tourbillon invertie"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Chambre d&rsquo;\u00e9chos du tourbillon invertie<\/h2>\n<\/p>\n<p><p>04 mars 2017 &ndash; A Washington D.C., au cas o&ugrave; on ne l&rsquo;aurait pas not\u00e9, tout se passe comme si BHO <strong>passait en <a href=\"http:\/\/www.dailymail.co.uk\/news\/article-4271412\/Obama-confidante-Valerie-Jarrett-moves-Kaloroma-home.html\">mode<\/a> \u00ab\u00a0<a href=\"http:\/\/www.zerohedge.com\/news\/2017-03-02\/valerie-jarrett-moves-obamas-dc-lead-fight-strategy-topple-trump\">ciel ouvert<\/a>\u00a0\u00bb pour activer <a href=\"http:\/\/www.breitbart.com\/big-government\/2017\/03\/03\/mark-levin-obama-used-police-state-tactics-undermine-trump\/\">son \u00ab\u00a0coup\u00a0\u00bb<\/a> <a href=\"http:\/\/www.breitbart.com\/radio\/2017\/03\/03\/robert-barnes-obama-chose-dangerous-precarious-path-encouraging-de-facto-coup-attempt-elements-deep-state\/\">contre Trump<\/a> <\/strong>; et le sort stup\u00e9fiant fait au secr\u00e9taire\u00e0 la Justice Sessions nous conduit tout droit \u00e0 une <a href=\"https:\/\/www.rt.com\/op-edge\/379355-sessions-russia-ambassador-us-msm\/\">\u00ab\u00a0crise institutionnelle\u00a0\u00bb<\/a>. A Paris, France, tout se passe comme si Fillon semblait pouvoir \u00eatre accus\u00e9 de pr\u00e9parer une sorte de \u00ab\u00a0coup\u00a0\u00bb contre l'\u00a0\u00bb&Eacute;tat-de-Droit\u00a0\u00bb&#8230; (Ils r\u00e9citent cette expression sans reprendre leur souffle, comme \u00e0 genoux devant monsieur le cur\u00e9, comme s&rsquo;ils \u00e9taient humbles-lyriques, comme s&rsquo;ils avaient le regard profond d&rsquo;une ardeur tournant \u00e0 vide, le vide endimanch\u00e9 et le parler majuscul\u00e9.) Bien, \u00e0 ce point de ce que je nommerais aussi bien \u00ab\u00a0Les convergences invertie\u00a0\u00bb (j&rsquo;ai h\u00e9sit\u00e9 \u00e0 mettre l&rsquo;expression en titre), je pr\u00e9cise fugacement le cas fran\u00e7ais avant de revenir \u00e0 la chose, &ndash; \u00ab\u00a0\u00e9chos\u00a0\u00bb, \u00ab\u00a0convergences\u00a0\u00bb&#8230; Il s&rsquo;agirait donc, dans le chef de Fillon de nous refaire, demain avec ce qui lui viendra au Trocad\u00e9ro du peuple-de-droite, un 6-f\u00e9vrier-34 mais dans le style <em>relook\u00e9<\/em> de la postmodernit\u00e9, avec la populace suppos\u00e9e avide de produire son acte de forfaiture contre la \u00ab\u00a0r\u00e9publique-dictature des juges\u00a0\u00bb. Observons \u00e0 ce point que la magistrature fran\u00e7ais si probe sur elle a, cela ne fait aucun doute, bien particip\u00e9, avec brio et sous le regard \u00e9tonnamment fourbe du pr\u00e9sident-poire, <strong>\u00e0 la manufacture de la forfaiture qu&rsquo;elle serait prompte \u00e0 d\u00e9noncer au gr\u00e9 de ses multiples silences<\/strong>.<\/p>\n<\/p>\n<p><p>Savent-ils ce qu&rsquo;ils disent et ce qu&rsquo;ils font, \u00e0 Washington D.C. et \u00e0 Paris, France ?<\/p>\n<\/p>\n<p><p>Voyez-vous, il est difficile de trouver des points de comparaison entre les deux hommes (BHO et Fillon), leurs postures, leurs buts, leurs ambitions, sinon qu&rsquo;ils s&rsquo;opposent sur nombre de points, au point qu&rsquo;on peut conjecturer sans surprise que ce tourbillon d&rsquo;\u00e9chos et de convergences se fait au seul rythme des inversions crois\u00e9es en qu\u00eate d&rsquo;une n\u00e9antisation qui s\u00e9duise le populo. Mais peu m&rsquo;importe. Ce qui importe, <strong>c&rsquo;est la dynamique de la chose \u00e9v\u00e9nementielle, et le \u00ab\u00a0bruit de fond\u00a0\u00bb de cette dynamique <\/strong>; et dans ce cas, l&rsquo;interpr\u00e9tation qu&rsquo;on doit en donner <strong>selon une approche habill\u00e9e de l&rsquo;objectivit\u00e9 m\u00e9tahistorique est celle de la similitude<\/strong> (\u00ab\u00a0\u00e9chos\u00a0\u00bb, \u00ab\u00a0convergences\u00a0\u00bb). Tout cela nous dit la m\u00eame chose de la couleur de ces temps d\u00e9cha&icirc;n\u00e9s.<\/p>\n<\/p>\n<p><p><strong>&Eacute;cho, es-tu l\u00e0 ?<\/strong> (Je parle de l&rsquo;\u00e9cho d&rsquo;un temps pass\u00e9.) &laquo; <em>L&rsquo;atmosph\u00e8re politique en France est devenue telle que des lignes anodines peuvent \u00eatre consid\u00e9r\u00e9es comme explosives<\/em> &raquo; \u00e9crit Jacques Laurent dans <em>Combat<\/em>, le 31 mars 1961. Vingt-cinq jours plus t\u00f4t, le sigle alors myst\u00e9rieux d'\u00a0\u00bbOAS\u00a0\u00bb est apparu sur les murs des immeubles d&rsquo;Alger ; 22 jours plus tard, c&rsquo;est le \u00ab\u00a0putsch des g\u00e9n\u00e9raux\u00a0\u00bb, \u00e0 Alger encore. Je sais tout \u00e7a, j&rsquo;y \u00e9tais, m\u00eame si je ne pr\u00eatais aux choses qu&rsquo;une attention mineure en allant chaque jour au lyc\u00e9e Bugeaud, perdu dans les r\u00eaveries de cette chambre d&rsquo;\u00e9chos que s&rsquo;\u00e9tait constitu\u00e9e mon \u00e2me si jeune et les angoisses adolescentes face aux jeunes filles de mon c&oelig;ur incertain.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il y a de la similitude dans tout cela o&ugrave; les cas choisis ne sont qu&rsquo;exemples de convergences et d&rsquo;\u00e9chos d\u00e9velopp\u00e9s en fatras, et d\u00e9veloppant entre eux des rapports compl\u00e8tement invertis. La vie, la vie disait Shakespeare, &laquo; <em>La vie n&rsquo;est qu&rsquo;une ombre errante <\/em>[&#8230;] <em>une histoire pleine de bruits et de fureurs, racont\u00e9e par un idiot et qui ne signifie rien <\/em>&raquo;. (*) La d\u00e9sagr\u00e9gation fran\u00e7aise actuelle qui solliciterait parfois d&rsquo;en rappeler d&rsquo;autres <strong>mais qui finalement n&rsquo;est semblable \u00e0 aucune autre (finalement, rien \u00e0 voir avec 1961, et le souvenir n&rsquo;est l\u00e0 que pour marquer le changement d&rsquo;esprit de l&rsquo;\u00e9poque, dont je t\u00e9moigne absolument)<\/strong>, cette d\u00e9sagr\u00e9gation s&rsquo;est align\u00e9e sur la d\u00e9sagr\u00e9gation am\u00e9ricaniste (<a href=\"http:\/\/www.dedefensa.org\/article\/france-2017-comme-usa-2016\">oui d\u00e9cid\u00e9ment<\/a>, \u00ab\u00a0France-2017\u00a0\u00bb apr\u00e8s \u00ab\u00a0USA-2016\u00a0\u00bb), aussi bien dans <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-chaos-nouveau\">le chaos-nouveau<\/a> des choses que dans le d\u00e9sordre-entropique des acteurs-figurants.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Si l&rsquo;on revient \u00e0 la br&ucirc;lante actualit\u00e9 qui n&rsquo;est qu&rsquo;une forme d&rsquo;expression parmi d&rsquo;autres des \u00e9v\u00e9nements extraordinaires qui nous emportent, ce sera pour mon compte pour poser cette question qui me permet une rapide digression du jugement, et montrant ainsi que la possibilit\u00e9 de cette digression est le signe de notre impuissance bien comprise \u00e0 ne rien pouvoir comprendre de ces \u00e9v\u00e9nements qui se passent de nous, qui s&rsquo;amusent \u00e0 faire de nous leur jouet&#8230; Cette question : \u00ab\u00a0faut-il juger Fillon\u00a0\u00bb ? (Dans le sens de \u00ab\u00a0le comprendre\u00a0\u00bb, pas pour l&rsquo;envoyer devant les juges qui sont d&rsquo;une cohorte que je n&rsquo;aime pas.) Je r\u00e9p\u00e8te donc que je me fiche bien des aspects politiques de l&rsquo;aventure, encore plus des aspects \u00ab\u00a0moraux\u00a0\u00bb ; que ne d\u00e9goisent-ils, par tonnes enti\u00e8res, par tombereaux et charretiers, en fait de \u00ab\u00a0moralisation de la politique\u00a0\u00bb, comme dit <strong>le surr\u00e9aliste Mayrou<\/strong> (il me rappelle tant le sympathique et fort placide \u00ab\u00a0Jojo-le-M\u00e9rou\u00a0\u00bb, rencontr\u00e9 je crois dans le premier film sur Cousteau, tourn\u00e9 \u00e0 la fin des ann\u00e9es 1950, premier film de Louis Malle, prim\u00e9 \u00e0 Cannes [documentaire]).<\/p>\n<\/p>\n<p><p>Bref, j&rsquo;avoue avoir une sympathie d&rsquo;instinct pour ce type, Fillon ; cet incroyable maladroit, ce strat\u00e8ge politique nul et ce tacticien toujours en retard, que tout le monde laisse tomber d\u00e9sormais, les copains et les coquins qui vont \u00e0 la soupe-d\u00e9mocratique, mais lui qui d\u00e9cide de r\u00e9sister, qui ne c\u00e8de pas, qui s&rsquo;acharne type-\u00ab\u00a0La Garde meurt mais ne se rend pas\u00a0\u00bb&#8230; C&rsquo;est vrai que j&rsquo;ai un faible pour les perdants, surtout quand ils le sont \u00e0 cause de la trouille et de la trahison des bandes habituelles du Syst\u00e8me, surtout ses \u00ab\u00a0amis\u00a0\u00bb qui se trouvent coinc\u00e9s dans la m\u00eame barque que lui ; d&rsquo;ailleurs, dans cette \u00e9poque qui est cul-par-dessus-t\u00eate du fait du tourbillon crisique de l&rsquo;inversion, le perdant chronique peut gagner par inadvertance, qu&rsquo;importe. En un mot qui dit tout, je dis que s&rsquo;il insiste avec un peu de succ\u00e8s, <strong>Fillon, il va vraiment finir par devenir compl\u00e8tement antiSyst\u00e8me tant il a tout le monde contre lui<\/strong> ; et je lui reconnaitrais donc, puisque j&rsquo;en suis l\u00e0, qu&rsquo;il a d\u00e9j\u00e0 rempli \u00e0 son corps d\u00e9fendant, ce qui est la meilleure m\u00e9thode, <strong>une bonne partie de son contrat d&rsquo;antiSyst\u00e8me, qui est d&rsquo;accentuer vertigineusement le d\u00e9sordre<\/strong>&#8230; On verra dimanche, s&rsquo;il fait son \u00ab\u00a0coup d&rsquo;&Eacute;tat\u00a0\u00bb style-<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Georges_Boulanger\">Boulanger<\/a>, selon ce qu&rsquo;il aura r\u00e9ussi \u00e0 rassembler du fameux peuple-de-droite ; il est vrai, \u00e0 tout prendre, qu&rsquo;il est plus glorieux d&rsquo;attendre que vienne le peuple, &ndash; un pari comme un autre, &ndash; que de tenter de retenir les rats quittant la navire, avant de se faire rat soi-m\u00eame et de plonger avec les autres.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus et ces choses ayant \u00e9t\u00e9 dites, il faut me permettre d&rsquo;en revenir \u00e0 ma sagesse habituelle : si vous pensez que je puisse, que j&rsquo;ose m&rsquo;aventurer \u00e0 offrir une pr\u00e9cision, \u00e0 esquisser une pr\u00e9vision, \u00e0 ordonner par avance la prog\u00e9niture furieuse de cette furieuse absence de sens et de cette d\u00e9termination de nos directions-Syst\u00e8me \u00e0 n&rsquo;aspirer \u00e0 \u00eatre que le rien supr\u00eame, <strong>vous serez \u00e9videmment d\u00e9\u00e7u<\/strong>. Et cela est dit, certes et revenant \u00e0 mon vrai sujet, aussi bien \u00e0 propos du d\u00e9sordre am\u00e9ricaniste que du d\u00e9sordre fran\u00e7ais, <strong>puisque les deux semblent d\u00e9sormais faire la paire pour aller ensemble<\/strong> et que celui qui \u00e9tudie l&rsquo;un n&rsquo;en peut rien appr\u00e9cier \u00e0 sa juste mesure s&rsquo;il ne tient pas compte de l&rsquo;autre. Il n&rsquo;y a rien \u00e0 faire, justement, <strong>qu&rsquo;\u00e0 prendre et \u00e0 suivre la juste mesure en constante \u00e9volution de l&rsquo;intensit\u00e9 et de la puissance de l&rsquo;\u00e9v\u00e9nement dont le dessein nous reste imp\u00e9n\u00e9trable<\/strong>. Mais ce n&rsquo;est pas rien, cette attention du g\u00e9om\u00e8tre de la catastrophe, pour tenter de faire sonner et d&rsquo;expliciter au moment qui importe les alarmes collectives ; on conviendra ais\u00e9ment, parce que cela est pure et bonne justesse de l&rsquo;esprit que cela vaut bien plus que les comm\u00e9rages et les radotages qui accompagnent ces \u00e9v\u00e9nements, en pr\u00e9tendant en \u00eatre les commentateurs sinon les ordonnateurs.<\/p>\n<\/p>\n<blockquote>\n<p><p>Car on ne peut que s&rsquo;extasier et s&rsquo;exclamer devant cette extraordinaire similitude dans la dynamique d\u00e9structurante des situations fran\u00e7aise et am\u00e9ricaniste. Les Fran\u00e7ais devraient donc retrouver leur fiert\u00e9 intemporelle, et les salons parisiens leur arrogance postmoderniste, la France est d\u00e9sormais au centre des pr\u00e9occupations du monde et de notre contre-civilisation, <strong>cette fois presque \u00e0 parit\u00e9 avec \u00ab\u00a0nos amis am\u00e9ricains\u00a0\u00bb, dans une sorte d'\u00a0\u00bbOTAN-du-d\u00e9sordre\u00a0\u00bb<\/strong>. (Peut-\u00eatre les Hollandais vont-ils nous rejoindre le 15 mars, et les Allemands, toujours un peu lourds, un peu plus tard dans cette attachante ann\u00e9e 2017.) Il n&rsquo;y a aucun parti \u00e0 prendre, aucune victoire \u00e0 esp\u00e9rer, malgr\u00e9 les sentiments et les r\u00e9flexes des uns et des autres parmi les chroniqueurs du d\u00e9sordre. <strong>Ni le concept de \u00ab\u00a0parti\u00a0\u00bb, ni celui de \u00ab\u00a0victoire\u00a0\u00bb n&rsquo;ont plus le moindre sens dans une dynamique des \u00e9v\u00e9nements compl\u00e8tement sup\u00e9rieure \u00e0 notre raison<\/strong>, et s&#8217;employant avec malice \u00e0 rendre insens\u00e9s et <em>irrelevent<\/em> tous nos concepts et autres structures \u00e9difi\u00e9es par notre raison pour tenter d&rsquo;ordonner le d\u00e9sordre qu&rsquo;elle-m\u00eame (notre raison) entretient, comme l&rsquo;incendiaire qui veut jouer au pompier.<\/p>\n<\/p>\n<\/blockquote>\n<p><p><strong>Le mot de la fin sera de d\u00e9tente et d&rsquo;armistice des assauts antagonistes<\/strong>&#8230; Il revient \u00e0 celui qui nous dit qu&rsquo;apr\u00e8s tout, tous ces gens que je et nous vouons aux g\u00e9monies, ne sont pas si m\u00e9chants et encore moins machiav\u00e9liques. Je parle des petites mains du Syst\u00e8me dont sont compos\u00e9es nos direction-Syst\u00e8me&#8230; Le mot de la fin donc, \u00e0 Jean-Claude Juncker, pour une intervention, hier au Parlement Europ\u00e9en, o&ugrave; il est dit par <em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-03-03\/juncker-has-meltdown-while-debating-future-eu-shit-what-do-you-want-us-do\">ZeroHedge.com<\/a><\/em>, imprudemment selon moi si l&rsquo;on entend la douceur et le calme de la voix, que Juncker \u00ab\u00a0semble nous avoir fait une petite crise de nerfs\u00a0\u00bb&lsquo; &#8230; &laquo; <em>And during that debate Jean-Claude Juncker, the President of the European Commission, appeared to have <strong>a little breakdown<\/strong>. When Juncker was criticized for wanting to consult ordinary Europeans on what they should do, this is what happened.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Ce qui se traduit (je parle de Juncker sur la vid\u00e9o, parlant avec calme et vraiment presque avec douceur \u00e0 la meute des d\u00e9put\u00e9s europ\u00e9ens) : &laquo; <em>Mais merte ! Je dirais \u00ab\u00a0merte\u00a0\u00bb si nous n&rsquo;\u00e9tions pas au Parlement Europ\u00e9en ! Que voulez-vous que nous fassions de plus.<\/em>.. &raquo; Ce \u00ab\u00a0merte\u00a0\u00bb si compl\u00e8tement belgo-luxembourgeois sonne haut et clair son brave petit maire d&rsquo;une chouette \u00ab\u00a0petite ville moyenne du Luxembourg\u00a0\u00bb, &ndash; cela, <a href=\"http:\/\/www.dedefensa.org\/article\/trump-brexit-et-la-guerre-contrelue\">justement vu<\/a> par Ted Malloch, l&rsquo;ambassadeur de Trump aupr\u00e8s de l&rsquo;UE ( &laquo; <em>Ted Malloch : \u00ab\u00a0Well Mr Juncker was a very adequate mayor of some city in Luxembourg and maybe he should go back and do that again.\u00a0\u00bb<\/em> &raquo;). Franchement, \u00e9coutez-le et r\u00e9pondez \u00e0 cette question : vous le voyez en dictateur cruel et terrible de notre contre-civilisation et porte-parole du <em>Deep State<\/em>-UE ? Moi pas vraiment, et l\u00e0 se trouvent le grand Secret et le Myst\u00e8re sublime de notre Grande Crise de l&rsquo;effondrement du Syst\u00e8me : ils ne sont pas si machiav\u00e9liques ni si m\u00e9chants que cela, c&rsquo;est-\u00e0-dire pas du tout, et pourtant la catastrophe accompagne leurs discours et suit leurs pas, de Washington D.C. \u00e0 Paris, France, et jusqu&rsquo;au PE o&ugrave; parle Juncker, surpris entre deux canettes et, \u00e0 mon avis, <em>off<\/em>-canettes&#8230;<\/p>\n<\/p>\n<p><p>Note<\/p>\n<\/p>\n<p><p>(*) &laquo; <em>Life&rsquo;s but a walking shadow<\/em> [&#8230;] <em>it is a tale<\/em>\/<em>Told by an idiot, full of sound and fury,<\/em>\/ <em>Signifying nothing. <\/em>&raquo; Nombre de cas montrent que le sublime nihilisme de la trag\u00e9die humaine-shakespearienne d\u00e9crit avec tant de puissance par Shakespeare trouve un bien plus bel \u00e9crin dans son adaptation fran\u00e7aise que dans l&rsquo;anglais original. L&rsquo;anglais appuie sur le nihilisme presque d&rsquo;une fa\u00e7on comptable, le fran\u00e7ais exalte le tragique ; la puissance du mot \u00ab\u00a0rien\u00a0\u00bb, sa brutale courtitude, sa nettet\u00e9 coupante, sa puissance potentielle, son ontologie premi\u00e8re rendent compte du Myst\u00e8re et de l&rsquo;immensit\u00e9 incompr\u00e9hensible du concept, surpassant de loin l&rsquo;aspect un peu tra&icirc;nant, trop visiblement compos\u00e9 (\u00ab\u00a0aucune chose\u00a0\u00bb), qui conc\u00e8de trop \u00e0 l&rsquo;explicitation et r\u00e9duit l&rsquo;ontologie, de \u00ab\u00a0<em>nothing<\/em>\u00ab\u00a0. Shakespeare en fran\u00e7ais laisse plus de place \u00e0 l&rsquo;espoir que Shakespeare en anglais, il exprime mieux la profondeur n\u00e9cessairement structurante de l&rsquo;\u00e9nergie qui l&rsquo;habitait, lui le grand tragique \u00e9lisab\u00e9thain. La langue fran\u00e7aise, quand elle existait encore et lorsqu&rsquo;elle est extraite de sa gangue de pourriture r\u00e9ductrice et puante de la modernit\u00e9, est plus <a href=\"http:\/\/www.dedefensa.org\/article\/ma-verite-de-situation\">logocratique<\/a>, elle est <strong>m\u00e9taphysique et mieux faite pour d\u00e9crire l&rsquo;unicit\u00e9 extraordinaire de la Grande Crise G\u00e9n\u00e9rale que nous vivons<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chambre d&rsquo;\u00e9chos du tourbillon invertie 04 mars 2017 &ndash; A Washington D.C., au cas o&ugrave; on ne l&rsquo;aurait pas not\u00e9, tout se passe comme si BHO passait en mode \u00ab\u00a0ciel ouvert\u00a0\u00bb pour activer son \u00ab\u00a0coup\u00a0\u00bb contre Trump ; et le sort stup\u00e9fiant fait au secr\u00e9taire\u00e0 la Justice Sessions nous conduit tout droit \u00e0 une \u00ab\u00a0crise&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[8381,8002,12845,2625,2631,3870,3756,2824,12846,8972,12761,4614,5006,3340,2639,3248],"class_list":["post-77126","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-8381","tag-bho","tag-boulanger","tag-coup","tag-de","tag-droit","tag-etat","tag-europeen","tag-fevrier","tag-fillon","tag-francaises","tag-juncker","tag-parlement","tag-presidentielles","tag-trump","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77126"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77126\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}