{"id":77177,"date":"2017-04-02T15:27:38","date_gmt":"2017-04-02T15:27:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/02\/leurovision-a-tout-de-meme-de-linteret-cette-annee\/"},"modified":"2017-04-02T15:27:38","modified_gmt":"2017-04-02T15:27:38","slug":"leurovision-a-tout-de-meme-de-linteret-cette-annee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/02\/leurovision-a-tout-de-meme-de-linteret-cette-annee\/","title":{"rendered":"L&rsquo;<em>Eurovision<\/em> a tout de m\u00eame de l&rsquo;int\u00e9r\u00eat (cette ann\u00e9e)"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;<em>Eurovision<\/em> a tout de m\u00eame de l&rsquo;int\u00e9r\u00eat (cette ann\u00e9e)<\/h2>\n<\/p>\n<p><p>Il y a une affaire divertissante et instructive autour du Grand Concours de l&rsquo;Eurovision qui, outre la constance de sa tr\u00e8s-m\u00e9diocre qualit\u00e9 artistique en g\u00e9n\u00e9ral, nous pr\u00e9sente cette fois une dimension politique marqu\u00e9e et tr\u00e8s significative. Nous parlons de l&rsquo;\u00e9dition 2017, qui a acquis une dimension politique int\u00e9ressante, d\u00e9montrant que <strong>la mort de la politique par incoh\u00e9rence puis d\u00e9mence et n\u00e9antisation, est parvenue faire s&rsquo;enfuir nombre de ses composants pour qu&rsquo;ils aillent infester d&rsquo;autres domaines jusqu&rsquo;alors assez immunis\u00e9 malgr\u00e9 divers incidents<\/strong>. Aujourd&rsquo;hui, certains \u00e9v\u00e9nements non-politiques par d\u00e9finition sont d&rsquo;abord clairement et outrageusement politiques avant de se r\u00e9aliser plus ou moins pour ce qu&rsquo;ils sont originellement, tant bien que mal. Il s&rsquo;agit <strong>d&rsquo;\u00e9v\u00e9nements de type <em>entertainment<\/em> dans le sens le plus large du mot, allant du spectacle aux sports<\/strong>.<\/p>\n<\/p>\n<p><p>Cette fois, c&rsquo;est le concours <em>Eurovision<\/em> qui se trouve dans une temp\u00eate s\u00e9rieuse, et une fois n&rsquo;est pas coutume c<strong>e n&rsquo;est pas contre les Russes mais pour une affaire russe et contre les Ukrainiens<\/strong>. Il s&rsquo;agit du refus  des ukrainiens d&rsquo;accorder un visa d&rsquo;entr\u00e9e \u00e0 Yulia Samiolova, chanteuse russe choisie pour repr\u00e9senter la Russie au concours qui a lieu en Ukraine. A l&rsquo;affaire elle-m\u00eame, qui transgresse toutes les r\u00e8gles du concours, s&rsquo;ajoute le fait qui charge la chose d&rsquo;un fort poids affectif que Samiolova, affect\u00e9e dans sa jeunesse d&rsquo;une grave maladie (une amyotrophie spinale) , est paralys\u00e9e des jambes et se d\u00e9place en chaise roulante. L&rsquo;Ukraine justifie son refus par le fait que Samiolova a chant\u00e9 en Crim\u00e9e au cours des trois derni\u00e8res ann\u00e9es, sans visa pour entrer en Crim\u00e9e selon la <em>narrative<\/em> ukrainienne que la Crim\u00e9e fait partie de l&rsquo;Ukraine et constitue de ce fait un pr\u00e9c\u00e9dent inadmissible dans la situation europ\u00e9enne depuis 1945 et depuis 1989-1991. (Cet argument, \u00e0 l&rsquo;ombre de l&rsquo;ind\u00e9pendance du Kosovo proclam\u00e9e le 17 f\u00e9vrier 2008 \u00e0 la suite d&rsquo;un processus manipul\u00e9 de bout en bout par le bloc-BAO et quelques faux-nez de l&rsquo;ONU, en d\u00e9pit de la r\u00e9solution 1244 affirmant l&rsquo;int\u00e9grit\u00e9 territoriale de la Serbie et \u00e9tablissant ainsi un pr\u00e9c\u00e9dent, si l&rsquo;on s&rsquo;en tient au strict plan du droit international, qui rend la position de l&rsquo;Ukraine et du bloc-BAO pour le moins sujette \u00e0 la contestation.)<\/p>\n<\/p>\n<p><p>Il se trouve, circonstance exceptionnelle que, cette fois, il existe un ensemble important dans la direction du Concours et chez les autres participants pour juger inacceptable la position de l&rsquo;Ukraine, ce qui repr\u00e9sente une premi\u00e8re depuis d\u00e9but 2014 (coup de force de Kiev). En effet, jusqu&rsquo;\u00e0 maintenant, dans quelque enceinte que ce soit o&ugrave; l&rsquo;organisation et la conception sont de l&rsquo;origine du bloc-BAO, tout conflit entre Russie et Ukraine tournait in\u00e9vitablement aux d\u00e9pens de la premi\u00e8re. Les circonstances de cette affaire d\u00e9passent le cadre habituel de ce Concours qui est devenue une institution dans l&rsquo;architecture des activit\u00e9s de tous ordres touchant tous les domaines qui s&rsquo;est mise en place selon les crit\u00e8res de la globalisation, selon la vision g\u00e9n\u00e9rale du globalisme. L&rsquo;<em>Eurovision <\/em>est un exemple institutionnel, non seulement de la qualit\u00e9 souvent m\u00e9diocre des chansons, mais surtout de leur caract\u00e8re multiculturel \u00e0 dominante globaliste, \u00e9galement avec la domination quasi-h\u00e9g\u00e9monique de la langue anglaise [anglosaxonisation] malgr\u00e9 la diversit\u00e9 des langues des pays engag\u00e9s, tout cela selon une pr\u00e9sentation qui renvoie constamment aux langages et aux \u00ab\u00a0valeurs\u00a0\u00bb du globalisme. <strong>Tout cela montre la volont\u00e9 d&rsquo;universalisation et de nivellement globaliste qui y r\u00e8gne.<\/strong><\/p>\n<\/p>\n<p><p>Par cons\u00e9quenct, <strong>ce \u00ab\u00a0tout cela\u00a0\u00bb est confront\u00e9 \u00e0 un conflit interne<\/strong> qui compromet d&rsquo;une fa\u00e7on pr\u00e9occupante malgr\u00e9 l&rsquo;apparente l\u00e9g\u00e8ret\u00e9 du cas, l&rsquo;ordre globaliste puisque les autorit\u00e9s de l&rsquo;<em>Eurovision<\/em> semblent dans l&rsquo;obligation de mettre en accusation l&rsquo;Ukraine, <strong>ce pays-phares et ce symbole de la r\u00e9ussite de la globalisation et du globalisme contre la Russie<\/strong>. Alexander Mercouris d\u00e9crit avec pr\u00e9cision ce conflit constituant un exemple de plus des difficult\u00e9s que rencontre aujourd&rsquo;hui le globalisme, m\u00eame dans des circonstances institutionnelles o&ugrave; sa pr\u00e9\u00e9minence devrait \u00eatre verrouill\u00e9e. (Dans <em>TheDuran.com<\/em>, le <a href=\"http:\/\/theduran.com\/despite-sanctions-threat-ukraine-digs-russian-eurovision-ban\/\">1<sup>er<\/sup> avril 2017<\/a>.)<\/p>\n<\/p>\n<p><p>&laquo; <em>Though told by the Eurovision Song Contest organisers that Ukraine risks being banned from future competitions, and despite rumours that some participants are now considering boycotting the forthcoming Contest in Kiev unless Ukraine changes its stance, Ukraine still refuses to grant a visa to Russian contestant Yulia Samoilova to attend this year&rsquo;s Contest.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The political origin of the decision to refuse Samoilova a visa has now been made even clearer by a public statement of Ukrainian Foreign Minister Pavel Klimkin refusing any concessions to allow Samoilova to participate in the Contest.  So far as I can recall, it is unheard of for the foreign minister of any country to comment on such a question involving the Contest.  If the Ukrainian government were not involved one would expect statements of such a nature to be made either by Ukraine&rsquo;s border control authorities or by the organisers of the Contest in Kiev.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>At this point I cannot help but note that some Western media outlets have reported that it was the Russians who rejected the idea that Samoilova compete in the Contest via satellite, without mentioning that the Russians only did this after the Ukrainian government had already signalled its rejection of the idea.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Though the Western media (at least in Britain) has downplayed its reporting of this story, <strong>there is no doubt Ukraine&rsquo;s intransigence over this issue has done it harm<\/strong>.  European Broadcasting Union (EBU) Director General Ingrid Deltenre &ndash; hardly someone who might be expected to be unsympathetic to Ukraine &ndash; has <a href=\"http:\/\/tass.com\/world\/938724\" target=\"_blank\">pointed this out in a letter to Ukrainian Prime Minister Volodymyr Groysman<\/a> : \u00ab\u00a0The current situation is causing anger amongst our Members &ndash; European Broadcasters across Europe &ndash; and we have received communication from a number of them criticizing the decision and <strong>considering to withdraw from the event<\/strong>.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>It seems that Deltrene also pointed out in the same letter that Ukraine is doing its international reputation great harm because of the stance it is taking, and that no other country has ever prevented a Contest participant from taking part before.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>None of this appears to be cutting any ice in Kiev.  Given the extent to which ultra-right &lsquo;activists&rsquo; with their pathologically anti-Russian views are making the running that is completely unsurprising.  It seems that the Ukrainian authorities <strong>are more concerned to appease them<\/strong> then they are to spare Ukraine the damage to its image this affair is doing it even amongst its friends<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est un des premiers cas tr\u00e8s publics et \u00e0 forter\u00e9sonnance de communication o&ugrave; le caract\u00e8re si particulier de l&rsquo;Ukraine, &ndash; r\u00e9p\u00e9tons-le pour bien nous enconvaincre, un des fleurons des entreprises lib\u00e9ratrices du bloc-BAO, &ndash; montre en m\u00eame temps le d\u00e9sordre, la corruption, le n\u00e9potisme, la puissance des organisations d&rsquo;extr\u00eame-droite, qui caract\u00e9risent le fonctionnement vibrant de la d\u00e9mocratie dans la situation interne du pays. Toutes les pressions ext\u00e9rieures, notamment celles des pays de l&rsquo;UE et de l&rsquo;UE elle-m\u00eame et, par entra&icirc;nement de solidarit\u00e9 globaliste, celle des organisations US impliqu\u00e9es qui interviennent par automatisme bien qu&rsquo;elles n&rsquo;aient pas le moindre int\u00e9r\u00eat pour l&rsquo;<em>Eurovision<\/em> dont elles ignorent sans doute l&rsquo;existence, ne semblent pas devoir pour l&rsquo;instant entamer la r\u00e9solution de l&rsquo;Ukraine. <strong>C&rsquo;est un cas classique o&ugrave; une \u00ab\u00a0marionnette\u00a0\u00bb du bloc-BAO, absolument subvertie par le bloc et elle-m\u00eame totalement corrompue et sans la moindre attitude principielle, r\u00e9siste avec fermet\u00e9 \u00e0 ses ma&icirc;tres pour ne pas perturber ses proppres arrangements int\u00e9rieurs<\/strong>, \u00e9galement faits d&rsquo;impostures et de corruptions selon l&rsquo;exemple du bloc-BAO, multipli\u00e9 par le d\u00e9sordre int\u00e9rieur. C&rsquo;est un exemple de plus de la remarque que nous rappelons souvent, d&rsquo;Immanuel Wallerstein (ici cit\u00e9 le 24 d\u00e9cembre 2015), qui pourrait \u00eatre nomm\u00e9 \u00ab\u00a0le th\u00e9or\u00eame de Wallerstein\u00a0\u00bb (<em>\u00ab\u00a0les marionnettes tiennent leurs tireurs de ficelles, et non l&rsquo;inverse\u00a0\u00bb) <\/em> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Nous sommes dans une \u00e9poque marqu\u00e9e par l&rsquo;inversion de l&rsquo;influence comme <a href=\"http:\/\/www.dedefensa.org\/article\/wallerstein-yeats-et-lapressysteme\">l&rsquo;observe Immanuel Wallerstein<\/a> (\u00ab\u00a0les marionnettes tiennent leurs tireurs de ficelles, et non l&rsquo;inverse\u00a0\u00bb) : \u00a0\u00bb Most analysts of the current strife tend to assume that the strings are still being pulled by Establishment elites&#8230; [&#8230;] This seems to me a fantastic misreading of the realities of our current situation, which is one of extended chaos as a result of the structural crisis of our modern world-system. I do not think that the elites are any longer succeeding in manipulating their low-level followers&#8230; [&#8230;] I think however that step one is to cease attributing what is happening to the evil machinations of some Establishment elites. They are no longer in control&hellip;\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>&hellip; Et ainsi pourrait-on arriver \u00e0 cette situation horrible o&ugrave; un \u00e9v\u00e9nement strat\u00e9gique de l&rsquo;importance de l&rsquo;<em>Eurovision<\/em>, &ndash;grand \u00e9v\u00e9nement de la strat\u00e9gie de l&rsquo;<em>entertainment<\/em>, &ndash; verrait une condamnation de l&rsquo;Ukraine vertueuse au profit de l&rsquo;immonde Russie. Il n&rsquo;y a plus qu&rsquo;esp\u00e9rer que, quelque part, quelque chose c\u00e8de dans le bon sens, et q<strong>u&rsquo;on arrive par exemple \u00e0 montrer que tout cela est d&rsquo;abord l&rsquo;effet d&rsquo;une machination russe<\/strong>. Cette sorte de d\u00e9marche est vraiment de plus en plus difficile si on veut continuer \u00e0 la situer dans le domaine de la vraisemblance mais, comme tout bon globaliste nous  le dirait, il ne fait pas d\u00e9sesp\u00e9rer.<\/p>\n<\/p>\n<p><p>Mis en ligne le 2 avril 2017 \u00e0 15H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Eurovision a tout de m\u00eame de l&rsquo;int\u00e9r\u00eat (cette ann\u00e9e) Il y a une affaire divertissante et instructive autour du Grand Concours de l&rsquo;Eurovision qui, outre la constance de sa tr\u00e8s-m\u00e9diocre qualit\u00e9 artistique en g\u00e9n\u00e9ral, nous pr\u00e9sente cette fois une dimension politique marqu\u00e9e et tr\u00e8s significative. Nous parlons de l&rsquo;\u00e9dition 2017, qui a acquis une dimension&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12910,12908,6945,6975,2730,12909,1296,3469],"class_list":["post-77177","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chansons","tag-eurovision","tag-marionnettes","tag-pressions","tag-russie","tag-samialova","tag-ukraine","tag-wallerstein"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77177"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77177\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}