{"id":77185,"date":"2017-04-07T10:00:37","date_gmt":"2017-04-07T10:00:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/07\/mieux-quhillary-bien-mieux-que-bho\/"},"modified":"2017-04-07T10:00:37","modified_gmt":"2017-04-07T10:00:37","slug":"mieux-quhillary-bien-mieux-que-bho","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/07\/mieux-quhillary-bien-mieux-que-bho\/","title":{"rendered":"Mieux qu&rsquo;Hillary, bien mieux que BHO"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mieux qu&rsquo;Hillary, bien mieux que BHO<\/h2>\n<\/p>\n<p><p>07 avril 2017 &ndash; Il y a une rapidit\u00e9 peu ordinaire et sans pr\u00e9c\u00e9dent ni \u00e9quivalent concevable dans cette situation qui ne cesse de se faire succ\u00e9der les renversements radicaux des positions. C&rsquo;est dire si, \u00e0 cette heure de ce matin (09H00), quelques heures apr\u00e8s l&rsquo;intervention militaire US avec le tir de 60 missiles de croisi\u00e8re contre, semble-t-il, une base a\u00e9rienne syrienne, mon intervention \u00e0 moi sera bas\u00e9e sur une tr\u00e8s faible quantit\u00e9 d&rsquo;informations, et s&rsquo;en tenant au fait brut : rapidit\u00e9 de la d\u00e9cision, ex\u00e9cution imm\u00e9diate&#8230; Cela conduit \u00e0 quelques constats mesur\u00e9s \u00e0 l&rsquo;\u00e9vidence des \u00e9v\u00e9nements, \u00e0 quelques questions \u00e9galement \u00e9videntes mais nullement pr\u00e9cipit\u00e9es parce que r\u00e9p\u00e9t\u00e9es depuis au moins quatre ann\u00e9es \u00e0 la lumi\u00e8re des menaces d&rsquo;intervention US. Mais l&rsquo;observateur bien plus que le commentateur que je suis en a bien conscience : <strong>rien d&rsquo;assur\u00e9 dans toutes les remarques qui suivent, rien qui ne puisse changer et \u00eatre compl\u00e8tement d\u00e9menti en quelques heures au gr\u00e9 de cette situation absolument incontr\u00f4lable<\/strong>&#8230; Comme il <a href=\"http:\/\/www.dedefensa.org\/article\/de-watergate-20-a-melenchon\">\u00e9tait \u00e9crit<\/a> hier dans ce m\u00eame <em>Journal-dde.crisis<\/em> qui a l&rsquo;avantage, par sa personnalisation subjective de ne pas pr\u00e9tendre \u00e0 la moindre objectivit\u00e9 sans r\u00e9plique et aux pr\u00e9visions assur\u00e9es, &laquo; <em>Les \u00e9v\u00e9nements courent et n&rsquo;attendent pas ; <\/em><strong><em>ils prennent au vol ce qui leur convient, sans nous demander notre avis<\/em>&#8230; <\/strong>&raquo;  (*)<\/p>\n<\/p>\n<p><p>L&rsquo;attaque de cette nuit <strong>s&rsquo;est faite dans des conditions bien pires que celle qui <a href=\"http:\/\/www.dedefensa.org\/article\/hystericisme-syriana\">\u00e9tait pr\u00e9vue<\/a> en ao&ucirc;t 2013 et qui <a href=\"http:\/\/www.dedefensa.org\/article\/une-amerique-antiguerre-une-amerique-en-revolte\">n&rsquo;eut pas lieu<\/a><\/strong> : aucune certitude sur la responsabilit\u00e9 de l&rsquo;attaque et quelques signes \u00e9vidents de l&rsquo;habituel <em>false flag<\/em>, l&rsquo;absence compl\u00e8te d&rsquo;int\u00e9r\u00eat tactique jusqu&rsquo;\u00e0 l&rsquo;absurde de la Syrie de r\u00e9aliser une telle attaque au moment o&ugrave; les USA venaient <a href=\"http:\/\/www.dedefensa.org\/article\/mccain-furieux-trump-sabote-ma-politique-des-usa\">de modifier leur position vis-\u00e0-vis d&rsquo;Assad<\/a>, la situation v\u00e9rifi\u00e9e (par l&rsquo;ONU, la Russie et les USA) du d\u00e9sarmement chimique de la Russie <a href=\"http:\/\/www.dedefensa.org\/article\/onu-syrie-russie-usa-et-la-guerre-dans-tout-ca\">depuis 2013<\/a>, une information biais\u00e9e par des fili\u00e8res connues depuis longtemps comme tr\u00e8s-douteuses, aucune v\u00e9rification d&rsquo;aucun \u00e9l\u00e9ment dans les circonstances, aucune l\u00e9galit\u00e9 internationale, quasiment aucune consultation r\u00e9elle mais quelques notifications pr\u00e9ventives ici et l\u00e0, un climat absolument plong\u00e9, noy\u00e9 dans l&rsquo;hyst\u00e9rie et <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">l&rsquo;affectivisme<\/a>, etc. (On y ajoutera des consid\u00e9rations objectives : la pr\u00e9sence des Russes, l&rsquo;aide indirecte apport\u00e9e \u00e0 <em>Daesh<\/em> et les autres bandes que Trump pr\u00e9tend d\u00e9truire, et un encouragement direct \u00e0 poursuivre plus que jamais, le d\u00e9cha&icirc;nement belliciste des acteurs qui ont \u00e9t\u00e9 peu ou prou disciplin\u00e9s par les Russes : Isra\u00ebl, la Turquie, l&rsquo;Arabie, etc., et chacun bien entendu avec des buts diff\u00e9rents qui vont rallumer ou aggraver les affrontements, etc.)<\/p>\n<\/p>\n<p><p>Le premier constat paradoxal est que Trump a enti\u00e8rement justifi\u00e9 l&rsquo;une des principales critiques de ses adversaires durant la campagne USA-2016, r\u00e9sum\u00e9e par cette question supr\u00eame : \u00ab\u00a0Peut-on laisser \u00e0 un homme aussi impulsif la responsabilit\u00e9 de d\u00e9tenir la d\u00e9cision supr\u00eame de l&rsquo;utilisation de l&rsquo;arme nucl\u00e9aire ?\u00a0\u00bb. Le paradoxe, qu&rsquo;on peut aussi qualifier de \u00ab\u00a0complot\u00a0\u00bb mais encore faut-il voir sur quoi il d\u00e9bouche sinon sur le nihilisme destructeur du Syst\u00e8me avec les effets n\u00e9gatifs en retour probables (<em>blowback<\/em>), <strong>est que ce sont les pressions de ceux qui d\u00e9non\u00e7aient cette impulsivit\u00e9 qui ont suscit\u00e9 cette impulsivit\u00e9<\/strong>. On dira donc que, finalement tout se passe comme s&rsquo;il s&rsquo;agissait d&rsquo;une man&oelig;uvre complotiste \u00e0 laquelle Trump s&rsquo;est pr\u00eat\u00e9 sans la moindre r\u00e9flexion politique et strat\u00e9gique ; que cette man&oelig;uvre, notamment et paradoxalement, renforcera le dossier contre Trump, &ndash; car, c&rsquo;est ma conviction absolue que cette attaque, m\u00eame si elle est approuv\u00e9e par principe belliciste et affectiviste par ceux qui veulent sa chute, ne d\u00e9sarmera en rien la haine contre Trump ; <strong>au contraire, elle l&rsquo;attisera, et les critiques absolument contradictoires de ces m\u00eames adversaires bellicistes et anti-Trump vont pleuvoir, pour le pousser encore plus dans l&rsquo;impasse de politiques compl\u00e8tement irr\u00e9fl\u00e9chies<\/strong>. (Pourquoi a-t-il agi d&rsquo;une fa\u00e7on si impulsive, sans consulter le Congr\u00e8s ? Pourquoi n&rsquo;a-t-il pas frapp\u00e9 plus fort ? Pourquoi ne continue-t-il pas \u00e0 frapper ? A quoi sert-il de frapper si l&rsquo;on n&rsquo;a pas de strat\u00e9gie de <em>regime change<\/em> et, s&rsquo;il vous pla&icirc;t, <em>illico presto<\/em> ? Et ainsi de suite.) (**)<\/p>\n<\/p>\n<p><p>Ce dernier point de la haine anti-Trump va \u00e9videmment compl\u00e8tement, &ndash; et l\u00e0 encore, c&rsquo;est ma conviction, &ndash; contre la possibilit\u00e9 qu&rsquo;il voit lui-m\u00eame dans cette attaque d&rsquo;une fa\u00e7on de r\u00e9tablir sa position et d&rsquo;\u00e9tablir son autorit\u00e9 ; par ailleurs, <strong>et ce n&rsquo;est pas rien<\/strong>, il est <a href=\"http:\/\/theduran.com\/5-famous-trump-supporters-who-oppose-war-with-syria\/\">en train de perdre<\/a> \u00e0 une tr\u00e8s grande vitesse le soutien de ceux qui l&rsquo;ont conduit \u00e0 la victoire du 8 novembre. Il affirmera peut-\u00eatre : \u00ab\u00a0Au moins, les Syriens vont cesser leurs attaques chimiques\u00a0\u00bb. C&rsquo;est assez juste <em>stricto sensu<\/em> puisque ce n&rsquo;est probablement pas eux qui ont fait cette attaque, &ndash; mais cela, en attendant le prochain <em>false flag<\/em>, non ? Ou bien en guettant les r\u00e9sultats, &ndash; excellent travail, certes, &ndash; de <strong>la relance de l&rsquo;attitude offensive de Daesh gr\u00e2ce aux frappes US<\/strong>, oui ? Pour ajouter un peu de sel sur la p\u00e9rennit\u00e9 des jugements de ces gens parmi lesquels il faut d\u00e9sormais le placer, on observera que Trump aurait aussi bien pu se r\u00e9f\u00e9rer \u00e0 cette <a href=\"https:\/\/www.rt.com\/usa\/383834-trump-syria-strike-old-tweets\/\">s\u00e9rie de tweets<\/a> diffus\u00e9s lors de l&rsquo;alerte de 2013, dans des circonstances quasiment identiques sinon le recul d&rsquo;Obama \u00e0 propos duquel on est oblig\u00e9 de reconna&icirc;tre qu&rsquo;il a c\u00e9d\u00e9 aux circonstances plus qu&rsquo;il ne les a ignor\u00e9es comme Trump, &ndash; une s\u00e9rie de tweets de l&rsquo;\u00e9poque, qu&rsquo;on retrouve un peu partout en citation, <strong>comme un rappel tristement ironique<\/strong>, comme celui-ci par exemple :<\/p>\n<\/p>\n<p><p>&laquo; <em>Donald J. Trump@realDonaldTrump : What will we get for bombing Syria besides more debt and a possible long term conflict? <\/em><em>Obama needs Congressional approval. 8:14 PM &#8211; 29 Aug 2013<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;extraordinaire rapidit\u00e9 de la dissolution de l&rsquo;administration Trump alors qu&rsquo;elle n&rsquo;est m\u00eame pas encore constitu\u00e9e <strong>re\u00e7oit avec l&rsquo;\u00e9v\u00e9nement de cette nuit un fameux coup de pouce<\/strong> ; cela, m\u00eame si cette \u00e9v\u00e9nement est interpr\u00e9t\u00e9 comme une victoire de ses adversaires (appelez-les comme vous voulez : <em>Deep State<\/em>, <em>neocons<\/em>, bellicistes soci\u00e9taux-progressistes et globaliste dont on apprend avec une surprise accabl\u00e9e sinon \u00e9puis\u00e9e car qui peut savoir le vrai dans ce cloaque de la <em>post-<\/em>V\u00e9rit\u00e9 que sa fille Ivanka et son gendre en font partie), ce d\u00e9veloppement ne laisse nullement deviner une situation nouvelle nettement tranch\u00e9e (au choix : Trump prisonnier ou Trump \u00e9limin\u00e9) ; parce que, <a href=\"http:\/\/www.dedefensa.org\/article\/de-watergate-20-a-melenchon\">par rapport \u00e0 hier<\/a>, rien, <strong>absolument rien n&rsquo;a chang\u00e9 et le <em>Deep State<\/em> est plus fractur\u00e9 que jamais, avec ses obsessions et ses hyst\u00e9ries pathologiques de la psychologie.<\/strong> <strong>Le r\u00e9sultat, c&rsquo;est du d\u00e9sordre, encore plus de d\u00e9sordre, toujours plus de d\u00e9sordre<\/strong>.<\/p>\n<\/p>\n<p><p>Du c\u00f4t\u00e9 russe, l&rsquo;action de l&rsquo;administration Trump pourrait bien faire \u00e9voluer d\u00e9cisivement la situation profonde et \u00e0 terme du pays, avec la possibilit\u00e9 d&rsquo;effets plus rapproch\u00e9s selon la voie choisie. C&rsquo;est-\u00e0-dire qu&rsquo;elle placerait \u00e9ventuellement <strong>Poutine devant une singuli\u00e8re alternative \u00e9lectorale<\/strong> : <strong>durcir sa position et sa politique, avec effets militaires<\/strong>, s&rsquo;il veut \u00eatre r\u00e9\u00e9lu en mars 2018 (dans onze mois) ; <strong>ou nous pr\u00e9parer \u00e0 voir surgir<\/strong> un dur nationaliste \u00e9ventuellement incontr\u00f4lable, type-Jirinovski, ou certainement inflexible, type-Rogozine, ou encore quelque g\u00e9n\u00e9ral d\u00e9cid\u00e9 au pire.<\/p>\n<\/p>\n<p><p>Dans quelque sens qu&rsquo;on se tourne, c&rsquo;est la surpuissance du Syst\u00e8me qui gronde, sans aucun espoir de stabilisation et avec de multiples possibilit\u00e9s de conflits. Dans ce cas, l&rsquo;automatique autodestruction qui suit aussit\u00f4t laisserait des traces profondes sur la situation du monde. Il ne reste plus qu&rsquo;\u00e0 esp\u00e9rer <strong>dans la capacit\u00e9 infinie des directions-Syst\u00e8me de se d\u00e9chirer entre elles<\/strong>, dans une atmosph\u00e8re si totalement d\u00e9pourvue de mesure et de logique, et compl\u00e8tement emport\u00e9e par l&rsquo;hyst\u00e9rie et l&rsquo;affectivisme.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h3>\n<\/p>\n<p><p>(*) Citation, pour mon cas et renseigner mes lecteurs sur cette position irr\u00e9fragable, \u00e0 toujours avoir \u00e0 l&rsquo;esprit : &laquo; <em>Puisque les \u00e9v\u00e9nements vont tr\u00e8s vite, beaucoup plus vite que nul ne peut imaginer, tentons de les suivre non pas pour les expliquer, ce qui supposerait d&rsquo;en \u00eatre en partie les instigateurs, mais de les comprendre comme un observateur ext\u00e9rieur qui ne peut rien pour les modifier. Il y a longtemps que je ne peux me d\u00e9partir du sentiment que \u00ab\u00a0les \u00e9v\u00e9nements\u00a0\u00bb, &ndash; expression passe-partout pour figurer la dynamique de la Grande Crise G\u00e9n\u00e9rale de l&rsquo;effondrement du Syst\u00e8me, &ndash; sont <strong>totalement d\u00e9tach\u00e9s de nous, hors de notre contr\u00f4le, qu&rsquo;ils ont leur propre logique et j&rsquo;irais m\u00eame jusqu&rsquo;\u00e0 dire comme pour les personnaliser en un \u00eatre leur propre essence<\/strong>. Je ne peux donc \u00eatre que cet \u00ab\u00a0observateur ext\u00e9rieur qui ne peut rien pour les modifier\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>(**) Par exemple, <em>BBC.News <\/em>estime que Trump est \u00ab\u00a0au moins en partie\u00a0\u00bb responsable de l&rsquo;attaque chimique lanc\u00e9e s&ucirc;rement (quoique ce ne soit pas \u00e9tabli) par Assad, parce qu&rsquo;il n&rsquo;a pas attaqu\u00e9 Assad d\u00e8s les premi\u00e8res dsemaines de son entr\u00e9e en fonction. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mieux qu&rsquo;Hillary, bien mieux que BHO 07 avril 2017 &ndash; Il y a une rapidit\u00e9 peu ordinaire et sans pr\u00e9c\u00e9dent ni \u00e9quivalent concevable dans cette situation qui ne cesse de se faire succ\u00e9der les renversements radicaux des positions. C&rsquo;est dire si, \u00e0 cette heure de ce matin (09H00), quelques heures apr\u00e8s l&rsquo;intervention militaire US avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[4202,2870,3903,12925,12572,2631,7153,12098,4327,3602,12926,2970,2730,3973,3867],"class_list":["post-77185","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-assad","tag-attaque","tag-chimique","tag-croisiere","tag-daesh","tag-de","tag-deep","tag-false","tag-flag","tag-haine","tag-impulsivite","tag-missiles","tag-russie","tag-state","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77185"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77185\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}