{"id":77186,"date":"2017-04-07T17:52:28","date_gmt":"2017-04-07T17:52:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/07\/lattaque-la-plus-post-verite-de-tous-les-temps\/"},"modified":"2017-04-07T17:52:28","modified_gmt":"2017-04-07T17:52:28","slug":"lattaque-la-plus-post-verite-de-tous-les-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/07\/lattaque-la-plus-post-verite-de-tous-les-temps\/","title":{"rendered":"L&rsquo;attaque la plus <em>post<\/em>-V\u00e9rit\u00e9 de tous les temps\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;attaque la plus <em>post<\/em>-V\u00e9rit\u00e9 de tous les temps ?<\/h2>\n<\/p>\n<p><p>Comme nous avons l&rsquo;habitude de ne jamais le cacher, il nous para&icirc;t aujourd&rsquo;hui impossible de faire un commentaire direct sur les intentions, les calculs et les manipulations qui sont d\u00e9velopp\u00e9es dans nombre, sinon dans la plupart des \u00e9v\u00e9nements crisiques auxquels nous assistons. C&rsquo;est donc logiquement le cas pour cette attaque de 59 missiles de croisi\u00e8re contre une seule base syrienne, dans des conditions effectivement \u00e9tranges, pour des r\u00e9sultats apparemment \u00e9tranges, selon des interpr\u00e9tations aussi nombreuses qu&rsquo;\u00e9tranges. <strong>Nous sommes bien dans l&rsquo;aire et dans les temps de la <em>post<\/em>-V\u00e9rit\u00e9<\/strong>, o&ugrave; plus rien ne peut \u00eatre tenu pour assur\u00e9 dans l&rsquo;apparence des faits, ou de ce qui est pr\u00e9sent\u00e9 comme \u00e9tant des faits. C&rsquo;est dire combien notre prudence extr\u00eame et notre r\u00e9ticence \u00e0 faire des commentaires directs sur les \u00e9v\u00e9nements, ou plut\u00f4t l&rsquo;apparence des \u00e9v\u00e9nements, sont plus grandes que jamais.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ci-dessous, nous allons signaler quelques affirmations, interpr\u00e9tations, consid\u00e9rations, etc., sans en prendre une seule \u00e0 notre compte d&rsquo;une fa\u00e7on affirm\u00e9e. Les r\u00e9actions de PhG dans son <em>Journal-dde.crisis<\/em> <a href=\"http:\/\/www.dedefensa.org\/article\/mieux-quhillary-bien-mieux-que-bho\">du jour<\/a> rendent compte d&rsquo;une perception des \u00e9v\u00e9nements de cette attaque qui semble avoir \u00e9t\u00e9 ordonn\u00e9e par Trump, qui ne correspondent n\u00e9cessairement pas \u00e0 l&rsquo;apparence de la r\u00e9alit\u00e9, mais dans ce cas selon l&rsquo;argument que, pour nous, la r\u00e9alit\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">a \u00e9t\u00e9 pulv\u00e9ris\u00e9e<\/a> depuis au moins le d\u00e9but de la crise ukrainienne. Cette \u00ab\u00a0perception\u00a0\u00bb-l\u00e0 a beaucoup d&rsquo;une interpr\u00e9tation ; elle correspond \u00e0 la recherche <strong>d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> comme antidote \u00e0 la doctrine de la <em>post<\/em>-V\u00e9rit\u00e9<\/strong> qui, aujourd&rsquo;hui, tente d&rsquo;influencer l&rsquo;observation des \u00e9v\u00e9nements dans le sens d&rsquo;une certitude faussaire et contrainte conduisant \u00e0 en tirer des commentaires faussement assur\u00e9s. <strong>C&rsquo;est bien cela que nous distinguons dans le concept de <em>post<\/em>-V\u00e9rit\u00e9 qui est un concept du Syst\u00e8me et nullement une accusation contre l&rsquo;antiSyst\u00e8me : un pi\u00e8ge tendu \u00e0 la perception pour la conduire vers ce qu&rsquo;elle croirait \u00eatre la certitude d&rsquo;un commentaire<\/strong>.<\/p>\n<\/p>\n<p><p>Justement dans le cas qui nous est offert aujourd&rsquo;hui, <strong>on d\u00e9couvre tant d&rsquo;interpr\u00e9tations qu&rsquo;on se trouve rassur\u00e9 d&rsquo;avoir choisi cette voie du refus d&rsquo;un commentaire assur\u00e9<\/strong>. Plus que jamais pr\u00e9vaut chez nous l&rsquo;id\u00e9e qu&rsquo;il y a deux volets, deux plans diff\u00e9rents dans les \u00e9v\u00e9nements : celui de la <em>post<\/em>-V\u00e9rit\u00e9, <strong>niveau des manigances humaines<\/strong> qui peuvent venir de diff\u00e9rentes sources, de diff\u00e9rents c\u00f4t\u00e9s, et qui est bien ce \u00ab\u00a0pi\u00e8ge tendu \u00e0 la perception vers ce qu&rsquo;elle croirait \u00eatre la certitude d&rsquo;u commentaire\u00a0\u00bb ; et celui des \u00e9v\u00e9nements eux-m\u00eames, tels qu&rsquo;ils sont et tels qu&rsquo;ils se d\u00e9ploient dans leur majest\u00e9, <strong>s\u00e9par\u00e9s des contingences humaines et indiquant les grandes dynamiques de force de la m\u00e9tahistoire<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(Citation pour ce dernier cas, de PhG <a href=\"http:\/\/www.dedefensa.org\/article\/de-watergate-20-a-melenchon\">du 6 avril<\/a> : &laquo; <em>Il y a longtemps que je ne peux me d\u00e9partir du sentiment que \u00ab\u00a0les \u00e9v\u00e9nements\u00a0\u00bb, &ndash; expression passe-partout pour figurer la dynamique de la Grande Crise G\u00e9n\u00e9rale de l&rsquo;effondrement du Syst\u00e8me, &ndash; sont <strong>totalement d\u00e9tach\u00e9s de nous, hors de notre contr\u00f4le, qu&rsquo;ils ont leur propre logique et j&rsquo;irais m\u00eame jusqu&rsquo;\u00e0 dire comme pour les personnaliser en un \u00eatre leur propre essence<\/strong>. Je ne peux donc \u00eatre que cet \u00ab\u00a0observateur ext\u00e9rieur qui ne peut rien pour les modifier\u00a0\u00bb<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Tout cela \u00e9tant bien pr\u00e9cis\u00e9, il s&rsquo;agit effectivement du constat qu&rsquo;on vit rarement sinon jamais une de ces attaques brutales et ill\u00e9gales, violatrices des souverainet\u00e9s, de la part des USA, appara&icirc;tre en quelques heures comme une \u00e9nigme ou un grand d\u00e9sordre tant dans son op\u00e9rationnalit\u00e9, son ex\u00e9cution et les buts recherch\u00e9s. Voici donc quelques th\u00e8ses, observations, interpr\u00e9tations, etc.<\/p>\n<\/p>\n<p><p>&bull; Du c\u00f4t\u00e9 du \u00ab\u00a0bloc-BAO\u00a0\u00bb, avec l&rsquo;UE, la France, etc., le soutien est d&rsquo;une unanimit\u00e9 un peu surprise et dubitative, sans exactement savoir o&ugrave; l&rsquo;on va, bien entendu en toute soumission \u00e0 la th\u00e8se qui nous \u00e9crase depuis 2011 : \u00ab\u00a0Il faut attaquer et abattre Bachar par tous les moyens pour r\u00e9soudre merveilleusement et d\u00e9mocratiquement la crise syrienne\u00a0\u00bb. Certains, comme le Fran\u00e7ais Hollande, pr\u00f4nent donc l&rsquo;id\u00e9e de la poursuite d&rsquo;une riposte \u00e0 l&rsquo;attaque chimique, toujours selon la <em>narrative<\/em> classique, mais dans le cadre de l&rsquo;ONU. D&rsquo;autres \u00e9mettent des serments de soutien, sans plus (Tusk, de l&rsquo;UE) et d&rsquo;autres annoncent prudemment qu&rsquo;ils ne pr\u00e9voient pas de participer \u00e0 quelque action que ce soit (la Britannique Theresa May).<\/p>\n<\/p>\n<p><p>Le cas du Fran\u00e7ais Hollande est particuli\u00e8rement marquant sinon r\u00e9jouissant, lui qui disait hier, avant les frappes, qu&rsquo;il fallait donc d\u00e9cider \u00e0 l&rsquo;ONU d&rsquo;une enqu\u00eate sur l&rsquo;attaque chimique (sans doute pour d\u00e9terminer et identifier les coupables ?) puis des sanctions \u00e0 prendre contre Assad ; autrement dit, on d\u00e9cide en m\u00eame temps d&rsquo;une enqu\u00eate pour d\u00e9terminer qui est le coupable et des sanctions qui seront prises contre Assad puisque c&rsquo;est lui qui est le coupable. (Apr\u00e8s les frappes US et selon cette approche classique bloc-BAO, nous en sommes <strong>au point o&ugrave; nous avons d\u00e9j\u00e0 commenc\u00e9 \u00e0 punir le coupable [Assad] avant de se lancer dans cette enqu\u00eate pour identifier le coupable<\/strong>.) L&rsquo;attitude de Hollande, qui affirme avoir \u00e9t\u00e9 averti \u00ab\u00a0avant les frappes\u00a0\u00bb montre bien qu&rsquo;il a \u00e9t\u00e9 averti \u00ab\u00a0apr\u00e8s les frappes\u00a0\u00bb, c&rsquo;est-\u00e0-dire pas averti du tout, <strong>et qu&rsquo;il est une fois de plus cocu, comme en ao&ucirc;t 2013<\/strong> (Fran\u00e7ais lan\u00e7ant d\u00e9j\u00e0 leur premiers avions contre Assad lorsqu&rsquo;Obama annonce, sans avoir consult\u00e9 personne, qu&rsquo;on remet l&rsquo;attaque, puis bient\u00f4t qu&rsquo;on l&rsquo;abandonne.) Habile, Hollande esp\u00e8re bien reprendre la main \u00e0 l&rsquo;ONU, dont Trump se contrefiche, pour en faire profiter son candidat Micron qui s&rsquo;est empress\u00e9 d&rsquo;approuver l&rsquo;attaque.<\/p>\n<\/p>\n<p><p>&#8230; Bref, tout le monde a \u00e9t\u00e9 pris \u00e0 contre-pied \u00e0 Paris, o&ugrave; l&rsquo;on va \u00e9lire un pr\u00e9sident dans 16-30 tout petits jours. Il fallait entendre cette remarque singuli\u00e8re d&rsquo;inversion d&rsquo;Alexis Brezet, du <em>Figaro<\/em>, ce matin sur LCI : \u00ab\u00a0Tout le monde a \u00e9t\u00e9 pris de court, \u00e0 contre-pied &#8230; On \u00e9tait tous s&ucirc;rs que Trump \u00e9tait un fou-furieux, et voil\u00e0 qu&rsquo;il ne l&rsquo;est pas du tout puisqu&rsquo;il frappe la Syrie et Assad\u00a0\u00bb ; ainsi, aujourd&rsquo;hui, pour montrer patte-blanche et prouver que vous n&rsquo;\u00eates pas un \u00ab\u00a0fou-furieux\u00a0\u00bb, il importe de taper ill\u00e9galement sur un pays souverain, donc de commettre un acte d&rsquo;ill\u00e9galit\u00e9 et d&rsquo;agression internationale ; ainsi, aujourd&rsquo;hui, <strong>qui n&rsquo;\u00e9pouse pas la <em>narrative<\/em> de l&rsquo;attaque \u00e0 tout prix n&rsquo;est rien d&rsquo;autre qu&rsquo;un \u00ab\u00a0fou-furieux\u00a0\u00bb<\/strong>. Dont acte, en <strong>hommage au langage automatis\u00e9 des zombies-Syst\u00e8me<\/strong>&#8230;  <\/p>\n<\/p>\n<p><p>&bull; Une autre th\u00e8se est que, non non, l&rsquo;objectif n&rsquo;\u00e9tait pas Assad ni la Syrie, mais d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale divers pays dans le monde \u00e0 qui il faut faire comprendre que les USA-Trump sont pr\u00eats \u00e0 frapper n&rsquo;importe o&ugrave; dans le monde. Par exemple, Alex Jones, de <em>Infowars.com<\/em>, qui a d&rsquo;abord condamn\u00e9 l&rsquo;attaque, s&rsquo;est <a href=\"https:\/\/www.youtube.com\/watch?v=CDwqBSw8nX0\">un peu rattrap\u00e9<\/a> en expliquant qu&rsquo;il s&rsquo;agissait d&rsquo;un message au pr\u00e9sident chinois Xi (alias \u00ab\u00a0le dictateur chinois\u00a0\u00bb), que Trump rencontre actuellement, \u00e0 destination indirecte de la Cor\u00e9e du Nord avec laquelle la Chine a des liens, et \u00e9ventuellement \u00e0 destination de la Chine, &ndash; histoire de montrer aux uns en aux autres ce que <em>America the Beautiful<\/em> est capable de faire.<\/p>\n<\/p>\n<p><p>&bull; Les Russes (officiels) ont \u00e9t\u00e9 tr\u00e8s diserts sur cette attaque US. (Il est souvent dit ici et l\u00e0 qu&rsquo;ils ont \u00e9t\u00e9 avertis de cette attaque, et m\u00eame de l&rsquo;objectif pr\u00e9cis, de fa\u00e7on \u00e0 ce qu&rsquo;aucun soldat russe ni avion russe ne soit touch\u00e9. En ont-ils touch\u00e9 un mot aux Syriens qui se trouvaient sur la base ?) Le Major G\u00e9n\u00e9ral Konachenkov, porte-parole du minist\u00e8re de la d\u00e9fense, nous explique donc <a href=\"https:\/\/sputniknews.com\/middleeast\/201704071052396220-airbase-syria-attack-prepared\/\">ce 7 avril<\/a> que l&rsquo;attaque des missiles de croisi\u00e8re \u00e9tait pr\u00e9par\u00e9e de longue date, que l&rsquo;attaque chimique en a \u00e9t\u00e9 le pr\u00e9texte, et que tout cela est fait comme \u00ab\u00a0une d\u00e9monstration de force militaire [&#8230;] justifi\u00e9e exclusivement par des raisons de politique interne\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>\u00ab\u00a0It is evident that the US cruise missile strikes against a Syrian airbase have been prepared long before today&rsquo;s events. A large system of measures of reconnaissance, planning, preparation of flight tasks and bringing the missiles to launch readiness needs to be carried out to prepare such an attack,\u00a0\u00bb ministry&rsquo;s spokesman Maj. Gen. Igor Konashenkov said. According to Konashenkov, the Idlib chemical attack \u00ab\u00a0served only as a formal pretext, while the demonstration of military force took place exclusively due to internal political reasons.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Au reste, bien des interrogations planent \u00e9galement sur les conditions et les effets de l&rsquo;attaque : 59 missiles de croisi\u00e8re dont 36 perdus dans la nature, &ndash; ce qui nous donnerait quelques pr\u00e9occupations technologiques sur la superbe et la puissance irr\u00e9sistible de notre contre-r\u00e9volution, &ndash; et comme r\u00e9sultat, de 3 \u00e0 6 morts selon les versions du c\u00f4t\u00e9 russe, o&ugrave; l&rsquo;on est \u00e9galement tr\u00e8s disert sur cet aspect des choses, et \u00e9galement tr\u00e8s prolixe de <a href=\"https:\/\/www.rt.com\/news\/383912-russia-mod-drone-syria-airbase\/\">documents film\u00e9s<\/a> et autres dans le <a href=\"https:\/\/www.rt.com\/news\/383857-video-syria-missile-attack-us\/\">domaine de l&rsquo;image<\/a> ; 5 ou 6 avions d\u00e9truits, l&rsquo;un ou l&rsquo;autre hangar, un poste radar, &ndash; et c&rsquo;est \u00e0 peu pr\u00e8s tout&#8230; <strong>\u00ab\u00a0D\u00e9gats insignifiants\u00a0\u00bb, r\u00e9sume le gouverneur syrien de Oms, relay\u00e9 par les m\u00e9dias russes<\/strong>. Sacr\u00e9 op\u00e9ration de l&rsquo;hyperpuissance am\u00e9ricaniste, r\u00e9sume le p\u00e9kin moyen, &ndash; si tout cela est juste, sinon <em>post<\/em>-V\u00e9rit\u00e9.<\/p>\n<\/p>\n<p><p>Donc, un r\u00e9sum\u00e9 de cet aspect des choses selon ces m\u00eames sources russes, c&rsquo;est-\u00e0-dire le minist\u00e8re de la d\u00e9fense et son porte-parole Konachenkov : &laquo; <em>\u00ab\u00a0On April 7, at the time between 3:42 and 3:56 a.m. Moscow time<\/em> [00:42-00:56 GMT] <em>a massive missile attack by 59 Tomahawk cruise missiles was carried out from two destroyers of the US Navy<\/em> [Ross and Porter]<em>, from the Mediterranean Sea, near the island of Crete, targeting Syrian airfield Ash Sha&rsquo;irat [Homs Province]. <\/em><em>According to the Russian data recording technology, only 23 cruise missiles reached the Syrian airbase. It is not clear where the other 36 cruise missiles landed,\u00a0\u00bb Konashenkov said at a briefing. The spokesman stressed that the strike destroyed many facilities and equipment, including six planes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Two Syrian servicemen are missing as a result of the US attack on an airfield in the country, while four were killed and six were injured extinguishing the flames, Russian Defense Ministry spokesman Maj. Gen. Igor Konashenkov said Friday. \u00ab\u00a0According to the information of the leadership of the Syrian airbase, two Syrian servicemen went missing, four were killed and six received burn injuries during the firefighting,\u00a0\u00bb he said<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Allant dans une autre direction, <em><a href=\"http:\/\/www.debka.com\/article\/26003\/US-strikes-Syrian-military-airfield-\">DEBKAFiles<\/a><\/em> affirme que l&rsquo;ensemble de cette affaire a \u00e9t\u00e9 mont\u00e9e d&rsquo;abord <strong>par la coalition Syrie-Iran-Russie pour contrer des projets US d&rsquo;\u00e9vincer les Iraniens et le Hezbollah de Syrie<\/strong>, et qu&rsquo;ensuite les conditions de l&rsquo;attaque ont \u00e9t\u00e9 tr\u00e8s pr\u00e9cis\u00e9ment n\u00e9goci\u00e9es entre Russes et Am\u00e9ricains pour \u00e9viter toute confrontation. Pour autant, <em>DEBKAFiles <\/em>se demande si la Russie ne va pas riposter, ou bien l&rsquo;Iran ou la Syrie elle-m\u00eame. Bref, on copine et on se castagne sans trop de mal de concert.<\/p>\n<\/p>\n<p><p>&laquo; <em>Washington has no doubt that the Syrian SU-22 bomber which Tuesday dropped a sarin gas bomb on Khan Sheikhoun in Idlib province, killing up to 100 people, was a joint Russian-Iranian-Syrian gambit to divert the Trump administration from a comprehensive plan for Syria. As US President and commander-in-chief he could not ignore this provocation.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Our sources report that the new US administration&rsquo;s plans for Syria center on an offensive to evict the Islamic State from its Syrian capital, Raqqa, a mission for which US military preparations have been going forward for the past two weeks at five centers. <\/em><em>To this operation Moscow, Tehran and Damascus were not averse. But that operation was also designed to rid Syria of Iranian and Hizballah forces &#8211; to which they were<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; &#8230;<em>The question now is whether Vladimir Putin will decide to hit back at the US operation. Russia did not retaliate for the Israel air strike on March 17 over the northern Syrian T4 air base. <\/em><em>If Putin chooses to sit on his hands once again, the same question may be addressed to Iran and Hizballah<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Very possibly, Trump and Putin reached accord on the limits of the US punitive attack in Syrian in long hours of debate during the day between the US State and Defense Departments and the Russian Foreign and Defense Ministries, which were first reported by DEBKAfile 24 hours ago<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>&bull; Stephen Bryan, sur <em>Asia Times<\/em>, donne <a href=\"http:\/\/www.atimes.com\/assad-use-nerve-gas\/?utm_source=The+Daily+Brief&#038;utm_campaign=08bda1926d-EMAIL_CAMPAIGN_2017_04_07&#038;utm_medium=email&#038;utm_term=0_1f8bca137f-08bda1926d-16240351\">le 7 avril<\/a> une version aussi complexe que <em>DEBKAFiles<\/em>, mais avec une r\u00e9partition diff\u00e9rente des r\u00f4les. <strong>Cette fois, Russie et US sont main dans la main et Assad joue en solo<\/strong>&#8230; Selon Bryan, l&rsquo;attaque au sarin est une initiative du seul Assad, avec le but, en obligeant les USA \u00e0 r\u00e9agir, d&#8217;emp\u00eacher l&rsquo;application d&rsquo;un accord secret entre les USA et la Russie qui transformerait la Syrie en une sorte d&rsquo;entit\u00e9 conf\u00e9d\u00e9rale o&ugrave; les Alawites de Assad ne contr\u00f4leraient plus que les r\u00e9gions essentiellement peupl\u00e9es d&rsquo;Alawites. Il s&rsquo;agit du projet ou de la menace r\u00e9currente de partition de la Syrie comme solution au conflit.<\/p>\n<\/p>\n<p><p>&bull; Enfin (pour notre compte, mais il y a bien d&rsquo;autres versions), il y a l&rsquo;interpr\u00e9tation de <em><a href=\"http:\/\/www.wsws.org\/en\/articles\/2017\/04\/07\/syri-a07.html\">WSWS.org<\/a><\/em>. Elle est bien entendu globale et apocalyptique. Pour le site de la IV\u00e8me internationale trotskiste, il s&rsquo;agit d&rsquo;un \u00e9pisode normal de remise dans le rang de Trump et de ses divers projets populistes, d&rsquo;un regroupement de la \u00ab\u00a0<em>ruling class<\/em>\u00a0\u00bb (le <em>Deep State<\/em>, si l&rsquo;on veut, ou l&rsquo;oligarchie dirigeante, etc.), pour entamer un nouveau conflit majeur au Moyen-Orient. <strong>Le risque d&rsquo;une confrontation avec la Russie d\u00e9bouchant sur un affrontement nucl\u00e9aire est r\u00e9el, majeur sinon catastrophique selon cette analyse, mais la \u00ab\u00a0<em>ruling class<\/em>\u00a0\u00bb est pr\u00eate \u00e0 le courir<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>An attack on Syria carries with it the direct threat of a far wider and potentially world catastrophic war. What will be the reaction of Russia, a nuclear power, if American missiles kill its military personnel on the ground in Syria? <\/em><em>The American ruling class is willing to take the risk. Confronted with the protracted decline of its once unchallenged dominance of the world economy, it is forced to rely more and more on its military power as a means of asserting global hegemony. That such a course points inevitably to a new world war that would threaten the survival of humanity will not cause it to change course.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The actions of the US oligarchy recalls nothing so much as Trotsky&rsquo;s description of the world bourgeoisie on the eve of World War II, hurtling \u00ab\u00a0with closed eyes toward an economic and military catastrophe.\u00a0\u00bbThe conflict that has erupted will not end with Tomahawk missiles. The drive of the United States for global hegemony cannot be resolved outside of an endless series of military escalations, each more reckless than the one before, leading ultimately to catastrophe<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Et, pour conclure, on constatera une fois encore que le fait est que rarement, sinon jamais, une op\u00e9ration \u00ab\u00a0classique\u00a0\u00bb d&rsquo;agression ill\u00e9gale et sans la moindre dissimulation des USA du type tr\u00e8s spectaculaire, avec flamboiement du d\u00e9part des missiles de croisi\u00e8re dans la nuit, une chose \u00e0 laquelle nous sommes d\u00e9sormais accoutum\u00e9s depuis bien plus de deux d\u00e9cennies mais pourtant convi\u00e9s \u00e0 continuer \u00e0 nous en extasier, <strong>jamais une telle op\u00e9ration n&rsquo;est apparue productrice de tant d&rsquo;interpr\u00e9tations diff\u00e9rentes<\/strong>. On notera que chacune a <strong>son charme, sa coh\u00e9rence, voire sa s\u00e9duction<\/strong>, et toutes sont avanc\u00e9es <strong>d&rsquo;une plume autoritaire et selon les meilleures sources<\/strong>. La question se pose si, finalement, ceux qui l&rsquo;ont lanc\u00e9e savent exactement pourquoi ils l&rsquo;ont lanc\u00e9e, s&rsquo;il n&rsquo;y a pas diff\u00e9rentes intentions et versions chez les lanceurs, et si m\u00eame, finalement et pour faire brutalement bref, &ndash; si quelqu&rsquo;un, quelque autorit\u00e9 est capable de dire pr\u00e9cis\u00e9ment qui a con\u00e7u cette op\u00e9ration, et comment, et pourquoi, <strong>et bla-bla-bla<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Ainsi r\u00e8gnent les temps de <em>post<\/em>-V\u00e9rit\u00e9&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 7 avril 2017 \u00e0 17H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;attaque la plus post-V\u00e9rit\u00e9 de tous les temps ? Comme nous avons l&rsquo;habitude de ne jamais le cacher, il nous para&icirc;t aujourd&rsquo;hui impossible de faire un commentaire direct sur les intentions, les calculs et les manipulations qui sont d\u00e9velopp\u00e9es dans nombre, sinon dans la plupart des \u00e9v\u00e9nements crisiques auxquels nous assistons. C&rsquo;est donc logiquement le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12929,2870,5518,3903,12933,12925,12927,2631,11462,12934,12932,3203,12935,12936,3957,2970,12928,12930,12931],"class_list":["post-77186","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-12929","tag-attaque","tag-base","tag-chimique","tag-cocu","tag-croisiere","tag-dune","tag-de","tag-debkafiles","tag-degats","tag-diverses","tag-hollande","tag-i","tag-insignifiants","tag-missile","tag-missiles","tag-syriennes","tag-tomahawk","tag-versions"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77186"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77186\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}