{"id":77203,"date":"2017-04-15T14:13:41","date_gmt":"2017-04-15T14:13:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/15\/psychologie-de-trump-20-post-trahison-1\/"},"modified":"2017-04-15T14:13:41","modified_gmt":"2017-04-15T14:13:41","slug":"psychologie-de-trump-20-post-trahison-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/15\/psychologie-de-trump-20-post-trahison-1\/","title":{"rendered":"Psychologie de Trump 2.0, <em>post<\/em>-trahison"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Psychologie de Trump 2.0, <em>post<\/em>-trahison<\/h2>\n<\/p>\n<p><p>15 avril 2017 &ndash; Nous allons commencer ce <em>F&#038;C<\/em> en nous r\u00e9f\u00e9rant \u00e0 trois de nos textes qui, \u00e0 la fois, r\u00e9sument l&rsquo;\u00e9v\u00e9nement <strong>extraordinairement brutal et massif<\/strong> qui s&rsquo;est produit la semaine derni\u00e8re et permettent d&rsquo;introduire aussit\u00f4t des notions compl\u00e8tement nouvelles, concernant le pr\u00e9sident des USA, Donald J. Trump. (Notez le ton solennel que nous employons inhabituellement pour le personnage : c&rsquo;est une fa\u00e7on pour nous, par antith\u00e8se orwellienne retourn\u00e9e contre les habitudes du Syst\u00e8me, de mettre en \u00e9vidence combien l&rsquo;imposture est parfaitement r\u00e9alis\u00e9e, mais au vu et au su de tous : <em>The-Donald<\/em> est devenu le pr\u00e9sident Donald J. Trump.) Quoi qu&rsquo;il en soit, nous ne devons pas perdre de vue que notre d\u00e9marche est d&rsquo;abord et essentiellement psychologique, mais avec les le\u00e7ons \u00e0 en tirer ; et il s&rsquo;agit de la psychologie d&rsquo;un seul homme, du susdit pr\u00e9sident des USA.<\/p>\n<\/p>\n<p><p>Dans notre pr\u00e9sentation hebdomadaire qui donne en fin de semaine, en t\u00eate de la page d&rsquo;accueil, un r\u00e9sum\u00e9 succinct des \u00e9v\u00e9nements trait\u00e9s durant la semaine qui se termine, et qui cette fois se concentre sur un seul \u00e9v\u00e9nement, nous \u00e9crivons ceci qui pr\u00e9tend r\u00e9sumer comment nous sommes pass\u00e9s \u00e0 une vitesse stup\u00e9fiante, dans des conditions rocambolesques, <strong>d&rsquo;un monde dans un autre monde avec une seule personne<\/strong> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Cette semaine a vu un basculement extraordinaire, insens\u00e9 et inimaginable, qui n&rsquo;est possible que <strong>parce que nous nous sommes dans cette \u00e9poque \u00e9trange et insaisissable, et qu&rsquo;elle nous donne, pour le meilleur et pour le pire, des personnages aussi \u00e9tranges et insaisissables que The-Donald Trump<\/strong>. Il est donc question de Trump, passant durant cette semaine, comme sans aucune transition, avec la brutalit\u00e9 d&rsquo;une explosion (\u00e9ventuellement nucl\u00e9aire, sp\u00e9cialit\u00e9 US), du \u00ab\u00a0meilleur\u00a0\u00bb au \u00ab\u00a0pire\u00a0\u00bb. &bull; M\u00eame si les deux mots, \u00ab\u00a0meilleur\u00a0\u00bb et \u00ab\u00a0pire\u00a0\u00bb, m\u00e9ritent des guillemets parce que nous ne sommes pas au bout de nos surprises, <strong>ils caract\u00e9risent n\u00e9anmoins la vigueur, la brutalit\u00e9, le caract\u00e8re inattendu et ultra-rapide, du changement de politique de Trump avec l&rsquo;ordre d&rsquo;attaquer une base syrienne suite \u00e0 une attaque chimique dont personne ne pouvait rien dire des auteurs<\/strong>, sinon qu&rsquo;il \u00e9tait compl\u00e8tement illogique d&rsquo;accuser aussit\u00f4t Assad parce qu&rsquo;une telle d\u00e9cision serait de son point de vue compl\u00e8tement absurde. (Mais bien s&ucirc;r, l&rsquo;absurde est notre quotidien, par les temps qui vont.) C&rsquo;est autour de ce changement brutal, <strong>sorte de d\u00e9cision catastrophique \u00e0 l&rsquo;\u00e9tat pur, sans la moindre r\u00e9flexion, sans aucune perspective<\/strong>, que s&rsquo;articulent les textes de cette semaine<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans un second texte, publi\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article\/de-la-telerealite-a-la-trahison-et-retour\">12 avril 2017<\/a> (<em>Journal-dde.crisis<\/em>), PhG donnant une appr\u00e9ciation effectivement psychologique du personnage, sans surprise comme \u00e9tant tr\u00e8s postmoderne, et appartenant <strong>au monde de l&rsquo;<em>entertainment<\/em> et de la t\u00e9l\u00e9r\u00e9alit\u00e9<\/strong> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Cet \u00ab\u00a0affectivisme mou\u00a0\u00bb, cette sensibilit\u00e9 \u00e9motionnelle incontr\u00f4l\u00e9e, me conduisent pour mon compte <strong>\u00e0 d\u00e9crire, en la personne de Trump, un personnage typique de l&rsquo;entertainment, de la communication-fun, de la t\u00e9l\u00e9r\u00e9alit\u00e9<\/strong>. C&rsquo;est ce personnage dont Michael Moore nous disait, et j&rsquo;avoue que j&rsquo;aurais plus que jamais tendance \u00e0 le croire comme on le comprendrait ais\u00e9ment, qu&rsquo;il s&rsquo;\u00e9tait engag\u00e9 dans cette course \u00e0 la pr\u00e9sidence <strong>d&rsquo;abord pour une querelle <a href=\"http:\/\/www.dedefensa.org\/article\/trump-aux-origines\">\u00e0 propos d&rsquo;une \u00e9mission de t\u00e9l\u00e9vision<\/a> qu&rsquo;il produisait<\/strong>, pour s&rsquo;apercevoir <a href=\"http:\/\/www.dedefensa.org\/article\/une-election-entre-survie-et-cocktail-molotov\">\u00e0 sa grande surprise<\/a> qu&rsquo;il enflammait le pays. Ce d\u00e9tail de \u00ab\u00a0Trump \u00e0 l&rsquo;origine\u00a0\u00bb nous ram\u00e8ne \u00e0 la t\u00e9l\u00e9r\u00e9alit\u00e9, et \u00e0 Trump comme \u00e9tant une cr\u00e9ature puissante et admirable du monde de la t\u00e9l\u00e9r\u00e9alit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans un autre texte du <a href=\"http:\/\/www.dedefensa.org\/article\/superman-en-syrie-tres-tres-tres-prudent\">13 avril 2017<\/a>, nous en venons sans explication pr\u00e9alable ni m\u00eame de pr\u00e9sentation, disons avec tout le naturel du monde, <strong>\u00e0 une appr\u00e9ciation compl\u00e8tement symbolique de l&rsquo;\u00e9v\u00e9nement avec le moyen de formules s&rsquo;inspirant des pratiques informatiques et de la dialectique postmodernes<\/strong>, pour indiquer de quelle sorte d&rsquo;\u00e9v\u00e9nement il est question, mais aussi de ce que nous pensons implicitement du personnage principal (le pr\u00e9sident Donald J. Trump). Bien entendu, il n&rsquo;est pas question une seconde de r\u00e9pudier l&rsquo;\u00e9pisode pr\u00e9c\u00e9dent (Trump-1.0), y compris les jugements que nous portions avec tant d&rsquo;autres. Il est question de comprendre comment nous sommes pass\u00e9s de ceci \u00e0 cela, et selon notre conviction intuitive selon laquelle la psychologie de Trump a jou\u00e9 un r\u00f4le fondamental :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; &#8230; <em>le nouveau sheriff, Trump-2.0 \u00ab\u00a0post-trahison\u00a0\u00bb<\/em> [&#8230;] &#8230;<strong><em>l&rsquo;irruption de Trump 2.0 (le Trump d&rsquo;apr\u00e8s la \u00ab\u00a0trahison de Trump\u00a0\u00bb, dit post-trahison)<\/em>&#8230; &raquo;<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette d\u00e9signation de Trump 2.0 signifie qu&rsquo;il y a eu auparavant, pour la s\u00e9quence qui nous importe, un Trump 1.0, c&rsquo;est-\u00e0-dire un changement complet de personnage. (Nous parlons de psychologie, de sa faiblesse et de sa vuln\u00e9rabilit\u00e9, avec les effets sur le caract\u00e8re. Nous ne disons en aucun cas que Trump est un imb\u00e9cile ou qu&rsquo;il est un homme intelligent, qu&rsquo;il est retors ou na\u00eff, etc. Nous parlons de la psychologie, donc de ses capacit\u00e9s de perception des r\u00e9alit\u00e9s, de perception intuitive, par cons\u00e9quent de la capacit\u00e9 de d\u00e9terminer des <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>.) L&#8217;emploi des intitul\u00e9s de code du monde postmoderne et monde informatis\u00e9 (\u00ab\u00a01.0\u00a0\u00bb et \u00ab\u00a02.0\u00a0\u00bb) indique la valeur du \u00ab\u00a0changement complet\u00a0\u00bb de la psychologie du personnage : <strong>quantativement massive, \u00e9norme, qualitativement d\u00e9risoire et vide de substance<\/strong>&#8230; Nous sommes bien dans <em>l&rsquo;\u00e8re de la quantit\u00e9<\/em>, c&rsquo;est-\u00e0-dire cette p\u00e9riode de compl\u00e8te d\u00e9cadence et du vide complet de l&rsquo;esprit, &ndash; pour faire bref mais d\u00e9cisif, <strong>l&rsquo;\u00e8re de la Chute pr\u00e9cipit\u00e9e dans l&rsquo;aire de toute chute<\/strong>.<\/p>\n<\/p>\n<p><p>Divers signes, anecdotes, d\u00e9clarations, montrent bien que <strong>l&rsquo;\u00e8re de Trump 2.0 est marqu\u00e9e par un ridicule objectif<\/strong>, c&rsquo;est-\u00e0-dire d&rsquo;une part un ridicule qui appara&icirc;t \u00e9vident aux nouveaux adversaires de Trump (ses partisans de l&rsquo;\u00e9poque Trump 1.0) qui se sont tout de suite regroup\u00e9s, avec une rapidit\u00e9 et finalement une absence de cas de conscience \u00e9vidents, en une masse compacte d&rsquo;opposants absolument d\u00e9termin\u00e9s ; mais aussi d&rsquo;autre part un ridicule qui affecte ses nouveaux partisans, c&rsquo;est-\u00e0-dire tout le grouillement-Syst\u00e8me, des limaces de la presseSyst\u00e8me aux rhizomes-Syst\u00e8me de l&rsquo;<em>establishment<\/em>. (On sait que le rhizome est un des personnages favoris du d\u00e9constructeur-d\u00e9structurateur Gilles Deleuze pour repr\u00e9senter un des outils favoris de la nouvelle r\u00e9alit\u00e9 de la postmodernit\u00e9, molle et gluante et donc n\u00e9cessairement glissant hors de la forme structur\u00e9e de la r\u00e9alit\u00e9 ; disons la r\u00e9alit\u00e9 hors-la-r\u00e9alit\u00e9.)<\/p>\n<\/p>\n<p><p>On notera trois \u00e9v\u00e9nements de ces tout derniers jours, particuli\u00e8rement repr\u00e9sentatifs et symboliques \u00e0 la fois du Trump 2.0 devenu diplomate-Syst\u00e8me et chef-de-guerre-Syst\u00e8me. (Il ne cesse d&rsquo;accumuler \u00e0 une vitesse \u00e9galement stup\u00e9fiante <a href=\"http:\/\/www.zerohedge.com\/news\/2017-04-12\/trump-flips-five-core-key-campaign-promises-under-24-hours\">les d\u00e9cisions et prises de position<\/a> qui pulv\u00e9risent Trump 1.0 au profit de Trump 2.0.)<\/p>\n<\/p>\n<p><p>&bull; Son renversement d&rsquo;opinion sur l&rsquo;OTAN, \u00e0 l&rsquo;occasion de la visite du secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN Soltenberg, personnalit\u00e9 d&rsquo;une transparence apaisante et qui avait \u00e9t\u00e9 terroris\u00e9 par l&rsquo;\u00e9lection de Trump. Soltenberg \u00e9tait convoqu\u00e9 \u00e0 Washington D.C. pour une r\u00e9union qui mettrait les choses ont point. Cela fut fait. Le pr\u00e9sident <a href=\"http:\/\/www.zerohedge.com\/news\/2017-04-12\/trump-reverses-nato-its-no-longer-obsolete\">fit ces interventions<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Finally, Trump said NATO is \u00ab\u00a0no longer <\/em>obsolete\u00a0\u00bb<em> during a Wednesday press conference with NATO Secretary General Jens Stoltenberg, backtracking on his past criticism of the alliance. During the campaign, he frequently called the organization \u00ab\u00a0obsolete,\u00a0\u00bb saying did little to crack down on terrorism and that its other members don&rsquo;t pay their \u00ab\u00a0fair share.\u00a0\u00bb \u00ab\u00a0<strong>I said it was obsolete. It is no longer obsolete<\/strong>,&quot; the president said Wednesday<\/em>. &raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Face \u00e0 Trump, Soltenberg est-il une limace ou un rhizome ? Dans tous les cas s&rsquo;il l&rsquo;est, c&rsquo;est d&rsquo;une mine imp\u00e9n\u00e9trable, en bon Norv\u00e9gien qui prof\u00e8re les mensonges-<em>narrative<\/em> les plus invraisemblables avec l&rsquo;impassibilit\u00e9 glac\u00e9e d&rsquo;une nuit d&rsquo;hiver sans fin au Cap Nord, lorsqu&rsquo;il dit que le pr\u00e9sident Trump a constamment montr\u00e9 \u00ab\u00a0un soutien consistant\u00a0\u00bb \u00e0 l&rsquo;OTAN, ce qui est tout de m\u00eame y aller un peu fort lorsque l&rsquo;autre dit, \u00e0 c\u00f4t\u00e9, \u00ab\u00a0je disais que l&rsquo;OTAN \u00e9tait tout \u00e0 fait d\u00e9pass\u00e9e. Elle n&rsquo;est plus du tout d\u00e9pass\u00e9e\u00a0\u00bb. On se demande lequel des deux surpasse l&rsquo;autre en fait de <em>narrative-fantasy<\/em>, ce qui conduit <em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-04-13\/wtf-headline-day-nato-general-says-trump-has-been-very-consistent-nato-support\">ZeroHedge.com<\/a><\/em> \u00e0 faire un commentaire vraiment tr\u00e8s amer :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Sometimes you have to wonder just what the hell planet the world&rsquo;s elites live on. <\/em><em>Despite the black versus white nature of President Trump&rsquo;s \u00ab\u00a0obsolete\u00a0\u00bb statements on NATO, the alliance&rsquo;s <strong>Secretary-General stated today that the U.S. leader has always been &quot;very consistent&quot; in his support<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le deuxi\u00e8me \u00e9v\u00e9nement illustratif du Trump 2.0 devenu diplomate-Syst\u00e8me date de la rencontre, du d&icirc;ner plus exactement, entre 2.0 lui-m\u00eame et son invit\u00e9, le pr\u00e9sident chinois Xi, durant les premi\u00e8res heures de la soir\u00e9e tandis qu&rsquo;au m\u00eame moment, mais en fin de nuit le 6 avril, en Syrie, l&rsquo;US Navy tirait ses merveilleux <em>Tomahawk <\/em>dans une profusion d&rsquo;explosion de d\u00e9part dans le style-feu d&rsquo;artifice qui a laiss\u00e9 pantois d&rsquo;admiration plus d&rsquo;un commentateur TV. (Celui de la MSNBC, cha&icirc;ne progressiste-soci\u00e9tale comme l&rsquo;on sait, r\u00e9p\u00e9tant sur un ton extatique devant les images des tirs de <em>Tomahawk, <\/em>\u00ab\u00a0<em>wonderful, wonderful<\/em>\u00ab\u00a0, ou bien est-ce \u00ab\u00a0<em>magnificent, magnificent<\/em>\u00ab\u00a0&#8230; Des esth\u00e8tes, enfin.)<\/p>\n<\/p>\n<p><p>Ainsi, Trump 2.0 annon\u00e7a-t-il \u00e0 son invit\u00e9, \u00e0 la fin du d&icirc;ner, qu&rsquo;on allait manger un \u00ab\u00a0merveilleux g\u00e2teau au chocolat\u00a0\u00bb, puis, sans transition, que de \u00ab\u00a0merveilleux missiles\u00a0\u00bb (am\u00e9ricanistes) venaient d&rsquo;accomplir leurs missions, avec 100% de coups au but assur\u00e9, \u00ab\u00a0c&rsquo;est brillant, c&rsquo;est g\u00e9nial, personne au monde ne peut se comparer \u00e0 nous en mati\u00e8re de technologie\u00a0\u00bb ; puis tout de m\u00eame, pour info, ceci tel que lui-m\u00eame (Trump 2.0) rapporta l&rsquo;anecdote lors d&rsquo;une interview \u00e0 <em>Fox.News<\/em> : \u00ab\u00a0Oui, comme je le disais, nous venions juste de tirer 59 missiles, qui se dirigeaient vers l&rsquo;Irak\u00a0\u00bb ; puis la pr\u00e9sentatrice TV qui recueillait ses pr\u00e9cisions rectifiant avec une voix incertaine, \u00ab\u00a0se dirigeant vers la Syrie ?\u00a0\u00bb, et 2.0, \u00e0 voix haute sinon tonitruante \u00ab\u00a0Ah oui, se dirigeant vers la Syrie\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>En effet, tout cela n&rsquo;est pas du domaine du potin puisque <strong>c&rsquo;est Trump 2.0 lui-m\u00eame, presque triomphant<\/strong>, qui a rapport\u00e9 ce m\u00eame <a href=\"https:\/\/www.rt.com\/usa\/384610-trump-syria-iraq-missile\/\">\u00ab\u00a0tout cela\u00a0\u00bb en d\u00e9tails<\/a>, pas m\u00e9content de lui ni du g\u00e2teau de chocolat, ni de la Syrie confondue avec l&rsquo;Irak, lors d&rsquo;une interview sur <em>Fox.News<\/em> :  <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>US President Donald Trump revealed he informed Chinese Premier Xi Jinping about the US air strike on a Syrian military base as the pair ate &quot;the most beautiful&quot; chocolate cake. <\/em><em>He then mixed up Syria and Iraq &ndash; and the internet had a meltdown.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Trump was speaking with Fox Business about the bizarre exchange with Chinese leader during a summit at his Mar-a-Lago estate. \u00ab\u00a0We had finished dinner, we&rsquo;re now having dessert,\u00a0\u00bb Trump began. \u00ab\u00a0And we had the most beautiful piece of chocolate cake that you&rsquo;ve ever seen and President Xi was enjoying it.\u00a0\u00bb \u00ab\u00a0We&rsquo;ve just fired 59 missiles, all of which hit by the way, unbelievable, from hundreds of miles away, it&rsquo;s brilliant, it&rsquo;s genius, what we have in terms of technology no-one can come close to competing,\u00a0\u00bb he continued.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0So I said, we&rsquo;ve just launched 59 missiles, heading to Iraq,\u00a0\u00bb said the President, seemingly oblivious to his mistake. \u00ab\u00a0Heading to Syria,\u00a0\u00bb host Maria Bartiromo interjected. \u00ab\u00a0Yes,\u00a0\u00bb Trump replied, \u00ab\u00a0heading toward Syria<\/em>.\u00a0\u00bb &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le troisi\u00e8me \u00e9v\u00e9nement (en attendant d&rsquo;autres de cette sorte) est ce point de la jubilation extr\u00eame, absolument emport\u00e9e, du pr\u00e9sident Trump 2.0, coinc\u00e9 entre deux superbes officiers pleins d&rsquo;\u00e9toiles (Africains-Am\u00e9ricains de surcro&icirc;t), et parlant avec enthousiasme \u00e0 propos de la bombe monstrueuse lanc\u00e9e par les USA en Afghanistan, &ndash; bombe de 8 tonnes fabriqu\u00e9e par la CIA pour $160 millions, le plus gros explosif en-dessous de l&rsquo;arme nucl\u00e9aire utilis\u00e9 effectivement d&rsquo;une fa\u00e7on op\u00e9rationnelle, &ndash; dont l&rsquo;ancien pr\u00e9sident afghan Karza\u00ef, ex-\u00ab\u00a0marionnette\u00a0\u00bb mais \u00ab\u00a0marionnette\u00a0\u00bb r\u00e9volt\u00e9 des USA, a tweet\u00e9 : &laquo; <em>Ce n&rsquo;est pas une guerre contre la terreur mais la plus inhumaine et brutale utilisation de notre pays pour tester de nouveaux et tr\u00e8s dangereux syst\u00e8mes d&rsquo;armes<\/em> &raquo; ; vieille habitude de la toujours jeune barbarie moderne des USA, une sp\u00e9cialit\u00e9 (la barbarie moderne) de la Grande R\u00e9publique, qui a non seulement beaucoup d&rsquo;armements mais qui adore les exp\u00e9rimenter pour \u00ab\u00a0de vrai\u00a0\u00bb et en faire la plus grande publicit\u00e9 possible.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit que d&rsquo;anecdotes, certes, ou d&rsquo;une phrase vol\u00e9 ici ou l\u00e0, mais toutes portant sur des sujets d&rsquo;importance et prononc\u00e9es lors d&rsquo;entretiens officiels. <strong>Ce qui est remarquable, c&rsquo;est la l\u00e9g\u00e8ret\u00e9 ou la pompe emphatique avec laquelle Trump 2.0 traite ces questions, sans craindre un instant de les rendre publiques, voire de s&rsquo;en glorifier<\/strong>. Les contradictions prennent le m\u00eame chemin : elles sont simplement exp\u00e9di\u00e9es selon l&rsquo;\u00e9vidence que les choses changent, m\u00eame si le constat ne craint pas l&rsquo;absurdit\u00e9 : \u00ab\u00a0J&rsquo;ai dit que l&rsquo;OTAN \u00e9tait obsol\u00e8te. D\u00e9sormais, elle n&rsquo;est plus obsol\u00e8te.\u00a0\u00bb Il ne dit pas \u00ab\u00a0je me suis tromp\u00e9\u00a0\u00bb dans la premi\u00e8re proposition, mais semble simplement confirmer que c&rsquo;\u00e9tait le cas, que l&rsquo;OTAN \u00e9tait bien obsol\u00e8te ; aujourd&rsquo;hui, ce n&rsquo;est plus le cas, elle n&rsquo;est plus obsol\u00e8te&#8230; L&rsquo;OTAN \u00e9volue contre le temps et \u00e0 l&rsquo;inverse du temps : hier, elle \u00e9tait vieille et d\u00e9pass\u00e9e, aujourd&rsquo;hui, trois mois plus tard, sans aucune intervention notable, elle est jeune, pimpante et particuli\u00e8rement adapt\u00e9e aux n\u00e9cessit\u00e9s du temps.<\/p>\n<\/p>\n<p><p>Trump 2.0 est <strong>non seulement <em>post<\/em>-V\u00e9rit\u00e9, il est au-del\u00e0 de toute r\u00e9f\u00e9rence \u00e0 la V\u00e9rit\u00e9. Trump 2.0 s&rsquo;occupe de l&rsquo;affaire, il est V\u00e9rit\u00e9 lui-m\u00eame<\/strong>&#8230; Le moins qu&rsquo;on puisse dire est que la transmutation de Trump 1.0 en Trump 2.0 s&rsquo;effectue sans le moindre embarras, \u00e0 toute vapeur et m\u00eame avec exub\u00e9rance : il s&rsquo;agit bien <a href=\"http:\/\/www.dedefensa.org\/article\/de-la-telerealite-a-la-trahison-et-retour\">de t\u00e9l\u00e9r\u00e9alit\u00e9<\/a>.<\/p>\n<\/p>\n<p><p>Pourtant, il n&rsquo;est pas assur\u00e9 que cela convienne parfaitement \u00e0 la machination elle-m\u00eame terriblement de type-t\u00e9l\u00e9r\u00e9alit\u00e9 qui a pr\u00e9sid\u00e9 \u00e0 cette maturation ultra-rapide. Le probl\u00e8me est qu&rsquo;il y a la psychologie de la bestiole qui joue son r\u00f4le.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Pourquoi 1.0 est-il devenu 2.0 ?<\/h3>\n<\/p>\n<p><p>Il y a quelque chose d&rsquo;\u00e9tourdissant dans le revirement de Trump ; \u00e0 la fois enlev\u00e9, presque roboratif, presque naturel \u00e0 force d&rsquo;impudence, presqu&rsquo;innocent \u00e0 force de naturel. Pas un instant de g\u00eane, pas une h\u00e9sitation, toujours le m\u00eame enthousiasme, les deux pouces lev\u00e9s, hilare en un sens, comme s&rsquo;il nous adressait un clin d&rsquo;&oelig;il : \u00ab\u00a0hein, je vous l&rsquo;avais dit que ma pr\u00e9sidence serait exceptionnelle, voyez comme je tiens mes promesses !\u00a0\u00bb Nous croyons, comme nous l&rsquo;avons bien fait comprendre dans ce qui pr\u00e9c\u00e8de, <strong>que le poids et surtout la forme de la psychologie de cet homme conv\u00e9nient qui est aussi un homme-t\u00e9l\u00e9r\u00e9alit\u00e9 ont jou\u00e9 un r\u00f4le consid\u00e9rable dans le poids et la forme cet \u00e9v\u00e9nement<\/strong>.<\/p>\n<\/p>\n<p><p>Nous partons de l&rsquo;hypoth\u00e8se que les derniers \u00e9v\u00e9nements nous permettent de poser. Nous admettons sans aucun doute que des \u00ab\u00a0forces obscures\u00a0\u00bb ont exerc\u00e9 des pressions consid\u00e9rables sur lui. (En l&rsquo;occurrence ce terme nous para&icirc;trait pr\u00e9f\u00e9rable par sa g\u00e9n\u00e9ralit\u00e9 extr\u00eamement signifiante parce que contenant autant une dimension complotiste justifi\u00e9e <strong>qu&rsquo;une dimension pseudo-\u00e9sot\u00e9rique sinon magique, et certainement mal\u00e9fique sinon diabolique<\/strong>, plut\u00f4t que la prolif\u00e9ration de <em>Deep State<\/em>, <em>neocons<\/em>, complexe militaro-industriel, <em>National Security State<\/em>, <em>establishment<\/em>, etc. Les \u00ab\u00a0forces obscures\u00a0\u00bb peuvent ais\u00e9ment \u00eatre identifi\u00e9es op\u00e9rationnellement par le terme \u00ab\u00a0globalistes\u00a0\u00bb.) Nous ajoutons qu&rsquo;\u00e0 l&rsquo;origine, et de toutes les fa\u00e7ons par sa psychologie m\u00eame d&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9, Trump <strong>n&rsquo;a pas une structure mentale<\/strong> qui lui permet d&rsquo;avoir une opinion \u00e9labor\u00e9e, ni m\u00eame une passion profonde qui animerait chez lui, comme chez nombre de globalistes des \u00ab\u00a0forces obscures\u00a0\u00bb un sentiment tr\u00e8s fort quasiment de type-religieux et les jugements qui vont avec, <strong>se traduisant parce qu&rsquo;il s&rsquo;agit d&rsquo;une passion par l&rsquo;hyst\u00e9rie instructur\u00e9e, et donc par une hyst\u00e9rie n\u00e9cessairement nihiliste<\/strong>.<\/p>\n<\/p>\n<p><p>Cet homme sans structure mentale \u00e9labor\u00e9e et tourn\u00e9 vers la t\u00e9l\u00e9r\u00e9alit\u00e9 est sensible \u00e0 l&rsquo;apparence de la communication, au bruit et \u00e0 l&rsquo;\u00e9clat spectaculaire de l&rsquo;apparence, au clinquant qui va avec, bref avec tout cet aspect de la postmodernit\u00e9 qui se satisfait du tumulte du <em><a href=\"http:\/\/www.dedefensa.org\/article\/du-big-now-a-lleternel-present\">Big Now<\/a><\/em>. Pour cette raison, nous acceptions volontiers et acceptons plus que jamais l&rsquo;explication du \u00ab\u00a0Trump \u00e0 l&rsquo;origine\u00a0\u00bb de la campagne USA-2016 que nous confia Michael Moore en ao&ucirc;t 2016. On rappelle ici un rapide r\u00e9sum\u00e9 de la chose donn\u00e9e dans le <em>Journal-dde.crisis<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article\/de-la-telerealite-a-la-trahison-et-retour\">12 avril 2017<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>C&rsquo;est ce personnage dont Michael Moore nous disait, et j&rsquo;avoue que j&rsquo;aurais plus que jamais tendance \u00e0 le croire comme on le comprendrait ais\u00e9ment, qu&rsquo;il s&rsquo;\u00e9tait engag\u00e9 dans cette course \u00e0 la pr\u00e9sidence <strong>d&rsquo;abord pour une querelle <a href=\"http:\/\/www.dedefensa.org\/article\/trump-aux-origines\">\u00e0 propos d&rsquo;une \u00e9mission de t\u00e9l\u00e9vision<\/a> qu&rsquo;il produisait<\/strong>, pour s&rsquo;apercevoir <a href=\"http:\/\/www.dedefensa.org\/article\/une-election-entre-survie-et-cocktail-molotov\">\u00e0 sa grande surprise<\/a> qu&rsquo;il enflammait le pays. Ce d\u00e9tail de \u00ab\u00a0Trump \u00e0 l&rsquo;origine\u00a0\u00bb nous ram\u00e8ne \u00e0 la t\u00e9l\u00e9r\u00e9alit\u00e9, et \u00e0 Trump comme \u00e9tant une cr\u00e9ature puissante et admirable du monde de la t\u00e9l\u00e9r\u00e9alit\u00e9. Je trouve que ce rappel, et de la personnalit\u00e9 de Trump qui vient \u00e0 l&rsquo;esprit \u00e0 cette lumi\u00e8re, correspondent assez bien au comportement g\u00e9n\u00e9ral de Trump. <strong>Ce n&rsquo;est pas qu&rsquo;il n&rsquo;est pas s\u00e9rieux, qu&rsquo;ils ne prennent pas au s\u00e9rieux les affaires du monde (voyez l&rsquo;\u00e9motion), c&rsquo;est bien qu&rsquo;il est d&rsquo;un autre monde<\/strong><\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;orientation populiste qu&rsquo;il prit d\u00e8s l&rsquo;origine \u00e9tait un choix assez naturel, sinon \u00e9vident, pour un homme-t\u00e9l\u00e9r\u00e9alit\u00e9 qui n&rsquo;a d&rsquo;ailleurs au d\u00e9part aucune id\u00e9e concevable de parvenir \u00e0 la pr\u00e9sidence. Il s&rsquo;assurait ainsi l&rsquo;originalit\u00e9 d&rsquo;une position d&rsquo;une part, un tr\u00e8s-possible succ\u00e8s de foule d&rsquo;autre part du fait de l&rsquo;\u00e9norme m\u00e9contentement populaire de la crise am\u00e9ricaniste. <strong>Effectivement, le succ\u00e8s vint, inesp\u00e9r\u00e9 et bient\u00f4t irr\u00e9sistible, qui se traduisait par un soutien populaire sans pr\u00e9c\u00e9dent, ce qui se traduisait \u00e0 son tour par un spectacle t\u00e9l\u00e9visuel exceptionnel<\/strong>. Trump 01 fut port\u00e9 par les foules et il ne cessa de manifester une exceptionnelle capacit\u00e9 \u00e0 l&rsquo;amplifier, r\u00e9pondant ainsi \u00e0 son go&ucirc;t irr\u00e9sistible pour le spectacle, avec lui au centre, sa personnalit\u00e9 n\u00e9cessairement narcissique trouvant un aliment d&rsquo;une joie et d&rsquo;un plaisir sans pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><p>Durant cette s\u00e9quence, <strong>Trump 1.0 sonnait exceptionnellement juste parce qu&rsquo;il rencontrait une v\u00e9rit\u00e9-de-situation \u00e9norme, qui \u00e9tait le m\u00e9contentement formidable de la foule<\/strong>. L&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9 adoub\u00e9 par la v\u00e9rit\u00e9-de-situation, quelle formule plus superbe et plus enthousiasmante pour lui ? Il fut dans ce cas excellent, sans faux-pas, avec une audace incroyable, et bien entendu une \u00ab\u00a0politique\u00a0\u00bb naturellement, fortement antiSyst\u00e8me. Bien entendu, il y avait un quiproquo mais qui s&rsquo;en souciait alors ? Comme l&rsquo;avait vu justement Michael Moore \u00e0 nouveau, Trump 1.0 \u00e9tait <a href=\"http:\/\/www.dedefensa.org\/article\/une-election-entre-survie-et-cocktail-molotov\">un \u00ab\u00a0cocktail Molotov\u00a0\u00bb<\/a> que ces foules enthousiastes entendaient lancer \u00e0 la figure de Washington D.C. Il \u00e9tait \u00ab\u00a0agi\u00a0\u00bb, manipul\u00e9 par les foules et non le contraire, et l&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9 s&rsquo;en arrangeait parfaitement parce qu&rsquo;il avait le bruit, les applaudissements, les tr\u00e9pignements, les cris d&rsquo;enthousiasme pour lui, et encore plus <a href=\"http:\/\/www.dedefensa.org\/article\/le-4eme-pouvoir-de-lex-4eme-pouvoir\">en <em>prime time <\/em>au-del\u00e0<\/a> de tout ce qu&rsquo;il pouvait esp\u00e9rer du c\u00f4t\u00e9 des cha&icirc;nes TV.<\/p>\n<\/p>\n<p><p>Ainsi fut-il \u00e9lu&#8230; <strong>D\u00e8s lors, les choses chang\u00e8rent puisque le public disparut<\/strong>. L&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9 se trouva brutalement confront\u00e9 \u00e0 cette guerre de tranch\u00e9e qu&rsquo;il avait affront\u00e9 multipli\u00e9e par dix, dans une occurrence o&ugrave; il n&rsquo;avait plus avec lui la chose puissante et enivrante qui soutenait son \u00e9lan et sa verve incroyable, &ndash; ces foules venues par vagues pour l&rsquo;applaudir. <strong>C&rsquo;est bien l\u00e0 qu&rsquo;il apparut qu&rsquo;il s&rsquo;agissait d&rsquo;un homme-t\u00e9l\u00e9r\u00e9alit\u00e9 et nullement d&rsquo;un homme d&rsquo;&Eacute;tat<\/strong>. Trump se trouva pris dans un tourbillon de pressions et d&rsquo;obligations, avec la t\u00e2che infiniment d\u00e9licate de composer un cabinet, accabl\u00e9 par les intrigues de son pr\u00e9d\u00e9cesseur, l&rsquo;encore-pr\u00e9sident Obama, de la CIA, des d\u00e9mocrates hyst\u00e9riques et d\u00e9cha&icirc;n\u00e9s, bref de tous ces d\u00e9bris divers du <em>Deep State<\/em> et avec la presseSyst\u00e8me \u00e0 un niveau paroxystique de la perfidie du <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> comme on ne vit jamais l&rsquo;\u00e9quivalent.<\/p>\n<\/p>\n<p><p><strong>S&rsquo;il avait \u00e9t\u00e9 un homme d&rsquo;&Eacute;tat<\/strong>, il se serait battu avec les moyens nouveaux que lui donnait cette fonction si puissante de pr\u00e9sident, organisant un cabinet de guerre d&rsquo;hommes et de femmes pr\u00eats \u00e0 \u00ab\u00a0&lsquo;mourir pour lui\u00a0\u00bb comme le lui recommandait Patrick Buchanan, organisant d\u00e9j\u00e0 sa politique r\u00e9volutionnaire avec une petite \u00e9quipe resserr\u00e9e autour de lui, <a href=\"http:\/\/www.dedefensa.org\/article\/le-binome-trump-flynn-1\">\u00e0-la-Nixon<\/a>. <strong>Ce n&rsquo;\u00e9tait pas le cas<\/strong>. Son chant du cygne se fit entre le discours d&rsquo;investiture, magnifique pi\u00e8ce de d\u00e9fi lanc\u00e9 au Syst\u00e8me, r\u00e9dig\u00e9 par Bannon qui avan\u00e7ait d\u00e9j\u00e0 d&rsquo;un pas leste du Capitole vers la Roche Tarp\u00e9ienne, et le lancement de son programme d&rsquo;une mani\u00e8re acc\u00e9l\u00e9r\u00e9 dans les premiers jours, sans m\u00e9thode, sans tactique, encore moins sans la moindre vision strat\u00e9gique&#8230; Le 13 f\u00e9vrier, il acceptait la d\u00e9mission du G\u00e9n\u00e9ral Flynn, et tout \u00e9tait consomm\u00e9 : <strong>Trump 1.0 entrait dans un processus d&rsquo;agonie pour rena&icirc;tre de ses cendres sous l&rsquo;identit\u00e9 Trump 2.0, ph\u00e9nix postmoderne, le 6 avril au son des <em>Tomahawk<\/em> qui, d\u00e9sormais, remplaceraient les tweets de 1.0<\/strong>.<\/p>\n<\/p>\n<p><p>(Flynn \u00e9tait un homme divers. S&rsquo;il avait une attitude remarquablement antiSyst\u00e8me pour la Syrie et les relations avec la Russie, sa position vis-\u00e0-vis de l&rsquo;Iran \u00e9tait par contre bien peu du go&ucirc;t d&rsquo;un antiSyst\u00e8me. Qu&rsquo;importe, c&rsquo;\u00e9tait un des hommes de base de l&rsquo;\u00e9quipe Trump 1.0, avec Trump d\u00e8s les premiers jours des primaires. Il fut l&rsquo;objet d&rsquo;une campagne de diffamation odieuse, mont\u00e9e par certains \u00e9l\u00e9ments de l&rsquo;IC [<em>Intelligence Community<\/em>] en complicit\u00e9 directe avec les \u00e9l\u00e9ments les plus pourris de la presseSyst\u00e8me [Washington <em>Post<\/em>\/WaPo] plus quelques sous-marins infiltr\u00e9s dans la nouvelle administration. Trump, s&rsquo;il avait \u00e9t\u00e9 encore 1.0, <strong>aurait refus\u00e9 sa d\u00e9mission, lui aurait renouvel\u00e9 sa confiance, aurait ordonn\u00e9 une enqu\u00eate dans les diverses agences de IC et demand\u00e9 sous forme d&rsquo;ultimatum aux membres de son cabinet qui venaient d&rsquo;\u00eatre nomm\u00e9s de soutenir Flynn ou de se d\u00e9mettre<\/strong>.)<\/p>\n<\/p>\n<p><p>Le basculement de Trump 1.0 en Trump 2.0 s&rsquo;est fait dans un bonheur parfait retrouv\u00e9 par l&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9. Priv\u00e9 d&rsquo;applaudissements et d&rsquo;enthousiasme depuis le 8 novembre 2016, il perdait tout int\u00e9r\u00eat pour sa situation en m\u00eame temps qu&rsquo;il perdait pied. Le 6 avril, par le coup de baguette magique des <em>Tomahawk<\/em>, il retrouve un public, une claque, les <em>prime time<\/em>, la pompe majestueuse de la fonction comme un vrai meneur de jeu dans une tr\u00e8s-grande \u00e9mission de t\u00e9l\u00e9r\u00e9alit\u00e9. Qu&rsquo;importe qu&rsquo;il s&rsquo;agisse de l&rsquo;<em>establishment<\/em>, de la presseSyst\u00e8me qui fait briller ses pompes comme jamais \u00e0 force de l\u00e9chage, du<em> Deep State<\/em> &#038; Cie. \u00ab\u00a0Trahison\u00a0\u00bb ? Bof&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Dans ce cas, la \u00ab\u00a0trahison\u00a0\u00bb n&rsquo;en est pas une, parce que c&rsquo;est un \u00e9v\u00e9nement, ou un choix, de la sorte qui n&rsquo;a pas cours dans le monde de la t\u00e9l\u00e9r\u00e9alit\u00e9 ; on n&rsquo;y conna&icirc;t rien de cette sorte justement, ni l&rsquo;honneur, ni l&rsquo;infamie, ni la parole donn\u00e9e, ni la trahison par cons\u00e9quent, <strong>mais simplement les agitations de l&rsquo;\u00e9motion et les attitudes individualistes, et puis bien s&ucirc;r les obligations de l&rsquo;apparence du sc\u00e9nario d&rsquo;une part, les n\u00e9cessit\u00e9s de l&rsquo;audience et du prime time d&rsquo;autre part<\/strong><\/em><strong>. &raquo;<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais l&rsquo;histoire ne s&rsquo;arr\u00eate pas l\u00e0, tant s&rsquo;en faut. Les \u00ab\u00a0forces obscures\u00a0\u00bb sont-elles satisfaites ? Elles ne sont pas sorties de l&rsquo;auberge&#8230; L&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9 devenu Trump 2.0 est un personnage exigeant, surtout d\u00e9sormais, alors qu&rsquo;il est adoub\u00e9 aux plus hautes destin\u00e9es, comme la jument de Caligula. <strong>A nouveau plong\u00e9 dans la t\u00e9l\u00e9r\u00e9alit\u00e9, il entend maximaliser le spectacle dont il est l&rsquo;ordonnateur<\/strong>. D\u00e9sormais, il ne s&rsquo;agit plus des foules de <em>Deplorable<\/em> et de pauvres gens aux abois, mais de <em>Tomahawk<\/em> frappant Assad sous la ceinture et de groupes de porte-avions cinglant vers la Cor\u00e9e du Nord, &ndash; et pour lui, c&rsquo;est toujours du spectacle. Comme on l&rsquo;a vu plus haut avec quelques exemples, il se fiche bien de ce qu&rsquo;il dit, de la fa\u00e7on dont il se contredit, du sourire crisp\u00e9 de Xi et des fus\u00e9es du dingue nord-cor\u00e9en point\u00e9es sur S\u00e9oul, du moment que le spectacle continue, et comment ! <em>The <\/em>t\u00e9l\u00e9r\u00e9alit\u00e9<em> Must Go On<\/em>.<\/p>\n<\/p>\n<p><p>Les \u00ab\u00a0forces obscures\u00a0\u00bb ont voulu que cet homme, Trump 1.0, se remette selon la ligne du Parti ? Trump 2.0 va mener le Parti \u00e0 un train d&rsquo;enfer, partant dans toutes les directions, prenant tous les risques, surtout les plus visibles, c&rsquo;est-\u00e0-dire exposant les arm\u00e9es \u00e9puis\u00e9es de la grande R\u00e9publique \u00e0 des aventures extraordinairement incertaines. Trump 1.0 a \u00e9t\u00e9 liquid\u00e9, mais Trump 2.0, qui semblerait leur prisonnier, est en r\u00e9alit\u00e9 un homme-t\u00e9l\u00e9r\u00e9alit\u00e9 sans conscience des risques qui pourrait bien les tenir prisonni\u00e8res, ces \u00ab\u00a0forces obscures\u00a0\u00bb, de ses foucades impr\u00e9visibles puisque, en derni\u00e8re minute, c&rsquo;est lui qui d\u00e9cide si l&rsquo;on tape (<em>to strike<\/em>) ou si l&rsquo;on ne tape pas&#8230; Konstantin Kosachev, pr\u00e9sident de la commission des affaires \u00e9trang\u00e8res de la chambre haute de la <em>Douma <\/em>dit \u00e0 propos des intentions US vis-\u00e0-vis de la Cor\u00e9e du Nord :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>La chose la plus alarmante \u00e0 propos de l&rsquo;actuelle administration US, c&rsquo;est que vous ne pouvez savoir si elle bluffe ou bien si elle est r\u00e9ellement en train de mettre ses menaces \u00e0 ex\u00e9cution&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p><strong>Nous sommes \u00e0 peu pr\u00e8s s&ucirc;r que plus d&rsquo;un g\u00e9n\u00e9ral, plus d&rsquo;un ministre, plus d&rsquo;un homme responsable \u00e0 Washington D.C., &ndash; il y en a tout de m\u00eame, &ndash; pense \u00e0 peu pr\u00e8s la m\u00eame chose, avec juste une nuance <\/strong>(\u00ab\u00a0La chose la plus alarmante \u00e0 propos de Trump, c&rsquo;est que vous ne pouvez pas savoir, m\u00eame si vous \u00eates un de ses ministres, s&rsquo;il bluffe ou bien s&rsquo;il est r\u00e9ellement en train de mettre ses menaces \u00e0 ex\u00e9cution&#8230;\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>Il y a deux mois, on avait appris, &ndash; petit bruit de couloir, &ndash; que les deux ministres anciens chefs du Corps des Marines, Mattis \u00e0 la d\u00e9fense et Kelly \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure, s&rsquo;\u00e9taient mis d&rsquo;accord pour coordonner leurs agendas, de fa\u00e7on \u00e0 ce qu&rsquo;en aucun cas les deux soient simultan\u00e9ment absents de Washington (mission, voyage, etc.). On avait pens\u00e9 que c&rsquo;\u00e9tait pour mettre des b\u00e2tons dans les roues de Trump 1.0 mis sous surveillance ; <strong>cela pourrait bien \u00eatre d\u00e9sormais pour tenter d&#8217;emp\u00eacher, &ndash; et le verbe \u00ab\u00a0tenter\u00a0\u00bb est de rigueur puisqu&rsquo;il s&rsquo;agit du pr\u00e9sident, &ndash; Trump 2.0 d&rsquo;aller trop loin jusqu&rsquo;\u00e0 une b\u00eatise strat\u00e9gique irr\u00e9parable d\u00e9bouchant sur un conflit catastrophique<\/strong>. Si Trump 1.0 semblait une catastrophe pour les \u00ab\u00a0forces obscures\u00a0\u00bb, il n&rsquo;est pas dit que Trump 2.0 ne se r\u00e9v\u00e8le pas comme une effroyable bombe \u00e0 retardement qui joue tellement le spectacle de la t\u00e9l\u00e9r\u00e9alit\u00e9 qu&rsquo;il en devient impossible d&rsquo;attraper la m\u00e8che pour l&rsquo;\u00e9teindre.<\/p>\n<\/p>\n<p><p>Deux choses doivent \u00eatre encore dite, \u00e0 notre sens, pour conclure cette revue de d\u00e9tails tr\u00e8s psychologique, essentiellement psychologique ; cela, dans une \u00e9poque domin\u00e9e par la communication et par cons\u00e9quent o&ugrave; le facteur psychologique et la perception qui vont avec comptent \u00e9norm\u00e9ment :<\/p>\n<\/p>\n<p><p>&bull; La premi\u00e8re concerne l&rsquo;observation que Trump 1.0 faisait infiniment \u00ab\u00a0plus vrai\u00a0\u00bb que Trump 2.0. Il repr\u00e9sentait vraiment une option, &ndash; r\u00e9volutionnaire et antiSyst\u00e8me, &ndash; qui soulevait, ou qui \u00e9tait soulev\u00e9e par un \u00e9lan populaire exceptionnel. Cet \u00e9lan n&rsquo;est d&rsquo;ailleurs nullement tari (aux USA comme ailleurs, cela va de soi), et se trouve simplement dans le cas de trouver une autre fa\u00e7on de s&rsquo;exprimer, \u00e9ventuellement Trump lui-m\u00eame, si jamais le 2.0 revenait faire une incursion vers le 1.0. Au contraire, dans sa fonction 2.0, Trump ne repr\u00e9sente plus rien que le nihilisme de la grande politique interpr\u00e9t\u00e9e par le spectacle et en arrive \u00e0 mettre son \u00ab\u00a0nouveau camp\u00a0\u00bb, les \u00ab\u00a0forces obscures\u00a0\u00bb qui l&rsquo;ont r\u00e9cup\u00e9r\u00e9, dans une position aussi malais\u00e9e que celle que ces m\u00eames forces occupaient lorsqu&rsquo;il \u00e9tait 1.0. <strong>C&rsquo;est l\u00e0, pour nous, un signe de la l\u00e9gitimit\u00e9 de l&rsquo;antiSyst\u00e8me : m\u00eame l&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9, ou homme-spectacle, est plus l\u00e9gitime lorsqu&rsquo;il interpr\u00e8te une partition antiSyst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>&bull; La seconde concerne la situation cr\u00e9\u00e9e, ou dans tous les cas telle que nous la voyons en train de se cr\u00e9er avec Trump 1.0 devenu Trump 2.0 ; c&rsquo;est-\u00e0-dire, la puissance US, \u00e9norme, massive, \u00e9rod\u00e9e et us\u00e9e, arrogante et stupide, lente et \u00e9puis\u00e9e, pr\u00e9tendant \u00e0 l&#8217;empire du monde avec des moyens de plus en plus illusoires, conduite par une sorte de \u00ab\u00a0capitaine-fou\u00a0\u00bb, &ndash; fou du point de vue politique et strat\u00e9gique mais tout \u00e0 fait \u00ab\u00a0normal\u00a0\u00bb du point de vue du spectacle et de la communication&#8230; <strong>En un sens, on comprend que les USA se trouvent devant un risque consid\u00e9rable d&rsquo;une aventure militaire risqu\u00e9e<\/strong>, comme celui que nous citons souvent de la possibilit\u00e9 \u00e9galement d&rsquo;un conflit avec l&rsquo;Iran, &ndash; comme nous le rappelions encore le <a href=\"http:\/\/www.dedefensa.org\/article\/liran-de-tous-les-dangers-suite\">31 mars 2017<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>\u00ab\u00a0La perspective appara&icirc;t alors, du point de vue de la communication, extr\u00eamement importante et s\u00e9rieuse, et elle rejoint une possibilit\u00e9 qu&rsquo;avait \u00e9voqu\u00e9e un n\u00e9o-s\u00e9cessionniste du Maine, <a href=\"http:\/\/www.dedefensa.org\/article\/voici-les-neo-secessionnistes\">Thomas Naylor, en 2010<\/a>, \u00e0 propos de la crise iranienne : &lsquo;Il y a trois ou quatre sc\u00e9narios possibles de l&rsquo;effondrement de l&#8217;empire <\/em><em>[les USA]. Une possibilit\u00e9 est une guerre avec l&rsquo;Iran&rsquo;&hellip;\u00a0\u00bb Apr\u00e8s tout, certes, ce serait une bonne mani\u00e8re de r\u00e9gler la \u00ab\u00a0guerre civile\u00a0\u00bb qui fait rage \u00e0 Washington D.C<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Certes, Trump 2.0 fait courir un danger consid\u00e9rable, non seulement aux USA mais au monde lui-m\u00eame. <strong>Simplement, a-t-on jamais pu imaginer une seule seconde que l&rsquo;on pourrait arr\u00eater sinon d\u00e9truire ce Syst\u00e8me, c&rsquo;est-\u00e0-dire d&rsquo;abord les USA, sans courir un risque \u00e0 la hauteur de cette t\u00e2che terrifiante et pourtant n\u00e9cessaire puisque l&rsquo;alternative est la destruction du monde par le Syst\u00e8me ?<\/strong> De ce point de vue, Trump 2.0 est le bienvenu, lui qui peut mettre le feu aux poudres, jusqu&rsquo;\u00e0 entra&icirc;ner les USA dans une aventure autodestructrice m\u00eame sans l&rsquo;hypoth\u00e8se apocalyptique du nucl\u00e9aire, dont les effets pourraient se faire sentir quasi-imm\u00e9diatement sur l&rsquo;\u00e9quilibre du pouvoir \u00e0 Washington D.C. Ce pouvoir aux mains de Trump 2.0, &ndash; m\u00eame s&rsquo;il est \u00ab\u00a0doubl\u00e9\u00a0\u00bb par d&rsquo;autres, notamment les militaires de son cabinet, il garde l&rsquo;exercice ultime du pouvoir, &ndash; c&rsquo;est le signe le plus convaincant que Trump n&rsquo;a pas \u00e9t\u00e9 inutile, d&rsquo;abord en l\u00e9gitimant la tendance antiSyst\u00e8me, ensuite, en trahissant et en devenant 2.0, c&rsquo;est-\u00e0-dire en introduisant la folie de l&rsquo;homme-t\u00e9l\u00e9r\u00e9alit\u00e9 au c&oelig;ur et au sommet de ce pouvoir.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Psychologie de Trump 2.0, post-trahison 15 avril 2017 &ndash; Nous allons commencer ce F&#038;C en nous r\u00e9f\u00e9rant \u00e0 trois de nos textes qui, \u00e0 la fois, r\u00e9sument l&rsquo;\u00e9v\u00e9nement extraordinairement brutal et massif qui s&rsquo;est produit la semaine derni\u00e8re et permettent d&rsquo;introduire aussit\u00f4t des notions compl\u00e8tement nouvelles, concernant le pr\u00e9sident des USA, Donald J. Trump. (Notez&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[12948,2831,3299,2651,3460,12949,2773,915,9542,3349,12950,3867,12930,2842,2639,12501,12538],"class_list":["post-77203","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-1-0","tag-2-0","tag-coree","tag-du","tag-forces","tag-homme-telerealite","tag-iran","tag-moore","tag-neo-secessionniste","tag-nord","tag-obscures","tag-syrie","tag-tomahawk","tag-trahison","tag-trump","tag-tweets","tag-usa-2016"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77203"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77203\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}