{"id":77216,"date":"2017-04-22T11:23:11","date_gmt":"2017-04-22T11:23:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/22\/humeur-de-crise-35\/"},"modified":"2017-04-22T11:23:11","modified_gmt":"2017-04-22T11:23:11","slug":"humeur-de-crise-35","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/22\/humeur-de-crise-35\/","title":{"rendered":"Humeur de crise-35"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Humeur de crise-35<\/h2>\n<\/p>\n<p><p>22 avril 2017 &ndash; La France vaut-elle une crise, c&rsquo;est-\u00e0-dire pour ce <em>Journal-dde.crisis<\/em> une \u00ab\u00a0humeur de crise\u00a0\u00bb ? Le seul fait de poser une telle question montre justement dans <strong>quel \u00e9tat de d\u00e9vastation, et donc \u00e9tat crisique bien entendu, se trouve la France <\/strong>: qu&rsquo;il soit concevable qu&rsquo;une r\u00e9flexion s&rsquo;impose pour d\u00e9terminer si la France est en elle-m\u00eame assez importante pour encore pr\u00e9tendre que sa crise \u00e9vidente puisse pr\u00e9tendre elle-m\u00eame \u00eatre reflet, miroir et symbole \u00e0 la fois de la crise du monde&#8230; Car, \u00e9videmment, s&rsquo;interroger pour savoir si \u00ab\u00a0la France vaut bien une crise\u00a0\u00bb, c&rsquo;est s&rsquo;interroger pour savoir si la France est encore assez signifiante pour que la crise o&ugrave; elle se trouve \u00e9videmment, &ndash; r\u00e9ponse de forme \u00e0 la question, &ndash; <strong>ait une dimension d&rsquo;universalit\u00e9 dans la lutte du Syst\u00e8me contre l&rsquo;antiSyst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>Il se trouve que la r\u00e9ponse tend \u00e0 \u00eatre positive. On le voit, on le sent, \u00e0 l&rsquo;int\u00e9r\u00eat peu ordinaire qui est port\u00e9 \u00e0 la France pour ce premier tour, y compris et surtout dans la presse anglo-saxonne, et particuli\u00e8rement la presse antiSyst\u00e8me anglophone, des USA et des sites anglophones \u00ab\u00a0internationalistes\u00a0\u00bb, de cette sorte d'\u00a0\u00bb\u00e9lite\u00a0\u00bb antiSyst\u00e8me qui a fleuri ces quatre-cinq derni\u00e8res ann\u00e9es. (<em>TheDuran.com<\/em>, <em>Russia Insider<\/em>, <em>ZeroHedge.com<\/em>, jusqu&rsquo;aux plus exotiques comme <em>Infowars.com<\/em>). Les \u00e9lections fran\u00e7aises et les \u00e9v\u00e9nements fran\u00e7ais y sont suivis avec un r\u00e9el int\u00e9r\u00eat, et la sensation <strong>qu&rsquo;ils comptent sans le moindre doute pour l&rsquo;\u00e9volution de l&rsquo;antiSyst\u00e8me<\/strong>. De ce point de vue, il semble que la France puisse envisager <strong>d&rsquo;\u00e0 nouveau \u00ab\u00a0tenir son rang\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>Je ne dirais pas une seconde quels sont mes sentiments ni m\u00eame mes pr\u00e9f\u00e9rences sur le r\u00e9sultat du scrutin, ni sur l&rsquo;\u00e9volution apr\u00e8s le scrutin selon son issue. Je n&rsquo;en ai <strong>aucun de v\u00e9ritablement structur\u00e9<\/strong>, fid\u00e8le \u00e0 mon habitude de ne rien pr\u00e9tendre pr\u00e9voir de formel dans les \u00e9v\u00e9nements qui ont d\u00e9sormais l&rsquo;habitude d&rsquo;agir d&rsquo;eux-m\u00eames, et encore moins dans les cons\u00e9quences des tendances et des dynamiques. Tout juste ai-je un espoir : c&rsquo;est que la France, qui fut admirable dans l&rsquo;Histoire pour sa capacit\u00e9 ontologique et souveraine \u00e0 subir et \u00e0 repousser toutes les tensions sans conna&icirc;tre de crise structurelle \u00e0 cet \u00e9gard, donc en \u00e9vitant le d\u00e9sordre pour sa propre structure, <strong>que la France, enfin, entre dans le d\u00e9sordre r\u00e9g\u00e9n\u00e9rateur, celui-l\u00e0 qui ne peut \u00eatre que r\u00e9g\u00e9n\u00e9rateur pour elle<\/strong>. J&rsquo;aimerais qu&rsquo;elle cesse de s&rsquo;abriter derri\u00e8re une direction prodigieusement inculte, grossi\u00e8re et imposteuse, qui elle-m\u00eame se donnait \u00e0 bon compte une esp\u00e8ce de vertu \u00e0 l&rsquo;ombre salvatrice de ses \u00ab\u00a0institutions\u00a0\u00bb ; <strong>que la pute subventionn\u00e9e qui lui servait de direction ne puisse plus se maquiller en marquise<\/strong> pour nous faire croire que l&rsquo;Elys\u00e9e est devenu autre chose que le bordel de ses incons\u00e9quences et de ses incoh\u00e9rences.<\/p>\n<\/p>\n<p><p>Bien entendu, on l&rsquo;a compris, ce d\u00e9sordre ne signifie pas n\u00e9cessairement insurrection, \u00e9lection folle, trouble des foules et des rues, &ndash; bien que cela puisse aider, je le reconnais. Le d\u00e9sordre-en-France, d&rsquo;abord, c&rsquo;est la continuation de l&rsquo;esp\u00e8ce de vertige piqu\u00e9 de panique, d&rsquo;incertitude et d&rsquo;angoisse de ceux qui ont l&rsquo;habitude de susciter panique, incertitude et angoisse chez leurs administr\u00e9s. <strong>Cette psychologie radicale est apparue durant la campagne<\/strong>, et il faut que cela se poursuive : une France en d\u00e9sordre aujourd&rsquo;hui, c&rsquo;est <strong>une France qui d\u00e9couvre enfin l&rsquo;antiSyst\u00e8me<\/strong>&#8230; <strong>Que le d\u00e9sordre soit<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Humeur de crise-35 22 avril 2017 &ndash; La France vaut-elle une crise, c&rsquo;est-\u00e0-dire pour ce Journal-dde.crisis une \u00ab\u00a0humeur de crise\u00a0\u00bb ? Le seul fait de poser une telle question montre justement dans quel \u00e9tat de d\u00e9vastation, et donc \u00e9tat crisique bien entendu, se trouve la France : qu&rsquo;il soit concevable qu&rsquo;une r\u00e9flexion s&rsquo;impose pour d\u00e9terminer&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[4646,3228,3356,12964,4141,2687,12860,7394,2891],"class_list":["post-77216","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-antisysteme","tag-crise","tag-desordre","tag-direction-systeme","tag-elections","tag-france","tag-france-2017","tag-generale","tag-grande"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77216"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77216\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}