{"id":77220,"date":"2017-04-29T06:28:44","date_gmt":"2017-04-29T06:28:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/29\/jules-cesar-et-la-gaule-divisee-en-partis\/"},"modified":"2017-04-29T06:28:44","modified_gmt":"2017-04-29T06:28:44","slug":"jules-cesar-et-la-gaule-divisee-en-partis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/04\/29\/jules-cesar-et-la-gaule-divisee-en-partis\/","title":{"rendered":"Jules C\u00e9sar et la Gaule divis\u00e9e en partis"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Jules C\u00e9sar et la Gaule divis\u00e9e en partis<\/h2>\n<\/p>\n<p><p>Consolons-nous comme nous pouvons. La France n&rsquo;est pas pli\u00e9e en quatre, comme le voulait Coluche (c&rsquo;est d&rsquo;ailleurs Jacques Attali qui avait lu son \u00e9loge fun\u00e8bre), mais elle reste apr\u00e8s tout divis\u00e9e en deux ! Il y a une droite divis\u00e9e (Fillon-Marine) et une gauche divis\u00e9e (Macron-M\u00e9lenchon), mais plus maligne. Or alors que certains nous parlent de Grand Remplacement, on d\u00e9montrera le contraire avec Jules C\u00e9sar, qui avait d\u00e9j\u00e0 dit d\u00e9crit le Clochemerle fran\u00e7ais.<\/p>\n<\/p>\n<p><p>Suivons Koj\u00e8ve et retournons au grec et au latin. Tout y \u00e9tait d\u00e9crit point par point, sauf la Cor\u00e9e du Nord (mais peut-\u00eatre qu&rsquo;en cherchant bien&hellip;).<\/p>\n<\/p>\n<p><p>Prenez donc le livre VI de la Guerre des Gaules, chapitres 11 et 12.<\/p>\n<\/p>\n<p><p>&laquo;  Au point o&ugrave; l&rsquo;on est arriv\u00e9, il n&rsquo;est pas sans doute hors de propos de parler des m&oelig;urs de la Gaule et de la Germanie, et de la diff\u00e9rence qui existe entre ces deux nations.<strong> Dans la Gaule, ce n&rsquo;est pas seulement dans chaque ville, dans chaque bourg et dans chaque campagne qu&rsquo;il existe des factions, mais aussi dans presque chaque famille<\/strong> : ces factions ont pour chefs ceux qu&rsquo;on estime et qu&rsquo;on juge les plus puissants ; c&rsquo;est \u00e0 leur volont\u00e9 et \u00e0 leur jugement que sont soumises la plupart des affaires et des r\u00e9solutions. &raquo;<\/p>\n<\/p>\n<p><p>Et C\u00e9sar d&rsquo;expliquer pourquoi avec commis\u00e9ration :<\/p>\n<\/p>\n<p><p>&laquo; <strong>La raison de cet antique usage para&icirc;t \u00eatre d&rsquo;assurer au peuple une protection contre les grands<\/strong> : car personne ne souffre que l&rsquo;on opprime ou circonvienne ses clients ; si l&rsquo;on agissait autrement, on perdrait bient\u00f4t tout son cr\u00e9dit. <strong>Ce m\u00eame principe r\u00e9git souverainement toute la Gaule : car toutes les cit\u00e9s sont divis\u00e9es en deux partis<\/strong> &raquo;<\/p>\n<\/p>\n<p><p>Le peuple gaulois veut de la s\u00e9curit\u00e9, de la nourriture, de la protection, donc le peuple devient esclave ; tout cela deux mille ans avant Tocqueville, qui ne se faisait gu\u00e8re d&rsquo;illusions sur la capacit\u00e9 des Fran\u00e7ais \u00e0 r\u00e9sister \u00e0 la mont\u00e9e en puissance de la modernit\u00e9 \u00e9tatique.<\/p>\n<\/p>\n<p><p>Mais restons-en \u00e0 nos divisions \u00e9voqu\u00e9es plus haut. Dans le latin de C\u00e9sar qu&rsquo;on a tous \u00e9tudi\u00e9 en troisi\u00e8me (essayez notre Tacite pour voir !), cela donne :<\/p>\n<\/p>\n<p><p>&laquo; Haec eadem ratio est in summa totius Galliae: namque omnes civitates in partes divisae sunt duas &raquo;.<\/p>\n<\/p>\n<p><p>Le grand homme poursuit avec humour :<\/p>\n<\/p>\n<p><p>&laquo; Lorsque C\u00e9sar vint dans la Gaule, les H\u00e9duens \u00e9taient les chefs d&rsquo;une de ces factions, les S\u00e9quanes, ceux de l&rsquo;autre. Cum Caesar in Galliam venit, alterius factionis principes erant Aedui, alterius Sequani. &raquo;<\/p>\n<\/p>\n<p><p>Et l\u00e0 cela devient carr\u00e9ment du Ast\u00e9rix :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;arriv\u00e9e de C\u00e9sar changea la face des choses :<strong> les H\u00e9duens reprirent leurs otages, recouvr\u00e8rent leurs anciens clients, en acquirent de nouveaux par le cr\u00e9dit de C\u00e9sar<\/strong>, parce qu&rsquo;on voyait que ceux qui entraient dans leur amiti\u00e9 jouissaient d&rsquo;une condition meilleure et d&rsquo;un gouvernement plus doux ; et ils obtinrent dans tout le reste un cr\u00e9dit et un pouvoir qui firent perdre aux S\u00e9quanes leur pr\u00e9pond\u00e9rance.  &Agrave; ceux-ci avaient succ\u00e9d\u00e9 les R\u00e8mes ;<strong> lorsqu&rsquo;on remarqua que leur faveur aupr\u00e8s de C\u00e9sar \u00e9galait celle des H\u00e9duens, ceux que d&rsquo;anciennes inimiti\u00e9s emp\u00eachaient de s&rsquo;unir \u00e0 ces derniers se ralliaient \u00e0 la client\u00e8le des R\u00e8mes, qui les prot\u00e9geaient avec z\u00e8le pour conserver le nouveau cr\u00e9dit qu&rsquo;ils avaient si rapidement acquis.<\/strong> Tel \u00e9tait alors l&rsquo;\u00e9tat des choses que les H\u00e9duens avaient, sans contredit, le premier rang parmi les Gaulois, et que les R\u00e8mes occupaient le second. &raquo;<\/p>\n<\/p>\n<p><p>Encore un peu de latin :<\/p>\n<\/p>\n<p><p>&laquo; Eo tum statu res erat, ut longe principes haberentur Aedui, secundum locum dignitatis Remi obtinerent. &raquo;<\/p>\n<\/p>\n<p><p>Les H\u00e9duens c&rsquo;est le PS alors, h\u00e9ritier du Mitterrand et de son virage imp\u00e9rial proam\u00e9ricain.<\/p>\n<\/p>\n<p><p>Concluons car c&rsquo;est lassant.<\/p>\n<\/p>\n<p><p>Comme disait Visconti dans le Gu\u00e9pard, il faut que tout change (m\u00eame la population, d&rsquo;ailleurs en Sicile&hellip;) pour que rien ne change : Et j&rsquo;ai d\u00e9j\u00e0 cit\u00e9 Aristote et sa Politique, sans oublier D\u00e9mosth\u00e8ne et sa R\u00e9forme, pour nous consoler des temps que nous vivons.<\/p>\n<\/p>\n<p><p><strong>N&rsquo;oubliez pas d&rsquo;aller p\u00eacher \u00e0 la ligne le jour des \u00e9lections<\/strong>. Car dans deux mille ans on en sera encore l\u00e0, entre R\u00e8mes et H\u00e9duens.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jules C\u00e9sar et la Gaule divis\u00e9e en partis Consolons-nous comme nous pouvons. La France n&rsquo;est pas pli\u00e9e en quatre, comme le voulait Coluche (c&rsquo;est d&rsquo;ailleurs Jacques Attali qui avait lu son \u00e9loge fun\u00e8bre), mais elle reste apr\u00e8s tout divis\u00e9e en deux ! Il y a une droite divis\u00e9e (Fillon-Marine) et une gauche divis\u00e9e (Macron-M\u00e9lenchon), mais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[12831,5581,4141,12860,12969,3340],"class_list":["post-77220","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-cesar","tag-division","tag-elections","tag-france-2017","tag-gaule","tag-presidentielles"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77220"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77220\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}