{"id":77234,"date":"2017-05-01T17:42:16","date_gmt":"2017-05-01T17:42:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/01\/ainsi-mccain-devint-il-temporairement-une-colombe\/"},"modified":"2017-05-01T17:42:16","modified_gmt":"2017-05-01T17:42:16","slug":"ainsi-mccain-devint-il-temporairement-une-colombe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/01\/ainsi-mccain-devint-il-temporairement-une-colombe\/","title":{"rendered":"Ainsi McCain devint-il (temporairement) une colombe"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Ainsi McCain devint-il (temporairement) une colombe<\/h2>\n<\/p>\n<p><p>Peut-on r\u00eaver abruti belliciste plus embl\u00e9matique, plus aveugle, plus catastrophique que lui ? Non, on ne peut pas r\u00eaver&#8230; Ainsi dirons-nous qu&rsquo;une fois de plus, la r\u00e9alit\u00e9 d\u00e9passe la fiction \u00e0 une vitesse inimaginable, et la distance en la ridiculisant d&rsquo;une mani\u00e8re qu&rsquo;il \u00e9tait impossible d&rsquo;imaginer. Car, ces derni\u00e8res soixante-douze heures, l&rsquo;on voit et entend le s\u00e9nateur de l&rsquo;Arizona, <em>neocon<\/em> brevet\u00e9-inoxydable, pompier pyromane partout o&ugrave; gronde l&rsquo;incendie, en Ukraine, en Syrie, au Yemen, en Afghanistan, partisan de tous les complots, de toutes les tentatives, de tous les projets de <em>strike-fiesta<\/em> depuis des ann\u00e9es (rappelez-vous son \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/mccain-bombin-usa-chanson-dapres-les-bomber-boys\">Bomb Bomb Bomb Iran<\/a><\/em>\u00ab\u00a0, sur un air des <em>Beach Boys<\/em>), car voici John McCain devenu soudain un homme de l&rsquo;apaisement, un v\u00e9ritable homme de paix cherchant par tous les moyens \u00e0 \u00e9viter l&rsquo;affrontement ; un de ces gens que les <em>neocons<\/em> nous ont habitu\u00e9s \u00e0 d\u00e9signer de \u00ab\u00a0Munichois\u00a0\u00bb en souvenir de Munich-1938 restant dans leur imagerie d&rsquo;Epinal comme la capitulation des d\u00e9mocraties face aux dictateur. <strong>John McCain est-il un \u00ab\u00a0Munichois\u00a0\u00bb et une colombe ? <em>Damned<\/em><\/strong>, les traditions se perdent.<\/p>\n<\/p>\n<p><p>&#8230; En attendant de trancher sur les causes de cet \u00e9trange volte-face par rapport \u00e0 son r\u00f4le de boutefeu, &ndash; ce \u00e0 quoi nous allons essayer de nous employer plus loin, &ndash;, McCain se d\u00e9pense terriblement. Son argument : un conflit avec la Cor\u00e9e du Nord serait terrible, <strong>il s&rsquo;agit d&rsquo;une crise des missiles de USA de 1962 qui se renouvelle mais en mouvement lent (\u00ab\u00a0<em>slow motion<\/em>\u00ab\u00a0). Il faut tout faire pour l&rsquo;\u00e9viter, et \u00ab\u00a0je crois que le pr\u00e9sident Trump est tr\u00e8s conscient de la dangerosit\u00e9 de la chose\u00a0\u00bb<\/strong> &#8230; Nous, nous dirions que cette derni\u00e8re phrase, qu&rsquo;il r\u00e9p\u00e8te, McCain, ressemble plus \u00e0 une incantation, \u00e0 une pri\u00e8re, qu&rsquo;\u00e0 une information dont il aurait connaissance et une certitude qu&rsquo;il aurait acquise. Voici quelques interventions successives de et concernant McCain.<\/p>\n<\/p>\n<p><p>&bull; Vendredi, <a href=\"http:\/\/time.com\/4759126\/john-mccain-north-korea-strike-option\/\">dans <em>Time<\/em><\/a>, une intervention de McCain via <em>Bloomberg.News <\/em>: &laquo; <em>Arizona Sen. John McCain said President Trump knows that launching a preemptive military strike against North Korea is a last resort.\u00a0\u00bbI hope there&rsquo;s a lot more to go before we have a preemptive strike,\u00a0\u00bb McCain said Thursday, <a href=\"https:\/\/www.bloomberg.com\/politics\/articles\/2017-04-27\/trump-knows-striking-north-korea-is-last-resort-mccain-says?cmpid=socialflow-twitter-business&#038;utm_content=business&#038;utm_campaign=socialflow-organic&#038;utm_source=twitter&#038;utm_medium=social\" target=\"_blank\">Bloomberg reports<\/a>. <\/em><em>\u00ab\u00a0They are exploring every option and the last option, and the least desirable option, is armed conflict.\u00a0\u00bb \u00ab\u00a0One of the major reasons is because of that artillery that&rsquo;s north of Seoul,&quot; McCain said, meaning that North Korean leader Kim Jong Un has weapons he could unleash on South Korea&rsquo;s capital. \u00ab\u00a0That is really of concern.\u00a0\u00bb<\/em>[&#8230;] \u00ab\u00a0The carnage would be horrendous.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; <em>Trump <\/em><em><a href=\"http:\/\/time.com\/4758883\/donald-trump-major-conflict-north-korea\/?iid=sr-link2\">told Reuters<\/a><\/em><em> Thursday, \u00ab\u00a0There is a chance that we could end up having a major, major conflict with North Korea.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Reprenant les m\u00eames d\u00e9clarations de McCain (d&rsquo;une interview \u00e0 CNN), <em>Politico.com<\/em> titre curieusement (le <a href=\"http:\/\/www.politico.com\/story\/2017\/04\/30\/mccain-north-korea-missiles-237803\">30 avril 2017<\/a>) : &laquo; <em>McCain on pre-emptive strike on North Korea: &lsquo;We have to consider that option&rsquo;<\/em> &raquo;, transformant les d\u00e9clarations du s\u00e9nateur de tonalit\u00e9 tr\u00e8s apaisante (&laquo; <em>I think that we have to consider that option as the very last option, and for a number of reasons <\/em>&raquo;) en une intervention belliciste avec cette option de l&rsquo;attaque pr\u00e9sent\u00e9e presque avec faveur, comme une possibilit\u00e9 qu&rsquo;il est n\u00e9cessaire de consid\u00e9rer en priorit\u00e9&#8230; Les habitudes commandent \u00e9videmment lorsqu&rsquo;on parle de McCain et que McCain parle : <strong>ce ne peut \u00eatre que dans le sens de l&rsquo;interventionnisme belliciste<\/strong>.<\/p>\n<\/p>\n<p><p>&bull;  Le <a href=\"http:\/\/www.independent.co.uk\/news\/world\/americas\/us-politics\/donald-trump-north-korea-nuclear-latest-war-a7711046.html\">1<sup>er<\/sup> mai 2017<\/a>, <em>The Independent<\/em> reprend une nouvelle d\u00e9claration de McCain en m\u00eame temps que Trump parlait de la crise sur CBS dimanche dans des termes ambigus et contrast\u00e9s ; McCain allant dans le m\u00eame sens de l&rsquo;apaisement, et mettant en \u00e9vidence les pertes terribles que causerait un conflit avec la Cor\u00e9e du Nord.<\/p>\n<\/p>\n<p><p>&laquo; <em>The stand-off between the US and North Korea could be \u00ab\u00a0like a Cuban missile crisis in slow motion\u00a0\u00bb according to Senator John McCain, with Donald Trump once again dancing around the subject of military action<\/em>&#8230; [&#8230;] <em>In a nod to the fluctuating rhetoric of the President and his team &ndash; which has moved from bombast to varying degrees of caution &ndash; Mr McCain told CNN that it might be better at times to \u00ab\u00a0watch what the President does, rather than what he says\u00a0\u00bb. <\/em><em>Although he agreed that China was the \u00ab\u00a0key\u00a0\u00bb to averting conflict. \u00ab\u00a0China can put the brakes on this\u00a0\u00bb, Mr McCain said, because he does \u00ab\u00a0not believe Kim Jong-un will do this by himself\u00a0\u00bb. Asked if he thought Mr Trump was preparing a pre-emptive strike on North Korea, Mr McCain said: \u00ab\u00a0I don&rsquo;t think so but, as somebody said, this could be a Cuban missile crisis in slow motion.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Enfin, il y a une interpr\u00e9tation des propos de McCain par Alexander Mercouris (sur <em>TheDuran.com<\/em>, le <a href=\"http:\/\/theduran.com\/mccain-us-attack-north-korea-horrendous\/\">1<sup>er<\/sup> mai 2017<\/a>), qui va dans le sens d&rsquo;un complet apaisement. Mercouris cr\u00e9dite McCain \u00e0 la fois d&rsquo;une retenue du jugement \u00e0 cause de son pass\u00e9 de combattant (pilote de l&rsquo;US Navy au Vietnam), \u00e0 la fois de ses contacts privil\u00e9gi\u00e9s avec les militaires du cabinet de Trump, notamment le directeur du NSC McMaster (surtout) et le ministre de la d\u00e9fense Mattis.<\/p>\n<\/p>\n<p><p>&laquo; <em>Senator McCain in contrast to other war-hawks like Senator Lindsey Graham &ndash; who has been saying that a war in the north east Pacific would not be so bad because it would not directly affect the US &ndash; or Governor John Kasich -who is calling for an <a href=\"https:\/\/theduran.com\/kasich-kill-kim-jong-un\/\" target=\"_blank\">assassination team to &lsquo;take out&rsquo;<\/a> Kim Jong-un and other members of the North Korean leadership &ndash; is a former active duty military officer who has actually served in combat during the war in Vietnam.  He also comes from a family with a long history of military service.  <\/em><em>He therefore presumably understands rather better the danger of some of the farfetched scenarios for military action than some of the people who are advocating them<\/em>.<\/p>\n<\/p>\n<p><p>&laquo; <em>If someone like Senator McCain thinks that military action against North Korea is a terrible idea and that the US should instead rely on diplomacy, then the risk of the US taking military action against North Korea must be very low<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The fact that Senator McCain also appears to be very close to President Trump&rsquo;s National Security Adviser General H.R. McMaster &ndash; who he continues to praise lavishly at every opportunity &ndash; suggests that what he says also reflects the thinking of President Trump&rsquo;s top national security and defence officials, including presumably General McMaster. That also suggests that the prospects of US military action against North Korea are actually very low<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; .<em> That of course makes the Trump&rsquo;s administration&rsquo;s various military moves of the last few weeks, such as the movements of the aircraft carrier Carl Vinson and of the cruise missile submarine USS Michigan, look even more like the empty bluff they obviously were<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Pour cette fois, nous diff\u00e9rons substantiellement de l&rsquo;appr\u00e9ciation de Mercouris. Nous ne voyons pas pourquoi, cette fois au contraire de tant d&rsquo;autres occasions o&ugrave; McCain recommanda et intrigua pour accentuer les risques de guerre et les conflits en cours, y compris avec d&rsquo;horribles pertes de civils, <strong>son exp\u00e9rience de pilote de combat au Vietnam pourrait servir de r\u00e9f\u00e9rence et d&rsquo;explication \u00e0 une sagesse pacificatrice qu&rsquo;on ne lui vit jamais auparavant<\/strong>. Par contre, il est vrai que McCain a des liens constants avec les militaires de l&rsquo;administration, notamment McMaster et Mattis.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il est vrai \u00e9galement, comme on ne cesse de le noter que Trump continue \u00e0 entretenir vis-\u00e0-vis du conflit nord-cor\u00e9en, comme vis-\u00e0-vis de nombre ce mati\u00e8res politiques, notamment de politique ext\u00e9rieure, <strong>une attitude \u00e0 la fois changeante et bombastique, c&rsquo;est-\u00e0-dire changeante d&rsquo;une mani\u00e8re extr\u00eamement visible sans en \u00eatre g\u00ean\u00e9 le moins du monde<\/strong> ; et cette remarque vaut pour Trump devenu Trump 2.0, c&rsquo;est-\u00e0-dire qu&rsquo;\u00e0 l&rsquo;int\u00e9rieur m\u00eame de ce r\u00f4le il va dans tous les sens&#8230; Justin Raimondo note justement (ce <a href=\"http:\/\/original.antiwar.com\/justin\/2017\/04\/30\/why-defend-south-korean-ingrates\/\">1<sup>er<\/sup> mai 2017<\/a>), employant cette m\u00eame terminologie (1.0 et 2.0) que nous avons inaugur\u00e9e pour notre part <a href=\"http:\/\/www.dedefensa.org\/article\/psychologie-de-trump-20-post-trahison-1\">le 15 avril 2017<\/a>, <strong>combien la question du caract\u00e8re et de son impr\u00e9visibilit\u00e9 joue un r\u00f4le essentiel dans le comportement du pr\u00e9sident<\/strong> (et Raimondo, loyal, reconnaissant combien lui-m\u00eame s&rsquo;\u00e9tait tromp\u00e9 \u00e0 cet \u00e9gard, ce qui est en bonne partie notre cas) :<\/p>\n<\/p>\n<p><p>&laquo; <em>When it came to foreign policy, Trump 1.0 was interesting albeit problematic: <strong>Trump 2.0 is menacingly unpredictable<\/strong>. Those of us who saw in him some hope that the \u00ab\u00a0America First\u00a0\u00bb agenda he gave voice to would be implemented, at least to some degree, neglected to take into consideration <strong>the vital question of character<\/strong>. I ignored the protestations of some of his critics, who said <strong>Trump was unstable, without core principles, and therefore perfectly capable of reversing himself in the name of making a supposedly smart deal<\/strong>. The first one-hundred days of his administration have proved them right<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A la lumi\u00e8re de ces divers constats, notre interpr\u00e9tation devient alors que l&rsquo;attitude inattendue de McCain, refl\u00e9tant en cela ce qu&rsquo;il sait par l&rsquo;interm\u00e9diaire de ses amis McMaster et Mattis, loin d&rsquo;\u00eatre la confirmation que les plans US vis-\u00e0-vis de la Cor\u00e9e du Nord sont verrouill\u00e9s dans l&rsquo;intention de ne pas provoquer une guerre, <strong>sont au contraire le signe d&rsquo;une crainte que l&rsquo;une ou l&rsquo;autre des sautes d&rsquo;humeur du pr\u00e9sident n&rsquo;aggrave brusquement la situation<\/strong>. Il faut rappeler que l&rsquo;affaire du <a href=\"http:\/\/www.dedefensa.org\/article\/le-uss-carl-vinson-est-tres-rocknroll\">USS <em>Carl Vinson<\/em><\/a> tra&icirc;nant des h\u00e9lices pour se diriger vers la Cor\u00e9e du Nord alors que la Maison-Blanche annon\u00e7ait qu&rsquo;il \u00e9tait \u00e0 pied d&rsquo;&oelig;uvre, \u00ab\u00a0sur zone\u00a0\u00bb comme l&rsquo;on dit, que Mercouris qualifie de bluff, \u00e9tait selon nous plut\u00f4t une confusion marqu\u00e9e de divers incidents entre les armes concern\u00e9es, la Maison-Blanche ne faisant que r\u00e9p\u00e9ter ce que le Pentagone lui disait, et le Pentagone lui disant une interpr\u00e9tation \u00e0 la fois confuse, \u00e9ventuellement tendancieuse, dans tous les cas ressortant plus d&rsquo;une inorganisation ou d&rsquo;une concurrence ridicule entre les armes que d&rsquo;un coup de bluff bien calcul\u00e9.<\/p>\n<\/p>\n<p><p>On peut donc avancer l&rsquo;hypoth\u00e8se que l&rsquo;intervention de McCain, si diff\u00e9rente de son comportement habituel, refl\u00e8te la pr\u00e9occupation de ses amis militaires, et de lui-m\u00eame par cons\u00e9quent, moins devant la politique conduite que devant les interf\u00e9rences impr\u00e9visibles du pr\u00e9sident. C&rsquo;est effectivement que les enjeux sont tr\u00e8s importants avec la Cor\u00e9e du Nord, et que <strong>le pr\u00e9sident, m\u00eame devenu 2.0, garde des pouvoirs d&rsquo;interf\u00e9rence extr\u00eamement puissants<\/strong>. Nous avons d\u00e9j\u00e0 plusieurs fois \u00e9crit que Trump 1.0 devenu Trump 2.0, s&rsquo;il \u00e9tait devenu prisonnier du <em>Deep State<\/em>, \u00e9tait un dr\u00f4le de prisonnier, qui pourrait se r\u00e9v\u00e9ler si impr\u00e9visible qu&rsquo;il retournerait finalement le r\u00f4le&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Trump 1.0 a \u00e9t\u00e9 liquid\u00e9, mais Trump 2.0, qui semblerait leur prisonnier, est en r\u00e9alit\u00e9 un homme-t\u00e9l\u00e9r\u00e9alit\u00e9 sans conscience des risques qui pourrait bien les tenir prisonni\u00e8res, ces \u00ab\u00a0forces obscures\u00a0\u00bb, de ses foucades impr\u00e9visibles puisque, en derni\u00e8re minute, c&rsquo;est lui qui d\u00e9cide si l&rsquo;on tape (to strike) ou si l&rsquo;on ne tape pas&#8230; Konstantin Kosachev, pr\u00e9sident de la commission des affaires \u00e9trang\u00e8res de la chambre haute de la Douma dit \u00e0 propos des intentions US vis-\u00e0-vis de la Cor\u00e9e du Nord : &laquo; La chose la plus alarmante \u00e0 propos de l&rsquo;actuelle administration US, c&rsquo;est que vous ne pouvez savoir si elle bluffe ou bien si elle est r\u00e9ellement en train de mettre ses menaces \u00e0 ex\u00e9cution&#8230; &raquo; <strong>Nous sommes \u00e0 peu pr\u00e8s s&ucirc;r que plus d&rsquo;un g\u00e9n\u00e9ral, plus d&rsquo;un ministre, plus d&rsquo;un homme responsable \u00e0 Washington D.C., &ndash; il y en a tout de m\u00eame, &ndash; pense \u00e0 peu pr\u00e8s la m\u00eame chose, avec juste une nuance <\/strong>(\u00ab\u00a0La chose la plus alarmante \u00e0 propos de Trump, c&rsquo;est que vous ne pouvez pas savoir, m\u00eame si vous \u00eates un de ses ministres, s&rsquo;il bluffe ou bien s&rsquo;il est r\u00e9ellement en train de mettre ses menaces \u00e0 ex\u00e9cution&#8230;\u00a0\u00bb)<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Saluons l&rsquo;exploit du bouffon-t\u00e9l\u00e9r\u00e9alit\u00e9 qui a chang\u00e9 de casquette (2.0 \u00e0 la place de 1.0) sans aucune difficult\u00e9 ni crise de conscience : il a r\u00e9ussi <strong>\u00e0 transformer McCain, au moins pour quelques jours, en une vertueuse colombe<\/strong> plaidant pour la retenue et la mesure dans la crise nord-cor\u00e9enne. La confusion et le d\u00e9sordre sont absolument et totalement, <strong>sinon totalitairement<\/strong>, le moteur universel et exclusif de la politique du monde ; et, bien entendu, l&rsquo;exceptionnelle \u00ab\u00a0hyperpuissance\u00a0\u00bb m\u00e8ne la charge.<\/p>\n<\/p>\n<p><p>Mis en ligne le 1<sup>er<\/sup> mai 2017 \u00e0 17H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainsi McCain devint-il (temporairement) une colombe Peut-on r\u00eaver abruti belliciste plus embl\u00e9matique, plus aveugle, plus catastrophique que lui ? Non, on ne peut pas r\u00eaver&#8230; Ainsi dirons-nous qu&rsquo;une fois de plus, la r\u00e9alit\u00e9 d\u00e9passe la fiction \u00e0 une vitesse inimaginable, et la distance en la ridiculisant d&rsquo;une mani\u00e8re qu&rsquo;il \u00e9tait impossible d&rsquo;imaginer. Car, ces derni\u00e8res&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12948,2831,3299,2651,4390,11900,12918,2667,3349,2639],"class_list":["post-77234","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-1-0","tag-2-0","tag-coree","tag-du","tag-et","tag-mattis","tag-mcmaster","tag-mercouris","tag-nord","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77234"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77234\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}