{"id":77243,"date":"2017-05-04T13:23:33","date_gmt":"2017-05-04T13:23:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/04\/rien-a-ecrire\/"},"modified":"2017-05-04T13:23:33","modified_gmt":"2017-05-04T13:23:33","slug":"rien-a-ecrire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/04\/rien-a-ecrire\/","title":{"rendered":"Rien \u00e0 \u00e9crire&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Rien \u00e0 \u00e9crire&#8230;<\/h2>\n<\/p>\n<p><p>04 mai 2017 &ndash; Cela m&rsquo;arrive rarement, tr\u00e8s rarement, et pourrait-on ajouter, encore plus rarement sinon jamais peut-\u00eatre apr\u00e8s un \u00e9v\u00e9nement de cette importance&#8230; Sauf qu&rsquo;il pourrait peut-\u00eatre me sembler, si j&rsquo;avais l&rsquo;esprit au sarcasme, qu&rsquo;il n&rsquo;eut gu\u00e8re d&rsquo;importance, cet \u00ab\u00a0\u00e9v\u00e9nement de cette importance\u00a0\u00bb, de m\u00eame que je me m\u00e9fie en g\u00e9n\u00e9ral des \u00ab\u00a0\u00e9v\u00e9nements de cette importance\u00a0\u00bb jusqu&rsquo;\u00e0 m&rsquo;interdire d&rsquo;en \u00e9crire l\u00e0-dessus aussi rapidement qu&rsquo;on le voudrait&#8230; Mais l\u00e0, c&rsquo;est tout diff\u00e9rent : je me suis retrouv\u00e9 plume s\u00e8che et esprit vide, sans vraiment de reproche \u00e0 faire \u00e0 quiconque, &ndash; sinon \u00e0 moi, peut-\u00eatre et encore vaguement, moi qui ai toujours une phrase \u00e0 \u00e9crire&#8230; <em>Tu quoque fili<\/em>, le vertige de la phrase blanche ?<\/p>\n<\/p>\n<p><p>D&rsquo;abord, je le confesse : je n&rsquo;ai pas vu grand&rsquo;chose de ce d\u00e9bat ; les quinze-vingt premi\u00e8res minutes, puis assez \u00e9difi\u00e9 sur le climat, le ton, l&rsquo;agressivit\u00e9 voire la sauvagerie. J&rsquo;ai d\u00e9cid\u00e9 alors de mener \u00e0 bien mon projet qui \u00e9tait de respecter mes horaires syndicaux malgr\u00e9 l&rsquo;\u00e9v\u00e9nement et d&rsquo;aller me coucher. Le lendemain, aujourd&rsquo;hui donc, quelques commentaires de-ci de-l\u00e0, des impressions entendues au vol, enfin rien qui puise modifier la pente suivie par mon jugement, et toujours cette absence d&rsquo;inspiration, un certain d\u00e9go&ucirc;t, ou disons un d\u00e9sint\u00e9r\u00eat pour faire moins dramatique, d&rsquo;\u00e9crire quoi que ce soit. Notez que cette attitude, comme influenc\u00e9e par le climat que j&rsquo;ai \u00e9voqu\u00e9, s&rsquo;est \u00e9tendue au reste des affaires du monde dans lesquelles je n&rsquo;ai trouv\u00e9 aucun int\u00e9r\u00eat \u00e9galement, rien pour \u00e9veiller le go&ucirc;t du commentaire, la flamme de la reconnaissance de quelque chose qui vaille un effort de l&rsquo;esprit et un \u00e9veil de l&rsquo;intuition superbe. Pourtant, je ne cesse de l&rsquo;\u00e9crire, nous sommes au c&oelig;ur d&rsquo;une crise g\u00e9n\u00e9rale, la fameuse Grande Crise G\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me&#8230; Eh bien, tout se passa durant ces quelques heures, comme si rien ne se passait.<\/p>\n<\/p>\n<p><p>Il y eut peut-\u00eatre une sorte d&rsquo;anesth\u00e9sie temporaire, ou disons d&rsquo;amn\u00e9sie momentan\u00e9e ? Je suis le premier \u00e0 le dire, aussit\u00f4t, et cela au contraire de mes habitudes o&ugrave; je ne crains pas de fixer mon parti : je ne fais porter la responsabilit\u00e9 de la chose \u00e0 aucun des deux d\u00e9bateurs. J&rsquo;ai ou\u00ef-dire que ce fut bien une bataille de rue, a <em>dogfight<\/em> comme disent les pilotes de combat, et pourtant s&rsquo;il y eut agressivit\u00e9 et sauvagerie comme cela se dit et comme j&rsquo;ai pu l&rsquo;entrevoir, je ne les en charge pas, aucun des deux, de la responsabilit\u00e9. Je crois que l&rsquo;on a connu un de ces instant o&ugrave;, soudain, le vide et le rien qui sont le seul enjeu de cette trajectoire effrayante que nous subissons, sont apparus, nus, tels qu&rsquo;en eux-m\u00eames.<\/p>\n<\/p>\n<p><p>&#8230; Restent alors, comme on se d\u00e9bat d\u00e9sesp\u00e9r\u00e9ment pour \u00e9viter la noyade, l&rsquo;agressivit\u00e9 et la sauvagerie du barbare, ou de l&rsquo;\u00eatre-ramen\u00e9-au-barbare. Ils n&rsquo;ont pas pu parler de leurs programmes, ou bien ils n&rsquo;ont pas voulu, ou bien ils n&rsquo;ont pas de programme ? Et alors ? Qui pourrait se vanter aujourd&rsquo;hui d&rsquo;\u00e9laborer un programme, de s&rsquo;y tenir, de le pr\u00e9senter en y croyant vraiment, en usant ce qu&rsquo;il lui reste de conviction \u00e0 y croire vraiment ? On n&rsquo;apaise pas les temp\u00eates avec de \u00ab\u00a0la poudre de perlimpinpin\u00a0\u00bb. (Je crois que ce fut un des mots les plus charmants, par sa d\u00e9su\u00e9tude, son aspect vieillot qui me touche dans ma nostalgie, &ndash; il \u00e9tait d&rsquo;usage courage quand j&rsquo;avais six-sept ans, dans le courant de mes \u00e9tudes \u00e0 la maternelle, il y a exactement deux-tiers de si\u00e8cle.)<\/p>\n<\/p>\n<p><p>Ils \u00e9taient l\u00e0, s&rsquo;invectivant, je les vois sans les avoir vus, en v\u00e9rit\u00e9 \u00e9cras\u00e9s par l&rsquo;\u00e9norme poids du vide qui p\u00e8se sur nous tous dans cette p\u00e9riode innommable de l&rsquo;histoire du monde, confront\u00e9s \u00e0 la t\u00e2che terrifiante de discourir du rien en faisant mine de sa conviction et de son talent. On dira : \u00ab\u00a0Mais il y avait bien des sujets, tout de m\u00eame, qu&rsquo;ils eussent pu aborder dans un certain ordre et avec dignit\u00e9, en confrontant leurs diff\u00e9rences et leurs oppositions si claires !\u00a0\u00bb ; et je r\u00e9pondrais que non, pas en cet instant dont je dis qu&rsquo;il est un instant o&ugrave; l&rsquo;ampleur de la crise du monde est apparue et a fondu sur eux, sur les uns et les autres, sur nous tous, dans nos \u00e2mes et dans nos esprits. Il n&rsquo;est nul besoin de leur avis ni de leurs confidences pour comprendre cette situation. \u00ab\u00a0L&rsquo;\u00eatre est d\u00e9vast\u00e9\u00a0\u00bb me dis-je, songeant au bouquin de Mattei que je suis en train de lire, lentement, \u00e0 petites gorg\u00e9es tant ce livre (<em>L&rsquo;homme d\u00e9vast\u00e9<\/em>) est un de ceux qui vous confie la clef pr\u00e9cieuse et si rare de l&rsquo;\u00e9clairage de la d\u00e9vastation du monde.<\/p>\n<\/p>\n<p><p>Au fait, je ne l&rsquo;ai pas dit, et ainsi ai-je au moins ma conclusion : je parlais du d\u00e9bat qui opposait hier soir, \u00e0 la t\u00e9l\u00e9vision, les deux candidats ultimes pour l&rsquo;\u00e9lection du pr\u00e9sident de la R\u00e9publique fran\u00e7aise. <em>Requiem In Pace<\/em>, douce France, et toi aussi, ardent r\u00e9formateur et illusionniste des utopies r\u00e9demptrices. En cet instant, je n&rsquo;entends plus que le vent myst\u00e9rieux et insaisissable de la grande plaine vide&#8230; Demain, nous nous remettrons au travail apr\u00e8s ces heures terribles o&ugrave; nous avons jet\u00e9 un regard terrifi\u00e9 au fond inatteignable des abysses.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rien \u00e0 \u00e9crire&#8230; 04 mai 2017 &ndash; Cela m&rsquo;arrive rarement, tr\u00e8s rarement, et pourrait-on ajouter, encore plus rarement sinon jamais peut-\u00eatre apr\u00e8s un \u00e9v\u00e9nement de cette importance&#8230; Sauf qu&rsquo;il pourrait peut-\u00eatre me sembler, si j&rsquo;avais l&rsquo;esprit au sarcasme, qu&rsquo;il n&rsquo;eut gu\u00e8re d&rsquo;importance, cet \u00ab\u00a0\u00e9v\u00e9nement de cette importance\u00a0\u00bb, de m\u00eame que je me m\u00e9fie en g\u00e9n\u00e9ral&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6045,6644,12860,2711,2617,3314,12999,3340,7716,6121],"class_list":["post-77243","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-catastrophe","tag-debat","tag-france-2017","tag-le","tag-macron","tag-pen","tag-presidentiel","tag-presidentielles","tag-rien","tag-vide"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77243"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77243\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}