{"id":77248,"date":"2017-05-06T02:21:04","date_gmt":"2017-05-06T02:21:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/06\/micmac-deconstructeur-ou-le-rien-necessaire\/"},"modified":"2017-05-06T02:21:04","modified_gmt":"2017-05-06T02:21:04","slug":"micmac-deconstructeur-ou-le-rien-necessaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/06\/micmac-deconstructeur-ou-le-rien-necessaire\/","title":{"rendered":"MicMac d\u00e9constructeur ou le <strong><em>Rien <\/em><\/strong>n\u00e9cessaire"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">MicMac d\u00e9constructeur ou le <strong><em>Rien <\/em><\/strong>n\u00e9cessaire<\/h2>\n<\/p>\n<p><p>06 mai 2017 &ndash; L&rsquo;affaire \u00ab\u00a0MicMac\u00a0\u00bb\/\u00a0\u00bbMicMacron\u00a0\u00bb\/McMacron ayant \u00e9t\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article\/bho-adoube-un-micmacron-chef-de-guerre-civile\">par ailleurs \u00e9claircie<\/a>, il convient d&rsquo;observer que l&rsquo;expression de \u00ab\u00a0MicMac\u00a0\u00bb, qui rejoint un mot d&#8217;emploi courant, introduit d&rsquo;une certaine fa\u00e7on le fond du sujet extr\u00eamement grave que je veux traiter, qui concerne on s&rsquo;en doute la profonde signification du candidat-promis-\u00e0-\u00eatre-pr\u00e9sident, ce que sa survenue probable signifie en fait de n\u00e9cessit\u00e9 pour notre compte. Pris famili\u00e8rement, <a href=\"https:\/\/fr.wiktionary.org\/wiki\/micmac\">Micmac<\/a> signifie aussi bien &laquo; <em>Intrigue, manigance, pratique secr\u00e8te dont le but est bl\u00e2mable ou semble tel <\/em>&raquo; que &laquo; <em>Confusion inextricable<\/em> &raquo; ; ces deux sens \u00e9tant illustr\u00e9 par deux citations de la m\u00eame d\u00e9finition donn\u00e9e par le <em>Wikip\u00e9dia<\/em> :<\/p>\n<\/p>\n<p><p>&bull; &laquo; <em>Un <strong>micmac<\/strong> \u00e0 n&rsquo;y rien comprendre ! reprit-il. <\/em>(&hellip;)<em> Maintenant, ils me tiennent \u00e0 droite, \u00e0 gauche, derri\u00e8re.<\/em> &mdash; (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%89mile_Zola\" title=\"w:\u00c9mile Zola\">&Eacute;mile Zola<\/a>, <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Au_Bonheur_des_Dames\" title=\"w:Au Bonheur des Dames\">Au Bonheur des Dames<\/a><\/em>, 1883) &raquo;<\/p>\n<\/p>\n<p><p>&bull; &laquo; <em>D&rsquo;o&ugrave; un <strong>micmac<\/strong> de paperasses \u00e0 d\u00e9fier un cochon d&rsquo;y retrouver ses petits et l&rsquo;immobilisation d\u00e9finitive d&rsquo;une affaire devenue insoluble.<\/em> &mdash; (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Georges_Courteline\" title=\"w:Georges Courteline\">Georges Courteline<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Messieurs_les_ronds-de-cuir\" title=\"w:Messieurs les ronds-de-cuir\"><em>Messieurs les ronds-de-cuir<\/em><\/a>, 1893) &raquo;<\/p>\n<\/p>\n<p><p>Ces diverses consid\u00e9rations et citations illustrant l&rsquo;abr\u00e9g\u00e9 \u00e0 propos de l&rsquo;identit\u00e9 de la chose auquel nous sommes arriv\u00e9s pour ces textes de fin de campagne, &ndash; \u00ab\u00a0MicMac\u00a0\u00bb pour \u00ab\u00a0Micron-Macron\u00a0\u00bb ou \u00ab\u00a0Mic-Macron\u00a0\u00bb, ou mieux encore, \u00e0 l&rsquo;am\u00e9ricanisme, \u00ab\u00a0McMacron\u00a0\u00bb, &ndash; sembleraient bien futiles ou fort oiseuses. Tout cela n&rsquo;est futile ou oiseux qu&rsquo;en apparence pour un \u00e9v\u00e9nement qu&rsquo;on pourrait justement juger l&rsquo;\u00eatre, oiseux et futile ; quoi qu&rsquo;il en soit et dit peut-\u00eatre plus s\u00e9rieusement, il s&rsquo;agit d&rsquo;une illustration un peu leste du caract\u00e8re fondamental de la chose : apr\u00e8s tout, MicMac avec son capharna\u00fcm de politique \u00ab\u00a0\u00e0 d\u00e9fier les cochons d&rsquo;y retrouver leurs ordures \u00e0 bouffer\u00a0\u00bb, cela vous a de l&rsquo;allure et va au-del\u00e0 des apparence, non ? Ah, ce Courteline&#8230;<\/p>\n<\/p>\n<p><p>Le candidat-donn\u00e9-vainqueur m&rsquo;appara&icirc;t en v\u00e9rit\u00e9 comme un arch\u00e9type exceptionnel dans son esp\u00e8ce de n\u00e9antisation propre sur elle ou, mieux, de passe-partousisme (n\u00e9ologisme un peu forc\u00e9 \u00e0 partir de \u00ab\u00a0passe-partout\u00a0\u00bb pour y faire entrer, pour une lettre, l&rsquo;involontaire allusion-partou(z)e si bienvenue comme image symbolique de l&rsquo;esprit de la chose, non ?) ; et par cons\u00e9quent m&rsquo;appara&icirc;t-il, ce candidat-pr\u00e9sident, comme un \u00e9v\u00e9nement fondamental et fort bien accord\u00e9 \u00e0 ces temps o&ugrave; la n\u00e9antisation la plus basse triomphe&#8230; C&rsquo;est-\u00e0-dire, pour pr\u00e9ciser, le d\u00e9constructeur achev\u00e9 lui-m\u00eame d\u00e9construit en une sorte de <strong><em>rien<\/em><\/strong>, dispensateur de l&rsquo;acte syst\u00e9matique de la d\u00e9construction qui sera la marque de sa pr\u00e9sidence s&rsquo;il est \u00e9lu ; c&rsquo;est-\u00e0-dire, j&rsquo;insiste, le premier pr\u00e9sident absolument d\u00e9constructeur, &ndash; ou d\u00e9structurant dans le langage-<em>dedefensa.org<\/em>, cette fois pris comme l&rsquo;acte voulu comme supr\u00eame dans la qu\u00eate du <strong><em>rien<\/em><\/strong>, &ndash; le premier \u00e0 l&rsquo;\u00eatre, \u00e0 l&rsquo;afficher, faisant vertu de cette d\u00e9marche, et donc nous conduisant \u00e0 l&rsquo;extr\u00eame du projet d\u00e9constructeur.<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Il serait donc n\u00e9cessaire qu&rsquo;il l&#8217;emport\u00e2t dimanche parce qu&rsquo;il est n\u00e9cessaire que nous allions au terme de ce terrible <em>Voyage au bout de la nuit<\/em><\/strong> pour enfin d\u00e9couvrir <strong>ce que nous voulons faire de notre futur<\/strong> (j&#8217;emploie ce mot \u00e0 dessein, et non celui de destin) : l&rsquo;entropisation en voie d&rsquo;ach\u00e8vement rompant d\u00e9cisivement avec notre destin pour suivre leur futur de la destruction ultime ou bien la r\u00e9volte n\u00e9cessaire rejetant leur futur pour retrouver un futur qui soit n\u00f4tre et s&rsquo;exprime en retrouvant notre destin ; et certes <strong>ce choix est possible parce que cette entropisation en voie d&rsquo;ach\u00e8vement enfante elle-m\u00eame la possibilit\u00e9 de cette r\u00e9volte n\u00e9cessaire<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je suis frapp\u00e9 effectivement de constater combien la g\u00e9n\u00e9alogie impliquant le projet de la d\u00e9construction trouve en lui son expression politique, d&rsquo;une politique r\u00e9duite au <strong><em>rien<\/em><\/strong>, et nous donne une description incontestable de la chose (\u00ab\u00a0Mic-Macron\u00a0\u00bb). C&rsquo;est un signe du ciel pour mon compte d&rsquo;avoir entam\u00e9 pour cette fin de campagne cet <em>Homme d\u00e9vast\u00e9<\/em> de Mattei, plusieurs fois cit\u00e9 d\u00e9j\u00e0 dans ce <em>Journal-dde.crisis<\/em>. Moi qui n&rsquo;ai qu&rsquo;une pi\u00e8tre culture et qui travaille si souvent d&rsquo;intuition, ce livre que je lis comme on d\u00e9plie une dentelle, lisant et relisant chaque phrase, m&rsquo;apprend ce qui importe, et clairement. Il constitue une somme pour embrasser le mouvement de d\u00e9construction comme ph\u00e9nom\u00e8ne fondamental de la deuxi\u00e8me moiti\u00e9 du XX\u00e8me si\u00e8cle jusqu&rsquo;\u00e0 nous d&rsquo;une pens\u00e9e triomphante <strong>qui, malgr\u00e9 son extr\u00eame complication d&rsquo;apparence, se r\u00e9duit \u00e0 un projet d&rsquo;une simplicit\u00e9 lumineuse, d&rsquo;une lumi\u00e8re sinistre, avec application directe et diabolique<\/strong>. Certes, je m&rsquo;y retrouve parfaitement avec ma perception de l&rsquo;ultime progression de la dynamique de n\u00e9antissement qui caract\u00e9rise cette irr\u00e9sistible \u00e9volution dynamique de la d\u00e9construction jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame d&rsquo;aujourd&rsquo;hui, notamment avec cette formule <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-dde-definition-et-usage-1\">dd&#038;e<\/a> (d\u00e9structuration, dissolution &#038; entropisation) dont je ne me doutais pas lorsque je l&rsquo;ai \u00e9labor\u00e9e qu&rsquo;elle rencontrait si compl\u00e8tement le ph\u00e9nom\u00e8ne dont je parle ici. Il tombe \u00e0 pic, <em>L&rsquo;homme d\u00e9vast\u00e9<\/em>, pour me donner \u00e0 comprendre qui est notre probable-futur-pr\u00e9sident.<\/p>\n<\/p>\n<p><p>&laquo; <em>La pens\u00e9e fran\u00e7aise de la seconde moiti\u00e9 du XX\u00e8me si\u00e8cle a \u00e9t\u00e9 fascin\u00e9e par le vide<\/em>, \u00e9crit Mattei. [&#8230;] <em>Leur fascination pour le naufrage de l&rsquo;\u00eatre, du langage et de l&rsquo;homme<\/em>. &raquo; Il s&rsquo;agit de la &laquo; <em>destruction de mod\u00e8les r\u00e9pressifs au b\u00e9n\u00e9fice de la lib\u00e9ration du simulacre <\/em>&raquo;, c&rsquo;est-\u00e0-dire <strong>la mal\u00e9diction m\u00eame de la libert\u00e9 par l&rsquo;inversion pour faire de la libert\u00e9 l&rsquo;outil m\u00eame de l&#8217;emprisonnement jusqu&rsquo;\u00e0 l&rsquo;entropisation<\/strong> ; et Gilles Deleuze &laquo; <em>se tient au fond de la caverne platonicienne<\/em> &raquo; pour mener avec une rage extr\u00eame, jusqu&rsquo;au suicide, et un g\u00e9nie dialectique extraordinaire jusqu&rsquo;\u00e0 l&rsquo;inversion suicidaire, &ndash; pour mener &laquo; [u]<em>ne lutte incessante contre le platonisme <\/em>&raquo;. Mais le v\u00e9ritable initiateur, le premier des d\u00e9constructeurs fran\u00e7ais, n&rsquo;est pas un philosophe essentiellement mais d&rsquo;abord un \u00e9crivain-romancier, \u00e0 l&rsquo;&oelig;uvre d\u00e8s les ann\u00e9es 1940 alors que je naissais \u00e0 peine, c&rsquo;est-\u00e0-dire Maurice Blanchot que je ne connaissais pas avant que Mattei ne me le pr\u00e9sent\u00e2t.<\/p>\n<\/p>\n<p><p>Donc, nous dit Mattei, <strong>chez Blanchot triomphe le Neutre, qui pourrait \u00eatre bien l&#8217;embl\u00e8me de notre candidat-futur-pr\u00e9sident<\/strong>. Dans son esprit (celui de Blanchot), &laquo; <em>le Neutre r\u00e9cuse l&rsquo;unit\u00e9 et la totalit\u00e9, l&rsquo;origine et la fin, sans que l&rsquo;\u00e9criture puisse \u00e9difier une &oelig;uvre dot\u00e9e de sens<\/em> &raquo;. (Mattei fait parler Blanchot de l&rsquo;\u00e9crit comme l&rsquo;on pourrait parler d&rsquo;un nouveau pr\u00e9sident \u00e0 venir.) Mieux encore pour ce temps politique du ni-gauche\/ni-droite que nous vivons si intens\u00e9ment, il doit \u00eatre act\u00e9 que, &laquo; [d&rsquo;] <em>une fa\u00e7on plus g\u00e9n\u00e9rale le Neutre est ce qui efface, par le double mouvement du \u00ab\u00a0ni\/ni\u00a0\u00bb toute diff\u00e9rence dans les choses et, par cons\u00e9quent, annule les oppos\u00e9s au point de les dissoudre <\/em>&raquo;. Nous aimerons tous \u00ab\u00a0Mic-Macron\u00a0\u00bb comme tous les d\u00e9constructeurs (Lyotard, Foucault, Deleuze, Derrida et toute la bande) firent l&rsquo;\u00e9loge du Neutre de Blanchot, par la gr\u00e2ce de cette occurrence presque divine, &ndash; excusez du peu, camarades, &ndash; que &laquo; <em>cet \u00e9loge du Neutre tient \u00e0 l&rsquo;absence de d\u00e9finition de cette notion <\/em>&raquo;. Car il se trouve qu&rsquo;elle (cette notion du Neutre comme du \u00ab\u00a0Mic-Macron\u00a0\u00bb dont l&rsquo;\u00e9loge retentit partout dans les salons litt\u00e9raires et les <em>talk-shows<\/em> du Gras-et-Gai-Savoir) &laquo; <em>intervient sur un mode incantatoire par la magie du verbe comme si cette entit\u00e9, nouvelle Reine de la Nuit, pouvait d\u00e9truire tous les liens du monde, du langage et de l&rsquo;homme. Il suffit de se r\u00e9clamer du Neutre<\/em> [de \u00ab\u00a0Mic-Macron\u00a0\u00bb] <em>pour que, d&rsquo;un coup, les jeux d&rsquo;opposition s&rsquo;efface, bien que le Neutre<\/em> [le \u00ab\u00a0Mic-Macron\u00a0\u00bb] <em>\u00e9chappe \u00e0 la conceptualisation<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>En d&rsquo;autres mots, encore : &laquo; <em>N&rsquo;avoir rien \u00e0 exprimer doit \u00eatre pris dans son sens le plus simple. Quoi qu&rsquo;il <\/em>[l&rsquo;homme politique futur pr\u00e9sident] <em>veuille dire, ce n&rsquo;est rien. Le monde, les choses, le savoir ne lui sont que des points de rep\u00e8re \u00e0 travers le vide. Et lui-m\u00eame est d\u00e9j\u00e0 r\u00e9duit \u00e0 rien. Le rien est sa mati\u00e8re. Il rejette les formes par lesquelles elle s&rsquo;offre \u00e0 lui comme \u00e9tant quelque chose. <\/em>&raquo; J&rsquo;aurais donc parl\u00e9 de \u00ab\u00a0Mic-Macron\u00a0\u00bb avec cette citation qu&rsquo;on vient de lire ? Oui et non, certes &#8230; L&rsquo;extrait avec \u00ab\u00a0[l&rsquo;\u00e9crivain]\u00a0\u00bb remplac\u00e9 par \u00ab\u00a0[l&rsquo;homme politique futur pr\u00e9sident]\u00a0\u00bb date de 1943, comme 4<sup>\u00e8me<\/sup> de couverture de <em>Faux pas<\/em>, dans un sens o&ugrave; les collabos auraient pu descendre Blanchot comme r\u00e9sistant, et les r\u00e9sistants descendre Blanchot comme collabo, les uns et les autres avec autant de bonnes raisons. Au reste, ce personnage insaisissable a un parcours pseudo-politique bigarr\u00e9, allant de-ci de-l\u00e0, aussi bien AF que proche-PCF, jamais tout \u00e0 fait fautif, jamais compl\u00e8tement h\u00e9ro\u00efque&#8230; Bref, personne ne fit rien, ni les r\u00e9sistants ni les collabos, et la Gestapo se le tint pour dit car Blanchot avait d\u00e9j\u00e0 annonc\u00e9 la Bonne Nouvelle des d\u00e9constructeurs, qui devrait devenir celle de la politique \u00e0 attendre du prochain quinquennat si c&rsquo;est bien celui que tout le monde bon chic bon genre tient d\u00e9j\u00e0 pour acquis. Nous sommes dans un temps o&ugrave; notre pouvoir est tel que nous pouvons d\u00e9truire tous les arguments de politique qui ne sont pas n\u00f4tres en niant m\u00eame que nous les d\u00e9truisons vraiment, p<strong>arce que ces choses, avant qu&rsquo;elles nous soient dites, \u00e9taient d\u00e9j\u00e0 tenues pour nulles<\/strong>.<\/p>\n<\/p>\n<p><p>(Mattei \u00e9crit : &laquo; <em>Pour Blanchot<\/em> [et pour \u00ab\u00a0Mic-Macron\u00a0\u00bb]<em>, il y a chez l&rsquo;homme \u00ab\u00a0un pouvoir transcendant de n\u00e9gation, pouvoir qui ne d\u00e9pend en rien des objets qu&rsquo;il d\u00e9truit, qui, pour les d\u00e9truire, ne suppose m\u00eame pas leur existence ant\u00e9rieure parce que, au moment o&ugrave; il les d\u00e9truit, il les a toujours, d\u00e9j\u00e0, ant\u00e9rieurement tenus pour nuls\u00a0\u00bb. [1949]. <\/em>&raquo; Je ne suis pas assur\u00e9, au fond de moi, que ce Blanchot, entra&icirc;n\u00e9 par l&rsquo;ivresse de la pens\u00e9e abstraite et conceptuelle, r\u00e9alisait \u00e0 quelle machine il donnait l&rsquo;acc\u00e9l\u00e9ration terminale pour qu&rsquo;elle accomplisse son affreuse t\u00e2che tandis qu&rsquo;il assurait par contre avec un ferme r\u00e9alisme sa place dans l&rsquo;<em>intelligentsia <\/em>de la Rive-Gauche. Ainsi en est-il de tout ce train \u00e9trange de la d\u00e9construction, dont la \u00ab\u00a0politique\u00a0\u00bb tente aujourd&rsquo;hui de faire une repr\u00e9sentation acceptable selon l&rsquo;id\u00e9e qu&rsquo;on peut \u00e9difier une architecture de la d\u00e9construction et une structure de la d\u00e9structuration, tout cela fort d\u00e9mocratiquement on vous l&rsquo;assure&#8230;)<\/p>\n<\/p>\n<p><p>Ainsi \u00ab\u00a0Mic-Macron\u00a0\u00bb et ses amis politiques \u00e9coutent-ils vos arguments avec bienveillance parce qu&rsquo;ils savent, en m\u00eame temps que vous les dites, que ces arguments n&rsquo;existaient m\u00eame pas avant m\u00eame que vous les disiez, alors qu&rsquo;il est presqu&rsquo;inutile de prendre la peine de les d\u00e9truire, &ndash; sans parler, absurdit\u00e9 compl\u00e8te, absurdit\u00e9 compl\u00e8te, de les r\u00e9futer, &ndash; puisqu&rsquo;ils sont d\u00e9j\u00e0 poussi\u00e8re, et qu&rsquo;il est d&rsquo;ailleurs et finalement impossible de les d\u00e9truire puisqu&rsquo;ils n&rsquo;exist\u00e8rent jamais. Ainsi vous regarde-t-on si vous parlez d&rsquo;une fa\u00e7on critique de l&rsquo;Europe et de la politique pr\u00e9datrice qu&rsquo;elle impose \u00e0 ses choses, \u00e0 ses membres, si vous fulminez \u00e0 propos de la globalisation sans \u00e2me et qui tue les \u00e2mes, si vous arguez qu&rsquo;il faut prot\u00e9ger les choses fran\u00e7aises, si vous sugg\u00e9rez qu&rsquo;il faut que l&rsquo;&Eacute;tat songe \u00e0 prot\u00e9ger les plus d\u00e9munis, si vous avancez que la culture fran\u00e7aise est une chose qu&rsquo;il faut d\u00e9fendre, si vous affirmez que la France existait avant qu&rsquo;elle n&rsquo;exist\u00e2t plus&#8230;<\/p>\n<\/p>\n<p><p>Nous entrerons, dimanche, si les augures ont bien lu la feuille de route et si le vote populaire s&rsquo;ordonne ainsi qu&rsquo;il est pr\u00e9vu qu&rsquo;il fasse, c&rsquo;est-\u00e0-dire s&rsquo;il se d\u00e9construit pour mieux exprimer cette absence de forme qui nous est promise parce que, comme l&rsquo;observait le philosophe LR Fran\u00e7ois Barouin apr\u00e8s une sortie de \u00ab\u00a0Mic-Macron\u00a0\u00bb &laquo; <em>il ne dit rien sur rien et il n&rsquo;en pense probablement pas plus<\/em> &raquo;, nous entrerons dans l&rsquo;aire magnifique et sans un pli de la d\u00e9construction achev\u00e9e. Il n&rsquo;est pas assur\u00e9 que tout cela se passera selon le plan pr\u00e9vu, comme ils disaient en URSS au temps du brejn\u00e9visme finissant ; lorsque \u00ab\u00a0Mic-Macron\u00a0\u00bb devenu-pr\u00e9sident, singeant Brejnev qui constatait que le train-URSS n&rsquo;avan\u00e7ait plus faute de charbon et qui, abandonnant la technique stalinienne de faire fusiller les chauffeurs, conseillait aux autres du <em>Politburo<\/em> : \u00ab\u00a0Camarades, faites comme moi, tirez les rideaux et dites &lsquo;tchouc-tchouc-tchouc&rsquo;&#8230;\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MicMac d\u00e9constructeur ou le Rien n\u00e9cessaire 06 mai 2017 &ndash; L&rsquo;affaire \u00ab\u00a0MicMac\u00a0\u00bb\/\u00a0\u00bbMicMacron\u00a0\u00bb\/McMacron ayant \u00e9t\u00e9 par ailleurs \u00e9claircie, il convient d&rsquo;observer que l&rsquo;expression de \u00ab\u00a0MicMac\u00a0\u00bb, qui rejoint un mot d&#8217;emploi courant, introduit d&rsquo;une certaine fa\u00e7on le fond du sujet extr\u00eamement grave que je veux traiter, qui concerne on s&rsquo;en doute la profonde signification du candidat-promis-\u00e0-\u00eatre-pr\u00e9sident, ce&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13004,12970,7482,11301,12860,2617,11303,13003,12868,11994,13005,3340,7716],"class_list":["post-77248","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-blanchot","tag-deconstructeur","tag-deconstruction","tag-deleuze","tag-france-2017","tag-macron","tag-mattei","tag-micmac","tag-micron","tag-neantisation","tag-neutre","tag-presidentielles","tag-rien"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77248"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77248\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}