{"id":77256,"date":"2017-05-09T12:09:56","date_gmt":"2017-05-09T12:09:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/09\/presidentielles-station-etat-de-grace-supprimee\/"},"modified":"2017-05-09T12:09:56","modified_gmt":"2017-05-09T12:09:56","slug":"presidentielles-station-etat-de-grace-supprimee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/09\/presidentielles-station-etat-de-grace-supprimee\/","title":{"rendered":"Pr\u00e9sidentielles\u00a0: station \u201c\u00c9tat de Gr\u00e2ce\u201d supprim\u00e9e"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Pr\u00e9sidentielles : station \u00ab\u00a0&Eacute;tat de Gr\u00e2ce\u00a0\u00bb supprim\u00e9e<\/h2>\n<\/p>\n<p><p>Dans un texte m\u00ealant d\u00e9rision et gravit\u00e9 que le New York <em>Times <\/em>nous restitue en fran\u00e7ais qui est sa langue du c&oelig;ur autant que de l&rsquo;esprit, l&rsquo;\u00e9crivain alg\u00e9rien Boualem Sansal constate : &laquo; <em>En France, on change de pr\u00e9sident tous les cinq ans, mais rien ne change jamais qui vienne vraiment d&rsquo;eux<\/em>. &raquo; &#8230; On notera que, sans le vouloir pr\u00e9cis\u00e9ment m\u00eame s&rsquo;il le sait \u00e9videmment, l&rsquo;\u00e9crivain a signifi\u00e9 ce nouveau ph\u00e9nom\u00e8ne de la politique fran\u00e7aise, qui est la durabilit\u00e9 extr\u00eamement r\u00e9duite des pr\u00e9sidents. Depuis Sarko, le pr\u00e9sident n&rsquo;est plus r\u00e9\u00e9lu m\u00eame s&rsquo;il se pr\u00e9sente, &ndash; et nous pourrions dire jusqu&rsquo;au paradoxe, \u00ab\u00a0m\u00eame s&rsquo;il ne se repr\u00e9sente pas\u00a0\u00bb. Nous disons cela comme s&rsquo;il s&rsquo;agissait d&rsquo;une r\u00e8gle nouvelle alors que la d\u00e9mission de De Gaulle, la mort de Pompidou et m\u00eame l&rsquo;\u00e9chec de Giscard de 1981, devraient \u00eatre consid\u00e9r\u00e9s comme autant d&rsquo;avatars accidentels dont certains tragiques. D\u00e9sormais, ce n&rsquo;est plus l&rsquo;accident : la r\u00e8gle semble \u00eatre devenue, aujourd&rsquo;hui, que <strong>le pr\u00e9sident est comme un <em>Kleenex<\/em>, jetable apr\u00e8s emploi et qui ne vaut que pour un seul emploi<\/strong>.<\/p>\n<\/p>\n<p><p>(La prochaine \u00e9tape pourrait \u00eatre et devrait \u00eatre, en bonne logique subversive, le pr\u00e9sident-<em>kleenex <\/em>impropre \u00e0 la consommation, <strong>jet\u00e9 avant de s&rsquo;en servir, bref par interruption du quinquennat pour cause de crise de r\u00e9gime<\/strong>. Macron, le pr\u00e9sident qui innove en tout, pourrait bien nous apporter \u00e9galement cette \u00ab\u00a0modernisation\u00a0\u00bb d\u00e9cisive de la postmodernit\u00e9. Il aurait alors bien m\u00e9rit\u00e9 de la R\u00e9publique fran\u00e7aise, europ\u00e9enne et la\u00efque.)<\/p>\n<\/p>\n<p><p>Plus encore et mieux encore, car l&rsquo;on nous dit, dans le chef de certaines plumes inspir\u00e9es, qu&rsquo;il s&rsquo;agit de l&rsquo;\u00e9lection \u00ab\u00a0triomphale\u00a0\u00bb d&rsquo;un pr\u00e9sident. (<em>Dixit<\/em> sans crainte de la r\u00e9alit\u00e9 des chiffres qui ridiculise la qualification de la performance l&rsquo;organe de r\u00e9f\u00e9rence du Syst\u00e8me ; le quotidien <em>Le Monde<\/em> dans sa <em>newsletter<\/em> d&rsquo;information pour les les lecteurs r\u00e9ticents : &laquo; <em>L<\/em><em>e triomphe de Macron, les d\u00e9fis du pr\u00e9sident<\/em> &raquo;)&#8230; Eh bien, ce \u00ab\u00a0triomphe\u00a0\u00bb est imm\u00e9diatement suivie (le lendemain) d&rsquo;une manifestation de contestation d&rsquo;une politique d&rsquo;ores et d\u00e9j\u00e0 condamn\u00e9e avant que d&rsquo;exister, avec des accusations redoutables (&laquo; <em>En marche vers la guerre sociale<\/em> &raquo;), que m\u00eame les sites US se font un plaisir de d\u00e9tailler, &ndash; <em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-05-08\/watch-live-french-activists-unions-clash-riot-police-first-anti-macron-protest\">ZeroHedge.com<\/a><\/em>, par exemple. On ne parle m\u00eame pas des horions qu&rsquo;ont aussit\u00f4t \u00e9chang\u00e9 ceux qui avaient soutenu Macron par inadvertance, et notamment ceux qui, dans cette diversit\u00e9 de circonstance, ont aussit\u00f4t proclam\u00e9 que leur ralliement s&rsquo;arr\u00eatait l\u00e0 et qu&rsquo;ils reprenaient aussit\u00f4t leur (vraie ?) bataille ; il suffisait d&rsquo;entendre un Barouin avertissant que tout soutien \u00e0 Macron pour les l\u00e9gislatives signifierait l&rsquo;exclusion imm\u00e9diate du fautif du parti LR. Autrement dit, <strong>non seulement il n&rsquo;y a pas d&rsquo;\u00e9tat de gr\u00e2ce mais il y aurait plut\u00f4t un imm\u00e9diat \u00e9tat de disgr\u00e2ce qui suivrait, vingt-quatre plus tard, \u00ab\u00a0le triomphe de Macron\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>(Certes, nous avons compris la finesse du titreur qui suit le d\u00e9terminisme impos\u00e9 par la <em>narrative <\/em>[<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>]. Le triomphe est celui de l&rsquo;homme sans \u00e9quivalent, la pure merveille sortie de la gl\u00e8be franco-globalis\u00e9e qui a r\u00e9ussi cet exploit sans pr\u00e9c\u00e9dent de s\u00e9duire un peuple entier, &ndash; et quel peuple, mazette, selon les statistiques de l&rsquo;\u00e9lection, &ndash; alors que \u00ab\u00a0les d\u00e9fis\u00a0\u00bb sont ceux de cette fonction supr\u00eame que le monde entier nous envie.)<\/p>\n<\/p>\n<p><p>Effectivement, la situation est singuli\u00e8re, le g\u00eanant n&rsquo;\u00e9tant pas l&rsquo;\u00e9lection face \u00e0 la contestation, mais le \u00ab\u00a0triomphe\u00a0\u00bb de l&rsquo;\u00e9lection salu\u00e9 aussit\u00f4t par la contestation tr\u00e8s organis\u00e9e par des acteurs sociaux habituels (syndicats) et selon une th\u00e9matique dont l&rsquo;extr\u00eame est du type \u00ab\u00a0vers la guerre sociale\u00a0\u00bb. L&rsquo;esprit de la V\u00e8me R\u00e9publique est bien que l&rsquo;\u00e9lection pr\u00e9sidentielle constitue effectivement un moment sacr\u00e9 (mais la\u00efque, certes car l&rsquo;on tient aux contradictions du genre) o&ugrave; un personnage identifi\u00e9 \u00e0 un parti ou \u00e0 une tendance devient par la gr\u00e2ce de la fonction, et au moins pour une p\u00e9riode symbolique (justement dit-\u00ab\u00a0\u00e9tat de gr\u00e2ce\u00a0\u00bb), le pr\u00e9sident de \u00ab\u00a0tous les Fran\u00e7ais\u00a0\u00bb ; Hollande lui-m\u00eame y avait eu droit bien que fort courtement, c&rsquo;est dire si l&rsquo;esprit a le cuir \u00e9pais et ne meurt pas facilement&#8230; <strong>La postmodernit\u00e9 a finalement balay\u00e9 tout cela avec le \u00ab\u00a0pr\u00e9sident Macron\u00a0\u00bb<\/strong> (il sera difficile de se passer de guillemets) comme d\u00e9j\u00e0 l&rsquo;\u00e9lection de Trump l&rsquo;annon\u00e7ait (quoique d&rsquo;une fa\u00e7on encore ambigu\u00eb tant l&rsquo;opposition publique, &ndash; dans la rue et dans les m\u00e9dias, &ndash; \u00e9tait ouvertement organis\u00e9e, manipul\u00e9e et financ\u00e9e par des manipulateurs id\u00e9ologis\u00e9s). L&rsquo;\u00e9lection de Macron inaugure donc une \u00e9poque nouvelle, ce qui fait d&rsquo;ailleurs partie de son programme.<\/p>\n<\/p>\n<p><p>Il est vrai que le texte de Sansal est int\u00e9ressant par ce m\u00e9lange de d\u00e9rision et de gravit\u00e9, ce qui est au fond parfaitement d\u00e9finir la forme de l&rsquo;op\u00e9ration. Aux USA, il y a quelques mois, pour l&rsquo;\u00e9lection de Trump, ce fut assez semblable si l&rsquo;on veut bien s&rsquo;en souvenir, au point que nous juge\u00e2mes judicieux d&rsquo;inclure dans notre <em>Glossaire.dde <\/em>l&rsquo;expression volontairement paradoxale sinon oxymorique de \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a>\u00ab\u00a0. Au fond, ce ph\u00e9nom\u00e8ne de suppression d&rsquo;un temps d&rsquo;armistice pour cause d'\u00a0\u00bb\u00e9tat de gr\u00e2ce\u00a0\u00bb qui renvoie \u00e0 un processus de modernisation et de rentabilisation, &ndash; comme l&rsquo;on supprime les arr\u00eats pour les bus et les trains, et les stations de m\u00e9tro, &ndash; signifie simplement que le temps m\u00e9tahistorique ne prend plus de gants, un peu comme s&rsquo;il disait : \u00ab\u00a0on n&rsquo;arr\u00eate pas une crise en cours, m\u00eame pour un nouveau pr\u00e9sident\u00a0\u00bb ; simplement, enfin, <strong>parce que le temps m\u00e9tahistorique est \u00e9galement et n\u00e9cessairement un temps crisique, et que, par cons\u00e9quent il ne souffre aucune interruption de la crise<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi avons-nous de ces contradictions presque imm\u00e9diates, y compris dans le propos et assum\u00e9es comme telles, qui rendent compte de cette cohabitation du d\u00e9risoire et du tragique. Sans en rendre compte par la logique pr\u00e9cise de son analyse le commentateur en rend compte effectivement en faisant d\u00e9filer ces contradictions. Nous ignorons si cela est voulu, mais dans tous les cas cela a la vertu du vrai (d&rsquo;une v\u00e9rit\u00e9-de-situation fondatrice du caract\u00e8re trag\u00e9die-bouffe). Ainsi nous dit-il que les pr\u00e9sidents changent et ne changent rien, parce que &laquo; <em>la France ne se gouverne plus elle-m\u00eame<\/em> &raquo;, qu&rsquo;il y a l&rsquo;Europe qui donne ses consignes et la \u00ab\u00a0mondialisation\u00a0\u00bb (le globalisation) qui fait que &laquo; <em>la terre ne tourne plus que dans un sens &raquo;, <\/em>celui du<em> &laquo; cartel des banques <\/em>&raquo; ; puis il encha&icirc;ne aussit\u00f4t par la proposition de bon aloi mais tout de m\u00eame assez paradoxale &laquo; <em>Voil\u00e0 pourquoi il importait que soient d\u00e9battus durant la campagne pr\u00e9sidentielle tous ces th\u00e8mes mondialis\u00e9s<\/em>&#8230; &raquo;, pour aussit\u00f4t \u00e9mettre la r\u00e9serve \u00e9vidente qui explique tout : &laquo; <em>Mais ceux-ci ont \u00e9t\u00e9 \u00e0 peine \u00e9voqu\u00e9s. Peut-\u00eatre est-ce \u00e0 cause d&rsquo;un sentiment d&rsquo;impuissance face \u00e0 ces probl\u00e8mes<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Ce qui fait bouffe encore plus dans cette affaire, bien entendu, c&rsquo;est qu&rsquo;on se pr\u00e9cipite en d\u00e9sespoir de cause mais pour une si belle cause, jusqu&rsquo;aux plus extr\u00eames hyst\u00e9riques <strong>contre la chose la plus s\u00e9rieuse du monde qui est, comme on le sait, la \u00ab\u00a0menace fasciste\u00a0\u00bb<\/strong>. La campagne se fit donc, surtout au second tour, <strong>comme si on nous \u00e9tions en 1924 ou en 1933<\/strong>, ce qui ne g\u00eane pas trop les tenants la globalisation tous comptes faits. M\u00e9lenchon s&rsquo;est vant\u00e9, apr\u00e8s le r\u00e9sultat final, d&rsquo;\u00eatre celui qui avait permis d&rsquo;arr\u00eater le fascisme (celui de 1924-33, donc) ; bien s&ucirc;r, puisque c&rsquo;est lui qui a permis en bonne partie de faire \u00e9lire l&rsquo;homme de la globalisation ; la belle intelligence de M\u00e9lenchon ne hume-t-elle pas ce que cette contradiction peut avoir de bouffe, \u00e0 c\u00f4t\u00e9 de la trag\u00e9die ? A peine indirectement, Sansal met cela en \u00e9vidence lorsqu&rsquo;il salue plut\u00f4t ironiquement le talent rassembleur de M\u00e9lenchon (&laquo; <em>En tout cas, il a formidablement \u00e9gay\u00e9 la campagne. Quel bateleur, quel strat\u00e8ge, ce Jean-Luc! Merci pour ces bons moments <\/em>&raquo;), puis en signale aussit\u00f4t la cons\u00e9quence qui n&rsquo;est pas des plus habiles (&laquo; <em>En affaiblissant les R\u00e9publicains, le Parti socialiste et le Front national, M\u00e9lenchon aura profit\u00e9 \u00e0 Macron ainsi qu&rsquo;aux oligarques <\/em>&raquo;). Tout cela cr\u00e8ve tellement les yeux que plus personne ne voit distinctement, &ndash; ceci explique cela, &ndash; que cette bataille si furieuse contre<strong> un danger vieux de 80 ans et totalement an\u00e9anti dans sa v\u00e9ritable puissance il y a 60 ans<\/strong> est conduite <strong>au profit<\/strong> <strong>exclusif du seul danger plan\u00e9taire et sans aucun pr\u00e9c\u00e9dent pour aujourd&rsquo;hui m\u00eame<\/strong>. Et pourtant, nombre de ces combattants du pass\u00e9 (les \u00ab\u00a0antifafs\u00a0\u00bb) connaisse parfaitement et d\u00e9noncent \u00e0 mesure l&rsquo;existence de cette puissance destructrice d&rsquo;aujourd&rsquo;hui m\u00eame qui passe tout puisqu&rsquo;elle menace le monde lui-m\u00eame, toutes esp\u00e8ces et id\u00e9ologies bouffe-fantasmagoriques confondues.<\/p>\n<\/p>\n<p><p>Sans doute se trouve-t-il une frustration secr\u00e8te de devoir tenir un r\u00f4le si faussaire et,<strong> en combattant l&rsquo;ennemi imaginaire, de favoriser non seulement \u00ab\u00a0l&rsquo;ennemi principal\u00a0\u00bb mais le seul Ennemi possible<\/strong> ; laquelle frustration, \u00e0 cause de son ampleur, fait souvent tomber le d\u00e9bat \u00ab\u00a0contre le fascisme\u00a0\u00bb dans l&rsquo;ivresse de l&rsquo;outrance et du bombastique, &ndash; le bruit remplit le vide et \u00e9carte les pens\u00e9es qui pourraient s&rsquo;aventurer sous l&rsquo;\u00e9cume des jours, &ndash; qui nous restitue le style trag\u00e9die-bouffe qui est le n\u00f4tre.<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, pour les lecteurs avis\u00e9s, on trouve dans le texte de Sansal plusieurs marques de cette situation attristante. Homme courageux et grand \u00e9crivain qui ne craint pas de d\u00e9noncer le pouvoir corrompu en Alg\u00e9rie tout en restant sur place au risque des contraintes et des pressions qu&rsquo;on imagine, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boualem_Sansal\">Sansal<\/a> est acclam\u00e9 par le monde culturel et litt\u00e9raire (et progressiste-soci\u00e9tal) fran\u00e7ais et europ\u00e9en, et les institutions qui vont avec. Il constitue une de ces situations paradoxales si nombreuses o&ugrave; le Syst\u00e8me ch\u00e9rie certains critiques de lui-m\u00eame dans une position sp\u00e9cifique, parce que le jeu de billard pratiqu\u00e9 entre les diverses tromperies et simulacres des situations lui permet tout de m\u00eame (au Syst\u00e8me) d&rsquo;en tirer avantage du point de vue de la vertu apparente qu&rsquo;il veut conserver dans le domaine de la communication. Il n&#8217;emp\u00eache, cet article qui dit une bonne partie de son fait \u00e0 un nouveau pr\u00e9sident si exceptionnel par son \u00ab\u00a0triomphe\u00a0\u00bb de jeune homme quasiment \u00ab\u00a0sorti de rien\u00a0\u00bb (les banques, une belle fortune qu&rsquo;il s&rsquo;est faite, un an \u00e0 Bercy mais jamais d&rsquo;\u00e9lection, un rassemblement d&rsquo;influence et de fortunes pour l&rsquo;encourager de consignes diverses, une presseSyst\u00e8me d\u00e9cha&icirc;n\u00e9 pour le promouvoir et d\u00e9truire ses adversaires, cela vous donne un innocent aux mains propres, un \u00eatre d&rsquo;exception et un \u00ab\u00a0inconnu\u00a0\u00bb vertueux pour une pr\u00e9sidentielle), &ndash; cet article-l\u00e0 a d&ucirc; faire penser au Syst\u00e8me, o&ugrave; l&rsquo;on est tr\u00e8s strict en ce moment pour maintenir la discipline dans ces moments tr\u00e8s difficiles, que la vertu dont on parlait plus haut, dont il a besoin, est parfois pay\u00e9e un peu cher.<\/p>\n<\/p>\n<p><p>Ainsi nous permettons-nous d&#8217;emprunter cet article de Boualem Sansal, \u00e9crivain, auteur derni\u00e8rement de <em>2084<\/em>, du <a href=\"https:\/\/www.nytimes.com\/2017\/05\/08\/opinion\/boualem-sansal-france-macron-le-pen.html?emc=edit_ty_20170508&#038;nl=opinion-today&#038;nlid=74743076&#038;te=1&#038;_r=1\">8 mai 2017<\/a>&#8230;<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La France, \u00e9tat alt\u00e9r\u00e9<\/h2>\n<\/p>\n<p><p>Il y a du nouveau en France: un nouveau syst\u00e8me pour d\u00e9signer le pr\u00e9sident de la r\u00e9publique. Ni plus r\u00e9ellement une d\u00e9mocratie, ni une dictature, c&rsquo;est quelque chose qui n&rsquo;a pas encore de nom. Un acronyme ou un mot porte-manteau construit de &laquo;d\u00e9mocratie&raquo;, &laquo;dictature&raquo; et &laquo;ploutocratie&raquo; ferait bien l&rsquo;affaire.<\/p>\n<\/p>\n<p><p>Le m\u00e9canisme fonctionne ainsi: des patrons de grands groupes financiers, industriels et commerciaux, ainsi que d&rsquo;\u00e9minents conseillers habitu\u00e9s de l&rsquo;Elys\u00e9e, de Matignon et de Bercy ont choisi le futur pr\u00e9sident de la r\u00e9publique &mdash; Emmanuel Macron, en l&rsquo;occurrence &mdash; et l&rsquo;ont instruit de sa mission. Ensuite ces oligarques ont mobilis\u00e9 l&rsquo;Etat, le gouvernement, la justice, les m\u00e9dias, les communicants, les artistes, les cachetiers, les sondeurs, les soci\u00e9t\u00e9s de Paris et les grands noms de la soci\u00e9t\u00e9 civile pour le porter \u00e0 la magistrature supr\u00eame. La machine s&rsquo;est mise au travail et en un tour de piste a fait de l&rsquo;imp\u00e9trant le candidat du peuple, le favori, le h\u00e9ros ind\u00e9passable. Lui-m\u00eame en est devenu convaincu.<\/p>\n<\/p>\n<p><p>Le reste \u00e9tait une simple formalit\u00e9: il suffisait juste d&rsquo;\u00e9liminer les autres candidats. On en a mis beaucoup sur la ligne de d\u00e9part, d\u00e9sesp\u00e9rant le peuple en lui donnant l&rsquo;image de la d\u00e9plorable division dans laquelle les partis politiques ont entrain\u00e9 le pays. Puis on a promis des primaires pour rem\u00e9dier \u00e0 \u00e7a: il y aura un tri impitoyable! En effet: les candidats s\u00e9rieux &mdash; Manuel Valls, Alain Jupp\u00e9 &mdash; ont \u00e9t\u00e9 \u00e9limin\u00e9s.<\/p>\n<\/p>\n<p><p>La justice a ensuite lanc\u00e9 des fatwas contre les gros candidats qui restaient, et la presse, bras s\u00e9culier de l&rsquo;oligarchie, les a traqu\u00e9s. Fran\u00e7ois Fillon et Marine Le Pen ont \u00e9t\u00e9 poursuivis pour vol \u00e0 l&rsquo;\u00e9talage, leurs photos placard\u00e9es \u00e0 la une des journaux.<\/p>\n<\/p>\n<p><p>On accuse aussi Jean-Luc M\u00e9lenchon de pas mal de crimes. Il aurait assassin\u00e9 le Parti socialiste, caporalis\u00e9 les communistes, vol\u00e9 des troupes aux R\u00e9publicains et aux frontistes et contrevenu aux r\u00e8gles de la soumission en appelant son mouvement La France insoumise.<\/p>\n<\/p>\n<p><p>En tout cas, il a formidablement \u00e9gay\u00e9 la campagne. Quel bateleur, quel strat\u00e8ge, ce Jean-Luc! Merci pour ces bons moments. Notre c\u00f4t\u00e9 romantique inv\u00e9t\u00e9r\u00e9 a appr\u00e9ci\u00e9 ton mot en forme de salut \u00e0 la veille du premier tour: &laquo;Allez, viennent les jours heureux et le go&ucirc;t du bonheur!&raquo;<\/p>\n<\/p>\n<p><p>En affaiblissant les R\u00e9publicains, le Parti socialiste et le Front national, M\u00e9lenchon aura profit\u00e9 \u00e0 Macron ainsi qu&rsquo;aux oligarques &mdash; mais tout en gagnant lui-m\u00eame aussi. Maintenant, les l\u00e9gislatives.<\/p>\n<\/p>\n<p><p>L&rsquo;autre inconnue dans l&rsquo;affaire aura \u00e9t\u00e9 le peuple. Il est trop b\u00eate, dit-on; c&rsquo;est un troupeau angoiss\u00e9, qui peut r\u00e9agir n&rsquo;importe comment. D&rsquo;ailleurs, le moment est peut-\u00eatre venu d&rsquo;en changer. Ce peuple-ci a fait son temps. Il parle encore de de Gaulle, Jaur\u00e8s, Jeanne d&rsquo;Arc. C&rsquo;est vrai qu&rsquo;il rechigne un peu: dimanche, les \u00e9lecteurs se sont abstenus de voter en nombre record.<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat de ce m\u00e9li-m\u00e9lo c&rsquo;est Macron. Jamais \u00e9lu auparavant, t\u00eate d&rsquo;un mouvement vieux de juste un an, le voil\u00e0 pr\u00e9sident de la R\u00e9publique. On ne faisait semblant de douter de son ultime succ\u00e8s que pour \u00e9carter la suspicion de manipulation politique. Alors que Fillon a \u00e9t\u00e9 mis en examen et que la justice fran\u00e7aise a demand\u00e9 la lev\u00e9e de l&rsquo;immunit\u00e9 parlementaire de Le Pen \u00e0 l&rsquo;Union europ\u00e9enne, elle a refus\u00e9 d&rsquo;ouvrir une enqu\u00eate sur le patrimoine de Macron, pourtant demand\u00e9e par de nombreux candidats.<\/p>\n<\/p>\n<p><p>Mais au fond tout \u00e7a c&rsquo;est du frichti, des amusettes, des histoires de carri\u00e8res personnelles. Valls, Jupp\u00e9, Le Pen, Fillon, Macron, M\u00e9lenchon, Hamon, Tartempion &mdash; tout \u00e7a c&rsquo;est pareil, \u00e0 peu de choses pr\u00e8s. En France, on change de pr\u00e9sident tous les cinq ans, mais rien ne change jamais qui vienne vraiment d&rsquo;eux.<\/p>\n<\/p>\n<p><p>La France ne se gouverne plus elle-m\u00eame; l&rsquo;Europe a toujours son mot \u00e0 dire. La mondialisation fait que la terre ne tourne plus que dans un sens &mdash; le sens du cartel des banques, qui a pris le relais du cartel des compagnies p\u00e9troli\u00e8res, qui avait pris le relais du cartel des compagnies mini\u00e8res.<\/p>\n<\/p>\n<p><p>Voil\u00e0 pourquoi il importait que soient d\u00e9battus durant la campagne pr\u00e9sidentielle tous ces th\u00e8mes mondialis\u00e9s: l&rsquo;islamisation, le terrorisme, le r\u00e9chauffement climatique, la migration, l&rsquo;affaiblissement des institutions multilat\u00e9rales. Mais ceux-ci ont \u00e0 peine \u00e9t\u00e9 \u00e9voqu\u00e9s. Peut-\u00eatre \u00e9tait-ce \u00e0 cause d&rsquo;un sentiment d&rsquo;impuissance face \u00e0 ces probl\u00e8mes. Mais le fait de ne pouvoir rien y changer n&rsquo;est pas une raison de ne pas y regarder.<\/p>\n<\/p>\n<p><p>Cette campagne pr\u00e9sidentielle n&rsquo;aura pas non plus confront\u00e9 les options strat\u00e9giques de la France \u00e0 moyen et long terme. La France saura-t-elle r\u00e9inventer ses institutions? Et surtout: saura-t-elle enrayer son d\u00e9clin? Saura-t-elle retrouver son r\u00f4le de moteur de l&rsquo;Europe, surtout face \u00e0 l&rsquo;Allemagne? Cette campagne pr\u00e9sidentielle aura \u00e9t\u00e9 une campagne de gouvernement qui discute de gestion des ressources et d&rsquo;\u00e9quilibre des comptes. On a parl\u00e9 boutique avec quelques accents lyriques pour faire grandiose. Mais tout du long on a pli\u00e9 sous la tyrannie du court-termisme et du pas-de-vague.<\/p>\n<\/p>\n<p><p>A gauche comme \u00e0 droite, les grands partis d&rsquo;antan ont \u00e9t\u00e9 bris\u00e9s, discr\u00e9dit\u00e9s. La recomposition politique en France ressemble \u00e0 un nettoyage par le vide. Entre-temps la fonction pr\u00e9sidentielle a aussi \u00e9t\u00e9 consid\u00e9rablement affaiblie. Merci Nicolas Sarkozy et Fran\u00e7ois Hollande. Macron, h\u00e9ritier d&rsquo;une fonction qui a \u00e9t\u00e9 mise au plus bas, va vite d\u00e9couvrir l&rsquo;\u00e9troitesse de sa marge de man&oelig;uvre &mdash; d&rsquo;autant plus qu&rsquo;il sera l&rsquo;otage de la troupe disparate qui l&rsquo;a fait arriver l\u00e0.<\/p>\n<\/p>\n<p><h4>Boualem Sansal<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sidentielles : station \u00ab\u00a0&Eacute;tat de Gr\u00e2ce\u00a0\u00bb supprim\u00e9e Dans un texte m\u00ealant d\u00e9rision et gravit\u00e9 que le New York Times nous restitue en fran\u00e7ais qui est sa langue du c&oelig;ur autant que de l&rsquo;esprit, l&rsquo;\u00e9crivain alg\u00e9rien Boualem Sansal constate : &laquo; En France, on change de pr\u00e9sident tous les cinq ans, mais rien ne change jamais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[13019,3402,2617,13021,4029,13020,11965],"class_list":["post-77256","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-boualem","tag-fascisme","tag-macron","tag-quinquennat","tag-republique","tag-sansal","tag-veme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77256"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77256\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}