{"id":77271,"date":"2017-05-19T13:23:09","date_gmt":"2017-05-19T13:23:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/19\/pourquoi-les-usa-nauraient-jamais-du-exister\/"},"modified":"2017-05-19T13:23:09","modified_gmt":"2017-05-19T13:23:09","slug":"pourquoi-les-usa-nauraient-jamais-du-exister","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/19\/pourquoi-les-usa-nauraient-jamais-du-exister\/","title":{"rendered":"Pourquoi les USA n&rsquo;auraient jamais d\u00fb exister"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pourquoi les USA n&rsquo;auraient jamais d&ucirc; exister<\/h2>\n<\/p>\n<p><p>Un article d&rsquo;Adam Gopnik dans The New Yorker a mis en rage les \u00e9nergum\u00e8nes de Prisonplanet.com (vive Trump, mais vive la guerre avec les russes). Il ne fait pourtant que reprendre \u00e0 sa mani\u00e8re gauchiste les arguments des libertariens et de quelques traditionalistes dont je suis sur une question importante : l&rsquo;existence-m\u00eame des USA.<\/p>\n<\/p>\n<p><p>Nous aurions pu \u00eatre le Canada. We could have been Canada.<\/p>\n<\/p>\n<p><p>On n&rsquo;avait donc pas besoin de faire une guerre d&rsquo;ind\u00e9pendance cruelle et dangereuse contre l&rsquo;Angleterre. L&rsquo;Am\u00e9rique aurait \u00e9t\u00e9 moins peupl\u00e9e, serait rest\u00e9e un dominion tranquille comme le Canada et l&rsquo;Australie, et l&rsquo;Angleterre aurait continu\u00e9 de tr\u00f4ner pragmatiquement sur le monde. L&rsquo;Allemagne n&rsquo;aurait bien s&ucirc;r pas os\u00e9 la d\u00e9fier, et nous n&rsquo;aurions pas connu les horreurs mondiales de nos guerres germano-britanniques.<\/p>\n<\/p>\n<p><p>Gopnik ajoute qu&rsquo;on aurait aboli l&rsquo;esclavage sans passer par cette folle et sanglante guerre de S\u00e9cession. C&rsquo;est une \u00e9vidence : l&rsquo;Angleterre a aboli dans la belle foul\u00e9e de sa r\u00e9volution industrielle l&rsquo;esclavage dans toutes ses colonies. Je pense aussi qu&rsquo;il y aurait eu une immigration  anglo-irlandaise dans ce grand pays, et cela aurait \u00e9t\u00e9 mieux. Je suis arriv\u00e9 \u00e0 cette conclusion en lisant Poe, Melville, Kipling, Grant, Stoddard, Ross et quelques dizaines d&rsquo;autres.<\/p>\n<\/p>\n<p><p>Thomas di Lorenzo dans son livre sur Lincoln a r\u00e9v\u00e9l\u00e9 le personnage que c&rsquo;\u00e9tait. Un radical, un whig, comme ceux qui voulaient la r\u00e9volution de 1776 aux relents Illuminati. J&rsquo;ai soulign\u00e9 dans un texte pr\u00e9c\u00e9dent que Lincoln d\u00e9nonce d&rsquo;un c\u00f4t\u00e9 la barbarie de la populace am\u00e9ricaine (crimes racistes, lynchages, pendaisons ; comparez au Canada) et cette adoration de la loi qui confine aujourd&rsquo;hui au totalitarisme, avec 42% de la population carc\u00e9rale mondiale.<\/p>\n<\/p>\n<p><p>La nation indispensable d&rsquo;Obama (qui vient de palper 3 .2 millions pour p\u00e9rorer en jet sur l&rsquo;effet de serre) n&rsquo;aurait pas d\u00e9truit (ou d\u00e9figur\u00e9) la moiti\u00e9 du monde et l&rsquo;Asie, et n&rsquo;aurait pas hypocritement g\u00e9r\u00e9 la question noire apr\u00e8s l&rsquo;esclavage (un million de jeunes noirs tu\u00e9s en trente ans l\u00e0-bas), n&rsquo;aurait pas d\u00e9truit la culture europ\u00e9enne et m\u00eame mondiale par sa sous-culture d\u00e9racin\u00e9e. Elle ne serait pas en train de nous pr\u00e9parer \u00e0 une guerre d&rsquo;extermination contre la Russie pour satisfaire son ego.<\/p>\n<\/p>\n<p><p>Oui, je pense aussi que l&rsquo;on pouvait se passer de l&rsquo;Am\u00e9rique et que la France aurait pu garder la Louisiane, l&rsquo;Espagne la Californie, et la Russie l&rsquo;Alaska. La destruction de la plan\u00e8te par l&rsquo;Am\u00e9ricanisme depuis deux-cent-quarante ans maintenant est certainement la plus grande catastrophe eschatologique de l&rsquo;histoire du monde. Ajoutez que si nous n&rsquo;avions pas aid\u00e9 cette anti-nation \u00e0 chasser les gentlemen Anglais, nous n&rsquo;aurions pas connu la r\u00e9volution et son cort\u00e8ge de catastrophes. Il est vrai qu&rsquo;il y en a que cela motive.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources<\/h3>\n<\/p>\n<p><p>We could have been Canada &ndash; The New Yorker &ndash; 05\/15\/2017<\/p>\n<\/p>\n<p><p>Samuel Johnson &ndash; The patriot (1774)<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; La culture comme arme de destruction massive (Amazon_Kindle)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi les USA n&rsquo;auraient jamais d&ucirc; exister Un article d&rsquo;Adam Gopnik dans The New Yorker a mis en rage les \u00e9nergum\u00e8nes de Prisonplanet.com (vive Trump, mais vive la guerre avec les russes). Il ne fait pourtant que reprendre \u00e0 sa mani\u00e8re gauchiste les arguments des libertariens et de quelques traditionalistes dont je suis sur une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[10870,3708,13044,4345,2949,2804],"class_list":["post-77271","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-10870","tag-canada","tag-gopnik","tag-independance","tag-secession","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77271"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77271\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}