{"id":77272,"date":"2017-05-19T13:23:49","date_gmt":"2017-05-19T13:23:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/19\/tristes-etats-de-lunion\/"},"modified":"2017-05-19T13:23:49","modified_gmt":"2017-05-19T13:23:49","slug":"tristes-etats-de-lunion","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/19\/tristes-etats-de-lunion\/","title":{"rendered":"Triste(s) \u00c9tat(s) de l&rsquo;Union"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Triste(s) &Eacute;tat(s) de l&rsquo;Union<\/h2>\n<\/p>\n<p><p>19 mai 2017 &ndash; Nous nous int\u00e9ressons \u00e0 une dynamique assez peu mise en \u00e9vidence, du point de vue de la communication ; on lui pr\u00e9f\u00e8re manifestement les diverses jacasseries plus ou moins putschistes de Washington D.C., &ndash; sans prendre garde au fait que <strong>ces jacasseries alimentent \u00e9videmment cette dynamique discr\u00e8te<\/strong>. Il s&rsquo;agit d&rsquo;un mouvement lanc\u00e9 aux USA pour parvenir \u00e0 une Convention Constitutionnelle d\u00e9bouchant sur une proposition d&rsquo;amendement \u00e0 la Constitution. Il s&rsquo;agit de l&rsquo;application de l&rsquo;Article V de la Constitution des Etats-Unis stipulant que si deux tiers des &Eacute;tats de l&rsquo;Union proposent un amendement \u00e0 la Constitution, le Congr\u00e8s des &Eacute;tats-Unis est requis d&rsquo;en d\u00e9battre pour se prononcer sur la validit\u00e9 de l&rsquo;amendement. (Les amendements ont en g\u00e9n\u00e9ral une importance d\u00e9terminante. Ils suppl\u00e9ent \u00e0 une insuffisance de la Constitution originelle. La perception populaire de la chose est \u00e9vidente : toutes les grandes causes politiques d\u00e9battues, notamment avec l&rsquo;\u00e9cho des auditions devant le Congr\u00e8s ou des grands proc\u00e8s, nous ont rendu familier le recours syst\u00e9matique aux amendements pour d\u00e9terminer la l\u00e9galit\u00e9 du comportement d&rsquo;un citoyen devant les demandes ou les exigences des grands corps, des organisations diverses, du <em>Corporate Power<\/em>, de la soci\u00e9t\u00e9, etc. Sur ce cas, le colonel Lang est d&rsquo;avis qu&rsquo;une telle demande ne pourrait en aucun cas \u00eatre repouss\u00e9e, ou \u00ab\u00a0confin\u00e9e\u00a0\u00bb, \u00e9crit-il, par un vote du Congr\u00e8s. Il remarque, dans son style inimitable, autant \u00e0 propos de cette affaire de Convention qu&rsquo;\u00e0 propos de la situation g\u00e9n\u00e9rale du pouvoir \u00e0 Washington D.C. : &laquo; <em>IMO we are a stage of potential dissolution of the Union that resembles 1859<\/em> &raquo; (\u00ab\u00a0Selon mon opinion, nous sommes <strong>dans un cadre potentiel de dissolution de l&rsquo;Union qui ressemble \u00e0 celui de 1859<\/strong>\u00ab\u00a0, c&rsquo;est-\u00e0-dire le processus qui conduisit \u00e0 l&rsquo;\u00e9clatement de l&rsquo;Union et \u00e0 la Guerre de S\u00e9cession, que le langage officiel d\u00e9signe comme <em>The Civil War<\/em>) ;<\/p>\n<\/p>\n<p><p>&bull; Mais essayons d&rsquo;arranger de fa\u00e7on plus compr\u00e9hensible et rationnelle notre d\u00e9marche. Donc, le <a href=\"http:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2017\/05\/is-the-dissoultion-of-the-union-what-you-want.html\">10 mai 2017<\/a>, nous lisons sur le site <em>Sic Semper Tyrannis<\/em>, un texte du colonel Lang qui en est l&rsquo;\u00e9diteur. Lang prend comme exemple de son argument tr\u00e8s court, abrupt et catastrophique, une circonstance parmi d&rsquo;autres, mais si nombreuses en ce moment : nombre de ses lecteurs lui ont \u00e9crit qu&rsquo;apr\u00e8s le limogeage de Comey, le directeur du FBI, et la r\u00e9action insurrectionnelle sinon putschiste des d\u00e9mocrates, ils ne pourraient accepter ni soutenir la nomination d&rsquo;un nouveau directeur du FBI qui serait d\u00e9mocrate. Lang s&rsquo;exclame devant ce que cette intervention dit du climat actuel aux USA, et \u00e0 Washington D.C., que tant d&rsquo;autres faits corroborent, et bien entendu par-dessus tout la \u00ab\u00a0guerre civile constitutionnelle et de communication\u00a0\u00bb actuellement en cours&#8230; <strong>Tout cela, dit-il, ressemble \u00e0 l&rsquo;\u00e9tat o&ugrave; se trouvait l&rsquo;Union en 1859, avec l&rsquo;issue qu&rsquo;on sait<\/strong> : \u00ab\u00a0est-ce cela que vous voulez ?\u00a0\u00bb semble-t-il interroger d\u00e9sesp\u00e9r\u00e9ment ; \u00ab\u00a0si les choses continuent comme elles vont actuellement, vos v&oelig;ux finiront par \u00eatre exauc\u00e9s\u00a0\u00bb, &ndash; et la Convention Constitutionnelle pr\u00e9sentera un amendement soutenu par 32 ou plus de 32 des &Eacute;tats de l&rsquo;Union, et cet amendement ne serait, sans n\u00e9cessit\u00e9 de le dire si hautement, <strong>rien d&rsquo;autre qu&rsquo;une dissolution <em>de facto <\/em>de l&rsquo;Union, et le <em>de jure <\/em>suivrait tr\u00e8s vite<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Lots of you folks on the right have written to me to say that the appointment of a Democrat to be FBI director is out of the question.  <strong>Do you really mean that?  IMO we are a stage of potential dissolution of the Union that resembles 1859<\/strong>.  To say that a Democrat could not and would not preside over an FBI investigation that would reveal the truth is an admission of the disappearance of the level of comity needed to hold the country together.  <\/em><em>I question your judgement about this.  1- Nothing has thus far been \u00ab\u00a0leaked\u00a0\u00bb that demonstrates ANY collusion between the Trump campaign and Russia or Russians.  <\/em><em>The Democrats are outraged because Lavrov and Putin laugh at the innuendo and agitprop in the media?  Well, why would they not?  There is no proof of any kind thus far.  Even Senator Feinstein admits that.  2-  The FBI is a large organization.  Many in the Bureau and in DoJ will know what the investigation reveals.  Do you really imagine that all those people<\/em> <em>would help conceal a result in the investigation that exonerates Trump?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Eleven state legislatures have voted for a new constitutional convention.  Thirty four are required, twenty-three more.  Amendments  produced by such a convention would normally require approval by the US Congress and the state legislatures, but, IMO, there would be no way on earth to confine the outcome of such a convention to these requirements any more than there was in the instance of the first constitutional convention in the Eighteenth Century.  In that instance the convention was called to make amendments to the Articles of Confederation, but the convention simply seized control of the process and created a wholly new form of government<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Is that what you want?  If feelings continue to run in the direction they now take on the left and right <strong>you may well have your wishes fulfilled<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Nous n&rsquo;avions eu aucun \u00e9cho de cette dynamique pour une Convention Constitutionnelle. Lang nous donne aimablement <a href=\"https:\/\/en.wikipedia.org\/wiki\/Convention_to_propose_amendments_to_the_United_States_Constitution\">le lien<\/a> de l&rsquo;article du <em>Wikip\u00e9dia<\/em> qui en traite, sous le titre &laquo; <em>Convention to propose amendments to the United States Constitution<\/em> &raquo;. Ce processus constitutionnel (proposition d&rsquo;un amendement \u00e0 la Constitution) est expos\u00e9 en d\u00e9tails, mais nous lisons que l&rsquo;affaire signal\u00e9e par Lang est pr\u00e9sent\u00e9e de la sorte : &laquo; <em>In recent years some have argued that state governments should call for such a convention. They include <a href=\"https:\/\/en.wikipedia.org\/wiki\/Michael_Farris_(lawyer)\">Michael Farris<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Lawrence_Lessig\">Lawrence Lessig<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Sanford_Levinson\">Sanford Levinson<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Larry_Sabato\">Larry Sabato<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Jonathan_Turley\">Jonathan Turley<\/a>, and <a href=\"https:\/\/en.wikipedia.org\/wiki\/Mark_Levin\">Mark Levin<\/a>. In 2015, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Citizens_for_Self-Governance\">Citizens for Self-Governance<\/a> launched a nationwide effort to call an Article V Convention, through a project called Convention of the States, in a bid <strong>to rein in the federal government<\/strong>. As of 2017, CSG&rsquo;s resolution has passed in 11 states<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Consult\u00e9 par nous ce 19 mai, le sujet du <em>Wikip\u00e9dia <\/em>n&rsquo;est pas \u00e0 jour, sans doute parce qu&rsquo;il est jug\u00e9 d&rsquo;un int\u00e9r\u00eat mineur par rapport aux jacasseries de Washington D.C. En effet, le 15 mai, quelques jours apr\u00e8s l&rsquo;article du colonel Lang, un douzi\u00e8me &Eacute;tat, le Missouri, a d\u00e9cid\u00e9 par un vote de 85 voix contre 50 de sa l\u00e9gislature de rejoindre le groupe des onze qui demandent la r\u00e9union d&rsquo;une telle Convention Constitutionnelle. <a href=\"http:\/\/www.wnd.com\/2017\/05\/12th-state-calls-for-convention-amending-constitution\/\">Un article fourni<\/a> de <em>World Net Daily<\/em> (WND) d\u00e9taille l&rsquo;\u00e9v\u00e9nement, en m\u00eame temps qu&rsquo;il explique les buts de cette Convention ; et l&rsquo;on comprend ais\u00e9ment que l&rsquo;id\u00e9e fondamentale de la d\u00e9marche est de pr\u00e9senter un amendement \u00e0 la Constitution qui, <em>de facto<\/em>, prive le gouvernement central de Washington D.C. de pouvoirs \u00e9ventuellement  importants, de fa\u00e7on \u00e0 interrompre la politique actuelle, notamment du point de vue de la dette \u00e9norme qui a \u00e9t\u00e9 accumul\u00e9e&#8230; \u00ab\u00a0<em>Washington<\/em> <em>is out of control<\/em>\u00ab\u00a0, il faut lui reprendre certains de ses pouvoirs les plus d\u00e9cisifs, <strong>le d\u00e9-f\u00e9d\u00e9raliser pour stopper cette politique insens\u00e9e d&rsquo;endettement catastrophique<\/strong>. Dans les conditions actuelles de tension, on peut ais\u00e9ment envisager l&rsquo;hypoth\u00e8se qu&rsquo;un tel programme implique l&rsquo;ouverture d&rsquo;<strong>un processus de dissolution de l&rsquo;Union au profit des &Eacute;tats, c&rsquo;est-\u00e0-dire un processus de dissolution des USA en tant que f\u00e9d\u00e9ration<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>Missouri has become the 12th state to pass legislation calling for an Article V Convention of States that would propose constitutional amendments to rein in the federal government. The COS resolution, SCR4, passed last Friday by a vote of 85 to 50. <\/em><em>It was sponsored by state Sen. Mike Kehoe, R-Jefferson City.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Article V of the U.S. Constitution states the Constitution may be amended if two-thirds of the state legislatures apply to Congress to call a convention for proposing amendments. All state applications must ask for a convention dealing with the same subject matter. The 12 applications submitted so far request a convention to propose amendments to limit the power and jurisdiction of the federal government, impose fiscal restraint on the federal government and limit the terms of federal officials and members of Congress. Now that Missouri has passed the COS resolution, more than one-third of the necessary 34 states have submitted applications for a Convention of States.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The driving force behind the nationwide push for a convention is the Convention of States Project. Keith Carmichael, state director for COS Project Missouri, celebrated his organization&rsquo;s victory in the Show Me State. \u00ab\u00a0Many Missourians, including a clear majority of the members in the Missouri House and Senate, have concluded that we as citizens must act now to save ourselves from a federal government that has grown far beyond its constitutional limits,\u00a0\u00bb Carmichael stated in a press release.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0It is past time for the states to come together as Article V of our Constitution provides in order to propose solutions in the form of amendments. We must quickly come to grips with the real crisis we have created &ndash; a &lsquo;house of cards&rsquo; we call the national debt and the immorality of forcing it upon future generations &ndash; plus interest! We should honor our Founders, who gave us Article V and expected us to use it. Article V is a remedy &ndash; a rudder that needs to be used now to steer America back on course. It is in the Constitution for this exact time.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le texte continue en mettant en \u00e9vidence l&rsquo;actualit\u00e9 pressante du processus, en rapportant l&rsquo;\u00e9chec r\u00e9cent de l&rsquo;administration Trump et de la direction r\u00e9publicaine de la Chambre (le <em>Speaker <\/em>Paul Ryan) \u00e0 faire voter l&rsquo;abrogation de la l\u00e9gislation dite <em>Obamacare<\/em> (les lois de s\u00e9curit\u00e9 sociale mises en place sous l&rsquo;administration Obama) qui est pourtant un point fondamental aussi bien de l&rsquo;administration Trump que de la majorit\u00e9 r\u00e9publicaine au Congr\u00e8s. Il faut bien comprendre la signification de cet \u00e9chec : le parti r\u00e9publicain a vu une partie de des \u00e9lus \u00e0 la Chambre refuser de voter l&rsquo;abrogation parce que ce qui \u00e9tait pr\u00e9vu en remplacement ne leur donnait aucune satisfaction en continuant \u00e0 faire la part trop belle aux diverses industries concern\u00e9es (assurances, industrie pharmaceutique) aux d\u00e9pens du citoyen. L&rsquo;\u00e9chec est donc d&ucirc; \u00e0 une d\u00e9fection justifi\u00e9e d&rsquo;une minorit\u00e9 populiste du parti r\u00e9publicain (<em>The Freedom Caucus<\/em>), tandis que l&rsquo;administration Trump \u00e9lue pour faire une r\u00e9forme radicale se r\u00e9v\u00e8le aussi corrompue que les pr\u00e9c\u00e9dentes, ainsi bien entendu que le \u00ab\u00a0parti unique\u00a0\u00bb (la majorit\u00e9 du parti r\u00e9publicain [aile droite du \u00ab\u00a0parti unique\u00a0\u00bb] et le parti d\u00e9mocrate [aile gauche, avec ses pseudo-dissidents totalement impuissants, comme Bernie Sanders]). <strong>Le d\u00e9sordre et l&rsquo;impuissance de Washington sont b\u00e2tis sur une corruption end\u00e9mique du <em>Corporate Power<\/em>, Trump ou pas Trump<\/strong>.<\/p>\n<\/p>\n<p><p>(La bataille en cours autour et contre le pr\u00e9sident Trump ne peut cacher que son administration est totalement infiltr\u00e9e par le pouvoir financier, notamment Goldman Sachs. Nous sommes dans une situation de corruption \u00e0 plusieurs \u00e9tages qui caract\u00e9rise Washington D.C. : absolument corrompu [le \u00ab\u00a0parti unique\u00a0\u00bb], puis des nuances dans lesquelles on trouve un Trump ou diverses tendances minoritaires, &ndash; les uns et les autres \u00ab\u00a0un peu, beaucoup, passionn\u00e9ment\u00a0\u00bb corrompus.)<\/p>\n<\/p>\n<p><p>Un autre passage du texte de WND met en \u00e9vidence cette actualit\u00e9 qui soutient puissamment la d\u00e9marche pour une Convention Constitutionnelle et devrait l&rsquo;acc\u00e9l\u00e9rer : &laquo; <em>Mark Meckler, co-founder of the Convention of States Project, said when the House of Representatives passed a bill that failed to fully repeal Obamacare earlier this month, it only served as further evidence that Republican control at the federal level is not enough to ensure the changes America needs. <\/em><em>Rather, he said, the states and the people must be empowered to take control of the country&rsquo;s destiny.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0I think for a lot of people there was a momentary pause and a sigh of relief when Trump was elected, that this might fix things, and certainly it&rsquo;s better that he was elected than Hillary Clinton was elected,\u00a0\u00bb Meckler told WND. \u00ab\u00a0But what we&rsquo;ve seen is that Congress doesn&rsquo;t have, and frankly never had, the will to take power away from itself and from Washington, D.C., and give it back to the people.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Il faut bien comprendre, nous semble-t-il, que ce mouvement n&rsquo;a rien d&rsquo;insurrectionnel, de \u00ab\u00a0populiste\u00a0\u00bb, de marginal, voire d&rsquo;antiSyst\u00e8me de notre point de vue, m\u00eame s&rsquo;il suit \u00e9videmment les orientations de toutes ces tendances et, d&rsquo;une certaine fa\u00e7on, les incorpore parce qu&rsquo;il va <strong>dans leur sens qui est de refuser pour des raisons diverses la dictature du \u00ab\u00a0centre\u00a0\u00bb-Syst\u00e8me washingtonien<\/strong>. Il s&rsquo;agit d&rsquo;abord d&rsquo;\u00e9lus, de l\u00e9gislatures, etc., qui viennent et\/ou font partie du Syst\u00e8me lui-m\u00eame. L&rsquo;inspirateur du mouvement est l&rsquo;ancien d\u00e9put\u00e9 puis s\u00e9nateur r\u00e9publicain de l&rsquo;Oklahoma Tom Coburn, Conseiller Principal du mouvement CSP (<em>Convention of States Project<\/em>). <a href=\"http:\/\/superstore.wnd.com\/smashing-the-DC-Monopoly-Tom-Coburn-Hardcover?promocode=MSTORY\">Son livre<\/a> au titre explicite (<em>Smashing the DC Monopoly: Using Article V to Restore Freedom and Stop America&rsquo;s Runaway Government<\/em>) sert de r\u00e9f\u00e9rence principale au mouvement, en exposant ce qui n&rsquo;est rien moins que l&rsquo;\u00e9chec d\u00e9cisif de l&rsquo;actuelle formule o&ugrave; le gouvernement f\u00e9d\u00e9ral poss\u00e8de tant de pouvoir. Un extrait de son introduction montre combien sa d\u00e9marche s&rsquo;appuie explicitement sur les r\u00e9f\u00e9rences aux P\u00e8res Fondateurs :<\/p>\n<\/p>\n<p><p>&laquo; <em>After sixteen years in Congress, it became chillingly clear to me that the constitutional safety feature in Article V had become necessary. Only the people could restore American ideals. Washington politicians could not and would not save us. Our steady delegation of power to and unhealthy dependence on our national government had lowered us to this condition<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The Founders, who had incorporated the \u00ab\u00a0experience of all ages\u00a0\u00bb in the Constitution, understood how the American people might someday have to save the republic from their central government. <\/em><em>We the People would have to assert our rightful sovereignty under the Constitution and rebalance our badly unbalanced federal government. <\/em><em>Washington had grown too self-interested, politically correct, and feckless to meet the challenge<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Le s\u00e9nateur Coburn et le projet CSP ont des soutiens importants et parfois paradoxaux mais dans le sens o&ugrave; ils montrent combien l&rsquo;actuelle situation aux USA, avec Trump \u00e0 la Maison-Blanche et la \u00ab\u00a0guerre civile\u00a0\u00bb \u00e0 Washington, est extr\u00eamement ambigu\u00eb. On trouve notamment l&rsquo;animateur de radio Mark Levin, dont la popularit\u00e9 est tr\u00e8s grande aux USA (&laquo; <em>The federal government is out of control. It&rsquo;s time for the states to take back control from Congress, and Senator Coburn explains how in this fantastic book<\/em> &raquo;). L&rsquo;ambigu\u00eft\u00e9 de la situation est soulign\u00e9e par le soutien d&rsquo;un membre important du gouvernement, le ministre de la justice Jeff Sessions :  &laquo; <em>Tom Coburn is one of the most remarkable senators who have served&#8230; <\/em><em>His whole philosophy and approach to government, had it been more effectively followed by other members of this body, would have led us to a better country<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La marche vers la d\u00e9-f\u00e9d\u00e9ralisation<\/h3>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat du ph\u00e9nom\u00e8ne CSP est qu&rsquo;il est fondamentalement conforme \u00e0 la fois au symbolisme, \u00e0 la v\u00e9rit\u00e9 officielle (<em>narrative<\/em>) et \u00e0 la psychologie fondamentale de l&rsquo;Am\u00e9rique originelle d&rsquo;une part, qu&rsquo;il est fondamentalement conforme \u00e0 la Loi fondamentale qui r\u00e9git la \u00ab\u00a0nation (!) exceptionnelle\u00a0\u00bb qu&rsquo;ordonne l&rsquo;esprit de la Constitution d&rsquo;autre part . \u00ab\u00a0<em>We the people<\/em>\u00a0\u00bb signifie \u00e0 Washington D.C. que les\/des \u00e9lus du peuple parlent au nom du peuple, et c&rsquo;est bien une \u00ab\u00a0conspiration d&rsquo;\u00e9lus\u00a0\u00bb \u00ab\u00a0au nom du peuple\u00a0\u00bb qui se d\u00e9veloppe avec le CSP, c&rsquo;est-\u00e0-dire une \u00ab\u00a0conspiration\u00a0\u00bb vertueuse du point de vue de l&rsquo;am\u00e9ricanisme officielle et des P\u00e8res Fondateurs. <strong>Il s&rsquo;agit donc d&rsquo;un mouvement issu d&rsquo;un \u00e9l\u00e9ment fondamental de la matrice originelle du Syst\u00e8me, et qui \u00e9volue dans un sens de plus en plus hostile au Syst\u00e8me, jusqu&rsquo;\u00e0 l&rsquo;\u00e9tat d&rsquo;antiSyst\u00e8me peut-on esp\u00e9rer. <\/strong>Bien entendu, la presseSyst\u00e8me se garde de faire une trop grande publicit\u00e9 \u00e0 la chose, pr\u00e9f\u00e9rant la chasse aux fascistes et aux pro-russes ; cette discr\u00e9tion, ce silence, sont bien le signe de l&rsquo;importance de la chose. Aujourd&rsquo;hui, tout ce dont la presseSyst\u00e8me ne dit mot est susceptible d&rsquo;\u00eatre la chose la plus importante qui soit.<\/p>\n<\/p>\n<p><p>(C&rsquo;est une des rares certitudes au niveau de la communication : la stupidit\u00e9-b\u00eatise align\u00e9e de la presseSyst\u00e8me rec\u00e8le <em>a contrario<\/em>, du fait de ce qu&rsquo;elle nous cache et que nous savons bien ou finissons par bien savoir, des <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a> d&rsquo;une inestimable valeur. Si elle se garde bien de faire ses gros titres sur le CSP, lui pr\u00e9f\u00e9rant les secrets hyper-<em>classified<\/em> que Trump file \u00e0 Lavrov dans une enveloppe innocente \u00e0 l&rsquo;adresse du FSB, <strong>c&rsquo;est que l&rsquo;affaire du CSP est d&rsquo;une importance fondamentale<\/strong>. &Eacute;crivant cela, nous n&rsquo;accusons m\u00eame pas la presseSyst\u00e8me : non, elle est trop engonc\u00e9e dans sa sablonneuse stupidit\u00e9 et dans sa b\u00eatise boueuse pour mesurer ce que le CSP a d&rsquo;important. Elle a perdu de vue les P\u00e8res Fondateurs depuis un certain temps d\u00e9j\u00e0 ; elle \u00e9gare, dans son hyst\u00e9rie furieuse, la m\u00e9moire du Syst\u00e8me lui-m\u00eame&#8230;)<\/p>\n<\/p>\n<p><p>Ce que le CSP d\u00e9veloppe, c&rsquo;est la reconnaissance de l&rsquo;insupportabilit\u00e9 de poursuivre avec un tel gouvernement que celui que nous dispense Washington D.C. Pour les &Eacute;tats, il s&rsquo;agit d&rsquo;admettre qu&rsquo;il devient insupportable de voir leurs sorts budg\u00e9taires li\u00e9s aux \u00ab\u00a0folies du Roi-Washington\u00a0\u00bb : tout comme le roi George d&rsquo;Angleterre qui d\u00e9clencha la col\u00e8re et l&rsquo;insurrection des colonies d&rsquo;Am\u00e9rique, Washington D.C. est fou. Sa dette nage dans les dizaines de milliers de milliards (<em>trillions)<\/em> de dollars. Peut-\u00eatre les illusionnistes de Wall Street s&rsquo;arrangent de la chose, ainsi que les innombrables \u00e9toiles du Pentagone, parce que tout cela vogue dans l&rsquo;univers enchant\u00e9 du Pays des merveilles (<em>WonderLand<\/em>) mais les &Eacute;tats c&rsquo;est diff\u00e9rent ; diff\u00e9rence entre le virtualisme de la <em>narrative<\/em> postmoderne et la v\u00e9rit\u00e9-de-situation du plouc moyen de l&rsquo;Am\u00e9rique dite-\u00ab\u00a0profonde\u00a0\u00bb. <strong>Ainsi le CSP nous rejouerait-il, folie contre folie, celle de washington D.C. contre celle du roi George, une sorte de 1776 mais \u00e0 l&rsquo;envers<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ce qui est s\u00e9rieux dans le CSP, c&rsquo;est non seulement que cela vienne d&rsquo;autorit\u00e9s officielles (y compris avec l&rsquo;appui d&rsquo;un ministre de poids de l&rsquo;administration \u00e0 Washington D.C.), <strong>mais surtout que cela prenne une voie mod\u00e9r\u00e9e<\/strong>. On ne parle pas de guerre civile, de s\u00e9cession, etc., non, mais simplement de priver Washington D.C. de certains de ses pouvoirs. Dans cette sorte d&rsquo;affaires o&ugrave; vous voulez d\u00e9pouiller un pouvoir central de \u00ab\u00a0certains de ses pouvoirs\u00a0\u00bb parce qu&rsquo;il est \u00ab\u00a0<em>out of control<\/em>\u00ab\u00a0, d&rsquo;une part cela veut dire que vous en viendrez \u00e0 le priver de tous ses pouvoirs parce que, sans tous ses pouvoirs et dans l&rsquo;humeur o&ugrave; il se trouve, <strong>Washington D.C. n&rsquo;est plus rien<\/strong>. D&rsquo;autre part, cette mod\u00e9ration de la d\u00e9marche qui rassemble pourtant les engagements des &Eacute;tats sur l&rsquo;essentiel et met au grand jour les exigence des &Eacute;tats,<strong> finit par transformer l&rsquo;alternative \u00ab\u00a0tous les pouvoirs \u00e0 Washington ou bien le CSP\u00a0\u00bb en \u00ab\u00a0le CSP ou bien la s\u00e9cession\u00a0\u00bb<\/strong> ; parce que, si Washington ne c\u00e8de pas d&rsquo;une fa\u00e7on ou l&rsquo;autre, si le CSP arriv\u00e9 \u00e0 sa maturit\u00e9 ne donne rien, <strong>la frustration des &Eacute;tats sera terrible et certains en viendront vite \u00e0 l&rsquo;id\u00e9e de l&rsquo;affirmation de leurs droits et de l&rsquo;affranchissement de la tutelle du \u00ab\u00a0centre\u00a0\u00bb par la s\u00e9cession<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Tout cela, ce beau raisonnement, vaut particuli\u00e8rement et \u00e9videmment si Washington D.C. continue son cirque. <strong>Quant \u00e0 cela, ce serait bien la chose dont nous serions le plus assur\u00e9s<\/strong> ; nous ne voyons pas une seconde comment quoi que ce soit pourrait transformer cet asile d&rsquo;ali\u00e9n\u00e9s travers\u00e9s de haines furieuses en une universit\u00e9 de la sagesse o&ugrave; la rigueur de la gestion et le bien-\u00eatre des gens redeviendraient des priorit\u00e9s. La haine, la vindicte, l&rsquo;hyst\u00e9rie, parcourues de paniques que l&rsquo;on mette \u00e0 jour les corruptions innombrables, de vertiges inconscients que le nihilisme de la non-politique activ\u00e9e en un tourbillon crisique finisse par \u00e9clater aux yeux de tous, <strong>tout cela est fait pour durer et s&rsquo;aggraver sans cesse<\/strong>, accroissant les raisons fondamentales des &Eacute;tats de trouver un moyen l\u00e9gal de litt\u00e9ralement castrer Washington D.C.<\/p>\n<\/p>\n<p><p>(On notera qu&rsquo;il s&rsquo;agit d&rsquo;ailleurs d&rsquo;un aspect tr\u00e8s difficile du commentaire : lorsque, par exemple, nous suivons l&rsquo;antirussisme d\u00e9cha&icirc;n\u00e9 et tous les soubresauts de la crise washingtonienne, nous ne pouvons que tenter d&rsquo;en montrer le ridicule, l&rsquo;absurdit\u00e9, l&rsquo;aspect faussaire et le simulacre. Mais il appara&icirc;t, dans ce cadre plus large o&ugrave; nous le pla\u00e7ons dans ce <em>F&#038;C<\/em>, <strong>que c&rsquo;est de notre int\u00e9r\u00eat profond que toutes ces choses malsaines et pourries se poursuivent et s&rsquo;accentuent \u00e0 Washington D.C.<\/strong> pour effectivement pousser les &Eacute;tats sur la voie d&rsquo;un amendement d\u00e9cisif de la Constitution ; ainsi devons-nous, parall\u00e8lement \u00e0 notre condamnation de cette pitoyable situation, l&rsquo;applaudir et l&rsquo;encourager \u00e0 poursuivre pour aller jusqu&rsquo;au bout de la catastrophe. Cela s&rsquo;appelle tr\u00e8s simplement et couramment \u00ab\u00a0vider l&rsquo;abc\u00e8s\u00a0\u00bb et, en g\u00e9n\u00e9ral, c&rsquo;est une op\u00e9ration fort peu agr\u00e9able.)<\/p>\n<\/p>\n<p><p>Nous pensons depuis longtemps, depuis les ann\u00e9es 2008-2010, que la question de la coh\u00e9sion des USA, et inversement de leur \u00e9ventuelle dissolution, est pos\u00e9e, notamment \u00e0 cause de la situation financi\u00e8re et budg\u00e9taire des USA comme c&rsquo;est le cas selon l&rsquo;analyse du CSP, mais surtout et d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale,<strong> \u00e0 cause de la crise fondamentale du pouvoir de l&rsquo;am\u00e9ricanisme \u00e0 laquelle finalement s&rsquo;adresse le CSP<\/strong>. A ceux qui opposent le patriotisme am\u00e9ricain comme un \u00ab\u00a0ciment\u00a0\u00bb susceptible de r\u00e9sister \u00e0 bien des chocs, nous avons toujours r\u00e9pondu par ce que nous jugeons \u00eatre les fondements principaux des &Eacute;tats-Unis, ce qui fait que ce pays existe \u00ab\u00a0historiquement\u00a0\u00bb tel qu&rsquo;il est et en mettant de c\u00f4t\u00e9 les divers complexit\u00e9s et fantasmes psychologisues ; notre id\u00e9e exprim\u00e9e d&rsquo;une mani\u00e8re \u00e0 peine caricaturale est bien celle d&rsquo;une entit\u00e9 de caract\u00e8re commercial dont la raison d&rsquo;\u00eatre est celle qui met ensemble des actionnaires (au contraire des &Eacute;tats de l&rsquo;Union pris individuellement, qui disposent souvent, avec leur anciennet\u00e9 et leurs traditions historiques, d&rsquo;une certaine vertu et d&rsquo;une l\u00e9gitimit\u00e9 souveraines, et par cons\u00e9quent d&rsquo;un patriotisme local). Sur cet aspect de la question, nous \u00e9crivions le <a href=\"http:\/\/www.dedefensa.org\/article\/justement-pense-limpensable-effondrement-des-usa\">9 juin 2015<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Il faut bien entendu rappeler que cet id\u00e9e du ciment de l&rsquo;Am\u00e9rique reposant sur le &lsquo;succ\u00e8s&rsquo;, qui peut \u00eatre aussi nomm\u00e9 &lsquo;int\u00e9r\u00eat&rsquo;, est parfaitement identifi\u00e9e par Tocqueville d\u00e8s ses premiers jours pass\u00e9s aux USA, lors de son voyage de 1831 qui servit de documentation \u00e0 son &lsquo;De la d\u00e9mocratie en Am\u00e9rique&rsquo; ; ainsi \u00e9crit-il dans ses &lsquo;Souvenirs&rsquo;, \u00e0 la date du 1er juin 1831 : \u00ab\u00a0Quand on r\u00e9fl\u00e9chit \u00e0 la nature de cette soci\u00e9t\u00e9-ci, on voit jusqu&rsquo;\u00e0 un certain point l&rsquo;explication de ce qui pr\u00e9c\u00e8de: la soci\u00e9t\u00e9 am\u00e9ricaine est compos\u00e9e de mille \u00e9l\u00e9ments divers nouvellement rassembl\u00e9s. Les hommes qui vivent sous ses lois sont encore anglais, fran\u00e7ais, allemands, hollandais. Ils n&rsquo;ont ni religion, ni m&oelig;urs, ni id\u00e9es communes; jusqu&rsquo;\u00e0 pr\u00e9sent on ne peut dire qu&rsquo;il y ait un caract\u00e8re am\u00e9ricain \u00e0 moins que ce soit celui de n&rsquo;en point avoir. Il n&rsquo;existe point ici de souvenirs communs, d&rsquo;attachements nationaux. Quel peut donc \u00eatre le seul lien qui unisse les diff\u00e9rentes parties de ce vaste corps? L&rsquo;<strong>int\u00e9r\u00eat.<\/strong>\u00a0\u00bb Le patriotisme des Am\u00e9ricains, qui sert si souvent d&rsquo;arguments aux intellectuels europ\u00e9ens et de convenance \u00e0 toutes les activit\u00e9s de communication US (jusqu&rsquo;\u00e0 la pr\u00e9sence oblig\u00e9e d&rsquo;un drapeau US dans tous les films US) est, justement, une construction de communication qui concerne un &lsquo;id\u00e9al&rsquo; fabriqu\u00e9 (type-American Dream) sans le moindre rapport avec la v\u00e9rit\u00e9 de la situation am\u00e9ricaniste ; s&rsquo;il tient la situation en temps normal par une narrative de strict encadrement, cet id\u00e9al faussaire a pour effet d&rsquo;alimenter, dans les p\u00e9riodes de crise int\u00e9rieure, lorsque le soi-disant &lsquo;succ\u00e8s&rsquo; am\u00e9ricaniste s&rsquo;efface, une ranc&oelig;ur et un d\u00e9faitisme extraordinaires devant ce qui n&rsquo;appara&icirc;t alors que comme le montage d&rsquo;une imposture, et donc une double trahison (l&rsquo;id\u00e9al lui-m\u00eame trahi, et la construction faussaire de cet id\u00e9al apparue en pleine lumi\u00e8re comme une autre trahison)<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, ce processus CSP met pleinement en lumi\u00e8re le caract\u00e8re fondamental, sinon d\u00e9cisif, de la crise de Washington D.C., et du pouvoir de l&rsquo;am\u00e9ricanisme. Clairement, l'\u00a0\u00bbexp\u00e9rience Trump\u00a0\u00bb n&rsquo;est nullement per\u00e7ue comme id\u00e9ologique ni partisane, &ndash; ces billeves\u00e9es qui encombrent la presseSyst\u00e8me et la perception des Europ\u00e9ens qui suivent \u00e0 leur fa\u00e7on le processus de l&rsquo;explosion de l&rsquo;am\u00e9ricanisme, en pr\u00e9parant de leur c\u00f4t\u00e9 leur propre bombe qui les fera exploser, &ndash; mais bien comme<strong> l&rsquo;ultime tentative pour que le pouvoir de Washington D.C. montre s&rsquo;il a encore une capacit\u00e9 de fonctionner, dans l&rsquo;hypoth\u00e8se extr\u00eame<\/strong> de la venue \u00e0 sa t\u00eate d&rsquo;une personnalit\u00e9 non issue de la bureaucratie des partis&#8230; <strong>Clairement, le verdict est d&rsquo;ores et d\u00e9j\u00e0 n\u00e9gatif<\/strong>, ouvrant effectivement la voie \u00e0 l&rsquo;affirmation de la seule possibilit\u00e9 d&rsquo;\u00e9volution, qui est une d\u00e9-f\u00e9d\u00e9ralisation, c&rsquo;est-\u00e0-dire <strong>une dissolution de la structure mise en place pour servir d&rsquo;outil central du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>Si l&rsquo;on admet l&rsquo;hypoth\u00e8se, \u00e9vidente pour nous, que l&rsquo;architecture-Syst\u00e8me op\u00e9rationnalis\u00e9e par le pouvoir de l&rsquo;am\u00e9ricanisme (Washington D.C.) a pour but essentiel <strong>la d\u00e9construction et la d\u00e9structuration, \u00e0 l&rsquo;image de la philosophie de la d\u00e9construction caract\u00e9risant la postmodernit\u00e9<\/strong>, on se trouve alors devant <strong>un processus de \u00ab\u00a0d\u00e9construction vertueuse\u00a0\u00bb par dissolution, constituant l&rsquo;acte essentiel de la crise d&rsquo;effondrement du Syst\u00e8me<\/strong>. Effectivement, notre conception selon laquelle l&rsquo;enti\u00e8ret\u00e9 du Syst\u00e8me tient, pour sa structure-d\u00e9structurante, dans la coh\u00e9sion et la puissance des USA, tant au niveau du syst\u00e8me du technologisme pour la puissance bien entendu, qu&rsquo;au niveau de la communication surtout, par la fascination exerc\u00e9e par les USA sur les conceptions de la postmodernit\u00e9, <strong>cette destruction de la coh\u00e9sion des USA constituerait un acte cathartique d\u00e9cisif<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;\u00e9tait cela que nous avancions, par exemple, le <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-lavenir-des-usa\">29 octobre 2009<\/a>, en mettant en \u00e9vidence l&rsquo;aspect psychologique, essentiel pour nous, <strong>de la fascination qu&rsquo;exercent sur nos psychologies les USA au nom du Syst\u00e8me, et cette fascination conditionnant l&rsquo;existence, l&rsquo;ontologie faussaires de la postmodernit\u00e9<\/strong> : &laquo; <em>Nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit et nous le r\u00e9p\u00e9tons avec force : il ne peut y avoir, aujourd&rsquo;hui, d&rsquo;\u00e9v\u00e9nements plus important pour la situation du monde qu&rsquo;une dynamique de dislocation des USA. Nous pensons que la crise actuelle est \u00e0 la fois, et contradictoirement, formidablement amplifi\u00e9e et formidablement bloqu\u00e9e dans sa compr\u00e9hension par la puissance de la communication. Ce ph\u00e9nom\u00e8ne ne cesse de dramatiser et d&rsquo;attiser les conditions de la crise tout en renfor\u00e7ant la pression du conformisme de la pens\u00e9e dominante pour ne pas mettre en cause les \u00e9l\u00e9ments qui sont les fondements de cette crise.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;un des fondements est psychologique, avec le ph\u00e9nom\u00e8ne de fascination &ndash; \u00e0 nouveau ce mot &ndash; pour l&rsquo;attraction exerc\u00e9e sur les esprits par le \u00ab\u00a0mod\u00e8le am\u00e9ricaniste\u00a0\u00bb, qui est en fait la repr\u00e9sentation \u00e0 la fois symbolique et onirique de la modernit\u00e9. C&rsquo;est cela qui est r\u00e9sum\u00e9 sous l&rsquo;expression populaire mais tr\u00e8s substantiv\u00e9e de American Dream. Cette repr\u00e9sentation donn\u00e9e comme seule issue possible de notre civilisation (le facteur dit TINA, pour \u00ab\u00a0There Is No Alternative\u00a0\u00bb) infecte la plupart des \u00e9lites en place; elle repr\u00e9sente un verrou d&rsquo;une puissance inou\u00efe, qui compl\u00e8te d&rsquo;une fa\u00e7on tragique la \u00ab\u00a0fascination de l&rsquo;am\u00e9ricanisme pour sa propre destin\u00e9e catastrophique\u00a0\u00bb pour former une situation totalement bloqu\u00e9e emp\u00eachant de chercher une autre voie tout en d\u00e9gringolant vers la catastrophe. La fin de l&rsquo;American Dream, qui interviendrait avec un processus de parcellisation de l&rsquo;Am\u00e9rique, constituerait un facteur d\u00e9cisif pour d\u00e9bloquer notre perception, \u00e0 la fois des conditions de la crise, de la gravit\u00e9 ontologique de la crise et de la n\u00e9cessit\u00e9 de tenter de chercher une autre voie pour la civilisation &ndash; ou, plus radicalement, une autre civilisation<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triste(s) &Eacute;tat(s) de l&rsquo;Union 19 mai 2017 &ndash; Nous nous int\u00e9ressons \u00e0 une dynamique assez peu mise en \u00e9vidence, du point de vue de la communication ; on lui pr\u00e9f\u00e8re manifestement les diverses jacasseries plus ou moins putschistes de Washington D.C., &ndash; sans prendre garde au fait que ces jacasseries alimentent \u00e9videmment cette dynamique discr\u00e8te.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5816,3612,9665,4518,7423,3276,3613,13046,4014,3784,13045,2639],"class_list":["post-77272","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-amendement","tag-american","tag-coburn","tag-constitution","tag-convention","tag-csp","tag-dream","tag-missouri","tag-of","tag-project","tag-states","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77272"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77272\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}