{"id":77280,"date":"2017-05-24T09:59:04","date_gmt":"2017-05-24T09:59:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/24\/une-melee-didiots-et-de-simulacres\/"},"modified":"2017-05-24T09:59:04","modified_gmt":"2017-05-24T09:59:04","slug":"une-melee-didiots-et-de-simulacres","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/24\/une-melee-didiots-et-de-simulacres\/","title":{"rendered":"Une m\u00eal\u00e9e d&rsquo;idiots et de simulacres"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une m\u00eal\u00e9e d&rsquo;idiots et de simulacres<\/h2>\n<\/p>\n<blockquote>\n<p><p>Le passage-\u00e9clair mais extr\u00eamement pesant du pr\u00e9sident &Eacute;tats-Unis et de sa caravane au Moyen-Orient (o&ugrave; l&rsquo;on signale que <a href=\"https:\/\/sputniknews.com\/us\/201705221053873588-melania-trump-swats-donald-trump\/\">Melania Trump<\/a> tra&icirc;ne de plus en plus les pieds qu&rsquo;elle a ravissants) a constitu\u00e9 <strong>la mise en place ultra-rapide d&rsquo;un simulacre que Trump entend affirmer pour tenter d&rsquo;\u00e9touffer celui qui a \u00e9t\u00e9 construit autour de <a href=\"http:\/\/www.dedefensa.org\/article\/russiagate-simulacre-extreme\"><em>Russiagate<\/em><\/a><\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En quelques jours, \u00e0 coup de discours et de promesses diverses, il a ralli\u00e9 \u00e0 lui quelques forces importantes qui participent \u00e0 la structure du Syst\u00e8me et au d\u00e9veloppement de la politiqueSyst\u00e8me :<\/p>\n<\/p>\n<p><p>&bull; Les princes de la maison Saoud, leur fric par $milliards, leur profonde veulerie politique et leur prodigieuse capacit\u00e9 de corruption, leur volont\u00e9 incroyable de pr\u00e9tendre dominer la r\u00e9gion comme si la mati\u00e8re la plus vile mang\u00e9e par la pourriture dont ils sont constitu\u00e9s pouvait pr\u00e9tendre \u00e0 l&rsquo;affirmation d&rsquo;une volont\u00e9 structur\u00e9e.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;appareil isra\u00e9lien dans son aspect le plus sordide, notamment dans sa connexion avec l&rsquo;appareil de corruption install\u00e9 \u00e0 Washington sous la forme de l&rsquo;AIPAC.<\/p>\n<\/p>\n<p><p>&bull; Enfin, pour unir ces deux forces dans leur commune haine sans fin contre une troisi\u00e8me, une affirmation d&rsquo;une hostilit\u00e9 agressive contre l&rsquo;Iran, pr\u00e9sent\u00e9 d&rsquo;une fa\u00e7on grotesque comme le centre du terrorisme et implicitement menac\u00e9 de terribles repr\u00e9sailles. (Les $350 milliards d&rsquo;armement sur les prochaines ann\u00e9es, plus les deux ou trois premiers F-35 livr\u00e9s aux Isra\u00e9liens pour \u00eatre parqu\u00e9s bien en \u00e9vidence, sont prmi les mesuresde renforcement de l&rsquo;arsenal anti-iranien.)<\/p>\n<\/p>\n<p><p>On a d\u00e9j\u00e0 dit la forme <a href=\"http:\/\/www.dedefensa.org\/article\/telerealite-pour-vomir\">de d\u00e9go&ucirc;t primaire<\/a> que provoque cette initiative de Trump en mati\u00e8re de ce qu&rsquo;il est vraiment tr\u00e8s difficile de d\u00e9signer comme une politique \u00e9trang\u00e8re. (Voir le <em>Journal-dde.crisis<\/em> de PhG du 23 mai 2017.) Pourtant, l&rsquo;initiative a attir\u00e9 un certain soutien de certaines forces au sein du Syst\u00e8me, \u00e0 Washington D.C. Le signe principal de la chose est <a href=\"http:\/\/www.zerohedge.com\/news\/2017-05-23\/america-worst-america-first-one-presidency\">un article<\/a> de John Freeman dans le <a href=\"https:\/\/www.wsj.com\/articles\/the-unapologetic-american-1495489950?mod=rss_Best_of_the_Web_Today\u00a3\">Wall Street <em>Journal<\/em><\/a>, sous le titre &laquo; <em>The Unapologetic American &ndash; Donald Trump brings a new message to the Middle East <\/em>&raquo;, qui compare \u00e0 l&rsquo;avantage de Trump l&rsquo;homme de \u00ab\u00a0l&rsquo;Am\u00e9rique redevenue forte\u00a0\u00bb, les discours d&rsquo;Obama <a href=\"http:\/\/www.dedefensa.org\/article\/obama-et-la-chute-de-mossadegh-en-1953\">en 2009 au Caire<\/a> et celui de Trump \u00e0 Ryad en 2017. On doit se pincer sans am\u00e9nit\u00e9 pour lire cet article sans \u00e9prouver d&rsquo;angoisse devant l&rsquo;extraordinaire puissance de la sottise cr\u00e9atrice d&rsquo;autant de simulacres qu&rsquo;il y a de pr\u00e9jug\u00e9s en activit\u00e9 surpuissante \u00e0 Washington D.C., entre les divers et tr\u00e8s nombreux points de ravitaillement de la corruption obligatoire&#8230;.<\/p>\n<\/p>\n<p><p>&laquo; <em>President Donald Trump&rsquo;s Sunday address in Saudi Arabia was bound to inspire comparisons to the speech Barack Obama delivered in Cairo, Egypt at a similar point in his young presidency. And just like his predecessor, Mr. Trump expressed gratitude and respect for his hosts. But the 45th U.S. President quickly made clear that he did not fly to the Middle East on his first overseas trip in order to explain what&rsquo;s wrong with America<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>It would be a crude overstatement to say that the message has gone from America worst to America first in one presidency. Mr. Obama did speak favorably of his country several times during his Cairo address. But the difference between Barack Obama&rsquo;s speech in 2009 and the Trump remarks on Sunday in Riyadh is striking<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Suit une litanie de citations du discours d&rsquo;Obama au Caire en juin 2009, compar\u00e9 a discours de Trump \u00e0 Ryad en 2017 : de l'\u00a0\u00bbAm\u00e9rique coupable et honteuse\u00a0\u00bb (version Obama) \u00e0 l'\u00a0\u00bbAm\u00e9rique forte et triomphante\u00a0\u00bb (Trump). Il est difficile de r\u00e9sister \u00e0 la stup\u00e9faction devant l&rsquo;absurdit\u00e9 de cette synth\u00e8se, quand on conna&icirc;t le destin d&rsquo;Obama, interventionniste et \u00ab\u00a0assassin-l\u00e9gal\u00a0\u00bb (drones et Cie) N&deg;1 de la Maison-Blanche, et Trump, homme-t\u00e9l\u00e9r\u00e9alit\u00e9 roul\u00e9 dans la boue pour \u00eatre un tra&icirc;tre soldant l&rsquo;Am\u00e9rique \u00e0 l&rsquo;ignominie russe et d\u00e9clarant il y a peu que l&rsquo;Am\u00e9rique devait se replier, oublier ses absurdes postures interventionnistes et ainsi de suite&#8230; Tout cela, pour deux discours et additions de simulacres antagonistes, <strong>tant la politique US et la situation washingtonienne ne sont plus faits que de tels actes vides de toute ontologie<\/strong>.<\/p>\n<\/p>\n<p><p>La fin de l&rsquo;article du WSJ vaut son pesant de <em>gay prides<\/em> puisqu&rsquo;on y d\u00e9peint implicitement Obama comme un machiste, anti-LGTBQ, tandis que, par logique contradictoire, Trump devait figurer dans les imaginaires des lecteurs comme le progressiste-LGTBQ par excellence&#8230; \u00ab\u00a0Cet article, termine le WSJ, est \u00e9crit dans l&rsquo;espoir que de nombreux auditeurs outremer [lire ROW] trouveront de nouvelles esp\u00e9rances dans ces messages de l&rsquo;Am\u00e9rique qui ne s&rsquo;excuse de rien du tout\u00a0\u00bb : brut de fonderie, entre drones et massacres des diverses populations, irakiennes, afghanes, syriennes, y\u00e9m\u00e9nites, etc.<\/p>\n<\/p>\n<p><p>&laquo; <em>By the way, this column should note that perhaps the most striking comment when one looks back at Mr. Obama&rsquo;s 2009 remarks has little to do with U.S. foreign policy, but underlines how far and how quickly the Democratic Party has moved on issues of sexual identity. <\/em><em>Toward the end of his speech, Mr. Obama said, \u00ab\u00a0The Holy Koran tells us: &lsquo;O mankind! We have created you male and a female; and we have made you into nations and tribes so that you may know one another.'\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Referencing that line today in the era of transgender politics would have progressives back in the U.S. shrieking for a safe space. As for the safety of the entire civilized world in its fight against Islamic terror, this column expects that many overseas listeners will find reassurance in a message from America without apologies<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>devrait-on croire que la chose signale une contre-offensive victorieuse de Trump sur tous les fronts, notamment \u00e0 Washington D.C. plein des \u00e9chos du <em>Russiagate<\/em> ? PhG avait laiss\u00e9 entendre que <a href=\"http:\/\/www.dedefensa.org\/article\/telerealite-pour-vomir\">non, pas du tout<\/a> : &laquo; <em>Ceux-l\u00e0 sont tellement prisonniers de leur <a href=\"http:\/\/www.dedefensa.org\/article\/russiagate-simulacre-extreme\">simulacre<\/a> fabriqu\u00e9 sur les emportements furieux et aveugles de leur psychologie hyst\u00e9rique que, malgr\u00e9 un soudain <a href=\"http:\/\/www.wsws.org\/fr\/articles\/2017\/mai2017\/wpnt-m23.shtml\">conseil de freinage<\/a> de l&rsquo;antitrumpiste dans les \u00e9ditoriaux (le 21 mai) curieusement similaires du WaPo et du NYT, <strong>ils continuent dans <a href=\"http:\/\/dailycaller.com\/2017\/05\/22\/msnbc-ruthlessly-cuts-to-trump-coverage-as-manchester-victims-scream-in-background-video\/\">le m\u00eame sens<\/a>, y compris <a href=\"https:\/\/www.washingtonpost.com\/world\/national-security\/trump-asked-intelligence-chiefs-to-push-back-against-fbi-collusion-probe-after-comey-revealed-its-existence\/2017\/05\/22\/394933bc-3f10-11e7-9869-bac8b446820a_story.html?utm_term=.f7a7e577065a\">le WaPo lui-m\u00eame<\/a><\/strong> qui ne semble pas capable de refreiner les incontinences inextinguible de sa haine antitrumpiste<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette observation est largement substantiv\u00e9e par quelques commentaires du colonel Lang, sur son site <em>Sic semper Tyrannis<\/em>. Lang observe que <strong>l&rsquo;activisme des partisans du <em>Russiagate<\/em> n&rsquo;en d\u00e9mord par une seconde<\/strong> malgr\u00e9 le voyage triomphal au c&oelig;ur de la corruption globalis\u00e9e du Moyen-Orient qui devrait absolument plaire au <em>Deep State<\/em> et \u00e0 l&rsquo;<em>establishment<\/em>. C&rsquo;est que l&rsquo;un et l&rsquo;autre (<em>Deep State<\/em> et <em>establishment<\/em>) continuent \u00e0 soutenir tous les simulacres en cours d&rsquo;affrontement, et notamment, dans ce cas, \u00e9galement l&rsquo;activisme-<em>Russiagate<\/em> qui continue \u00e0 faire de Trump d&rsquo;Arabie un tra&icirc;tre vicieux et sordide au service des Russes. De cette fa\u00e7on et selon cette logique, <a href=\"http:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2017\/05\/tidbits-23-may-2017.html\">nous dit Lang<\/a>, \u00ab\u00a0la presseSyst\u00e8me attend avec impatience le retour de Trump pour en revenir \u00e0 son objectif fondamental, &ndash; la destitution\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&laquo; <strong><em>Media meltdown over President Trump<\/em><\/strong><em>.  The ravening MSM types in most of the available platforms for propaganda are eagerly awaiting DT&rsquo;s return from overseas so that it can get on with the its basic objective &#8211; impeachment.  Neither CNN nor MSNBC makes any effort in disguising their essential focus on impeachment.  The level of their fascination with this now extends to their network  news services own advertising.  MSNBC now runs a staged ad in which a woman reporter is portrayed as chasing a congressman down a hallway while baQSQS&gt;EEddgering him for &quot;answers&quot; to hypotheticals as to what he will do if Trump is &quot;proven&quot; to have obstructed justice.  It is now evident (to me) that &quot;obstruction of justice&quot; will be the main thrust of the impeachment drive.  Mueller&rsquo;s investigation of Comey&rsquo;s various statements, memos and the like now seems to be intended to elicit evidence of President Trumps supposed obstruction.  <\/em><em>Since he has a grand jury at his disposal and is conducting a criminal investigation (as opposed to the congressional counter-intelligence investigations) Mueller&rsquo;s investigation could easily result in an indictment of President Trump.  <\/em><em>IMO that would trigger an resolution of impeachment in the House of Representative.  DNI Dan Coats declined this morning before the US Senate to state that Trump had tried to persuade him to help in shutting down the Russia collusion investigations.  This is probably a preview of what others may say to Mueller under oath.  This may well be the crack of doom for Trump<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Ainsi se retrouve-t-on effectivement <strong>dans un affrontement de simulacres<\/strong>, &ndash; celui de Trump parti en caravane jusqu&rsquo;au trou du cul de la corruption du monde, \u00e0 Ryad, valant bien celui de <em>Russiagate<\/em> dans les rets duquel il se d\u00e9bat. C&rsquo;est-\u00e0-dire qu&rsquo;il y a implicitement affrontement furieux et plein d&rsquo;agressivit\u00e9 entre deux simulacres qui suscitent et stimulent des d\u00e9bats et des d\u00e9clarations du type civilisationnel absolument vides de sens et sans la moindre ontologie comme tout v\u00e9ritable simulacre ; pour cela, ils ont choisi <strong>un mode contradictoire et antagoniste rempli de haines sans retour qui ne cesse de les affaiblir mutuellement.<\/strong><\/p>\n<\/p>\n<p><p>Cela se fait, on l&rsquo;aura bien compris, <strong>entre les deux branches de la m\u00eame politique<\/strong>. Il y a d&rsquo;un c\u00f4t\u00e9 l&rsquo;interpr\u00e9tation interventionniste-belliciste, de l&rsquo;autre l&rsquo;interpr\u00e9tation progressiste soci\u00e9tale du m\u00eame ultra-lib\u00e9ralisme transmut\u00e9e en politiqueSyst\u00e8me par le grand Ordonnateur, &ndash; le Syst\u00e8me soi-m\u00eame. Ces deux branches sont l&rsquo;une et l&rsquo;autre n\u00e9cessaires \u00e0 cette <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> et au Syst\u00e8me, elles se compl\u00e8tent, elles se renforcent, &ndash; <strong>mais non, pas du tout ! <\/strong>Les voil\u00e0 qui s&rsquo;interpr\u00e8tent et se repr\u00e9sentent dans d&rsquo;incroyables simulacres vou\u00e9s \u00e0 cette m\u00eame haine inexpiable et sans retour pour pouvoir mieux s&rsquo;entred\u00e9chirer et se d\u00e9vorer \u00e0 belles dents. Il faut bien constater qu&rsquo;aujourd&rsquo;hui, <strong>une seule chose para&icirc;t r\u00e9ellement solide, consistante, permanente au c&oelig;ur du Syst\u00e8me, et c&rsquo;est bien la haine de soi-m\u00eame, &ndash;la haine du Syst\u00e8me pour lui-m\u00eame<\/strong>.<\/p>\n<\/p>\n<p><p>Mis en ligne le 24 mai 2017 \u00e0 09H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une m\u00eal\u00e9e d&rsquo;idiots et de simulacres Le passage-\u00e9clair mais extr\u00eamement pesant du pr\u00e9sident &Eacute;tats-Unis et de sa caravane au Moyen-Orient (o&ugrave; l&rsquo;on signale que Melania Trump tra&icirc;ne de plus en plus les pieds qu&rsquo;elle a ravissants) a constitu\u00e9 la mise en place ultra-rapide d&rsquo;un simulacre que Trump entend affirmer pour tenter d&rsquo;\u00e9touffer celui qui a&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8379,2773,2711,6208,13022,12619,2639],"class_list":["post-77280","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-caire","tag-iran","tag-le","tag-obama","tag-russiagate","tag-ryad","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77280"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77280\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}