{"id":77283,"date":"2017-05-25T17:32:48","date_gmt":"2017-05-25T17:32:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/25\/mon-simulacre-a-lorigine\/"},"modified":"2017-05-25T17:32:48","modified_gmt":"2017-05-25T17:32:48","slug":"mon-simulacre-a-lorigine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/25\/mon-simulacre-a-lorigine\/","title":{"rendered":"\u201cMon\u201d simulacre, \u00e0 l&rsquo;origine"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0Mon\u00a0\u00bb simulacre, \u00e0 l&rsquo;origine<\/h2>\n<\/p>\n<p><p>25 mai 2017 &ndash; J&rsquo;ai d\u00e9j\u00e0 dit, d&rsquo;une fa\u00e7on ou l&rsquo;autre, combien j&rsquo;ai avanc\u00e9 dans ma vie comme un autodidacte, entrant dans des domaines que je n&rsquo;avais jamais pr\u00e9cis\u00e9ment envisag\u00e9s pour moi-m\u00eame. Ainsi en est-il principalement des mati\u00e8res proches de la philosophie, de la m\u00e9taphysique, etc., autour desquelles il m&rsquo;arrive de plus en plus souvent de m&rsquo;agiter, qui m&rsquo;\u00e9taient inconnues \u00e0 l&rsquo;origine de ma carri\u00e8re. J&rsquo;ai fait cela, je l&rsquo;avoue, sans autorisation de l&rsquo;Universit\u00e9. J&rsquo;y suis venu de mani\u00e8re naturelle, empirique, parce qu&rsquo;en progressant j&rsquo;ai d\u00e9couvert combien cette progression n\u00e9cessitait de faire appel \u00e0 ces domaines.<\/p>\n<\/p>\n<p><p>Ainsi en est-il des mots et des concepts dans ces mati\u00e8res, qui permettent d&rsquo;appuyer et de structurer une pens\u00e9e, de la guider, de lui donner \u00e0 la fois des outils et des r\u00e9f\u00e9rences, de la faire progresser, parfois \u00e0 pas de g\u00e9ant, parfois de la r\u00e9volutionner. (On trouve de ces mots, ou concepts, bien s&ucirc;r dans le <em>Glossaire.dde<\/em>.) <strong>Ainsi en est-il du mot \u00ab\u00a0simulacre\u00a0\u00bb, dont on voit qu&rsquo;il est d&#8217;emploi r\u00e9p\u00e9t\u00e9 ces derniers temps sur le site<\/strong> : voil\u00e0 le point central justifiant ce texte aujourd&rsquo;hui, puisqu&rsquo;effectivement \u00ab\u00a0simulacre\u00a0\u00bb est apparu de nombreuses fois ces derniers jours.<\/p>\n<\/p>\n<p><p>Certes, je ne d\u00e9couvre pas le mot, qui est d&rsquo;un emploi courant et ancien (le latin <em>simulacrum <\/em>pour \u00ab\u00a0simulacre\u00a0\u00bb et <em>simulatio <\/em>pour \u00ab\u00a0feinte\u00a0\u00bb, \u00ab\u00a0faux-semblant\u00a0\u00bb, et \u00ab\u00a0simulation\u00a0\u00bb \u00e9videmment), ni m\u00eame sa signification, ni m\u00eame sa place (approximative pour moi, jusqu&rsquo;alors) dans la philosophie depuis si longtemps, au moins depuis Platon. Ce que je d\u00e9couvre peu \u00e0 peu, puis brusquement en v\u00e9rit\u00e9, c&rsquo;est son poids consid\u00e9rable pour moi-m\u00eame et pour le travail que j&rsquo;effectue, sa puissance ph\u00e9nom\u00e9nale et la complexit\u00e9 de sa signification depuis que je l&rsquo;ai adopt\u00e9 pour le consid\u00e9rer d&rsquo;un point de vue plus personnel, pour lui donner une place dans mon rangement dialectique (ou, disons, mon arsenal dialectique). C&rsquo;est dire, effectivement, que je me le suis appropri\u00e9 \u00e0 ma fa\u00e7on, selon mes conceptions, comme chaque esprit doit pouvoir faire en toute loyaut\u00e9 et en toute libert\u00e9, c&rsquo;est-\u00e0-dire en signalant, en expliquant et en d\u00e9finissant cet emprunt. On comprend ais\u00e9ment, par ailleurs, en lisant certaines pages r\u00e9centes de ce <em>Journal-dde.crisis<\/em> et du site lui-m\u00eame, combien le livre de Mattei, <em>L&rsquo;homme d\u00e9voy\u00e9<\/em>, m&rsquo;y a aid\u00e9.<\/p>\n<\/p>\n<p><p>(Sans m&rsquo;attarder une seconde \u00e0 juger de leur qualit\u00e9 relative [\u00ab\u00a0le plus grand\u00a0\u00bb, \u00ab\u00a0le plus important\u00a0\u00bb, etc.] ni m\u00eame de leur qualit\u00e9 absolue [\u00ab\u00a0chef d&rsquo;&oelig;uvre\u00a0\u00bb, etc.], je pr\u00e9ciserais ma conviction qu&rsquo;il y a des livres qui, convenant \u00e0 un esprit et \u00e0 sa qu\u00eate, donne \u00e0 cet esprit par une sorte de connivence spirituelle indescriptible le mat\u00e9riel et la force que lui donneraient cinquante autres livres qu&rsquo;on jugerait sans aucune h\u00e9sitation d&rsquo;une qualit\u00e9 relative et d&rsquo;une qualit\u00e9 absolues \u00e9gales. Les jugements et classements \u00e0 cet \u00e9gard n&rsquo;ont gu\u00e8re d&rsquo;importance \u00e0 mes yeux ; je les consid\u00e8re comme le produit de cette tendance \u00e0 la comp\u00e9tition typiquement de la modernit\u00e9, qui se fait croire \u00e9litiste et qui est en fait niveleuse en imposant \u00e0 chacun r\u00e8gles et normes de la comp\u00e9tition, et tend au bout du compte \u00e0 imposer un jugement conformiste. Ce qui m&rsquo;importe est <strong>ce rapport de connivence unique, d&rsquo;une grandeur et d&rsquo;une beaut\u00e9 \u00e9piques<\/strong>, lorsque ce ph\u00e9nom\u00e8ne survient entre un livre et un esprit, et de pouvoir ainsi se passer des cinquante autres. Rien ne me ravit plus que d&rsquo;entendre et de me r\u00e9p\u00e9ter ce jugement de Gustave Thibon : &laquo; <em>Voyez-vous, l&rsquo;important ce n&rsquo;est pas de lire beaucoup de livres, c&rsquo;est de lire en profondeur le peu qu&rsquo;on lit. Tout est dans tout. <\/em>&raquo;)<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Simulacre\u00a0\u00bb, donc. Bien entendu, le mot nous fait plonger dans le d\u00e9bat fondamental des rapports de l&rsquo;\u00eatre, ou de l&rsquo;ontologie, avec ce qu&rsquo;on nomme \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb, ce que je nommerais selon mon rangement \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">V\u00e9rit\u00e9 &#038; v\u00e9rit\u00e9-de-situation<\/a>\u00a0\u00bb dans une \u00e9poque o&ugrave; la communication a fracass\u00e9 toute r\u00e9alit\u00e9 possible. <strong>Le mot nous inscrit dans la crise catastrophique qu&rsquo;affrontent la pens\u00e9e et la psychologie de notre \u00e9poque, elle-m\u00eame catastrophique<\/strong>. Il nous plonge dans les agitations terribles de la postmodernit\u00e9, autour de cette pens\u00e9e absolument terrifiante de l&rsquo;\u00e9cole, ou plut\u00f4t de la non-\u00e9cole des d\u00e9constructeurs. Avant m\u00eame de m&rsquo;y reconna&icirc;tre un peu dans ce salmigondis philosophique, je m&rsquo;\u00e9tais forg\u00e9 mes propres conceptions, ou concepts, finalisant tout cela avec la formule <em><a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-dde-definition-et-usage-1\">dd&#038;e<\/a><\/em> (\u00ab\u00a0d\u00e9structuration, dissolution &#038; entropisation\u00a0\u00bb) con\u00e7ue comme la formule \u00ab\u00a0op\u00e9rationnalisant\u00a0\u00bb pour moi d&rsquo;une fa\u00e7on satisfaisante l&rsquo;action du Mal dans cette \u00e9poque sp\u00e9cifique. C&rsquo;est le <a href=\"http:\/\/www.dedefensa.org\/article\/du-social-au-societal-et-consequences\">30 avril 2013<\/a> que la formule avait \u00e9t\u00e9 utilis\u00e9e pour la premi\u00e8re fois sous cette forme si compl\u00e8te apr\u00e8s de nombreux emplois divers non encore conceptualis\u00e9s sous cette forme :<\/p>\n<\/p>\n<p><p>&laquo; <em>Si la question du Syst\u00e8me devient pressante d\u00e8s qu&rsquo;une pol\u00e9mique \u00ab\u00a0soci\u00e9tale\u00a0\u00bb est d\u00e9velopp\u00e9e sur le champ social laiss\u00e9 libre, c&rsquo;est parce qu&rsquo;elle implique n\u00e9cessairement la dynamique destructrice du Syst\u00e8me, &ndash; sp\u00e9cifiquement l&rsquo;\u00e9quation d\u00e9structuration-dissolution-entropisation (ou d\u00e9structuration, dissolution &#038; entropisation, que nous pourrions r\u00e9sumer sous le sigle \u00ab\u00a0dd&#038;e\u00a0\u00bb qui nous est cher puisque c&rsquo;est aussi celui de notre publication-papier initiale, \u00ab\u00a0dedefensa &#038; eurostrat\u00e9gie\u00a0\u00bb). L&rsquo;instinct social de la psychologie r\u00e9volt\u00e9e reconna&icirc;t imm\u00e9diatement cette attaque type-dd&#038;e, qui met en cause tout ce qui tient ensemble le champ social, les traditions, l&rsquo;organisation, etc., &ndash; bref, ce qu&rsquo;on a coutume de nommer \u00ab\u00a0civilisation\u00a0\u00bb&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Dans ces temps-l\u00e0 o&ugrave; je d\u00e9veloppais l&rsquo;id\u00e9e \u00ab\u00a0dd&#038;e\u00a0\u00bb, jusqu&rsquo;en 2013, je ne m&rsquo;int\u00e9ressais gu\u00e8re sur le fond et en fonction des \u00e9v\u00e9nements aux \u00ab\u00a0d\u00e9constructeurs\u00a0\u00bb (Deleuze, Derrida, Foucault). J&rsquo;ai commenc\u00e9 \u00e0 le faire d&rsquo;une mani\u00e8re appuy\u00e9e \u00e0 partir de l&rsquo;\u00e9poque ci-dessus (2013), lorsque je me suis aper\u00e7u avec quelle force, quelle puissance, quelle rapidit\u00e9, quelle directivit\u00e9 presqu&rsquo;impeccable, une \u00ab\u00a0\u00e9cole\u00a0\u00bb philosophique <strong>s&rsquo;\u00e9tait aussi compl\u00e8tement inscrite dans l&rsquo;op\u00e9rationnalisation des \u00e9v\u00e9nements d&rsquo;une \u00e8re compl\u00e8te<\/strong>. Bien entendu, on peut et on doit \u00e9galement consid\u00e9rer l&rsquo;inverse de cet \u00e9nonc\u00e9 venu sous la plume naturellement mais faussement (d\u00e9j\u00e0 une simulation !) : on peut et on doit consid\u00e9rer l&rsquo;hypoth\u00e8se qui, une fois \u00e9nonc\u00e9e, devient irr\u00e9sistible, que ce sont les \u00e9v\u00e9nements eux-m\u00eames, l'\u00a0\u00bbop\u00e9rationnel\u00a0\u00bb, qui ont fait na&icirc;tre ces philosophes et leur \u00ab\u00a0\u00e9cole\u00a0\u00bb. Les \u00e9v\u00e9nements, que je consid\u00e8re comme issus du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00a0\u00bb <strong>ont dict\u00e9 \u00e0 la philosophie soudain ouverte comme une plaie b\u00e9ante, avec une psychologie extraordinairement affaiblie, cet \u00e9lan de la d\u00e9construction<\/strong>.<\/p>\n<\/p>\n<p><p>(Mattei fait remonter les d\u00e9constructeurs dont on parle au romancier Maurice Blanchot, qui commen\u00e7a \u00e0 publier en 1943. Je consid\u00e9rerais bien, \u00e0 cet \u00e9gard, que la tendance d\u00e9constructrice de la simulation dans les \u00e9v\u00e9nements courants pour conduire au simulacre est apparue apr\u00e8s la Grande Guerre, que je consid\u00e8re comme le premier \u00e9v\u00e9nement tellurique majeur accouch\u00e9 par le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb. La Grande Guerre avait mis en \u00e9vidence les effets catastrophiques du Progr\u00e8s de fa\u00e7on tragique et apocalyptique, par ses caract\u00e8res \u00e9pouvantables de destruction par d\u00e9construction g\u00e9n\u00e9rale [y compris de l&rsquo;environnement], qui \u00e9taient dus au progr\u00e8s de la technologie li\u00e9e au Progr\u00e8s. De l\u00e0 est n\u00e9e \u00ab\u00a0naturellement\u00a0\u00bb la tendance puissante \u00e0 la dynamique de la simulation engendrant <strong>le simulacre du courant progressiste dominant pour dissimuler sinon \u00e9radiquer cette v\u00e9rit\u00e9 de l&rsquo;\u00e9chec du Progr\u00e8s dans sa production absolument catastrophique<\/strong>. Effectivement encore, c&rsquo;est \u00e0 partir de l\u00e0 que commenc\u00e8rent \u00e0 appara&icirc;tre, puis pullul\u00e8rent, dans divers domaines, des d\u00e9veloppements de d\u00e9structuration et de dissolution permettant le simulacre, notamment dans les arts.)<\/p>\n<\/p>\n<p><p>C&rsquo;est donc avec d\u00e9j\u00e0 beaucoup en t\u00eate \u00e0 cet \u00e9gard, que j&rsquo;ai accueilli le mot bien-connu de \u00ab\u00a0simulacre\u00a0\u00bb, pour soudain m&rsquo;en saisir et l&rsquo;inscrire dans mon \u00ab\u00a0arsenal dialectique\u00a0\u00bb. L\u00e0 aussi, les \u00e9v\u00e9nements me l&rsquo;ont impos\u00e9 dans la mesure o&ugrave; je crois qu&rsquo;avec la crise ukrainienne, puis d\u00e9sormais avec une puissance accrue, avec les \u00e9lections USA-2016 et avec le <em>Russiagate<\/em>, une nouvelle sorte d&rsquo;\u00e9v\u00e9nements de pure communication, impliquant si l&rsquo;on veut une sorte de \u00ab\u00a0virtualit\u00e9-r\u00e9elle\u00a0\u00bb, s&rsquo;est impos\u00e9e comme un facteur majeur de la situation crisique. Ces \u00e9v\u00e9nements peuvent \u00eatre parfaitement d\u00e9finis selon le classement que rappelle Mattei, depuis Platon : &laquo; <em>Au troisi\u00e8me niveau de r\u00e9alit\u00e9, on constate une rupture : la <strong>simulation <\/strong>se substitue \u00e0 la mod\u00e9lisation et \u00e0 la repr\u00e9sentation. Le simulacre, en tant que r\u00e9sultat de cette op\u00e9ration, poss\u00e8de un pouvoir de d\u00e9r\u00e9alisation des pr\u00e9c\u00e9dents niveaux de r\u00e9alit\u00e9 en raison de son proc\u00e8s de virtualisation. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ce qui est fondamental avec le <em>Russiagate<\/em> dont j&rsquo;ai avanc\u00e9 l&rsquo;hypoth\u00e8se qu&rsquo;il constitue quasiment une perfection dans l&rsquo;op\u00e9rationnalit\u00e9, c&rsquo;est qu&rsquo;il se r\u00e9alise, pour sa v\u00e9ritable constitution, hors de toutes les consid\u00e9rables capacit\u00e9s technologiques de simulation dont nous disposons \u00e0 cet \u00e9gard, et pr\u00e9cis\u00e9ment toutes les capacit\u00e9s consid\u00e9rables de simulation des technologies avanc\u00e9es de l&rsquo;informatique. Au contraire, j&rsquo;ai propos\u00e9 comme <strong>mat\u00e9riau essentiel de la construction de ce simulacre <em>Russiagate<\/em>, quelque chose d&rsquo;imm\u00e9morial qui est la psychologie<\/strong>. Je rappelle ici les deux passages qui mettent en-avant ce point si important, qui fait toute l&rsquo;originalit\u00e9 de <em>Russiagate<\/em>, dans le cadre de l&rsquo;antirussisme qui est une tr\u00e8s puissante d\u00e9formation de la psychologie, et qui constitue par contre l&rsquo;outil majeur \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>&laquo; <em>La sp\u00e9cificit\u00e9 du Russiagate est double, ce qui en fait un simulacre que nous qualifierions d&rsquo;extr\u00eame, \u00e9chappant \u00e0 tout contr\u00f4le, \u00e0 toute aide et incitation venues des capacit\u00e9s \u00e9lectroniques, informatiques de simulation, des jeux \u00e9lectroniques, des repr\u00e9sentations de spectacle (par exemple, les films Tron, Minority Report, ou la s\u00e9rie des Matrix, auxquels Mattei fait allusion). Le Russiagate est construit <strong>essentiellement sinon exclusivement sur des \u00e9l\u00e9ments humains de la psychologie<\/strong>, et il est si extr\u00eame justement que les moyens \u00e9lectroniques et informatiques n&rsquo;y ont aucune part sinon par la situation \u00e9trange de leur \u00e9chec \u00e0 renforcer le simulacre (non-production de preuves, de communications Trump-Russie, etc.). Il n&rsquo;y a que la conviction hyst\u00e9rique, la puissance paradoxale d&rsquo;une psychologie trop affaiblie pour r\u00e9sister \u00e0 des pressions ext\u00e9rieures que permet sa pathologie, &ndash; pressions qui viennent \u00e0 notre sens <strong>de ce que nous nommons \u00ab\u00a0des forces obscures\u00a0\u00bb dont nous jugeons cat\u00e9goriquement qu&rsquo;elles sont hors du champ des manigances et manipulations humaines<\/strong><\/em>.  [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Ces diff\u00e9rentes fluctuations viennent du fait que Russiagate est effectivement un simulacre extr\u00eame, c&rsquo;est-\u00e0-dire <strong>un simulacre qui s&rsquo;est install\u00e9 sans am\u00e9nager ni ma&icirc;triser \u00e0 son image les \u00e9v\u00e9nements en cours et qu&rsquo;il s&rsquo;est pourtant install\u00e9 au c&oelig;ur de ces \u00e9v\u00e9nements<\/strong>. Ce n&rsquo;est pas un simulacre par ruse, par habilet\u00e9, par \u00ab\u00a0consentement mutuel\u00a0\u00bb, par s\u00e9duction, par faiblesse, par abandon, par l\u00e2chet\u00e9, etc. ; et surtout ce n&rsquo;est pas un simulacre install\u00e9 par les instruments technologiques (simulation) de la postmodernit\u00e9 alors qu&rsquo;il utilise \u00e0 fond la communication de la postmodernit\u00e9,<strong> ainsi mettant en opposition les deux forces de la postmodernit\u00e9, technologisme et communication<\/strong>&#8230; Non, <strong>c&rsquo;est un simulacre de conqu\u00eate qui d\u00e9pend du seul hybrisdes psychologies malades<\/strong>, un simulacre qui veut d\u00e9truire tout le reste, et notamment les diverses v\u00e9rit\u00e9s-de-situation qu&rsquo;on peut trouver ici et l\u00e0, \u00e9parses mais puissamment vibrantes, si l&rsquo;enqu\u00eateur a du flair<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Je serais donc inclin\u00e9 \u00e0 consid\u00e9rer que le simulacre du type-<em>Russiagate<\/em> comme accomplissement de l&rsquo;\u00e9volution crisique (avec l&rsquo;Ukraine imm\u00e9diatement avant, et d\u00e9j\u00e0 li\u00e9e \u00e0 l&rsquo;antirussisme) constitue quelque chose de tout \u00e0 fait original, sinon de d\u00e9cisif, par rapport au simulacre tel qu&rsquo;il est pr\u00e9sent\u00e9 en g\u00e9n\u00e9ral, comme irr\u00e9m\u00e9diablement li\u00e9 au monde virtuel de l&rsquo;informatique, des jeux vid\u00e9os, du cin\u00e9ma utilisant les technologies du domaine, etc. Justement, le <em>Russiagate <\/em>a ceci de remarquable qu&rsquo;au lieu de se d\u00e9tacher compl\u00e8tement d&rsquo;une \u00e9ventuelle pseudo-r\u00e9alit\u00e9 pour cr\u00e9er une r\u00e9alit\u00e9 virtuelle (un simulacre), <strong>il s&rsquo;affirme au contraire en plein milieu de la pseudo-r\u00e9alit\u00e9 pour pr\u00e9tendre la cong\u00e9dier totalement<\/strong>. De m\u00eame, dans la m\u00eame logique, ce simulacre-l\u00e0, qui se fait vertu de ne pas user des technologies pour se constituer, affirme qu&rsquo;il est la vraie r\u00e9alit\u00e9-r\u00e9elle, alors que son action, relay\u00e9e par la communication, a pulv\u00e9ris\u00e9 le concept m\u00eame de r\u00e9alit\u00e9, au profit, pour ceux qui r\u00e9sistent \u00e0 tous ces courants d\u00e9constructeurs, de ce que nous nommons les v\u00e9rit\u00e9s-de-situation.<\/p>\n<\/p>\n<p><p>Certains observeront que rien de tout cela n&rsquo;est nouveau, ce qui est l&rsquo;\u00e9vidence en th\u00e9orie puisque l&rsquo;all\u00e9gorie de la caverne de Platon est le simulacre-type. Mais quelle importance, lorsqu&rsquo;on sait, avec Thibon, que \u00ab\u00a0tout est dans tout\u00a0\u00bb, c&rsquo;est-\u00e0-dire pour notre compte, que nous d\u00e9battons depuis deux \u00e0 trois mill\u00e9naires, toujours des m\u00eames probl\u00e8mes de l&rsquo;ontologie de l&rsquo;\u00eatre, f&ucirc;t-il celui de l&rsquo;homme ou celui de l&rsquo;univers. Ce qui importe, c&rsquo;est de d\u00e9couvrir et d&rsquo;identifier les manifestations diverses, extr\u00eamement nombreuses et ambitieuses, du Malin dans cette \u00e9poque si SESP (Sans Equivalent, Sans Pr\u00e9c\u00e9dent).<\/p>\n<\/p>\n<p><p>De ce point de vue, le simulacre tel que je le d\u00e9finis, apporte une aide consid\u00e9rable car il entre parfaitement dans une pseudo-repr\u00e9sentation op\u00e9rationnelle, sinon dans une pseudo-mod\u00e9lisation de l&rsquo;attaque que le concept de civilisation, que le structure du monde elle-m\u00eame sont en train de subir. Il s&rsquo;inscrit dans un cadre o&ugrave; les forces en jeu se d\u00e9clinent selon les m\u00e9thodes des d\u00e9constructeurs, qui savent parfaitement, eux, ce qu&rsquo;il faut attaquer : la grande bataille entre les structures du monde, qui sont en fait les principes issus de l&rsquo;Unit\u00e9 originale, et l&rsquo;attaque de d\u00e9construction et de dissolution&#8230; Dans ce cadre, l&rsquo;organisation en simulacre devient presque un r\u00e9flexe, et un r\u00e9flexe n&rsquo;h\u00e9sitant pas \u00e0 aller jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame qui le fait plonger plus qu&rsquo;\u00e0 son tour dans un absurde qui devient vite insupportable, &ndash; comme on le voit avec le <em>Russiagate<\/em> qui est un simulacre pouss\u00e9 \u00e0 un tel extr\u00eame qu&rsquo;il se met lui-m\u00eame au risque de la folie de sa propre d\u00e9construction. <strong>Ce sort ne pourrait d&rsquo;ailleurs que satisfaire les d\u00e9constructeurs, qui jugent, au terme de leur logique, que la d\u00e9construction elle-m\u00eame doit \u00eatre d\u00e9construite<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi soit-il, sans n\u00e9cessit\u00e9 d&rsquo;aller chercher chez les d\u00e9constructeurs l&rsquo;explication finale de leur action&#8230; Puisque Mattei, dans le cours de son livre, fait cette remarque terrible : &laquo; <em>Le plus \u00e9tonnant, c&rsquo;est qu&rsquo;\u00e0 aucun moment ils <\/em>[les d\u00e9constructeurs] <em>ne nous donnent la raison de cette furie de d\u00e9construction qui se porte sur tout et sur elle-m\u00eame, au point de s&rsquo;an\u00e9antir puisque, selon Derrida, la d\u00e9construction n&rsquo;est \u00ab\u00a0rien\u00a0\u00bb. <\/em>&raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Mon\u00a0\u00bb simulacre, \u00e0 l&rsquo;origine 25 mai 2017 &ndash; J&rsquo;ai d\u00e9j\u00e0 dit, d&rsquo;une fa\u00e7on ou l&rsquo;autre, combien j&rsquo;ai avanc\u00e9 dans ma vie comme un autodidacte, entrant dans des domaines que je n&rsquo;avais jamais pr\u00e9cis\u00e9ment envisag\u00e9s pour moi-m\u00eame. Ainsi en est-il principalement des mati\u00e8res proches de la philosophie, de la m\u00e9taphysique, etc., autour desquelles il m&rsquo;arrive de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3162,7482,13051,11303,13064],"class_list":["post-77283","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-dde","tag-deconstruction","tag-derrida","tag-mattei","tag-simulation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77283"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77283\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}