{"id":77287,"date":"2017-05-30T11:40:00","date_gmt":"2017-05-30T11:40:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/30\/le-legs-de-zbig-a-lorigine\/"},"modified":"2017-05-30T11:40:00","modified_gmt":"2017-05-30T11:40:00","slug":"le-legs-de-zbig-a-lorigine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/30\/le-legs-de-zbig-a-lorigine\/","title":{"rendered":"Le legs de Zbig\u00a0: \u00e0 l&rsquo;origine&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le legs de Zbig : \u00e0 l&rsquo;origine&#8230;<\/h2>\n<\/p>\n<p><p>Comme l&rsquo;\u00e9crit Neil Clark ce <a href=\"https:\/\/www.rt.com\/op-edge\/390067-brzezinski-afghanistan-ussr-cold-war\/\">29 mai 2017<\/a> sur RT, on pourrait dire que le legs de Zbigniew Brzezinski, qui vient de mourir \u00e0 89 ans, <strong>est notre \u00ab\u00a0monde en flammes\u00a0\u00bb<\/strong> (&laquo; <em>World in flames &#8211; the deadly legacy of Cold War warrior Brzezinski<\/em> &raquo;). C&rsquo;est lui, Brzezinski, qui recommanda et orchestra le lancement de l&rsquo;op\u00e9ration qui allait conduire \u00e0 l&rsquo;implication de l&rsquo;URSS en Afghanistan, au d\u00e9veloppement de la r\u00e9sistance afghane de laquelle d\u00e9coul\u00e8rent les innombrables branches du terrorisme islamiste, \u00e0 commencer par Ben Laden. D\u00e8s l&rsquo;origine, l<strong>a CIA fut l&rsquo;instrument op\u00e9rationnel de cette \u00e9norme entreprise, \u00e0 laquelle l&rsquo;Arabie Saoudite notamment fut largement partie prenante (financi\u00e8rement) d\u00e8s le d\u00e9part<\/strong>.<\/p>\n<\/p>\n<p><p>Clark \u00e9crit, et c&rsquo;est le \u00ab\u00a0<em>before<\/em>\u00a0\u00bb qui compte puisque la version officielle fut longtemps que les USA avaient r\u00e9pliqu\u00e9 en formant les <em>moudjahidines<\/em> (\u00ab\u00a0combattants de la libert\u00e9\u00a0\u00bb) comme on les appelait alors, apr\u00e8s l&rsquo;intervention sovi\u00e9tique de d\u00e9cembre 1979 : &laquo; <em>In fact, US financial assistance for anti-government forces had begun BEFORE the invasion- and was expressly designed to provoke a Soviet military response. <\/em><em>In 1998 Brzezinski admitted that he had got President Carter to sign the first order for secret aid to &lsquo;rebels&rsquo; in July 1979 a full five months before the Soviets intervened. \u00ab\u00a0I wrote a note to the president in which I explained to him that in my opinion, this aid was going to induce a Soviet military intervention,\u00a0\u00bb Brzezinski said. Even before that, US officials had been meeting with &lsquo;rebel&rsquo; leaders. While in 1977 Zbig had set up the Nationalities Working Group &#8211; whose goal was to weaken the Soviet Union by stirring up ethnic and religious tensions<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>La r\u00e9v\u00e9lation de cette action pr\u00e9ventive (juillet 1979), qui donne toute la responsabilit\u00e9 de l&rsquo;origine des \u00e9v\u00e9nements de d\u00e9stabilisation massive qui viennent jusqu&rsquo;\u00e0 nous se fit dans une interview du <em>Nouvel Observateur <\/em>; interview tr\u00e8s courte mais tr\u00e8s r\u00e9v\u00e9latrice, qui r\u00e9sume en quelque phrase, non seulement la pens\u00e9e de Brzezinski (avec la multiplication par ce qu&rsquo;on peut nommer la \u00ab\u00a0haine antirusse\u00a0\u00bb de son origine polonaise) <strong>mais aussi la strat\u00e9gie op\u00e9rationnelle de l&rsquo;<em>establishment<\/em> US depuis des d\u00e9cennies<\/strong>. Cette strat\u00e9gie \u00e0 tendance globalisante existait d\u00e9j\u00e0 de mani\u00e8re offensive durant la Deuxi\u00e8me Guerre mondiale, avec l&rsquo;activisme des divers services officiels US aupr\u00e8s des indig\u00e8nes et des diverses organisations soit nationalistes, soit panarabes avec de fortes consonances religieuses dans les pays \u00e0 population arabe sous colonisation europ\u00e9enne, y compris par exemple dans les pays du Maghreb alors fran\u00e7ais \u00e0 partir du d\u00e9barquement de novembre 1942. Cette m\u00eame attitude pr\u00e9valut dans les pays asiatiques dans la m\u00eame situation, notamment dans l&rsquo;Indochine fran\u00e7aise. (Ho Chi-minh re\u00e7ut l&rsquo;aide de l&rsquo;OSS pour former son organisation et il fondait \u00e0 l&rsquo;origine ses ambitions sur le sch\u00e9ma de la Constitution des &Eacute;tats-Unis.) Dans cette attitude US, on retrouve un m\u00e9lange d&rsquo;un puissant affairisme avec l&rsquo;annexion au profit des USA des march\u00e9s ext\u00e9rieurs, d&rsquo;un anticolonialisme remontant au temps de la Guerre d&rsquo;Ind\u00e9pendance, et enfin de l&rsquo;id\u00e9alisme de type-wilsonien selon lequel la diffusion de la formule am\u00e9ricaniste de la d\u00e9mocratie et de la modernit\u00e9 constitue la voie \u00e9vidente vers une globalisation et une uniformisation vertueuses du monde, &ndash; <strong>selon le \u00ab\u00a0mod\u00e8le\u00a0\u00bb am\u00e9ricaniste naturellement<\/strong>. Ainsi l&rsquo;anticolonialisme si souvent acclam\u00e9 par la pens\u00e9e moderniste <strong>trouve-t-il l\u00e0 une parent\u00e8le inattendue sinon quelque peu g\u00eanante<\/strong>. (Nous avons d\u00e9j\u00e0 rappel\u00e9 combien <a href=\"http:\/\/www.dedefensa.org\/article\/crepuscule-de-la-civilisation\">Arnold Toynbee<\/a> a bien montr\u00e9 comment il importait de faire toute la lumi\u00e8re sur ce mouvement \u00e0 partir des conceptions du <strong><a href=\"http:\/\/www.dedefensa.org\/article\/souverainisme-versus-suprematisme\">supr\u00e9macisme<\/a> de l&rsquo;anglosaxonisme<\/strong>, de l'\u00a0\u00bbanglosph\u00e8re\u00a0\u00bb, puis de l&rsquo;am\u00e9ricanisme gobant le tout au bout du compte.)<\/p>\n<\/p>\n<p><p>Voici donc la courte interview de Zbigniew Brzezinski parue dans <em>Le Nouvel Observateur <\/em>num\u00e9ro 1732 du 15 janvier 1998, lorsque on s&rsquo;int\u00e9ressait encore fort peu \u00e0 l&rsquo;implication des r\u00e9v\u00e9lations qu&rsquo;il y fait. (Le propos est recueilli par Vincent Jauvert, les m\u00e9moires de Robert Gates servant de r\u00e9f\u00e9rence sont intitul\u00e9s : <em>From the Shadows<\/em>, chez Simon and Schuster. Nous avions d\u00e9j\u00e0 publi\u00e9 cette interview le <a href=\"http:\/\/www.dedefensa.org\/article\/brzezinski-a-lorigine-du-desordre\">15 juillet 2005<\/a>.)<\/p>\n<\/p>\n<p><p><strong><em>Le Nouvel Observateur : <\/em><\/strong><em>&laquo; L&rsquo;ancien directeur de la CIA Robert Gates l&rsquo;affirme dans ses M\u00e9moires<\/em> <em>: les services secrets am\u00e9ricains ont commenc\u00e9 \u00e0 aider les moudjahidine afghans six mois avant l&rsquo;intervention sovi\u00e9tique. A l&rsquo;\u00e9poque, vous \u00e9tiez le conseiller du pr\u00e9sident Carter pour les affaires de s\u00e9curit\u00e9 ; vous avez donc jou\u00e9 un r\u00f4le cl\u00e9 dans cette affaire. Vous confirmez? <\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zbigniew Brzezinski<\/em><\/strong><em> <strong>:<\/strong><\/em> &laquo; <em>Oui. Selon la version officielle de l&rsquo;histoire, l&rsquo;aide de la CIA aux moudjahidine a d\u00e9but\u00e9 courant 1980, c&rsquo;est-\u00e0-dire apr\u00e8s que l&rsquo;arm\u00e9e sovi\u00e9tique eut envahi l&rsquo;Afghanistan, le 24 d\u00e9cembre 1979. Mais la r\u00e9alit\u00e9, gard\u00e9e secr\u00e8te jusqu&rsquo;\u00e0 pr\u00e9sent, est tout autre : c&rsquo;est en effet le 3 juillet 1979 que le pr\u00e9sident Carter a sign\u00e9 la premi\u00e8re directive sur l&rsquo;assistance clandestine aux opposants du r\u00e9gime prosovi\u00e9tique de Kaboul. Et ce jour-l\u00e0, j&rsquo;ai \u00e9crit une note au pr\u00e9sident dans laquelle je lui expliquais qu&rsquo;\u00e0 mon avis cette aide allait entra&icirc;ner une intervention militaire des Sovi\u00e9tiques.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Le Nouvel Observateur : <\/em><\/strong><em>&laquo; Malgr\u00e9 ce risque, vous \u00e9tiez partisan de cette \u00ab\u00a0covert action\u00a0\u00bb<\/em> [op\u00e9ration clandestine]. <em>Mais peut-\u00eatre m\u00eame souhaitiez-vous cette entr\u00e9e en guerre des Sovi\u00e9tiques et cherchiez-vous \u00e0 la provoquer ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zbigniew Brzezinski<\/em><\/strong><em> <strong>:<\/strong><\/em> &laquo; <em>Ce n&rsquo;est pas tout \u00e0 fait cela. Nous n&rsquo;avons pas pouss\u00e9 les Russes \u00e0 intervenir, mais nous avons sciemment augment\u00e9 la probabilit\u00e9 qu&rsquo;ils le fassent.<\/em><\/p>\n<\/p>\n<p><p><strong><em>Le Nouvel Observateur : <\/em><\/strong><em>&laquo; Lorsque les Sovi\u00e9tiques ont justifi\u00e9 leur intervention en affirmant qu&rsquo;ils entendaient lutter contre une ing\u00e9rence secr\u00e8te des Etats-Unis en Afghanistan, personne ne les a crus. Pourtant, il y avait un fond de v\u00e9rit\u00e9&#8230; Vous ne regrettez rien aujourd&rsquo;hui ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zbigniew Brzezinski<\/em><\/strong><em> <strong>:<\/strong><\/em> &laquo; <em>Regretter quoi ? Cette op\u00e9ration secr\u00e8te \u00e9tait une excellente id\u00e9e. Elle a eu pour effet d&rsquo;attirer les Russes dans le pi\u00e8ge afghan et vous voulez que je le regrette ? Le jour o&ugrave; les Sovi\u00e9tiques ont officiellement franchi la fronti\u00e8re, j&rsquo;ai \u00e9crit au pr\u00e9sident Carter, en substance : \u00ab\u00a0Nous avons maintenant l&rsquo;occasion de donner \u00e0 l&rsquo;URSS sa guerre du Vietnam.\u00a0\u00bb De fait, Moscou a d&ucirc; mener pendant presque dix ans une guerre insupportable pour le r\u00e9gime, un conflit qui a entra&icirc;n\u00e9 la d\u00e9moralisation et finalement l&rsquo;\u00e9clatement de l&#8217;empire sovi\u00e9tique.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Le Nouvel Observateur : <\/em><\/strong><em>&laquo; Vous ne regrettez pas non plus d&rsquo;avoir favoris\u00e9 l&rsquo;int\u00e9grisme islamiste, d&rsquo;avoir donn\u00e9 des armes, des conseils \u00e0 de futurs terroristes ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zbigniew Brzezinski<\/em><\/strong><em> <strong>:<\/strong><\/em> &laquo; <em>Qu&rsquo;est-ce qui est le plus important au regard de l&rsquo;histoire du monde ? Les talibans ou la chute de l&#8217;empire sovi\u00e9tique ? Quelques excit\u00e9s islamistes ou la lib\u00e9ration de l&rsquo;Europe centrale et la fin de la guerre froide ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Le Nouvel Observateur : <\/em><\/strong><em>&laquo; \u00ab\u00a0Quelques excit\u00e9s\u00a0\u00bb? Mais on le dit et on le r\u00e9p\u00e8te: le fondamentalisme islamique repr\u00e9sente aujourd&rsquo;hui une menace mondiale<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zbigniew Brzezinski<\/em><\/strong><em> <strong>:<\/strong><\/em> &laquo; <em>Sottises ! Il faudrait, dit-on, que l&rsquo;Occident ait une politique globale \u00e0 l&rsquo;\u00e9gard de l&rsquo;islamisme. C&rsquo;est stupide: il n&rsquo;y a pas d&rsquo;islamisme global. Regardons l&rsquo;islam de mani\u00e8re rationnelle et non d\u00e9magogique ou \u00e9motionnelle. C&rsquo;est la premi\u00e8re religion du monde avec 1,5 milliard de fid\u00e8les. Mais qu&rsquo;y a-t-il de commun entre l&rsquo;Arabie Saoudite fondamentaliste, le Maroc mod\u00e9r\u00e9, le Pakistan militariste, l&rsquo;Egypte pro-occidentale ou l&rsquo;Asie centrale s\u00e9cularis\u00e9e? Rien de plus que ce qui unit les pays de la chr\u00e9tient\u00e9&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Apr\u00e8s l&rsquo;attaque du 11 septembre 2001 et avec l&rsquo;attaque am\u00e9ricaine contre l&rsquo;Afghanistan puis contre l&rsquo;Irak qui suivirent, certains avaient ressorti cette courte interview de Zbigniew Brzezinski au <em>Nouvel Observateur<\/em>, pensant qu&rsquo;elle servirait \u00e0 temp\u00e9rer toutes les affirmations officielles sur le terrorisme dans sa quasi-fatalit\u00e9 islamiste, sur \u00ab\u00a0le choc des civilisations\u00a0\u00bb, sur le Mal et sur le diable. Il n&rsquo;en fut rien et la version officielle aussit\u00f4t proclam\u00e9e par l&rsquo;administration GW Bush fut bien qu&rsquo;il y avait un terrorisme islamiste n\u00e9 d&rsquo;une origine lointaine, li\u00e9 \u00e0 la religion, ami du Diable et repr\u00e9sentant le Mal contre le Bien qui tenait et tient toujours congr\u00e8s permanent \u00e0 Washington D.C.<\/p>\n<\/p>\n<p><p>Bien entendu, les man&oelig;uvres sans nombre des divers services de l&rsquo;IC (<em>Intelligence Community<\/em>), CIA en t\u00eate, et des divers services des forces arm\u00e9es, pour cr\u00e9er et instrumenter diff\u00e9rents groupes extr\u00e9mistes en les \u00e9quipant d&rsquo;armes et en les couvrant d&rsquo;ors saoudiens, constitu\u00e8rent un \u00e9l\u00e9ment fondamental qui intervint dans un ph\u00e9nom\u00e8ne o&ugrave; l&rsquo;existence pr\u00e9c\u00e9dait l&rsquo;essence pour satisfaire les conceptions sartriennes, les Am\u00e9ricano-Saoudiens se chargeant de d\u00e9finir de quelle essence il s&rsquo;agissait ; <strong>vue la nature de leurs liens, aux am\u00e9ricanistes et aux Saoudiens, ce n&rsquo;\u00e9tait pas difficile<\/strong>. En d&rsquo;autres mots, l&rsquo;islamo-terroriste qui n&rsquo;existait pas comme ph\u00e9nom\u00e8ne majeur ni m\u00eame annexe en 1980, \u00e9tait devenu le ph\u00e9nom\u00e8ne universel qu&rsquo;on conna&icirc;t apr\u00e8s 9\/11, et bien plus encore apr\u00e8s le <em>surge<\/em> de Petraeus en Irak en 2007-2007, n\u00e9gociant \u00e0 coup de conteneur de dollars le ralliement des sunnites d&rsquo;Irak et <strong>mettant ainsi en place les structures du futur <em>Daesh<\/em> et de toute la galaxie qu&rsquo;on retrouve en Syrie<\/strong>.<\/p>\n<\/p>\n<p><p>Brzezinski et son m\u00e9pris pour les craintes d&rsquo;un mouvement terroristes islamiste avait s&ucirc;rement raison d&rsquo;un point de vue strat\u00e9gique en 1980 ; il avait sans doute encore un peu raison en 1999 malgr\u00e9 qu&rsquo;il ait \u00e9t\u00e9 d\u00e9montr\u00e9 par la mise \u00e0 jour d&rsquo;archives diverses que l&rsquo;URSS n&rsquo;avait nullement \u00e9t\u00e9 le danger d&rsquo;agression permanente que Brzezinski eut continuellement \u00e0 l&rsquo;esprit pour minorer tous les autres dangers. (Le v\u00e9ritable danger de la Guerre froide \u00e9tait de type \u00ab\u00a0objectif\u00a0\u00bb et catastrophique pour tous les acteurs, dans le chef de la possibilit\u00e9 de l&rsquo;usage de l&rsquo;arme nucl\u00e9aire.) Comme en 1980, le terrorisme islamiste n&rsquo;\u00e9tait pas encore, en 1999, un danger majeur, sauf peut-\u00eatre en Russie avec la Tch\u00e9tch\u00e9nie, c<strong>e qui n&rsquo;\u00e9tait d&rsquo;ailleurs pas pour d\u00e9plaire \u00e0 Zbig<\/strong>. Il l&rsquo;est devenu avec 9\/11, communication oblige, et op\u00e9rationnellement notamment gr\u00e2ce aux canaux et aux complicit\u00e9s sans nombre, aux corruptions innombrables, aux manipulations vertigineusement nombreuses et aussi sans queues ni t\u00eates, d\u00e9j\u00e0 en place avec l&rsquo;activisme forcen\u00e9 et incontr\u00f4l\u00e9 de la CIA que Brzezinski avait imm\u00e9diatement mis sur le coup en 1979.<\/p>\n<\/p>\n<p><p>Brzezinski avait \u00e9t\u00e9 le conseiller pour la s\u00e9curit\u00e9 nationale du pr\u00e9sident Jimmy Carter, de 1977 \u00e0 1981. A ce poste, il fut effectivement le principal animateur, contre l&rsquo;avis du secr\u00e9taire d&rsquo;&Eacute;tat Vance, du prologue et du lancement de l&rsquo;aide am\u00e9ricaine aux moudjahidines luttant contre les communistes en Afghanistan (effectivement: \u00ab\u00a0contre les communistes\u00a0\u00bb en g\u00e9n\u00e9ral ; d&rsquo;abord contre le r\u00e9gime communiste de Babrak Karmal puis, \u00e0 partir de d\u00e9cembre 1979, contre les Sovi\u00e9tiques de l&rsquo;Arm\u00e9e Rouge \u00e9galement). Cette politique a donc \u00e9t\u00e9 souvent et justement d\u00e9crite comme l&rsquo;\u00e9v\u00e9nement cr\u00e9ant le Osama Ben Laden pr\u00e9sent\u00e9 depuis comme le cerveau d&rsquo;une offensive mondiale de terrorisme, avant de passer le relais aux vedettes actuelles. Elle prit, avec Reagan et son directeur de la CIA Bill Casey, relais de Wall Street et ma&icirc;tre des coups fourr\u00e9s impliquant diverses branches du crime organis\u00e9, des proportions importantes, accentuant l&rsquo;effet initial voulu par Brzezinski et l&rsquo;administration Carter (l&rsquo;accentuation de la lutte contre les Sovi\u00e9tiques passant par le renforcement des structures de l&rsquo;extr\u00e9misme islamiste).<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est effectivement de l\u00e0 que datent le d\u00e9veloppement et la mise en place, et l&rsquo;\u00e9quipement militaire initial \u00e9galement, de la n\u00e9buleuse islamiste qu&rsquo;il est de bon ton de consid\u00e9rer aujourd&rsquo;hui, dans les milieux de la pens\u00e9e conformiste globalis\u00e9e, comme la premi\u00e8re menace contre la civilisation. <strong>La v\u00e9ritable responsabilit\u00e9 est donc bien celle du Syst\u00e8me<\/strong>, avec l&rsquo;organisation colossale venue des divers services d&rsquo;agitation et de subversion des moyens op\u00e9rationnels de l&rsquo;am\u00e9ricanisme (IC et le reste), et <strong>sans aucun doute l&rsquo;op\u00e9ration globale de d\u00e9stabilisation la plus ambitieuse jamais lanc\u00e9e par les USA<\/strong>. (En 1980, Brzezinski parlait de \u00ab\u00a0l&rsquo;arc de crise\u00a0\u00bb du monde allant de l&rsquo;Inde \u00e0 la Somalie et le pr\u00e9sident Carter cr\u00e9ait le Central Command qui constitue aujourd&rsquo;hui le commandement militaro-politique le plus puissant des forces bellicistes et expansionnistes US. (Carter, qui a \u00e9voul\u00e9 dans le meilleur sens du monde, <strong>devenu parfaitement antiSyst\u00e8me<\/strong>, n&rsquo;a jamais dit pr\u00e9cis\u00e9ment ce qu&rsquo;il pensait de cette \u00e9volution-l\u00e0 \u00e0 laquelle il avait pr\u00e9sid\u00e9, c<strong>omme parfait jouet du Syst\u00e8me<\/strong>.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Certes, personne de s\u00e9rieux, en 1998, \u00e0 Washington, n&rsquo;aurait contredit Brzezinski sur le fond, malgr\u00e9 l&rsquo;insistance de l&rsquo;intervieweur. Aujourd&rsquo;hui, rappeler ces d\u00e9clarations de Brzezinski pourrait repr\u00e9senter un cas d&rsquo;une condamnation sans appel, avec effet r\u00e9troactif s&rsquo;il le faut. Restent la r\u00e9alit\u00e9, les faits, les manigances, les intentions, &mdash; bref, ce qui fait ici la cause premi\u00e8re de l&rsquo;encha&icirc;nement menant aux \u00e9v\u00e9nements du 11 septembre 2001 et apr\u00e8s. Il est bon de se rappeler jusqu&rsquo;\u00e0 quel point, et \u00e0 quelle profondeur, avec quel z\u00e8le, quelle absence de d\u00e9fiance et de scrupule, quelle courte vue et quel cynisme, quel id\u00e9alisme niais et si fortement li\u00e9 aux gains du capitalisme, l<strong>es &Eacute;tats-Unis ont sem\u00e9 les graines dont ils r\u00e9coltent aujourd&rsquo;hui les fruits amers (d&rsquo;ailleurs pas amers pour tout le monde, y compris \u00e0 Washington D.C.)<\/strong>. Si ce n&rsquo;est de la pr\u00e9destination, cela y ressemble, jusques et y compris dans l&rsquo;entra&icirc;nement vers un destin catastrophique pour les USA que suppose cette vaste op\u00e9ration ; apr\u00e8s tout, <strong>c&rsquo;est elle qui n&rsquo;a cess\u00e9 d&rsquo;exercer une influence d\u00e9stabilisatrice, directement et indirectement, aux USA m\u00eame, \u00e0 Washington D.C<\/strong>., en d\u00e9veloppant une corruption effr\u00e9n\u00e9e, en installant une communication tout \u00e0 fait faussaire et en cr\u00e9ant des \u00e9v\u00e9nements relevant du simulacre pur et simple, en donnant \u00e0 des organisations diverses dont la CIA est l&rsquo;arch\u00e9type des pouvoirs \u00e9normes et incontr\u00f4lables ; <strong>bref, en donnant les moyens op\u00e9rationnels de faire entrer la postmodernit\u00e9 comme simulacre de r\u00e9alit\u00e9 \u00e0 la place de la v\u00e9rit\u00e9 du monde<\/strong>.<\/p>\n<\/p>\n<p><p>Mis en ligne le 30 mai 2017 \u00e0 11H38<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le legs de Zbig : \u00e0 l&rsquo;origine&#8230; Comme l&rsquo;\u00e9crit Neil Clark ce 29 mai 2017 sur RT, on pourrait dire que le legs de Zbigniew Brzezinski, qui vient de mourir \u00e0 89 ans, est notre \u00ab\u00a0monde en flammes\u00a0\u00bb (&laquo; World in flames &#8211; the deadly legacy of Cold War warrior Brzezinski &raquo;). C&rsquo;est lui, Brzezinski,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,13070,3643,3104,12572,2632,857,11341,4290,4675,13071,4146,1267,963,4140],"class_list":["post-77287","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-anticolonialisme","tag-carter","tag-cia","tag-daesh","tag-globalisation","tag-irak","tag-islamiste","tag-mercantilisme","tag-moudjahidines","tag-surgi","tag-talibans","tag-terrorisme","tag-urss","tag-wilson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77287"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77287\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}