{"id":77290,"date":"2017-05-29T15:24:25","date_gmt":"2017-05-29T15:24:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/29\/merkel-et-son-moment-decisif-quels-effets\/"},"modified":"2017-05-29T15:24:25","modified_gmt":"2017-05-29T15:24:25","slug":"merkel-et-son-moment-decisif-quels-effets","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/05\/29\/merkel-et-son-moment-decisif-quels-effets\/","title":{"rendered":"Merkel et son \u201cMoment d\u00e9cisif\u201d\u00a0: quels effets\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Merkel et son \u00ab\u00a0Moment d\u00e9cisif\u00a0\u00bb : quels effets ?<\/h2>\n<\/p>\n<p><p>29 mai 2017 &ndash; Apr\u00e8s la r\u00e9union du G7 devenu G6+1 et qu&rsquo;on pourrait aussi bien d\u00e9signer comme le \u00ab\u00a0G7-1\u00a0\u00bb, on ne parle que de ce \u00ab\u00a0moment d\u00e9cisif\u00a0\u00bb, le \u00ab\u00a0<em>Watershed Moment<\/em>\u00a0\u00bb d&rsquo;Angela Merkel ; lorsque, rentr\u00e9e du sommet en Sicile et venue \u00e0 Munich pour un discours dans le cadre de la campagne \u00e9lectorale et notamment sur le sujet du <em>Brexit <\/em>\u00e9tendu bien entendu aux derniers \u00e9v\u00e9nements, elle nous annonce (hier) que, &laquo; <em>bien entendu nous avons besoin de relations amicales avec les USA et avec le Royaume-Uni, et avec nos autres voisins, y compris la Russie<\/em> &#8230; [Pour autant,] <em>nous devons nous battre nous-m\u00eames pour notre propre futur<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Pour l&rsquo;AFP, &laquo; <em>Merkel<\/em> [nous] <em>a avertis <strong>que les USA et le Royaume-Uni ne sont plus des partenaires fiables<\/strong><\/em> &raquo;, tandis que <em><a href=\"http:\/\/www.zerohedge.com\/print\/596826\">ZeroHedge.com<\/a><\/em> prend la peine de citer une phrase directement en allemand, pour en tirer la substantifique moelle : &laquo; <em>die zeiten, in denen wir uns auf andere v\u00f6llig verlassen konnten, sind ein St\u00fcck vorbei<\/em> &raquo;, ce qui donnerait \u00e0 peu pr\u00e8s cette adaptation selon laquelle \u00ab\u00a0les temps <strong>o&ugrave; nous pouvions compl\u00e8tement d\u00e9pendre des autres sont en train de se finir<\/strong>\u00ab\u00a0, assorti de ce commentaire personnel venu  tout droit du G7-1 : &laquo; <em>J&rsquo;ai exp\u00e9riment\u00e9 la chose durant ces derniers jours<\/em> &raquo;. Catastrophiste et apocalyptique comme \u00e0 l&rsquo;habitude, <em><a href=\"http:\/\/www.wsws.org\/en\/articles\/2017\/05\/29\/pers-m29.html\">WSWS.org<\/a> <\/em>ajoute : &laquo;<em> Le fait que ces mots aient \u00e9t\u00e9 prononc\u00e9s \u00e0 une f\u00eate de la bi\u00e8re \u00e0 Munich, rappelant les d\u00e9buts de la carri\u00e8re politique d&rsquo;Adolphe Hitler, ajoute \u00e0 leur signification<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Les r\u00e9actions aux d\u00e9clarations de Merkel sont donc tr\u00e8s nombreuses, <strong>toutes dans le m\u00eame sens, surtout en provenance du monde anglo-saxon<\/strong>. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il s&rsquo;agit \u00e0 la fois de prendre acte, \u00e0 la fois de mettre en \u00e9vidence que ces d\u00e9clarations constituent une \u00e9volution jug\u00e9e peut-\u00eatre d\u00e9cisive de la politique allemande, souvent avec le rappel de l&rsquo;\u00e9poque d&rsquo;avant la Deuxi\u00e8me Guerre mondiale comme le fait <em>WSWS.org <\/em>:<\/p>\n<\/p>\n<p><p>&laquo; <em>Reactions to Merkel&rsquo;s striking comment came pouring in from the likes of Edward Snowden who called her speech an \u00ab\u00a0era-defining moment\u00a0\u00bb, the president of the Council on Foreign Relations. Richard Haass, who called it a \u00ab\u00a0watershed moment\u00a0\u00bb, the editor of the Financial Times, calling it a \u00ab\u00a0big moment in transatlantic relations\u00a0\u00bb&#8230; and many others: in short, it seems that the time for a New-er World Order may be at hand, and many are not too happy<\/em>. &raquo; (<em>ZeroHedge.com<\/em>)<\/p>\n<\/p>\n<p><p>&laquo; <em>Henry Farrell, professor of political science and international affairs at George Washington University, noted in the Washington Post, that Merkel&rsquo;s comments were \u00ab\u00a0an enormous change in political rhetoric.\u00a0\u00bb While the \u00ab\u00a0special relationship\u00a0\u00bb between Britain and the US had assumed more public prominence, \u00ab\u00a0the German-US relationship has arguably been more important.\u00a0\u00bb One of the purposes of NATO, Farrell wrote, was to \u00ab\u00a0embed Germany in an international framework that would prevent it from becoming a threat to European peace as it had been in World War I and World War II.\u00a0\u00bb He recalled the words of the first NATO secretary-general, Hastings Ismay, that the alliance aimed \u00ab\u00a0to keep the Russians out, the Americans in, and the Germans down.\u00a0\u00bb Now, Germany was seeking to play a more independent role than at any time since the end of World War II.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The immediate cause of the rift at the G7 was almost universally described as Trump&rsquo;s \u00ab\u00a0boorish\u00a0\u00bb behaviour. But his actions are only the latest, and so far most graphic, expression of the deepening tensions between the major imperialist powers<\/em>. &raquo; (<em>WSWS.org<\/em>)<\/p>\n<\/p>\n<p><p>&bull; Dans le dernier paragraphe du texte de <em>WSWS.org<\/em>, ci-dessus, on voit tout de m\u00eame le rappel que le comportement de Trump est la cause \u00ab\u00a0universellement appr\u00e9ci\u00e9e\u00a0\u00bb de la querelle qui s&rsquo;est d\u00e9velopp\u00e9e durant les deux sommets successifs, <strong>mais aussi le rappel implicite que cette \u00ab\u00a0attitude\u00a0\u00bb n&rsquo;est que l&rsquo;extr\u00eame des effets de la logique du comportement des USA au moins depuis 9\/11<\/strong>. Le texte rappelle la m\u00e9sentente entre l&rsquo;Allemagne et les USA en 2001 pour l&rsquo;attaque de l&rsquo;Irak, &ndash; en omettant tout de m\u00eame, <strong>ce qui n&rsquo;est pas rien et qui est m\u00eame l&rsquo;essentiel<\/strong>, que ce comportement allemand \u00e9tait alors compl\u00e9mentaire et suiviste de l&rsquo;action de la France qui menait sans le moindre doute la fronde contre la politique d&rsquo;agression US. Cette pr\u00e9cision nous \u00e9loignerait d\u00e9cisivement du simple jeu du rapport des forces entre l&rsquo;Allemagne et les USA, avec l&rsquo;appr\u00e9ciation, courante ces derniers temps, que l&rsquo;Allemagne veut jouer un r\u00f4le global (III\u00e8me <em>Reich<\/em>, le retour) et qu&rsquo;elle se heurte de plus en plus aux USA. Ce jugement n&rsquo;est certainement pas le n\u00f4tre, comme nous l&rsquo;avons r\u00e9p\u00e9t\u00e9 \u00e0 plusieurs reprises : l&rsquo;Allemagne repr\u00e9sente certes un poids \u00e9conomique consid\u00e9rable et elle exerce un <em>leadership<\/em> de fait en Europe, mais cela ne lui donne aucune capacit\u00e9 d&rsquo;action ni d&rsquo;influence, ni sur le terrain strat\u00e9gique et militaire, ni sur le terrain de la dplomatie et de l&rsquo;influence active ; d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, d&rsquo;ailleurs, ce <em>leadership<\/em> doit \u00eatre appr\u00e9ci\u00e9 comme <strong>une sorte d&rsquo;\u00e9tat de fait et la cons\u00e9quence de l&rsquo;impuissance et de la dissolution politique et souveraine des autres (la France en premi\u00e8re place, certes)<\/strong>. Quant \u00e0 l&rsquo;Europe sous direction allemande, son impuissance est flagrante, y compris dans ses entreprises d&rsquo;expansion qui se terminent en g\u00e9n\u00e9ral, \u00e0 l&rsquo;image de ce qui reste son mod\u00e8le, qui est la m\u00e9thode bruissante d&rsquo;intelligence de la puissance US, de catastriophe en catastrophe comme l&rsquo;on peut voir avec l&rsquo;Ukraine, et indirectement avec la Libye.<\/p>\n<\/p>\n<p><p>Un exemple de notre sentiment si souvent exprim\u00e9 sur les ambitions allemandes, et qui reste toujours valable, on le trouve par exemple dans ce commentaire du 20 d\u00e9cembre 2013 o&ugrave; l&rsquo;on parlait d\u00e9j\u00e0, ou encore, de la domination europ\u00e9enne de l&rsquo;Allemagne et de ses suppos\u00e9es ambitions mondiales : &laquo; <em>Cela ne signifie pas que nous fassions l&rsquo;hypoth\u00e8se de la r\u00e9surgence d&rsquo;une puissance h\u00e9g\u00e9monique suivant l&rsquo;affirmation bruyante de sa sup\u00e9riorit\u00e9 \u00e9conomique, d&rsquo;une puissance comme celle qui se manifesta entre 1864 et 1945. La dimension militaire et strat\u00e9gique est absente. R\u00e9p\u00e9tons-le, l&rsquo;Allemagne d&rsquo;aujourd&rsquo;hui n&rsquo;a pas la Wehrmacht et le reste, ni une structure capable d&rsquo;en constituer le noyau (pas d&rsquo;\u00e9tat-major g\u00e9n\u00e9ral, pas d&rsquo;int\u00e9gration strat\u00e9gique des arm\u00e9es, l&rsquo;OTAN ayant \u00e0 cet \u00e9gard son mot \u00e0 dire pour ce pays-l\u00e0, vaincu de 1945, pr\u00e9cis\u00e9ment) ; elle n&rsquo;a ni les moyens technologiques ni le temps n\u00e9cessaire, ni sans doute l&rsquo;id\u00e9e, d&rsquo;en reconstituer une, etc. De toutes les fa\u00e7ons, l&rsquo;Allemagne distinguerait rapidement les d\u00e9savantages d&rsquo;une telle orientation, qui trouverait la Russie sur sa route sans lui apporter quelque avantage que ce soit en Europe, par rapport \u00e0 sa position dominante actuelle<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Adam Garrie, dans <em><a href=\"\/Dans%20ce%20cadre%20totalement%20d%C3%A9l%C3%A9t%C3%A8re,%20et%20pour%20ce%20qui%20nous%20concerne,%20nous-Europ%C3%A9ens,%20il%20n&#039;%C3%A9tonnera%20personne%20que%20nous%20ajoutions%20un%20volet%20concernant%20une%20pouss%C3%A9e%20vers%20l&#039;abdication%20des%20souverainet%C3%A9s,%20qu&#039;il%20faut%20r%C3%A9solument%20placer%20dans%20le%20cadre%20de%20cette%20c\">TheDuran.com<\/a><\/em> le 28 mai 2017, \u00e9largit un peu le probl\u00e8me en ne singularisant plus l&rsquo;Allemagne comme on a trop tendance \u00e0 le faire selon des r\u00e9f\u00e9rences d&rsquo;il y a trois-quarts de si\u00e8cles. Il parle plut\u00f4t <strong>des deux \u00ab\u00a0blocs\u00a0\u00bb, &ndash; les USA et l&rsquo;Europe, &ndash; et de leurs \u00e9volutions possibles en fonction des \u00e9v\u00e9nements r\u00e9cents, \u00e9volution notamment par rapport \u00e0 la Russie<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>It is unlikely that under Donald Trump NATO troops will leave Europe any time soon, but the ideological agenda of neo-liberal Europe and the very bureaucratic and technocratic method that the EU conducts business is simply anathema to Donald Trump.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Whether the much welcomed strain in the hegemonic alliance between the US and EU powers leads to a thaw in US relations with Russia is largely up to Donald Trump&rsquo;s ability to whether the storm of Russiagate on the domestic front. <\/em><em>However, ironically if America really is going to grow manifestly distant from Europe, it could have the ironic effect of forcing Europe closer to Russia, the country on which Europe depends for much of its energy supplies.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>During the Obama years, Europe was a political colony of the US and its political elite were all too happy to act as colonial Viceroys. Now things have changed. The style questions means that the leaders of Europe and the American leadership have little in common. It remains to be seen whether the substance will follow the style into this chasm<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Processus de d\u00e9structuration-dissolution du bloc-BAO<\/h3>\n<\/p>\n<p><p>Bien que les supputations de Garrie soient, selon notre point de vue, plus satisfaisantes que les r\u00e9flexions sur les seuls rapports de force entre USA et Allemagne, elles ne nous satisfont pas pour autant dans leur fondement. Lorsque Garrie dit que &laquo; <em>durant les ann\u00e9es Obama, l&rsquo;Europe \u00e9tait une colonie politique des USA<\/em> &raquo;, etc., \u00e0 notre avis il fait un faux-sens fondamental par rapport \u00e0 ce que nous estimons \u00eatre la situation g\u00e9n\u00e9rale qui a pr\u00e9valu depuis 2008-2010, \u00e0 partir de la p\u00e9riode crise financi\u00e8re\/automne 2008-\u00ab\u00a0printemps arabe\u00a0\u00bb\/fin 2010. (On peut m\u00eame avancer que la crise g\u00e9orgienne [G\u00e9orgie-Russie] d&rsquo;ao&ucirc;t 2008, g\u00e9r\u00e9e du c\u00f4t\u00e9 am\u00e9ricaniste-occidentaliste essentiellement par l&rsquo;UE, marque le d\u00e9but de la p\u00e9riode.) Cette p\u00e9riode est celle que nous avons baptis\u00e9e pour tout ce qui est am\u00e9ricaniste-occidentaliste de \u00ab\u00a0Bloc Am\u00e9ricaniste-Occidentaliste\u00a0\u00bb, ou \u00ab\u00a0bloc-BAO\u00a0\u00bb, et elle a pour particularit\u00e9 fondamentale <strong>de voir dispara&icirc;tre la pr\u00e9pond\u00e9rance absolue des USA qui se dilue dans un ensemble englobant les USA, l&rsquo;OTAN, l&rsquo;UE et les divers organisations financi\u00e8res et humanitaires y aff\u00e9rant<\/strong>. Certes, les avantages consid\u00e9rables amass\u00e9es par les USA durant plus d&rsquo;un demi-si\u00e8cle, comme le renseignement, l&rsquo;infrastructure militaire, l&rsquo;usage du dollar, etc., ont subsist\u00e9, mais d&rsquo;ailleurs avec des contraintes de plus en plus grandes pesant sur eux, et dans nombre de domaines des d\u00e9savantages co&ucirc;teux contribuant \u00e0 la \u00ab\u00a0d\u00e9cadence du [pseudo-]empire\u00a0\u00bb. Mais le c&oelig;ur m\u00eame de la dynamique, ce que nous nommons <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, est devenu commun \u00e0 tous les \u00e9l\u00e9ments constituant le bloc-BAO, avec ses diverses contraintes pesant sur tous les \u00e9l\u00e9ments constitutifs.<\/p>\n<\/p>\n<p><p>En un sens, on pourrait certainement donner l&rsquo;interpr\u00e9tation que <strong>le bloc-BAO est devenu la transcription op\u00e9rationnelle du globalisme, domaine o&ugrave; il n&rsquo;y a aucune sup\u00e9riorit\u00e9 d\u00e9cisive marqu\u00e9e d&rsquo;un des \u00e9l\u00e9ments constitutifs sur les autres<\/strong>, m\u00eame s&rsquo;il peut y avoir des querelles internes, des divergences, etc., lesquelles se terminaient jusqu&rsquo;\u00e0 il y a peu toujours par un arrangement, un compromis, etc. C&rsquo;est bien entendu ce que Merkel et ses acolytes reprochent \u00e0 Trump, qui est d\u00e9cid\u00e9ment une bestiole assez particuli\u00e8re : la disparition brutale, furieuse, pr\u00e9datrice pour le bloc, de cette volont\u00e9 d&rsquo;arrangement et de compromis. Bien que d\u00e9pourvu de la moindre pens\u00e9e politique, de la moindre conception structur\u00e9e, etc., <strong>Trump est visc\u00e9ralement un anti-globaliste encore plus qu&rsquo;un <em>America-Firster<\/em>, mais cela le conduisant \u00e0 une attitude qui s&rsquo;apparente souvent (pas toujours) \u00e0 celle d&rsquo;un <em>America-Firster<\/em><\/strong>. Cela n&rsquo;est donc pas l&rsquo;Allemagne (renaissante) de Merkel contre les USA de Trump perdus dans un d\u00e9lire \u00e0 propos d&rsquo;une h\u00e9g\u00e9monie d&rsquo;un autre temps mais les globalistes avec Merkel comme porte-drapeau et l&rsquo;UE en bandouill\u00e8re contre Trump, avec le <em>Deep State<\/em> US de plus en plus tent\u00e9 de suivre cette voie et de rallier Trump sur ce terrain particulier, ne serait-ce qu&rsquo;\u00e0 cause des avantages \u00e9lectoraux qu&rsquo;on y r\u00e9colte.<\/p>\n<\/p>\n<p><p>Voil\u00e0 pour les positions th\u00e9oriques&#8230; Dans la pratique, ce \u00e0 quoi nous assistons, avec un passage effectivement tr\u00e8s important, <strong>c&rsquo;est \u00e0 la poursuite simultan\u00e9e de la d\u00e9structuration et de la dissolution du bloc-BAO<\/strong>, et nullement sous la seule forme de deux blocs (Europe et USA) se s\u00e9parant en position d&rsquo;affrontement mais sous la forme de l&rsquo;\u00e9loignement de deux constituants (US et Europe) <strong>eux-m\u00eames en cours de dissolution interne<\/strong> (\u00ab\u00a0guerre civile\u00a0\u00bb \u00e0 Washington D.C., rupture du public avec l&rsquo;<em>establishment<\/em> ; positions tr\u00e8s diff\u00e9rentes sur les questions de souverainet\u00e9 notamment entre &Eacute;tats-membres de l&rsquo;UE et l\u00e0 aussi rupture entre le public et les <em>establishment<\/em> globalistes). (Cela n&#8217;emp\u00eache ni n&#8217;emp\u00eachera nullement des affrontements qui prendront \u00e0 certains moments l&rsquo;allure \u00ab\u00a0de bloc \u00e0 bloc\u00a0\u00bb, mais cela ne sera que dispositions tactiques.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Tout cela s&rsquo;additionne et s&#8217;empile pour affecter l&rsquo;ensemble du bloc-BAO, et le \u00ab\u00a0<em>Watershed Moment<\/em>\u00a0\u00bb d&rsquo;Angela Merkel <strong>n&rsquo;est nullement une rupture<\/strong> impliquant un \u00e9ventuel tournant complet dans l&rsquo;orientation de la dynamique en cours, <strong>mais un \u00e9v\u00e9nement important pour acc\u00e9l\u00e9rer encore plus la dynamique en cours<\/strong>, de m\u00eame que l&rsquo;\u00e9lection de Trump et le mirobolant exercice du pouvoir par le nouveau pr\u00e9sident constituent <strong>un autre \u00e9v\u00e9nement de cette sorte, acc\u00e9l\u00e9rant de son c\u00f4t\u00e9 la m\u00eame dynamique<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(On mentionnera un addendum assez tristounet concernant l&rsquo;entr\u00e9e dans le jeu international du pr\u00e9sident Macron marqu\u00e9 par deux \u00e9v\u00e9nements sur lesquels il n&rsquo;est pas utile d&rsquo;exercer quelque ironie excessive (\u00ab\u00a0\u00e0 vaincre sans gloire&#8230;\u00a0\u00bb) : <a href=\"http:\/\/theduran.com\/beta-male-macron-talks-tough-about-handshake-with-trump-that-is-how-you-get-respect\/\">la poign\u00e9e de main<\/a> avec Trump, o&ugrave; Macron a tenu plus longtemps serr\u00e9e la main de son interlocuteur, remportant ainsi une incontestable victoire \u00e0 mettre \u00e0 l&rsquo;actif de la France ; et l&rsquo;annonce que, lors de sa rencontre avec Poutine de ce jour, Macron devrait <a href=\"https:\/\/euobserver.com\/foreign\/138046\">tenir ferme<\/a> sur les sanctions contre la Russie, justifi\u00e9e par une guerre absolument extraterrestre men\u00e9e par Russie en Ukraine, ou plus pr\u00e9cis\u00e9ment dans le royaume enchant\u00e9 de <em>Wonderland<\/em> qui fait l&rsquo;objet de constructions extraordinaires des services de renseignement occidentaux, sanctions dont plus personne n&rsquo;est capable d&rsquo;expliquer la Cause Premi\u00e8re, la fonction, la coh\u00e9rence, la logique, l&rsquo;utilit\u00e9, le but et finalement la Fin Derni\u00e8re. Bref, c<strong>&lsquo;est d&rsquo;autant plus beau que personne n&rsquo;y comprend rien \u00e0 part de nous dire que \u00ab\u00a0les Russes sont vraiment m\u00e9chants\u00a0\u00bb<\/strong>.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Anatomie du bloc-BAO<\/h3>\n<\/p>\n<p><p>Pour mieux expliciter nos conceptions, il nous para&icirc;t bon, non seulement de renvoyer \u00e0 l&rsquo;article du <em>Glossaire.dde<\/em> sur le bloc-BAO (du <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">10 d\u00e9cembre 2012<\/a>), mais \u00e9galement de reprendre ci-dessous quelques extraits de ce sujet donnant un aper\u00e7u de l&rsquo;un de ses principaux caract\u00e8res qui concerne l&rsquo;un des aspects les plus importants de cette entit\u00e9 telle que nous la concevons&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Le deuxi\u00e8me aspect de cette politique est l&rsquo;\u00e9galitarisation, le nivellement de la politique qu&rsquo;est la politique du bloc BAO, avec notamment l&rsquo;effacement, d&rsquo;ailleurs naturel et comme allant de soi, de la pr\u00e9pond\u00e9rance US. En fait, plus personne n&rsquo;a vraiment besoin d&rsquo;imposer une \u00ab\u00a0politique commune\u00a0\u00bb qui semble couler de source et na&icirc;tre d&rsquo;elle-m\u00eame&hellip; Il existe d\u00e9sormais, depuis 2008-2010, une remarquable unit\u00e9 de pens\u00e9e, de r\u00e9flexe, d&rsquo;attitude, entre tous les pays du bloc. (Le retour de la France au bercail fut le grand \u00e9v\u00e9nement rupturiel \u00e0 cet \u00e9gard. L\u00e0 aussi, nous croyions, dans notre grande na\u00efvet\u00e9, que cela serait l&rsquo;\u00e9pisode d&rsquo;un homme, dito Sarko, comme l&rsquo;on crut \u00e0 l&rsquo;\u00e9pisode Bush aux USA, mais non cela \u00e9tait fondamental et substantiel. Trahissant tous les principes, comme cette exceptionnelle nation a l&rsquo;habitude de faire dans ses p\u00e9riodes de basses eaux o&ugrave; elle devient le double inverti, l&rsquo;\u00e9pouvantable caricature de sa grandeur, la France a sombr\u00e9 dans la subversion d&rsquo;elle-m\u00eame et s&rsquo;est impos\u00e9e comme un des p\u00f4les du bloc ; comme une fille et comme une midinette, sans s&rsquo;apercevoir de son infamie, toute fi\u00e9rote de se croire l&rsquo;\u00e9gale d&rsquo;elle-m\u00eame avec sa si fameuse intelligence r\u00e9duite au slogan \u00e2nonn\u00e9 par les salons parisiens. Son ralliement, qui est presque v\u00e9cu dans leurs esprits r\u00e9duits aux acqu\u00eats comme une affirmation de la grandeur et de l&rsquo;ind\u00e9pendance fran\u00e7aises, a constitu\u00e9 le verrou ultime qui cimente le bloc. Dont acte.) <\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>La politique disons \u00ab\u00a0atlantiste\u00a0\u00bb ou \u00ab\u00a0occidentale\u00a0\u00bb, avec domination des USA, est devenue la \u00ab\u00a0politique du bloc BAO\u00a0\u00bb en adoptant des th\u00e8mes centraux qui n&rsquo;ont plus de rapports avec la politique de force qu&rsquo;affectionnaient des gens comme Kagan et autres neocons du d\u00e9but de la d\u00e9cennie 2000 (du type \u00ab\u00a0les USA sont sur Mars, l&rsquo;Europe est sur V\u00e9nus\u00a0\u00bb). Ces th\u00e8mes centraux sont essentiellement moraux, dans le registre humanitariste. Il ne s&rsquo;agit plus de la \u00ab\u00a0d\u00e9mocratie conqu\u00e9rante\u00a0\u00bb de l&rsquo;\u00e9poque Bush, mais du \u00ab\u00a0droitdel&rsquo;hommisme\u00a0\u00bb dans toute sa pl\u00e9nitude, laquelle inclut une dimension d\u00e9mocratique pos\u00e9e comme une \u00e9vidence vertueuse objective comme l&rsquo;est une patte molle. C&rsquo;est une politique v\u00e9ritablement inspir\u00e9e de caract\u00e8res exceptionnellement mous, sinon caoutchouteux et adh\u00e9rant \u00e0 n&rsquo;importe quelle circonstance, exprim\u00e9s par une voix m\u00e2le, martiale et superbe (qui ne pense pas \u00e0 BHL, ou Bernard-Henri Levy, se verrait difficilement pardonn\u00e9), justifiant l&#8217;emploi de la force comme une chose qui va de soi et qui devrait l&rsquo;\u00eatre id\u00e9alement sans aucune contrainte. La vertu affich\u00e9e de cette \u00ab\u00a0politique\u00a0\u00bb cr\u00e9e le Droit \u00e0 chaque instant et selon les circonstances (le Droit constamment recr\u00e9\u00e9 selon la partition du bloc BAO, avec une seule constante qui est la majuscule) ; elle objective ceux qui s&rsquo;en r\u00e9clament en les d\u00e9gageant de toute responsabilit\u00e9<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; [&#8230;Cette] <em>politique est devenue, bien entendu, compl\u00e8tement soumise \u00e0 l&rsquo;affectivit\u00e9, selon ce que nous en avons largement dit le <a href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\">11 juin 2012<\/a><\/em> [et aussi le <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">5 octobre 2016<\/a>, l'\u00a0\u00bbaffectivit\u00e9\u00a0\u00bb \u00e9tant devenu \u00ab\u00a0affectivisme\u00a0\u00bb]<em>&hellip; A ce point, on peut repousser compl\u00e8tement le soup\u00e7on de \u00ab\u00a0f\u00e9minisation\u00a0\u00bb qui nous ferait classer parmi les relaps de la modernit\u00e9 et excommunier vite fait : tous, absolument tous, les hommes aussi bien, sont frapp\u00e9s par cela, et il n&rsquo;y a plus de \u00ab\u00a0f\u00e9minisation\u00a0\u00bb \u00e0 cet \u00e9gard mais, simplement, une pression constante de l&rsquo;affectivit\u00e9 qui devient comme une formule universelle de tout acte politique. On comprend, bien entendu, \u00e0 relire le texte auquel nous faisions r\u00e9f\u00e9rence, qu&rsquo;il s&rsquo;agit l\u00e0 du point fondamental de cette \u00ab\u00a0politique du bloc BAO\u00a0\u00bb, qui implique une soumission compl\u00e8te des psychologies au Syst\u00e8me, et cela passant par cette pr\u00e9pond\u00e9rance de l&rsquo;affectivit\u00e9 sur la raison subvertie et devenue \u00ab\u00a0idiote utile\u00a0\u00bb<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Dans ce cadre totalement d\u00e9l\u00e9t\u00e8re, et pour ce qui nous concerne, \u00ab\u00a0nous-Europ\u00e9ens\u00a0\u00bb, il n&rsquo;\u00e9tonnera personne que nous ajoutions un volet concernant une pouss\u00e9e vers l&rsquo;abdication des souverainet\u00e9s, qu&rsquo;il faut r\u00e9solument placer dans le cadre de cette constitution du bloc BAO. Aujourd&rsquo;hui, l&rsquo;id\u00e9e du transfert de souverainet\u00e9 des nations vers les institutions europ\u00e9ennes pour renforcer une \u00ab\u00a0politique \u00e9trang\u00e8re commune\u00a0\u00bb est l&rsquo;un des grands th\u00e8mes en vogue des discours et des divers documents de r\u00e9flexion dans les milieux europ\u00e9ens<\/em>&#8230; &raquo; <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Merkel et son \u00ab\u00a0Moment d\u00e9cisif\u00a0\u00bb : quels effets ? 29 mai 2017 &ndash; Apr\u00e8s la r\u00e9union du G7 devenu G6+1 et qu&rsquo;on pourrait aussi bien d\u00e9signer comme le \u00ab\u00a0G7-1\u00a0\u00bb, on ne parle que de ce \u00ab\u00a0moment d\u00e9cisif\u00a0\u00bb, le \u00ab\u00a0Watershed Moment\u00a0\u00bb d&rsquo;Angela Merkel ; lorsque, rentr\u00e9e du sommet en Sicile et venue \u00e0 Munich pour un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[12550,7844,13074,5627,584,3182,4079,1205,2639,11216,13075],"class_list":["post-77290","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bloc-bao","tag-g7","tag-g71","tag-moment","tag-otan","tag-reich","tag-servilite","tag-transatlantique","tag-trump","tag-volontaire","tag-watershed"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77290"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77290\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}