{"id":77301,"date":"2017-06-06T10:21:28","date_gmt":"2017-06-06T10:21:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/06\/crise-idiote-pleine-de-bruit-et-de-fureur-qui-ne-signifie-rien\/"},"modified":"2017-06-06T10:21:28","modified_gmt":"2017-06-06T10:21:28","slug":"crise-idiote-pleine-de-bruit-et-de-fureur-qui-ne-signifie-rien","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/06\/crise-idiote-pleine-de-bruit-et-de-fureur-qui-ne-signifie-rien\/","title":{"rendered":"Crise idiote, pleine de bruit et de fureur, qui ne signifie rien"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Crise idiote, pleine de bruit et de fureur, qui ne signifie rien<\/h2>\n<\/p>\n<p><p>Notre \u00e9poque est parcourue de tant de foyers crisiques, qu&rsquo;on peut aussi bien nommer, par exemple et bon exemple pour le cas choisi, \u00ab\u00a0s\u00e9isme g\u00e9opolitique\u00a0\u00bb, qu&rsquo;on finit par se lasser \u00e0 en chercher les causes rationnelles pour y voir, \u00e0 notre sens justement, l&rsquo;action de forces d\u00e9structurantes et dissolvantes, semeuses de d\u00e9sordres et de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-chaos-nouveau\">chaos-nouveaux<\/a> c&rsquo;est selon, bien entendu hors de toute causalit\u00e9 consciente et de capacit\u00e9 humaines, y compris pour l&rsquo;annonce de leur survenue, pour les causes profonds de ces spasmes, sur la fa\u00e7on de les traiter quand on y songe encore, sur les cons\u00e9quences \u00e0 envisager, etc. Cette phrase, par sa longueur notamment, montre bien l&#8217;embarras de poser un jugement net sur l&rsquo;\u00e9v\u00e9nement qui vient de survenir, et par cons\u00e9quent la difficut\u00e9 de d\u00e9velopper un commentaire. Pourtant il faut en parler, <strong>et m\u00eame il est n\u00e9cessaire d&rsquo;en parler pour dire notamment pourquoi on pourrait se dispenser d&rsquo;en parler s&rsquo;il ne s&rsquo;agissait que de la seule raison<\/strong>.<\/p>\n<\/p>\n<p><p>Des explications plus ou moins p\u00e9remptoires \u00e0 propos de cet \u00e9v\u00e9nement abondent dont aucune n&rsquo;est convaincante et de loin, dont il s&rsquo;av\u00e8re qu&rsquo;il est (cet \u00e9v\u00e9nement) sans pr\u00e9c\u00e9dent sans que l&rsquo;absence de pr\u00e9c\u00e9dent ne semble avoir \u00e0 la lumi\u00e8re de la situation actuelle la moindre importance, et ainsi de suite. Tout au plus dira-t-on que l&rsquo;\u00e9v\u00e9nement se situe au bon endroit pour <strong>justifier tout ce scepticisme un peu fatigu\u00e9 devant le simulacre d&rsquo;\u00e9v\u00e9nements que nous offrent la quotidiennet\u00e9 de la postmodernit\u00e9<\/strong>, puisqu&rsquo;il s&rsquo;agit principalement d&rsquo;une querelle incompr\u00e9hensible \u00e0 l&rsquo;int\u00e9rieur du cercle tr\u00e8s ferm\u00e9 des &Eacute;tats du Golfe ; cela, apr\u00e8s le montage de la mirobolante coalition des Mille-et-Une-Nuits mont\u00e9e par l&rsquo;Arabie (55 pays !), \u00e0 Ryad le mois dernier, sous les yeux \u00e9blouis du pr\u00e9sident Trump. <\/p>\n<\/p>\n<p><p>Voici quelques d\u00e9tails assez \u00ab\u00a0neutres\u00a0\u00bb de l&rsquo;\u00e9v\u00e9nements, dans <em>Le Figaro-Vox<\/em> <a href=\"http:\/\/www.lefigaro.fr\/flash-actu\/2017\/06\/05\/97001-20170605FILWWW00022-l-arabie-et-ses-allies-rompent-avec-le-qatar-accuse-de-soutenir-le-terrorisme.php\">du 5 juin, d&rsquo;apr\u00e8s AFP<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ryad, Le Caire, Abou Dhabi et Manama ont rompu aujourd&rsquo;hui avec le Qatar, accus\u00e9 de soutenir le &quot;terrorisme&quot;, quinze jours apr\u00e8s un voyage de Donald Trump qui avait exhort\u00e9 les pays musulmans \u00e0 se mobiliser contre l&rsquo;extr\u00e9misme<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le Qatar, qui se targue de jouer un r\u00f4le r\u00e9gional et d&rsquo;avoir \u00e9t\u00e9 choisi pour organiser le Mondial-2022 de football, a \u00e9galement \u00e9t\u00e9 exclu de la coalition militaire arabe qui combat des rebelles pro-iraniens au Y\u00e9men. Doha a r\u00e9pondu en accusant ses voisins du Golfe de chercher \u00e0 le mettre sous tutelle. Ces mesures sont &quot;injustifi\u00e9es&quot; et &quot;sans fondement&quot;, a r\u00e9agi le minist\u00e8re des Affaires \u00e9trang\u00e8res du Qatar dans un communiqu\u00e9. Elles ont un &quot;objectif clair: placer l&rsquo;Etat (du Qatar) sous tutelle, ce qui marque une violation de sa souverainet\u00e9&quot; et est &quot;totalement inacceptable&quot;, a-t-il ajout\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il s&rsquo;agit de la crise la plus grave depuis la cr\u00e9ation en 1981 du Conseil de coop\u00e9ration du Golfe (CCG: Arabie saoudite, Bahre\u00efn, Emirats arabes unis, Kowe\u00eft, Oman, Qatar). Trois de ces pays (Arabie, Emirats, Bahre\u00efn), ainsi que l&rsquo;Egypte, ont tour \u00e0 tour annonc\u00e9 \u00e0 l&rsquo;aube la rupture de leurs relations diplomatiques avec le Qatar, qu&rsquo;ils accusent de &quot;soutien au terrorisme&quot;, y compris Al-Qa\u00efda, le groupe Etat islamique (EI) et la confr\u00e9rie des Fr\u00e8res musulmans.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; On voit que cette \u00ab\u00a0crise dans la crise\u00a0\u00bb (et cette derni\u00e8re dans une \u00ab\u00a0autre crise\u00a0\u00bb, et ainsi les crises s&#8217;emboitant comme des poup\u00e9es russes jusqu&rsquo;\u00e0 en arriver \u00e0 la Grande Crise G\u00e9n\u00e9rale bien entendu) intervient apr\u00e8s le grand sommet de Ryad, avec pr\u00e9sence enthousiaste de Trump. Les \u00e9chos des commentateurs s\u00e9rieux avaient en g\u00e9n\u00e9ral \u00e9t\u00e9 tr\u00e8s pr\u00e9occup\u00e9s par les r\u00e9sultats de cette conf\u00e9rence et notamment par l&rsquo;attitude de Trump. L&rsquo;on peut r\u00e9sumer ces pr\u00e9occupations par <a href=\"https:\/\/consortiumnews.com\/2017\/06\/03\/trump-tumbles-into-saudi-israeli-trap\/\">la th\u00e8se d&rsquo;Alastair Crooke<\/a>, sp\u00e9cialiste incontestable du domaine, selon lequel il semblait bien que Trump f&ucirc;t tomb\u00e9 dans un pi\u00e8ge tendu par l&rsquo;Arabie et Isra\u00ebl,&ndash; selon la promesse fallacieuse qu&rsquo;en agr\u00e9ant aux conventions saoudiennes et \u00e0 l&rsquo;hostilit\u00e9 \u00e0 l&rsquo;Iran que cela implique, avec Isra\u00ebl applaudissant \u00e0 la chose et promettant ce qu&rsquo;il n&rsquo;a jamais tenu, il (Trump) parviendrait \u00e0 parrainer un r\u00e8glement de l&rsquo;interminable impasse isra\u00e9lo-palestinienne&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>This &ndash; the Sunni-Israeli regional Alliance; the renewed peace process &ndash; is a trap into which Trump has been persuaded to enter. It is a trap, because once entered into, the peace process becomes formaldehyde to all other political processes. <\/em><em>How often have we been told \u00ab\u00a0you can&rsquo;t do this; you can&rsquo;t do that\u00a0\u00bb because it might endanger the (vacuous) \u00ab\u00a0peace process.\u00a0\u00bb <\/em><em>A peace process gives Israel huge anesthetic leverage in the region &ndash; as always it has so done. It is a trap &ndash; because it ties Trump into trying to assuage the Irano-phobia of Saudi Arabia, which will prove to be just as insatiable as are Israel&rsquo;s \u00ab\u00a0security needs.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>These liabilities will undercut Trump&rsquo;s possibilities for defeating ISIS and for d\u00e9tente with Russia. Russia has been trying <a href=\"http:\/\/www.al-monitor.com\/pulse\/originals\/2017\/05\/trump-russia-middle-east-saudi-arabia-visit-israel-iran.html\">to bring<\/a> the Shi&rsquo;a and the Turks to the negotiating table on Syria. <\/em><em>Trump&rsquo;s role was to be to help bring the Sunni side to the table &ndash; in order to forge a wider regional settlement. That will be less likely now, as Saudi Arabia levers Trump&rsquo;s visit towards weakening Iran.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>With Trump&rsquo;s homage to the Sunni cause, it is more likely that the Sunni-Shi&rsquo;a fissure will deepen, rather than its sore edges be reconciled. And, viewed from a pure realpolitik perspective, does Trump really believe that Saudi Arabia and its allies will succeed in weakening the Russia, Iran, Syria, Iraq and Hizbullah alliance?<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; &#8230; Mais la question aussit\u00f4t pos\u00e9e dans les jours qui suivirent de savoir dans quel le pi\u00e8ge Trump \u00e9tait tomb\u00e9, devint bient\u00f4t de savoir si l&rsquo;Arabie, m\u00eame avec son acolyte isra\u00e9lien en soutien, est capable de tendre un pi\u00e8ge s\u00e9rieux. Il s&rsquo;agit d&rsquo;une situation o&ugrave; elle-m\u00eame, l&rsquo;Arabie, se trouve enferm\u00e9e dans des pressions continuelles venues de tous c\u00f4t\u00e9s, qui sont autant de pi\u00e8ges, qu&rsquo;il s&rsquo;agisse d&rsquo;un effondrement budg\u00e9taire constant \u00e0 cause du prix du p\u00e9trole, d&rsquo;une guerre du Y\u00e9men devenue un bourbier sanglant d\u00e9signant le pays \u00e0 la vindicte g\u00e9n\u00e9rale de toute diplomatie s\u00e9rieuse et d\u00e9cente, d&rsquo;une \u00ab\u00a0grande strat\u00e9gie\u00a0\u00bb de l&rsquo;aide \u00e0 de redoutables terroristes extr\u00e9mistes qui <strong>devaient,<\/strong> <strong>il y a cinq ans d\u00e9j\u00e0, faire tomber Assad \u00ab\u00a0en trois semaines\u00a0\u00bb (selon les Isra\u00e9liens eux-m\u00eames)<\/strong>&#8230; La r\u00e9union de Ryad fut donc \u00e0 cette image, <strong>un simulacre enlumin\u00e9 d&rsquo;un luxe inou\u00ef et de d\u00e9clarations bombastiques o&ugrave; personne ne croyait vraiment un seul mot<\/strong> de la construction postmoderne dont l&rsquo;\u00e9dification \u00e9tait confi\u00e9e \u00e0 des architectes experts instinctifs en d\u00e9construction.<\/p>\n<\/p>\n<p><p>Sur RT, la sp\u00e9cialiste du Moyen-Orient Shamine Narwani concluait son analyse (le <a href=\"https:\/\/www.rt.com\/op-edge\/390453-trump-saudi-orb-arab-summit\/\">1<sup>er<\/sup> juin 2017<\/a>) de cette fa\u00e7on, apr\u00e8s avoir \u00e9num\u00e9r\u00e9 les innombrables contradictions, fausses propositions, affirmations erron\u00e9es, int\u00e9r\u00eats divergents, etc., qui caract\u00e9risent les acteurs pr\u00e9sents :<\/p>\n<\/p>\n<p><p>&laquo; <em>On the surface, the purpose of the Riyadh summit was to amass a coalition of like-minded Arab and Muslim partner-states, under a Saudi-American banner, to wage war against terror. In fact, this is a Saudi and American-led initiative created not to tackle terror, but to &lsquo;reframe&rsquo; it to encompass political adversaries. Look out for pundits and politicians spinning these new narratives that Iran, Hezbollah, and the Muslim Brotherhood are equally as dangerous as ISIS and Al-Qaeda &ndash; never mind that the former have been around for decades without triggering the global security meltdown spawned by the latter.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>In Riyadh, the Americans and Saudis made a great show of jointly announcing two additions to their \u00ab\u00a0terrorism\u00a0\u00bb list &ndash; one was a senior Hezbollah official, the other a senior member of ISIS. <\/em><em>This is not the war against terror that the heads of states gathered in Riyadh anticipated. This is a sectarian war, conceived by a sectarian state that has <\/em><em><a href=\"https:\/\/mideastshuffle.com\/2014\/10\/04\/biden-turks-saudis-uae-funded-and-armed-al-nusra-and-al-qaeda\/\" target=\"_blank\">funded, armed and organized<\/a><\/em><em> the very global terrorism it purports to fight. And every single US administration since the events of 9\/11 has acknowledged this direct Saudi role in terror.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>In Riyadh, the show went on anyway. But there&rsquo;s not a person in that room who didn&rsquo;t understand the game. Forget the &lsquo;Sunni consensus&rsquo; after Riyadh. Of the 55 nations represented at the summit, the Saudis will be lucky to retain five<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Venons-en maintenant \u00e0 la \u00ab\u00a0bombe\u00a0\u00bb d&rsquo;hier matin : l&rsquo;attaque diplomatique et \u00e9conomique lanc\u00e9e contre le Qatar par \u00ab\u00a0une coalition dans la coalition\u00a0\u00bb initiale des 55, contre un des membres de cette \u00ab\u00a0coalition initiale\u00a0\u00bb&#8230; <em>TheDuran.com<\/em>, apr\u00e8s avoir insist\u00e9 sans vraiment y croire sur le fait que cette initiative illustrait une tentative de l&rsquo;Arabie \u00e9conomiquement \u00e0 bout de souffle de faire <a href=\"http:\/\/theduran.com\/qatar-crisis-oil-stupid\/\">monter le prix du p\u00e9trole<\/a>, estime que l&rsquo;appr\u00e9ciation finalement (pour l&rsquo;instant, c&rsquo;est-\u00e0-dire au moins jusqu&rsquo;\u00e0 demain) qu&rsquo;on peut faire de cet \u00e9v\u00e9nement de la rupture avec le Qatar est qu&rsquo;il <a href=\"http:\/\/theduran.com\/donald-trump-is-a-clear-winner-in-the-qatarsaudi-divide\/\">satisfait pleinement<\/a> Trump. Adam Gurrie d\u00e9veloppe ici l&rsquo;id\u00e9e que Trump, en bon n\u00e9o-isolationniste, \u00e9tait venu dire aux Saoudiens \u00ab\u00a0Vous voulez la t\u00eate de l&rsquo;Iran ? Eh bien allez-y, nous vous regardons faire\u00a0\u00bb, cela en esp\u00e9rant que les notoirement militairement-catastrophiques Saoudiens, avec l&rsquo;immense d\u00e9sordre que repr\u00e9sentent les rassemblements sunnites, n&rsquo;iraient pas tr\u00e8s loin et, au contraire, finiraient par introduire le d\u00e9sordre dans leurs propres rangs, entre sunnites. Cela commence \u00e0 se faire, poursuit l&rsquo;hypoth\u00e8se, et compromet toute pression s\u00e9rieuse sur l&rsquo;Iran, ce qui satisfait pleinement le pr\u00e9sident US \u00e0 qui ni les Saoudiens ni les Isra\u00e9liens ne peuvent rien reprocher, et qui voit s&rsquo;\u00e9loigner la possibilit\u00e9 d&rsquo;un conflit avec l&rsquo;Iran&#8230; Car Trump, m\u00eame s&rsquo;il est notoirement anti-Iran, est d&rsquo;abord n\u00e9o-isolationniste et <em>America First <\/em>et n&rsquo;a vraiment pas besoin d&rsquo;une nouvelle guerre sur ce th\u00e9\u00e2tre, et encore moins avec l&rsquo;Iran !<\/p>\n<\/p>\n<p><p>&laquo; <em>And why might Trump be privately happy about that?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Few in America, even in the deep state seriously believe that US involvement in a war with Iran would be a good thing. They are willing to talk tough on Iran, lie about Iran to the hilt and sanction Iran but when it comes to direct conflict, every President from Jimmy Carter up through Donald Trump has yet to raise a realistic finger against the Islamic Republic of Iran.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Trump, in spite of his own anti-Iranian rhetoric is if anything still far less interventionist than either Bush or Obama and even they didn&rsquo;t go after Iran. If Saudi Arabia was ever so foolish as to provoke a war with Iran, America would be forced to make the uncomfortable decision of refraining from a fight that many at least at the level of perverse dreams seek to fight. Now, an all ready insane idea of Saudi launching a war against Iran is even less likely as two major Arab Gulf powers are themselves arguing over Iran in public. <\/em><em>Trump has said what he &lsquo;needed&rsquo; to say and can now wash his hands of further attempts at forcing the Arab world to do what it has always been incapable of doing.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Increasingly, it has become apparent that Trump sees international relations in terms of monetary benefit and personal status, but critically now ideology. He enjoyed being treated by a king in Saudi and getting paid for it, he enjoyed being lauded endlessly by the Likud government in Israel and he distinctly did not enjoy his trip to Europe where NATO and G7 leaders treated him far less respectfully than did Saudi or Israel and even more importantly, they didn&rsquo;t pay up in respect of NATO.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Donald Trump got the two things he wanted from the Gulf: money and respect. While Obama may have been making urgent phone calls at such a time, Trump will probably leave matters to civil servants in the State Department. His mind is more on golf than on the Gulf<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Pour le site tenu par \u00ab\u00a0b\u00a0\u00bb de <em>Moon of Alabama <\/em>(<a href=\"http:\/\/russia-insider.com\/en\/politics\/beautiful-gcc-tears-itself-apart-saudis-uae-bahrain-break-qatar-links\/ri20032\">ici repris<\/a> par <em>Russia Insider<\/em>), il semble acquis que le grand vainqueur de cette pantalonnade cosmique qualifi\u00e9e en g\u00e9n\u00e9ral de \u00ab\u00a0s\u00e9isme g\u00e9ostrat\u00e9gique\u00a0\u00bb dont on se demande pr\u00e9cis\u00e9ment \u00e0 quoi il correspond et sa raison d&rsquo;\u00eatre sera sans nul doute l&rsquo;Iran. On peut ais\u00e9ment le croire apr\u00e8s tout parce qu&rsquo;au royaume des fous, l&rsquo;Iran appara&icirc;t comme une grande &icirc;le de sagesse&#8230; Effectivement, dans cette d\u00e9bauche de violence, de folies et d&rsquo;irrationalit\u00e9 qui touche la plupart des pays de la r\u00e9gion depuis six ans et les d\u00e9buts du \u00ab\u00a0printemps arabe\u00a0\u00bb, essentiellement les &Eacute;tats du Golfe et l&rsquo;Arabie, la Turquie, Isra\u00ebl, etc., l&rsquo;Iran est certainement lr pays qui garde le plus la t\u00eate froide (avec Assad de Syrie, Sisi d&rsquo;&Eacute;gypte malgr\u00e9 sa pr\u00e9sence du bout des l\u00e8vres \u00e0 Ryad, et le Hezbollah). Tout cela ne fait que pr\u00e9parer la mise en sc\u00e8ne de l&rsquo;effondrement du rassemblement en carton-p\u00e2te des &Eacute;tats du Golfe.<\/p>\n<\/p>\n<p><p>&laquo; <em>Iran could see a chance to further blow up the GCC by intensifying its relations with Qatar. It could increase its food exports to the country and host Qatar airline flights. <\/em><em>This in exchange for a Qatari retreat from Syria. The U.S.\/Saudi plan of confronting Iran through the GCC would then be in complete jeopardy.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The linch pin of all this is the Saudi war on Yemen. The Saudis support the Hadi puppet government of Yemen and two years ago aligned the other Gulf states, including Qatar, to fight against the Houthi in north Yemen. They accuse the Houthi of receiving Iranian support. There is zero evidence for that claim.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The war and the coalition have failed. <\/em><em>Houthi resistance continues unabated. With Yemen sinking into a famine thanks to a Saudi border blockade and a Cholera epidemic rapidly extending, the war must come to a close. <\/em><em>Kuwait, Oman and Qatar are talking with the Houthi in Sanaa. Last week troops from the UAE used helicopters to again fight Saudi supported militia around the southern airport in Aden.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The U.S. and Britain urge for the war to end and, behind closed doors, threaten to withdraw their support for it. The Saudi under their new leadership overestimate their capabilities. So did Trump when he raised their role. The Saudi &quot;apes with Macbooks&quot; do not have the capabilities needed for a serious political actor in this world. Their money can pamper over that for only so long.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The above all reminds of a <\/em><em><a href=\"https:\/\/twitter.com\/BaFana3\/status\/632453961233092609@BaFana3\">prediction made<\/a><\/em><em> nearly two years ago by a Yemeni attorney in Sanaa (<a href=\"https:\/\/twitter.com\/BaFana3\/status\/632453961233092609\">9:29 AM &#8211; 15 Aug 2015) : <\/a>\u00ab\u00a0At the end of this war on <\/em><em><a href=\"https:\/\/twitter.com\/hashtag\/Yemen?src=hash\">#Yemen<\/a><\/em><em>, the GCC states led by Saudi Arabia will collapse into oblivion. I do not know what will replace them.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Ceux qui essaient d&rsquo;expliquer l&rsquo;antagonisme entre l&rsquo;Arabie et le Qatar et tombent au bout du compte sur l&rsquo;\u00e9vidence d&rsquo;un vide abyssal ne peuvent tout de m\u00eame s&#8217;emp\u00eacher de r\u00e9agit par des formules refl\u00e9tant l&rsquo;absurdit\u00e9 du conflit. <a href=\"https:\/\/www.rt.com\/op-edge\/390453-trump-saudi-orb-arab-summit\/\">Comme l&rsquo;explique<\/a> Marwa Osman \u00e0 RT, il s&rsquo;agit apr\u00e8s tout <strong>de &laquo; <em>gens qui soutiennent le terrorisme, qui accusent d&rsquo;autres gens qui soutiennent le terrorisme de soutenir le terrorisme<\/em> &raquo;<\/strong>. N\u00e9anmoins l&rsquo;excellente analyste, qui fait son travail avec conscience et utilise par cons\u00e9quent ses connaissances d&rsquo;une fa\u00e7on rationnelle et mesur\u00e9e, entend rester s\u00e9rieuse en offrant une explication \u00e0 une hostilit\u00e9 dont les racines remontent au moins aux ann\u00e9es 1950 :<\/p>\n<\/p>\n<p><p>&laquo; <em>They started surfacing, to begin with, in 2011&hellip; But I think people who are harboring terrorism are now accusing other people who are also harboring terrorism of harboring terrorism. <\/em><em>That should be a punch line of a very serious joke, but it is not. It is very risky, challenging for the entire region. We started feeling the heat between Qatar and Saudi Arabia three month ago when the affiliates that are being funded by both states started bickering and fighting each other in Syria. That was the first mark that started a war of words between them which concluded in what happened today. But they surfaced at the beginning of the so-called Arab uprisings, and Arab Spring in 2011, that had a historical background. It did show that they challenged one another since the 2011 uprisings to take control of the MENA region &ndash; who funds which group in which state starting from Tunisia ending up in Syria passing through Libya, obviously. But it all started in the 1950&rsquo;s. The main bickering of Saudi Arabia and Qatar started with the Saudi support for the Muslim Brotherhood and started from the Gulf War being enemies<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Alexander Mercouris <a href=\"http:\/\/theduran.com\/saudi-arabia-versus-qatar-folly-saudi-deputy-crown-prince\/\">intervient sur <em>TheDuran.com<\/em><\/a>, sans doute de la fa\u00e7on la plus justifi\u00e9e et la plus responsable que nous puissions imaginer, en observant simplement qu&rsquo;on ne comprend rien \u00e0 cette initiative des Saoud parce qu&rsquo;il n&rsquo;y a rien \u00e0 comprendre, qu&rsquo;elle n&rsquo;est explicable par rien, et qu&rsquo;elle marquerait, si nous traduisons la chose selon nos conceptions, une sorte de fr\u00e9n\u00e9sie psychologique proche de la pathologie. Il s&rsquo;agit bien d&rsquo;une initiative, ou d&rsquo;une crise plus simplement, \u00ab\u00a0dite par un idiot, pleine de bruit et de fureur, et qui ne signifie rien\u00a0\u00bb. &laquo; <em>La d\u00e9cision pr\u00e9cipit\u00e9e et inexpliqu\u00e9e de rompre les relations avec le Qatar et d&rsquo;imposer contre lui un blocus a\u00e9rien et terrestre porte <strong>la marque de l&rsquo;habituelle mani\u00e8re erratique de prise de d\u00e9cision<\/strong> du Prince h\u00e9ritier et monarque r\u00e9gnant de facto, Prince Mohammed bin Salman. Il y a des d\u00e9bats consid\u00e9rables sur les explications de cette attaque diplomatique et \u00e9conomique organis\u00e9e aujourd&rsquo;hui par l&rsquo;Arabie contre le Quatar. <strong>Ce qui la rend stup\u00e9fiante est bien qu&rsquo;il n&rsquo;y a aucune explication<\/strong><\/em>&#8230; &raquo; (Quant au Qatar, tout de m\u00eame affol\u00e9 par cette attaque, sa premi\u00e8re r\u00e9action a \u00e9t\u00e9 <a href=\"http:\/\/theduran.com\/desperate-qatar-calls-russia\/\">d&rsquo;appeler le Russe Lavrov<\/a>, &ndash; <strong>on voit qui compte, aujourd&rsquo;hui<\/strong>, &ndash; qui lui a assur\u00e9 que ce conflit, comme les autres, devrait se r\u00e9soudre par la n\u00e9gociation et non par la force.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Il s&rsquo;agit d&rsquo;un royaume, l&rsquo;Arabie, qui avait habitu\u00e9 \u00e0 la prudence et au calcul peureux en toutes choses, et qui semble avoir atteint l&rsquo;\u00e9tape finale d&rsquo;un comportement erratique, chaotique, etc., ce qui incite effectivement \u00e0 donner une explication qui n&rsquo;est pas \u00e9loign\u00e9e du <strong>diagnostic de la simple d\u00e9mence <\/strong>caract\u00e9risant aujourd&rsquo;hui tant d&rsquo;actes diplomatiques et tant de politiques. L&rsquo;Arabie <strong>ne ferait apr\u00e8s tout que succomber \u00e0 un mal g\u00e9n\u00e9ral qui touche une civilisation-Syst\u00e8me<\/strong>, une civilisation globalis\u00e9e qui a perdu tout son sens et tout son \u00e9quilibre, une civilisation en cours d&rsquo;effondrement mais qu&rsquo;on d\u00e9crirait mieux en se r\u00e9f\u00e9rant \u00e0 la dynamique g\u00e9n\u00e9rale de l&rsquo;\u00e9poque <strong>comme \u00e9tant en cours de d\u00e9construction acc\u00e9l\u00e9r\u00e9e<\/strong>&#8230; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>&laquo; <em>Saudi Arabia is a notoriously closed and secretive society, whose inner counsels are very difficult for outsiders to read or penetrate.  However there must be people within Saudi Arabia who must be becoming increasingly worried at the erratic and increasingly reckless way in which the affairs of the Kingdom are being managed.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Not so long ago Saudi Arabia was famous throughout the region for always acting quietly and with discretion.  Today under the leadership of Deputy Crown Prince Mohammed bin Salman it acts brazenly and irresponsibly. One wonders for how long this will continue before opposition to Prince Mohammed bin Salman crystallises.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The Saudi Princes have in the past shown a ruthless ability to act decisively in order to preserve their positions, and <a href=\"https:\/\/en.wikipedia.org\/wiki\/Saud_of_Saudi_Arabia\" target=\"_blank\">it is not unknown for a Saudi King to be removed from the throne<\/a> if his behaviour comes to be seen as destabilising. <\/em><em>Perhaps it is time for Prince Mohammed bin Salman &ndash; who is not even King yet &ndash; to start watching his back.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Better still, he needs &ndash; urgently &ndash; to start listening to some advice<\/em>.<\/p>\n<\/p>\n<p><p>On observera que l&rsquo;Arabie, qui reste la grande vedette de cet \u00e9pisode, est <strong>une sorte d&rsquo;arch\u00e9type de la pourriture de toutes les sortes de corruption possibles, et pourtant qui ne parvient pas \u00e0 s&rsquo;effondrer<\/strong>. Depuis des d\u00e9cennies, (depuis 1976 et la mort du roi Fay\u00e7al, depuis 1979 et l&rsquo;attaque terroriste des Lieux saints), nous entendons des bruits, analyses et hypoth\u00e8ses sur l&rsquo;effondrement de la baraque branlante des Saoud. Chaque fois, l&rsquo;hypoth\u00e8se nous para&icirc;t absolument fond\u00e9e, chaque fois elle ne se r\u00e9alise pas. Il est vrai que pendant longtemps, comme le souligne Mercouris, le royaume, tremblant de trouille, <strong>continuait \u00e0 suivre une politique de prudence et de circonspection, m\u00eame s&rsquo;il participa plus qu&rsquo;\u00e0 son tour au grand mouvement de d\u00e9stabilisation initi\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article\/le-legs-de-zbig-a-lorigine\">par Brzezinski<\/a> \u00e0 partir de 1979<\/strong> en finan\u00e7ant fastueusement tous les mouvements salafistes extr\u00e9mistes, puis les organisations terroristes qui en sortirent (le r\u00f4le consid\u00e9rable de l&rsquo;Arabie dans l&rsquo;attaque 9\/11 est aujourd&rsquo;hui largement connu et indiscutable, y compris dans la direction am\u00e9ricaniste).<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Le cas est assez semblable car l&rsquo;on est du m\u00eame monde apr\u00e8s tout,<\/strong> au syst\u00e8me de l&rsquo;am\u00e9ricanisme, ou bien au monstre bruxellois de l&rsquo;UE. Partout des structures extr\u00eamement puissantes, arrogantes, croulant sous le poids de l&rsquo;or, de la machinerie technologique hypersophistiqu\u00e9e, de la corruption (corruption psychologie en t\u00eate) et pourtant rien ne semble bouger&#8230; <strong>Cela ne nous d\u00e9courage absolument pas, bien au contraire, de suivre notre questionnement intuitif<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous sommes conduits par les \u00e9v\u00e9nements qui additionnent les destructions des destructeurs par eux-m\u00eames \u00e0 notre hypoth\u00e8se intuitive ultime, &ndash; celle qui nous dit qu&rsquo;il faut atteindre un certain degr\u00e9 de dissolution et de d\u00e9construction interne r\u00e9alis\u00e9es, autodestruction induite par la surpuissance, pour que l&rsquo;effondrement se fasse, disons dans les r\u00e8gles de l&rsquo;art. Cela d\u00e9courage d&rsquo;autant moins que ces structures incapables de se r\u00e9former \u00e0 cause de l&rsquo;immobilisme de leur paralysie et leur impuissance se sont lanc\u00e9es depuis peu (depuis 2012 pour l&rsquo;Arabie) dans des aventures inconsid\u00e9r\u00e9es, imprudentes, contrastant radicalement avec leur hyper-prudence d&rsquo;antan ; aventures d&rsquo;autant plus ambitieuses et vuln\u00e9rables \u00e0 la fois que ces structures ne dissimulent plus, ou <strong>n&rsquo;arrivent plus \u00e0 dissimuler combien ces initiatives sont absolument vides de sens et qu&rsquo;elles commencent vraiment \u00e0 ressembler \u00e0 ce qu&rsquo;elles sont : les deniers soubresauts d&rsquo;un monstre, &ndash; du Syst\u00e8me aux abois<\/strong>&#8230; <\/p>\n<\/p>\n<p><p>Mis en ligne le 6 juin 2017 \u00e0 10H10<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crise idiote, pleine de bruit et de fureur, qui ne signifie rien Notre \u00e9poque est parcourue de tant de foyers crisiques, qu&rsquo;on peut aussi bien nommer, par exemple et bon exemple pour le cas choisi, \u00ab\u00a0s\u00e9isme g\u00e9opolitique\u00a0\u00bb, qu&rsquo;on finit par se lasser \u00e0 en chercher les causes rationnelles pour y voir, \u00e0 notre sens justement,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3259,3228,13082,3723,2773,6555,3600,4859,2766,2789,3558,3867,1267,2639],"class_list":["post-77301","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabie","tag-crise","tag-diplomatiques","tag-golfe","tag-iran","tag-isolement","tag-petrole","tag-qatar","tag-relations","tag-rupture","tag-saoudite","tag-syrie","tag-terrorisme","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77301"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77301\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}