{"id":77306,"date":"2017-06-10T08:59:34","date_gmt":"2017-06-10T08:59:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/10\/cnn-pravda-en-mode-nucleaire\/"},"modified":"2017-06-10T08:59:34","modified_gmt":"2017-06-10T08:59:34","slug":"cnn-pravda-en-mode-nucleaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/10\/cnn-pravda-en-mode-nucleaire\/","title":{"rendered":"CNN-<em>Pravda<\/em>+ en mode nucl\u00e9aire"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">CNN-<em>Pravda<\/em>+ en mode nucl\u00e9aire<\/h2>\n<\/p>\n<p><p>&#8230; En fait, peut-on parler de <em>Pravda <\/em>\u00e0 propos de CNN, &ndash; le r\u00e9seau \u00e9tait pris comme symbole et embl\u00e8me de l&rsquo;incroyable position que prend la presseSyst\u00e8me dans le simulacre install\u00e9 \u00e0 Washington D.C. ? <strong>Sans doute est-ce injuste pour la <em>Pravda<\/em>, qui n&rsquo;en demandait pas tant et qui n&rsquo;en fit jamais autant<\/strong>. Le texte ci-dessous, du directeur du site <em>The Federalist<\/em>, nous fait sentir par les d\u00e9tails et l&rsquo;atmosph\u00e8re qu&rsquo;il restitue en analysant le \u00ab\u00a0travail\u00a0\u00bb de la cha&icirc;ne autour de l&rsquo;audition de Comey devant le S\u00e9nat, qu&rsquo;il y a chez CNN (dans la presseSyst\u00e8me) une sorte d&rsquo;autonomie compl\u00e8te dans l&rsquo;action de simulacre ; qu&rsquo;il y a une sorte de libert\u00e9 diffamatoire et d\u00e9constructrice compl\u00e8te des journalistes par rapport \u00e0 ce que disent et \u00e9crivent les gens dont ils ont \u00e0 rendre compte des paroles et des \u00e9crits. Pour synth\u00e9tiser cette sorte de sentiment n\u00e9 de la perception g\u00e9n\u00e9rale du ph\u00e9nom\u00e8ne, nous dirions que nous sommes conduits \u00e0 penser qu&rsquo;il y a, chez les journalistes eux-m\u00eames, <strong>une croyance, une foi dans l&rsquo;orientation qu&rsquo;ils ont prise, qui dispenseraient compl\u00e8tement une \u00e9ventuelle direction id\u00e9ologique d&rsquo;exercer quelque pression que ce soit<\/strong>.<\/p>\n<\/p>\n<p><p>Autrement dit, le texte ci-dessous, ajout\u00e9 \u00e0 l&rsquo;exp\u00e9rience de pr\u00e8s de deux ans d\u00e9sormais (depuis le d\u00e9p\u00f4t de la candidature-Trump en juin 2015) que nous avons du ph\u00e9nom\u00e8ne abord\u00e9, renforc\u00e9 par l&rsquo;impression g\u00e9n\u00e9rale que nous \u00e9prouvons devant cette pente catastrophique dans le simulacre, nous conduisent \u00e0 penser que cette presseSyst\u00e8me US, un peu comme le Pentagone dans son domaine mais d&rsquo;une fa\u00e7on beaucoup plus bruyante puisque par d\u00e9finition en contact constant avec le public, <strong>est quasiment hors de contr\u00f4le (et \u00e9ventuellement, hors de contr\u00f4le de sa propre raison)<\/strong>. Sans grand effort intellectuel ou penchant \u00e0 dramatiser la situation, on en vient effectivement \u00e0 se demander si les grands patrons de cette presseSyst\u00e8me, les \u00ab\u00a0oligarques\u00a0\u00bb du contr\u00f4le des esprits \u00e0-la-Chomsky, <strong>ne sont pas eux-m\u00eames d\u00e9pass\u00e9s<\/strong>. (La direction de CNN est <a href=\"https:\/\/www.infowars.com\/cnn-axes-host-who-called-trump-piece-of-sht\/\">oblig\u00e9e de sanctionner<\/a> certains de ses journalistes qui vont vraiment trop loin, parce qu&rsquo;il faut bien para&icirc;tre respecter les r\u00e8gles de censure de l&rsquo;usage du langage ordurier dans l&rsquo;exercice de la diffamation permanente des plus hautes autorit\u00e9s.)<\/p>\n<\/p>\n<blockquote>\n<p><p>On justifie la question (\u00ab\u00a0peut-on parler de <em>Pravda <\/em>\u00e0 propos de CNN?\u00a0\u00bb) par cette r\u00e9ponse \u00e0 peine audacieuse : <strong>la presseSyst\u00e8me US a d\u00e9pass\u00e9 la <em>Pravda<\/em>, comme une <em>Pravda<\/em> qui aurait \u00e9t\u00e9 au-del\u00e0 de la \u00ab\u00a0ligne du Parti\u00a0\u00bb<\/strong>, ou bien pour faire plus classique absolument \u00ab\u00a0plus royaliste que le Roi\u00a0\u00bb, \u00e0 force d&rsquo;en faire trop <strong>avec un entrain extraordinaire, une esp\u00e8ce de joie diabolique n\u00e9e d&rsquo;une certitude de sa propre vertu qui ne l&rsquo;est pas moins (diabolique)<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette impression qu&rsquo;on \u00e9prouve sur la dur\u00e9e et instruit par l&rsquo;habitude constitue l&rsquo;un des aspects les plus remarquables de cette crise qui semble destin\u00e9e \u00e0 n&rsquo;avoir pas de fin qui ne soit absolument catastrophique. On comprend par cons\u00e9quent que nous parlions \u00e0 propos de CNN, de <em>Pravda<\/em>+, ce qui rassurera en partie les mannes de notre bonne vieille <em>Pravda<\/em>. Nous sommes, avec la presseSyst\u00e8me US, dans un domaine infiniment plus large, plus profond, plus \u00e9tendu dans un domaine qui n&rsquo;a plus rien \u00e0 voir avec la propagande et les consignes tatillonnes et \u00e9troites du Parti ou les choses de ce genre, <strong>mais qui est enti\u00e8rement un simulacre plein de dynamisme et d&rsquo;imagination, instituant une r\u00e9alit\u00e9 propre et compl\u00e8tement sp\u00e9cifique, \u00e9trang\u00e8re au reste, r\u00e9pondant d&rsquo;une v\u00e9rit\u00e9 qui ne l&rsquo;est pas moins<\/strong>.<\/p>\n<\/p>\n<p><p>(Mentionnons aussit\u00f4t, pour nous rassurer, que nos \u00ab\u00a0confr\u00e8res\u00a0\u00bb journalistes-parisiens suivent la consigne avec un z\u00e8le qui ne laisse, l\u00e0 aussi, de nous stup\u00e9fier par sa constance et son constant renforcement. Organiser un d\u00e9bat, comme ce fut le cas hier \u00e0 19H00 sur <em>France-24<\/em>, sur le th\u00e8me de \u00ab\u00a0L&rsquo;ancien chef du FBI accable le pr\u00e9sident Trump\u00a0\u00bb, et comparer cela avec ce que fut cette audition de Comey en v\u00e9rit\u00e9 [on veut dire : \u00e0 l&rsquo;oreille], ce qui fut \u00e9crit, etc., est tout simplement super-surr\u00e9aliste. C&rsquo;\u00e9tait la m\u00eame chose sur LCI deux jours plus t\u00f4t, etc. De ce point de vue, certes, \u00ab\u00a0nous sommes tous am\u00e9ricanis\u00e9s\u00a0\u00bb comme l&rsquo;on dirait \u00ab\u00a0nous sommes tous contamin\u00e9s\u00a0\u00bb, mais \u00e0 la sauce \u00ab\u00a0CNN-<em>Pravda<\/em>+\u00a0\u00bb dont on voit qu&rsquo;elle est si cors\u00e9e que tout cela pourrait d\u00e9boucher sur d&rsquo;\u00e9tranges situations.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Il faut donc traiter ce cas de la presseSyst\u00e8me \u00e0 part, comme un ph\u00e9nom\u00e8ne sp\u00e9cifique, <strong>nous dirions presque comme \u00ab\u00a0un simulacre \u00e0 l&rsquo;int\u00e9rieur du simulacre\u00a0\u00bb<\/strong>, dans une ambiance g\u00e9n\u00e9rale extraordinairement exacerb\u00e9e. Ainsi, par r\u00e9f\u00e9rence \u00e0 ce qui pr\u00e9c\u00e8de, devrait-on observer que parler de l'\u00a0\u00bbam\u00e9ricanisation\u00a0\u00bb de notre presseSyst\u00e8me fran\u00e7aise (comme de notre culture et de notre soci\u00e9t\u00e9 en g\u00e9n\u00e9ral d&rsquo;ailleurs) ne suffit plus, parce qu&rsquo;il y a vraiment une sp\u00e9cificit\u00e9 de la presseSyst\u00e8me aux USA, comme l&rsquo;on dirait <strong>d&rsquo;une sur-am\u00e9ricanisation, ou d&rsquo;une \u00ab\u00a0am\u00e9ricanisation dans l&rsquo;am\u00e9ricanisation\u00a0\u00bb (pendant du \u00ab\u00a0simulacre \u00e0 l&rsquo;int\u00e9rieur du simulacre\u00a0\u00bb)<\/strong>. Dans ce cas, le terme \u00ab\u00a0am\u00e9ricanisation\u00a0\u00bb n&rsquo;a plus rien \u00e0 voir avec ce qu&rsquo;il signifie \u00e0 l&rsquo;origine : il n&rsquo;est plus au profit d&rsquo;un pays, d&rsquo;une id\u00e9ologie, d&rsquo;une culture, mais au profit de quelque chose d&rsquo;autre <strong>qui d\u00e9passe toutes les d\u00e9finitions connues<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce ph\u00e9nom\u00e8ne sp\u00e9cifique de la presseSyst\u00e8me tend \u00e0 se s\u00e9parer du Syst\u00e8me en g\u00e9n\u00e9ral, pour le \u00ab\u00a0d\u00e9border sur sa gauche\u00a0\u00bb (<strong>ou bien \u00ab\u00a0le d\u00e9border sur son extr\u00eame\u00a0\u00bb<\/strong>, pour ne parler que de la dynamique sans n\u00e9cessairement l&rsquo;id\u00e9ologiser). Ce ph\u00e9nom\u00e8ne accompagne ou s&rsquo;accompagne c&rsquo;est selon, de l&rsquo;hyper-radicalisation culturelle et soci\u00e9tale de certains milieux culturels et universitaires, et d&rsquo;autre part Africains-Am\u00e9ricains, lorsque des th\u00e9ories \u00ab\u00a0\u00e0 l&rsquo;extr\u00eame de l&rsquo;extr\u00eame\u00a0\u00bb sont d\u00e9velopp\u00e9es sans soulever des protestations quelconques. (On y trouve notamment des propositions ou des th\u00e8ses extraordinaires, comme les r\u00e9unions <a href=\"https:\/\/www.infowars.com\/blm-activist-unleashes-racist-tirade-on-tucker-boo-hoo-white-people\/\">interdites aux Blancs<\/a>, les propositions de re-s\u00e9gr\u00e9gation venues de groupes id\u00e9ologiques Africains-Am\u00e9ricains ou d&rsquo;extr\u00e9mistes soci\u00e9taux extr\u00eames, voire de th\u00e8ses \u00e9voqu\u00e9es ici et l\u00e0 selon lesquelles la solution de tous les probl\u00e8mes actuels se trouve dans l&rsquo;\u00e9limination de la \u00ab\u00a0race blanche\u00a0\u00bb [\u00ab\u00a0<em><a href=\"https:\/\/www.infowars.com\/anthropologist-says-white-genocide-is-a-good-plan\/\">White Genocide<\/a><\/em>\u00ab\u00a0], etc.)<\/p>\n<\/p>\n<p><p>Il faut traiter ce cas \u00e9galement \u00e0 part pour ses effets sur les psychologies, aussi bien des acteurs que des auditeurs, en se disant que nous ne sommes plus tr\u00e8s loin, dans certains cas, d&rsquo;obtenir des \u00ab\u00a0effets-<em>blowback<\/em>\u00a0\u00bb tr\u00e8s f\u00e2cheux, et qu&rsquo;il est m\u00eame probable que nous en obtenons d\u00e9j\u00e0 dans la mesure o&ugrave; cette action de communication emprisonne le monde politique <strong>dans l&rsquo;hyper-radicalisation constante de la crise dont l&rsquo;effet devient \u00e9videmment autodestructeur<\/strong>. (Les fractions plus mod\u00e9r\u00e9es chez les d\u00e9mocrates, qui voudraient freiner la crise pour ne pas endommager sans retour le pouvoir de l&rsquo;am\u00e9ricanisme, sont totalement impuissantes \u00e0 cet \u00e9gard.) Il y a une fa\u00e7on chez ces journalistes d&rsquo;\u00e9craser de leur m\u00e9pris les <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>, de les d\u00e9fier, de les nier, qui les rapproche d&rsquo;une sorte de n\u00e9gationnisme militant tout \u00e0 fait remarquable. (Et nous employons ce mot de \u00ab\u00a0n\u00e9gationnisme\u00a0\u00bb avec l&rsquo;intention de lui donner toute la charge n\u00e9gative dont le Syst\u00e8me l&rsquo;accable : mais il s&rsquo;agirait alors du point de vue de ses producteurs d&rsquo;un n\u00e9gationnisme vertueux, consid\u00e9r\u00e9 d&rsquo;une fa\u00e7on invertie.)<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un ph\u00e9nom\u00e8ne d&rsquo;une puissance colossale, dont le <em>Russiagate <\/em>et Trump en g\u00e9n\u00e9ral constituent une occasion unique pour lui de s&rsquo;exprimer. Nous voulons dire par l\u00e0 que cette action anti-Trump d&rsquo;une cha&icirc;ne comme CNN et des autres selon des degr\u00e9s vari\u00e9s de puissance et d&rsquo;impudence, <strong>ne constitue que l&rsquo;occasion de la mise \u00e0 jour et du d\u00e9veloppement acc\u00e9l\u00e9r\u00e9 d&rsquo;une dynamique d\u00e9structurante et dissolvante qui n&rsquo;attendait qu&rsquo;une occasion cr\u00e9atrice pour s&rsquo;activer<\/strong>. Cette dynamique n&rsquo;est pas conjoncturelle (anti-Trump) mais structurelle et concerne bien entendu la crise g\u00e9n\u00e9rale du Syst\u00e8me, l&rsquo;\u00e9clatement g\u00e9n\u00e9rale des structures, la transformation de toute cette activit\u00e9 de communication en autant de simulacres niant toute l\u00e9gitimit\u00e9 \u00e0 une r\u00e9alit\u00e9 d&rsquo;ores et d\u00e9j\u00e0 pulv\u00e9ris\u00e9e, et entrant en conflit direct avec ce que nous nommons les v\u00e9rit\u00e9-de-situation. <strong>Il s&rsquo;agit du conflit supr\u00eame<\/strong>, qui supplante tous les autres parce qu&rsquo;il va au c&oelig;ur de la crise qu&rsquo;est notre contre-civilisation, et par cons\u00e9quent au c&oelig;ur de la crise du Syst\u00e8me, acc\u00e9l\u00e9rant l&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Voici donc le texte de Ben Domenech, \u00e9diteur et directeur du site <em>The Federalist<\/em>, en date du <a href=\"http:\/\/thefederalist.com\/2017\/06\/09\/cnns-war-trump-going-swimmingly\/\">9 juin 201<\/a>7.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>__________________________<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">CNN&rsquo;s War On Trump Is Going Swimmingly<\/h2>\n<\/p>\n<p><p>Back in February, I was riding on the New York to DC shuttle and CNN&rsquo;s own Jeff Zucker was seated in the row behind me with a woman I took to be a colleague or personal assistant. She was yelling loudly into her phone, loudly enough that the other passengers took note of it, at one point escalating her voice to say: \u00ab\u00a0If they want war with CNN, they got it.\u00a0\u00bb When we landed, I noted the likely inspiration for the call: the administration had offered Mike Pence to every network except for CNN.<\/p>\n<\/p>\n<p><p>Since the new administration arrived in Washington, CNN has continued this war at a fever pitch. Daily they roll out eight-person panels where not one person defending the administration is represented. They have offered the most biased coverage of the Trump administration by far, to the point that Republicans on Capitol Hill openly mock their lack of balance. A network that once strove to be centrist in their approach is now openly antagonistic, and will run with the thinnest of scoops for hours at a time in order to make their case against President Trump.<\/p>\n<\/p>\n<p><p>This has led them to be sloppier journalists than we&rsquo;ve ever seen before. Consider their worst performance this week: CNN didn&rsquo;t get anywhere near enough flack for their ridiculous story that ran on Tuesday night, which they talked about for hours, saying that James Comey would refute Trump&rsquo;s claim that he was cleared three times. The four-person byline included a major host and commentator: Gloria Borger, Eric Lichtblau, Jake Tapper, and Brian Rokus. They have <a href=\"http:\/\/vlt.tc\/2vtf\">since changed<\/a> the headline on the piece from \u00ab\u00a0Comey expected to refute Trump\u00a0\u00bb to \u00ab\u00a0Comey unlikely to judge on obstruction.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>For the entire evening, CNN <a href=\"http:\/\/vlt.tc\/2vpg\">ran with this story<\/a> as their main discussion point.  They told viewers over and over again that Comey was set to utterly undermine what Trump had claimed, and that he would do it in front of Congress and the people, based on two anonymous sources who turned out to be totally wrong.<\/p>\n<\/p>\n<p><p>On air, <a href=\"http:\/\/vlt.tc\/2vtg\">Borger doubled down<\/a> on the story she helped report:  \u00ab\u00a0On CNN&rsquo;s air, analyst Gloria Borger put matters more starkly, saying, &lsquo;Comey is going to dispute the president on this point if he&rsquo;s asked about it by senators, and we have to assume that he will be. He will say he never assured Donald Trump that he was not under investigation, that that would have been improper for him to do so.'\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Of course, none of that happened. In fact, <a href=\"http:\/\/vlt.tc\/2vsq\">Comey testified<\/a> that he volunteered that information, and that contrary to Borger&rsquo;s claims, he saw nothing inappropriate in doing so.  The correction and update CNN ran doesn&rsquo;t come anywhere near what they should&rsquo;ve done, which was a total retraction: \u00ab\u00a0CORRECTION AND UPDATE: This article was published before Comey released his prepared opening statement. The article and headline have been corrected to reflect that Comey does not directly dispute that Trump was told multiple times he was not under investigation in his prepared testimony released after this story was published.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Does not directly dispute\u00a0\u00bb should be read as \u00ab\u00a0utterly and totally confirms.\u00a0\u00bb At some point, CNN is going to have to decide what they are willing to do in this war on the president and his administration, and whether they are willing to sacrifice even a semblance of balance and centrism in their quest against him, transforming themselves from a news network to an agenda-driven propaganda unit, complete with their useful idiots, their organs of the past administration, and their collection of invented sources who pass along useful lies.<\/p>\n<\/p>\n<p><h4>Ben Domenech<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CNN-Pravda+ en mode nucl\u00e9aire &#8230; En fait, peut-on parler de Pravda \u00e0 propos de CNN, &ndash; le r\u00e9seau \u00e9tait pris comme symbole et embl\u00e8me de l&rsquo;incroyable position que prend la presseSyst\u00e8me dans le simulacre install\u00e9 \u00e0 Washington D.C. ? Sans doute est-ce injuste pour la Pravda, qui n&rsquo;en demandait pas tant et qui n&rsquo;en fit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3642,2839,4757,13088,12820,13022,3965,2639,9707],"class_list":["post-77306","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-cnn","tag-comey","tag-genocide","tag-hyper-radicalisation","tag-pressesysteme","tag-russiagate","tag-simulacre","tag-trump","tag-white"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77306"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77306\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}