{"id":77340,"date":"2017-06-29T10:29:42","date_gmt":"2017-06-29T10:29:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/29\/pleurs-tremblements-extasies\/"},"modified":"2017-06-29T10:29:42","modified_gmt":"2017-06-29T10:29:42","slug":"pleurs-tremblements-extasies","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/06\/29\/pleurs-tremblements-extasies\/","title":{"rendered":"Pleurs &amp; tremblements extasi\u00e9s"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pleurs &#038; tremblements extasi\u00e9s<\/h2>\n<\/p>\n<p><p>29 juin 2017 &ndash; Rompant avec mes habitudes de vieil ours chauve perdu dans les bois hors-postmodernit\u00e9, je regardai mardi en fin d&rsquo;apr\u00e8s-midi l&rsquo;\u00e9mission <em>machin-truc<\/em> de l&rsquo;inimitable Calvi G\u00e9rard sur le segment royal de 18H00-20H00 sur LCI, et je suis s&ucirc;r qu&rsquo;ailleurs \u00e0 la m\u00eame heure ce devait \u00eatre pareil car ainsi fonctionne notre univers de la communication-Syst\u00e8me. (Align\u00e9, pli\u00e9, pas un pli pour d\u00e9passer, ne veux voir qu&rsquo;une t\u00eate, n&rsquo;entendre qu&rsquo;un soupir, et ce sera ce soir-l\u00e0 celui de l&rsquo;extasi\u00e9 bonheur.) On nous avait montr\u00e9 auparavant, vers 15H00-17H00 &ndash; j&rsquo;ai beaucoup lambin\u00e9 devant la TV avant-hier apr\u00e8s-midi, parce que le temps \u00e9tait \u00e0 l&rsquo;orage et que ma chienne <em>Klara <\/em>en a grand&rsquo;peur, en cons\u00e9quence de quoi je reste pr\u00e8s d&rsquo;elle,<em> &ndash; <\/em>nous e&ucirc;mes donc un spectacle consid\u00e9rable de la tradition m\u00eame, haut en couleur et de grand int\u00e9r\u00eat ethnologique, les us &#038; coutumes, et le vote dans toute sa chor\u00e9graphie solennelle, pour l&rsquo;\u00e9lection du Pr\u00e9sident de la nouvelle Assembl\u00e9e Nationale de la R\u00e9publique &#038; du Peuple. C&rsquo;est de cela qu&rsquo;on parlait, chez Calvi G\u00e9rard.<\/p>\n<\/p>\n<p><p>Non, plut\u00f4t, on parlait de ceci, soudain la chose m&rsquo;\u00e9tant apparue \u00e0 moi qui suis toujours en retard sur mon si\u00e8cle, &ndash; de ceci que cette Assembl\u00e9e-l\u00e0 comprend autour de 40% de femmes, presque la parit\u00e9 ! Mille sabords, quelle aventure&#8230; J&rsquo;en fus sit\u00f4t retourn\u00e9 ! Qu&rsquo;on me comprenne bien, aussit\u00f4t, et qu&rsquo;on n&rsquo;aille point me faire quelque m\u00e9chant proc\u00e8s en LGTBQ-d\u00e9ficient, j&rsquo;en serais affreusement marrie. Je n&rsquo;ai rien contre les femmes, contre les homos, les trans, les lesbs, les multi, les couleurs brun, <em>black<\/em>, jaune, orange, bleue et m\u00eame blanc, et en plus j&rsquo;adore les animaux \u00e0 un point que vous ne pouvez imaginer.<\/p>\n<\/p>\n<p><p>(Qui parle d&rsquo;ironiser ? Voyez ma peine immense et jamais \u00e9teinte, d&rsquo;une v\u00e9rit\u00e9 poignante, quand mourut <a href=\"http:\/\/www.dedefensa.org\/article\/a-margot-pour-quelle-repose-en-paix\">ma chienne <em>Margot<\/em><\/a>, et il en fut de m\u00eame pour <em>Balzac<\/em> avant elle, et il en sera ainsi pour <em>Klara <\/em>qui est pour moi comme la fille en plus que je n&rsquo;esp\u00e9rais plus. De ce parti des animaux, mon choix est fait depuis longtemps et je mourrai avec, sans militantisme n\u00e9cessaire, simplement reconnaissant de l&rsquo;esprit tr\u00e8s haut de la chose.)<\/p>\n<\/p>\n<p><p>Donc, nous laissons de c\u00f4t\u00e9 cet aspect pol\u00e9mique-LGTBQ qui vient si souvent sous la plume par les temps qui courent. (J&rsquo;y reviendrai \u00e0 l&rsquo;aspect pol\u00e9mique-LGTBQ, ayant \u00e9t\u00e9 au moins une fois h\u00e9l\u00e9 de rude fa\u00e7on \u00e0 ce propos, et fort injustement de mon point de vue ; j&rsquo;ai not\u00e9 ce sujet dans mon petit carnet type \u00ab\u00a0sujet-\u00e0-aborder\u00a0\u00bb que je tente chaque jour de ne pas \u00e9garer&#8230;) Ce qui m&rsquo;a arr\u00eat\u00e9 dans ces diverses \u00e9missions de mardi fin d&rsquo;apr\u00e8s-midi\/d\u00e9but de soir\u00e9e, c&rsquo;est l&rsquo;extraordinaire sentimentalisme des divers commentateurs, experts, professionnels, statisticiens, politologues, ou devrais-je dire selon mon expression pr\u00e9f\u00e9r\u00e9e : leur <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a> ? Alors, il n&rsquo;est plus question simplement de ces femmes qui envahissent comme c&rsquo;est justice les trav\u00e9es de l&rsquo;Assembl\u00e9e, mais de l&rsquo;\u00e9galit\u00e9 enfin presque r\u00e9alis\u00e9e, et l&rsquo;\u00e9galit\u00e9 r\u00e9publicaine, dans l&rsquo;enceinte m\u00eame de la R\u00e9publique du Peuple. Ils \u00e9taient tous, l\u00e0, assis autour de la table, avec le gros Calvi G\u00e9rard allant de l&rsquo;un \u00e0 l&rsquo;autre avec ses grands bras, sa mine de vrai-na\u00eff jouant au faux-na\u00eff, son expression favorite &laquo; <em>donc, vous \u00eates en train de nous dire<\/em> &raquo; (de m\u00eame que l&rsquo;Hollande, qui avait comme expression favorite entre intimes &laquo; <em>il se trouve que je suis pr\u00e9sident<\/em> &raquo;) ; ils \u00e9taient l\u00e0, tous, <strong>les yeux brillants disant le vrai de l&rsquo;\u00e9panchement de leurs c&oelig;urs, comme l&rsquo;on aurait vu perler une de ces larmes r\u00e9publicaines<\/strong> qu&rsquo;on ne laisse couler que dans les tr\u00e8s-grandes occasions. Je crois <strong>qu&rsquo;ils croyaient en v\u00e9rit\u00e9<\/strong> \u00e0 la grandeur formidable du Moment, c&rsquo;est-\u00e0-dire ce Moment historique de la repr\u00e9sentation populaire, juste, proportionn\u00e9e, \u00e9galitaire, absolument r\u00e9publicaine. Il ne parlait que de cela, de \u00ab\u00a0La R\u00e9publique\u00a0\u00bb, comme l&rsquo;on parle de Notre-P\u00e8re-qui-n&rsquo;\u00eates-plus-aux-cieux, avec une immense et respectable ferveur religieuse.<\/p>\n<\/p>\n<p><p>Dans cette description, <strong>croyez-le bien, je balance entre l&rsquo;ironie et le s\u00e9rieux sinon la gravit\u00e9<\/strong> ; il y a en effet \u00e0 la fois un air d&rsquo;incroyable simulacre et un air d&rsquo;implacable v\u00e9rit\u00e9 dans ce que je d\u00e9cris&#8230; Mais dans quel ordre, cela ? Est-ce le simulacre de la v\u00e9rit\u00e9 ou bien la v\u00e9rit\u00e9 du simulacre ? <strong>Poser ces questions, ce n&rsquo;est m\u00eame pas y r\u00e9pondre<\/strong> tant r\u00e8gne l&rsquo;ambigu\u00eft\u00e9 dans ces moments-l\u00e0.<\/p>\n<\/p>\n<p><p>Il y a aujourd&rsquo;hui dans ces esprits pr\u00e9tendument intellectuels, c&rsquo;est-\u00e0-dire faits pour appr\u00e9cier et juger une situation de fa\u00e7on rationnelle et nous donner le fruit de leur r\u00e9flexion, une formidable et \u00e9trange fusion conditionnant la pens\u00e9e, dans le chef de la raison ou dans ce qui en reste d&rsquo;une part, de l&rsquo;affectivisme d&rsquo;autre part. Cela donne une production \u00e9tonnante de v\u00e9locit\u00e9 et de cr\u00e9ativit\u00e9 des artefacts conceptuels qui se pr\u00e9tendent symboles, ou dans tous les cas de caract\u00e8re symbolique, et qui affirment par cons\u00e9quent ce qu&rsquo;ils jugent \u00eatre leurs dimensions mythiques. Ainsi en f&ucirc;t-il de cette pr\u00e9sence f\u00e9minine \u00e9quilibr\u00e9e, du vote de cette Assembl\u00e9e compl\u00e8tement neuve, de la solennit\u00e9 de cet \u00e9v\u00e9nement qui affirma se transformer lui-m\u00eame en une repr\u00e9sentation symbolique d&rsquo;un \u00ab\u00a0Moment R\u00e9publicain\u00a0\u00bb dont il allait de soi qu&rsquo;il avait les dimensions d&rsquo;un mythe ; et ce mythe qui resterait <strong>parce qu&rsquo;il fixait dans l&rsquo;\u00e9ternit\u00e9 d&rsquo;une la\u00efcit\u00e9 vertueuse \u00e0 ne pas croire la vision d&rsquo;une soci\u00e9t\u00e9 id\u00e9ale enfin accomplie<\/strong>. On e&ucirc;t cru, ou e&ucirc;t m\u00eame pens\u00e9, pour les quelques heures de commentaires qui se d\u00e9versaient sans v\u00e9ritable anicroche, que l&rsquo;on \u00e9tait enfin au port et que l&rsquo;Histoire pouvait se clore.<\/p>\n<\/p>\n<p><p>(Je vous confierais entre nous que la M\u00e9luche, refusant de porter la cravate, refusant de se lever et d&rsquo;applaudir le discours de notre nouveau-Pr\u00e9sident [de l&rsquo;Assembl\u00e9e-du-Peuple], n&rsquo;eut pas bonne presse chez nos commentateurs appoint\u00e9s. Tout le monde exprima hautement son indignation : au piquet, la M\u00e9luche ! Moi-m\u00eame, malgr\u00e9 le ton distant et ambigu\u00eb de cette chronique, je ne l&rsquo;approuvai pas sans pour autant voter la peine capitale.)<\/p>\n<\/p>\n<p><p>J&rsquo;avais l&rsquo;impression d&rsquo;assister, avec toute la retenue bien fran\u00e7aise et l&rsquo;\u00e9vident brio de la non moins \u00e9vidente intelligence parisienne, \u00e0 quelque chose d&rsquo;une transmutation hollywoodienne par instant, ou l&rsquo;histoire compos\u00e9e selon les normes de cette industrie ; si vous voulez, un <em>remake<\/em> en plus cart\u00e9sien de <em>Mister Smith Goes To Senate<\/em> (je pr\u00e9f\u00e8re ce titre \u00e0 l&rsquo;original <em>Mr. Smith Goes to Washington<\/em>) ; ce qui donnerait, \u00e0-la-Derrida et un peu plus long tout de m\u00eame que la sobri\u00e9t\u00e9 hollywoodienne et beaucoup moins rythm\u00e9 que le <em>swing<\/em> hollywoodien, une sorte de \u00ab\u00a0Mr. et Mme Dupont, immigr\u00e9s, d\u00e9construisent l&rsquo;Assembl\u00e9e du Peuple pour refonder la R\u00e9publique\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>J&rsquo;exag\u00e8re en disant tout cela, je force le trait, c&rsquo;est bien connu, et si c&rsquo;est pour mieux m\u00e9nager mon effet ce n&rsquo;est nullement pour le d\u00e9naturer. <strong>Si l&rsquo;on revient \u00e0 l&rsquo;id\u00e9e du m\u00e9lange<\/strong> d&rsquo;une raison dont on sait par ailleurs que je la tiens pour absolument et compl\u00e8tement <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-humaine-1\">subvertie<\/a>, avec l&rsquo;affectivisme, on arrive enfin \u00e0 ce constat que j&rsquo;ai fait que tous ces importants commentateurs, par instant, <strong>semblaient comme des enfants devant le sapin de No\u00ebl<\/strong> <strong>achaland\u00e9 de ses beaux joujoux<\/strong>. Ils me semblaient \u00eatre vraiment, &ndash; et je ne tiens pas pr\u00e9cis\u00e9ment \u00e0 les moquer en disant cela, mais tenter de restituer le vrai d&rsquo;une perception, &ndash; <strong>comme si, dans ces instants fugaces de ce grand \u00ab\u00a0Moment R\u00e9publicain\u00a0\u00bb, ils croyaient vraiment au P\u00e8re No\u00ebl<\/strong>.<\/p>\n<\/p>\n<p><p>Plus rien ne semblait exister, l&rsquo;absurde quinquennat Hollande, la campagne chaotique, les invraisemblables affaires, la monstrueuse campagne d&rsquo;abstention, les conditions catastrophiques qui nous habitent autant qu&rsquo;elles nous entourent, l&rsquo;incroyable surgissement de Macron et son raz-de-mar\u00e9e irr\u00e9sistible avec autour de 15% des voix exprim\u00e9es effectivement sur son nom, &ndash; et encore ne parle-t-on pas du flot des r\u00e9fugi\u00e9s, de la Syrie et de Trump, de la m\u00e9chante Russie, &ndash; toutes ces singularit\u00e9s qui ne cess\u00e8rent de les pousser les uns et les autres \u00e0 parler d&rsquo;une crise majeure de la d\u00e9mocratie, et \u00ab\u00a0la R\u00e9publique est en danger\u00a0\u00bb par cons\u00e9quent. Ce jour-l\u00e0, je parle toujours de cet avant-hier, c&rsquo;\u00e9tait un instant de gr\u00e2ce, au sens qu&rsquo;on donne aujourd&rsquo;hui au mot \u00ab\u00a0gr\u00e2ce\u00a0\u00bb, c&rsquo;est-\u00e0-dire un sens tr\u00e8s chichement mesur\u00e9 pour qu&rsquo;il n&rsquo;\u00e9veille rien d&rsquo;intemporel et de transcendant. Ils y croyaient, j&rsquo;en mets ma main au feu, exactement, &ndash; toujours cette image qui revient et me retient, &ndash; comme les enfants croient au P\u00e8re No\u00ebl ; <strong>ils avaient les yeux pleins d&rsquo;\u00e9toiles lorsque l&rsquo;un d&rsquo;entre eux parlait de \u00ab\u00a0la R\u00e9publique\u00a0\u00bb<\/strong> ; et, en v\u00e9rit\u00e9, j&rsquo;en \u00e9prouvais presque une certaine \u00e9motion, d\u00e9courag\u00e9 du moindre jugement critique devant ce spectacle. Il y a quelque chose de sacr\u00e9 dans le fait de la croyance enfantine, je veux dire de compl\u00e8tement pur, sans asp\u00e9rit\u00e9 aucune, ce qui interdit qu&rsquo;on puisse songer un instant \u00e0 s&rsquo;en saisir pour en faire une \u00e9valuation critique. C&rsquo;est ainsi et ce n&rsquo;est pas autrement&#8230;<\/p>\n<\/p>\n<p><p>(Je parle de ce \u00ab\u00a0sacr\u00e9\u00a0\u00bb-l\u00e0, qui permet tant d&rsquo;interpr\u00e9tations&#8230; &laquo; <em>Le sacr\u00e9 fait signe vers ce qui est mis en dehors des choses ordinaires, banales, communes&#8230;<\/em> [&#8230;] <em>Il d\u00e9signe ce qui est inaccessible, indisponible, mis hors du monde normal, et peut \u00eatre objet de d\u00e9votion et de peur<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Voyez-vous, je reviens sur la chose dite plus haut, entre parenth\u00e8ses comme si j&rsquo;avais signifi\u00e9 que je changeai un instant de sujet, car il s&rsquo;av\u00e8re que ce n&rsquo;est pas du tout le cas&#8230; Effectivement, <strong>au sortir de ce parcours initiatique <\/strong>je me sentis comme je le disais plus haut, plus que jamais d\u00e9gag\u00e9 de tout antagonisme vis-\u00e0-vis de ces constructions postmodernes (LGTBQ, \u00e9galit\u00e9 et le reste) ; <strong>au sortir dis-je<\/strong>, je me sentis plus que jamais dans ma singularit\u00e9 postmoderne \u00e0 moi, je me sentis plus que jamais, compl\u00e8tement, exclusivement, absolument du parti des animaux.<\/p>\n<\/p>\n<p><p>Je suis un des leurs, j&rsquo;esp\u00e8re qu&rsquo;ils m&rsquo;accueilleront&#8230; J&rsquo;ai bon espoir, je sais d\u00e9j\u00e0 qu&rsquo;ils ont d\u00e9cid\u00e9 de ne pas d\u00e9battre entre les deux formules : \u00ab\u00a0Vive la for\u00eat !\u00a0\u00bbet \u00ab\u00a0Nique la for\u00eat !\u00a0\u00bb. Ils s&rsquo;en foutent.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pleurs &#038; tremblements extasi\u00e9s 29 juin 2017 &ndash; Rompant avec mes habitudes de vieil ours chauve perdu dans les bois hors-postmodernit\u00e9, je regardai mardi en fin d&rsquo;apr\u00e8s-midi l&rsquo;\u00e9mission machin-truc de l&rsquo;inimitable Calvi G\u00e9rard sur le segment royal de 18H00-20H00 sur LCI, et je suis s&ucirc;r qu&rsquo;ailleurs \u00e0 la m\u00eame heure ce devait \u00eatre pareil car&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3395,3837,13137,13135,8315,2937,13136,3309],"class_list":["post-77340","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-assemblee","tag-feminisme","tag-hommes-femmes","tag-lgbtq","tag-melenchon","tag-nationale","tag-parite","tag-postmodernite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77340"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77340\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}