{"id":77342,"date":"2017-07-01T10:21:50","date_gmt":"2017-07-01T10:21:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/01\/stone-au-travail-pour-rt\/"},"modified":"2017-07-01T10:21:50","modified_gmt":"2017-07-01T10:21:50","slug":"stone-au-travail-pour-rt","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/01\/stone-au-travail-pour-rt\/","title":{"rendered":"Stone au travail pour RT"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Stone au travail pour RT<\/h2>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il y a dans les pays du bloc-BAO une campagne constante d&rsquo;insultes, de diffamations, d&rsquo;obsc\u00e9nit\u00e9s et de m\u00e9pris furieux contre les \u00ab\u00a0<em>m\u00e9dias d&rsquo;&Eacute;tat<\/em>\u00a0\u00bb russes. Le terme \u00ab\u00a0<em>m\u00e9dias d&rsquo;&Eacute;tat<\/em>\u00a0\u00bb semble l&rsquo;insulte supr\u00eame dans le neurone-Syst\u00e8me des robots de la presseSyst\u00e8me, <strong>qui pr\u00e9f\u00e8re manifestement la situation tr\u00e8s vertueuse qui est la leur de domestiques des \u00ab\u00a0<em>m\u00e9dias du Corporate Power<\/em>\u00ab\u00a0<\/strong>. Cela en dit long sur leur consid\u00e9ration du service public, comme celui que Pompidou d\u00e9finissait lorsqu&rsquo;il disait de l&rsquo;ORTF qu&rsquo;elle \u00e9tait \u00ab\u00a0<em>La voix de la France<\/em>\u00ab\u00a0.<\/p>\n<\/p>\n<blockquote>\n<p><p>Le tombereau d&rsquo;insultes est en g\u00e9n\u00e9ral r\u00e9serv\u00e9 \u00e0 <em>Sputnik.News<\/em> et \u00e0 RT. On ne s&#8217;embarrasse gu\u00e8re du fait que les extensions internationales de ces r\u00e9seaux, celles qui sont en g\u00e9n\u00e9ral mises en cause,<strong> emploient des journalistes non-Russes, avec un tr\u00e8s fort contingent d&rsquo;Anglo-Saxons<\/strong>. RT-USA emploie ainsi un tr\u00e8s grand nombre de tr\u00e8s grands journalistes US, qui sont soumis souvent de la part des officiels US des relations publiques \u00e0 des traitements ahurissants d&rsquo;impolitesse, de grossi\u00e8ret\u00e9 et de m\u00e9pris, &ndash; <strong>comme seuls les domestiques savent user pour les gens libres que leurs ma&icirc;tres n&rsquo;aiment pas<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>(Exemple singuli\u00e8rement extraordinaire <strong>de l&rsquo;arrogance de la domestique parlant pour son ma&icirc;tre et ainsi baptis\u00e9e dans cette occasion \u00ab\u00a0porte-parole d&rsquo;al Qa\u00efda\u00a0\u00bb<\/strong>, rapport\u00e9e par <em>TheDuran.com<\/em> <a href=\"http:\/\/theduran.com\/busted-us-state-department-doesnt-care-about-false-flag-attacks-video\/\">sur cette vid\u00e9o<\/a> : &laquo; <em>During a press conference, RT&rsquo;s Caleb Maupin asked US State Department Spokeswoman Heather Nauert if US stories about an &lsquo;imminent chemical weapons attack&rsquo; will bait terrorist groups into staging one themselves. Her answer was both arrogant, flippant and factually incorrect as Mr. Maupin pointed out, even as Nauert tried to shut him up. It has to be seen to be believed.<\/em> &raquo;)<\/p>\n<\/p>\n<p><p>Cette <strong>situation (l&#8217;emploi massif de journalistes non-nationaux) pourtant singuli\u00e8rement lib\u00e9rale et par cons\u00e9quent totalement inconnue dans la presseSyst\u00e8me du bloc-BAO<\/strong>, est illustr\u00e9e directement par la pr\u00e9sence chez RT de Sean Stone, fils d&rsquo;Oliver. <em>Fort Russ News<\/em> <a href=\"http:\/\/www.fort-russ.com\/2017\/06\/oliver-stones-son-works-for-rt.html\">rapporte la nouvelle<\/a> venue de <em><a href=\"http:\/\/novorossia.today\/syn-olivera-stouna-rabotaet-na-rt\/\">Novorossia Today<\/a><\/em> (traduction, Inessa Sinchougova). Voici le texte adapt\u00e9 en fran\u00e7ais<\/p>\n<\/p>\n<p><p>&laquo; <em>L&rsquo;acteur et animateur de t\u00e9l\u00e9vision Sean Stone, fils du metteur en sc\u00e8ne Oliver Stone, a r\u00e9pondu \u00e0 des questions concernant son travail sur le r\u00e9seau TV RT. Stone ne se consid\u00e8re nullement comme \u00ab\u00a0un agent du Kremlin\u00a0\u00bb. \u00ab\u00a0Comment pourrais-je \u00eatre un agent du Kremlin alors que je n&rsquo;ai jamais re\u00e7u une seule instruction concernant quelque chose dont je ne devrais pas parler, depuis que je travaille pour RT ?\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Stone pr\u00e9cise qu&rsquo;il a toujours respect\u00e9 RT, parce que c&rsquo;est un r\u00e9seau qui prend des risques alors que les autres grands m\u00e9dias US prennent garde de n&rsquo;en prendre jamais. \u00ab\u00a0De toutes les fa\u00e7ons, je continue \u00e0 \u00eatre un journaliste et un commentateur compl\u00e8tement ind\u00e9pendants. Cela ne me cause aucun pr\u00e9judice de d\u00e9velopper les th\u00e8mes que je choisis et d&rsquo;orienter leur traitement du point de vue de la politique am\u00e9ricaine. Je ressens pour moi-m\u00eame l&rsquo;obligation d&rsquo;utiliser cette opportunit\u00e9 pour orienter mon travail vers les questions am\u00e9ricaines internes, et traiter dans une perspective diff\u00e9rente ce qui se passe ux Etats-Unis&#8230;\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 1<sup>er<\/sup> juillet 2017 \u00e0 10H14<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stone au travail pour RT D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il y a dans les pays du bloc-BAO une campagne constante d&rsquo;insultes, de diffamations, d&rsquo;obsc\u00e9nit\u00e9s et de m\u00e9pris furieux contre les \u00ab\u00a0m\u00e9dias d&rsquo;&Eacute;tat\u00a0\u00bb russes. Le terme \u00ab\u00a0m\u00e9dias d&rsquo;&Eacute;tat\u00a0\u00bb semble l&rsquo;insulte supr\u00eame dans le neurone-Syst\u00e8me des robots de la presseSyst\u00e8me, qui pr\u00e9f\u00e8re manifestement la situation tr\u00e8s vertueuse qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3568,3889,2651,3570,9063,13140,11789,3571,3749,5793],"class_list":["post-77342","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-corporate","tag-detat","tag-du","tag-medias","tag-oliver","tag-ortf","tag-pompidou","tag-power","tag-sean","tag-stone"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77342"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77342\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}