{"id":77349,"date":"2017-07-04T16:07:11","date_gmt":"2017-07-04T16:07:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/04\/sous-le-regard-du-fantome-de-lempire\/"},"modified":"2017-07-04T16:07:11","modified_gmt":"2017-07-04T16:07:11","slug":"sous-le-regard-du-fantome-de-lempire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/04\/sous-le-regard-du-fantome-de-lempire\/","title":{"rendered":"Sous le regard du fant\u00f4me de l&rsquo;Empire"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Sous le regard du fant\u00f4me de l&rsquo;Empire<\/h2>\n<\/p>\n<p><p>04 juillet 2017 &ndash; Le 4 juillet est la f\u00eate nationale aux USA, et cette ann\u00e9e est marqu\u00e9e par un appel de divers groupes anti-Trump domin\u00e9 notamment par un \u00ab\u00a0appel aux armes\u00a0\u00bb lanc\u00e9 par Michael Moore avec son groupe \u00ab\u00a0<em>Resistance<\/em>\u00ab\u00a0. Ce 4 juillet donc, <a href=\"https:\/\/www.resistancecalendar.org\/event\/5959737ac37a11b46c717a69\">une marche est pr\u00e9vue<\/a> \u00e0 Washington pour demander la destitution du pr\u00e9sident Trump. La veille, ce 3 juillet 2017, l&rsquo;&Eacute;tat du New Jersey a publi\u00e9 dans sa l\u00e9gislation l&rsquo;annonce que les groupes \u00ab\u00a0<em>Antifa<\/em>\u00a0\u00bb (\u00ab\u00a0antifascistes\u00a0\u00bb), label g\u00e9n\u00e9ral dont se r\u00e9clament nombre de groupes anti-Trump, \u00e9taient d\u00e9sormais consid\u00e9r\u00e9s <a href=\"https:\/\/www.njhomelandsecurity.gov\/analysis\/anarchist-extremists-antifa?rq=antifa\">comme des groupes terroristes<\/a>. Adam Garrie, sur le site <em>TheDuran.com<\/em>, qui avait demand\u00e9 cette classification le <a href=\"http:\/\/theduran.com\/antifa-is-a-terrorist-group-in-the-blood-soaked-bolshevik-tradition\/\">1<sup>er<\/sup> juillet<\/a> annonce avec satisfaction, ce m\u00eame <a href=\"http:\/\/theduran.com\/confirmed-antifa-is-classified-as-a-domestic-terrorism-organisation-by-new-jersey\/\">3 juillet<\/a>, la d\u00e9cision du New Jersey. Ainsi voit-on combien la violence est d&rsquo;actualit\u00e9 dans ce temps courant aux USA, tout cela li\u00e9 \u00e0 l&rsquo;\u00e9lection du pr\u00e9sident Trump et \u00e0 l&rsquo;\u00e9trange d\u00e9roulement des d\u00e9buts de sa pr\u00e9sidence <strong>dont rien, absolument rien ne laisse pr\u00e9voir qu&rsquo;elle finira par se normaliser<\/strong>.<\/p>\n<\/p>\n<p><p>La d\u00e9cision du New Jersey est int\u00e9ressante, encore plus d&rsquo;un point de vue symbolique que du point de vue op\u00e9rationnel g\u00e9n\u00e9ral. Elle signale que la violence d\u00e9ploy\u00e9e par ces groupes, jusqu&rsquo;ici trait\u00e9e avec plus ou moins d&#8217;empressement et de s\u00e9v\u00e9rit\u00e9, passe au niveau officiel de la violence officiellement reconnue comme telle, comme contestatrice et destructrice de l&rsquo;ordre public, \u00e9ventuellement destructrice des \u00ab\u00a0valeurs\u00a0\u00bb que cet ordre repr\u00e9sente, etc. (Le qualificatif \u00ab\u00a0terrorisme\u00a0\u00bb est aujourd&rsquo;hui tr\u00e8s large et entre dans le classement op\u00e9rationnel de ce que nous nommons la Grande Guerre postmoderne, et \u00ab\u00a0<em>Second Civil War<\/em>\u00a0\u00bb aux USA.)<\/p>\n<\/p>\n<p><p>Cette premi\u00e8re cat\u00e9gorisation officielle des \u00ab\u00a0<em>Antifa<\/em>\u00a0\u00bb aux USA, intervenant dans le cadre bien identifi\u00e9 de la crise qui secoue le pouvoir de l&rsquo;am\u00e9ricanisme et Washington D.C. depuis quasiment deux ans, et sans aucun doute d&rsquo;une fa\u00e7on paroxystique depuis un an, constitue une \u00e9tape importante dans la prise en compte de la violence sp\u00e9cifique \u00e0 cette crise de l&rsquo;am\u00e9ricanisme. Il est bon, \u00e0 cette occasion, de consulter un texte du <a href=\"http:\/\/thefederalist.com\/2017\/06\/27\/can-expect-increased-violence-left-power\/\">27 juin 2017<\/a> dans <em>The Federalist<\/em>, du pasteur Peter M. Burfeind, Pasteur de l&rsquo;Universit\u00e9 de Toledo et th\u00e9ologien tr\u00e8s c\u00e9l\u00e8bre et tr\u00e8s lu, notamment avec son livre de 2015, dont le titre (<em><a href=\"http:\/\/www.amazon.com\/Gnostic-America-Contemporary-according-Christianitys\/dp\/0692260498\">Gnostic America<\/a>: A Reading of Contemporary American Culture &#038; Religion according to Christianity&rsquo;s Oldest Heresy<\/em>) nous conduit \u00e0 la fois au c&oelig;ur de son propos actuel, <strong>et au c&oelig;ur de la crise actuelle, avec<\/strong><strong> notamment la violence, &ndash; extraordinaire au niveau de la communication, &ndash; qu&rsquo;on y voit chaque jour<\/strong>. Burnfeind estime en effet que la violence politique actuelle, qu&rsquo;il identifie essentiellement \u00ab\u00a0\u00e0 gauche\u00a0\u00bb, renvoie essentiellement au gnosticisme auquel il juge que cette partie de la soci\u00e9t\u00e9 US renvoie elle-m\u00eame, comme r\u00e9f\u00e9rence principale pour sa propre d\u00e9finition et son identit\u00e9. Lorsqu&rsquo;il note que <strong>le candidat d\u00e9mocrate au fauteuil du 6\u00e8me district de la G\u00e9orgie \u00e0 la Chambre, Jon Ossoff, eut comme dernier mot apr\u00e8s sa d\u00e9faite d&rsquo;il y a deux semaines ce constat que &laquo; <em>les t\u00e9n\u00e8bres ont envahi le monde <\/em>&raquo;<\/strong>, Burnfeind constate qu&rsquo;il s&rsquo;agissait d&rsquo;une m\u00e9taphore ou d&rsquo;une observation de type spirituel, mais certainement pas exemplaire du &laquo; <em>s\u00e9cularisme scientifique que la Gauche pr\u00e9tend repr\u00e9senter. En fait, <\/em>[cette observation]<em> repr\u00e9sente <strong>la r\u00e9surgence d&rsquo;une posture spirituelle avec des r\u00e9f\u00e9rences th\u00e9ologiques pr\u00e9cises<\/strong> <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Burnfeind constate ainsi que la Gauche US a compl\u00e8tement \u00e9pous\u00e9 le Gnosticisme, qui est une des h\u00e9r\u00e9sies fondamentales du christianisme de l&rsquo;origine et a laiss\u00e9 sa psychologie compl\u00e8tement s&rsquo;impr\u00e9gner du Manich\u00e9isme (autre h\u00e9r\u00e9sie chr\u00e9tienne des origines, qui est une variante du Gnosticisme). Il s&rsquo;agit pour lui d&rsquo;une \u00e9volution r\u00e9cente, qu&rsquo;il classe comme une r\u00e9action brutale apr\u00e8s une p\u00e9riode marqu\u00e9e par la doctrine de l&rsquo;Herm\u00e9ticisme, &laquo; <em>variante optimisme du Gnosticisme<\/em> &raquo; qui s&rsquo;\u00e9tait install\u00e9e comme la doctrine dominante du Progr\u00e8s et du progressisme triomphant en Occident depuis la Renaissance : l&rsquo;homme plac\u00e9e au centre du monde, prenant en charge la destin\u00e9e du monde contre le \u00ab\u00a0dieu mauvais\u00a0\u00bb tra&icirc;tre au Dieu dominant (selon le Gnosticisme), qui entendait imposer un destin catastrophique ; et ainsi, l&rsquo;homme triomphant prenant la ma&icirc;trise de l&rsquo;Histoire autant que de son destin, toujours selon cette pens\u00e9e, et lui insufflant une course triomphante pav\u00e9e notamment de divers \u00ab\u00a0lendemains qui chantent\u00a0\u00bb. &laquo; <em>Depuis les ann\u00e9es 1960, et avec le succ\u00e8s d\u00e9montr\u00e9 <\/em>[selon elle]<em> de cette approche, la Gauche s&rsquo;\u00e9tait install\u00e9e confortablement en laissant faire le reste \u00e0 l&rsquo;Histoire<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Mais, poursuit brusquement Burnfeind, il s&rsquo;av\u00e8re tout aussi brusquement que &laquo; <em>la Gauche a perdu, et continue \u00e0 perdre, et une autre dynamique s&rsquo;es<\/em>t [brusquement] <em>mise en marche<\/em> &raquo;, la dynamique de la violence, qui implique aussi la folie. Ici, le propos de Burnfeind est brutal.<\/p>\n<\/p>\n<p><p>Burnfeind ne pr\u00e9cise par les correspondances et chronologies politiques de ce qu&rsquo;il d\u00e9crit d&rsquo;un point de vue th\u00e9ologique mais on d\u00e9duit ais\u00e9ment de ce qui suit qu&rsquo;il s&rsquo;agit de l&rsquo;opposition ultraviolente de la Gauche (ce que nous nommons, nous, les \u00ab\u00a0progressistes-soci\u00e9taux\u00a0\u00bb) qui caract\u00e9rise l&rsquo;extr\u00e9misme de l&rsquo;opposition \u00e0 Trump. Les exemples qu&rsquo;ils citent ensuite le montrent \u00e9videmment : la violence dont il parle est essentiellement de communication et symbolique, bien qu&rsquo;il y ait des campagnes de violence effective et quelques attentats, mais en nombre pour l&rsquo;instant restreint. <strong>Quelque forme qu&rsquo;elle prenne, cette violence est d&rsquo;une extr\u00eame brutalit\u00e9 et d&rsquo;une cruaut\u00e9 \u00e0 mesure<\/strong> ; d&rsquo;un point de vue symbolique, c&rsquo;est-\u00e0-dire dans sa repr\u00e9sentation fantasmagorique refl\u00e9tant la force de conviction de la psychologie, elle est extr\u00eamement brutale et violente&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans chacun de ces exemples <\/em>[de cette extr\u00eame violence], <em>les auteurs ou les intervenants symboliques ont perdu tout contact avec la d\u00e9cence humaine fondamentale, prisonniers d&rsquo;une repr\u00e9sentation psycho-spirituelle<\/em> [leur tenant lieu de perception] <em>o&ugrave; le monde est <\/em>[lui-m\u00eame] <em>prisonnier de forces des t\u00e9n\u00e8bres op\u00e9rant par le biais d&rsquo;entit\u00e9s, y compris des personnes, qui ne m\u00e9ritent que la destruction. Pourquoi ? Parce que la sauvegarde l&rsquo;humanit\u00e9 est \u00e0 ce prix. <\/em>[&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; [&#8230;] [I]<em>l y a une compl\u00e8te impr\u00e9gnation d&rsquo;un esprit iconoclaste dans l&rsquo;\u00e2me am\u00e9ricaine. Et cet esprit est le Gnosticisme. <\/em>[&#8230;] <em>L&rsquo;Iconoclasme signifie litt\u00e9ralement \u00ab\u00a0briser des images\u00a0\u00bb. Les images, selon les conceptions grecques, sont des phantasmes, c&rsquo;est-\u00e0-dire une production mentale ou psychologique qui devient la seule sorte de r\u00e9alit\u00e9 qui compte. <\/em>[&#8230;]<em> A mesure que je r\u00e9alise mon emprisonnement des forces des t\u00e9n\u00e8bres qui ont envahi le monde, <\/em>[ma] <em>r\u00e9alit\u00e9 est transf\u00e9r\u00e9e de l&rsquo;ext\u00e9rieur \u00e0 l&rsquo;int\u00e9rieur <\/em>[de moi-m\u00eame]. &raquo;<\/p>\n<\/p>\n<p><p>Dans cette situation, le syst\u00e8me de la communication joue un r\u00f4le fondamental d&rsquo;acc\u00e9l\u00e9rateur, de renforcement de tous ces phantasmes, d&rsquo;une puissance et d&rsquo;une efficacit\u00e9 inou\u00efes. &laquo;<em> Par leur nature m\u00eame, les m\u00e9dias travaillent dans le champ du fantasmagorique, manipulant les archetypes et les narratives&#8230;<\/em> &raquo; ; et certes, l&rsquo;on parle ici des m\u00e9dias d&rsquo;information, de la t\u00e9l\u00e9vision, de la musique d&rsquo;<em>entertainment<\/em> comme le rock et ses diverses d\u00e9g\u00e9n\u00e9rescences, du cin\u00e9ma, des r\u00e9seaux sociaux hyper-actifs et sans aucun frein, etc. Burnfeind nous annonce que cette violence multipli\u00e9e par la communication, jusqu&rsquo;alors r\u00e9serv\u00e9e essentiellement \u00e0 la Gauche, &laquo; <em>est en train de gagner la droite, avec des <a href=\"https:\/\/www.theatlantic.com\/magazine\/archive\/2017\/04\/breaking-faith\/517785\/\">groupes droitiers non-religieux<\/a> qui commencent \u00e0 appara&icirc;tre. Amusez-vous bien avec eux.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Le pasteur Burnfeind termine en rappelant les r\u00e9ussites de la religion qu&rsquo;il repr\u00e9sente, mais aussi les limites auxquelles son action est soumise et qui sont justement le champ d&rsquo;action de la violence actuelle. Cette religion s&rsquo;exprime dans toute sa grandeur &laquo; <em>avec Dieu comblant le gouffre entre l&rsquo;esprit et la chair, devenant notre voisin d&rsquo;esprit et de chair et faisant de notre voisin un objet d&rsquo;amour, et cr\u00e9ant une communaut\u00e9 transcendant miraculeusement les races et les nationalit\u00e9s. <strong>Mais cette m\u00eame religion nous a averti que la folie guette ceux qui se d\u00e9connectent de cette r\u00e9alit\u00e9. La folie, et aussi la violence<\/strong>. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Bien entendu, nous nous r\u00e9f\u00e9rons \u00e0 ce texte comme \u00e0 un exemple d&rsquo;un aspect de la pens\u00e9e g\u00e9n\u00e9rale qui se r\u00e9pand aux USA, et touche maintenant les th\u00e9ologiens eux-m\u00eames, qui prennent actes des \u00e9v\u00e9nements et leur donnent une signification eschatologique directement imbriqu\u00e9e dans le courant quotidien de l&rsquo;affrontement politique. Ce texte montre \u00e9galement que cette interpr\u00e9tation transcende la question nationale (des USA) pour en faire une question de civilisation avec une crise fondamentale affectant le christianisme comme vecteur de la civilisation dominante, donc impliquant une crise de civilisation qui affecte par d\u00e9finition notre monde dans sa globalit\u00e9 dans la mesure o&ugrave; la civilisation occidentale domine ce monde : <strong>la crise de la civilisation occidentale qui est maintenant \u00e0 son point d&rsquo;explosion aux USA n&rsquo;est rien de moins la crise du monde et de sa civilisation<\/strong>. Simplement, les USA, du fait de leur position dominante de puissance et d&rsquo;influence, ont, avec leur crise actuelle commenc\u00e9e dans sa phase aig\u00fce il y a deux ans, et dans sa phase paroxystique il y a un an, surmont\u00e9 en puissance toutes les autres crises pour <strong>exprimer \u00e0 eux seuls la puissance totalitaire de la crise du monde<\/strong>. Que cela soit dit en termes th\u00e9ologiques n&rsquo;importe pas pour notre lecture de la crise, <strong>sinon comme l&rsquo;indication sans doute d\u00e9cisive de l&rsquo;ampleur globale de la crise<\/strong>, surmontant tous les autres aspects, financier, politique, soci\u00e9taux, etc. ; sinon comme l&rsquo;indication que cette crise ne se tient plus au niveau des concepts et des querelles th\u00e9ologiques justement, <strong>mais qu&rsquo;elle est d\u00e9sormais dans la rue, dans chaque foyer, et m\u00eame dans la dialectique des hommes politiques<\/strong> qui pratiquent d&rsquo;habitude un langage extr\u00eamement normatif pour satisfaire au Syst\u00e8me (le candidat d\u00e9mocrate Jon Ossoff saluant sa d\u00e9faite dans une \u00e9lection partielle qui concerne un cinq cent trente-cinqui\u00e8me de la Chambre des Repr\u00e9sentants du Congr\u00e8s par rien moins que le constat que &laquo; <em>les t\u00e9n\u00e8bres ont envahi le monde <\/em>&raquo;).<\/p>\n<\/p>\n<blockquote>\n<p><p>Que cela soit dit en termes th\u00e9ologiques n&rsquo;importe pas enfin pour notre lecture de la crise, sinon, pour clore le propos ci-dessus, que cette lecture ne concerne plus ni l&rsquo;histoire imm\u00e9diate, ni l&rsquo;histoire des USA, ni m\u00eame l&rsquo;histoire de la modernit\u00e9, mais <strong>l&rsquo;histoire jusqu&rsquo;\u00e0 ses origines extr\u00eames puisqu&rsquo;il est question finalement de la r\u00e9surgence d&rsquo;une h\u00e9r\u00e9sie du christianisme du II\u00e8me si\u00e8cle<\/strong>, le Gnosticisme, per\u00e7ue d\u00e9sormais (\u00e0 juste raison ou pas, qu&rsquo;importe) comme une force active de d\u00e9stabilisation, de d\u00e9construction, de violence et de folie&#8230; Comme si les temps furieux de la fin de l&rsquo;Empire de Rome et des d\u00e9bats \u00e9galement furieux au sein du christianisme des origines revenaient pour former <strong>l&rsquo;ordinaire de l&rsquo;extension de notre crise<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Crise de la haine et du satanisme<\/h3>\n<\/p>\n<p><p>Un des aspects du texte de Burnfeind est surprenant d&rsquo;un point de vue politique et op\u00e9rationnel, qu&rsquo;il n&rsquo;explicite d&rsquo;ailleurs en aucune fa\u00e7on&#8230; Nous reprenons ici le passage, plus haut dans notre texte, qui en rend compte :<\/p>\n<\/p>\n<p><p>&laquo; \u00ab\u00a0<em>Depuis les ann\u00e9es 1960, et avec le succ\u00e8s d\u00e9montr\u00e9 <\/em>[selon elle]<em> de cette approche, la Gauche s&rsquo;\u00e9tait install\u00e9e confortablement en laissant faire le reste \u00e0 l&rsquo;Histoire<\/em>.\u00a0\u00bb Mais, tranche brusquement Burnfeind, il s&rsquo;av\u00e8re tout aussi brusquement que \u00ab\u00a0<em>la Gauche a perdu, et continue \u00e0 perdre, et une autre dynamique s&rsquo;es<\/em>t [brusquement] <em>mise en marche<\/em>\u00ab\u00a0, la dynamique de la violence, qui implique aussi la folie&#8230; &raquo;<\/p>\n<\/p>\n<p><p>On voit mal comment la Gauche, c&rsquo;est-\u00e0-dire le n\u00e9o-Gnosticisme, c&rsquo;est-\u00e0-dire l&rsquo;Herm\u00e9ticisme triomphant, c&rsquo;est-\u00e0-dire le progressisme-soci\u00e9tal selon notre classification actuelle, peuvent \u00eatre d\u00e9crits comme perdants. Certes, il y a eu aux USA la d\u00e9faite de Clinton, mais en quoi cela repr\u00e9sente-t-il une v\u00e9ritable d\u00e9faite de \u00ab\u00a0la Gauche\u00a0\u00bb au regard du flux g\u00e9n\u00e9ral qui a envahi tout l&rsquo;Occident, le bloc-BAO, au niveau du \u00ab\u00a0politiquement correct\u00a0\u00bb en mati\u00e8re de pens\u00e9e, au niveau des \u00ab\u00a0valeurs\u00a0\u00bb n\u00e9olib\u00e9rales &#038; libertaires, de l&rsquo;activisme soci\u00e9tal, de la d\u00e9construction de tout ce qui tient la soci\u00e9t\u00e9 ? Et tout cela face serait d\u00e9fait \u00e0 cause de la victoire d&rsquo;un Trump qui est \u00e9videmment un bouffon erratique dont le pseudo-\u00ab\u00a0populisme\u00a0\u00bb est une sorte de kal\u00e9idoscope abracadabrant faisant aussi bien la part belle aux p\u00e9troliers qui se pr\u00e9cipite sur tous les gisements comestibles aux USA, qu&rsquo;aux marchands de canon gavant de missiles sophistiqu\u00e9s la pourriture impuissante des Saoud ?&#8230; D&rsquo;ailleurs, n&rsquo;entend-on pas le sublime-tribun La-M\u00e9luche, place de la R\u00e9publique et en bras de chemises, nous rejouant hier Maurice Thorez <em>circa<\/em>-36 et Front Popu&rsquo;, en traitant Sa Majest\u00e9 Emmanuel Ier \u00e0 la fois de Prince et de \u00ab\u00a0populiste\u00a0\u00bb au milieu des ors de Versailles abritant temporairement la repr\u00e9sentation nationale, r\u00e9publicaine et la\u00efque ? Un conseil nous vient \u00e0 l&rsquo;esprit : n&rsquo;essayons pas de comprendre, et encore moins d&rsquo;expliquer la situation pr\u00e9sente en nous r\u00e9f\u00e9rant \u00e0 de tels concepts (\u00ab\u00a0la gauche\u00a0\u00bb, le \u00ab\u00a0populisme\u00a0\u00bb) relevant de temps o&ugrave; l&rsquo;on avait plus d&rsquo;attention pour la coh\u00e9rence des concepts bien compris et la mesure des situations observ\u00e9es avec justesse, de temps o&ugrave;, selon le langage du pasteur Bernfeind, la modernit\u00e9 se satisfaisait encore d&rsquo;un Herm\u00e9ticisme triomphant. <strong>La violence du langage, nous avertit Burnfeind, s&rsquo;accompagne de la d\u00e9mence<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi pr\u00e9f\u00e9rons-nous appr\u00e9hender l&rsquo;analyse du Pasteur de l&rsquo;Universit\u00e9 de Toledo du point de vue du Syst\u00e8me et simplement observer \u00e0 son propos que, d\u00e9sormais, la th\u00e9ologie, avec l&rsquo;in\u00e9vitable extension et l&rsquo;ennoblissement du champ des r\u00e9flexions qu&rsquo;elle impose, <strong>prend \u00e0 son compte, selon ses conceptions qui nous conduisent heureusement aux origines, la crise de l&rsquo;effondrement du Syst\u00e8me<\/strong>. Effectivement, l&rsquo;int\u00e9r\u00eat de la th\u00e9ologie dans ce cas n&rsquo;est pas tant de nous instruire du facteur religieux qui nous importe peu, que <strong>d&rsquo;introduire le facteur de l&rsquo;eschatologie que nous devons consid\u00e9rer hors et m\u00eame au-dessus du facteur religieux<\/strong> ; mais elle le fait, la th\u00e9ologie, en s&rsquo;appuyant sur une documentation et une culture nourries \u00e0 un aspect de la tradition qui, justement, <strong>renoue, ou noue plus fortement encore notre r\u00e9flexion aux origines<\/strong>.<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, et ce n&rsquo;est pas rien <strong>parce que c&rsquo;est l&rsquo;essentiel<\/strong>, en d\u00e9veloppant cette analyse d&rsquo;un n\u00e9o-Gnosticisme Burnfeind introduit l&rsquo;\u00e9l\u00e9ment et <strong>surtout l&rsquo;\u00e9v\u00e9nement imm\u00e9diat du Mal<\/strong> qui est naturellement fondamental dans le courant du Gnosticisme construit selon l&rsquo;id\u00e9e de son omnipr\u00e9sence (du Mal). Il rejoint ainsi l&rsquo;atmosph\u00e8re psychologique qui r\u00e8gne aujourd&rsquo;hui, avec cette haine de tous bords, saisissante de puissance, qui caract\u00e9rise les positions et qui <strong>r\u00e9pond \u00e0 une tr\u00e8s forte perception du satanisme sans que l&rsquo;on puisse identifier avec certitude, &ndash; mais cette dissimulation est le propre du satanisme, &ndash; dans quel sens il se manifeste, qui le manifeste, etc.<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>La crise du pouvoir de l&rsquo;am\u00e9ricanisme est ainsi sortie des limites que lui impose justement cet intitul\u00e9. L&rsquo;analyse nous restitue parfaitement la dimension psychologique, c&rsquo;est-\u00e0-dire essentiellement la haine qui oppose les protagonistes et rend cette crise totalement insoluble en la faisant appara&icirc;tre en v\u00e9rit\u00e9 comme une repr\u00e9sentation du mod\u00e8le central qu&rsquo;est la crise du Syst\u00e8me. (On voit qu&rsquo;on se trouve ainsi dans l&rsquo;inversion compl\u00e8te, le mod\u00e8le fondamental de la crise, la crise du Syst\u00e8me, \u00e9tant lui-m\u00eame simulacre, et par cons\u00e9quent inversion de ce qui devrait \u00eatre un mod\u00e8le de civilisation.) Cela implique <strong>la force inou\u00efe de la dimension psychologique de la crise<\/strong>, facteur que l&rsquo;on ressent partout sous des formes diff\u00e9rentes malgr\u00e9 le <em>black-out <\/em>impos\u00e9 par le syst\u00e8me de communication et la presseSyst\u00e8me, dans les diverses crises en cours, comme si le premier effet en importance et en totalit\u00e9 de la globalisation portait sur la nature de la crise, en l&rsquo;inscrivant irr\u00e9sistiblement <strong>dans la dimension psychologique qui est le v\u00e9ritable facteur globalis\u00e9, qui se joue des fronti\u00e8res, des langues, des ethnies, des restes de culture, etc<\/strong>.<\/p>\n<\/p>\n<p><p>L&rsquo;analyse nous sort \u00e9galement des limites chronologiques habituelles, symboliquement et essentiellement avec ses r\u00e9f\u00e9rences \u00e0 l&rsquo;origine du christianisme qui ne sont pas seulement anecdotiques ou utilitaires. Ce d\u00e9placement historique fondamental est \u00e0 la fois symbolique et conceptuel. Il contribue fortement \u00e0 nous rappeler, indirectement et involontairement \u00e0 la fois mais d&rsquo;une fa\u00e7on lancinante une fois la chose r\u00e9alis\u00e9e, que <strong>les racines de la crise du syst\u00e8me, et de cette contre-civilisation qui en est l&rsquo;aboutissement, se trouvent \u00e0 l&rsquo;origine m\u00eame de l&rsquo;ensemble structurel et spirituel de notre histoire<\/strong>.<\/p>\n<\/p>\n<p><p>A ces lumi\u00e8res diff\u00e9rentes, la crise du pouvoir de l&rsquo;am\u00e9ricanisme, si elle garde \u00e9videmment sa position de <em>leadership<\/em> comme il convient avec les USA (la premi\u00e8re de toutes les crises), n&rsquo;est plus li\u00e9e \u00e0 sa sp\u00e9cificit\u00e9 am\u00e9ricaniste. Cette sp\u00e9cificit\u00e9 am\u00e9ricaniste n&rsquo;est plus qu&rsquo;un moyen permettant \u00e0 l&rsquo;importance de la crise de s&rsquo;exprimer dans toute sa fureur et toute sa haine. Il devient alors \u00e9vident, selon la logique de cette d\u00e9marche, que la crise du pouvoir de l&rsquo;am\u00e9ricanisme est une crise transnationale et internationale, une crise globale et cosmique, <strong>une crise de type syst\u00e9mique et de fonction eschatologique<\/strong>, bref sans aucun doute et plus que jamais <strong>le c&oelig;ur grondant de la crise d&rsquo;effondrement du syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>Bon anniversaire USA, sous le regard du fant\u00f4me de l&rsquo;Empire de Rome&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sous le regard du fant\u00f4me de l&rsquo;Empire 04 juillet 2017 &ndash; Le 4 juillet est la f\u00eate nationale aux USA, et cette ann\u00e9e est marqu\u00e9e par un appel de divers groupes anti-Trump domin\u00e9 notamment par un \u00ab\u00a0appel aux armes\u00a0\u00bb lanc\u00e9 par Michael Moore avec son groupe \u00ab\u00a0Resistance\u00ab\u00a0. Ce 4 juillet donc, une marche est pr\u00e9vue&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[13154,13151,2963,11626,7548,13149,3602,13152,13150,13153,6884,915,3256,13155,9995,2693,2755,1267,3248],"class_list":["post-77349","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antifa","tag-burnfeind","tag-christianisme","tag-d-c","tag-eschatologie","tag-gnosticisme","tag-haine","tag-heresie","tag-hermeticisme","tag-jersey","tag-jon","tag-moore","tag-new","tag-ossof","tag-pasteur","tag-peter","tag-resistance","tag-terrorisme","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77349"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77349\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}