{"id":77373,"date":"2017-07-16T09:20:18","date_gmt":"2017-07-16T09:20:18","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/16\/notes-sur-leur-house-of-cards\/"},"modified":"2017-07-16T09:20:18","modified_gmt":"2017-07-16T09:20:18","slug":"notes-sur-leur-house-of-cards","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/16\/notes-sur-leur-house-of-cards\/","title":{"rendered":"Notes sur leur <em>House of Cards<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur leur <em>House of Cards<\/em><\/h2>\n<\/p>\n<p><p>16 juillet 2017 &ndash; Au d\u00e9part, ce n&rsquo;est qu&rsquo;une observation anecdotique faite par un twitter plus ou moins anonyme, dit-<em>00Author87<\/em>, le <a href=\"https:\/\/twitter.com\/00Author87\/status\/883348320550359041\/photo\/1\">7 juillet 2017<\/a>, avec comme l\u00e9gende : &laquo; <em>When you&rsquo;re watching the news but you&rsquo;ve seen it all before on House of Cards<\/em>&#8230; &raquo; RT a repris ce tweet pour en faire l&rsquo;argument d&rsquo;un article, montrant \u00e9videmment les sc\u00e8nes concern\u00e9es.<\/p>\n<\/p>\n<p><p>&laquo; <em>Donald Trump&rsquo;s ascend to the White House has often been compared to something out of fiction. But on Friday at the G20 Summit, Trump&rsquo;s meeting with Putin in front of the cameras took on the uncanny resemblance of a scene from a Netflix series<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>The G20 summit has already yielded two <\/em><em><a href=\"https:\/\/www.youtube.com\/watch?v=3opRPbs2ZuE\">handshakes<\/a><\/em><em> between Putin and Trump, with the second official greeting garnering the most interest due to its resemblance to a scene in chapter 29 of the &lsquo;House of Cards<\/em>. [&#8230;] <em>In the 2015 episode, the fictionalized US President Frank Underwood (Kevin Spacey) and President of the Russian Federation Viktor Petrov (Lars Mikkelsen) are at loggerheads over a European missile defense system<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;int\u00e9r\u00eat central de la psychologie<\/h3>\n<\/p>\n<p><p>L&rsquo;anecdotique est dans ce sens que cette similitude n&rsquo;a gu\u00e8re de signification politique, ne serait-ce que parce que le Petrov-Poutine de <em>House of Cards<\/em> (il appara&icirc;t dans la Saison 3, lorsqu&rsquo;Underwood est devenu pr\u00e9sident) n&rsquo;est qu&rsquo;une caricature absolument antirussiste de Poutine tandis qu&rsquo;Underwood, produit direct et impeccable de l&rsquo;<em>establishment<\/em> dans l&rsquo;esprit de la chose (corruption, hypocrisie, double langage et cynisme, cruaut\u00e9), est lui aussi sans rapport aucun avec Trump. D&rsquo;autre part, la \u00ab\u00a0similitude\u00a0\u00bb renvoie \u00e0 la Saison 4 (tourn\u00e9e en 2015 jusqu&rsquo;au tout d\u00e9but 2016), alors que ce qui nous int\u00e9resse ici plus directement, et cette fois avec un sens politique, est la Saison 5 qui a commenc\u00e9 \u00e0 \u00eatre diffus\u00e9 en mars 2017 aux USA et \u00e0 la fin juin 2017 sur certaines cha&icirc;nes europ\u00e9ennes (francophones).<\/p>\n<\/p>\n<p><p>Nous allons publier deux textes ci-dessous : l&rsquo;un assez long, qui est une traduction fran\u00e7aise d&rsquo;un excellent texte de critique de la Saison 5 de la s\u00e9rie de <em>WSWS.org<\/em>, assorti des quelques phrases du type-trotskiste de rigueur auxquelles il n&rsquo;est pas n\u00e9cessaire de s&rsquo;attarder ; l&rsquo;autre est beaucoup plus court, un extrait d&rsquo;une appr\u00e9ciation trouv\u00e9e dans une lecture extr\u00eamement dans l&rsquo;air de notre culture-Syst\u00e8me, venu d&rsquo;un hebdomadaire belge de t\u00e9l\u00e9vision, <em>Moustique<\/em>. On s&rsquo;en expliquera plus longuement plus loin, lorsque son tour sera venu.<\/p>\n<\/p>\n<p><p>(Pr\u00e9cisons que nous n&rsquo;avons vu que des extraits la Saison 5 apr\u00e8s \u00eatre au terme de la Saison 4. Mais <strong>ce n&rsquo;est pas l&rsquo;intrigue qui nous int\u00e9resse mais l&rsquo;\u00e9volution des caract\u00e8res et des psychologies, puis des actes par cons\u00e9quent, que cette \u00e9volution engendre <\/strong>: il y a beaucoup \u00e0 dire l\u00e0-dessus m\u00eame sans visionner la S\u00e9rie 5 dans son d\u00e9tail, <strong>et bien suffisamment pour notre propos<\/strong>. Par ailleurs, le texte de <em>WSWS.org<\/em>, bien que tr\u00e8s critique, en dit bien assez sur l&rsquo;intrigue <strong>pour une connaissance de base nous donnant la s\u00e9curit\u00e9 qu&rsquo;il faut dans la connaissance<\/strong>, qui compl\u00e8te effectivement ce que nous voulons et devons savoir de l&rsquo;\u00e9volution de la s\u00e9rie sur le plan de l&rsquo;intrigue pour notre propos th\u00e9orique qu&rsquo;on verra plus loin.)<\/p>\n<\/p>\n<p><p>Voici donc d&rsquo;abord le texte de WSWS.org (en original <a href=\"http:\/\/www.wsws.org\/en\/articles\/2017\/06\/20\/card-j20.html\">le 20 juin 2017<\/a>) : <em>The House of Cards<\/em>, Saison 5, ou \u00ab\u00a0La mort de l&rsquo;&Acirc;ge de la Raison\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\"><em>The House of Cards<\/em>, ou \u00ab\u00a0La mort de l&rsquo;&Acirc;ge de la Raison\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>&laquo; <em>Dans la Saison 5 de la s\u00e9rie Netflix House of Cards <\/em>[\u00ab\u00a0ch\u00e2teau de cartes\u00a0\u00bb]<em>, l&rsquo;administration du pr\u00e9sident Frank Underwood (Kevin Spacey) fabrique une menace terroriste pour influencer une \u00e9lection, ordonne l&rsquo;assassinat d&rsquo;un citoyen am\u00e9ricain qui a \u00e9t\u00e9 d\u00e9tenu et tortur\u00e9 en secret, fait un usage r\u00e9gulier des scandales sexuels et d&rsquo;enregistrement secrets pour faire chanter un parlementaire et manipuler l&rsquo;opinion publique, et est finalement confront\u00e9e \u00e0 des factions dans la communaut\u00e9 militaire et du renseignement qui s&rsquo;opposent \u00e0 la pr\u00e9sidence Underwood<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Si les auteurs de la s\u00e9rie avaient commenc\u00e9 chaque \u00e9pisode avec la mention \u00ab\u00a0inspir\u00e9 d&rsquo;\u00e9v\u00e9nements r\u00e9els\u00a0\u00bb, ils auraient \u00e9t\u00e9 parfaitement dans leur droit. Il n&rsquo;y a rien dans House of Cards qui est exag\u00e9r\u00e9 par rapport \u00e0 la r\u00e9alit\u00e9. Avec les administrations successives impliqu\u00e9es dans les crimes les plus barbares, avec des \u00e9l\u00e9ments ouvertement fascistes peuplant les pi\u00e8ces de la Maison-Blanche, n&rsquo;importe quelle personne visionnant la s\u00e9rie ne peut \u00eatre choqu\u00e9e ni \u00e9prouver la moindre incr\u00e9dulit\u00e9. Tout est enti\u00e8rement cr\u00e9dible et dans les habitudes de Washington D.C<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les \u00e9v\u00e9nements d\u00e9crits dans ces \u00e9pisodes n&rsquo;appartiennent nullement \u00e0 un futur dystopien mais \u00e0 un pr\u00e9sent parfaitement reconnaissable. L&rsquo;\u00e9lite criminelle de la s\u00e9rie se retrouve parfaitement dans celle qui domine la vie officielle des &Eacute;tats-Unis. Si les auteurs de la s\u00e9rie \u00e9prouvent quelque difficult\u00e9, c&rsquo;est en tentant de suivre le rythme du crime et de la d\u00e9pravation de la v\u00e9ritable vie de Washington D.C.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>A la fin de la Saison 4, Underwood et sa femme, &ndash; et sa co-listi\u00e8re pour la fonction de vice-pr\u00e9sidence, &ndash; Claire (Robin Bright) \u00e9taient engag\u00e9s dans une bataille furieuse contre leur challenger, le candidat r\u00e9publicain Will Conway (Joel Kinnaman). Risquant de perdre leur \u00e9lection et de devoir affronter l&rsquo;exposition publique de leurs crimes, les Underwood r\u00e9solvent de lutter de toutes leurs forces et par tous les moyens. D\u00e9termin\u00e9s \u00e0 utiliser la menace d&rsquo;une attaque terroriste de l&rsquo;ICO, le surnom fictif donn\u00e9 \u00e0 Daesh dans la s\u00e9rie, pour influencer l&rsquo;\u00e9lection, Frank Underwood fixe des yeux la cam\u00e9ra selon le proc\u00e9d\u00e9 employ\u00e9 dans la s\u00e9rie et s&rsquo;adressant au public (\u00e0 nous), avertit froidement : \u00ab\u00a0Nous ne nous soumettrons pas \u00e0 la terreur, nous ferons r\u00e9gner la terreur\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Dans la Saison 5, les Underwood tiennent parole<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Ils prennent diverses mesures pour cette \u00e9lection. Citant des menaces terroristes (de leur propre invention), les Underwood imposent la loi martiale dans certaines zones urbaines et soumettent de nombreux bureaux de vote \u00e0 des proc\u00e9dures sp\u00e9ciales, en insistant sur les n\u00e9cessit\u00e9s de la s\u00e9curit\u00e9 mais en fait pour emp\u00eacher une partie de la population rurale, notoirement r\u00e9publicaine, de voter<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Aidan MacCallan (Damian Young), le sp\u00e9cialiste de l&rsquo;informatique et \u00e9galement hacker, qui a fourni aux Underwood, lors de la Saison 4, un acc\u00e8s aux donn\u00e9es de la NSA sur des citoyens US, se fait engager dans cette m\u00eame NSA pour travailler pour les Underwoood \u00ab\u00a0de l&rsquo;int\u00e9rieur \u00ab\u00a0. Il joue un r\u00f4le central lors des derniers jours de la campagne \u00e9lectorale quand il utilise son poste \u00e0 la NSA pour monter une fausse cyberattaque de l&rsquo;ICO contre le r\u00e9seau de t\u00e9l\u00e9communication de Washington D.C. Apr\u00e8s qu&rsquo;il ait termin\u00e9 son travail pour les \u00e9lections, MacAllan, r\u00e9alisant qu&rsquo;il va \u00eatre liquid\u00e9 parce qu&rsquo;il plus d&rsquo;aucune utilit\u00e9, pr\u00e9f\u00e8re fuir le pays.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le jour de l&rsquo;\u00e9lection, plac\u00e9 devant la possibilit\u00e9 d&rsquo;une d\u00e9faite, Underwood provoque un blocage du vote dans le Tennessee et l&rsquo;Ohio au travers d&rsquo;une autre fausse menace d&rsquo;attaque terroriste, et finalement emporte le recomptage de l&rsquo;Ohio apr\u00e8s avoir fait fuit\u00e9 une vid\u00e9o impliquant son adversaire Conway, qu&rsquo;il a obtenue gr\u00e2ce au principal adjoint du m\u00eame Conway. Ce dernier, Mark Usher (Campbell Scott) sera r\u00e9compens\u00e9 par une position de conseiller de haut niveau \u00e0 la Maison-Blanche d\u00e9mocrate des Underwood. Le programme rend bien compte du cynisme extr\u00eame des politiciens capitalistes am\u00e9ricains et de la facilit\u00e9 avec laquelle on change de candidats, de politiques et de partis aussi bien que l&rsquo;on change de cravates<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les efforts des Underwood pour manipuler les \u00e9lections cr\u00e9e un imbroglio dans lequel aucun vainqueur assur\u00e9 n&rsquo;appara&icirc;t, laissant au Congr\u00e8s le soin de d\u00e9terminer qui sera le prochain pr\u00e9sident. Les Underwood lancent une campagne de chantage, d&rsquo;espionnage et d&rsquo;assassinat pour obtenir le r\u00e9sultat qu&rsquo;ils d\u00e9sirent<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le journaliste Tom Hammerschmidt (Boris McGiver) continue de son c\u00f4t\u00e9 ses investigations pour tenter d&rsquo;obtenir le plus d&rsquo;informations possibles sur les Underwood, recevant des fuites de la part d&rsquo;une source \u00e0 la Maison-Blanche. Mais m\u00eame alors que l&rsquo;\u00e9tau se resserre autour d&rsquo;eux, les Underwood montre une fois de plus leurs capacit\u00e9s \u00e0 reprendre la main dans toutes les circonstances<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, la Saison 5 est un succ\u00e8s. Spacey continue \u00e0 \u00eatre excellent dans le r\u00f4le de Frank Underwood, et Patricia Clarkson est sp\u00e9cialement remarquable dans le r\u00f4le de la myst\u00e9rieuse Jane Davois, une personne qui a des liens personnels avec la communaut\u00e9 du renseignement et \u00e0 laquelle tout le monde se confie d&rsquo;une fa\u00e7on follement imprudente. Elle conna&icirc;t plus de v\u00e9rit\u00e9s et dit plus de mensonges que n&rsquo;importe qui d&rsquo;autre dans la s\u00e9rie. Son caract\u00e8re repr\u00e9sente cette fraction du Deep State qui tente de modifier la politique \u00e9trang\u00e8re US en Syrie et elle favorise l&rsquo;installation de Claire dans le bureau ovale. Elle encourage les Underwood \u00e0 monter une attaque chimique en Syrie de fa\u00e7on \u00e0 avoir un pr\u00e9texte pour lancer une guerre contre les int\u00e9r\u00eats russes dans le pays. Ce passage est le plus intrigant par sa cr\u00e9dibilit\u00e9 et le plus remarquable<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>La faiblesse de la s\u00e9rie reste ce qu&rsquo;elle a toujours \u00e9t\u00e9 : une tendance \u00e0 se concentrer sur les intrigues de palais elles-m\u00eames, aux d\u00e9pens des questions sociales plus larges \u00e0 proprement parler. Il y a peu d&rsquo;efforts ou des efforts mal \u00e0 propos pour nous expliquer le fait de la corruption de ces personnalit\u00e9s de la cat\u00e9gorie des Underwood e leurs sous-fifres sinon par des r\u00e9f\u00e9rences sur les caract\u00e8res sexuels r\u00e9prim\u00e9s ou d\u00e9tourn\u00e9s de l&rsquo;un ou l&rsquo;autre, &ndash; l&rsquo;homosexualit\u00e9 contenue de Frank Underwood, les \u00e9lans sans joie de sa femme, les obsessions de leur principal conseiller Doug Stamper (Michael Kelly)<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Quelles que soient ces limitations, n\u00e9anmoins, on peut trouver mille fois plus de v\u00e9rit\u00e9 \u00e0 propos de Washington dans la s\u00e9rie The House of Cards que dans tous les commentaires l\u00e9nifiants qu&rsquo;on trouve dans la plupart des grands journaux et sur les r\u00e9seaux t\u00e9l\u00e9vis\u00e9s. Ici au moins, les secrets \u00e9vidents le sont justement, ils sont mis en \u00e9vidence<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Un moment dans cette Saison 5 tranche sur tous les autres. Durant une audition au Congr\u00e8s sur les crimes commis par son administration, Frank Underwood brise la loi du silence pour faire cette extraordinaire d\u00e9claration \u00e0 notre intention, nous autres les spectateurs : \u00ab\u00a0Le pont est plein d&rsquo;ordures, les lois sont bafou\u00e9es. Bienvenue \u00e0 la mort de l&rsquo;&Acirc;ge de la Raison.\u00a0\u00bb C&rsquo;est une phrase qui r\u00e9sume puissamment la crise terminale de la d\u00e9mocratie bourgeoise<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>On en vient \u00e0 la fin \u00e0 un long apart\u00e9 o&ugrave; Underwood nous confie finalement le sens des choses qu&rsquo;il dit aux gens ordinaires : \u00ab\u00a0Oh, ne le niez pas\u00a0\u00bb, dit-il \u00e0 son audience, \u00ab\u00a0vous adorez cela. Vous n&rsquo;avez pas besoin en fait que je m&rsquo;affirme pour quelque cause. Vous avez juste besoin que je m&rsquo;affirme. Vous avez besoin d&rsquo;un homme fort, d&rsquo;un homme d&rsquo;action. Mon Dieu, vous \u00eates prisonniers de l&rsquo;action et des slogans. Peu importe ce que je dis. Peu importe ce que je fais. Du moment que je fais quelque chose, vous \u00eates heureux et vous embarquez pour la chevauch\u00e9e. Et franchement, je ne peux pas vous bl\u00e2mer. Avec toutes la folie et l&rsquo;ind\u00e9cision de vos vies, pourquoi pas un homme comme moi ? A la fin, je me fiche que vous m&rsquo;aimiez ou que vous me ha\u00efssiez, du moment que je gagne<\/em>.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; <em>Ce discours sonne comme un d\u00e9fi pour le spectateur. Tous les Underwood du monde ont pu si longtemps agir sans le moindre contr\u00f4le. Leur brutalit\u00e9 est \u00e9quilibr\u00e9e seulement par leur arrogance, par leur confiance, parce qu&rsquo;ils croient pouvoir faire ce qui leur pla&icirc;t. Il est temps de leur montrer qu&rsquo;ils ont tort<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;infantilisme postmoderne : <em>Moustique <\/em>&#038;<em> House of Cards<\/em><\/h3>\n<\/p>\n<p><p>Voici un autre point de vue. Il est infiniment plus court, parce qu&rsquo;il ne s&rsquo;agit que d&rsquo;un extrait d&rsquo;un ensemble qui s&rsquo;attache aux aspects techniques et \u00e9ventuellement \u00ab\u00a0artistiques\u00a0\u00bb de la s\u00e9rie. Cet extrait concerne l&rsquo;aspect purement politique, celui qu&rsquo;analyse principalement <em>WSWS.org<\/em>. Il vient du magazine-TV <em>Moustique<\/em>, le plus vendu en Belgique, et dont on peut affirmer sans aucun besoin de d\u00e9monstration qu&rsquo;il faut partie de la sous-presseSyst\u00e8me universelle dans le bloc-BAO, des domaines populaires de l&rsquo;<em>entertainment, people <\/em>(pipole), de pseudo-vulgarisation des probl\u00e8mes soci\u00e9taux, etc., en plus des sacro-saints programmes TV. Il s&rsquo;agit d&rsquo;une publication typique de l&rsquo;endoctrinement de base du Syst\u00e8me r\u00e9alis\u00e9 par des \u00ab\u00a0journalistes\u00a0\u00bb dont la culture est enti\u00e8rement dispens\u00e9e par le Syst\u00e8me avec ses normes progressistes-soci\u00e9tales. (<em>Moustique<\/em> du 28 juin 2017, pages 78-79, pr\u00e9sentant <em>House of Cards<\/em> Saison 5, programm\u00e9 sur <em>BE S\u00e9rie<\/em> \u00e0 partir du 7 juillet)&#8230; <strong>Texte typique, donc, \u00e0 consid\u00e9rer comme une sorte de pi\u00e8ce arch\u00e9ologique pr\u00e9cieuse pour nos lointains successeurs qui chercheront la cause de la catastrophe qui a frapp\u00e9 notre civilisation<\/strong>&#8230; Le voici (pour les incultes comme nous-m\u00eames, nous avons renvoy\u00e9 deux mots d\u00e9pendant de notre tr\u00e8s-haute culture de notre-postmodernit\u00e9 \u00e0 leurs int\u00e9ressantes d\u00e9finitions) :<\/p>\n<\/p>\n<p><p>&laquo; <em>POLITIQUEMENT BIZARRE<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Face aux r\u00e9publicains, le parti de Clinton, Gore et Obama, c&rsquo;est celui des \u00ab\u00a0gentils\u00a0\u00bb, surtout pour nous, europ\u00e9ens. Faire d&rsquo;Underwood un de leurs leaders \u00e9tait une trouvaille g\u00e9niale, ses vilenies semblant d&rsquo;autant plus vilaines face aux valeurs de sa formation politique. Ici, impossible d&rsquo;y croire. Impossible de croire qu&rsquo;un d\u00e9mocrate puisse pi\u00e9tiner \u00e0 ce point la d\u00e9mocratie, d\u00e9cider de r\u00e9gner par la terreur et bafouer les institutions. A nouveau, la fronti\u00e8re entre fiction et <a href=\"https:\/\/fr.wiktionary.org\/wiki\/portnawak\">portnawak<\/a> est largement franchie<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>ET SURTOUT&#8230; LES TEMPS CHANGENT<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cr\u00e9\u00e9 sous la pr\u00e9sidence Obama, House of Cards fascinait par son c\u00f4t\u00e9 obscur. C&rsquo;\u00e9tait <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Palpatine\">Palpatine<\/a> \u00e0 la Maison-Blanche ! de la pure fiction, pour jouer \u00e0 se faire peur. Dans le monde de Trump et d&rsquo;Erdogan, on r\u00e9alise qu&rsquo;elle \u00e9tait proph\u00e9tique. Aujourd&rsquo;hui, des Underwood, il y en a plein le JT, en rajouter \u00e0 la soir\u00e9e c&rsquo;est l&rsquo;\u00e9c&oelig;urement. La boue (au sens propre comme au sens figur\u00e9) de Frank nous plombe. Et ce n&rsquo;est vraiment plus le moment<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;horreur de l&rsquo;infantilisme postmoderne <\/h3>\n<\/p>\n<p><p>Ce texte imm\u00e9diatement ci-dessus est accablant d&rsquo;infantilisme, puisque nous sommes d\u00e9cid\u00e9s \u00e0 ne pas employer d&rsquo;autre mot que celui d&rsquo;infantilisme qui nous signifie l&rsquo;arr\u00eat du d\u00e9veloppement du cerveau et de tout ce qui va avec \u00e0 un stade extr\u00eamement pr\u00e9liminaire, quand le mot m\u00eame de \u00ab\u00a0culture\u00a0\u00bb n&rsquo;a pas encore \u00e9t\u00e9 rencontr\u00e9. Qualifier de \u00ab\u00a0gentils\u00a0\u00bb un Clinton ou un Obama (laissons Gore de c\u00f4t\u00e9), c&rsquo;est-\u00e0-dire l&rsquo;attaque du Kosovo, les drones liquidateurs, l&rsquo;attaque de la Libye, l&rsquo;activisme en Syrie avec ses <em>false-flag<\/em>, le \u00ab\u00a0coup de Kiev\u00a0\u00bb, etc., c&rsquo;est effectivement de l&rsquo;infantilisme ; nous parler des \u00ab\u00a0valeurs\u00a0\u00bb du parti d\u00e9mocrate (les \u00ab\u00a0gentils\u00a0\u00bb), et voir dans le fait de \u00ab\u00a0bafouer les institutions\u00a0\u00bb \u00ab\u00a0de la pure fiction\u00a0\u00bb puisqu&rsquo;Underwood est un d\u00e9mocrate, c&rsquo;est sans aucun doute de l&rsquo;infantilisme.<\/p>\n<\/p>\n<p><p>Nos braves petites babioles postmodernistes croyaient que <em>House of Cards <\/em>c&rsquo;\u00e9tait pour le <em>fun<\/em>, un jeu-video &laquo; <em>pour se faire peur <\/em>&raquo; quoi, mais voil\u00e0 qu&rsquo;un secret instinct que l&rsquo;infantilisme n&rsquo;a pas vu venir avertit l&rsquo;esprit simple que non, pas du tout, il s&rsquo;agit du vrai&#8230; M\u00eame si on tente de s&rsquo;en tirer en citant Trump (et Erdogan ! Que vient-il faire dans cette salade ? Pourquoi pas le moustachu du Nuremberg ?), c&rsquo;est comme si l&rsquo;infantilisme devinait inconsciemment et avec terreur qu&rsquo;il y a du vrai l\u00e0-dedans, m\u00eame et surtout <strong>avec le parti des \u00ab\u00a0gentils\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>La v\u00e9rit\u00e9 du ph\u00e9nom\u00e8ne se trouve effectivement dans l&rsquo;appr\u00e9ciation de <em>WSWS.org<\/em>, qui observe que les auteurs de la s\u00e9rie ont comme principale difficult\u00e9 de <strong>parvenir \u00e0 suivre l&rsquo;aggravation constante de l&rsquo;horreur et de la corruption \u00e0 Washington pour nourrir leur vision prospective des \u00e9v\u00e9nements<\/strong>. La remarque est donc parfaitement fond\u00e9e : on en apprend bien plus en regardant <em>House of Cards <\/em>qu&rsquo;en lisant le New York <em>Times<\/em>, le Washington <em>Post<\/em> et <em>Le Soir <\/em>de Bruxelles, &ndash; les trois ensemble m\u00eame, on vous fera un prix&#8230; (&laquo; <em>Quelles que soient ces limitations, n\u00e9anmoins, on peut trouver mille fois plus de v\u00e9rit\u00e9 \u00e0 propos de Washington dans la s\u00e9rie The House of Cards que dans tous les commentaires l\u00e9nifiants qu&rsquo;on trouve dans la plupart des grands journaux et sur les r\u00e9seaux t\u00e9l\u00e9vis\u00e9s. Ici au moins, les secrets \u00e9vidents le sont justement, ils sont mis en \u00e9vidence<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Bref, le texte des infantiles que nous avons cit\u00e9s n&rsquo;est rien d&rsquo;autre qu&rsquo;une r\u00e9v\u00e9lation brutale et \u00e9videmment tentativement repouss\u00e9e mais sans grand succ\u00e8s qu&rsquo;avec la Saison 5 nous pourrions bien \u00eatre dans la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> de Washington D.C. Par sa simple affirmation horrifi\u00e9e que ce qu&rsquo;elle avait pris pour du<em> fun<\/em> et qui s&rsquo;av\u00e8re \u00eatre une v\u00e9ritable repr\u00e9sentation (<strong>c&rsquo;est-\u00e0-dire \u00ab\u00a0repr\u00e9sentation\u00a0\u00bb selon la d\u00e9finition que des ingr\u00e9dients d\u00e9cisifs de la substance du mod\u00e8le de la v\u00e9rit\u00e9 sont bien pr\u00e9sents, et non pas la simulation qui renverse le tout et rompt d\u00e9cisivement avec le mod\u00e8le<\/strong>), par cette affreuse d\u00e9couvertes l&rsquo;infantilisme jusqu&rsquo;alors triomphant devient l&rsquo;infantilisme terrifi\u00e9 devant le spectacle qu&rsquo;on lui offre de ses \u00ab\u00a0gentils\u00a0\u00bb&#8230; C&rsquo;est \u00e0 ce point que l&rsquo;int\u00e9r\u00eat de <em>The House of Cards<\/em>, d\u00e9cel\u00e9 d\u00e8s la premi\u00e8re saison, se r\u00e9v\u00e8le dans toute sa puissance.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La fiction pr\u00e9c\u00e8de la r\u00e9alit\u00e9<\/h3>\n<\/p>\n<p><p>Ces p\u00e9rip\u00e9ties qui pourraient para&icirc;tre accessoires prennent tout leur sens, en effet, avec la s\u00e9rie elle-m\u00eame qui, \u00e0 mesure des saisons qui se sont succ\u00e9d\u00e9es, a effectivement accompagn\u00e9 l&rsquo;\u00e9volution de Washington en observant cette \u00e9volution, mais justement en en tirant une prospective de plus en plus brutale et de plus en plus violente, et surtout de plus en plus radicale dans le d\u00e9sordre effarant d&rsquo;un monde du pouvoir en pleine d\u00e9composition&#8230; Les \u00ab\u00a0infantiles\u00a0\u00bb \u00e9crivent &laquo; <em>Et surtout les temps changent <\/em>&raquo;, et ils ne croient pas si bien dire, mais sans savoir pourquoi ils le disent, comment, dans quel sens, etc., et que cela va dr\u00f4lement les secouer.<\/p>\n<\/p>\n<p><p>Ce que montre <em>The House of Cards<\/em>, c&rsquo;est comment Washington est pass\u00e9 d&rsquo;un certain ordre dans l&rsquo;instabilit\u00e9, ou dans le d\u00e9sordre si l&rsquo;on veut \u00eatre paradoxal, ce qui \u00e9tait le r\u00f4le d&rsquo;Underwood au d\u00e9but de la s\u00e9rie. Comme chef de la majorit\u00e9 \u00e0 la Chambre, et donc l&rsquo;un des hommes les plus puissants du Congr\u00e8s et de Washington D.C. mais plut\u00f4t dans le r\u00f4le de flic tout-puissant des troupes parlementaires, il devait faire r\u00e9gner un certain ordre \u00e0 l&rsquo;int\u00e9rieur du d\u00e9sordre complet qu&rsquo;est Washington D.C. Tout cela va \u00e9videmment avec l&rsquo;ill\u00e9galit\u00e9 compl\u00e8te, les actes brutaux, les trahisons, mais contenus dans une sorte d&rsquo;apparence complaisante o&ugrave; tout le monde est tout de m\u00eame tenu \u00e0 une certaine solidarit\u00e9 par complicit\u00e9 n\u00e9cessaire, exactement comme vont les choses dans le monde du crime organis\u00e9. On pourrait alors comprendre comment des esprits infantiles peuvent s&rsquo;y laisser prendre, imaginant qu&rsquo;au-dessus et autour de tout cela <strong>r\u00e8gnent les principes inviolables, et une sorte de paradis collat\u00e9ral o&ugrave; les \u00ab\u00a0gentils\u00a0\u00bb viendront toucher leurs jetons de pr\u00e9sence avant de prendre une retraite bien gagn\u00e9e, fortune \u00e0 peu pr\u00e8s faite<\/strong>. (Les parlementaires US sont millionnaires en dollars \u00e0 plus de 95%.)<\/p>\n<\/p>\n<p><p>Mais voil\u00e0 que le garde-chiourme, l&rsquo;ex\u00e9cuteur des hautes &oelig;uvres de la Chambre et du Congr\u00e8s, Frank Underwood, devient VP puis, ayant \u00e9limin\u00e9 prestement son pr\u00e9sident, lui-m\u00eame, Underwood, pr\u00e9sident \u00e0 la place du pr\u00e9sident. L&rsquo;homme qui faisait r\u00e9gner un certain ordre dans le d\u00e9sordre g\u00e9n\u00e9ral, devient le ma&icirc;tre absolu et, changeant brusquement d&rsquo;activit\u00e9s, <strong>il sait \u00e9videmment que, pour garder son pouvoir, il doit installer le d\u00e9sordre au c&oelig;ur du d\u00e9sordre pour que nul ne s&rsquo;organise contre lui<\/strong> ; garder son pouvoir, pour lui qui est n\u00e9cessairement ill\u00e9gitime, c&rsquo;est tout faire pour maintenir son pouvoir, et maintenir son pouvoir s&rsquo;est \u00e9largir le d\u00e9sordre autour de lui en s&rsquo;assurant qu&rsquo;il le manipule. La campagne \u00e9lectorale pour son \u00e9lection (nullement sa r\u00e9\u00e9lection, puisqu&rsquo;il n&rsquo;a \u00e9t\u00e9 \u00e9lu ni vice-pr\u00e9sident, ni pr\u00e9sident, proc\u00e9dant chaque fois par manipulation aboutissant \u00e0 sa nomination arbitraire) sera donc la campagne de tous les d\u00e9sordres, aboutissant sur un d\u00e9sordre pire encore, qui ne peut \u00eatre identifi\u00e9 que comme une crise de r\u00e9gime et au-del\u00e0. En ce sens, elle pr\u00e9figure la campagne pr\u00e9sidentielle 2016-2017, ou plut\u00f4t l&rsquo;accompagne (la saison 5 a \u00e9t\u00e9 tourn\u00e9e en 2016) et elle en est, dans l&rsquo;esprit, comme un miroir).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&#8230; La fiction explique la r\u00e9alit\u00e9<\/h3>\n<\/p>\n<p><p>Mais finalement, on en arrive, si l&rsquo;on embrasse toute la s\u00e9rie jusqu&rsquo;\u00e0 cette Saison 5 comprise, \u00e0 comprendre que ce document a finalement saisi l&rsquo;esprit m\u00eame du basculement formidable qui s&rsquo;est effectu\u00e9 \u00e0 Washington D.C., c&rsquo;est-\u00e0-dire au c&oelig;ur du Syst\u00e8me, c&rsquo;est-\u00e0-dire dans notre civilisation devenue contre-civilisation pour s&rsquo;\u00e9crouler &ndash; <strong>et tout cela, avec ce simple mot du pr\u00e9sident Underwood, s&rsquo;adressant \u00e0 nous, spectateurs : &laquo; &#8230;<em>Bienvenue \u00e0 la mort de l&rsquo;&Acirc;ge de la Raison<\/em>. &raquo; <\/strong>Cette formule m\u00eame r\u00e9sume l&rsquo;esprit de la nouvelle \u00e9poque qui s&rsquo;est install\u00e9e avec les pr\u00e9sidentielles USA-2016 et ce qui suit depuis, et qui n\u00e9cessairement marque toute l&rsquo;\u00e9volution du bloc-BAO et du reste, tout fonctionnant \u00e0 cause de la communication sur les interf\u00e9rences, les imbrications et les fusions de la globalisation dont le principal champ d&rsquo;action, et le champ d&rsquo;action de l&rsquo;effondrement, est la psychologie.<\/p>\n<\/p>\n<p><p><strong>Ce &laquo; &#8230;<em>Bienvenue \u00e0 la mort de l&rsquo;&Acirc;ge de la Raison<\/em> &raquo; explique enti\u00e8rement ce qui se passe aujourd&rsquo;hui \u00e0 Washington<\/strong>, o&ugrave; la haine des uns et des autres et des uns pour les autres, haine pure, sans explication rationnelle s\u00e9rieuse (on ne peut tenir pour s\u00e9rieuses ni rationnelles les <em>narrative<\/em> abracadabrante sur <em>Russiagate<\/em>, les <em>false-flag<\/em> syriens, etc.), cette haine est le principal moteur, le moteur grondant et dominant de tous les actes d&rsquo;agression et de corruption, les montages fictifs, les d\u00e9lires qui vont jusqu&rsquo;aux perspectives guerri\u00e8res les plus folles, &ndash; certes, sans passer \u00e0 l&rsquo;acte, puisque tout est communication. On sent bien effectivement que la seule cible et la seule victime n&rsquo;est pas dans le champ de la g\u00e9opolitique, des \u00ab\u00a0int\u00e9r\u00eats nationaux\u00a0\u00bb, de toutes ces choses concr\u00e8tes et qui ont une substance rationnelle, <strong>mais bien dans le champ quasiment exclusif de la psychologie <\/strong>avec ses infinies vari\u00e9t\u00e9s pathologiques de la schizophr\u00e9nie, de la parano\u00efa, de la d\u00e9mence courante (nous dirions \u00ab\u00a0d\u00e9mence de communications\u00a0\u00bb ou \u00ab\u00a0d\u00e9mence mondaine\u00a0\u00bb), etc. Bien entendu, tous les ingr\u00e9dients que nous connaissons bien, de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a> au <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>, sont les outils favoris sinon exclusifs de l&rsquo;esprit.<\/p>\n<\/p>\n<blockquote>\n<p><p>Nous sommes dans l&rsquo;esprit de la chose, qui est l&rsquo;esprit m\u00eame de Washington D.C. et l&rsquo;esprit de la crise d&rsquo;effondrement du Syst\u00e8me : &laquo; &#8230;<em>Bienvenue \u00e0 la mort de l&rsquo;&Acirc;ge de la Raison<\/em> &raquo;. <strong>De ce point de vue, qui n&rsquo;est pas rien et qui est m\u00eame l&rsquo;essentiel, chapeau bas \u00e0 <em>The House of Cards<\/em><\/strong> : l&rsquo;industrie de l&rsquo;<em>entertainment<\/em>, ou \u00ab\u00a0industrie du spectacle\u00a0\u00bb, a r\u00e9ussi \u00e0 produire ce qui est sans doute un des meilleurs spectacles qui est <strong>comme une repr\u00e9sentation de la v\u00e9rit\u00e9-de-situation de l&rsquo;effondrement du Syst\u00e8me dont elle est l&rsquo;\u00e9manation<\/strong>, effondrement frappant prioritairement et d\u00e9cisivement la t\u00eate pourrie du poisson, les \u00e9lites-Syst\u00e8me, ceux-l\u00e0 m\u00eame qui ont travaill\u00e9 avec tant de z\u00e8le \u00e0 la construction du \u00ab\u00a0ch\u00e2teau de cartes\u00a0\u00bb.<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Salut \u00e0 l&rsquo;involontaire interpr\u00e9tation des forces sup\u00e9rieures<\/h3>\n<\/p>\n<p><p>Nous doutons fortement que les divers acteurs au sens larges (sc\u00e9naristes, r\u00e9alisateurs, acteurs justement souvent devenus producteurs, etc.) aient conscience de cette interpr\u00e9tation hypoth\u00e9tique que nous proposons. Nous pensons plut\u00f4t que leur ind\u00e9niable et exceptionnel savoir-faire professionnel, aiguis\u00e9 par le succ\u00e8s, qui les a conduits \u00e0 r\u00e9aliser <strong>une &oelig;uvre de repr\u00e9sentation et non une &oelig;uvre (?) de simulacre<\/strong>, t\u00e9moigne <strong>d&rsquo;une inspiration sup\u00e9rieure dont ils ont \u00e9t\u00e9 le r\u00e9ceptacle inconscient<\/strong>.<\/p>\n<\/p>\n<p><p>Cette s\u00e9rie porte une mission qui est de r\u00e9v\u00e9ler \u00e0 l&rsquo;inconscient du public l&rsquo;\u00e9tat r\u00e9el du Syst\u00e8me et de sa direction, qui est effectivement &laquo; &#8230;<em> la mort de l&rsquo;&Acirc;ge de la Raison<\/em> &raquo;, c&rsquo;est-\u00e0-dire l&rsquo;arriv\u00e9e de la crise \u00e0 son point de fission comme l&rsquo;on parle de l&rsquo;explosion nucl\u00e9aire d\u00e9cisive ; mais nous parlons de l&rsquo;explosion nucl\u00e9aire affectant la psychologie&#8230;<\/p>\n<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\"><u>Note en forme de P.S.<\/u><\/h3>\n<\/p>\n<p><p>&#8230; Nous irions jusqu&rsquo;\u00e0 croire que le c\u00f4t\u00e9 le plus subversif d&rsquo;Underwood, natif de Virginie, ce sont ses hallucinations, dans ses p\u00e9riodes de faiblesse, ou de graves alt\u00e9rations de sant\u00e9 (apr\u00e8s l&rsquo;attentat dont il est l&rsquo;objet). Ses hallucinations dues \u00e0 son \u00e9tat de coma autant qu&rsquo;aux drogues qu&rsquo;on lui administre portent sur son anc\u00eatre, un officier sudiste (g\u00e9n\u00e9ral, peut-\u00eatre ?), ou sur des soldats sudistes d\u00e9penaill\u00e9s qui viennent l&rsquo;ex\u00e9cuter dans son lit de souffrance comme l&rsquo;on fait d&rsquo;un tra&icirc;tre, d&rsquo;un homme qui, en s&rsquo;installant \u00e0 Washington au c&oelig;ur du Syst\u00e8me, a trahi la Cause sacr\u00e9e de ses anc\u00eatres. <strong><em>The House of Cards <\/em>n&rsquo;en rate pas une<\/strong>&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur leur House of Cards 16 juillet 2017 &ndash; Au d\u00e9part, ce n&rsquo;est qu&rsquo;une observation anecdotique faite par un twitter plus ou moins anonyme, dit-00Author87, le 7 juillet 2017, avec comme l\u00e9gende : &laquo; When you&rsquo;re watching the news but you&rsquo;ve seen it all before on House of Cards&#8230; &raquo; RT a repris ce&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[7726,11957,3285,4640,13191,13190,4014,13192,13188,13189,5169],"class_list":["post-77373","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-7726","tag-cards","tag-congres","tag-house","tag-infantilisme","tag-moustique","tag-of","tag-saison","tag-spacey","tag-underwood","tag-wsws-org"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77373"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77373\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}