{"id":77396,"date":"2017-07-28T14:00:52","date_gmt":"2017-07-28T14:00:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/28\/quand-lavrov-plaisante\/"},"modified":"2017-07-28T14:00:52","modified_gmt":"2017-07-28T14:00:52","slug":"quand-lavrov-plaisante","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/07\/28\/quand-lavrov-plaisante\/","title":{"rendered":"Quand Lavrov plaisante&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Quand Lavrov plaisante&#8230;<\/h2>\n<\/p>\n<p><p>28 juillet 2017 &ndash; Je ne crois pas qu&rsquo;il y ait <strong>une anecdote plus significative et aussi plus symbolique de notre situation de folie absolument inimaginable d&rsquo;ampleur et de rythme, essentiellement suscit\u00e9e, assum\u00e9e et anim\u00e9e par \u00ab\u00a0Washington D.C.-la-folle\u00a0\u00bb<\/strong>. Elle \u00e9chappe, cette folie, \u00e0 la plupart des observateurs, aussi bien les plus fins diplomates prisonniers de vieilles habitudes qui les conduisent \u00e0 regarder pour ne pas trop voir, que les fonctionnaires-Syst\u00e8me habitu\u00e9s \u00e0 regarder pour ne rien voir du tout, que les journalistes-Syst\u00e8me dress\u00e9s pour ne pas regarder de fa\u00e7on \u00e0 ne voir que les simulacres en forme de vessies et \u00e0 jurer que ce sont des lanternes qui \u00e9clairent le monde.<\/p>\n<\/p>\n<p><p>Je parle de cette rencontre entre Lavrov, le meilleur ministre des affaires \u00e9trang\u00e8res sur la place aujourd&rsquo;hui, un des meilleurs qu&rsquo;aient eu les Russes, un des meilleurs de l&rsquo;\u00e9poque moderne et postmoderne depuis le d\u00e9but du XX\u00e8me si\u00e8cle ; et, d&rsquo;autre part, face \u00e0 lui, un journaliste am\u00e9ricaniste de la prestigieuse cha&icirc;ne de le presseSyst\u00e8me NBC. C&rsquo;\u00e9tait dans un article du site, <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-une-visite-de-routine-a-la-maison-des-fous\">il y a trois jours<\/a>&#8230; Je cite la description de la chose :<\/p>\n<\/p>\n<p><p>&laquo; <em>Une toute r\u00e9cente remarque du ministre des affaires \u00e9trang\u00e8res de l&rsquo;inqui\u00e9tante Russie, Sergei Lavrov, fixe effectivement <strong>la gravit\u00e9 hyper-extraordinaire de la situation politique et surtout psychologique dans le chef de ses acteurs<\/strong>, par la d\u00e9monstration a contrario du d\u00e9lire paroxystique de la presseSyst\u00e8me US&#8230; En deux mots : peut-\u00eatre, a sugg\u00e9r\u00e9 ce ministre russe aussi solide qu&rsquo;un roc et aussi s\u00e9rieux qu&rsquo;un pape v\u00e9ritable, y a-t-il eu complot au G20 entre Trump et Poutine lorsqu&rsquo;ils se sont trouv\u00e9s ensemble aux toilettes, en train de pisser ? Lavrov, plein de l&rsquo;impudente puissance de la Russie \u00e0 la conqu\u00eate du monde, sugg\u00e8re \u00e0 la fine-fleur de l&rsquo;intelligentsia journalistique occidentaliste-am\u00e9ricaniste de suivre cette piste, &ndash; \u00ab\u00a0<strong>enqu\u00eate dans les latrines, ou comment le terrifiant Poutine a r\u00e9ussi \u00e0 conqu\u00e9rir le monde en pissant<\/strong>\u00ab\u00a0<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>(Le passage est \u00e0 voir sur <a href=\"https:\/\/www.youtube.com\/watch?v=vnAPW_Bq2Vg\">l&rsquo;interview de NBC<\/a> du 21 juillet 2017 \u00e0 58-59 seconde de cette vid\u00e9o de 91 secondes, lorsque l&rsquo;intervieweur parle tr\u00e8s s\u00e9rieusement de \u00ab\u00a0trois rencontres Poutine-Trump\u00a0\u00bb dont deux secr\u00e8tes <\/em>[au G20]<em>, et que Lavrov r\u00e9plique, avec un formidable s\u00e9rieux et le regard glac\u00e9-\u00e9crasant d&rsquo;une d\u00e9rision fatigu\u00e9e port\u00e9 sur son interlocuteur, et en anglais directement pour que personne ne s&rsquo;y trompe : \u00ab\u00a0Oui, mais peut-\u00eatre qu&rsquo;il y a eu une quatri\u00e8me rencontre secr\u00e8te, quand ils se sont rencontr\u00e9s aux toilettes\u00a0\u00bb. Nous savons bien ce que Lavrov veut dire, car nous savons d\u00e9coder les messages venus des pratiques du KGB : &lsquo;Poutine et Trump pissant de concert, pour couvrir le bruit de leurs conversation complotiste\u00a0\u00bb&hellip; Et, miracle \u00e9tourdissant, nous voyons aussi bien <strong>que le journaliste-NBC continue avec le plus grand s\u00e9rieux<\/strong>, prenant manifestement pour du comptant cette r\u00e9ponse puisqu&rsquo;il l&rsquo;avait sugg\u00e9r\u00e9e en ouverture de la s\u00e9quence comme un v\u00e9ritable scoop&#8230; Fatigue et respect.) <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Lavrov, on le conna&icirc;t ; un travailleur forcen\u00e9, un n\u00e9gociateur implacable, une haute conscience de sa fonction et de la souverainet\u00e9 de la Russie, dur avec les autres comme avec lui-m\u00eame, conscient des int\u00e9r\u00eats de son pays et respectant ceux des autres, dur implacablement mais loyal sans restriction d&rsquo;une certaine fa\u00e7on. Ce n&rsquo;est pas un homme \u00e0 faire une plaisanterie facile, et lorsqu&rsquo;il en fait une c&rsquo;est pour en rire aussit\u00f4t de fa\u00e7on \u00e0 partager avec son interlocuteur ce moment de d\u00e9tente qui doit contribuer \u00e0 renforcer un climat propice \u00e0 une bonne entente. Quand il enrage parce qu&rsquo;il sent qu&rsquo;on essaie de l&rsquo;avoir, <strong>l&rsquo;allure se glace et le visage prend cette consistance de granit<\/strong>, le regard droit, sans ciller&#8230; Je me rappelle avoir lu qu&rsquo;au cours d&rsquo;une rencontre avec les \u00ab\u00a0partenaires\u00a0\u00bb US en 2008, lors de la crise g\u00e9orgienne, il avait litt\u00e9ralement terroris\u00e9 la pauvre Condoleezza Rice rien qu&rsquo;avec cette allure-l\u00e0.<\/p>\n<\/p>\n<p><p>Mais l\u00e0, pour cet instant, ces quelques secondes de la NBC, <strong>c&rsquo;est tout autre chose<\/strong>.<\/p>\n<\/p>\n<p><p>Il fait cette plaisanterie grossi\u00e8re et sans le moindre sens avec ces m\u00eames attributs, &ndash; l&rsquo;allure glac\u00e9e et le visage de granit, &ndash; mais l\u00e0 pour exprimer une exasp\u00e9ration silencieuse et sans fin, et incroyablement m\u00e9prisante, en regardant au fond des yeux son interlocuteur qui prend au s\u00e9rieux la suggestion du ministre (le complot du pissoir) ; <strong>oui, au s\u00e9rieux<\/strong>, ce type qui est un envoy\u00e9 sp\u00e9cial de la cha&icirc;ne NBC ! Eh bien, il me semble que l&rsquo;on pourrait aussi bien observer ceci, &ndash; pour qu&rsquo;un ministre comme Lavrov, apr\u00e8s des ann\u00e9es et des ann\u00e9es de contacts avec les \u00ab\u00a0partenaires\u00a0\u00bb am\u00e9ricanistes, en arrive \u00e0 cette attitude avec un journaliste du m\u00eame camp exceptionnel des am\u00e9ricanistes, alors qu&rsquo;en g\u00e9n\u00e9ral on soigne la communication, il faut que la situation dont les Russes sont les mieux inform\u00e9s, et par rapport \u00e0 laquelle ils sont les seuls vraiment lucides, <strong>soit bien en v\u00e9rit\u00e9 ce tourbillon de folie, ce trou noir d&rsquo;incons\u00e9quence paroxystique et de d\u00e9mence hallucin\u00e9e<\/strong> que l&rsquo;on d\u00e9crit, pour notre compte chaque jour sur ce site, autant que faire se peut.<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Jamais<\/strong> une telle sc\u00e8ne n&rsquo;e&ucirc;t \u00e9t\u00e9 concevable, il y a cinquante ans, quarante ans, trente ans, vingt ans, dix ans, <strong>et m\u00eame 5 ans, peu avant que ne se d\u00e9clenche la grande crise hallucin\u00e9e de \u00ab\u00a0Kiev-la-folle\u00a0\u00bb<\/strong>&#8230; (\u00ab\u00a0Kiev-la-folle\u00a0\u00bb pour \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, ce fut en v\u00e9rit\u00e9 <strong>le banc d&rsquo;essai de la phase actuelle du \u00ab\u00a0d\u00e9cha&icirc;nement de la d\u00e9mence\u00a0\u00bb<\/strong>, phase ultime non pas du communisme ni du capitalisme mais du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb&#8230;). Notre \u00e9poque, c&rsquo;est vraiment une g\u00e2terie des temps m\u00e9tahisoriques, le g\u00e2teau sur la cerise du Progr\u00e8s.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Apr\u00e8s des ann\u00e9es d&rsquo;une patience qui restera un des plus grands accomplissements diplomatiques des temps-modernes, <strong>les Russes en sont arriv\u00e9s \u00e0 une compr\u00e9hension compl\u00e8te de cette situation de n\u00e9antissement complet de toute raison et de toute mesure<\/strong>, et tirant la le\u00e7on de cet \u00e9tat de chose pour la faire entrer dans leur communication, lorsqu&rsquo;il rencontre les princes US de la communication&#8230; J&rsquo;ai la conviction que Lavrov, bien entendu a fait cela de propos d\u00e9lib\u00e9r\u00e9, et m\u00eame qu&rsquo;<strong>il l&rsquo;a fait avec l&rsquo;accord sinon les encouragements de son pr\u00e9sident sur le principe<\/strong>. Je crois que les Russes en sont arriv\u00e9s au stade o&ugrave; la consigne est bien du genre dit \u00ab\u00a0en d\u00e9sespoir de cause\u00a0\u00bb, quelque chose comme \u00ab\u00a0Foutez-vous de leur poire, ouvertement, sans prendre de gants, sans m\u00eame sourire, racontez-leur n&rsquo;importe quoi \u00e0 propos de tous les paroxysmes de leur d\u00e9mence, peut-\u00eatre que \u00e7a en fera sortir l&rsquo;un ou l&rsquo;autre de son d\u00e9lire hallucin\u00e9, dans tous les cas \u00e7a les rendra encore plus ridicules\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mais \u00ab\u00a0encore plus ridicules\u00a0\u00bb aux yeux de qui, d&rsquo;ailleurs ? Hormis ces <em>moujiks <\/em>arri\u00e9r\u00e9s et quelques allum\u00e9s de l&rsquo;internet et autres antiSyst\u00e8me, qui d&rsquo;entre les autres oserait croire ce que lui disent ses yeux et sa perception lorsqu&rsquo;il s&rsquo;agit de la mythique Washington D.C. ? A la d\u00e9mence absolument sans fin et sans fond correspondent leur fascination, leur emprisonnement comme si les \u00e9ructations de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb avait l&rsquo;irr\u00e9sistibilit\u00e9 divine du chant des sir\u00e8nes auquel r\u00e9sista le rus\u00e9 Ulysse parce qu&rsquo;il avait eu le bon sens de se faire ligoter au mat de son navire. Du moment qu&rsquo;un Zuckerberg, mi-Platon mi-Plotin en <em>t-shirt<\/em>, leur dit que le bonheur c&rsquo;est pour <a href=\"http:\/\/www.dedefensa.org\/article\/mark-facebook-contre-le-catastrophisme-irresponsable\">dans dix ans-pas-plus<\/a>, que pourraient-ils d\u00e9sirer de plus ?<\/p>\n<\/p>\n<p><p>Le probl\u00e8me de l&rsquo;effondrement de cette contre-civilisation, malgr\u00e9 tout le bruit que cela fera et que cela est d\u00e9j\u00e0 en train de faire, <strong>c&rsquo;est qu&rsquo;il ne faut surtout rien faire, ni pour l&rsquo;arr\u00eater, ni m\u00eame pour le ralentir, et au contraire tout pour l&rsquo;acc\u00e9l\u00e9rer<\/strong>. Alors, peut-\u00eatre que la plaisanterie de Lavrov voulait dire au fond : \u00ab\u00a0C&rsquo;est bien, les gars, continuez comme \u00e7a, n&rsquo;h\u00e9sitez pas, foncez, osez tout car c&rsquo;est \u00e0 cela que <strong>Dieu, qui aime bien se d\u00e9tendre, reconna&icirc;tra les siens et ainsi serez-vous parmi les &Eacute;lus<\/strong>&#8230;\u00a0\u00bb <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand Lavrov plaisante&#8230; 28 juillet 2017 &ndash; Je ne crois pas qu&rsquo;il y ait une anecdote plus significative et aussi plus symbolique de notre situation de folie absolument inimaginable d&rsquo;ampleur et de rythme, essentiellement suscit\u00e9e, assum\u00e9e et anim\u00e9e par \u00ab\u00a0Washington D.C.-la-folle\u00a0\u00bb. Elle \u00e9chappe, cette folie, \u00e0 la plupart des observateurs, aussi bien les plus fins&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[6305,4926,6306,12683,4384,13227,916,13228,2639],"class_list":["post-77396","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-affaires","tag-complot","tag-etrangeres","tag-ministres","tag-nbc","tag-pissoir","tag-poutine","tag-toilettes","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77396"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77396\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}